{"id":25074,"date":"2022-12-28T17:00:00","date_gmt":"2022-12-28T16:00:00","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=25074"},"modified":"2025-01-08T14:11:35","modified_gmt":"2025-01-08T13:11:35","slug":"news_2022","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/en\/noticias_2022\/","title":{"rendered":"The most important mountaineering and mountain news of 2022"},"content":{"rendered":"\n<p>En el<span style=\"background-color:#ffbfb5\" class=\"td_text_highlight_marker\"><strong>Bolet\u00edn Semanal<\/strong><\/span>hemos incorporado una nueva secci\u00f3n en la que seleccionamos la actualidad semanal y noticias diferentes. <strong><a href=\"https:\/\/www.getrevue.co\/profile\/travesia\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Suscr\u00edbete a la <em>newsletter<\/em><\/a> <\/strong>aires de altura y rec\u00edbelo cada semana. \ud83d\ude42<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 28 diciembre 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Como en pasadas semanas vamos a hacer un repaso de la actualidad de las 3 expediciones en el Himalaya invernal. Por un lado,&nbsp;<strong>Alex Txikon y sus compa\u00f1eros ya han realizado la primera rotaci\u00f3n en altura<\/strong>. Tras la tradicional puya en el CB el equipo ha subido hoy hasta el C1. Txikon tiene buenas sensaciones y traslada que se encuentra con fuerzas y muchas ganas. En los pr\u00f3ximos d\u00edas se les unir\u00e1 Simone Moro. Este a\u00f1o&nbsp;<strong>han instalado el CB a 3.700m para evitar las copiosas nevadas y avalanchas<\/strong>, que el a\u00f1o pasado les enviaron para casa de manera precipitada. La contrapartida, los 1.200m de desnivel adicional que tendr\u00e1n entre CB y cima.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u00a1Este a\u00f1o hemos instalado el CB a 3.700m para estar m\u00e1s resguardados de las nevadas y el viento, a ver! \ud83e\udd1e\ud83c\udffc\ud83d\ude4f\ud83c\udffc Se ha animado a venir unos d\u00edas con nosotros Pasang Themba, que tras ayudarle a poner a punto su audici\u00f3n en Katmand\u00fa, est\u00e1 feliz y ha recuperado la ilusi\u00f3n \ud83e\udd70 <a href=\"https:\/\/t.co\/E2pWV2N7In\">pic.twitter.com\/E2pWV2N7In<\/a><\/p>&mdash; Alex Txikon (@AlexTxikon) <a href=\"https:\/\/twitter.com\/AlexTxikon\/status\/1607350597430165505?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 26, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Por su parte,&nbsp;<strong>David Goettler y Herve Barmasse siguen con su aclimataci\u00f3n<\/strong>&nbsp;en el valle de Khumbu. Pasaron el d\u00eda de Nochebuena escalando el pico Island Peak (Imja Tse) de 6.160 m. La ascensi\u00f3n de este pico en otras estaciones es un trekking muy popular. Por ahora no han decidido el reto que afrontar\u00e1n este invierno. Recordar que decidir\u00e1n si su objetivo ser\u00e1 el Annapurna, el Dhaulagiri o si se desplazan a Pakistan para volver a intentar la vertiente Rupal del Nanga Parbat. Para ambos \u00abel estilo alpino puro es irrenunciable\u00bb.<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CmjXvrIty6b\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CmjXvrIty6b\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Ver esta publicaci\u00f3n en Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CmjXvrIty6b\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida de David Goettler (@david_goettler)<\/a><\/p><\/div><\/blockquote> <script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Diferente est\u00e1 siendo la Navidad para la<strong>&nbsp;expedici\u00f3n al Cho Oyu<\/strong>, la m\u00e1s adelantada, que comenz\u00f3 la actividad antes del invierno astron\u00f3mico. Los sherpas ya han fijado la cuerda hasta el C3 (7.200 m antes de una gran meseta previa a la zona final de cumbre). Kristin Harila y Adriana Brownlee han llegado al C2 (6.700m). \u00ab<a href=\"https:\/\/explorersweb.com\/winter-himalayan-update-from-classic-base-camps-to-village-outskirts\/\" target=\"_blank\" rel=\"noopener\">Esper\u00e1bamos dormir en el C3, pero el fuerte viento nos oblig\u00f3 a bajar de nuevo al Campo Base<\/a>\u00bb&nbsp;<em>(explorersweb)<\/em>, escribi\u00f3 Harila. \u00ab<strong>Estamos bien aclimatados, as\u00ed que ahora s\u00f3lo necesitamos que el viento amaine durante al menos tres d\u00edas<\/strong>\u00ab, viendo el intento de ataque a la cima cercano. El Equipo ha completado las rotaciones de aclimataci\u00f3n y ahora est\u00e1 a la espera de una ventana meteorol\u00f3gica para intentar fijar el campo 4 y posiblemente el campo 5 y hacer cumbre.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Patagonia en venta<\/strong>. \u00bfSe puede comprar una monta\u00f1a? Pues s\u00ed. Y un valle entero. At\u00f3nito leo la noticia que nos trae&nbsp;<em>Desnivel<\/em>: \u201c<strong><a href=\"https:\/\/www.desnivel.com\/escalada-roca\/accesos\/subastan-buena-parte-del-valle-de-cochamo\/\" target=\"_blank\" rel=\"noopener\">Subastan buena parte del valle de Cocham\u00f3<\/a><\/strong>\u201d. 131.000 hect\u00e1reas en la Patagonia chilena que han sido puestas a la venta en una subasta en&nbsp;<em>Christie\u2019s<\/em>&nbsp;de Nueva York. Lugar que ha sido&nbsp;<strong>comparado por muchos escaladores con Yosemite<\/strong>, por las enormes posibilidades que ofrece para el big wall. \u201cEl Dorado de los buscadores de placas, fisuras y paredes kilom\u00e9tricas, descubierto por los&nbsp; escaladores en 1996\u201d. Las organizaciones locales piden que se declare Santuario de la Naturaleza.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Plataforma en Defensa de las Monta\u00f1as de Arag\u00f3n<\/strong>&nbsp;ha iniciado esta petici\u00f3n dirigida a Gobierno de Arag\u00f3n, para que paralicen sus pretensiones de destruir el valle de Canal Roya dentro de su megaproyecto de esqu\u00ed para la zona. Adem\u00e1s se pide la declaraci\u00f3n de&nbsp;<strong>Canal Roya<\/strong>&nbsp;como parque natural, incluyendo tambi\u00e9n el macizo del Anayet, Canal de Izas y la sierra de la Partacua, bajo la denominaci\u00f3n conjunta de Parque Natural del Anayet. &nbsp;&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><strong>No destruyan el valle de Canal Roya por la ampliaci\u00f3n de las estaciones de esqu\u00ed.&nbsp;<\/strong>&#8211;&nbsp;<strong>\u00a1Firma la petici\u00f3n!&nbsp;<a href=\"https:\/\/t.co\/bmS3GJwHwP\">https:\/\/chng.it\/Cx9JPjf7<\/a><\/strong>&nbsp;a trav\u00e9s de&nbsp;<a href=\"https:\/\/twitter.com\/change_es\" target=\"_blank\" rel=\"noopener\">@change_es<\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Gobierno de Arag\u00f3n: No destruyan el valle de Canal Roya por la ampliaci\u00f3n de las estaciones de esqu\u00ed. &#8211; \u00a1Firma la petici\u00f3n! <a href=\"https:\/\/t.co\/Prw9nnAEMR\">https:\/\/t.co\/Prw9nnAEMR<\/a> a trav\u00e9s de <a href=\"https:\/\/twitter.com\/change_es?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@change_es<\/a><\/p>&mdash; Eduardo Vi\u00f1uales (@EduVinuales) <a href=\"https:\/\/twitter.com\/EduVinuales\/status\/1547928244157947908?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 15, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 22 diciembre 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comenzamos con el&nbsp;<strong>Himalaya invernal. Y con los enfrentamientos dial\u00e9cticos que se est\u00e1n produciendo<\/strong>. \u00abNo pretendo crear pol\u00e9mica, pero despu\u00e9s de 22 expediciones invernales, s\u00e9 lo que digo (\u2026)&nbsp;<a href=\"https:\/\/explorersweb.com\/cho-oyu-manaslu-and-the-definition-of-winter\/\" target=\"_blank\" rel=\"noopener\">El invierno astron\u00f3mico es el \u00fanico comienzo de la verdadera temporada invernal de escalada en el hemisferio norte\u00bb<\/a>&nbsp;<em>(explorersweb)<\/em>, afirma Simone Moro.&nbsp;<strong>Simone y \u00c1lex Txikon ir\u00e1n a por la invernal en el Manaslu (8.163 m) por tercer a\u00f1o consecutivo.<\/strong>&nbsp;No pisar\u00e1n la monta\u00f1a hasta pasado el 21 de diciembre, sino \u201ccambiar\u00edan las reglas a su favor\u201d.&nbsp;<strong>Esto no aplica para el nuevo intento de apertura de ruta normal por la vertiente sur del Cho Oyu, en invierno<\/strong>&nbsp;y por parte de Adriana Brownlee, Kristin Harila, Gelje Sherpa y Seven Summit Treks que ya se encuentran en la monta\u00f1a (explorersweb). Y de ah\u00ed viene toda la pol\u00e9mica<em>.<\/em>&nbsp;Adem\u00e1s,&nbsp;<a href=\"https:\/\/explorersweb.com\/another-controversy-for-grace-tseng-kangchenjunga\/\" target=\"_blank\" rel=\"noopener\">m\u00e1s problemas para Grace Tseng, con nuevas dudas sobre su cima al Kangchenjunga en el oto\u00f1o del 2021&nbsp;<\/a><em>(explorersweb)<\/em>. Por otro lado, seguimos la&nbsp;<strong>expedici\u00f3n de David Goettler y Herve Barmasse, que se encuentran entrenando y aclimatando en el valle del Khumbu<\/strong>&nbsp;para preparar su objetivo de este invierno (por determinar). Recordar que el a\u00f1o pasado intentaron en estilo alpino, y en invierno, la Rupal al Nanga Parbat. Decidir\u00e1n este a\u00f1o si su objetivo ser\u00e1 el Annapurna, el Dhaulagiri o si se desplazan a Pakistan para volver a intentar la vertiente Rupal del Nanga Parbat. Para ambos \u00abel estilo alpino puro es irrenunciable\u00bb.<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/Cmbzay7hH9m\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/reel\/Cmbzay7hH9m\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Ver esta publicaci\u00f3n en Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/reel\/Cmbzay7hH9m\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida de David Goettler (@david_goettler)<\/a><\/p><\/div><\/blockquote> <script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Os traemos la aventura veraniega del gu\u00eda UIAGM holand\u00e9s Roeland Van Oss, de las que nos gustan porque son muy inspiradoras.&nbsp;<strong><a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11741\/82-cuatromiles-alpes-72-dias\" target=\"_blank\" rel=\"noopener\">Los 82 cuatromiles de los Alpes en 72 d\u00edas, en bicicleta entre ellos<\/a><\/strong>&nbsp;<em>(Barrabes)<\/em>. Las cifras son: 1.300km en bicicleta, 600 a pie y 100.000m de desnivel positivo. \u201cRealiz\u00f3 la traves\u00eda de este a oeste, comenzando el 25 de mayo en el Bernina y finalizando el 12 de agosto, Roeland escal\u00f3 su \u00faltimo pico, en Ecrins.\u201d Os invitamos a entrar en el art\u00edculo de Barrabes y leer la \u00faltima parte en la que Roeland cuenta que le llevo a esta aventura. Creo que suscribir\u00edamos al 100% esas palabras, cada cual en sus retos. La pregunta que se hizo fue \u201c\u00bfPor qu\u00e9 escalamos?\u201d.<\/li>\n\n\n\n<li>El&nbsp;<em>Comit\u00e9 de Seguridad FEDME&nbsp;<\/em>presenta un<a href=\"https:\/\/www.desnivel.com\/cultura\/analisis-de-accidentes\/accidente-durante-una-quedada-de-senderismo-propuesta-en-un-grupo-de-facebook\/\" target=\"_blank\" rel=\"noopener\">&nbsp;<\/a><strong><a href=\"https:\/\/www.desnivel.com\/cultura\/analisis-de-accidentes\/accidente-durante-una-quedada-de-senderismo-propuesta-en-un-grupo-de-facebook\/\" target=\"_blank\" rel=\"noopener\">an\u00e1lisis de accidente en una actividad organizada por un grupo de \u00abamigos\u00bb en redes sociales, que en realidad no se conoc\u00edan en persona<\/a><\/strong><a href=\"https:\/\/www.desnivel.com\/cultura\/analisis-de-accidentes\/accidente-durante-una-quedada-de-senderismo-propuesta-en-un-grupo-de-facebook\/\" target=\"_blank\" rel=\"noopener\">&nbsp;<\/a><em>(Desnivel)<\/em>. \u201c\u00bfQu\u00e9 puede llevarnos a quedar a hacer un sendero desconocido de estas caracter\u00edsticas con un grupo de diez personas que no conocemos de nada? \u00bfQu\u00e9 puede hacer que nos pongamos en manos de un organizador-gu\u00eda virtual que pone un anuncio en el grupo?\u201d El error en la percepci\u00f3n del riesgo se uni\u00f3 en este caso a la falta de v\u00ednculo afectivo entre los miembros del grupo. A veces se organizan estas quedadas sin valorar los riesgos y es bueno conocerlos de antemano.<\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.deia.eus\/deportes\/2022\/12\/18\/an-accidental-life-henna-taylor-6303188.html\" target=\"_blank\" rel=\"noopener\">\u00abAn Accidental Life\u00bb, de Henna Taylor, se lleva el Gran Premio del Mendi Film Bilbao Bizkaia 2022<\/a><\/strong><em><a href=\"https:\/\/www.deia.eus\/deportes\/2022\/12\/18\/an-accidental-life-henna-taylor-6303188.html\" target=\"_blank\" rel=\"noopener\">&nbsp;<\/a>(Deia)<\/em>. La directora aborda el tr\u00e1gico accidente, con ca\u00edda de m\u00e1s de 30 metros, que la escaladora estadounidense Quinn Brett tuvo en 2017 y que le releg\u00f3 a una silla de ruedas. De Brett, antes del accidente, destacan el r\u00e9cord de velocidad femenino de<em>&nbsp;The Nose<\/em>, tambi\u00e9n en El Capit\u00e1n; y la apertura de&nbsp;<em>The Colorado Route<\/em>&nbsp;en la cara sur del Fitz Roy, en La Patagonia. Os dejo aqu\u00ed el tr\u00e1iler de la pel\u00edcula.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"AN ACCIDENTAL LIFE Trailer\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/YSP0EKgaWeo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y cerramos con un&nbsp;<em>reality show<\/em>&nbsp;que llega. Y es que la escalada va imparable en su camino hacia el&nbsp;<em>mainstream&nbsp;<\/em>(perdonar por la de anglicismos qeu os pongo por aqu\u00ed). <strong>El actor (y escalador) Jason Momoa y la leyenda de la escalada Chris Sharma se han unido para producir un nuevo&nbsp;<em>reality&nbsp;<\/em>de competici\u00f3n para HBO Max titulado \u2018<em>The Climb\u2019<\/em><\/strong>. El programa, que se estrenar\u00e1 el 12 de enero de 2023, presentar\u00e1 a Momoa, Sharma y la escaladora profesional Meagan Martin supervisando a 10 escaladores que compiten por un premio de 100.000 d\u00f3lares y un patrocinio.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"The Climb | Official Trailer | HBO Max\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/wKUce1x-njY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se me olvidaba algo. A mi francamente me cabrea, duele, me sorprende. Hemos tra\u00eddo a esta secci\u00f3n muchas veces este tema, pero quiz\u00e1s este tuit sea la mejor manera de contarlo.  <\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u00bfSe imaginan un parking dentro del Museo del Prado? \u00bfo un lavacoches en la fuente de los Leones de la Alhambra? pues eso es lo que planea <a href=\"https:\/\/twitter.com\/GobAragon?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@GobAragon<\/a> en el santuario natural pirenaico de Canal Roya-Anayet, arrasarlo metiendo una absurda nueva estaci\u00f3n de esqu\u00ed <a href=\"https:\/\/twitter.com\/hashtag\/SalvemosCanalRoya?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#SalvemosCanalRoya<\/a> <a href=\"https:\/\/t.co\/cPaRqaFXQB\">pic.twitter.com\/cPaRqaFXQB<\/a><\/p>&mdash; Paco Iturbe (@paco_iturbe) <a href=\"https:\/\/twitter.com\/paco_iturbe\/status\/1603327678223994883?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 15, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 14 diciembre 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Como venimos haciendo en las \u00faltimas semanas comenzamos con el Himalaya invernal, con las expediciones que se est\u00e1n montando. As\u00ed, hemos conocido que&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/herve-barmasse-y-david-gottler-volveran-a-intentar-un-ochomil-en-estilo-alpino-este-invierno\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Herv\u00e9 Barmasse y David G\u00f6ttler volver\u00e1n a intentar un ochomil en estilo alpino este invierno<\/strong><\/a>&nbsp;<em>(Desnivel)<\/em>. Recordar que el a\u00f1o pasado intentaron en este estilo, y en invierno, la Rupal al Nanga Parbat. Viajar\u00e1n en breve a Nepal y decidir\u00e1n si ser\u00e1 el Annapurna, el Dhaulagiri o si se desplazan a Pakistan para volver a intentar la vertiente Rupal del Nanga Parbat. Para ambos \u201cel estilo alpino puro es irrenunciable\u201d. Por otro lado, os habl\u00e1bamos las semanas pasadas del&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11737\/adriana-brownlee-kristin-harila-gelje?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>nuevo intento de apertura de ruta normal por la vertiente sur del Cho Oyu, en invierno y por parte de Adriana Brownlee, Kristin Harila, Gelje Sherpa y Seven Summit Treks<\/strong><\/a>&nbsp;<em>(Barrabes)<\/em>.<\/li>\n\n\n\n<li>Ahora vamos con una conversaci\u00f3n muy interesante que se ha producido en Twitter.&nbsp;<a href=\"https:\/\/twitter.com\/C_Castillejo\/status\/1600858440314032134?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Carles Castillejo, corredor ol\u00edmpico, se preguntaba c\u00f3mo hab\u00eda cambiado el panorama en los p\u00f3diums del Campeonato de Europa de cross<\/strong><\/a>, donde ahora era predominante de pa\u00edses del norte de Europa, diferente a hace 10 a\u00f1os. Entraba entonces en la conversaci\u00f3n<strong>&nbsp;kilian jornet para explicar c\u00f3mo se trabaja el deporte en estos pa\u00edses<\/strong>, de su experiencia, recordar que ahora reside con su familia en Noruega. Resumiendo, que luego os dejo los tuits: deporte base (escolar, clubs) sin discriminar, sin clasificaciones hasta los 12, multideporte y en \u00e9lite mucha apertura y buscando el rendimiento a largo plazo. Pod\u00e9is ver las respuestas de la gente.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Trabajo de base muy bueno (escolar, clubes&#8230; de una forma que no potencia que solo sigan haciendo deporte los mejores sino tod@s) y un entrenamiento muy cient\u00edfico en la \u00e9lite, tranversalmente en todos los deportes.<\/p>&mdash; kilian jornet (@kilianj) <a href=\"https:\/\/twitter.com\/kilianj\/status\/1601865069272485888?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 11, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">En \u00e9lite:<br>&#8211; Una estructura central donde todos los deportes comparten informacion (fisiolog\u00eda, entrenamiento&#8230;) <br>&#8211; Mucha ciencia (inversi\u00f3n, investigaci\u00f3n y profesionales)<br>&#8211; Mucha apertura, se comparte como entrena..<br>&#8211; Rendimiento largo plazo (no presi\u00f3n por resultado siguiente)<\/p>&mdash; kilian jornet (@kilianj) <a href=\"https:\/\/twitter.com\/kilianj\/status\/1602022459951435776?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 11, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Me parece interesante compartir aqu\u00ed la&nbsp;<strong>serie de art\u00edculos que escribe Manuel Guijarro en SalyRoca&nbsp;<\/strong>contando su periplo desde que le llega una notificaci\u00f3n de la Guardia Civil. Su art\u00edculo:&nbsp;<strong>\u201cTe denuncia tu compa\u00f1ero de escalada\u201d<\/strong>&nbsp;(<a href=\"https:\/\/www.salyroca.es\/articulo\/roca\/denuncia-companero-escalada-parte-1\/20221213023600007823.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">parte 1&nbsp;<\/a>\/&nbsp;<a href=\"https:\/\/www.salyroca.es\/articulo\/roca\/denuncia-companero-escalada-parte-2\/20221213030141007826.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">parte 2<\/a>).&nbsp;<em>\u201cTanto expertos como principiantes. Todos estamos expuestos a sufrir un accidente de escalada. Existen publicaciones que analizan en detalle causas de accidentes reales. Factores que lo desencadenaron, c\u00f3mo evitarlos y sus consecuencias. Pero pocos se centran en un aspecto que por desgracia cada vez est\u00e1 m\u00e1s de actualidad:&nbsp;<\/em><strong><em>la responsabilidad penal o civil<\/em><\/strong><em>&nbsp;entre la propia cordada.\u201d<\/em><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No s\u00e9 si hab\u00e9is visto el video en el que la<a href=\"https:\/\/elpais.com\/deportes\/el-montanista\/2022-12-13\/un-rescate-de-pelicula-una-escaladora-salva-la-vida-de-un-saltador-colgado-de-su-paracaidas-a-25-metros-del-suelo.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;<strong>escaladora estadounidense River Barry libera y salva la vida de un saltador colgado de su paraca\u00eddas a 25 metros del suelo<\/strong><\/a>&nbsp;<em>(elpa\u00eds)<\/em>. De pel\u00edcula. \u201cUna fisura rectil\u00ednea conduc\u00eda directamente hasta el accidentado, colgado 25 metros por encima de sus cabezas\u201d. Pod\u00e9is leer el&nbsp;<a href=\"https:\/\/elpais.com\/deportes\/el-montanista\/2022-12-13\/un-rescate-de-pelicula-una-escaladora-salva-la-vida-de-un-saltador-colgado-de-su-paracaidas-a-25-metros-del-suelo.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">art\u00edculo de \u00d3scar Gogorza<\/a>&nbsp;en el que de una manera amena nos da todos los detalles. Y aqu\u00ed ten\u00e9is el video del afortunado desenlace a esta historia.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Rescue team, bystander recount daring Moab rescue after BASE jumper cliff crash\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/zOuixakk3fQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y para cerrar la secci\u00f3n, lo hacemos con la ilustraci\u00f3n de 72kilos. <strong>Y t\u00fa, \u00bferes rico? \u00bfQu\u00e9 eliges?<\/strong><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"it\" dir=\"ltr\">Rico. <a href=\"https:\/\/t.co\/LjvGHUeL3n\">pic.twitter.com\/LjvGHUeL3n<\/a><\/p>&mdash; 72kilos (@72kilos) <a href=\"https:\/\/twitter.com\/72kilos\/status\/1602390391591927846?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 12, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 7 diciembre 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se empiezan a desvelar las expediciones invernales de esta temporada en el Himalaya.&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/simone-moro-intentara-el-manaslu-invernal-por-quinta-vez\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Simone Moro y \u00c1lex Txikon&nbsp;volver\u00e1n a compartir expedici\u00f3n invernal en el&nbsp;Manaslu<\/strong>&nbsp;<\/a>(8.163 m) por tercer a\u00f1o consecutivo&nbsp;<em>(Desnivel)<\/em>. En el caso de Simone Moro ser\u00e1 su quinto intento invernal a esta monta\u00f1a. Poco se sabe de los aspectos de la expedici\u00f3n, quiz\u00e1s se reunir\u00e1 el equipo en el CB. Txikon se encuentra en Nepal liderando un trekking hacia el campamento base del Makalu y luego tiene agendado otro hasta el CB del Everest. Seguiremos las noticas a esta nueva tentativa invernal.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Estamos en kunghma a 3600m\ud83d\uddfb. La previsi\u00f3n es que lleguemos en 4 d\u00edas las CB del Makalu. La conexi\u00f3n a internet es mala, falla continuamente\u2026 peeeeero lo m\u00e1s importante es que estamos disfrutando de un tiempo incre\u00edble con un grupo de gente s\u00faper maja!\ud83d\udc4f\ud83c\udffb <a href=\"https:\/\/t.co\/NkrwnKhHIO\">pic.twitter.com\/NkrwnKhHIO<\/a><\/p>&mdash; Alex Txikon (@AlexTxikon) <a href=\"https:\/\/twitter.com\/AlexTxikon\/status\/1598705050968129537?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 2, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/gelje-sherpa-vuelve-a-la-cara-sur-del-cho-oyu-este-invierno\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>En la Cara Sur del Cho Oyu este invierno estar\u00e1 Gelje Sherpa<\/strong><\/a><strong>&nbsp;<\/strong>en su tercer intento de abrir una nueva ruta en esta vertiente&nbsp;<em>(Desnivel)<\/em>. Ser\u00eda su catorce ochomil. El equipo lo completan Kristin Harila y Adriana Brownlee.<\/li>\n\n\n\n<li>Cambiando de disciplina,&nbsp;<strong>Omar di Felice abandona su reto ant\u00e1rtico<\/strong>. El cansancio mental ha minado la moral del aventurero. El comienzo de su aventura ha sido m\u00e1s complicado de lo esperado. Una prueba de resistencia mental que le ha quitado una energ\u00eda m\u00e1s que necesaria para afrontar el reto.&nbsp;<strong>La traves\u00eda de la Ant\u00e1rtida en bicicleta (1.600 km) y en solitario quedar\u00e1 para un pr\u00f3ximo intento.&nbsp;<\/strong><em>\u201cDespu\u00e9s de 3 d\u00edas encerrado en mi tienda necesitaba asomar la nariz y recuperar la confianza en m\u00ed mismo. Las condiciones no han sido mejores que las de los \u00faltimos d\u00edas, y el esfuerzo (1h30 para montar la tienda, 3 horas empujando contra el viento y casi 2 horas para montar de nuevo la tienda) puede parecer injustificado para los 4,6 km que he conseguido recorrer, pero necesitaba mantener vivo el sue\u00f1o.\u201d<\/em>, comentaba Omar en su Instagram.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">I\u2019m ok even if sad and shocked. Unfortunately forced to come back Italy due to a problem not related to Antarctica. <br><br>I will be there again: this is a promise. Thanks for your support. <a href=\"https:\/\/twitter.com\/hashtag\/antarcticaunlimited?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#antarcticaunlimited<\/a> \ud83c\udde6\ud83c\uddf6\u267e\ufe0f <a href=\"https:\/\/t.co\/Vi01rHpGRW\">pic.twitter.com\/Vi01rHpGRW<\/a><\/p>&mdash; Omar Di Felice (@omardifelice) <a href=\"https:\/\/twitter.com\/omardifelice\/status\/1600142242152255490?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 6, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">The beginning, more complicated than expected, is affecting my morale rather than the body. It\u2019s a test of mental endurance that is taking away precious energies. <br><br>But, as long as I can, I will go further centimeter by centimeter.<a href=\"https:\/\/twitter.com\/hashtag\/AntarcticaUnlimited?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#AntarcticaUnlimited<\/a> \ud83c\udde6\ud83c\uddf6\u267e\ufe0f <a href=\"https:\/\/t.co\/kkgl3IgRmW\">pic.twitter.com\/kkgl3IgRmW<\/a><\/p>&mdash; Omar Di Felice (@omardifelice) <a href=\"https:\/\/twitter.com\/omardifelice\/status\/1598952394402197504?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 3, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.nevasport.com\/noticias\/art\/63690\/andorra-comenzara-a-cobrar-por-los-rescates-en-la-montana\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Andorra comenzar\u00e1 a cobrar por algunos rescates en el esqu\u00ed y la monta\u00f1a<\/strong><\/a><strong>&nbsp;<\/strong><em>(Nevasport).&nbsp;<\/em>Hasta la fecha se resist\u00eda a aplicar los mismos criterios que los pa\u00edses vecinos. Ahora, ante el incremento del n\u00famero de rescates en los \u00faltimos a\u00f1os, comenzar\u00e1 a cobrar los rescates que se considere propiciados \u201cpor&nbsp;imprudencia o&nbsp;por la pr\u00e1ctica de deportes de riesgo\u201d. Y consideran de riesgo: el&nbsp;esqu\u00ed de monta\u00f1a, el alpino, el paraesqu\u00ed, el snowboard, el bicitrineo o la bicicleta de nieve.&nbsp;<\/li>\n\n\n\n<li>Y cerramos la secci\u00f3n con un tuit que comparten desde la cuenta de&nbsp;<a href=\"https:\/\/twitter.com\/arriskeus\/status\/1600448516588830721?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><em>\u201cRiesgosNaturales, CambioClim\u00e1tico &amp; MedioAmbiente\u201d<\/em><\/a>. En el, nos hacen reflexionar sobre el<strong>&nbsp;futuro de las pistas de esqu\u00ed en los Pirineos en un contexto de Cambio Clim\u00e1tico<\/strong>. La lluvia vuelve a los Pirineos este jueves, y puede alcanzar los 2000m, degradando las condiciones de la nieve en las estaciones en un inicio de temporada complicado. Se preguntan sobre la \u201ccapacidad de alcanzar los objetivos esperados\u201d de la innivaci\u00f3n artificial.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">En un contexto de <a href=\"https:\/\/twitter.com\/hashtag\/emergenciaclim%C3%A1tica?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#emergenciaclim\u00e1tica<\/a> con anomal\u00edas positivas de temp. a lo largo de varios meses al a\u00f1o y una clara irregularidad de las precipitaciones, soluciones planteadas en los a\u00f1os 80 como la innivaci\u00f3n artificial NO tienen capacidad de alcanzar los objetivos esperados. <a href=\"https:\/\/t.co\/3hxM0dtOgd\">pic.twitter.com\/3hxM0dtOgd<\/a><\/p>&mdash; RiesgosNaturales, CambioClim\u00e1tico &amp; MedioAmbiente (@arriskeus) <a href=\"https:\/\/twitter.com\/arriskeus\/status\/1600448516588830721?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 7, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 30 noviembre 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comenzamos con un<a href=\"https:\/\/cumbresmountainmagazine.com\/cumbres-del-mundo\/seven-summits-a-cumbres-del-mundo\/aconcagua-seven-summits-a-cumbres-del-mundo\/un-inedito-desafio-intentaran-esta-temporada-en-aconcagua\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>&nbsp;in\u00e9dito desaf\u00edo en el Aconcagua<\/strong><\/a>&nbsp;<em>(Cumbres)<\/em>:&nbsp;<strong>desde el nivel 0&nbsp;<\/strong>en Buenos Aires hasta los 6.962m de la cima del Aconcagua.&nbsp;<strong>1200 km en bicicleta y el ascenso a pie<\/strong>. Este es el reto de tres italianos: hacerlo en menos de 98 horas. Esta aventura se encuentra dentro de una \u201cserie\u201d; algunos de los desaf\u00edos que ya han cumplido: la traves\u00eda de Venecia a la cima de la Marmolada o completar los 570 km de la v\u00eda Gonnella y ascender al Mont Blanc.<\/li>\n\n\n\n<li><strong>La Fiesta del Oso&nbsp;<\/strong>se celebra en dos municipios andorranos y tres franceses de los Pirineos. \u201c&nbsp;J\u00f3venes disfrazados de osos que llegan desde las afueras de los pueblos interact\u00faan con la poblaci\u00f3n&nbsp;e imitan el rapto de ni\u00f1as\u201d.&nbsp;<a href=\"https:\/\/www.elperiodico.com\/es\/sociedad\/20221129\/fiesta-oso-pirineos-patrimonio-inmaterial-79309686?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Este martes ha sido inscrita en la&nbsp;Lista de Patrimonio Cultural Inmaterial de la Humanidad por la Unesco<\/strong><\/a>&nbsp;<em>(El Peri\u00f3dico)<\/em>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\ud83d\udd34 \u00daLTIMA HORA<br><br>Nueva inscripci\u00f3n en la lista del <a href=\"https:\/\/twitter.com\/hashtag\/PatrimonioInmaterial?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#PatrimonioInmaterial<\/a>: las Fiestas del Oso en los Pirineos.<br><br>\u00a1Felicidades <a href=\"https:\/\/twitter.com\/hashtag\/Andorra?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Andorra<\/a> \ud83c\udde6\ud83c\udde9 y <a href=\"https:\/\/twitter.com\/hashtag\/Francia?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Francia<\/a> \ud83c\uddeb\ud83c\uddf7 ! \ud83d\udc4f<br><br>\u2139\ufe0f <a href=\"https:\/\/t.co\/xDY5qyi0m2\">https:\/\/t.co\/xDY5qyi0m2<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/PatrimonioVivo?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#PatrimonioVivo<\/a> <a href=\"https:\/\/t.co\/fiPrRRdKjH\">pic.twitter.com\/fiPrRRdKjH<\/a><\/p>&mdash; UNESCO en espa\u00f1ol \ud83c\udfdb\ufe0f#Educaci\u00f3n #Ciencia #Cultura (@UNESCO_es) <a href=\"https:\/\/twitter.com\/UNESCO_es\/status\/1597616992223387651?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">November 29, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.heraldo.es\/noticias\/sociedad\/2022\/11\/29\/springfield-campana-moda-glaciares-pirineo-aragones-1615577.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Los glaciares del Pirineo aragon\u00e9s han sido escenario de la campa\u00f1a de sensibilizaci\u00f3n de una marca de ropa<\/strong><\/a><strong>&nbsp;<\/strong>(m\u00e1s concretamente de Springfield)&nbsp;<em>(Heraldo)<\/em>. Se grab\u00f3 en<a href=\"https:\/\/travesiapirenaica.com\/forau-aiguallut\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;<strong>Forau de Aigualluts<\/strong><\/a>&nbsp;frente al glaciar del parque Posets-Maladeta.&nbsp;Objetivo del&nbsp;<em>spot<\/em>&nbsp;\u201c<strong>concienciar sobre la necesidad de frenar el calentamiento del planeta<\/strong>, que est\u00e1 provocando entre otras cosas el deshielo de los glaciares\u201d. Me pregunto si este \u201cenfoque\u201d lo aplican tambi\u00e9n a su filosof\u00eda de empresa y procesos productivos. Diremos que al menos algo es algo, aunque el mensaje sea interesado.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"742\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/Los-glaciares-del-Pirineo-aragones-han-sido-escenario-de-la-campana-de-sensibilizacion-de-una-marca-de-ropa-mas-concretamente-de-Springfield-Heraldo..jpeg\" alt=\"\" class=\"wp-image-34036\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/Los-glaciares-del-Pirineo-aragones-han-sido-escenario-de-la-campana-de-sensibilizacion-de-una-marca-de-ropa-mas-concretamente-de-Springfield-Heraldo..jpeg 990w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/Los-glaciares-del-Pirineo-aragones-han-sido-escenario-de-la-campana-de-sensibilizacion-de-una-marca-de-ropa-mas-concretamente-de-Springfield-Heraldo.-300x225.jpeg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/Los-glaciares-del-Pirineo-aragones-han-sido-escenario-de-la-campana-de-sensibilizacion-de-una-marca-de-ropa-mas-concretamente-de-Springfield-Heraldo.-768x576.jpeg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/Los-glaciares-del-Pirineo-aragones-han-sido-escenario-de-la-campana-de-sensibilizacion-de-una-marca-de-ropa-mas-concretamente-de-Springfield-Heraldo.-150x112.jpeg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/Los-glaciares-del-Pirineo-aragones-han-sido-escenario-de-la-campana-de-sensibilizacion-de-una-marca-de-ropa-mas-concretamente-de-Springfield-Heraldo.-696x522.jpeg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/Los-glaciares-del-Pirineo-aragones-han-sido-escenario-de-la-campana-de-sensibilizacion-de-una-marca-de-ropa-mas-concretamente-de-Springfield-Heraldo.-560x420.jpeg 560w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/Los-glaciares-del-Pirineo-aragones-han-sido-escenario-de-la-campana-de-sensibilizacion-de-una-marca-de-ropa-mas-concretamente-de-Springfield-Heraldo.-80x60.jpeg 80w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/Los-glaciares-del-Pirineo-aragones-han-sido-escenario-de-la-campana-de-sensibilizacion-de-una-marca-de-ropa-mas-concretamente-de-Springfield-Heraldo.-265x198.jpeg 265w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/Los-glaciares-del-Pirineo-aragones-han-sido-escenario-de-la-campana-de-sensibilizacion-de-una-marca-de-ropa-mas-concretamente-de-Springfield-Heraldo.-600x450.jpeg 600w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y cerramos la secci\u00f3n hablando de la nieve que ha vuelto al Pirineo. Los asiduos a la monta\u00f1a invernal est\u00e1n de alegr\u00eda, igual que los amantes del esqu\u00ed de pista.&nbsp;<a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/huesca\/2022\/11\/28\/la-nieve-vuelve-al-pirineo-y-las-estaciones-trabajan-con-vistas-a-abrir-el-fin-de-semana-1615214.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Las estaciones trabajan con vistas a abrir el fin de semana<\/strong><\/a><strong>&nbsp;<\/strong><em>(Heraldo)<\/em>.<strong>&nbsp;<\/strong>Y la apertura de la temporada de esqu\u00ed nos recuerdan los pol\u00e9micos (mega) \u201c<a href=\"https:\/\/www.eldiario.es\/aragon\/economia\/temporada-nieve-pirineo-grandes-expectativas-proyectos-chocan-oposicion-vecinos-ecologistas_1_9751094.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>proyectos que chocan con la oposici\u00f3n de vecinos y ecologistas<\/strong><\/a>\u201d&nbsp;<em>(eldiario)<\/em>, como la futura uni\u00f3n de las estaciones de esqu\u00ed de Ast\u00fan y Candanch\u00fa con Formigal-Panticosa.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Y ahora que las <a href=\"https:\/\/twitter.com\/hashtag\/nubes?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#nubes<\/a> nos dejan verlos, salvo una capa de\u2601\ufe0faltas que cubre el <a href=\"https:\/\/twitter.com\/hashtag\/Pirineo?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Pirineo<\/a> m\u00e1s occidental, as\u00ed lucen los <a href=\"https:\/\/twitter.com\/hashtag\/Pirineos?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Pirineos<\/a> a mediod\u00eda de hoy 30\/11\/22 en el canal visible HRVIS. Hoy <a href=\"https:\/\/twitter.com\/hashtag\/SanAndr%C3%A9s?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#SanAndr\u00e9s<\/a> la\u2744\ufe0fdeber\u00eda estar ya en los &quot;pies&quot;, de momento est\u00e1 en &quot;los altos&quot; <a href=\"https:\/\/t.co\/jmaNJ9rTyj\">pic.twitter.com\/jmaNJ9rTyj<\/a><\/p>&mdash; AEMET_Arag\u00f3n (@AEMET_Aragon) <a href=\"https:\/\/twitter.com\/AEMET_Aragon\/status\/1597917570790617088?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">November 30, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Por encima del Puente de los Navarros las hayas ya est\u00e1n desnudas. S\u00f3lo los abedules aportan una nota de color.<a href=\"https:\/\/twitter.com\/hashtag\/ordesa?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#ordesa<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/oto%C3%B1o?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#oto\u00f1o<\/a> <a href=\"https:\/\/twitter.com\/ordesatorla?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@ordesatorla<\/a> <a href=\"https:\/\/t.co\/9HwOm8EZs5\">pic.twitter.com\/9HwOm8EZs5<\/a><\/p>&mdash; julian morcillo garc (@trailjulian) <a href=\"https:\/\/twitter.com\/trailjulian\/status\/1595389637958275072?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">November 23, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 23 noviembre 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comenzamos con fr\u00edo polar como el que nos ha llegado estos d\u00edas. Ya est\u00e1 todo blanco por las alturas del Pirineo, si. Al l\u00edo. Te cuento por un lado que&nbsp;<strong>Antonio de la Rosa intentar\u00e1 de nuevo<\/strong>&nbsp;(recordar que su intento anterior fue truncado por el Covid y los problemas de log\u00edstica asociados en 2022)&nbsp;<strong>cruzar el Ant\u00e1rtico a remo, vela y esqu\u00eds, ello en solitario<\/strong>, desde el cabo de Hornos hasta la Ant\u00e1rtida, cruzando los casi 1.000km del mar de Hoces. All\u00ed transformar\u00e1 el Ocean Defender con una peque\u00f1a vela para llegar a isla Elefante y emulando a Shackleton navegar\u00e1 2.000km hasta Georgia del Sur, d\u00f3nde ya en tierra firme con sus esqu\u00eds atravesar\u00e1 la isla. Si te has perdido, tranquilidad, que te pongo un video en el que te lo cuenta el mismo:<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Ant\u00e1rtico Remando en Solitario - PROMO 2023 ANTONIO DE LA ROSA\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/drKOQ-0ev-U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y sin dejar las aventuras polares en solitario,&nbsp;<strong>Omar di Felice&nbsp;<\/strong>quiere hacer historia en la Ant\u00e1rtida. Intentar\u00e1 completar la&nbsp;<a href=\"https:\/\/www.revistaoxigeno.es\/deportes\/omar-di-felice-quiere-hacer-historia-en-antartida_268182_102.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>traves\u00eda de la Ant\u00e1rtida en bicicleta (1.600 km) y en solitario<\/strong><\/a>, tambi\u00e9n algo por hacer en la aventura polar&nbsp;<em>(Revista Ox\u00edgeno)<\/em>. El a\u00f1o pasado dio la primera vuelta al mundo en bici por el \u00e1rtico,&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/omar-di-felice-vuelta-al-mundo-artica-en-bici\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed os lo explicamos<\/a>. Tambi\u00e9n tenemos video del reto, bautizado como&nbsp;<em>Antartica Unlimited<\/em>:<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Ferrino with Omar Di Felice for Antartica Unlimited\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/rc_eWYeWlEQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Volviendo a las alturas de la monta\u00f1a.&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/los-rusos-tiran-de-insistencia-para-hacer-cima-en-el-annapurna-iv\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>La insistencia de los rusos ha culminado con la cima del Annapurna IV&nbsp;<\/strong><\/a>(7.525 m)&nbsp;<em>(Desnivel)<\/em>. Dos integrantes de la expedici\u00f3n de 14 miembros, Sasha Eliseev&nbsp;y Andrei Dergachev, han alcanzado la cima prescindiendo del apoyo de los sherpas para el ataque final. Un estilo cl\u00e1sico de expedici\u00f3n en el que han instalado&nbsp;<strong>hasta cinco campamentos de altura<\/strong>.<\/li>\n\n\n\n<li>Ahora os traemos una&nbsp;<strong>entrevista en profundidad de&nbsp;<em>Jot Down sport<\/em><\/strong>, nuevo vertical de la revista que se va a centrar en las grandes historias del deporte.&nbsp;<a href=\"https:\/\/sport.jotdown.es\/2022\/11\/20\/reinhold-messner-el-arte-del-gran-alpinismo-es-no-morir\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Hablan con Reinhold Messner.&nbsp;<\/strong><\/a>\u201cSi entras en una gran pared existe la inc\u00f3gnita de no saber a d\u00f3nde vas, d\u00f3nde terminar\u00e1s, si puedes hacerlo, si encontrar\u00e1s el camino correcto. Es verdaderamente aventura. Primero hay que leer con los ojos por d\u00f3nde pasar.\u201d \u201c<a href=\"https:\/\/sport.jotdown.es\/2022\/11\/20\/reinhold-messner-el-arte-del-gran-alpinismo-es-no-morir\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>El arte del gran alpinismo es no morir\u201d<\/strong><\/a>.<\/li>\n\n\n\n<li>Y nos despedimos con un video de&nbsp;<em>La Sportiva<\/em>&nbsp;que nos llega v\u00eda la<em>&nbsp;Revista Ox\u00edgeno<\/em>&nbsp;<strong><a href=\"https:\/\/www.revistaoxigeno.es\/actualidad\/fracaso-parte-mas-camino_267992_102.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u201cFracaso: una parte m\u00e1s del camino\u201d<\/a>. <\/strong>Varios atletas de \u00e9lite reflexionan sobre el concepto del fracaso en el mundo deporte. \u201cCada \u00e9xito es la cumbre de una monta\u00f1a de fracasos.\u201d<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"FRACASO | La Sportiva\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/IvZc2L0EVHo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 09 noviembre 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arrancamos la secci\u00f3n cont\u00e1ndote que ha finalizado la edici\u00f3n de&nbsp;<strong>Skimetraje&nbsp;<\/strong>tras su retorno despu\u00e9s de la pandemia con un nuevo enfoque y etapa. Como novedades este a\u00f1o los 15 cortos a competici\u00f3n pudieron ser grabados en cualquier parte del mundo, no ya solo en el Pirineo.&nbsp;<a href=\"https:\/\/www.skimetraje.com\/sk-past\/edicion-2022\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u201c<strong>El corto ganador,&nbsp;<em>Dimensi\u00f3n Blanca<\/em>&nbsp;es la pieza protagonizada por el rider&nbsp;Alex Blasco&nbsp;y rodada en Andorra, con el que&nbsp;Mario Manso y Ana G\u00f3mez<\/strong><\/a><strong>&nbsp;<\/strong>logran trasladar la m\u00edstica que rodea la pr\u00e1ctica del esqu\u00ed con unas potentes im\u00e1genes, que a su vez nos hacen reflexionar sobre las terribles consecuencias del cambio clim\u00e1tico.\u201d&nbsp;<em>(Skimetraje)<\/em><\/li>\n\n\n\n<li><a href=\"https:\/\/explorersweb.com\/jost-kobusch-no-everest-this-winter\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Jost Kobusch no intentar\u00e1 el Everest este invierno<\/strong>&nbsp;<\/a><em>(ExplorersWeb)<\/em>. Te cont\u00e1bamos hace unas semanas que el alpinista alem\u00e1n aclimataba en los seismiles de Nepal y ascend\u00eda al Chulu West. Donde contrajo el dengue y fue hospitalizado. Una enfermedad grave que este oto\u00f1o lleno de mosquitos en el pa\u00eds est\u00e1 afectando a muchos alpinistas.&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/jost-kobusch-everest-invernal\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">El a\u00f1o pasado seguimos el proyecto de Jost<\/a>, un reto a 3 a\u00f1os, cuando intent\u00f3 llegar a los 8.000 metros donde comienza el corredor&nbsp;<em>Hornbein&nbsp;<\/em>y ver sus condiciones para el asalto final este a\u00f1o. Kobusch admite que la enfermedad ha sido dura tanto f\u00edsica como mentalmente. \u201cQuiero entrenar, quiero hacer cosas, pero\u2026 mi cuerpo todav\u00eda est\u00e1 demasiado d\u00e9bil\u201d, admiti\u00f3 para&nbsp;<em>Explorers Web<\/em>. Sus planes a corto plazo pasan por ir a Alaska para seguir entrenando para su proyecto de Everest invernal en solitario.<\/li>\n\n\n\n<li>Os compartimos este art\u00edculo de&nbsp;<em>Eldiario.es<\/em>&nbsp;\u201c<a href=\"https:\/\/www.eldiario.es\/aragon\/sociedad\/sobreestimar-capacidades-principal-causa-aumento-numero-rescates-montanas-aragonesas_1_9673237.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Sobreestimar nuestras capacidades, la principal causa del aumento del n\u00famero de rescates en las monta\u00f1as aragonesas<\/strong><\/a>\u201d. Desde&nbsp;<strong>Monta\u00f1a Segura&nbsp;<\/strong>se ha realizado una campa\u00f1a de encuestas a practicantes de actividades en el medio natural aragon\u00e9s, recogiendo datos a m\u00e1s de&nbsp;<a href=\"https:\/\/montanasegura.com\/campana-de-encuestas-2022-a-los-practicantes-de-actividades-en-el-medio-natural\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">8340 personas<\/a>. Estos datos y los propios de los rescates realizados nos dan una idea de las claves de la seguridad en entornos de monta\u00f1a. Algunos datos:&nbsp;<strong>la mitad de los monta\u00f1eros no llevan material para orientarse y un 13% de los senderistas llevan calzado urbano. \u201cLos rescates aumentaron en un 6,3% en la \u00e9poca estival,<\/strong>&nbsp;en la que once personas perdieron la vida\u201d.<\/li>\n\n\n\n<li>Ya sab\u00e9is que&nbsp;<strong>los Hermanos Pou&nbsp;<\/strong>son unos asiduos de esta secci\u00f3n. En esta ocasi\u00f3n&nbsp;<strong>se ha hecho viral&nbsp;<\/strong>(pasando por todos los noticieros) un video suyo en el que realizan la<strong>&nbsp;<\/strong><a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11705\/video-pou-1-escalada-8a?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>1\u00aa escalada de 8a\/+ de 120 metros, y descienden con un salto<\/strong><\/a>&nbsp;<em>(Barrab\u00e9s)<\/em>. Aqu\u00ed no vamos a ser menos y te ponemos tambi\u00e9n el video del salto al Estrecho de Mijares \ud83d\ude09<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"LOS POU ESCALAN PRIMERO Y DESPUES SALTAN EL ESTRECHO DE MIJARES\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/-0HwBqnWBUk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cUn alpinista ecuatoriano pone en la balanza la amistad, el amor y la suerte en su intento de escalar una nueva ruta en una de las monta\u00f1as m\u00e1s altas y peligrosas del mundo.&nbsp;Esteban \u00abTopo\u201d Mena es un gu\u00eda de monta\u00f1a ecuatoriano y estrella emergente del alpinismo cuyo sue\u00f1o es ascender por primera vez una nueva ruta en el Monte Everest. Se une a Cory Richards, un fot\u00f3grafo de National Geographic y el primer estadounidense en escalar un pico de 8.000 metros en invierno, (\u2026)\u201c As\u00ed comienza la sinopsis del&nbsp;<strong>documental \u2018Dhaulagiri\u2019 de Carla P\u00e9rez y Topo Mena<\/strong>. \u201d<a href=\"https:\/\/www.desnivel.com\/expediciones\/expediciones-galeria-multimedia\/video-el-emotivo-dhaulagiri-de-carla-perez-y-topo-mena\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Premiado en los festivales de Florencia y Ouray, el documental de Tommy Joyce sobre la expedici\u00f3n de Carla P\u00e9rez y Esteban \u2018Topo\u2019 Mena al Dhaulagiri<\/strong>&nbsp;en la primavera de 2021 es una de las pel\u00edculas de monta\u00f1a del a\u00f1o<\/a>\u201c&nbsp;<em>(Desnivel)<\/em>. Aqu\u00ed os dejamos la cinta.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Dhaulagiri\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/cHpo4V5No0A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 26 octubre 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.desnivel.com\/cultura\/piolets-dor-2022-para-sean-villanueva-y-los-georgianos-del-saraghrar\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Piolets d\u2019Or 2022 para Sean Villanueva y los georgianos del Saraghrar&nbsp;<\/a><em>(Desnivel)<\/em>. El jurado premia la \u2018The Moonwalk Traverse\u2019 en solitario en el Fitz Roy&nbsp;del escalador belga, la ascensi\u00f3n del Saraghrar Noroeste por parte del tr\u00edo Archil Badriashvili, Baqar Gelashvili y Giorgi Tepnadze. Y la menci\u00f3n especial para el Annapurna III&nbsp;por parte de los ucranianos, que seg\u00fan el jurado fue una ascensi\u00f3n que merec\u00eda m\u00e1s pero el hecho de utilizaci\u00f3n de helic\u00f3ptero para acceder al circo incumple algunos de los punto de la carta de los Piolets d&#8217;Or. Para cerrar esta noticia os voy a poner el video de Sean Villanueva realizando esa traves\u00eda imposible en el Fitz Roy. Ya sab\u00e9is por los videos que os solemos traer aqu\u00ed de Sean, que son muy divertidos.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Moonwalking | Behind the scenes of Sean Villanueva\u2019s solo Fitz Roy traverse\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/85CG527AST0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pasamos ahora a noticias en el Himalaya.&nbsp;<a href=\"https:\/\/www.turiski.es\/kristin-harila-sin-opcion-para-superar-el-record-de-los-14x8000-de-nims\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Kristin Harila lo tiene imposible para superar el r\u00e9cord de los 14&#215;8000 de Nims<\/a>&nbsp;<em>(Turiski)<\/em>. Las condiciones meteorol\u00f3gicas malas impiden que la v\u00eda nepal\u00ed al Cho Oyu se pueda abrir en su totalidad. Recordar que China no le dio autorizaci\u00f3n para ascender el Shisha Pangma y el Cho Oyu. Kristin Harila ascendi\u00f3 a los doce primeros ocho miles en 147 d\u00edas y tenia hasta el 2 de noviembre&nbsp;para completar los 14 y superar a Nirmal Purja. Como os dec\u00edamos, la ruta nepal\u00ed al Cho Oyu por la cara sur tendr\u00e1 que esperar a la pr\u00f3xima temporada.&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/abandonan-las-dos-expediciones-de-la-cara-sur-del-cho-oyu\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Abandonan las dos expediciones: los grupos de Pioneer Adventure y de Seven Summit Treks, la apertura de la cara sur del Cho Oyu<\/a>&nbsp;<em>(Desnivel)<\/em>, ante las condiciones meteorol\u00f3gicas adversas.<\/li>\n\n\n\n<li>Comienza el&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11693\/jost-kobusch-everest-invernal-solitario?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">nuevo intento de Jost Kobusch al Everest invernal en solitario. Lo que sabemos es que se encontraba aclimatando en los seismiles de Nepal y ha sido hospitalizado por dengue<\/a>&nbsp;<em>(Barrabes)<\/em>. El a\u00f1o pasado seguimos el proyecto de Jost, un reto a 3 a\u00f1os, cuando intent\u00f3 llegar a los 8.000 metros donde comienza el corredor&nbsp;<em>Hornbein&nbsp;<\/em>y ver sus condiciones para el asalto final este a\u00f1o. (Puedes seguir el&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/jost-kobusch-everest-invernal\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">timeline de los acontecimiento de su aventura aqu\u00ed<\/a>).<\/li>\n\n\n\n<li><strong>La campeona de escalada iran\u00ed Elnaz Rekabi se ha atrevido a competir sin hiyab en los Campeonatos de Asia&nbsp;<\/strong>que se han disputado en Se\u00fal, y apoyar as\u00ed la revoluci\u00f3n de su pa\u00eds. A su llegada a Teher\u00e1n ha sido vitoreada,&nbsp;<a href=\"https:\/\/elpais.com\/internacional\/2022-10-19\/la-escaladora-irani-que-compitio-sin-velo-llega-a-teheran-entre-aplausos-y-gritos-de-campeona.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u201cpero persiste el temor a que sea encarcelada\u201d<\/a>&nbsp;<em>(El Pa\u00eds)<\/em>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">La campeona de escalada iran\u00ed Elnaz Rekabi se ha atrevido a competir sin hiyab. Salt\u00e1ndose las normas de la federaci\u00f3n iran\u00ed. <br>Es un gesto poderoso y valiente que le puede costar caro. <br>Por eso hay que compartir este v\u00eddeo y difundir su haza\u00f1a. \ud83d\udc9c<a href=\"https:\/\/t.co\/aoycOo3Utx\">pic.twitter.com\/aoycOo3Utx<\/a><\/p>&mdash; Almudena Ariza (@almuariza) <a href=\"https:\/\/twitter.com\/almuariza\/status\/1581754940531576832?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">October 16, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y para cerrar la secci\u00f3n os compartimos el video documental \u201cBravo Marcel\u201d&nbsp;que la marca Mammut ha presentado sobre<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11695\/video-bravo-marcel-larga-vida?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;la vida del alpinista suizo Marcel R\u00e9my, \u201cque falleci\u00f3 este verano a los 99 a\u00f1os<\/a>, y se mantuvo escalando hasta el fin de sus d\u00edas\u201d&nbsp;<em>(Barrabes)<\/em>. Una vida que va a inspirar a muchas personas, sin lugar a dudas.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Bravo Marcel | The life of Swiss climbing legend Marcel Remy\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/XUfK-N_SMTo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Jueves, 13 octubre 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comenzamos la secci\u00f3n cont\u00e1ndote c\u00f3mo se ha desarrollado el reto del corredor catal\u00e1n Eugeni Rosell\u00f3 en el Camino de Santiago, lo completa en&nbsp;<a href=\"https:\/\/carreraspormontana.com\/retos\/eugeni-rosello-parte-a-por-el-record-del-camino-de-santiago-8\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">6 d\u00edas y 22 horas. Eugeni Rosell\u00f3 lleg\u00f3 a la plaza del Obradoiro a las 7:04h, tras superar 800 km y 11.000 m+ y qued\u00e1ndose a 12h del MTC de Miguel Mataix&nbsp;<\/a><em>(Carreras por Monta\u00f1a)<\/em>. Os dejamos un video de Rosell\u00f3 cuando le quedaba claro que no batir\u00eda el r\u00e9cord pero si cumplir\u00eda con su objetivo de llega a Santiago.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">No batir\u00e1 el r\u00e9cord (6d10h15&#39;) pero <a href=\"https:\/\/twitter.com\/EugeniRosello?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@EugeniRosello<\/a> est\u00e1 dando un gran ejemplo de determinaci\u00f3n y compromiso con su objetivo en el <a href=\"https:\/\/twitter.com\/hashtag\/CaminoNonStop?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#CaminoNonStop<\/a>. As\u00ed nos lo contaba anoche.<br><br>\ud83d\udcf9 plumadron <a href=\"https:\/\/t.co\/VIiBIKow8a\">pic.twitter.com\/VIiBIKow8a<\/a><\/p>&mdash; Carreras por monta\u00f1a (@CarrerasTrail) <a href=\"https:\/\/twitter.com\/CarrerasTrail\/status\/1578664914926784512?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">October 8, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y como hemos comenzado a la \u201ccarrera\u201d continuamos con la velocidad, como la de&nbsp;<a href=\"https:\/\/www.desnivel.com\/alpinismo\/filip-babicz-asciende-el-grand-capucin-en-49-minutos-de-solo-integral\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Filip Babicz al ascender el Grand Capucin en 49 minutos de solo integral<\/a>&nbsp;<em>(Desnivel)<\/em>, para completar 570 metros que incluyen partes de la v\u00eda \u2018Suiza\u2019 y de la \u2019O Sole Mio\u2019. Y tambi\u00e9n esta semana el propio Filip ha compartido el video de su<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11679\/video-filip-babicz-arista-norte?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;r\u00e9cord a la arista norte del Piz Badile en 42:53 minutos&nbsp;<\/a><em>(Barrabes)<\/em>, que realiz\u00f3 hace un a\u00f1o. La de la Piz Badile es una ruta emblem\u00e1tica de las mejores en su grado IV+V- de los Alpes. El alpinista polaco se ha especializado en las escaladas express a las grandes cl\u00e1sicas de los Alpes. A continuaci\u00f3n ten\u00e9is el video.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Nordkante Piz Badile Speed Record\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/lPIC9UIlEas?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"http:\/\/www.pioletsdor.net\/index.php\/en\/2022-silvo-karo?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">El alpinista esloveno de 61 a\u00f1os Silvo Karo recibir\u00e1 el 14\u00ba Premio Piolets d&#8217;Or Carri\u00e8re a la Trayectoria<\/a>. La ceremonia de entrega del premio se celebrar\u00e1 del 17 al 20 de noviembre en Brian\u00e7on (Francia). Silvo ha escalado m\u00e1s de 2000 rutas y ha realizado m\u00e1s de 300 primeras ascensiones, adem\u00e1s de escaladas de velocidad en sus Alpes Julianos y Kamnik. Quiz\u00e1s los mayores logros de su carrera sean la&nbsp;<strong>cara oeste del Bhagirathi III, en el Himalaya hind\u00fa, la primera escalada de la cara sur del Cerro Torre&nbsp;<\/strong>o la apertura de la cara sur de la Torre Egger.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Os compartimos el<strong>&nbsp;art\u00edculo de Christian Pau:<\/strong><a href=\"https:\/\/christianpau.blogspot.com\/2022\/10\/manaslu-la-palabra-sofa-como-comodin.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>&nbsp;<\/strong>\u201cManaslu, la palabra \u00absofa\u201d como comod\u00edn\u00bb en Monta\u00f1as de Camille<\/a>, en el que hace un recorrido hist\u00f3rico desde que Toshio Imanishi y Gyalzen Norbu Sherpa&nbsp;escalaron por primera vez el&nbsp;Manaslu en 1956, y nos cuenta los diferentes hechos y mucho de lo que se ha hablado reci\u00e9ntemente sobre la verdadera y falsa cumbre del Manaslu.&nbsp;<em>\u201cLa verdadera cima del Manaslu, fotografiada y grabada para documental en 1956.&nbsp;<\/em><strong><em>Medio siglo despu\u00e9s, a muchos y muchas alpinistas que la merodean, les cuesta encontrarla.\u201d<\/em><\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/huesca\/2022\/10\/04\/por-que-tantos-montaneros-acaban-enriscados-1603423.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u00bfPor qu\u00e9 tantos monta\u00f1eros acabaron enriscados el fin de semana?<\/a>&nbsp;<em>(Heraldo)<\/em>&nbsp;El pasado fin de semana:&nbsp;de los 12 excursionistas auxiliados por la&nbsp;Guardia Civil, ocho fueron por encontrarse enriscados.&nbsp;&nbsp;Una de las causas: tras las primeras nevadas de oto\u00f1o la monta\u00f1a \u201cest\u00e1 complicada\u201d.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">La Guardia Civil de Huesca rescata a ocho monta\u00f1eros enriscados este fin de semana <a href=\"https:\/\/t.co\/1JkKjJyaiu\">https:\/\/t.co\/1JkKjJyaiu<\/a><\/p>&mdash; Alberto Ayora (@seguridadriesgo) <a href=\"https:\/\/twitter.com\/seguridadriesgo\/status\/1576819189502726145?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">October 3, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 28 septiembre 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arrancamos la secci\u00f3n con el reto de los&nbsp;<strong>14\u00d78000 en un mismo a\u00f1o de la alpinista noruega Kristin Harila<\/strong>, que quiere emular el r\u00e9cord de los 14 de Nirmal Purja. A Harila<strong>&nbsp;le acompa\u00f1an los nepalies Dawa Ongju Sherpa y Pasdawa Sherpa.&nbsp;<\/strong><a href=\"https:\/\/www.turiski.es\/kristin-harila-corona-el-manaslu-y-esta-a-dos-cimas-de-los-14-ochomiles\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>Suman los tres el 12\u00ba ochomil del a\u00f1o con la ascensi\u00f3n al Manaslu<\/strong><\/a><strong>&nbsp;<\/strong><em>(Turiski)<\/em>. \u00abel ascenso fue dif\u00edcil, pero quer\u00edamos llegar a la cima de Manaslu a la primera oportunidad para evitar la multitud de escaladores que esperaban en el campamento base.\u00bb, comenta Harila. Ahora el principal escollo con el que se encuentran es conseguir los permisos chinos de ascensi\u00f3n al Shisha Pangma y el Cho Oyu, sus \u00faltimos ochomiles para conseguir el reto. Deber\u00edan hacerlo antes del 2 de noviembre si quieren batir el r\u00e9cord de Nirmal Purja. Desde aqu\u00ed queremos tambi\u00e9n matizar que frente a lo vistoso de estas haza\u00f1as, nada tienen que ver en medios y \u201cfilosof\u00eda\u201d con otras grandes gestas que os traemos a esta secci\u00f3n de noticias cada semana \u2014utilizaci\u00f3n de ox\u00edgeno suplementario entre otras\u2014.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sin movernos del Manaslu<\/strong>&nbsp;os contamos que en los \u00faltimos d\u00edas ha habido un enorme caos, y dramas, con una avalancha que ha barrido la monta\u00f1a.&nbsp;<a href=\"https:\/\/explorersweb.com\/manaslu-summits-deaths-chaos\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u201cAl menos un alpinista ha muerto y unos 12 han resultado heridos cerca del campo 4 tras la importante avalancha\u201d<\/a>&nbsp;<em>(explorersweb).&nbsp;<\/em>Phurba Sonam Sherpa, gu\u00eda del equipo&nbsp;Elite Expedition&nbsp;<a href=\"https:\/\/www.instagram.com\/reel\/Ci1mZpzph-v\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">comparti\u00f3 un video en el que se ve el descomunal volumen de nieve e hielo cayendo<\/a>&nbsp;monta\u00f1a abajo. Ha sido tambi\u00e9n&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/hallado-el-cuerpo-sin-vida-de-hilaree-nelson-en-el-manaslu\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">hallado el cuerpo sin vida de Hilaree Nelson en el Manaslu<\/a>&nbsp;<em>(Desnivel)<\/em>. Hilaree Nelson&nbsp;desapareci\u00f3 el lunes por la ma\u00f1ana en la parte alta del&nbsp;Manaslu&nbsp;(8.163 m), despu\u00e9s de haber alcanzado la cumbre junto con su compa\u00f1ero&nbsp;Jim Morrison, para descender esquiando.<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/Ci1mZpzph-v\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/reel\/Ci1mZpzph-v\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Ver esta publicaci\u00f3n en Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/reel\/Ci1mZpzph-v\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida de Phurba Sonam Sherpa (@phurba_sonam_sherpa)<\/a><\/p><\/div><\/blockquote> <script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.deia.eus\/otros-deportes\/2022\/09\/23\/mendi-film-premia-martinez-pison-6041256.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">El ge\u00f3grafo, escritor y alpinista vallisoletano&nbsp;Eduardo Mart\u00ednez de Pis\u00f3n&nbsp;ser\u00e1&nbsp;galardonado por el Mendi Film 2022&nbsp;<\/a><em>(Deia)<\/em>, que&nbsp;se celebrar\u00e1 del 9 al 18 de diciembre, con el premio Fundaci\u00f3n Walk On Proyect (WOP) por su labor en la defensa y la divulgaci\u00f3n de los valores del alpinismo.<\/li>\n<\/ul>\n\n\n\n<p>\u201c<em>Es un honor para nosotros reconocer con el&nbsp;<\/em><a href=\"http:\/\/mendifilmfestival.com\/MFF\/index.php\/es\/2015-05-31-19-10-25\/notas-de-prensa\/100-noticias-2021\/7408-eduardo-martinez-de-pison-recibira-el-premio-wop-mendi-film-2022-en-la-15-edicion-del-bbk-mendi-film-bilbao-bizkaia?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Premio Fundaci\u00f3n WOP Mendi Film a Eduardo Mart\u00ednez de Pis\u00f3n<\/em><\/a><em>. Eduardo es un enamorado de la naturaleza y muy especialmente de la monta\u00f1a. Un enamoramiento erudito, trascendente y comprometido desde la responsabilidad que siente con ella y en la que se reconoce a s\u00ed mismo. Una naturaleza que ha configurado su vida al completo desde lo m\u00e1s accesorio a lo m\u00e1s espiritual. Un territorio que, siendo un paisaje cargado de cultura, se ha convertido en su morada y fuente de felicidad y pasi\u00f3n. Unos paisajes en los que ha vivido y a los que ha ense\u00f1ado a mirar y ver a tantas y tantas personas, transmiti\u00e9ndoles su amor por ellos. Por su vida de autenticidad, compromiso, pasi\u00f3n, protecci\u00f3n de nuestros \u201cpaisajes\u201d y por su incansable tarea de transmisi\u00f3n inspiradora de esos valores, nos emociona y es un orgullo para nosotros, otorgarle a Eduardo Mart\u00ednez de Pis\u00f3n el Premio Fundaci\u00f3n WOP a la defensa y transmisi\u00f3n de los valores sociales del alpinismo<\/em>\u201d.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11672\/pirineismo-luto-fallece-jean-ravier?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">La leyenda de los Pirineos Jean Ravier ha fallecido a los 88 a\u00f1os tras una larga y fruct\u00edfera vida<\/a>&nbsp;<em>(Barrabes)<\/em>. Couloir de Gaube, Tozal del Mallo en Ordesa, Piton Carre al Vignemale, cara norte de la Grand Aiguille d&#8217;Ansab\u00e8re, espol\u00f3n norte del Midi d&#8217;Ossau, cara norte de la Torre de Marbor\u00e9, Pilar de la Embarad\u00e8re\u2026; toda monta\u00f1a emblem\u00e1tica en los Pirineos tiene la cl\u00e1sica de los hermanos Ravier. &nbsp;Participaron tambi\u00e9n en expediciones himal\u00e1yicas de gran renombre hist\u00f3rico como la del Jannu de 1962, con la flor y nata del alpinismo franc\u00e9s, como Lionel Terray.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y para cerrar nos vamos a la cima del&nbsp;<strong>Monte Perdido<\/strong>, donde se ha procedido a&nbsp;<a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/huesca\/2022\/09\/24\/la-cima-de-monte-perdido-se-libra-del-dragon-1601318.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">retirar basura que acumulaba la cima, incluyendo la figura de forja de San Jorge luchando contra el drag\u00f3n instalada sin permiso en la cima<\/a>&nbsp;<em>(Heraldo)<\/em>. Est\u00e1 acci\u00f3n se realiza aprovechando los trabajos de sustituci\u00f3n del punto geod\u00e9sico actual que lleva en la cima ni m\u00e1s ni menos que cuarenta a\u00f1os.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 27 julio 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arrancamos hablando del fruct\u00edfero verano de&nbsp;<strong>Denis Urubko<\/strong>&nbsp;en el Karak\u00f3rum. Primero fue una&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/denis-urubko-y-benjamin-vedrines-se-suben-al-broad-peak-express\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>ascensi\u00f3n express de 14h40\u2019 al Broad Peak desde el CB<\/strong><\/a>. Urubko hab\u00eda ya ascendido a la monta\u00f1a en dos ocasiones anteriores. Ahora&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/denis-urubko-suma-su-25o-ochomil-con-otra-cima-express-en-el-gasherbrum-ii\/\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>suma su 25\u00ba ochomil con otra cima express en el Gasherbrum II<\/strong><\/a>&nbsp;<em>(Desnivel)<\/em>. Quinta vez en el G2. Lo hizo en 15h20\u2019 para llegar a la cima y 25 horas para regresar, estando a solo un ochomil del r\u00e9cord de Juanito Oiarzabal con 26 ascensiones sin ox\u00edgeno a ochomiles. Y el verano contin\u00faa para Denis que tiene permiso para la ascensi\u00f3n de cuatro ochomiles en la zona del Baltoro (Broad Peak, K2 y los dos Gasherbrums). Iremos siguiendo sus pasos.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.planetmountain.com\/en\/news\/alpinism\/edu-marin-makes-second-free-ascent-eternal-flame-on-nameless-tower.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Edu Mar\u00edn realiza la segunda ascensi\u00f3n libre de \u2018Eternal flame\u2019<\/strong>&nbsp;<\/a>en la Nameless Tower (6251m) en la cordillera de la Trango Tower en Pakist\u00e1n&nbsp;<em>(Planet Mountain)<\/em>. Despu\u00e9s de estar muy cerca de conseguirlo en el verano de 2021, ahora escalando con el apoyo de su hermano \u00c1lex y su padre Francisco, el escalador catal\u00e1n Edu Mar\u00edn lo ha conseguido tras permanecer 28 d\u00edas en la pared.&nbsp;<a href=\"https:\/\/woguclimbing.com\/eternal-flame-decimo-aniversario-primera-ascension-en-libre-karakorum\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>La ruta&nbsp;<\/strong><\/a>estableci\u00f3 un hito en la escalada de pared a gran altura, cuando Wolfgang Gullich, Kurt Albert, Christof Stiegler y Milan Sykora la abrieron por primera vez en 1989. Veinte a\u00f1os despu\u00e9s, Alex y Thomas Huber realizaron la primera escalada en libre con algunas variantes. Tras solo dos jornadas de que lo consiguiera Mar\u00edn,<strong>&nbsp;<\/strong><a href=\"https:\/\/www.desnivel.com\/escalada-roca\/barbara-zangerl-y-jacopo-larcher-tambien-repiten-eternal-flame-en-libre\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>la austriaca Barbara Zangerl y el italiano Jacopo Larcher tambi\u00e9n repiten \u2018Eternal flame\u2019<\/strong><\/a><strong>&nbsp;en libre en 6 d\u00edas<\/strong>&nbsp;<em>(Desnivel)<\/em>. Todos ellos tambi\u00e9n coincidieron en la monta\u00f1a en 2021.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Venimos varias semanas hablando de los efectos del&nbsp;<strong>cambio clim\u00e1tico<\/strong>&nbsp;en las condiciones de los glaciares. El exponente m\u00e1s dram\u00e1tico y actual ha sido el desplome parcial del glaciar de la Marmolada en los Alpes italianos, que ha dejado 11 muertos. En el&nbsp;<strong>Mont Blanc<\/strong>&nbsp;los riesgos no son menores: \u201c<a href=\"https:\/\/www.desnivel.com\/cultura\/ecologia\/alerta-climatica-en-el-mont-blanc-rutas-peligrosas-y-0oc-en-la-cima\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>los gu\u00edas de Chamonix y de Courmayeur evitan este verano las rutas normales<\/strong>&nbsp;al techo de los Alpes debido al elevado riesgo de desprendimientos de roca y desplome de seracs<\/a>\u201d&nbsp;<em>(Desnivel)<\/em>.&nbsp; En los Pirineos, \u201c<a href=\"https:\/\/www.lavanguardia.com\/natural\/20220722\/8393604\/requiem-ultimos-glaciares-pirineodel-plas-masas-heladas-ultimos-glaciares-pirineo-han-perdido-20-superficie-9-anos.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>los \u00faltimos glaciares del Pirineo han perdido una cuarta parte de su superficie en 9 a\u00f1os\u201d<\/strong><\/a><em>&nbsp;(La Vanguardia).&nbsp;<\/em>El retroceso de los glaciares trae consigo tambi\u00e9n que aparezcan situaciones de gran riesgo para el pirineista. En esta entrevista en la revista&nbsp;<em>Cumbres<\/em>,&nbsp;<a href=\"https:\/\/cumbresmountainmagazine.com\/cumbres-del-mundo\/europa\/espana\/jonatan-garcia-peligrosas-condiciones-glaciar-aneto\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Jonatan Garc\u00eda nos advierte por ejemplo de las peligrosas condiciones en el glaciar del Aneto<\/strong><\/a>. Con zonas en las que el hielo es&nbsp;\u201cnegro y muy duro, parecido al m\u00e1rmol\u201d, en zonas complicadas, \u201cuna inclinaci\u00f3n perfecta, haciendo una diagonal, es muy dif\u00edcil no tener un accidente\u201d, apunta Garc\u00eda.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y los \u00faltimos d\u00edas han llegado de nuevo im\u00e1genes de una cola interminable de personas ascendiendo al K2, aprovechando la ventana de buen tiempo, concretamente en la zona despu\u00e9s del cuello de botella. Y es que&nbsp;<a href=\"https:\/\/elpais.com\/deportes\/2022-07-27\/atasco-en-el-k2-unos-150-alpinistas-hacen-cima-en-un-solo-dia-casi-la-mitad-que-en-toda-la-historia.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">unos 150 alpinistas han hecho cima en un solo d\u00eda, casi la mitad que en toda la historia<\/a>&nbsp;<em>(El Pa\u00eds)<\/em>. Recuerdan otras im\u00e1genes que hemos visto por ejemplo de la cima del Everest. Masificaci\u00f3n total en las ascensiones a ochomiles. Circulaban por la red tuit ir\u00f3nicos como el que compartimos a continuaci\u00f3n de @KrisAnnapurna<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"fr\" dir=\"ltr\">Nonsense and humans. <a href=\"https:\/\/t.co\/cjoCC5QrdG\">pic.twitter.com\/cjoCC5QrdG<\/a><\/p>&mdash; k2 (@KrisAnnapurna) <a href=\"https:\/\/twitter.com\/KrisAnnapurna\/status\/1552048041246474240?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 26, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 13 julio 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arrancamos la secci\u00f3n con un aviso que nos dan desde el GREIM si tenemos planificada para estos d\u00edas la<strong>&nbsp;subida al Aneto<\/strong>. Nos sugieren&nbsp;<a href=\"https:\/\/twitter.com\/montana_segura\/status\/1544957989416849408?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>evitar la ruta por el Portill\u00f3n Superior y optar por pasar por el ib\u00f3n de Salterillo<\/strong><\/a>. Las condiciones del glaciar son muy peligrosas debido a la dureza del hielo. En el siguiente tuit de Monta\u00f1a Segura nos explican las dos alternativas que tenemos con acceso a las fichas explicativas de cada una.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Nota de la <a href=\"https:\/\/twitter.com\/guardiacivil?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@guardiacivil<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/GREIM?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#GREIM<\/a> sobre el <a href=\"https:\/\/twitter.com\/hashtag\/Aneto?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Aneto<\/a>: Las condiciones del glaciar del ANETO son especialmente PELIGROSAS debido a la dureza de su hielo. Se recomienda EVITAR LA RUTA POR EL<br>PORTILL\u00d3N SUPERIOR y optar por las rutas del ib\u00f3n del SALTERILLO.<a href=\"https:\/\/twitter.com\/112Aragon?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@112Aragon<\/a> <a href=\"https:\/\/twitter.com\/internetfam?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@internetfam<\/a> <a href=\"https:\/\/t.co\/cYjdYnpiVz\">pic.twitter.com\/cYjdYnpiVz<\/a><\/p>&mdash; Monta\u00f1a Segura (@montana_segura) <a href=\"https:\/\/twitter.com\/montana_segura\/status\/1544957989416849408?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 7, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/cumbresmountainmagazine.com\/actualidad\/montana-estival\/expediciones-montana-estival\/alud-hielo-nieve-kyrgyzstan\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>\u00bfHab\u00e9is visto el espectacular video del alud de nieve y hielo en Kyrgyzstan?<\/strong><em>&nbsp;<\/em><\/a><em>(Cumbres)<\/em><strong>&nbsp;<\/strong>Un alpinista brit\u00e1nico lo grab\u00f3 y comparti\u00f3. Poco tard\u00f3 en hacerse viral. Literalmente le pas\u00f3 por encima en las monta\u00f1as Tian Shan, en Kyrgyzstan. Todos los integrantes del grupo resultaron ilesos.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"El impresionante alud de hielo y nieve en Kyrgyzstan\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/XBy4R46CnuA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><em>\u201cMe refugie detr\u00e1s de una roca, dentro de la ventisca. Una vez que termin\u00f3, la adrenalina me golpe\u00f3 con fuerza. S\u00f3lo qued\u00e9 cubierto por una peque\u00f1a capa de nieve, sin ning\u00fan rasgu\u00f1o. Cuando me reincorpor\u00e9 al grupo pude ver que todos estaban a salvo, aunque un integrante se hab\u00eda cortado bastante la rodilla (mont\u00f3 en uno de los caballos hasta el centro m\u00e9dico m\u00e1s cercano). Otra se hab\u00eda ca\u00eddo de un caballo y hab\u00eda sufrido algunas contusiones leves.\u201d<\/em><a href=\"https:\/\/www.instagram.com\/p\/CfyT6xcA27D\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u2014Harry Shimmin<\/a><\/p>\n\n\n\n<p>Estos aludes extraordinarios, as\u00ed como noticias como con la que hemos abierto la secci\u00f3n (el estado del glaciar del Aneto), nos enfrentan de lleno con los efectos acelerados del calentamiento global.&nbsp;<a href=\"https:\/\/www.desnivel.com\/alpinismo\/once-victimas-balance-final-de-la-tragedia-de-la-marmolada\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=pocket_mylist\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Solo hace unos d\u00edas el desplome de un serac en la Marmolada provocaba once victimas<\/strong><\/a><em> (Desnivel)<\/em>. Una amenaza que se extiende a otros puntos tanto de los Alpes como de los Pirineos.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se abre la pol\u00e9mica:&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/investigacion-8000ers-solo-ed-viesturs-y-veikka-gustafsson-habrian-completado-los-catorce-sin-oxigeno\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Seg\u00fan una investigaci\u00f3n de 8000ers, solo Ed Viesturs y Veikka Gustafsson habr\u00edan completado los Catorce sin ox\u00edgeno<\/strong><\/a>&nbsp;<em>(Desnivel)<\/em>. Seg\u00fan Eberhard Jurgalski la mayor\u00eda de catorceochomilistas no habr\u00eda alcanzado la cumbre verdadera del Manaslu. Con ox\u00edgeno suplementario tambi\u00e9n habr\u00eda alcanzado los 14 ochomiles Nirmal Purja. En el<a href=\"https:\/\/christianpau.blogspot.com\/2022\/07\/una-nueva-era-en-el-ochomilismo-el.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;<strong>post de Monta\u00f1as de Camille<\/strong><\/a><strong>&nbsp;<\/strong>pod\u00e9is ver una traducci\u00f3n del&nbsp;<strong>art\u00edculo de<\/strong>&nbsp;<strong>Eberhard Jurgalski&nbsp;<\/strong>en el que hace un repaso a los entresijos de la investigaci\u00f3n. Y como veis por el tuit de Sebastian Alvaro que os enlazo a continuaci\u00f3n, el \u201csalseo\u201d y la discrepancias a la investigaci\u00f3n est\u00e1n servidas. Seg\u00fan Alvaro \u00abhay debate sobre el Manaslu, que es interesado por parte de las comerciales.\u201c&nbsp;<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">1- Querido Aitor, pero se queda en un fuego de artificio. Y, nada es inocente, en favor del \u00ednclito Nirmal. Es decir Eberhard nos propone (con un informe que no tiene el rigor que deber\u00eda tener un periodista) cambiar a Messner, Kukuczka, I\u00f1urrategui, Juanito y Loretan, por Nirmal <a href=\"https:\/\/t.co\/zCP9rWuh3I\">https:\/\/t.co\/zCP9rWuh3I<\/a><\/p>&mdash; Sebastian Alvaro (@sebas_alvaro) <a href=\"https:\/\/twitter.com\/sebas_alvaro\/status\/1546452413950955520?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 11, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La expedici\u00f3n de los Pou en los Andes continua.&nbsp;<a href=\"https:\/\/www.desnivel.com\/alpinismo\/one-push-cuarta-via-de-los-pou-en-los-andes-con-micher-quito\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Iker y Eneko Pou, junto al andinista Micher Quito abren \u201cOne push\u201d (M.7\/85\u00b0\/V\/1.000 m), l\u00ednea que surca la cara &nbsp;suroeste del Pumahuacanca, en la Cordillera Blanca<\/strong><\/a>&nbsp;<em>(Desnivel)<\/em>. La que catalogan como su mejor ruta de alpinismo.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">&quot;ONE PUSH&quot; M.7\/85\u00b0\/V\/1.000 m \ud83d\udca5: ABRIMOS NUESTRA MEJOR RUTA DE ALPINISMO \ud83d\ude00\ud83d\ude4c<br><br>WE OPEN OUR BEST HIGH MOUNTAIN ROUTE \ud83d\ude4c <br><br>&quot;ONE PUSH&quot; M.7\/85\u00b0\/V\/1.000 m \ud83d\udca5: GURE ALPINISMO ko BIDE ONENA IREKITZEN DUGU \ud83d\ude00\ud83d\ude4c <a href=\"https:\/\/twitter.com\/thenorthface?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@thenorthface<\/a><a href=\"https:\/\/twitter.com\/LaSportiva?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@lasportiva<\/a> <a href=\"https:\/\/twitter.com\/Petzl?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@petzl<\/a> @arabakoforualdundia <a href=\"https:\/\/twitter.com\/leathermam?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@leathermam<\/a> <a href=\"https:\/\/twitter.com\/totemmt?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@totemmt<\/a> <a href=\"https:\/\/t.co\/TsiZqU10T5\">pic.twitter.com\/TsiZqU10T5<\/a><\/p>&mdash; Hermanos Pou (@hermanospou) <a href=\"https:\/\/twitter.com\/hermanospou\/status\/1547108194438320129?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 13, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 29 junio 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/carreraspormontana.com\/carreras\/sara-alonso-gana-el-marathon-du-mont-blanc-2022-y-se-pone-lider-de-las-golden\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Sara Alonso gana el Marathon du Mont-Blanc 2022<\/a><em>&nbsp;(Carreras por Monta\u00f1a).&nbsp;<\/em>En Zegama ya apunt\u00f3 que se encontraba entre las mejores con su meritorio podio. As\u00ed se lleva su primer triunfo en las Golden Trail Series y se pone l\u00edder. Tambi\u00e9n fue vencedor Jonathan Albon.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\ud83d\udca3\ufe0f Sara Alonso, la m\u00e1s r\u00e1pida en el Marathon du Mont-Blanc <br><br>\ud83d\udc49 Tras su meritorio podio en <a href=\"https:\/\/twitter.com\/ZegamaAizkorri?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@ZegamaAizkorri<\/a> , la vasca rompe los 42 km y 2.540 m+ y suma su primera gran victoria en las Golden Trail Series. <br><br>\ud83d\udcf8 <a href=\"https:\/\/twitter.com\/jsaragossa?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@jsaragossa<\/a> <a href=\"https:\/\/t.co\/lfYzgdmVuO\">pic.twitter.com\/lfYzgdmVuO<\/a><\/p>&mdash; Carreras por monta\u00f1a (@CarrerasTrail) <a href=\"https:\/\/twitter.com\/CarrerasTrail\/status\/1541030279166451715?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 26, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.desnivel.com\/alpinismo\/jonatan-garcia-enlaza-las-crestas-de-salenques-llosas-y-alba-en-20-horas\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Las crestas cl\u00e1sicas de Salenques-Tempestades, Llosas y la cresta de los 15 Gendarmes de Alba en 20 horas por Jonatan Garc\u00eda&nbsp;<\/a><em>(Desnivel)<\/em>. 59 km y 4.315 metros de desnivel positivo a lo que ha bautizado<strong>&nbsp;\u2018Tr\u00edo de ases\u2019<\/strong>, de Benasque a Benasque en bici y a pie. Esta aventura se encuentra dentro de los proyectos personales de Jonatan como el de la \u201c<a href=\"https:\/\/www.desnivel.com\/alpinismo\/jonatan-garcia-escala-los-51-tresmiles-del-macizo-maladeta-aneto-en-34-horas-desde-benasque\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Vuelta al mundo<\/a>\u201d como llam\u00f3 a subir a los&nbsp;51 tresmiles del macizo Maladeta-Aneto que realiz\u00f3 en 34 horas.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11586\/video--pou-micher-quito?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Los hermanos Pou y el Huaracino Micher Quito abren 2 nuevas v\u00edas y cima virgen en los Andes<\/a>&nbsp;<em>(Barrabes)<\/em>, apertura de \u2018Hanan Pacha\u2019 90\u00ba\/425m y \u2018EMMOA\u2019 M6\/75\u00ba\/640m en los Urus. Sigue siendo fruct\u00edfero el viaje de los hermanos alaveses en la Cordillera Blanca del Per\u00fa. Los Pou se hab\u00edan fijado en este macizo la temporada anterior (2.021), cuando en la ultima actividad en la que recorrieron la quebrada de Ishinca, repararon en estas monta\u00f1as dif\u00edciles y muy poco transitadas.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"PER\u00da 22 - HANAN PACHA\u201d 90\u00ba\/425 m al Urus Oeste  y \u201cEMMOA\u201d M.6\/75\u00ba\/640 m al Urus Oeste III\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/yJKtXCVg_oc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/youtu.be\/FLzFSBfxF7U?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Carros de Foc estrena documental<\/a>&nbsp;<em>(diaridelaneu)<\/em>. La Travessa dels Refugis se presentar\u00e1 por primera vez en el Garmin Mountain Festival del Valle de Bo\u00ed y en la Val d&#8217;Aran by UTMB. La&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/carros-de-foc\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">ruta de Carros de Foc&nbsp;<\/a>es mucho m\u00e1s que una traves\u00eda de monta\u00f1a. \u201cEs un itinerario que deja una impronta imborrable en todo aquel que se atreve a adentrarse en su mundo abrupto: un c\u00famulo de im\u00e1genes, sensaciones, paisajes y experiencias, un caleidoscopio de roca, nieve, viento y naturaleza en estado puro\u201d.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"TEASER CARROS DE FOC\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/FLzFSBfxF7U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Jueves, 16 junio 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comenzamos cont\u00e1ndote que s<a href=\"https:\/\/www.desnivel.com\/cultura\/encontrada-la-otra-bota-de-gunther-messner-en-el-nanga-parbat\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">e ha encontrado la otra bota de &nbsp;G\u00fcnther Messner en el Nanga Parbat<\/a>&nbsp;<em>(Desnivel)<\/em>. Lo ha anunciado Reinhold Messner. Se ha hallado a los pies del glaciar Diamir y corrobora el relato de Reinhold sobre la desgracia de hace 52 a\u00f1os, lo que es uno de los episodios hist\u00f3ricos tr\u00e1gicos del himalayismo. Los hermanos Messner hicieron cumbre en el Nanga Parbat el 27 de junio de 1970 por la primera a la vertiente del Rupal, y descendieron por la vertiente del Diamir. Ello constitu\u00eda la primera traves\u00eda la monta\u00f1a. Ya en la base del Diamir G\u00fcnther desapareci\u00f3 sepultado por una avalancha. <\/li>\n\n\n\n<li><a href=\"https:\/\/woguclimbing.com\/los-hermanos-pou-liberan-aupa-gasteiz-160m-7c-una-via-por-encima-de-los-4-000-metros-de-altitud\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Los hermanos Pou escalan en libre \u2018\u00a1A\u00fapa Gasteiz!\u2018 (160m 7c+), en la Quebrada de Yaca, una ruta por encima de los 4.000 metros de altitud<\/a>&nbsp;<em>(Woguclimbing)<\/em>. Culminan as\u00ed un proyecto que iniciaron en la Cordillera Blanca en 2019. \u00abSon 160 metros muy atl\u00e9ticos y desplomados, repartidos en cinco largos de cuerda, con dificultades mantenidas en el s\u00e9ptimo grado y con tres largos que rozan el octavo.\u00bb, explican Eneko e Iker.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">ESCALANDO A 4000m.<br>La Quebrada de Yaca es un lugar magnifico con v\u00edas de corte deportivo a 1h de Huaraz \ud83e\uddd7\u2600\ufe0f<br><br>CLIMBING AT 4000m.<br>La Quebrada de Yaca is an amazing spot with sport climbing routes.\ud83e\udd29\ud83c\udfd4\ufe0f<a href=\"https:\/\/twitter.com\/thenorthface?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@thenorthface<\/a><br>@lasportivagram<br>@petzl_official <a href=\"https:\/\/twitter.com\/hashtag\/poubros?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#poubros<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/neverstopexploring?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#neverstopexploring<\/a> <a href=\"https:\/\/t.co\/mSvKvPF2Ud\">pic.twitter.com\/mSvKvPF2Ud<\/a><\/p>&mdash; Hermanos Pou (@hermanospou) <a href=\"https:\/\/twitter.com\/hermanospou\/status\/1536233443067060225?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 13, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Os recomendamos la lectura del art\u00edculo que firman Jes\u00fas Samp\u00e9riz y Santiago Mart\u00edn:&nbsp;<a href=\"https:\/\/www.eldiario.es\/opinion\/zona-critica\/macroproyectos-amenazan-pirineo-aragones_129_9052923.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Macroproyectos que amenazan el Pirineo Aragon\u00e9s<\/a><em>&nbsp;(elDiario)<\/em>. \u00abCuesta entender que, a d\u00eda de hoy, haya quien crea que sembrar de cables y telesillas el paisaje es herramienta de progreso. Cuesta creer que subir a un telecabina en la Estaci\u00f3n de Canfranc, y de ah\u00ed llegar hasta la estaci\u00f3n de Ast\u00fan o la de Formigal, violentando los valores naturales del valle del r\u00edo Canal Roya (La Canal Roya), sea la forma m\u00e1s adecuada de promocionar las comarcas de monta\u00f1a.\u00bb&nbsp; <\/li>\n\n\n\n<li>Y nos despedimos con este divertido video<strong>&nbsp;\u2018<\/strong><a href=\"https:\/\/youtu.be\/r0PzmDoCj_A?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Consequences<\/strong><\/a><strong>\u2019, loca s\u00e1tira escaladora de los anticlecas&nbsp;<\/strong>que nos llega&nbsp;<a href=\"https:\/\/www.desnivel.com\/escalada-roca\/escalada-roca-galeria-multimedia\/video-consequences-loca-satira-escaladora-de-los-anticlecas\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">v\u00eda&nbsp;<em>Desnivel<\/em>.<\/a>&nbsp;Sean Villanueva, Nico Favresse, C\u00e9dric Lachat y Charlotte Durif protagonizan esta divertida producci\u00f3n grabada durante el Petzl Roc Trip celebrado recientemente en Grecia. El humor nunca falta en los videos y publicaciones de Sean y Nico. Os dejamos aqu\u00ed el video.<em> \u00abA\u00f1o 2082: Un d\u00eda, alguien marc\u00f3 la primera cleca. Como consecuencia de este acto criminal, la temperatura de la Tierra se ha elevado de forma dram\u00e1tica y la contaminaci\u00f3n ha crecido a niveles extremos. El planeta se ha vuelto casi completamente des\u00e9rtico, excepto por un peque\u00f1o santuario, en el que la vida contin\u00faa como antes de la primera cleca.\u00bb<\/em><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u201cCONSEQUENCES\u201d \u2013 Creative Onsight \u2013 Petzl RocTrip\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/r0PzmDoCj_A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles,1 junio 2022<\/h3>\n\n\n\n<p><a href=\"https:\/\/www.desnivel.com\/expediciones\/kristin-harila-alcanza-la-cima-del-makalu-seis-ochomiles-en-un-mes\/\" target=\"_blank\" rel=\"noreferrer noopener\">La himalayista noruega Kristin Harila contin\u00faa imparable en su proyecto&nbsp;de corononar los 14 ochomiles en 6 meses.<\/a> De momento lleva 6 en tan solo un mes: Dhaulagiri, Annapurna, Kanchenjunga, Everest, Lhotse y Makalu. (Desnivel).<\/p>\n\n\n\n<p><a href=\"https:\/\/fedme.es\/erik-noya-se-anota-su-tercer-record-de-espana-consecutivo-en-salt-lake-city\/\" target=\"_blank\" rel=\"noreferrer noopener\">La Copa del Mundo de Boulder y Velocidad de la IFSC disputada en Salt Lake City acaba con Erik Noya en s\u00e9ptima posici\u00f3n, rebajando en dos ocasiones el record de Espa\u00f1a hasta situarlo en 5,66 segundos.<\/a> Mar\u00eda Laborda acabo en el top20 mientras que la cruz fue para Alberto Gin\u00e9s, que tuvo que retirarse por problemas f\u00edsicos (FEDME). El video de la final pod\u00e9is verlo completo en <a href=\"https:\/\/olympics.com\/es\/video\/escalada-deportiva-finales-de-velocidad-m-y-f-copa-del-mundo-salt-lake-city\" target=\"_blank\" rel=\"noreferrer noopener\">Olympics.com<\/a>.<\/p>\n\n\n\n<p>Siguiendo con los records, continuamos con <a href=\"https:\/\/www.noticiasdegipuzkoa.eus\/deportes\/otros-deportes\/2022\/05\/29\/maraton-montana--emision-directo\/1218099.html\" target=\"_blank\" rel=\"noreferrer noopener\">los que este fin de semana establecieron Kilian Jornet (3h36:40) y Nienke Brinkman (4h16:43) en la Zegama-Aizkorri<\/a>, la carrera de las carreras por monta\u00f1a (Noticias de Gipuzkoa). El catal\u00e1n rebaj\u00f3 en m\u00e1s de 8 minutos la marca conseguida por Angermund hace 5 a\u00f1os, tiempo que tambi\u00e9n fue superado por Magnini (3h39:31) que acab\u00f3 en segunda posici\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles,18 mayo 2022 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/kristin-harila-corona-el-kangchenjunga-va-a-ochomil-por-semana-y-ya-suma-tres\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">14&#215;8000 en un mismo a\u00f1o, ese es el reto de la alpinista noruega Kristin Harila que ha coronado el Kangchenjunga&nbsp;<\/a><em>(Desnivel)<\/em>, sumando tres tras el Annapurna y el Dhaulagiri, a un ritmo de ochomil por semana. Ahora se dirige al Khumbu en helic\u00f3ptero para intentar las cimas del Everest y Lhotse. Siguiendo el r\u00e9cord de los 14 de Nirmal Purja.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/carlos-soria-ya-esta-de-regreso-en-casa-tras-su-intento-al-dhaulagiri-una-expedicion-fantastica-sin-cumbre\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Carlos Soria se encuentra ya en casa tras su intento al Dhaulagiri<\/a>&nbsp;<em>(Desnivel)<\/em>. En una ventana de buen tiempo pudieron ascender hasta el campamento 2, pero ya all\u00ed se encontraron con malas condiciones en los tramos que llevan al C3. \u00abCuando la monta\u00f1a est\u00e1 dif\u00edcil se lucha con ello, pero cuando est\u00e1 peligrosa es otra cosa\u00bb, comenta Soria. \u00abNo quiero pensar que no voy a volver al Himalaya. Quiero pensar que s\u00ed. (\u2026)&nbsp;No s\u00e9 si podr\u00e1 ser este oto\u00f1o \u00f3 la pr\u00f3xima primavera, pero&nbsp;quiero volver al Dhaulagiri porque a\u00fan me veo en condiciones suficientes (\u2026)\u00bb. Os dejamos aqu\u00ed&nbsp;<a href=\"https:\/\/www.instagram.com\/tv\/CdgJDZfAyO6\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">el video de Carlos Soria<\/a>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u00a1Hola amigos! Ya desde Espa\u00f1a, os cuento el desenlace de nuestros \u00faltimos d\u00edas en el Dhaulagiri. \u00a1Un abrazo muy fuerte para todos! <a href=\"https:\/\/t.co\/mN7xw7DYV7\">https:\/\/t.co\/mN7xw7DYV7<\/a><\/p>&mdash; Carlos Soria (@RetoCarlosSoria) <a href=\"https:\/\/twitter.com\/RetoCarlosSoria\/status\/1525127927238623233?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">May 13, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfSab\u00edas que el 90% de las personas de todo el mundo respiran aire contaminado? Para concienciar sobre la contaminaci\u00f3n del aire&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/running-up-for-air-patagonia\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">el pr\u00f3ximo 25 de junio tendr\u00e1 lugar el evento Running Up For Air, que se realizar\u00e1 en formato digital<\/a>. As\u00ed que puedes participar desde donde te encuentres. A trav\u00e9s del reto&nbsp;<strong>Running Up For Air Strava<\/strong>, los participantes pueden llevar un control del&nbsp;desnivel acumulado y conectarse con otros corredores.&nbsp;Puedes estar desde 1 hora hasta 24 y as\u00ed apoyar a las ONGs europeas que luchan por una mejor calidad del aire,&nbsp;como&nbsp;ClientEarth,&nbsp;Cittadini per l\u2019Aria&nbsp;o&nbsp;German Zero.&nbsp;<\/li>\n\n\n\n<li>Y cerramos la secci\u00f3n con el documental<a href=\"https:\/\/travesiapirenaica.com\/run-to-the-source-n-johnson-patagonia\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;<strong>\u00abRun to the source\u00bb<\/strong>.&nbsp;<strong>Martin Johnson explora la naturaleza y la diversidad que se extiende m\u00e1s all\u00e1 de Londres&nbsp;<\/strong><\/a>en el nuevo documental de Patagonia. Este sigue a Johnson en el intento de establecer el mejor tiempo a lo largo de los 296 km que recorren el &nbsp;Thames River Trail desde la Thames Barrier al sudeste de Londres hasta el nacimiento del r\u00edo en Cotswolds, el 25 de mayo,&nbsp;la fecha del aniversario del asesinato de George Floyd. Como deportista y brit\u00e1nico de color, Johnson lidia con el reto f\u00edsico, adem\u00e1s de reflexionar sobre la historia de las personas de color en Gran Breta\u00f1a.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n <iframe loading=\"lazy\" title=\"Run to the Source | Full Film\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/l5IG9IjqpnA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 11 mayo 2022 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11545\/karl-egloff-nico-miranda-cumbre?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Karl Egloff y Nico Miranda: 17 horas y 18 minutos para hacer cima en el Makalu<\/a>&nbsp;<em>(Barrabes)<\/em>&nbsp;sin ox\u00edgeno suplementario. Mejor tiempo conocido en la monta\u00f1a desde el campo base avanzado (5700m). \u201cMomentos inolvidables, cuando todo el sufrimiento y esfuerzo se esfuma e invade la emoci\u00f3n y alegr\u00eda de llegar a la cumbre del Makalu (8463m) sin ox\u00edgeno. \u201d, comentaba Egloff en sus<a href=\"https:\/\/www.instagram.com\/p\/CdYCLECLWrT\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;redes sociales<\/a>. Haza\u00f1a que tiene como precedente dos grandes figuras del himalayismo:&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/makalu-expres-karl-egloff-y-nico-miranda-vs-marc-batard-y-anatoli-boukreev\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Marc Batard (1988) y Anatoli Boukreev (1994) realizaron tambi\u00e9n ascensiones r\u00e1pidas al Makalu&nbsp;<\/a><em>(Desnivel)<\/em>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Cumbre del Makalu 8463m junto a <a href=\"https:\/\/twitter.com\/nicomiranda360?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@nicomiranda360<\/a> sin ox\u00edgeno suplementario, 17horas desde campo base avanzado 5700m. Sin palabras para describir las emociones! <a href=\"https:\/\/twitter.com\/ChevroletEc?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@ChevroletEc<\/a> <a href=\"https:\/\/twitter.com\/Sportiva?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@Sportiva<\/a> <a href=\"https:\/\/twitter.com\/alpenglowexp?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@alpenglowexp<\/a> <a href=\"https:\/\/t.co\/WEVghxItD0\">pic.twitter.com\/WEVghxItD0<\/a><\/p>&mdash; Karl Egloff (@karlmtb) <a href=\"https:\/\/twitter.com\/karlmtb\/status\/1523989856963207170?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">May 10, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/travesiapirenaica.com\/carlos-soria-dhaulagiri\/\">Carlos Soria abandona de momento el intento de cima debido a las \u00faltimas nevadas y al pron\u00f3stico de fuertes vientos en altura<\/a>. Carlos Soria, Sito Carcavilla y Mikel Sherpa se encuentran ya en el campo base, viendo como evolucionan las nevadas. La madrugada del d\u00eda 6, Carlos parti\u00f3 del CB para encontrarse con Sito Carcavilla en el C1, con la esperanza de lanzar un ataque a cima para el d\u00eda 9. La cima tendr\u00e1 que esperar hasta que la monta\u00f1a d\u00e9 paso.<\/li>\n\n\n\n<li>Os compartimos este interesante hilo de&nbsp;<a href=\"https:\/\/twitter.com\/descuentor_com?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Aitor Tilla<\/a>&nbsp;en Twitter en el que habla del&nbsp;<a href=\"https:\/\/twitter.com\/descuentor_com\/status\/1523615758948831234?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u201cdebate sobre la \u00e9tica del uso de trabajadores en retos de vanguardia\u201d<\/a>&nbsp;despu\u00e9s del accidente mortal del sherpa en la sur del Lhotse. Como dice \u00e9l, algo que \u201chace no mucho estaba claro\u201d y como muchas otras cosas en alpinismo \u201cpoco a poco se han ido diluyendo\u201d. \u201cA esos alpinistas que buscan la honra les corresponde el trabajo de escalar la monta\u00f1a y como dec\u00eda Terray, conquistar lo in\u00fatil\u2026 aunque se jueguen la vida. Lo que no es aceptable es que jueguen con la vida de trabajadores in\u00fatilmente.\u201d, comenta Aitor.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Vi\u00e9ndolo desde este prisma \u00e9tico, es evidente que cuanto m\u00e1s dif\u00edcil y peligroso sea el reto, mayor nivel alpino y menor justificaci\u00f3n tiene la contrataci\u00f3n de gente que abra la ruta.<\/p>&mdash; Aitor Tilla (@descuentor_com) <a href=\"https:\/\/twitter.com\/descuentor_com\/status\/1523615779102822400?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">May 9, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Surge en Francia una gran traves\u00eda que enlaza 47 senderos de Gran Recorrido GR\u00ae en una sola ruta de trekking.&nbsp;<a href=\"https:\/\/en.hexatrek.com\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>HexaTrek&nbsp;<\/strong><\/a>es una ruta de trekking de&nbsp;<strong>3034 km que conecta 14 de los m\u00e1s bellos parques nacionales y atraviesa Francia desde los Vosgos hasta los Pirineos<\/strong>. El sendero recorre las regiones monta\u00f1osas m\u00e1s altas de Francia, pa\u00eds a menudo apodado \u201cl&#8217;Hexagone\u201d por su forma hexagonal, uniendo algunas de las cumbres m\u00e1s emblem\u00e1ticas, maravillas naturales y lugares m\u00e1s salvajes.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/www.google.com\/maps\/d\/u\/0\/viewer?ll=45.52769769781092,1.7817221704029258&amp;mid=15yc_QfNRfCAQKWRGbcMPeXa9wyRg2bGY&amp;utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue+newsletter&amp;z=6\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"735\" height=\"662\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/05\/Hexatrek.jpg\" alt=\"\" class=\"wp-image-33124\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/05\/Hexatrek.jpg 735w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/05\/Hexatrek-300x270.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/05\/Hexatrek-150x135.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/05\/Hexatrek-696x627.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/05\/Hexatrek-466x420.jpg 466w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/05\/Hexatrek-600x540.jpg 600w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/><\/a><\/figure>\n<\/div>\n\n\n<ul class=\"wp-block-list\">\n<li>Y para cerrar os recomendamos que ve\u00e1is el \u00faltimo episodio de&nbsp;<a href=\"https:\/\/www.rtve.es\/play\/videos\/de-parque-en-parque\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u201cDe parque en parque\u201d<\/a>; la serie documental de 16 cap\u00edtulos de Rtve en la que cada cap\u00edtulo se recorre uno de los 16 Parques Nacionales. En esta ocasi\u00f3n nos llevan al Parque Nacional de Ordesa y Monte Perdido. El macizo calc\u00e1reo m\u00e1s alto de Europa, una suerte de paisajes de alta monta\u00f1a, bosques atl\u00e1nticos, nieve e hielo. Qu\u00e9 os vamos a contar. Dejo aqu\u00ed el&nbsp;<a href=\"https:\/\/www.rtve.es\/play\/videos\/de-parque-en-parque\/parque-nacional-ordesa-monte-perdido\/6530634\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">enlace al episodio<\/a>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/www.rtve.es\/play\/videos\/de-parque-en-parque\/parque-nacional-ordesa-monte-perdido\/6530634\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/05\/De-parque-en-parque.jpg\" alt=\"\" class=\"wp-image-33125\" width=\"1070\" height=\"617\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/05\/De-parque-en-parque-300x173.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/05\/De-parque-en-parque-768x442.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/05\/De-parque-en-parque-150x86.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/05\/De-parque-en-parque-696x400.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/05\/De-parque-en-parque-730x420.jpg 730w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/05\/De-parque-en-parque-600x345.jpg 600w\" sizes=\"auto, (max-width: 1070px) 100vw, 1070px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 04 mayo 2022 <\/h3>\n\n\n\n<p><a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11539\/ana-alonso-desciende-3-grandes?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">La esquiadora y monta\u00f1era granadina Ana Alonso primera mujer en descender las tres grandes nortes de Sierra Nevada en el d\u00eda&nbsp;<\/a><em>(Barrabes)<\/em>. Descensos en esqu\u00ed extremo a la Canuto del Veleta, Norte del Mulhac\u00e9n y la cara norte de la Alcazaba (una l\u00ednea esquiada previamente s\u00f3lo por 3 personas).&nbsp;<em>\u201cno tuvimos miedo en ning\u00fan momento, pero s\u00ed que son zonas en las que tienes que ir al m\u00e1ximo de concentraci\u00f3n en tu esqu\u00ed para no cometer ning\u00fan fallo\u201d<\/em>, Alonso. Os dejo aqu\u00ed el video de la gesta. No faltan algunos momentos expuestos en los que la tensi\u00f3n llega al propio espectador.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\ud83c\udfbf Bajamos Las 3 GRANDES NORTES en el d\u00eda\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/DIL8-uachW8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>La corta ventana de buen tiempo en el Annapurna fue exprimida por los himalayistas.&nbsp;<\/strong>&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/annapurna-cimas-confusion-y-rescates-al-limite-de-giampaolo-corona-y-tim-bogdanov\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Treinta cimas, cuatro de ellas sin ox\u00edgeno, incluyendo las de los dos rescatados Giampaolo Corona y Tim Bogdanov&nbsp;<\/a><em>(Desnivel)<\/em>. Salt\u00f3 la alarma de la p\u00e9rdida de contacto desde el campamento base del alpinista &nbsp;Giampaolo Corona y sus dos compa\u00f1eros que ascend\u00edan sin ox\u00edgeno. Finalmente lleg\u00f3 la informaci\u00f3n de la evacuaci\u00f3n de Tim Bogdanov y Giampaolo Corona&nbsp;desde el campo 4 (6.800 m) con&nbsp;graves congelaciones. Como causa de los problemas se cita la falta de aclimataci\u00f3n de los ascensionistas sin ox\u00edgeno, en una planificaci\u00f3n de intento de cima planeado principalmente para los que lo hac\u00edan con ox\u00edgeno.<\/li>\n\n\n\n<li>Y para que os hag\u00e1is una idea de a lo que lidiaron los que hicieron cima en el Annapurna, os inserto aqu\u00ed el video que compart\u00eda&nbsp;<a href=\"https:\/\/twitter.com\/KrisAnnapurna?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">@KrisAnnapurna<\/a>, unas im\u00e1genes virales de<strong>&nbsp;la avalancha grabada por Kasturi Deepak Savekar, escaladora india de 20 a\u00f1os, que aunque os sorprenda hizo cima<\/strong>&nbsp;despu\u00e9s de este incidente. Vaya sangre fr\u00eda para grabar sin echar a correr y buscar un lugar algo m\u00e1s seguro.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Annapurna, La Diosa de la Abundancia<br><br>Avalancha grabada por Kasturi Deepak Savekar, escaladora india de 20 a\u00f1os (v\u00eda Trifish Chan). <a href=\"https:\/\/t.co\/tTcJ7S1vtp\">pic.twitter.com\/tTcJ7S1vtp<\/a><\/p>&mdash; k2 (@KrisAnnapurna) <a href=\"https:\/\/twitter.com\/KrisAnnapurna\/status\/1521548323290849280?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">May 3, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y nos despedimos con un documental.<strong>&nbsp;HIELO sigue a Fernanda Maciel mientras vuelve con su compa\u00f1era de equipo Kaytlyn Gerbin a enfrentarse a este salvaje y remoto glaciar<\/strong>&nbsp;mientras corre por las emblem\u00e1ticas monta\u00f1as de los macizos de Torre y Fitzroy, poniendo a prueba su fuerza, resistencia y habilidades t\u00e9cnicas. La traves\u00eda del \u201cHielo Continental\u201d es uno de los campos de hielo m\u00e1s grandes del mundo y el coraz\u00f3n de los Andes patag\u00f3nicos. La ruta se realiza en 6-8 d\u00edas y comienza en El Chalt\u00e9n (Argentina).&nbsp;<a href=\"https:\/\/www.revistaoxigeno.es\/deportes\/vuelta-hielo-con-fernanda-maciel-kaytlyn-gerbin_255634_102.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Fernanda Maciel y Kaytlyn Gerbin establecieron un nuevo r\u00e9cord para la traves\u00eda: 13 horas y 15 minutos, rebajando en casi 7 horas la anterior marca<\/a>&nbsp;<em>(Ox\u00edgeno)<\/em>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"HIELO | The North Face\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/PUo1JnhGsQU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 27 abril 2022 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Subir y bajar el Makalu en menos de 24 horas, el reto de Karl Egloff y Nicol\u00e1s Miranda<\/strong>. Estos dos asiduos de la velocidad en las ascensiones se plantean subir al Makalu en menos de 24 horas. Ser\u00e1 un entrenamiento para batir en los pr\u00f3ximos a\u00f1os el r\u00e9cord del Everest. Pod\u00e9is&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/expediciones-alpinistas\/karl-egloff-queremos-subir-y-bajar-el-makalu-en-menos-de-24-horas\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">escuchar a Karl Egloff&nbsp;desde el CB a las preguntas de Desnivel<\/a>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Un poco perdido por Twitter por problemas t\u00e9cnicos \u263a\ufe0f. Reportando desde el Makalu 8463m en nuestra expedici\u00f3n con <a href=\"https:\/\/twitter.com\/nicomiranda360?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@nicomiranda360<\/a> <a href=\"https:\/\/twitter.com\/CarlaPerez_ec?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@CarlaPerez_ec<\/a> <a href=\"https:\/\/twitter.com\/alpenglowexp?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@alpenglowexp<\/a> <br>Vamos por nuestra segunda rotaci\u00f3n a C2 6600m por par d\u00edas. <a href=\"https:\/\/t.co\/9IqH8DVCzk\">pic.twitter.com\/9IqH8DVCzk<\/a><\/p>&mdash; Karl Egloff (@karlmtb) <a href=\"https:\/\/twitter.com\/karlmtb\/status\/1518741384869687298?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">April 25, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11533\/1-cara-noroeste-kangchung-nup?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>La cordada japonesa formada por Toshiyuki Yamada y Takeshi Tani escalan por primera vez la vertiente norte del Kangchung Nup (6.089m)<\/strong><\/a>&nbsp;<em>(Barrabes)<\/em>.&nbsp;<em>\u201cLa meteo y las condiciones han sido perfectas. Hemos vivido una experiencia maravillosa en una pared bell\u00edsima\u201d<\/em>, afirma Yamada. El seismil Kangchung Nup es una monta\u00f1a hist\u00f3rica; fue ascendida por primera vez por su cara sur (poco tiene que ver en vertiginosidad con la norte) por Sir Edmund Hillary y otros miembros de la expedici\u00f3n brit\u00e1nica al Everest de 1953 como preparaci\u00f3n en su aclimataci\u00f3n.<\/li>\n\n\n\n<li>Te contamos que&nbsp;<strong>el 20 de abril se constituy\u00f3 la Asociaci\u00f3n Entrepyr, que re\u00fane a los refugios de monta\u00f1a de todo el Pirineo<\/strong>, la&nbsp;primera red de refugios&nbsp;de&nbsp;toda la cordillera&nbsp;pirenaica, con el&nbsp;objetivo&nbsp;de&nbsp;impulsar los refugios y el monta\u00f1ismo&nbsp;como&nbsp;elemento&nbsp;de&nbsp;desarrollo sostenible&nbsp;para el territorio. Un gran proyecto conjunto y una web com\u00fan para centralizar las reservas de los refugios del Pirineo. Os dejamos aqu\u00ed la&nbsp;<a href=\"https:\/\/entrepyr.eu\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">web de Entrepyr&nbsp;<\/a>que cuenta ya con interesantes recursos: refugios, circuitos, rutas, etc.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">M\u00e1s de 60 <a href=\"https:\/\/twitter.com\/hashtag\/refugiosdemonta%C3%B1a?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#refugiosdemonta\u00f1a<\/a> del <a href=\"https:\/\/twitter.com\/hashtag\/Pirineo?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Pirineo<\/a>, en Francia, Espa\u00f1a y Andorra se han unido en la asociaci\u00f3n <a href=\"https:\/\/twitter.com\/hashtag\/Entrepyr?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Entrepyr<\/a> para desarrollar proyectos de gesti\u00f3n y promoci\u00f3n conjuntos. El vocal de Refugios de la FAM, Sergio Rivas, preside la Junta Directiva<a href=\"https:\/\/t.co\/RwPALYbLlo\">https:\/\/t.co\/RwPALYbLlo<\/a> <a href=\"https:\/\/t.co\/lLEagwyKjw\">pic.twitter.com\/lLEagwyKjw<\/a><\/p>&mdash; FAM (@internetfam) <a href=\"https:\/\/twitter.com\/internetfam\/status\/1517506269178994688?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">April 22, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Para cerrar nos despedimos con el documental<a href=\"https:\/\/youtu.be\/vmPredMTXpg?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;\u2018The last Tepui\u00bb<\/a>&nbsp;de National Geographic, disponible en<a href=\"https:\/\/travesiapirenaica.com\/disney-montana-aventura\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;Disney+<\/a>. Alex Honnold y un equipo de cient\u00edficos y exploradores se internan en al selva del Amazonas. Las formaciones son impresionantes: mesetas de paredes escarpadas de hasta 300m sobre la selva, jardines colgantes, cascadas que descienden al abismo.&nbsp;Honnold y el bi\u00f3logo Dr. Bruce Means exploran las tierras altas de la Guayana en busca de nuevas especies. \u201cTepui\u201d se traduce como \u201ccasa de los dioses\u201d en pem\u00f3n, la lengua nativa de la Gran Sabana de Guyana.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Explorer: The Last Tepui Trailer | National Geographic\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/vmPredMTXpg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 20 abril 2022 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/travesiapirenaica.com\/carlos-soria-dhaulagiri\/\">Tras pasar la noche en el C3 Carlos Soria y su equipo descienden al Campamento Base en el Dhaulagiri<\/a>. Los partes meteorol\u00f3gicos no eran buenos para los siguientes d\u00edas. Llegaron al campamento base hace 8 d\u00edas encontr\u00e1ndose la monta\u00f1a equipada por las expediciones m\u00e1s tempranas y una ventana de buen tiempo. Decidieron as\u00ed hacer una r\u00e1pida ascensi\u00f3n, que les llevar\u00eda a descansar en el C3 y realizar un ataque a cima que han descartado por el parte meteorol\u00f3gico. Ya en el CB, sin duda esta primera incursi\u00f3n a las alturas de la monta\u00f1a les ha llevado a conseguir una buena aclimataci\u00f3n para la siguiente incursi\u00f3n en la monta\u00f1a.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Tras ver los pron\u00f3sticos del tiempo, Carlos Soria y Sito Carcavilla han decidido descender al CB para esperar una oportunidad m\u00e1s favorable. Han conseguido  una aclimataci\u00f3n inmejorable y solo queda aguardar con paciencia el mejor momento para alcanzar la cumbre del Dhaulagiri <a href=\"https:\/\/t.co\/IiOvn2mhbx\">pic.twitter.com\/IiOvn2mhbx<\/a><\/p>&mdash; Carlos Soria (@RetoCarlosSoria) <a href=\"https:\/\/twitter.com\/RetoCarlosSoria\/status\/1516315228266508288?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">April 19, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/carreraspormontana.com\/noticias\/kilian-jornet-no-podemos-contar-con-la-suerte-cuando-vamos-a-la-montana\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">\u00abNo podemos contar con la suerte cuando vamos a la monta\u00f1a\u00bb<\/a>&nbsp;<em>(Carreras por Monta\u00f1a)<\/em>.&nbsp;<strong>Kilian Jornet<\/strong>&nbsp;ha explicado en sus redes un incidente con una avalancha en el Himalaya para reflexionar sobre los riesgos que asumimos en la monta\u00f1a. \u00abEsta foto fue tomada dentro de una grieta. Estaba escalando en el Himalaya hace un par de a\u00f1os y una avalancha me hizo caer y entrar en una grieta. Pens\u00e9 que eso era todo.\u00bb.&nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/cumbresmountainmagazine.com\/actualidad\/montana-invernal\/expediciones-montana-invernal\/espanol-tres-6-500-puna-argentina\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">El espa\u00f1ol Daniel Zaragoza se aproxima a las cumbres de los nevados Cachi, Quewar y Llullaillaco en bicicleta para su ascensi\u00f3n<\/a>&nbsp;<em>(Cumbres Mountain)<\/em>. 1.000 kil\u00f3metros en bici, la mayor\u00eda por caminos de tierra y con pasos de hasta 5.000 metros, en autosuficiencia y en solitario. Arranc\u00f3 el domingo 10 el desaf\u00edo que le demandar\u00e1 entre 20 y 30 d\u00edas de esfuerzo aut\u00f3nomo y solitario. \u00abSaldr\u00e9 con la bici desde la Quebrada de Humahuaca, Jujuy, en el norte de Argentina, cargado con todo el material necesario y me dirigir\u00e9 rumbo al sur siguiendo la cordillera de los Andes y encadenando los ascensos del Nevado Cachi 6.380m, Nevado Quewar 6.160m y el volc\u00e1n Llullaillaco 6.739m, el segundo volc\u00e1n m\u00e1s alto del mundo.\u00bb<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Andinismo en bici\ud83d\udeb5\u200d\u2640\ufe0f\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/lJRwSB_XS_U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y para cerrar,<a href=\"https:\/\/www.youtube.com\/channel\/UCa9CpwCfSVKBZ79ogXfWbWw?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;descubrimos al youtuber Eli del Pirineu<\/a>. Os compartimos un video con cierto toque de humor de un d\u00eda haciendo la Transpirenaica. \u00abEste fue el d\u00eda en que pase m\u00e1s miedo en toda mi vida, ocurri\u00f3 en Mi Rom\u00e1ntica Traves\u00eda de los Pirineos, mientras caminaba por la Alta ruta Pirenaica.\u00bb<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u26a1 Estuve Dentro de una Nube EL\u00c9CTRICA \u26a1 La vez que pas\u00e9 m\u00e1s miedo \ud83d\ude31 en mis AVENTURAS en el GR11\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/dFBuu1IlH0A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 13 abril 2022 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/explorersweb.com\/hong-sung-taek-and-team-leave-for-lhotse-south-face\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Sung-Taek Hong y Jorge Egocheaga vuelven a la cara sur del Lhotse<\/a>&nbsp;<em>(ExplorersWeb)<\/em>. Ya camino del CB, se ha puesto en marcha una de las expediciones m\u00e1s interesantes de la primavera. Se trata del s\u00e9ptimo intento de Sung-Taek Hong a esta cara sur, un sue\u00f1o de m\u00e1s de dos d\u00e9cadas que esperemos se alcance en esta ocasi\u00f3n. Como hermanos: Jorge Egocheaga ha acompa\u00f1ado a Hong en los intentos del oto\u00f1o del 2017 y primavera de 2019, ambos superaron los 8.200 m de altitud, pero las complicaciones meteorol\u00f3gicas le impidieron alcanzar la cumbre.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/carlos-soria-y-sito-carcavilla-por-primera-vez-vamos-a-un-dhaulagiri-que-ya-estara-equipado\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Carlos Soria y Sito Carcavilla se dirigen al CB del Dhaulagiri&nbsp;<\/a><em>(Desnivel)<\/em>. Ya se han logrado las primeras cumbres, con lo que la monta\u00f1a se encuentra equipada. En los \u00faltimos intentos Carlos Soria y su equipo se ve\u00edan obligados a la equipaci\u00f3n y a la ardua tarea de abrir huella. Ante ello, no descartan un intento del tir\u00f3n. \u201cLo ideal ser\u00eda pasar dos noches en el C1 (5.600 m)\u201c, comenta Sito. El Dhaulagiri es el pen\u00faltimo ochomil que le falta a Carlos Soria para completar los Catorce, a sus 83 a\u00f1os y con una pr\u00f3tesis de rodilla. El equipo lo completan los traumat\u00f3logos que lo operaron y su fisioterapeuta, sorprendidos por el buen hacer de su rodilla con pr\u00f3tesis.<\/li>\n\n\n\n<li><a href=\"https:\/\/adventureblog.net\/2022\/04\/first-all-black-everest-team-heads-to-himalaya.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">El primer equipo negro del Everest se dirige al Himalaya<\/a>&nbsp;<em>(AdventureBlog)<\/em>. En Katmand\u00fa se encuentra ya un&nbsp;grupo (<em>Expedici\u00f3n Full Circle al Everest<\/em>) de escaladores\/as afroamericanos que forman el primer equipo negro al Everest. Pero sus objetivos van mucho m\u00e1s all\u00e1 de poner un pie en esa emblem\u00e1tica monta\u00f1a. Dirigido por el veterano aventurero y alpinista Phil Henderson, en 2013 form\u00f3 parte de un equipo exclusivamente negro que fue al Denali y en 2018 le toco paso al Kilimanjaro. Tras la primera ascensi\u00f3n al Everest pasaron 40 a\u00f1os antes de que el primer hombre negro alcanzara al cima. Ahora este grupo trata de romper barreras sociales que, aunque hoy no queramos reconocerlas, existen. Esperan que su ejemplo \u00abanime a la gente de color no s\u00f3lo a so\u00f1ar en grande, sino tambi\u00e9n simplemente a salir al outdoor\u201d.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">About 4,000 people have summited Mount Everest, the world&#39;s highest peak. And only eight of them have been Black.<br><br>That is one of the reasons that Full Circle, a group of Black climbers and mountaineers, was formed. <a href=\"https:\/\/t.co\/7VUwsLpjE0\">https:\/\/t.co\/7VUwsLpjE0<\/a><\/p>&mdash; CNN International (@cnni) <a href=\"https:\/\/twitter.com\/cnni\/status\/1485808973857107970?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">January 25, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/travesiapirenaica.com\/omar-di-felice-vuelta-al-mundo-artica-en-bici\/\">Omar Di Felice concluye la primera vuelta al mundo en bicicleta por el \u00c1rtico<\/a>. Han sido m\u00e1s de dos meses sobre el sill\u00edn a temperaturas polares (-42\u00b0C fue la m\u00e1s baja que ha registrado). \u201cM\u00e1s de 4.000 km y 33.000 metros de desnivel sobre hielo y nieve, contra tormentas y climas extremos, viviendo bajo cero.\u201d Di Felice parti\u00f3 el 2 de febrero de Kamchatka (Rusia) y luego se dirigi\u00f3 a Laponia (desde Murmansk, en Rusia, hasta Troms\u00f8, en Noruega), las islas Svalbard, Groenlandia e Islandia. Desde Rusia consigui\u00f3 salir unos d\u00edas antes del inicio de la guerra en Ucrania. La \u00faltima etapa, en las regiones \u00e1rticas de Norteam\u00e9rica, le llev\u00f3 a pedalear por Whitehorse (regi\u00f3n de Yuk\u00f3n, Canad\u00e1) y Alaska (Estados Unidos) a lo largo de la autopista Dalton. En total, Di Felice recorri\u00f3 4.000 km y 33.000 metros de altitud.<\/li>\n<\/ul>\n\n\n\n<p><em>\u201c\u00a1Eso es todo amigos! Lo hice, la vuelta al mundo por el \u00c1rtico y ahora estoy a 66\u00ba33\u2019 Norte en el C\u00edrculo Polar \u00c1rtico. De nuevo desde la salida en la remota pen\u00ednsula de Kamchatka.\u201d \u2014<a href=\"https:\/\/www.instagram.com\/p\/CcNsoDZtZLF\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Omar Di Felice<\/a><\/em><\/p>\n\n\n\n<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CcNsoDZtZLF\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CcNsoDZtZLF\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Ver esta publicaci\u00f3n en Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CcNsoDZtZLF\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida de Omar Di Felice (@omardifelice)<\/a><\/p><\/div><\/blockquote> <script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y para despedirnos os compartimos el art\u00edculo que escribe&nbsp;<a href=\"https:\/\/twitter.com\/oscargogorza?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Oscar Gogorza<\/a>&nbsp;para El Pa\u00eds, \u201c<a href=\"https:\/\/elpais.com\/eps\/2022-04-08\/los-escaladores-que-abren-vias-en-las-grandes-paredes-remotas-del-planeta.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Los escaladores que abren v\u00edas en las grandes paredes remotas del planeta<\/a>\u201d. Una \u201cradiograf\u00eda\u201d de la vida y aventuras de Nicolas Favresse y Sean Villanueva. En 2011 recibieron el Piolet d\u2019Or por su viaje en Groenlandia en busca de grandes paredes que emerg\u00edan directamente del mar. El periodista se cita con ellos en Etxauri; \u201cLa furgoneta se detiene. De ella bajan dos peque\u00f1as figuras desali\u00f1adas. Son ellos, pero podr\u00edan ser dos personajes de la pel\u00edcula de los hermanos Coen&nbsp;<em>El gran Lebowski<\/em>.\u201d<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 6 abril 2022 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arrancamos la secci\u00f3n cont\u00e1ndote que&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11515\/marc-batard-everest-sin-o2?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Marc Batard, a sus 70 a\u00f1os, intentar\u00e1 el Everest sin ox\u00edgeno por una nueva v\u00eda que evita la cascada de Khumbu<\/a>&nbsp;<em>(Barrabes)<\/em>. Tener en cuenta que la persona de mayor edad que ha escalado el Everest sin ox\u00edgeno es el italiano Abele Blanc que lo hizo a los 55 a\u00f1os. Marc junto con su hijo Alan y de&nbsp;Pasang Nuru Sherpa y su hijo lo intentar\u00e1 por la variante que abrieron el pasado oto\u00f1o y que evita el caos de hielo de la Cascada de Klumbu. Esta nueva ruta puede convertirse en normal con el paso del tiempo ante el riesgo creciente por el cambio clim\u00e1tico que supone el paso del glaciar en la cascada de Khumbu. Apunte hist\u00f3rico: Marc Batard fue la primera persona en escalar el Everest sin ox\u00edgeno en menos de 24 horas, lo hizo en 1988.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.sportaragon.com\/la-chesa-nieves-gil-hace-historia-en-el-eiger\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">La aragonesa Nieves Gil y la madrile\u00f1a Luc\u00eda Guichot hacen la cara norte del m\u00edtico Eiger<\/a>, la Nordwand, lo que representa la primera cordada femenina espa\u00f1ola en hacerlo.&nbsp;<em>(Sport Arag\u00f3n)<\/em>.<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/Cbk9sylNukk\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/Cbk9sylNukk\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Ver esta publicaci\u00f3n en Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/Cbk9sylNukk\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida de Lucia Guichot Martin (@luciaguichot)<\/a><\/p><\/div><\/blockquote> <script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Compartimos esta<a href=\"https:\/\/www.elmundo.es\/deportes\/nieve\/2022\/03\/31\/62458667fc6c83130b8b45a9.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;entrevista que hacen desde&nbsp;<em>Elmundo&nbsp;<\/em>a Miquel S\u00e1nchez, 40 a\u00f1os como guarda del refugio Ventosa i Calvell en el Pirineo de Lleida.<\/a>&nbsp;\u201cEl tipo de p\u00fablico que viene ahora no tiene nada que ver. Cuando empec\u00e9 al refugio s\u00f3lo llegaban esquiadores y escaladores. Ahora siguen viniendo monta\u00f1eros, pero tambi\u00e9n hay turistas. Gente de ciudad que ya se atreve a subir hasta aqu\u00ed y disfrutar de esto. Y yo encantado\u201d.&nbsp;<\/li>\n\n\n\n<li>Suiza es un para\u00edso para la escalada en varios largos. C\u00e9dric Lachat naci\u00f3 y creci\u00f3 all\u00ed. A trav\u00e9s de su singular sentido del humor y su entusiasmo desenfrenado experimenta la belleza y el asombro de cinco picos y paredes emblem\u00e1ticas: el Eiger, Gastlosen, Wendenst\u00f6cke, Lauterbrunnen y R\u00e4tikon.&nbsp;<strong>S<em>wissway to heaven<\/em><\/strong>&nbsp;(camino suizo hacia el cielo). Adem\u00e1s de las secuencias de escalada dura (a partir de 8a), los aperturistas hablan de los cambios en el equipo y la escalada a lo largo del tiempo, desde el alpinismo tradicional hasta la escalada deportiva moderna. Os dejamos aqu\u00ed el documental (pod\u00e9is poner subt\u00edtulos)<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Swissway to Heaven - Full movie\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/knxL3pPf1Gs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y para cerrar os dejamos un&nbsp;<strong>cortometraje de animaci\u00f3n&nbsp;<\/strong>\u2014Esta semana os hemos puesto doble tarea audiovisual\u2014. Dos hombres escalan una monta\u00f1a para colocar una estatua de la Virgen Mar\u00eda en la cima, y todo va bien hasta que a alguien se le cae la pierna. Es entonces cuando las cosas empiezan a ser hilarantes. Este cortometraje de animaci\u00f3n es una maravilla visual, y quiz\u00e1s se os escape alguna que otra risa.&nbsp;<\/li>\n<\/ul>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/124780139?h=8bf094fe1d\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen=\"\" width=\"640\" height=\"269\" frameborder=\"0\"><\/iframe>\n<p><a href=\"https:\/\/vimeo.com\/124780139\" target=\"_blank\" rel=\"noopener\">Ascension<\/a> from <a href=\"https:\/\/vimeo.com\/ascensionlefilm\" target=\"_blank\" rel=\"noopener\">Ascension Le Film<\/a> on <a href=\"https:\/\/vimeo.com\" target=\"_blank\" rel=\"noopener\">Vimeo<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 30 marzo 2022 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arrancamos cont\u00e1ndote que&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/expediciones-alpinistas\/carlos-soria-ya-esta-en-nepal-para-intentar-el-dhaulagiri-ese-viejo-amigo\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Carlos Soria vuelve al Dhaulagiri, pen\u00faltimo ochomil que le falta para completar los Catorce. Ya se encuentra en Nepal<\/a>&nbsp;<em>(Desnivel)<\/em>. A sus 83 a\u00f1os, con una pr\u00f3tesis de rodilla y sin patrocinadores para afrontar este reto. Pod\u00e9is ver esta entrevista que le realiza&nbsp;<a href=\"https:\/\/twitter.com\/DarioDesnivel?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Dar\u00edo Rodr\u00edguez<\/a>. En un futuro se pondr\u00e1 en valor, m\u00e1s si cabe, lo que est\u00e1 haciendo Carlos Soria.<span style=\"color: initial;\"><\/span><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Carlos Soria vuelve al Dhaulagiri &quot;He entrenado como siempre, como si me fuese la vida en ello&quot;\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/SdDnKt8RsVg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sin dejar el himalayismo, nos hacemos eco del&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/sanu-sherpa-busca-completar-el-2022-el-proyecto-2x14x8000\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">reto del nepal\u00ed Sanu Sherpa, completar los 2x14x8000<\/a>&nbsp;<em>(Desnivel)<\/em>. &nbsp;Kangchenjunga y el Makalu en primavera y &nbsp;Gasherbrum II en verano para completar doblemente la lista. Este desaf\u00edo ya se lo propuso Juanito Oiarzabal, pero le quedaron 4 cumbres para completarlo despu\u00e9s de su retirada del Shisha Pangma, y de los ochomiles, por un problema cardiaco.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/p\/CbkfzJlttMo\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">La alpinista Laura Tiefenthaler escala la cara Norte del Eiger en solitario por la ruta cl\u00e1sica \u201cHeckmair\u201d<\/a>. Es la segunda ascensi\u00f3n solitaria femenina: Catherine Destivelle tambi\u00e9n escal\u00f3 la cara norte sola en el 92. Laura hab\u00eda escalado justo hace dos semanas la ruta con la alemana Jana M\u00f6hrer en un solo d\u00eda. Pens\u00f3, \u201cesta vez por mi cuenta.\u201d<\/li>\n<\/ul>\n\n\n\n<p><em>\u201cA medida que avanzaba, la confianza crec\u00eda. Hab\u00eda hecho todos los largos dif\u00edciles y algunos tramos cortos con la cuerda. Al llegar a la Traves\u00eda de los Dioses a las 10 de la ma\u00f1ana, sab\u00eda que el tiempo estaba de mi lado.\u201d<\/em>&nbsp;\u2014<a href=\"https:\/\/www.instagram.com\/p\/CbkfzJlttMo\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Laura_tiefenthaler<\/a><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ya sabemos en qu\u00e9 proyecto se ha involucrado&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11503\/kilian-jornet-mallorquines-camper-lanzan?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Kilian Jornet; junto a los mallorquines Camper lanza su propia marca, NNormal&nbsp;<\/a><em>(Barrabes)<\/em>. \u201cEl respeto por el arte y la artesan\u00eda es el eje en torno al cual la marca se compromete a crear productos atemporales y de calidad, teniendo en cuenta el impacto social y medioambiental\u201d. Tras el revuelo de su salida de Salomon exist\u00eda una gran expectaci\u00f3n por ver cuales eran los pasos que iba a seguir Kilian.<\/li>\n\n\n\n<li>Y nos despedimos con el&nbsp;<a href=\"https:\/\/youtu.be\/Tv3NtPq6MF8?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">documental que se acaba de estrenar sobre la \u201cHeavenly Trap\u201d al Baruntse de M\u00e1rek Hole\u010dek y Radoslav Groh<\/a>. Marek y Radoslav abrieron esta nueva ruta de estilo alpino a la que llamaron \u201cHeavenly Trap\u201d (trampa celestial) en la cara noroeste del Baruntse (7162m) en Nepal. Realizaron un \u00e9pico descenso de 80 horas en el que sufrieron los embates del cicl\u00f3n Yass, despu\u00e9s de escalar en estilo alpino y establecer la primera a la cara noroeste. (le pod\u00e9is poner subt\u00edtulos).<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"&quot;Heavenly Trap&quot; - M\u00e1rek Hole\u010dek and Radoslav Groh complete hard first ascent on Baruntse\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/Tv3NtPq6MF8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 23 marzo 2022 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/explorersweb.com\/12-women-begin-5000km-trek-across-himalaya\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Doce mujeres mayores de 50 a\u00f1os, encabezadas por Bachendri Pal (primera mujer india en alcanzar la cima del Everest), de 68 a\u00f1os, han comenzado un viaje de cinco meses y 4977 km a trav\u00e9s del Himalaya<\/a>&nbsp;<em>(explorersweb)<\/em>. Partiendo de Arunachal Pradesh en el noreste de India, atravesar\u00e1n el Himalaya de este a oeste, salvando 37 pasos de monta\u00f1a. El objetivo: romper con el relato de \u2018Soy demasiado mayor para esto\u2019, especialmente para las mujeres de 50 y 60 a\u00f1os.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/p\/CbKskxJNIZt\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Tom Livingstone libera la \u2018Voie des Guides\u2019 (Ruta de los Gu\u00edas) (850m, M8+)&nbsp;en la cara norte de Les Drus<\/a>, la que puede ser la&nbsp;<strong>primera ascensi\u00f3n en libre<\/strong>. Tercer intento para lograr el objetivo. La primera vez lo intent\u00f3 junto a Rob Smith, luego una segunda intentona junto a Matt Glenn, pero en ambas ocasiones se encontraron la pared helada. La tercera y definitiva la realiz\u00f3 junto a Tom Seccombe. Si quieres ver c\u00f3mo amanece despu\u00e9s de un vivac en esa pared, aqu\u00ed te dejo un video de Tom.<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/tv\/CbZnsdjrkLJ\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/tv\/CbZnsdjrkLJ\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Ver esta publicaci\u00f3n en Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/tv\/CbZnsdjrkLJ\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida de Tom Livingstone (@tom__livingstone)<\/a><\/p><\/div><\/blockquote> <script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/travesiapirenaica.com\/gangapurna-jonatan-garcia-topo-mena\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Jonatan Garc\u00eda y Esteban \u2018Topo\u2019 Mena deciden retirarse del Gangapurna dadas las malas condiciones&nbsp;que se han encontrado<\/a>, con nieve por la cintura y ninguna l\u00ednea clara en la pared. Decidieron acometer la escalada en marzo, antes de la plena primavera, pero las condiciones que se han encontrado no han sido las esperadas. Jonatan Garc\u00eda compart\u00eda en redes sociales el fin de la actual expedici\u00f3n, y los planes de volver en el futuro. \u00abHasta aqu\u00ed lleg\u00f3 nuestra aventura en el Gangapurna. (\u2026) Nos quedaron muchas cosas por hacer, volveremos a ese rinc\u00f3n tan preciado del Himalaya lo antes que podamos\u00bb.<\/li>\n\n\n\n<li>Los polacos&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/invernal-torre-sin-nombre-trango-ruta-britanica\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Janusz Go\u0142\u0105b, Maciej Kimel y Micha\u0142 Kr\u00f3l&nbsp;se retiran de su intento a la Ruta Brit\u00e1nica&nbsp;en la invernal a la Torre Sin Nombre, Trango<\/a>. 8 d\u00eda en pared, hab\u00edan conseguido instalar el C1 a 5.500m y llegaron a alcanzar los 5.750m, pero las duras condiciones que se han encontrado, con fuertes vientos de hasta 65 km\/h, nevadas en aumento y avalanchas les ha echo tomar la decisi\u00f3n de retirarse. El descenso ha sido tambi\u00e9n complicado entre m\u00faltiples avalanchas, pero se encuentran sanos y salvos en el CB. Este gran tesoro invernal del Karak\u00f3rum seguir\u00e1 esperando a los siguientes osados.<\/li>\n\n\n\n<li>Y para cerrar te contamos que el explorador y&nbsp;bi\u00f3logo navarro&nbsp;<a href=\"https:\/\/www.salyroca.es\/articulo\/lyfestyle\/ignacio-oficialdegui-exploradores-influentes\/20220316172317007243.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Ignacio Oficialdegui<\/strong>&nbsp;ha sido elegido como uno de las 50 personas \u201cque necesita el planeta y es preciso conocer porque est\u00e1n cambiando este mundo\u201d por parte de la prestigiosa sociedad norteamericana Explorers Club de Nueva York<\/a>&nbsp;<em>(Sal y Roca)<\/em>, entidad creada en 1904 y de la que han formado parte a lo largo de su historia personajes como&nbsp;Roald Amundsen,&nbsp;Edmund Hillary&nbsp;o&nbsp;Neil Armstrong.&nbsp;Os dejamos tambi\u00e9n aqu\u00ed un<a href=\"https:\/\/www.efeverde.com\/noticias\/ignacio-oficialdegui-explorador-autopistas-viento\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;interesante art\u00edculo de EFEverde sobre la figura de Ignacio Oficialdegui<\/a>.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 16 marzo 2022 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/travesiapirenaica.com\/gangapurna-jonatan-garcia-topo-mena\/\" target=\"_blank\" rel=\"noreferrer noopener\">Jonatan Garc\u00eda y Esteban \u2018Topo\u2019 Mena ya han instalado su campamento base a los pies del Gangapurna&nbsp;(7.455m)<\/a>, en un lugar seguro a 4.700m de altitud. Se han decantado por la cara sur, por el peligro que presentaban los seracs sobre la norte. El objetivo es llevar el estilo alpino ligero, r\u00e1pido y en autonom\u00eda a la cara sur de la monta\u00f1a, de terreno mixto y con menos hielo que la norte. Esta cara fue abierta en 1981 por el grupo canadiense liderado por &nbsp;John Lauchlan, y existe otra ruta abierta por un grupo coreano en 2016 \u2014la \u00faltima ascensi\u00f3n a la monta\u00f1a\u2014. A d\u00eda de hoy existe la incertidumbre si abrir\u00e1n nueva v\u00eda o repetir\u00e1n alguna de las anteriores.<\/li>\n\n\n\n<li><a href=\"https:\/\/travesiapirenaica.com\/invernal-torre-sin-nombre-trango-ruta-britanica\/\" target=\"_blank\" rel=\"noreferrer noopener\">Los polacos Janusz Go\u0142\u0105b, Maciej Kimel y Micha\u0142 Kr\u00f3l&nbsp;han instalado y asegurado el C1 a 5.500m de la Ruta Brit\u00e1nica<\/a>, a pesar de las malas condiciones de la nieve. Se est\u00e1n encontrando nevadas y viento fuerte, que les han tenido esperando en la pared. El grupo polaco se encuentra inmerso en el intento de la <strong>primera invernal a la Torre Sin Nombre<\/strong>, uno de los grandes tesoros invernales del Karak\u00f3rum. La Ruta Brit\u00e1nica (1000m, VI, 5.10, A2) es la original, pero cuentan con la incertidumbre de no saber lo que se encontrar\u00e1n en su estado invernal. Esperan que el hielo ofrezca la continuidad que les permita ascender utilizando solamente piolets y crampones.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Trango,Torre Sin Nombre<br>12\/3<br><br>Janusz Go\u0142\u0105b,Maciej Kimel y Micha\u0142 Kr\u00f3l anoche llegaron a C1,5500m.<br>Malas condiciones de nieve.<br><br>Hoy nevada y viento.<br>Los 3 parados en la pared esperando. <br>Lograron asegurar el campo de nieve (marcado en la \ud83d\udcf7)en la Ruta Brit\u00e1nica VI 5.10 A2, 1100m) <a href=\"https:\/\/t.co\/thWNNfQVsM\">pic.twitter.com\/thWNNfQVsM<\/a><\/p>&mdash; k2 (@KrisAnnapurna) <a href=\"https:\/\/twitter.com\/KrisAnnapurna\/status\/1502605754049744899?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">March 12, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y ahora toca paso a los \u00abrecorridos\u00bb vertiginosos, como el que han realizado <a href=\"https:\/\/www.desnivel.com\/alpinismo\/seba-pelletti-hernan-rodriguez-y-antar-machado-completan-la-travesia-del-grupo-la-paz\/\" target=\"_blank\" rel=\"noreferrer noopener\">Seba Pelletti, Hern\u00e1n Rodr\u00edguez y Antar Machado completando la traves\u00eda del Grupo La Paz<\/a> <em>(Desnivel)<\/em>. Tres jornadas y dos vivacs recorriendo los perfiles del Grupo La Paz en la Patagonia chilena. La ruta a la que han bautizado \u2018Ayayema Wesqar\u2019 cuenta con 1.000 metros de desnivel y dificultades de hasta 5.11-. Y cambiando de continente, <a href=\"https:\/\/www.desnivel.com\/alpinismo\/simon-gietl-completa-la-travesia-invernal-del-rosengarten-en-solitario\/\" target=\"_blank\" rel=\"noreferrer noopener\">Simon Gietl completa en solitario la traves\u00eda invernal del Rosengarten, los Dolomitas&nbsp;<\/a><em>(Desnivel)<\/em>. A la traves\u00eda se le conoce como Catinaccio, y lo ha realizado en tres d\u00edas, para completar sus 17 kil\u00f3metros y m\u00e1s de 5.000m de desnivel positivo, en una l\u00ednea evidente que conecta todas las cimas del macizo, y que nadie hab\u00eda afrontado en este estilo.<\/li>\n\n\n\n<li>Y no pod\u00edamos despedirnos sin hablar del<a href=\"https:\/\/www.salyroca.es\/articulo\/roca\/calima-pirineos\/20220315125503007239.html\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;curioso fen\u00f3meno que ha producido la calima en los Pirineos<\/a> <em>(Sal y Roca)<\/em>. No se hab\u00eda visto en 30 a\u00f1os, al menos con esta intensidad. \u00abCurioso adem\u00e1s como s\u00f3lo afecta por debajo de los 2400m, dejando un corte perfecto a esa altitud con nieve limpia por encima de ella\u00bb, comenta Urko Jalle meteor\u00f3logo del Diario de Noticias de Navarra<strong>.<\/strong><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\ud83c\udfdc La advecci\u00f3n de polvo en suspensi\u00f3n (<a href=\"https:\/\/twitter.com\/hashtag\/calima?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#calima<\/a>) desde el <a href=\"https:\/\/twitter.com\/hashtag\/S%C3%A1hara?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#S\u00e1hara<\/a> argelino es muy evidente en <a href=\"https:\/\/twitter.com\/hashtag\/Pirineos?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Pirineos<\/a><br><br>\u26aa\ud83d\udfe0 Curioso adem\u00e1s como s\u00f3lo afecta por debajo de los 2400m, dejando un corte perfecto a esa altitud con nieve limpia por encima de ella<br><br>\ud83c\udfa5 WebCams v\u00eda <a href=\"https:\/\/twitter.com\/hashtag\/AyR?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#AyR<\/a> e <a href=\"https:\/\/twitter.com\/infonieve?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@infonieve<\/a> : <a href=\"https:\/\/t.co\/jlq7KHlRLc\">pic.twitter.com\/jlq7KHlRLc<\/a><\/p>&mdash; La Meteo del Norte (@meteodelnorte) <a href=\"https:\/\/twitter.com\/meteodelnorte\/status\/1503655525665452035?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">March 15, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 9 marzo 2022 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arrancamos a golpe de dicho, cont\u00e1ndote que los viejos roqueros nunca mueren (y siempre vuelven):&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11490\/yuji-hirayama-libera-peaceful-mountain?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Yuji Hirayama libera Peaceful Mountain, 9a, a los 53 a\u00f1os<\/a>&nbsp;<em>(Barrabes)<\/em>. El monte Fotogoyama, en Jap\u00f3n, es donde se encuentra la v\u00eda de 30 m y 9a que ha liberado tras mucho esfuerzo y a la que ha llamado Peaceful Mountain,<em>&nbsp;\u201cMt Futago es una monta\u00f1a en donde reina la paz\u201d.&nbsp;<\/em><\/li>\n\n\n\n<li>Este&nbsp;<a href=\"https:\/\/www.elperiodicoextremadura.com\/deportes\/2022\/03\/03\/400-corredores-espectaculo-prevision-kilometro-63398777.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">s\u00e1bado d\u00eda 12 se celebra el campeonato de Espa\u00f1a de kil\u00f3metro vertical individual y por selecciones en el ya cl\u00e1sico Kil\u00f3metro Vertical de Las Hurdes&nbsp;<\/a><em>(el Peri\u00f3dico Extremadura)<\/em>&nbsp;que cumple su octava edici\u00f3n y que se celebre en la localidad hurdana de Ladrillar (C\u00e1ceres). M\u00e1s de 400 corredores tomar\u00e1n salida en lo que bien seguro ser\u00e1 un gran espect\u00e1culo. Para los que quieran conocer el recorrido para cubrir esos 1000 m de desnivel os diremos que corresponde a una ruta que os compart\u00edamos de subida al Cerro Rongiero (<a href=\"https:\/\/travesiapirenaica.com\/rongiero-ladrillar\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">os dejamos aqu\u00ed el enlace<\/a>).&nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/travesiapirenaica.com\/anwar-lleno-de-luz-alex-txikon\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Pel\u00edcula Anwar (Lleno de luz) con Alex Txikon: alpinismo, solidaridad y energ\u00eda renovable<\/a>. Una ascensi\u00f3n invernal de Alex Txikon al Manaslu, en Nepal, ser\u00e1 el germen de una historia que llevar\u00e1 luz sostenible a Newton en Sierra Leona y a una escuela muy especial en Diamer, Pakist\u00e1n.&nbsp;En palabras de Alex, En palabras del protagonista,<em>&nbsp;\u201ceste es un proyecto que nace del buen hacer en el que quiero destacar la dificultad del rodaje en plena pandemia, la importancia de los valores humanitarios y la creencia de que ser\u00e1 capaz de hacer empatizar y reflexionar al espectador sobre la diferencia de oportunidades\u201d.<\/em><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Eyyyy! Aqu\u00ed un adelanto de \u201cAnwar. Lleno de luz\u201d. A ver qu\u00e9 os parece!! Dejarme en comentarios \ud83d\udc47\ud83c\udffc\ud83d\udc47\ud83c\udffcvuestra impresi\u00f3n xfa \ud83d\ude4f\ud83c\udffc <a href=\"https:\/\/t.co\/RYtMRE8axU\">pic.twitter.com\/RYtMRE8axU<\/a><\/p>&mdash; Alex Txikon (@AlexTxikon) <a href=\"https:\/\/twitter.com\/AlexTxikon\/status\/1499878561703940096?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">March 4, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Una expedici\u00f3n de b\u00fasqueda encuentra&nbsp;<a href=\"https:\/\/www.eldiario.es\/cultura\/hallan-endurance-mitico-barco-hundido-explorador-polar-shackleton_1_8814563.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">en perfecto estado el \u2018Endurance\u2019&nbsp;<\/a><em>(Eldiario);&nbsp;<\/em>el buque de Ernest Shackleton congelado en el tiempo desde que qued\u00f3 atrapado en 1915 en el hielo y su tripulaci\u00f3n lo abandon\u00f3. Shackleton y su expedici\u00f3n partieron en 1914 para intentar llegar desde el mar Weddell hasta el mar de Ross, una ruta transant\u00e1rtica pasando por el Polo Sur. Tuvieron que dejar el buque y con botes salvavidas llegar hasta la Isla Elefante, donde sobrevivieron comiendo focas y ping\u00fcinos.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u26a0\ufe0fNuevo gran hito de la arqueolog\u00eda submarina: en sorprendente estado de conservaci\u00f3n, restos del legendario <a href=\"https:\/\/twitter.com\/hashtag\/Endurance?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Endurance<\/a>, el buque de Ernest Shackleton hundido en 1915, fueron encontrados en Marzo 5 a &gt;3km de profundidad en el <a href=\"https:\/\/twitter.com\/hashtag\/MarDeWeddell?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#MarDeWeddell<\/a>, <a href=\"https:\/\/twitter.com\/hashtag\/Antartica?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Antartica<\/a>\ud83d\udc47 <a href=\"https:\/\/t.co\/JTguQY6lVb\">https:\/\/t.co\/JTguQY6lVb<\/a> <a href=\"https:\/\/t.co\/GiFPZVFa5M\">pic.twitter.com\/GiFPZVFa5M<\/a><\/p>&mdash; Antarctica.cl (@Antarcticacl) <a href=\"https:\/\/twitter.com\/Antarcticacl\/status\/1501525447133339653?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">March 9, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y terminamos la secci\u00f3n de esta semana&nbsp;<a href=\"https:\/\/www.instagram.com\/p\/CZzo9CrJBNW\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">con este video aterrador, viendo como Leland Nisky se aferra con sus piolets al hielo<\/a>&nbsp;cuando empieza a caerle encima una avalancha de nieve. Leland se encontraba escalando en hielo en solitario. \u201cAgradezco los a\u00f1os de experiencia y entrenamiento en situaciones de estr\u00e9s que me mantuvieron calmado y me permitieron superar esta extra\u00f1a situaci\u00f3n y volver a casa sano y salvo\u201d, coment\u00f3 Leland despu\u00e9s en las redes sociales. Una experiencia aterradora.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Leland Nisky on The Ribbon (Ouray,Colorado)<br><br>\u201cThis was probably one of the most terrifying experiences I\u2019ve had while solo climbing.\u201d<br><br>\ud83d\udcf9Leland Nisky via ExpedReview. <a href=\"https:\/\/t.co\/ri5pOokicO\">pic.twitter.com\/ri5pOokicO<\/a><\/p>&mdash; k2 (@KrisAnnapurna) <a href=\"https:\/\/twitter.com\/KrisAnnapurna\/status\/1500924592981950465?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">March 7, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 2 marzo 2022 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Durante meses hemos seguido el <strong>Everest solo invernal de Jost Kobusch<\/strong>. Tras un \u00faltimo intento para llegar a m\u00e1s altura, alcanzando los 6.500, <a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11483\/jost-kobusch-alcanza-6500m-everest\" target=\"_blank\" rel=\"noreferrer noopener\">Jost decide dar por finalizada la expedici\u00f3n&nbsp;<\/a>(Barrabes). Recordad que este es el segundo a\u00f1o de un proyecto de tres. El objetivo de este invierno era llegar a 8.000 metros donde comienza el corredor&nbsp;<em>Hornbein&nbsp;<\/em>y ver sus condiciones para el asalto final el pr\u00f3ximo a\u00f1o. (Puedes seguir el <a href=\"https:\/\/travesiapirenaica.com\/jost-kobusch-everest-invernal\/\">timeline de los acontecimiento de su aventura aqu\u00ed<\/a>)<\/li>\n<\/ul>\n\n\n\n<p><em>\u00abSi fu\u00e9ramos de vacaciones a la playa y lloviera los 14 d\u00edas, \u00bfel mal tiempo arruin\u00f3 nuestras vacaciones? \u00bfO quiz\u00e1s fueron nuestros deseos, sue\u00f1os y esperanzas? \u00bfQui\u00e9n controla nuestras expectativas? Cuando part\u00ed para esta expedici\u00f3n, era consciente de que los vientos pod\u00edan golpear la monta\u00f1a a 250 km\/h. Tambi\u00e9n era consciente de que las condiciones meteorol\u00f3gicas pod\u00edan ser muy malas. En consecuencia, la expedici\u00f3n fue como esperaba que fuera. De acuerdo, entre t\u00fa y yo, fue realmente tormentosa y quiz\u00e1 un poco peor de lo que esperaba. Pero al final del d\u00eda, aprend\u00ed mucho y estoy muy agradecido por la experiencia. Hoy he decidido no seguir ascendiendo. Continuar en estas condiciones no tiene mucho sentido.\u00bb&nbsp;<\/em>\u2014<a href=\"https:\/\/www.instagram.com\/p\/CaiBLbZg88_\/\" target=\"_blank\" rel=\"noreferrer noopener\">Jost Kobusch<\/a><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tambi\u00e9n <a href=\"https:\/\/www.desnivel.com\/expediciones\/la-expedicion-de-grace-tseng-planea-intentar-manana-la-cima-del-k2-invernal\/\" target=\"_blank\" rel=\"noreferrer noopener\">termina el intento al K2 invernal con ox\u00edgeno de Grace Tseng&nbsp;<\/a><em>(Desnivel)<\/em>. Se encontraban en el C3 esperando un posible ataque a cumbre una vez los sherpas hab\u00edan equipado la ruta hasta el C4. Finalmente decidieron descender al campo base y dar por concluida la expedici\u00f3n. Todos sanos y salvos. Han indicado que continuar\u00e1n su escalada en verano.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Finalmente, la segunda ascensi\u00f3n hist\u00f3rica al <a href=\"https:\/\/twitter.com\/hashtag\/K2?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#K2<\/a> invernal deber\u00e1 esperar. El intento a cima que el grupo liderado por la taiwanesa Grace Tseng hab\u00eda encarado tan bien finalmente no se ha materializado<a href=\"https:\/\/t.co\/RqkewE62ry\">https:\/\/t.co\/RqkewE62ry<\/a> <a href=\"https:\/\/t.co\/VBQ8nClkYW\">pic.twitter.com\/VBQ8nClkYW<\/a><\/p>&mdash; Desnivel (@desnivelados) <a href=\"https:\/\/twitter.com\/desnivelados\/status\/1498228520950108162?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">February 28, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.turiski.es\/omar-di-felice-completa-la-primera-parte-de-la-vuelta-al-artico-en-bicicleta\/\" target=\"_blank\" rel=\"noreferrer noopener\">Omar di Felice completa la primera parte de la Vuelta al \u00c1rtico en bicicleta&nbsp;<\/a><em>(Turiski).<\/em> A finales de enero nos hac\u00edamos eco de su aventura: intentar <a href=\"https:\/\/www.revistaoxigeno.es\/actualidad\/primera-vuelta-mundo-artica-en-bici-en-solitario-reto-omar-di-felice_249945_102.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">la primera vuelta al mundo \u00e1rtica en bici y en solitario<\/a>. 4.000 km y 40.000 m de desnivel positivo para concienciar sobre el cambio clim\u00e1tico, y dar visibilidad a c\u00f3mo est\u00e1 afectando a esa regi\u00f3n; desde Kamchatka, en Rusia, hasta Laponia, y despu\u00e9s desde Svalbard hasta las islas, e incluso Groenlandia, Canad\u00e1 y Alaska. Comenzando el 2 de febrero de 2022, hasta la fecha <strong>ha cruzado la regi\u00f3n rusa de Kamchatka y recorrido la Laponia desde Murmansk hasta Tromso, <\/strong>en un total de 2000 km. Omar es muy activo en Instagram (<a href=\"https:\/\/www.instagram.com\/omardifelice\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed su perfil<\/a>), donde pod\u00e9is seguir su periplo \u00e1rtico.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Riding into the ice-cold lands. <a href=\"https:\/\/twitter.com\/omardifelice?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@omardifelice<\/a> has carried out Svalbard\u2019s exploration, a journey marked by strong wind, whiteout and low temperatures.<br><br>Ready for Greenland!<a href=\"https:\/\/twitter.com\/hashtag\/lovemywilier?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#lovemywilier<\/a> <a href=\"https:\/\/t.co\/st66FbFVJo\">pic.twitter.com\/st66FbFVJo<\/a><\/p>&mdash; Wilier Triestina (@WilierTriestina) <a href=\"https:\/\/twitter.com\/WilierTriestina\/status\/1498686772016037889?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">March 1, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y nos despedimos mostr\u00e1ndote como el alpinista suizo <a href=\"https:\/\/www.planetmountain.com\/en\/news\/climbing\/marcel-remy-still-climbing-strong-aged-99.html\" target=\"_blank\" rel=\"noreferrer noopener\">Marcel R\u00e9my sigue escalando con energ\u00eda a sus 99 a\u00f1os<\/a> <em>(Planet Mountain)<\/em>.&nbsp;Un 4c de 16 metros para celebrar su cumplea\u00f1os.&nbsp;<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"it\" dir=\"ltr\">Marcel Remy sale un 4c nel giorno del suo 99esimo compleanno <a href=\"https:\/\/t.co\/BqVcoueyMG\">https:\/\/t.co\/BqVcoueyMG<\/a> <a href=\"https:\/\/t.co\/1dotVmqdXt\">pic.twitter.com\/1dotVmqdXt<\/a><\/p>&mdash; Mountain Blog (@mountainblogit) <a href=\"https:\/\/twitter.com\/mountainblogit\/status\/1497146117779189760?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">February 25, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mi\u00e9rcoles, 23 febrero 2022 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arrancamos cont\u00e1ndote que una expedici\u00f3n va a intentar la&nbsp;<strong>primera invernal a la Torre Sin Nombre<\/strong>. L<a href=\"https:\/\/www.revistaoxigeno.es\/deportes\/en-busca-primera-invernal-torre-sin-nombre_251575_102.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">os polacos Janusz Go\u0142\u0105b, Maciej Kimel y Micha\u0142 Kr\u00f3l han puesto rumbo a Paquist\u00e1n para tratar de llevarse uno de los grandes tesoros invernales del Karak\u00f3rum<\/a>&nbsp;<em>(Ox\u00edgeno)<\/em>. Intentar\u00e1n hacerlo por la Ruta Brit\u00e1nica (1000m, VI, 5.10, A2), la original, con la incertidumbre de no saber lo que se encontrar\u00e1n en su estado invernal. Esperan que el hielo ofrezca la continuidad que les permita ascender utilizando solamente piolets y crampones.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Por su parte,<a href=\"https:\/\/www.desnivel.com\/expediciones\/jonatan-garcia-vamos-al-gangapurna-con-topo-mena-para-escalar-como-mas-nos-gusta\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;Jonatan Garc\u00eda quiere llevar su estilo alpino ligero, r\u00e1pido y en autonom\u00eda al macizo del Annapurna para intentar escalar el Gangapurna (7.455m)<\/a>.<em>&nbsp;(Desnivel)<\/em>&nbsp;El estilo de Jonatan es ampliamente conocido con sus actividades en el Valle de Benasque. Lo har\u00e1 junto con Esteban \u2018Topo\u2019 Mena. Ambos se conocieron en el Dhaulagiri en la primavera de 2021 d\u00f3nde surgi\u00f3 un gran entendimiento entre ambos y planes de futuro.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tambi\u00e9n del Himalaya, informarte de la&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11478\/intento-cima-invernal-cho-oyu?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">retirada debido al mal tiempo de los dos equipos nepaleses que trataban de abrir una nueva ruta invernal al Cho Oyu<\/a>&nbsp;<em>(Barrabes)<\/em>. Han llegado en su intento a los 7000m. Y en cuanto a la&nbsp;<a href=\"https:\/\/explorersweb.com\/k2-plans-for-the-final-summit-push\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">expedici\u00f3n al K2 invernal con ox\u00edgeno liderada por Nima Gyalzen, se encuentran en el C3 esperando un posible ataque a cumbre para este jueves<\/a>&nbsp;<em>(Explorersweb)<\/em>. Los \u00faltimos d\u00edas el viento ha sido muy fuerte en los campamentos de altura.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.salyroca.es\/articulo\/vida-eco\/cola-caballo-cascada-mas-bonita-mundo-amenazada-calentamiento-global\/20220215141738007149.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">La cascada de la Cola de Caballo amenazada por el calentamiento global<\/a>&nbsp;<em>(Sal y Roca)&nbsp;<\/em>seg\u00fan un estudio del IGME. El agua que descarga el manantial de Garc\u00e9s procede fundamentalmente de la infiltraci\u00f3n del agua producida por la fusi\u00f3n nival.&nbsp;Se espera un ascenso de la temperatura media en el Pirineo a finales del siglo de hasta 7,1 grados, las precipitaciones en forma de nieve se reducir\u00edan y la cobertura nival que llegue a formarse durar\u00e1 menos. Esto reducir\u00eda la recarga que garantiza la supervivencia de la cascada de la Cola de Caballo.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Llegan los carnavales al Pirineo, y se viste de tradici\u00f3n, colorido y misticismo.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">El carnaval pirenaico anuncia el fin del largo invierno en las monta\u00f1as. <br>Las bestias despiertan. Salen de de sus madrigueras.<br>En Prats de Mollo, al pie del Canig\u00f3, surgen osos, hombres salvajes vestidos con pieles, y con la cara negra de aceite y holl\u00edn.<br>Bonita fiesta ancestral. <a href=\"https:\/\/t.co\/bHKj0x90sc\">pic.twitter.com\/bHKj0x90sc<\/a><\/p>&mdash; Eduardo Vi\u00f1uales (@EduVinuales) <a href=\"https:\/\/twitter.com\/EduVinuales\/status\/1496110603777290242?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">February 22, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-16-febrero-2022\">Mi\u00e9rcoles, 16 febrero 2022 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comenzamos con una&nbsp;<strong>&nbsp;S\u00faper Trilog\u00eda Alpina invernal<\/strong>: la de Benjamin V\u00e9drines, L\u00e9o Billon y Seb Ratel, que han realizado la&nbsp;<a href=\"https:\/\/www.desnivel.com\/alpinismo\/benjamin-vedrines-leo-billon-y-seb-ratel-completan-la-super-trilogia-alpina-invernal-en-la-norte-del-cervino\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">primera ascensi\u00f3n en el d\u00eda de la \u2018Gogna-Cerruti\u2019 (1.000 m, A2, 6b, M7) y la suman a las escaladas de las caras norte del Eiger y las Grandes Jorasses por sus v\u00edas directas hist\u00f3ricas en invierno<\/a>&nbsp;<em>(Desnivel)<\/em>. Ven\u00edamos siguiendo el gran desaf\u00edo alpin\u00edstico de los tres franceses que han retado y salido victoriosos en invernal de las caras Norte de los emblem\u00e1ticos Eiger, Grandes Jorasses y Matterhorn.&nbsp;<a href=\"https:\/\/cumbresmountainmagazine.com\/tres-franceses-invierno-trilogia-alpes\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Lo han logrado en 23 d\u00edas. El primero en completar la famosa Trilog\u00eda de los Alpes fue Gast\u00f3n R\u00e9buffat, entre 1945 y 1952<\/a>&nbsp;(<em>Cumbres mountain magazine<\/em>).<\/li>\n<\/ul>\n\n\n\n<p><em>\u201cUna pizca de an\u00e1lisis, una pizca de compromiso y un pu\u00f1ado de motivaci\u00f3n. Esos son los ingredientes necesarios para sacar partido de esta \u00faltima ventana con precisi\u00f3n.\u201d&nbsp;\u2014Benjamin V\u00e9drines<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pasando al Himalaya te contamos que&nbsp;<strong>Simone Moro, Alex Txikon y su equipo<\/strong>&nbsp;<strong>dicen adi\u00f3s al Manaslu invernal<\/strong>.&nbsp;<a href=\"https:\/\/twitter.com\/AlexTxikon\/status\/1493658023927205897?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Alex Txikon<\/a>:&nbsp;<em>\u201cHa sido muy duro decidir dar por acabado el proyecto #Manaslu2022. (\u2026) Estamos con ganas de volver a casa, pero con el sabor agridulce de no haber podido trabajar en la monta\u00f1a todo lo que nos hubiera gustado.\u201d<\/em>&nbsp;El duro invierno con copiosas nevadas no les ha ayudado. Por otro lado en la&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/la-expedicion-al-k2-invernal-alcanza-c3-y-espera-una-ventana-de-cima-en-cb\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>expedici\u00f3n al K2 invernal<\/strong>&nbsp;liderada por Grace Tseng&nbsp;han alcanzado el C3 y est\u00e1n a la espera en el CB de una ventana de buen tiempo para intentar la cumbre con ox\u00edgeno<\/a>&nbsp;<em>(Desnivel)<\/em>.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La semana pasada, el d\u00eda 9,&nbsp;<a href=\"https:\/\/carrerasdemontana.com\/2022\/02\/11\/ruta-del-cares-cortada-por-desprendimiento-reabierta-provisionalmente\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">se produjo un aparatoso derrumbe que cort\u00f3 la ruta del Cares<\/a>&nbsp;<em>(Carreras de Monta\u00f1a), l<\/em>o pod\u00e9is ver en el tuit que compartimos. El desprendimiento se produjo en la zona de Culiembru, a unos cinco kil\u00f3metros de Poncebos, en la parte asturiana de la senda que comunica con Ca\u00edn.<strong>&nbsp;Se ha reabierto la ruta<\/strong>&nbsp;a los senderistas, pero habr\u00e1 que transitar con cuidado. En la zona son muy frecuentes los desprendimientos.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u203c\ufe0fAVISO  IMPORTANTE\u203c\ufe0fLa direcci\u00f3n del parque nacional de Picos de Europa \ud83c\udfd4\ufe0f nos ha comunicado que se ha producido un corte \ud83d\udea7 por derrumbe en la Ruta del Cares. El paso \ud83d\udeb7por la misma queda limitado. <a href=\"https:\/\/t.co\/AxEscsb9Ya\">pic.twitter.com\/AxEscsb9Ya<\/a><\/p>&mdash; 112 Asturias (@112Asturias) <a href=\"https:\/\/twitter.com\/112Asturias\/status\/1491438887847473154?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">February 9, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hoy, jueves 17 de febrero,&nbsp;<a href=\"https:\/\/www.desnivel.com\/cultura\/el-club-montaneros-de-aragon-celebrara-un-acto-de-homenaje-a-alberto-martinez-embid\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">el club Monta\u00f1eros de Arag\u00f3n celebra un acto de homenaje a Alberto Mart\u00ednez Embid, el prol\u00edfico escritor y pirine\u00edsta que falleci\u00f3 el pasado mes de noviembre<\/a>&nbsp;<em>(Desnivel)<\/em>. En el enlace que os compartimos pod\u00e9is leer el art\u00edculo que le dedic\u00f3 su amigo, el naturalista&nbsp;<a href=\"https:\/\/twitter.com\/EduVinuales?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Eduardo Vi\u00f1uales<\/a>.<\/li>\n<\/ul>\n\n\n\n<p><em>\u201cAlberto reten\u00eda las fechas, conoc\u00eda los sitios, sab\u00eda detalles de cada protagonista, conoc\u00eda los pormenores de las primeras descubiertas que propiciaron aquellos primeros naturalistas, arist\u00f3cratas ociosos o fot\u00f3grafos hace m\u00e1s de un siglo largo\u2026 y as\u00ed era \u00e9l, hasta el punto de que podr\u00edamos asegurar que era el Henri Beraldi de nuestro Pirineo, el gran cronista de la aventura y la conquista de las c\u00faspides del Alto Arag\u00f3n\u201d.<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y para terminar, os compartimos la foto que nos llega v\u00eda&nbsp;<a href=\"https:\/\/twitter.com\/Benasque_?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">@Benasque_<\/a>&nbsp;en twitter, perteneciente al Archivo del Centre Excursionista de Catalunya. \u201cUn colosal glaciar para acoger la mayor cumbre pirenaica\u201d, el Aneto con sus 3.404m. Si le pondr\u00edamos color a la fotograf\u00eda nos parecer\u00edan las mism\u00edsimas grietas del Everest. Una pena la agon\u00eda de los hielos del Pirineo.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\ud83c\udfd4La espectacularidad del glaciar del Aneto (3.404m) en el siglo pasado. <br><br>\ud83e\uddca Un colosal glaciar para acoger la mayor cumbre pirenaica. <a href=\"https:\/\/t.co\/evvPEoB4XA\">pic.twitter.com\/evvPEoB4XA<\/a><\/p>&mdash; Benasque \ud83c\udfd4\ufe0f (@Benasque_) <a href=\"https:\/\/twitter.com\/Benasque_\/status\/1492399288197992455?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">February 12, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-09-febrero-2022\">Mi\u00e9rcoles, 09 febrero 2022 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11466\/denis-urubko-cima-invernal-kosar?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Denis Urubko hace cima en el 6mil, Kosar Gang, Pakist\u00e1n<\/a>&nbsp;<em>(Barrabes)<\/em>. Lo ha hecho por una nueva variante y junto con los rusos Anton Kravchenko, Andrey Shliapnikov y Maksim Berngard. Es la vuelta de Denis a las altas monta\u00f1as, tras su \u201cretirada\u201d del himalayismo de \u00e9lite. El Kosar Gang es una monta\u00f1a que se suele frecuentar en verano en su ruta normal, pero que no hab\u00eda sido ascendido en invernal. Lo llamativo es la vuelta de Denis a la palestra medi\u00e1tica del alpinismo tras 2 a\u00f1os de \u201cretirada\u201d, en los que se ha dedicado a la familia y la escalada en roca. En una entrevista al medio&nbsp;<em>Mozg\u00e1svil\u00e1g Outdoor Magazine<\/em>, sentencia que hay tres cosas que le inspiran a volver: \u201cbatir el r\u00e9cord de Juanito Oiarz\u00e1bal (26 veces en cumbre de ochomiles sin O2, Denis 23 veces hasta ahora); abrir una nueva ruta en estilo alpino a un ochomil en compa\u00f1\u00eda de una mujer alpinista (hasta ahora ninguna mujer ha hecho ruta nueva a un ochomil en estilo alpino); escalar una cumbre en invierno en la zona de muerte.&nbsp;<a href=\"https:\/\/twitter.com\/KrisAnnapurna\/status\/1489715951985733636?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">En los pr\u00f3ximos 2 \u00f3 3 a\u00f1os quiero intentar cumplir con estos objetivos<\/a>.&nbsp;<em>(v\u00eda @KrisAnnapurna)<\/em>\u201d Estaremos atentos a su \u201cvuelta\u201d.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sin salir del Himalaya, te contamos que<a href=\"https:\/\/www.desnivel.com\/expediciones\/la-expedicion-de-grace-tseng-monta-c2-y-ya-piensa-en-la-cima-del-k2-invernal\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;la expedici\u00f3n de Grace Tseng ya est\u00e1 pensando en la cima del K2 invernal tras montar el C2<\/a>&nbsp;<em>(Desnivel).&nbsp;<\/em>Las copiosas nevadas de estos d\u00edas quiz\u00e1s bajen un poco las expectativas. Recordar que lo que sorprendi\u00f3 de la expedici\u00f3n era lo \u201ctarde\u201d que iban, siendo el intento de K2 invernal m\u00e1s tard\u00edo de la historia. La expedici\u00f3n se lleva a cabo usando ox\u00edgeno suplementario.&nbsp;Por otro lado,&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/instalados-los-dos-cb-en-el-cho-oyu-invernal\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">en el CB del Cho Oyu ya se han instalado dos expediciones de sherpas<\/a>&nbsp;que pretenden abrir una ruta comercial en la vertiente nepal\u00ed.<\/li>\n\n\n\n<li>Al mal tiempo buena cara.&nbsp;<strong>Alex Txikon, I\u00f1aki \u00c1lvarez y Simone Moro esperan la vuelta de la nieve en el Manaslu invernal<\/strong>. Un invierno duro, que no les ha dado respiro, \u201c<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11468\/nieve-no-cesa-entierra-tiendas?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">metros y metros de nieve que caen sin descanso desde hace un mes<\/a>\u201d. Antes de ayer, Txikon compart\u00eda en sus redes la manera con la que pretenden afrontar lo que les viene: \u201cla cosa est\u00e1 complicada, pero para afrontarlo con fuerza hoy hemos comido chuleta de Terrabuey a la brasa.\u201d. Vemos que la log\u00edstica para asar una txuleta en un campo base de un 8000 hace necesaria cierta imaginaci\u00f3n y creatividad. Lo pod\u00e9is ver a continuaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u2744\ufe0f Esta misma noche parece que vuelve la nieve y en los pr\u00f3ximos d\u00edas m\u00e1s\u2026 La cosa est\u00e1 complicada, pero para afrontarlo con fuerza hoy hemos comido chuleta de Terrabuey a la brasa. Buen\u00edsima! <a href=\"https:\/\/t.co\/qDZUcKMXAo\">pic.twitter.com\/qDZUcKMXAo<\/a><\/p>&mdash; Alex Txikon (@AlexTxikon) <a href=\"https:\/\/twitter.com\/AlexTxikon\/status\/1491002749919498242?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">February 8, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.revistaoxigeno.es\/actualidad\/nace-pirineos-mountain-film-festival_250692_102.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Nace el Pirineos Mountain Film Festival&nbsp;<\/a><em>(Ox\u00edgeno)<\/em>.<a href=\"https:\/\/pirineosmff.com\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;Un nuevo certamen&nbsp;<\/a>en Huesca toma el testigo del&nbsp;<em>Tour Mundial de Banff<\/em>, buscando ser referente internacional para el cine de aventura y naturaleza. La primera edici\u00f3n del 16 al 19 de febrero&nbsp;en Huesca. Como padrino para esta edici\u00f3n contar\u00e1 con el alpinista y escritor Sebasti\u00e1n \u00c1lvaro. Tambi\u00e9n&nbsp;<a href=\"https:\/\/www.ondacero.es\/emisoras\/aragon\/noticias\/escaladora-silvia-vidal-pirineos-mountain-film-festival_202202086202492523324700011a8d23.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">visitar\u00e1 el certamen la escaladora Silvia Vidal para presentar \u201cSincronia m\u00e0gica\u201d, la primera ascensi\u00f3n de la cara oeste del cerro chileno grande<em>&nbsp;<\/em><\/a><em>(Onda Cero).<\/em>&nbsp;Recordar que Silvia fue distinguida hace unos meses con una \u201cmenci\u00f3n especial\u201d en los Piolets de Oro del 2021.<\/li>\n\n\n\n<li>Y nos despedimos con un video espectacular de Jeff Wright que nos compart\u00eda&nbsp;<a href=\"https:\/\/twitter.com\/KrisAnnapurna?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">@KrisAnnapurna<\/a>&nbsp;en Twitter. \u201c\u00bfTe sentar\u00edas all\u00ed?\u201d Priti y Jeff Wright hicieron hace unas semanas la traves\u00eda de Cerro Standhardt &#8211; Punta Herron &#8211; Torre Egger.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Priti y Jeff Wright acaban de cumunicar que  hace dos semanas hicieron la traves\u00eda de Cerro Standhardt &#8211; Punta Herron &#8211; Torre Egger! <br><br>\u201cEs sin duda el mayor orgullo de escalada de nuestra vida\u201d- dice Jeff.<br>Priti es la tercera mujer que escala la Torre Egger.<br><br>Te sentar\u00edas all\u00ed?\ud83d\ude48 <a href=\"https:\/\/t.co\/S0r4d4gyiO\">pic.twitter.com\/S0r4d4gyiO<\/a><\/p>&mdash; k2 (@KrisAnnapurna) <a href=\"https:\/\/twitter.com\/KrisAnnapurna\/status\/1490771473568514051?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">February 7, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-02-febrero-2022\">Mi\u00e9rcoles, 02 febrero 2022 <\/h3>\n\n\n\n<p><strong>Tragedia en el Cerro Torre<\/strong>:&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11461\/korra-pesce-fallece-cerro-torre?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Una avalancha de roca y hielo alcanza a Tom\u00e1s Aguil\u00f3 y Korra Pesce en el Cerro Torre, acabando con la vida del segundo&nbsp;<\/a><em>(Barrabes)<\/em>. Fueron alcanzados por la avalancha tras abrir una nueva v\u00eda, y se quedaron sin equipo de vivac. Korra Pesce fue quien qued\u00f3 m\u00e1s herido imposibilit\u00e1ndole la movilidad, por su parte Tom\u00e1s Aguil\u00f3 pudo descender 300 metros vitales para que le localizar\u00e1 un dron. Un potente equipo de rescate formado por el italiano Matteo della Bordella,&nbsp;el suizo&nbsp;Roger Schaeli, el alem\u00e1n&nbsp;Thomas Huber&nbsp;y el argentino&nbsp;Roberto Treu lo descendieron tras 7 largos de escalada y una traves\u00eda. Tras haber sobrepasado sus \u201cl\u00edmites f\u00edsicos y psicol\u00f3gicos\u201d tuvieron que descender amargamente dando por fallecido a Korra.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Se confirma el peor de los pron\u00f3sticos en el Cerro Torre: Se suspenden las labores de rescate dada la imposibilidad de llegar hasta Korra Pesce ni escalando ni por v\u00eda a\u00e9rea&#8230;Mucho amor \u2764\ufe0f para familia y amigos y gracias a todo el equipo de rescate que han hecho lo imposible \ud83d\ude4f <a href=\"https:\/\/t.co\/Uihhm2AGwH\">pic.twitter.com\/Uihhm2AGwH<\/a><\/p>&mdash; Hermanos Pou (@hermanospou) <a href=\"https:\/\/twitter.com\/hermanospou\/status\/1487486323665559554?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">January 29, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En los Alpes la cordada del&nbsp;<strong>GMHM (Grupo Militar de Alta Monta\u00f1a) franc\u00e9s: L\u00e9o Billon, Seb Ratel y Benjamin V\u00e9drines<\/strong>&nbsp;lo han vuelto a hacer,&nbsp;<a href=\"https:\/\/www.desnivel.com\/alpinismo\/leo-billon-seb-ratel-y-benjamin-vedrines-escalan-directe-de-lamitie-a-las-grandes-jorasses\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">escalan \u2018Directe de l\u2019amiti\u00e9\u2019 a las Grandes Jorasses<\/a>&nbsp;<em>(Desnivel)<\/em>. Recordar que la semana pasada os cont\u00e1bamos que&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11456\/1-escalada-invernal-alpino-directisima?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">consegu\u00edan superar en alpino y en invierno la Direct\u00edsima Harlin al Eiger<\/a><em>&nbsp;(Barrabes).<\/em>&nbsp;D\u00edas muy fruct\u00edferos para esta cordada que solo les queda el Cervino en su S\u00faper Trilog\u00eda Alpina invernal. En estos dos itinerarios lo han hecho por v\u00edas directas de gran dificultad t\u00e9cnica.<\/li>\n\n\n\n<li><a href=\"https:\/\/as.com\/ascolor\/2022\/01\/22\/reportajes\/1642823681_835163.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">250 d\u00edas de escalada con 90 primaveras: Maria Kittl<\/a>&nbsp;<em>(diario As)<\/em>. A sus 90 a\u00f1os Maria Kittl sigue escalando a trav\u00e9s de Austria, Francia, Espa\u00f1a y Croacia. \u201cLa primera raz\u00f3n por la que escalo: por mi mente\u201d, nos dice. En su juventud fue una de las primeras mujeres en abrir rutas alpinas en 1960 y 1970, junto con su marido que le dej\u00f3 en 2008 en un accidente.&nbsp;Una fuente de inspiraci\u00f3n sin duda, junto con otros ejemplos como Carlos Soria o Marcel Remy que segu\u00eda escalando a los 98 a\u00f1os.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Die 89-j\u00e4hrige Kletterin | Klettern in \u00d6sterreich\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/pvqFzbDCr_o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En el&nbsp;<strong>Everest solo invernal de Jost Kobusch<\/strong>&nbsp;os cont\u00e1bamos la semana pasada lo crudas que lo pasaba Jost en su tienda de campa\u00f1a zarandeada por el viento (<a href=\"https:\/\/www.instagram.com\/p\/CZH3X4Rh3wP\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">pod\u00e9is ver el video<\/a>).&nbsp;Ahora se encuentra en el pueblo de Lobuche esperando se pase este periodo de vientos huracanados. \u201cY todav\u00eda estoy esperando un mejor tiempo\u2026 Se me ocurre que probablemente podr\u00eda pasar un tiempo antes de que tenga sentido volver a subir.\u201d<\/li>\n\n\n\n<li><a href=\"https:\/\/www.revistaoxigeno.es\/deportes\/buenas-posibilidades-en-manaslu_250465_102.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Txikon y su equipo vuelven a la carga en el Manaslu invernal<\/a>, tras llegar al C1 se encuentran en el CB con motivaci\u00f3n para plantar cara a la monta\u00f1a. \u201cHay que ir d\u00eda a d\u00eda. Todav\u00eda tenemos todo febrero por delante y soy optimista, pero no me quiero pasar. Si la monta\u00f1a nos da una tregua vamos a intentarlo. De eso no tengo ninguna duda. Est\u00e1 siendo un invierno muy duro y con mucha nieve, pero nos agarramos a estos pron\u00f3sticos positivos. Esperemos tener m\u00e1s suerte en esta segunda parte de la expedici\u00f3n\u201d, finaliza Txikon&nbsp;<em>(Ox\u00edgeno)<\/em>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Arrancamos febrero con una importante nevada, pero con la motivaci\u00f3n por las nubes y siendo testigos de que el viento sopla con m\u00e1s fuerza en cotas m\u00e1s altas y nieva m\u00e1s a menor altura. Y en base a ello estamos planteando la estrategia. Trabajando a tope! \ud83d\udcaa\ud83c\udffb <a href=\"https:\/\/t.co\/wVGxWza0uO\">pic.twitter.com\/wVGxWza0uO<\/a><\/p>&mdash; Alex Txikon (@AlexTxikon) <a href=\"https:\/\/twitter.com\/AlexTxikon\/status\/1488529370264260611?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">February 1, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-26-enero-2022\">Mi\u00e9rcoles, 26 enero 2022 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nos hacemos eco de una aventura \u00e1rtica en bicicleta. Es el&nbsp;<a href=\"https:\/\/www.revistaoxigeno.es\/actualidad\/primera-vuelta-mundo-artica-en-bici-en-solitario-reto-omar-di-felice_249945_102.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">reto de Omar di Felice: la primera vuelta al mundo \u00e1rtica en bici y en solitario<\/a>&nbsp;<em>(Oxigeno)<\/em>. 4.000 km y 40.000 m de desnivel positivo para concienciar sobre el cambio clim\u00e1tico, y dar visibilidad a c\u00f3mo est\u00e1 afectando a esa regi\u00f3n; desde Kamchatka, en Rusia, hasta Laponia, y despu\u00e9s desde Svalbard hasta las islas, e incluso Groenlandia, Canad\u00e1 y Alaska. La aventura comenzar\u00e1 el 2 de febrero de 2022&nbsp;y le podremos seguir en sus redes sociales. Omar es muy activo en Instagram (<a href=\"https:\/\/www.instagram.com\/omardifelice\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed su perfil<\/a>). Ahora como aperitivo pod\u00e9is ver c\u00f3mo est\u00e1 preparando el reto en este&nbsp;<em>Teaser&nbsp;<\/em>\u201c<em>THE ARCTIC WORLD TOUR<\/em>\u201d.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"THE ARCTIC WORLD TOUR - Winter 2022 - Video Teaser\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/mfWp0vhNSnE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pasando ahora al alpinismo, os contamos la<a href=\"https:\/\/www.desnivel.com\/alpinismo\/solitario-invernal-de-charles-dubouloz-a-la-rolling-stones-de-las-grandes-jorasses\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;extraordinaria ascensi\u00f3n del alpinista Charles Dubouloz&nbsp;con la solitaria invernal a la \u201cRolling Stones\u201d de las Grandes Jorasses<\/a>&nbsp;<em>(Desnivel)<\/em>.<\/li>\n<\/ul>\n\n\n\n<p><em>\u201cAcabo de llegar esta noche a Courmayeur y todav\u00eda no me lo puedo creer. Hace mucho tiempo que so\u00f1aba con esta ascensi\u00f3n. 6 d\u00edas en la pared, a la sombra bajo el viento. Es el logro de muchos a\u00f1os (\u2026)\u201d<\/em>&nbsp;\u2014<a href=\"https:\/\/www.instagram.com\/charles_dubouloz\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Charles Dubouloz<\/a><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y sin salir de los Alpes, los franceses del GMHM (Grupo Militar de Alta Monta\u00f1a),&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11456\/1-escalada-invernal-alpino-directisima?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">L\u00e9o Billon, S\u00e9bastien Ratel y Benjamin V\u00e9drines, consiguen superar en alpino y en invierno la Direct\u00edsima Harlin al Eiger<\/a><em>&nbsp;(Barrabes)<\/em>. La primera invernal en estilo alpino a la v\u00eda m\u00e1s directa hasta la cumbre en la que quiz\u00e1s es la m\u00e1s famosa pared norte de los Alpes. Han necesitado 5 d\u00edas y 4 vivacs para superar los 1.800m de pared. La ruta Harlin se abri\u00f3 en el invierno de 1966, y fue llamada as\u00ed en honor al alpinista John Harlin, que falleci\u00f3 el 22 de marzo durante el intento al romperse una cuerda.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Saltamos al Himalaya. Debido a las malas condiciones meteorol\u00f3gicas,&nbsp;<a href=\"https:\/\/www.instagram.com\/p\/CZFPaRCIN7T\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Herv\u00e9 Barmasse y David G\u00f6ttler han suspendido su expedici\u00f3n que pretend\u00eda escalar la Rupal al Nanga Parbat en invierno<\/a>. \u201cNunca me he arrepentido de ninguna experiencia y ciertamente no me arrepentir\u00e9 de esta. La de haber cre\u00eddo (y sigo creyendo) que es posible escalar la pared m\u00e1s grande del mundo (el Rupal del Nanga Parbat 8126 m) en invierno y con un estilo limpio, ligero y alpino.\u201d,&nbsp;<a href=\"https:\/\/www.instagram.com\/p\/CZFPaRCIN7T\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">dice Herv\u00e9<\/a>.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Unos se van y otros llegan:&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/la-expedicion-de-grace-tseng-al-k2-invernal-llega-al-campo-base\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">La expedici\u00f3n de la alpinista taiwanesa Grace Tseng al K2 invernal llega al campo base<\/a>&nbsp;<em>(Desnivel)<\/em>. La expedici\u00f3n se llevar\u00e1 a cabo usando ox\u00edgeno suplementario.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El equipo (con algunas bajas que te cont\u00e1bamos la semana pasada) de&nbsp;<a href=\"https:\/\/twitter.com\/AlexTxikon\/status\/1485964731714318346?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Alex Txikon y Simone Moro permanecen en el pueblo de Samagaun<\/a>, esperando su oportunidad para subir al CB y retomar la aventura del Manaslu invernal. Por su parte, en el&nbsp;<strong>Everest solo invernal de Jost Kobusch<\/strong>&nbsp;se ven cosas como el video que te compartimos a continuaci\u00f3n. \u201cJost Kobusch el otro d\u00eda a 6000m\u201d. Fr\u00edo, \u00bfno?\u2026<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Everest solo<br>23\/1 <br><br>Jost Kobusch el otro d\u00eda a 6000m.<br>Ahora est\u00e1 abajo. <br>As\u00ed pas\u00f3 la noche Jost: <br>(Ponlo con sonido) <a href=\"https:\/\/t.co\/Pv2BqRud9B\">pic.twitter.com\/Pv2BqRud9B<\/a><\/p>&mdash; k2 (@KrisAnnapurna) <a href=\"https:\/\/twitter.com\/KrisAnnapurna\/status\/1485341982453121030?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">January 23, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y para cerrar te contamos que<a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/huesca\/2022\/01\/26\/el-parque-nacional-prohibe-la-acampada-nocturna-en-el-valle-de-ordesa-1548762.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;el Parque Nacional proh\u00edbe la acampada nocturna en el valle de Ordesa<\/a>&nbsp;<em>(Heraldo)<\/em>. Excepci\u00f3n en el entorno del refugio de G\u00f3riz (previa reserva y con tarifa, limitado a un per\u00edmetro y con cupo) y siempre que el aforo del refugio est\u00e9 completo. Pod\u00e9is leer el art\u00edculo que os enlazamos para m\u00e1s informaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-12-enero-2022\">Mi\u00e9rcoles, 12 enero 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Precauci\u00f3n: Arrancamos la secci\u00f3n poniendo foco en las condiciones invernales del pirineo. \u201c<strong>Nieve dura, con las umbr\u00edas especialmente peligrosas<\/strong>\u201d. La combinaci\u00f3n de diversos factores metereol\u00f3gicos han convertido el manto de nieve en una pista de hielo muy peligrosa, una \u201ctrampa mortal\u201d.&nbsp;<strong>Una semana tr\u00e1gica en el Pirineo<\/strong>&nbsp;con hasta seis muertes en la \u00faltima semana.&nbsp;<a href=\"https:\/\/twitter.com\/montana_segura\/status\/1482029102949597184?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Desde Monta\u00f1a Segura nos piden prudencia<\/a>: \u201cPiolet, crampones y casco imprescindibles, y buenas habilidades en su manejo. En seg\u00fan qu\u00e9 zonas y momentos puede ser dif\u00edcil autodetener una ca\u00edda incluso con el material\u201d.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Ante la presencia de <a href=\"https:\/\/twitter.com\/hashtag\/hielo?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#hielo<\/a> y nieve dura en la <a href=\"https:\/\/twitter.com\/hashtag\/monta%C3%B1a?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#monta\u00f1a<\/a>, extrema la <a href=\"https:\/\/twitter.com\/hashtag\/prudencia?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#prudencia<\/a>. <br>Recordamos:<br>Monta\u00f1eros: llevad piolet, crampones y casco. <br>Esqu\u00ed alpino: seguid las recomendaciones de la estaci\u00f3n y evitad los fuera pistas.<a href=\"https:\/\/twitter.com\/montana_segura?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@montana_segura<\/a> <a href=\"https:\/\/t.co\/QhfQlgbxJm\">pic.twitter.com\/QhfQlgbxJm<\/a><\/p>&mdash; 112 Arag\u00f3n (@112Aragon) <a href=\"https:\/\/twitter.com\/112Aragon\/status\/1483481500276465664?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">January 18, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cEn una monta\u00f1a tan aislada como el Nanga Parbat, el viento est\u00e1 casi siempre presente. (\u2026) Entonces la noche y el tiempo se dilatan\u2026 decenas de minutos como horas que nunca terminan y el pensamiento de que ma\u00f1ana, en estas condiciones, sin las cuerdas fijas que garantizan una conexi\u00f3n segura con el campo base, ser\u00e1 m\u00e1s dif\u00edcil de lo esperado descender. Podr\u00eda ser un d\u00eda m\u00e1s largo que la subida, un d\u00eda dif\u00edcil. (\u2026) Una noche de mierda. Uno de los m\u00e1s duros de nuestra vida\u201d&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11447\/nanga-parbat-herve-barmasse-david?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Herve Barmasse y David G\u00f6ttler alcanzan los 6.200m en la Rupal invernal, Nanga Parbat<\/a>&nbsp;(Barrab\u00e9s).<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sigue la espera de Alex Txikon y Simone Moro para el Manaslu invernal. Como os cont\u00e1bamos la semana pasada las intensas nevadas hab\u00edan hecho al grupo bajar al pueblo de Samagaun, aguardando una oportunidad. \u201cHay una cantidad enorme de nieve en la cascada y en las dos paredes, y no se aprecia ning\u00fan signo de avalanchas que hayan purgado de nieve la zona, lo que se traduce en un riesgo muy alto si subi\u00e9semos hasta all\u00ed.\u201d.&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/llegan-mas-nevadas-al-manaslu-invernal-y-tres-alpinistas-abandonan\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Sin opciones se quedan Stef Maginelle, Sofie Lenaerts, y Paula Strengell que regresan a casa viendo que llegan m\u00e1s nevadas&nbsp;<\/a>y la ruta en su incursi\u00f3n a los campos de altura est\u00e1 impracticable por el riesgo<em>&nbsp;(Desnivel)<\/em>. Oswald Rodrigo Pereira y el grupo de sherpas de&nbsp;<em>Seven Summit Treks<\/em>&nbsp;permanecen.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Aupa! Os dejo algunas fotos de estos \u00faltimos dias. Ma\u00f1ana parece que vuelve a nevar, as\u00ed que aqu\u00ed seguimos, en Samagaun, tranquilos, con nuestras rutinas y muy motivados \ud83e\udd70 <a href=\"https:\/\/t.co\/IErHAPdrSY\">pic.twitter.com\/IErHAPdrSY<\/a><\/p>&mdash; Alex Txikon (@AlexTxikon) <a href=\"https:\/\/twitter.com\/AlexTxikon\/status\/1483136560623194112?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">January 17, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Esta ma\u00f1ana hemos sobrevolado el CB de Manaslu y hemos sacado fotos que han permitido al equipo de Elur evaluar la situaci\u00f3n comparando las im\u00e1genes con las del 25 de diciembre y 5 de enero. Hay una cantidad enorme de nieve en la cascada y en las dos paredes, y no se aprecia\u2026\ud83d\udc47\ud83c\udffb <a href=\"https:\/\/t.co\/ecbOQ8O75Z\">pic.twitter.com\/ecbOQ8O75Z<\/a><\/p>&mdash; Alex Txikon (@AlexTxikon) <a href=\"https:\/\/twitter.com\/AlexTxikon\/status\/1482089661430484995?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">January 14, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y estamos de suerte los amantes de los audiovisuales; a los estrenos de pel\u00edculas como Free Solo, The Alpinist, 14 ochomiles, le sigue nuevos: nos llega&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11446\/trailer-torn-pelicula-alex-lowe?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">v\u00eda Barrabes<\/a>&nbsp;el&nbsp;<strong>trailer del documental TORN<\/strong>. Esta pel\u00edcula explora la historia intensamente personal del cineasta Max Lowe y su padre Alex, ambientada en la enorme sombra del Himalaya tibetano. \u201cAlex Lowe, ampliamente aclamado como el mejor alpinista de su generaci\u00f3n, era una figura imponente en el mundo de los deportes al aire libre. Pero lo era a\u00fan m\u00e1s para su hijo mayor, Max, que s\u00f3lo ten\u00eda 11 a\u00f1os en 1999 cuando Alex fue sepultado por una avalancha junto con el c\u00e1mara David Bridges mientras intentaba esquiar la cara norte del monte Shisha Pangma, en el Himalaya tibetano. Diecisiete a\u00f1os despu\u00e9s de su muerte, los cuerpos de Lowe y Bridges fueron encontrados por dos escaladores que intentaban la misma ruta, y en los meses siguientes, la familia de Lowe viaj\u00f3 a la remota monta\u00f1a para recuperarlos. En el nuevo documental&nbsp;<strong>TORN, poderoso y profundamente conmovedor, el director Max Lowe examina los sentimientos largamente enterrados que esto desenterr\u00f3 para \u00e9l y su familia<\/strong>, incluida su madre, Jennifer; sus hermanos menores, Sam e Isaac; y su padrastro, Conrad Anker, compa\u00f1ero de escalada y mejor amigo de Alex.\u201d<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Torn - Official Trailer\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/TIbdmSG1lSk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-12-enero-2022\">Mi\u00e9rcoles, 12 enero 2022<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>La expedici\u00f3n de Alex Txikon y Simone Moro al Manaslu invernal <\/strong>ha tenido contratiempos: una avalancha ha destruido parcialmente el campo base. La decisi\u00f3n de descender al pueblo de Samagaon tras una fuerte nevada les ha puesto a salvo. El CB del Manaslu se encuentra actualmente con 3 metros de nieve y un alto riesgo de avalancha en la monta\u00f1a. En un comunicado Simone Moro, dirigi\u00e9ndose al polaco Oswald Rodrigo Pereira y en extensi\u00f3n al resto del equipo, pone a la luz que tomar esta decisi\u00f3n gener\u00f3 controversias en el grupo. Pod\u00e9is ver el comunicado de Simone en el <a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11444\/avalancha-alcanza-campo-base-manaslu\" target=\"_blank\" rel=\"noreferrer noopener\">art\u00edculo de Barrabes<\/a>. Divergen las estrategias de ascensi\u00f3n en el Manaslu. Simone y Alex esperar\u00e1n unos d\u00edas para volver a la monta\u00f1a.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Seguimos muy pendientes de la meteorolog\u00eda en el Manaslu. Tenemos muchas ganas de volver all\u00ed, a reconstruir el CB y ponernos a trabajar en altura. \ud83e\udd70<\/p>&mdash; Alex Txikon (@AlexTxikon) <a href=\"https:\/\/twitter.com\/AlexTxikon\/status\/1480949381918601218?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">January 11, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Jost Kobusch avanza en su proyecto<\/strong>, ha superado la muralla rocosa que separa el glaciar del Klumbu del Lho La, donde comienza la arista oeste.&nbsp;<a href=\"https:\/\/explorersweb.com\/jost-kobusch-this-winter-everest-is-harder-icier-and-colder\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Ha descendido por el valle del Khumbu, pasando por su base habitual en Lobuche, hasta Pangboche<\/a>&nbsp;<em>(explorersweb)<\/em>. Recordemos que el alpinista alem\u00e1n tiene como objetivo&nbsp;<strong>subir en solitario el Everest invernal por la arista oeste<\/strong>&nbsp;y combinar las rutas yugoslava y americana. Un proyecto a tres a\u00f1os que tiene como punto cumbre el pr\u00f3ximo invierno. Este invierno deber\u00eda llegar a la base del Corredor Hornbein a 8.000 m. Recordemos que se encuentra<strong>&nbsp;literalmente solo<\/strong>, sin ning\u00fan apoyo, con su CB en una peque\u00f1a tienda que instala cada vez que se interna en la monta\u00f1a, accediendo desde una peque\u00f1a aldea a 3 horas, Lobuche. Su osado reto invernal al Everest en solitario&nbsp;<a href=\"https:\/\/explorersweb.com\/messner-still-not-impressed-by-jost-kobusch\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">no le est\u00e1 gustando mucho a Reinhold Messner<\/a>; en una entrevista al <em>Nepali Times <\/em>lo ha criticado, sin embargo mantiene su admiraci\u00f3n a los controvertidos 14 ochomiles de Nirma Purja.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>\u201cCero basura en la monta\u00f1a, sin campos instalados, sin ayuda externa, sin ox\u00edgeno y sin cuerdas fijas\u201d.<\/em>&nbsp;Estas son las palabras de Herve Barmasse, que junto a David G\u00f6ttler y Mike Arnold, se mantienen fieles a su estilo de alpinismo ligero. As\u00ed est\u00e1n&nbsp;<strong>intentando la primera invernal al Nanga Parbat por Rupal<\/strong>, la muralla m\u00e1s alta del mundo.&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/herve-barmasse-david-gottler-y-mike-arnold-se-pasan-a-la-schell-en-el-nanga-parbat-invernal\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Han ascendido 2.200 metros de desnivel (mitad de pared) pas\u00e1ndose a la ruta Schell dado el riesgo de otras rutas<\/a>&nbsp;<em>(Desnivel)<\/em>.<\/li>\n<\/ul>\n\n\n\n<p><em>\u201cLa caracter\u00edstica principal de una expedici\u00f3n es la espera del buen tiempo. En invierno a veces las cosas se complican. Desde que llegamos al campo base s\u00f3lo hemos tenido dos d\u00edas de sol sin viento, los \u00fanicos d\u00edas en los que pudimos subir y echar un vistazo a la ruta Schell.\u201d&nbsp;<\/em>\u2014<a href=\"https:\/\/www.instagram.com\/p\/CYbePLwpGE6\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Herve Barmasse<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-22-diciembre-2021\">Mi\u00e9rcoles, 22 diciembre 2021  <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comenzamos fuerte la secci\u00f3n, con la noticia del intento al mayor desnivel del mundo en invernal.<a href=\"https:\/\/www.desnivel.com\/expediciones\/david-gottler-herve-barmasse-mike-arnold-y-qudrat-ali-a-por-la-primera-invernal-del-nanga-parbat-por-el-rupal\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;G\u00f6ttler, Barmasse, Qudrat Ali y Arnold, a por la primera invernal por Rupal a Nanga Parbat<\/a>&nbsp;<em>(Desnivel)<\/em>. Una pared invernal que ya ha resistido 10 intentos anteriores. Ante tal reto, un equipo extraordinario, t\u00e9cnico, con algunos de los mejores en las artes del estilo alpino y con larga experiencia en Himalaya.<\/li>\n\n\n\n<li>Tambi\u00e9n os contamos que otras expediciones invernales en el Himalaya ya est\u00e1n moviendo ficha. El himalayista nepal\u00ed&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11422\/gelje-sherpa-cho-oyu-invernal?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Gelje Sherpa intentar\u00e1 el Cho Oyu invernal&nbsp;<\/a>por la cara nepalesa. Desde 2009 no se ha escalado esta cara sur. Por otro lado,&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/jost-kobusch-ya-esta-a-los-pies-del-everest-para-su-intento-invernal-en-solitario\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Jost Kobusch ya est\u00e1 a los pies del Everest para su intento invernal en solitario<\/a>. Su objetivo: alcanzar al menos los 8.000 metros, donde comienza el corredor Hornbein a la cima, que la dejar\u00eda para otro intento (<a href=\"https:\/\/mount-everest3d.com\/de\/jost-kobusch-himalaya-expedition-2021-2022\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">fases de su escalada<\/a>). Y para cerrar la secci\u00f3n invernal en el Himalaya, Alex Txikon nos cuenta que ya se encuentran en el Campamento Base del Manaslu ante d\u00edas duros de mucho \u201ccurro\u201d.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Ya estamos en el campo base. \ud83d\ude09Ma\u00f1ana nos espera un d\u00eda duro, de mucho curro. La experiencia nos ha ense\u00f1ado que el montaje del cb es clave para el \u00e9xito de una expedici\u00f3n.  El invierno pasado llegamos a cb mediados de enero y no recordamos haber pasado tanto fr\u00edo como hace hoy\ud83e\udd76 <a href=\"https:\/\/t.co\/mt13GwoxJF\">pic.twitter.com\/mt13GwoxJF<\/a><\/p>&mdash; Alex Txikon (@AlexTxikon) <a href=\"https:\/\/twitter.com\/AlexTxikon\/status\/1473374819395813377?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 21, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Os imagin\u00e1is&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11423\/video-helias-millerioux-pierre-hourticq?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">25 d\u00edas de alpinismo y descensos en esqu\u00eds por los Pirineos<\/a>&nbsp;<em>(Barrabes)<\/em>. Pierre Hourticq y Helias Millerioux han estado recorriendo la cordillera con rutas como al Pic du Midi D&#8217;Ossau, el Couloir de Gaube en el Vignemale, la cara norte del Taill\u00f3n, el Couloir Swan a los Astazus, entre&nbsp;otras. Todas ellas cl\u00e1sicas invernales de los Pirineos, que luego han descendido con sus esqu\u00eds. Junto con Victor De Le Rue descendieron el Coloir de Gaube, por el que fueron nominados a la \u201cl\u00ednea del a\u00f1o\u201d este 2021 en el&nbsp;<a href=\"https:\/\/www.mountainsonstage.com\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Mountains On Stage Film Festival<\/em><\/a>. Aqu\u00ed os dejamos el video de esa aventura:<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Freedom to Explore Ep.4 - SAUVATGE feat. Pierre Hourticq &amp; Helias Millerioux\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/EO6XqG5UaX4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-15-diciembre-2021\">Mi\u00e9rcoles, 15 diciembre 2021 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Manaslu invernal:<\/strong> <a href=\"https:\/\/www.desnivel.com\/expediciones\/una-segunda-expedicion-para-el-manaslu-invernal\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c1lex Txikon e I\u00f1aki \u00c1lvarez ya est\u00e1n en Katmand\u00fa&nbsp;para reunirse con Simone Moro<\/a> <em>(Desnivel)<\/em>, que lleva ya d\u00edas aclimatando. A esta expedici\u00f3n ya conocida, que vuelven despu\u00e9s del intento del a\u00f1o pasado, se suma una segunda expedici\u00f3n integrada por &nbsp;Oswald Rodrigo Pereira y la pareja belga Stef Maginelle y Sofie Lenaerts. Oswald Rodrigo particip\u00f3 el a\u00f1o pasado en el K2 invernal como c\u00e1mara y compa\u00f1ero de Magdalena Gorzkowska en su intento sin ox\u00edgeno.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Hace apenas 24h que hemos llegado a Katmand\u00fa y ya estamos currando a tope en la sede de Seven Summit para preparar todo. El viaje desde Madrid fue duro, mucho papeleo y mil ojos con el tema COVID. Pero ya estamos en Nepal, y tenemos muchas ganas de afrontar el reto del Manaslu! <a href=\"https:\/\/t.co\/poL5AkV7yd\">pic.twitter.com\/poL5AkV7yd<\/a><\/p>&mdash; Alex Txikon (@AlexTxikon) <a href=\"https:\/\/twitter.com\/AlexTxikon\/status\/1471084006821277702?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 15, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Estos d\u00edas&nbsp;se dieron a conocer<a href=\"https:\/\/www.salyroca.es\/articulo\/arte\/mejores-fotografias-deportes-aventura-2021\/20211208124055007047.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;las fotograf\u00edas premiadas en el&nbsp;<em>Red&nbsp;Bull Illume Image Quest 2021&nbsp;<\/em><\/a><em>(SalyRoca)<\/em>, el concurso anual que lleva haciendo Red Bull desde hace 6 a\u00f1os y que premia las mejores fotograf\u00edas de deportes extremos. Os pod\u00e9is pasar<a href=\"https:\/\/www.redbullillume.com\/stories?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;por su web<\/a>&nbsp;para echar un vistazo a las fotograf\u00edas ganadoras y conocer la historia que hay detr\u00e1s de cada una de ellas. Sin duda en muchas de ellas han tenido que estar en el momento y lugar, y ser muy \u201cr\u00e1pidos\u201d, como para sacar la fotograf\u00eda ganadora:<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">The overall winner of the 6th edition of Red Bull Illume is\ud83c\udfc6 Will Saunders \ud83c\udfc6 with this impaccable shot of athlete Jake Talley&#39;s a superhero whip in front of the unreal backdrop of Indian Creek, UT \ud83c\uddfa\ud83c\uddf8<br><br>The story behind the shot\ud83d\udc49<a href=\"https:\/\/t.co\/cS7ipfFYoI\">https:\/\/t.co\/cS7ipfFYoI<\/a><a href=\"https:\/\/twitter.com\/hashtag\/redbullillume?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#redbullillume<\/a> <a href=\"https:\/\/t.co\/pLadeRgOI8\">pic.twitter.com\/pLadeRgOI8<\/a><\/p>&mdash; Red Bull Illume (@redbullillume) <a href=\"https:\/\/twitter.com\/redbullillume\/status\/1467309209050128389?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 5, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00abUno de los momentos m\u00e1s legendarios de la historia de la escalada en Yosemite no se desarroll\u00f3 en las enormes paredes de granito de El Capit\u00e1n o Half Dome, sino en las orillas del lago Lower Merced Pass, un punto de agua bastante oscuro en lo alto del valle que hasta principios de 1977 casi nadie conoc\u00eda. Las cosas cambiaron dr\u00e1sticamente ese invierno cuando los escaladores del Campo 4 escucharon que un avi\u00f3n procedente de M\u00e9xico lleno de marihuana de alta calidad se hab\u00eda estrellado en el lago en diciembre de 1976\u00bb.&nbsp;\u00bfOs imagin\u00e1is a esos melenudos hippies con un avi\u00f3n lleno de marihuana? Sin duda las l\u00edneas en las paredes de granito se volvieron m\u00e1s creativas. <a href=\"https:\/\/www.planetmountain.com\/en\/news\/climbing\/video-the-legendary-yosemite-valley-drug-plane-crash.html\" target=\"_blank\" rel=\"noreferrer noopener\">Esta historia nos la comparten desde planetmountain.com<\/a>, con un extracto&nbsp;de la galardonada pel\u00edcula \u00ab<em>Valley Uprising<\/em>\u00ab, que documenta este legendario momento.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Yosemite Drug Plane Crash - Climbers Get Rich!\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/s5YGQjh7MyQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-8-diciembre-2021\">Mi\u00e9rcoles, 8 diciembre 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/montanasegura.com\/cartografia-ates-en-el-macizo-de-monte-perdido-ordesa\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">El macizo de Monte Perdido \u2013 Ordesa ya cuenta con cartograf\u00eda ATES<\/a>&nbsp;<em>(Monta\u00f1a Segura)<\/em>; una herramienta de planificaci\u00f3n en actividades invernales para escoger los itinerarios mas seguros. Adem\u00e1s de ATES en el macizo de Monte Perdido \u2013 Ordesa, existen en la actualidad otras cartograf\u00edas ATES desarrolladas por&nbsp;Monta\u00f1a Segura:&nbsp;<a href=\"https:\/\/montanasegura.com\/cartografia-ates-en-el-macizo-del-aneto\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">ATES en el macizo del Aneto<\/a>,&nbsp;<a href=\"https:\/\/montanasegura.com\/cartografia-ates-en-el-macizo-de-posets\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">ATES en el macizo de Posets \u2013 Perdiguero<\/a>&nbsp;y&nbsp;<a href=\"https:\/\/montanasegura.com\/cartografia-ates-en-el-macizo-de-infiernos\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">ATES en el macizo de Infiernos \u2013 Balaitus.<\/a><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/montanasegura.com\/ates\/MAPA_ATES_MontePerdido-Ordesa.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"469\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/12\/ates-monte-perdido-ordesa-1024x469.jpg\" alt=\"El macizo de Monte Perdido \u2013 Ordesa ya cuenta con cartograf\u00eda ATES \" class=\"wp-image-31064\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/12\/ates-monte-perdido-ordesa-1024x469.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/12\/ates-monte-perdido-ordesa-300x137.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/12\/ates-monte-perdido-ordesa-768x352.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/12\/ates-monte-perdido-ordesa-150x69.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/12\/ates-monte-perdido-ordesa-696x319.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/12\/ates-monte-perdido-ordesa-1068x489.jpg 1068w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/12\/ates-monte-perdido-ordesa-917x420.jpg 917w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/12\/ates-monte-perdido-ordesa-600x275.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/12\/ates-monte-perdido-ordesa.jpg 1384w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/montanasegura.com\/ates\/MAPA_ATES_MontePerdido-Ordesa.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">PINCHA en la imagen para acceder a la cartograf\u00eda en pdf. <\/a><\/figcaption><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.noticiasdenavarra.com\/deportes\/montaismo\/2021\/12\/04\/sebastian-alvaro-lugares-favoritos\/1207281.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Sebastian \u00c1lvaro, conocido por \u2018Al fino de lo Imposible\u2019, recibe el Premio WOP<\/a>-The Walk On Project 2021 del BBK Mendi Film Bilbao-Bizkaia a una vida profesional dedicada a defender y transmitir los valores del alpinismo&nbsp;<em>(Noticias)<\/em>. \u201cEstamos en el estadio de la banalizaci\u00f3n de las cumbres \u2014coment\u00f3 Sebastian\u2014 Primero fue la masificaci\u00f3n, luego alguien se dio cuenta de que eso pod\u00eda ser rentable y pas\u00f3 a la comercializaci\u00f3n.\u201d<\/li>\n\n\n\n<li>Y cerramos la secci\u00f3n con el trailer del documental<a href=\"https:\/\/www.eldiario.es\/euskadi\/blogs\/piedra-de-toque\/mendiak-1976-documental-grupo-navarros-abrio-camino-grandes-cimas-mundo_132_8532332.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"> \u2018Mendiak 1976\u2019, dirigida por el cineasta y escalador Luis Arrieta, que se ha estrenado en el BBK Mendi Film Festival Bilbao<\/a>&nbsp;<em>(Piedra de Toque)<\/em>. Y con la historia de la aventura de un grupo de navarros que abri\u00f3 el camino a las grandes cumbres del mundo. El documental recrea la primera ascensi\u00f3n navarra a un 7 mil y el rescate posterior. El estreno ha reunido a los monta\u00f1eros supervivientes de esa expedici\u00f3n y los integrantes de la expedici\u00f3n polaca que les ayud\u00f3.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/646202284?h=64449435e8&amp;dnt=1&amp;app_id=122963\" width=\"720\" height=\"405\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-1-diciembre-2021\">Mi\u00e9rcoles, 1 diciembre 2021             <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.desnivel.com\/cultura\/briancon-celebra-los-30-anos-del-piolet-dor-con-silvia-vidal-de-protagonista\/\" target=\"_blank\" rel=\"noreferrer noopener\">Brian\u00e7on ha celebrado los 30 a\u00f1os del Piolet d\u2019Or&nbsp;<\/a><em>(Desnivel)<\/em>, en los que se ha reflexionado sobre las tres d\u00e9cada y su futuro. <a href=\"https:\/\/elpais.com\/deportes\/el-montanista\/2021-11-30\/silvia-vidal-hito-en-el-alpinismo-espanol.html\" target=\"_blank\" rel=\"noreferrer noopener\">Silvia Vidal<\/a> se llev\u00f3 un reconocimiento especial; Yasushi Yamanoi fue homenajeado por su carrera alpin\u00edstica; Los premios principales fueron recogidos por: Symon Welfringer y Pierrick Fine por su nueva ruta en el Sani Pakkush (6.952m, Himalaya Paquistan\u00ed) y Uisdean Hawthorn y Ethan Berman por la apertura en el Mt. Robson (3.954m, Rocosas Canadienses). Una edici\u00f3n que dio importancia a las actividades en menor altura, sin olvidar su compromiso y exposici\u00f3n.<\/li>\n\n\n\n<li>Y han sido los Piolet d&#8217;Or los que han suscitado uno de los debates de la semana dentro de la comunidad de alpinistas y escaladores. Esto al hilo de un art\u00edculo publicado en el <em>The New York Times<\/em>, \u00ab<a href=\"https:\/\/www.nytimes.com\/2021\/11\/29\/sports\/piolet-dor-climbing.html\" target=\"_blank\" rel=\"noreferrer noopener\"><em>A Climbing Award That May Be a Winner\u2019s Last&nbsp;<\/em><\/a>(Un premio de escalada que puede ser el \u00faltimo del ganador)\u00bb. \u00bfEl premio anual tienta a los alpinistas a correr riesgos mortales en la alta monta\u00f1a? El Times se puso en contacto con algunos de los nombres m\u00e1s importantes del alpinismo para conocer sus puntos de vista, entre ellos el franc\u00e9s Symon Welfringer, el argentino Rolando Garibotti e incluso a Reinhold Messner, que acept\u00f3 el premio Piolet d&#8217;Or en 2010. \u00abSiempre he estado en contra de la idea de que la escalada tradicional sea una competici\u00f3n\u00bb, dijo Messner a <em>The Times<\/em>. \u00abEn general, no estoy a favor de las medallas en absoluto. El premio a toda una vida es una cuesti\u00f3n de respeto\u00bb. Opiniones para todos los gustos en la comunidad alpinista.<\/li>\n\n\n\n<li><a href=\"https:\/\/twitter.com\/kilianj\/status\/1465725783318609921\" target=\"_blank\" rel=\"noreferrer noopener\">Kilian Jornet deja la marca Salomon tras 18 a\u00f1os para empezar un proyecto personal<\/a>. \u00abHa sido un viaje loco que termina a fines de 2021. No se trata de ir a otra marca existente sino de comenzar un nuevo proyecto del que les contar\u00e9 muy pronto.\u00bb<\/li>\n\n\n\n<li>Y para cerrar os hablamos de la Pel\u00edcula \u00abLos 14 ochomiles: No hay nada imposible\u00bb que sigue al nepal\u00ed Nimsdai Purja&nbsp;en su proyecto 14&#215;8000. Ha suscitado el debate (por comparaci\u00f3n) por lo comercial del proyecto, la falta de estilo en las ascensiones y los medios utilizados. Os animo a leer el hilo que nos comparte <a href=\"https:\/\/twitter.com\/KrisAnnapurna\" target=\"_blank\" rel=\"noreferrer noopener\">@KrisAnnapurna<\/a> en Twitter con la traducci\u00f3n de un art\u00edculo del periodista Lasszlo Pinter (<a href=\"https:\/\/twitter.com\/KrisAnnapurna\/status\/1465685182078455822\" target=\"_blank\" rel=\"noreferrer noopener\">AQU\u00cd HILO DE TWITTER<\/a>) .<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Hay un abismo entre el turismo de ochomiles superficial de Nims y el alpinismo de Messner o Kukuczka en sus 14 ochomiles.<\/p>&mdash; Mauricio Purto (@DoctorPurto) <a href=\"https:\/\/twitter.com\/DoctorPurto\/status\/1465789418137178122?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">November 30, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"14 Peaks: Nothing Is Impossible | Official Trailer | Netflix\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/8QH5hBOoz08?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-24-noviembre-2021\">Mi\u00e9rcoles, 24 noviembre 2021            <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Os contamos que la sociedad de ciencias Aranzadi ha lanzado la web \u201c<a href=\"https:\/\/www.calzadaromanadelpirineo.eus\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Calzada Romana del Pirineo<\/a>\u201d d\u00f3nde hace p\u00fablica las investigaciones y prospecciones que han realizado desde el 2008 en el norte de Navarra sobre caminos antiguos y especialmente encaminados a encontrar las calzadas del periodo romano. Y para el que quiera aventurarse por estos itinerarios, se ha&nbsp;<a href=\"https:\/\/www.calzadaromanadelpirineo.eus\/recorre-el-sendero\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">se\u00f1alizado un sendero con marcas de color morado y blanco<\/a>, recorriendo Artzibar\/Valle de Arce de norte a sur.<\/li>\n\n\n\n<li>\u00bfD\u00f3nde encuentras una fisura horizontal de 750m y 8a+\u2026? Eso se debieron preguntar&nbsp;<a href=\"https:\/\/www.desnivel.com\/escalada-roca\/tom-randall-y-pete-whittaker-abren-una-fisura-horizontal-de-750-m-y-8a-bajo-un-puente\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">los brit\u00e1nicos Tom Randall y Pete Whittaker antes de encontrarla bajo un puente<\/a>&nbsp;<em>(Desnivel)<\/em>, uno de los m\u00e1s largos de la autopista M5 en el condado de Devon. Han abierto as\u00ed \u2018<em>The Great Rift<\/em>\u2019, para lo que han necesitado sesenta largos de escalada urbana. Tom Randall y Pete Whitakker&nbsp;forman una cordada de fan\u00e1ticos de las fisuras que han cambiado en esta ocasi\u00f3n pand\u00e9mica el desierto de Utah por los puentes de al lado de casa. Por cierto, todo captado por las c\u00e1maras de Reel Rock, que estrenar\u00e1 el video el pr\u00f3ximo marzo.<\/li>\n\n\n\n<li>Las expediciones invernales calentando motores, se empiezan a conocer m\u00e1s proyectos. Semanas pasadas habl\u00e1bamos del proyecto de Jost Kobusch de invernal solitario en el Everest y de \u00c1lex Txikon y Simone Moro hacia el Manaslu. Adem\u00e1s,&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/jost-kobusch-viaja-ya-a-nepal-para-su-everest-invernal\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">la taiwanesa Grace Tseng intentar\u00e1 el K2 y una expedici\u00f3n estadounidense busca el Nanga Parba<\/a>t&nbsp;<em>(Desnivel)<\/em>.<\/li>\n\n\n\n<li>\u00daltimamente Kilian Jornet est\u00e1 siendo muy medi\u00e1tico (m\u00e1s si cabe). En esta ocasi\u00f3n reflexiona sobre su influencia en los deportes de monta\u00f1a. \u201cEscalar el Everest por su ruta normal no es alpinismo\u201d, sentencia Kilian.&nbsp;<a href=\"https:\/\/elpais.com\/deportes\/el-montanista\/2021-11-18\/kilian-jornet-escalar-el-everest-por-su-ruta-normal-no-es-alpinismo.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Esta completa entrevista de El Pa\u00eds&nbsp;<\/a>nos acerca m\u00e1s a su discurso y manera de entender la monta\u00f1a.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-17-noviembre-2021\">Mi\u00e9rcoles, 17 noviembre 2021           <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Abrimos la secci\u00f3n con el&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/zdenek-hak-y-kuba-kacha-repiten-la-american-direct-al-ama-dablam-en-estilo-alpino\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Ama Dablam (6.814 m)&nbsp;y la ruta que los checos Zdenek H\u00e1k y Kuba K\u00e1cha abren en la cara oeste en estilo alpino<\/a>&nbsp;<em>(Desnivel)<\/em>, una variante a la&nbsp;<em>American Direct&nbsp;<\/em>de&nbsp;Chris Warner y Glenn Dunmire, que conecta con la ruta Smid en la parte final. 3 d\u00edas y 2 vivacs para completar la que han han llamado&nbsp;<em>Lan\u010dm\u00edt Direct<\/em>&nbsp;(1.500 m, TD+\/ED-), la l\u00ednea m\u00e1s directa a la cima. El Himalaya de Nepal est\u00e1 siendo escenario de grandes apuestas por el alpinismo m\u00e1s t\u00e9cnico.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.revistaoxigeno.es\/deportes\/nueva-apertura-en-pared-sur-chekigo-6257m-alpinistas-equipo-femenino-alpin_246136_102.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">El Equipo Femenino de Alpinismo de la FEDME abre una nueva v\u00eda en la pared sur del Chekigo (6.257m), Valle del Rolwaling nepal\u00ed&nbsp;<\/a><em>(Ox\u00edgeno)<\/em>. Tras 22h de actividad, dejaban abierto un nuevo itinerario (1.000m, MD) en la cara sur del Chekigo (6.257m) hasta la arista cimera.<\/li>\n\n\n\n<li>Y nos despedimos con esta gran aventura de<a href=\"https:\/\/www.youtube.com\/channel\/UC0zAX6PQUKro_p8GwdFYjmg?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;Peter Baumeister<\/a>: \u201c<a href=\"https:\/\/www.youtube.com\/watch?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter&amp;v=_lbiKXdNY-w\" target=\"_blank\" rel=\"noreferrer noopener\">Camino a Lisboa&nbsp;<\/a>&#8211; un viaje en bicicleta por los Alpes, los Pirineos y los Picos de Europa\u201d (<a href=\"https:\/\/www.komoot.de\/collection\/1343756\/-road-to-lisbon-live?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed la ruta<\/a>). Ahora Peter acaba de cruzar los Pirineos. \u201cCruzar los Pirineos en noviembre seguramente fue uno de los desaf\u00edos m\u00e1s dif\u00edciles que he asumido (\u2026) Creo que en ning\u00fan otro lugar de Europa occidental se puede encontrar tanta belleza natural y salvaje como aqu\u00ed\u201d. Todo inmortalizado en un precioso video que os compartimos.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Road to Lisbon - Episode 3: bikepacking across the Pyrenees - wildest experience of my life\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/4XTI-bktkYQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-10-noviembre-2021\">Mi\u00e9rcoles, 10 noviembre 2021          <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.europapress.es\/deportes\/olimpiadas-00169\/noticia-kilian-jornet-contra-pirineos-barcelona-2030-modelo-socio-economico-falta-nieve-20211110124500.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Kilian Jornet encabeza la plataforma Stop JJOO, en contra de Pirineos-Barcelona 2030 por su modelo socio-econ\u00f3mico y la falta de nieve&nbsp;<\/a><em>(Europapress)<\/em>. \u201cNo creo que sean lo que necesita ahora el Pirineo\u201d, dice Kilian. Los firmantes del manifiesto de la plataforma exponen que es insostenible en plena emergencia clim\u00e1tica y que acentuar\u00eda la dependencia tur\u00edstica del Pirineo.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/tom-livingstone-y-matt-glenn-escalan-el-pilar-noreste-del-tengkangpoche\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">La cordada brit\u00e1nica formada por Tom Livingstone y Matt Glenn escalan el Pilar Noreste del Tengkangpoche&nbsp;<\/a><em>(Desnivel)<\/em>. Una ascensi\u00f3n de siete d\u00edas en pared para conseguir uno de los desaf\u00edos pendientes para el himalayismo de Nepal. Muchas cordadas han intentado marcar la primera ruta al pilar durante los \u00faltimos veinte a\u00f1os. \u201cLa dura escalada mixta, el dif\u00edcil artificial (puaj) y una larga arista de nieve fueron un gran desaf\u00edo\u201d.&nbsp;<a href=\"https:\/\/www.adventure-journal.com\/2021\/11\/what-are-the-ethics-of-using-someone-elses-gear-cache-to-make-first-ascent\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Gran proeza, pero hay un pero<\/a>&nbsp;<em>(Adventure-Journal)<\/em>. La pol\u00e9mica que ha suscitado el que utilizaran la informaci\u00f3n proporcionada por Quentin Roberts y un almac\u00e9n de comida y equipo que dej\u00f3 en la ruta Roberts, que hab\u00eda hecho dos intentos infructuosos en el pico en las \u00faltimas temporadas. El intento m\u00e1s reciente lo rechaz\u00f3 cerca de la cumbre, y Roberts y su compa\u00f1ero Jesse Huey dejaron el equipamiento para su siguiente intento. Una gran discusi\u00f3n sobre \u00e9tica en las escaladas y l\u00edneas rojas.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/nikita-balabanov-mikhail-fomin-y-viacheslav-polezhaiko-abren-la-arista-sureste-del-annapurna-iii\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Los ucranianos Nikita Balabanov, Viacheslav Polezhaiko y Mikhail Fomin abren la arista sureste del Annapurna III<\/a>&nbsp;(7555m)&nbsp;<em>(Desnivel)<\/em>. Ruta codiciada a esta cima secundaria del macizo de los Anapurnas, que se manten\u00eda virgen, despu\u00e9s de ser intentada por primera vez en 1981. Pod\u00e9is haceros una idea de qu\u00e9 se encontraron los ucranianos, en el siguiente documental, en el que David Lama, Hansj\u00f6rg Auer y Alex Bl\u00fcmel contaban su intento del 2016.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Annapurna III \u2013 Unclimbed\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/zp72WjMVhTQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y para cerrar os dejamos otra pel\u00edcula, para amantes de la escalada y de los Galayos, que nos llega v\u00eda Desnivel. \u201cEn la primavera, en las agujas de los Galayos, el escalador Samuel G\u00f3mez intenta liberar una de las \u00faltimas v\u00edas que le quedan por escalar en libre: \u00abAl rot Bridwell\u201d 6b+\/A3+. Abierta en la impactante pared de la Pe\u00f1a del \u00c1guila en el a\u00f1o 1988 por Josechu Jimeno y P\u00e9rez. Una desafiante escalada de 120 mts de recorrido.\u201c.&nbsp;<a href=\"https:\/\/www.youtube.com\/watch?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter&amp;v=2TvI5NQ4McY\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>\u00abAl rot Bridwell\u201d&nbsp;Pe\u00f1a del \u00c1guila. Galayos.<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"&quot;Al rot Bridwell&quot;  Pe\u00f1a del \u00c1guila. Galayos.\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/2TvI5NQ4McY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-03-noviembre-2021\"> Mi\u00e9rcoles, 03 noviembre 2021         <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En solitario, sin ox\u00edgeno y sin apoyos, <a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11380\/jost-kobusch-vuelta-everest-invernal\" target=\"_blank\" rel=\"noreferrer noopener\">Jost Kobusch de vuelta al Everest invernal&nbsp;<\/a><em>(Barrabes)<\/em>. En 2019 consigui\u00f3 llegar aproximadamente hasta unos 7400m de altitud. Vuelve a elegir la ruta de la arista oeste&nbsp;y el corredor <em>Hornbein<\/em>. Para acceder a la arista tiene que salvar el collado <em>Llo La<\/em>, una antiguo paso comercial entre Nepal y T\u00edbet, que el retroceso glaciar ha convertido en una muralla de roca con secciones t\u00e9cnicas, que Jost tendr\u00e1 que salvar como inicio a su desaf\u00edo. Lo har\u00e1 colocando cuerdas fijas, el resto de la escalada ser\u00e1 en estilo alpino. Su objetivo: llegar a 8000m donde comienza el corredor <a href=\"https:\/\/www.barrabes.com\/blog\/reportajes\/2-10999\/video-tom-hornbein-1963-apertura\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Hornbein&nbsp;<\/em><\/a>y ver sus condiciones en invierno para el asalto final.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/nejc-marcic-y-luka-strazar-ascienden-la-cara-oeste-del-chobutse\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nejc Marcic y Luka Strazar ascienden la cara oeste del Chobutse<\/a> (6686m) <em>(Desnivel)<\/em>. Tres d\u00edas de escalada en estilo alpino para estos dos \u00ab<em>Piolets d&#8217;Or\u00bb<\/em> (dos de Luka Strazar y uno de Nejc Marcic); os pod\u00e9is hacer una idea del desaf\u00edo de la empresa. Esta misma cara oeste fue ascendida<a href=\"https:\/\/www.desnivel.com\/expediciones\/mingma-gyalje-sherpa-escala-en-solitario-la-virgen-cara-oeste-del-chobutse\/\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;en solitario por Mingma G<\/a>. en el oto\u00f1o de 2015.<\/li>\n\n\n\n<li>Cambiando ahora de registro, os compartimos este art\u00edculo de <em>elDiario <\/em>sobre las <a href=\"https:\/\/www.eldiario.es\/aragon\/navatas-rio-camino-no-frontera-viaje-madera-pirineo-desembocadura-ebro_1_8442708.html\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Navatas<\/em>, en su viaje del Pirineo a la desembocadura del Ebro<\/a>. Las <em>navatas <\/em>en Arag\u00f3n, las <em>almad\u00edas <\/em>en Navarra y <em>rai <\/em>en el Pirineo Catal\u00e1n. \u00abTalar los bosques, desemboscar la madera sacando el \u00e1rbol, lanzar los troncos sueltos y manejarlos por todo el recorrido hasta llegar a los<em>&nbsp;ligaderos<\/em>&nbsp;donde poder ligar los troncos y construir las <em>navatas <\/em>(plataformas de troncos atados)\u00bb. Todo ello de manera previa a un viaje en la aventura que es descender r\u00edo abajo.<\/li>\n\n\n\n<li>Y ya para cerrar, esta historia peculiar por si quieres la mejor vista del skyline de Nueva York: <a href=\"https:\/\/www.elconfidencial.com\/alma-corazon-vida\/2021-10-28\/escalada-exterior-edificio-mas-alta_3313328\/\" target=\"_blank\" rel=\"noreferrer noopener\">Se ofrece la escalada m\u00e1s alta del planeta en el exterior de un rascacielos<\/a> <em>(el Confidencial)<\/em>. 161 escalones con una inclinaci\u00f3n de 45 grados hasta la punta del rascacielos <em>30 Hudson Yards<\/em>, de 395 metros de altura, emplazado en el coraz\u00f3n de la ciudad estadounidense.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-27-octubre-2021\"> Mi\u00e9rcoles, 27 octubre 2021        <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11372\/simon-messner-martin-sieberer-repiten?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Simon Messner, el hijo de la gran leyenda del himalayismo, escala junto con Martin Sieberer la Bonatti a la N del Matterhorn en el d\u00eda&nbsp;<\/a><em>(Barrabes)<\/em>. \u201cPara ambos, un sue\u00f1o largamente acariciado se ha hecho realidad\u201d, comentaba en las redes. \u201cLo que queda es un gran respeto por Walter Bonatti, que abri\u00f3 esta fant\u00e1stica ruta en 1965 en solitario y en invierno durante varios d\u00edas\u201d. Cada vez que alguien escala esta m\u00edtica ruta, es noticia en el mundo del alpinismo, por lo que signific\u00f3: con esta ruta Bonatti se retiro y fue un salto cualitativo en el alpinismo.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/mikel-zabalza-iker-madoz-y-mikel-inoriza-hacen-cumbre-en-el-dorje-lhakpa\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Mikel Zabalza, Iker Madoz y Mikel Inoriza abren una nueva ruta en estilo alpino en la cara sur del Dorje Lhakpa (6.966&nbsp;m) en el Himalaya de Nepal&nbsp;<\/a><em>(Desnivel)<\/em>. La actividad se enmarca dentro de la expedici\u00f3n del EEA del que Zabalza es Director. Primera ruta en esta cara, para una monta\u00f1a que Mikel Zabalza ya hab\u00eda intentado en el pasado junto a Ferm\u00edn Izco.<\/li>\n\n\n\n<li>El pasado verano de 2020, en bicicleta y en s\u00f3lo dos semanas, los escaladores belgas Nico Favresse y Seb Berthe escalaron la famosa Trilog\u00eda Alpina (compuesta por tres rutas hist\u00f3ricas de varios largos 8b+: End of Silence de Huber, Des Kaisers neue Kleider por Stefan Glowacz en el macizo de Wilder Kaiser en Austria y Silbergeier en el R\u00e4tikon de Suiza por Beat Kammerlander). A este viaje les acompa\u00f1aron sus perros Koux y Bintche. Este hilarante trailer nos llega&nbsp;<a href=\"https:\/\/www.desnivel.com\/escalada-roca\/escalada-roca-galeria-multimedia\/videoclip-hilarante-de-la-trilogia-alpina-en-bicis-y-con-perros-de-nico-favresse-y-seb-berthe\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">v\u00eda&nbsp;<em>Desnivel<\/em><\/a>, os dejamos aqu\u00ed el video:&nbsp;<em>Alpine Trilogy \u201cDoggystyle\u201d<\/em>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Alpine Trilogy \u201cDoggystyle\u201d - Des p\u00e9dales, nos boules de poils\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/OR681DvgFr0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y cerramos la secci\u00f3n con lo que se ha convertido en toda una epidemia:&nbsp;<a href=\"https:\/\/www.rtve.es\/play\/videos\/telediario\/persona-muere-cada-13-dias-selfie\/6158262\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Una persona muere cada 13 d\u00edas por hacerse un \u2018selfie\u2019&nbsp;<\/a><em>(RTVE)<\/em>, seg\u00fan un reciente estudio. Puede ser la punta del iceberg de un problema emergente de salud p\u00fablica. \u201cLas redes sociales premian los contenidos m\u00e1s extremos\u00bb, comenta Liliana Arroyo, autora del libro \u201cT\u00fa no eres tu selfi: 9 secretos digitales que todo el mundo vive y nadie cuenta\u201d.&nbsp;<a href=\"https:\/\/elpais.com\/sociedad\/2021-10-26\/los-selfis-mortales-bajo-la-lupa-de-los-epidemiologos.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Los selfis mortales, bajo la lupa de los epidemi\u00f3logos<\/a>&nbsp;<em>(El Pa\u00eds)<\/em>.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-20-octubre-2021\">Mi\u00e9rcoles, 20 octubre 2021       <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Abrimos la secci\u00f3n con la aventura de Mike Coppock en la Alta Ruta Pirenaica<a href=\"https:\/\/travesiapirenaica.com\/arp\/arp.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">:&nbsp;<\/a><a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11363\/mike-coppock-alta-ruta-pirenaica?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">12 d\u00edas, 750km y 40.000m de desnivel positivo<\/a>&nbsp;<em>(Barrabes)<\/em>, lo que representa el mejor tiempo de la ruta. La realiz\u00f3 en autosuficiencia, cargando con la comida para los 4 d\u00edas siguientes y parando en los pueblos a reabastecerse. Os dejo aqu\u00ed informaci\u00f3n sobre la&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/arp\/arp.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Alta Ruta Pirenaica<\/a>.<\/li>\n\n\n\n<li>Nueva&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/benjamin-vedrines-y-charles-dubouloz-abren-una-nueva-ruta-en-la-cara-norte-del-chamlang\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">ruta en la cara norte del Chamlang de la mano de los alpinistas franceses Benjamin V\u00e9drines y Charles Dubouloz&nbsp;<\/a>(Desnivel). Itinerario de 1600m de desnivel para la primera ascensi\u00f3n de la cara norte, posteriormente descendieron por la arista oeste. Una actividad con may\u00fasculas que sin duda se dejar\u00e1 o\u00edr para los Piolet d&#8217;Or del pr\u00f3ximo a\u00f1o. Chamlang&nbsp;(7.319 m) atesora algunos de los desaf\u00edos para el himalayismo moderno como es la traves\u00eda de las tres cimas.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.revistaoxigeno.es\/podcast-oxigeno\/alex-txikon-hombre-hielo-metodo-extremo_244286_102.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Alex Txikon se prepara junto con Wim Hof, el \u201cHombre de Hielo\u201d, para su nuevo intento del Manaslu<\/a>&nbsp;<em>(Revista Ox\u00edgeno)<\/em>. El recordman Wim Hof adem\u00e1s de coleccionar r\u00e9cords como permanecer 112 minutos en un contenedor cubierto de hielo, ha desarrollado un&nbsp;<a href=\"https:\/\/www.wimhofmethod.com\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">m\u00e9todo de entrenamiento<\/a>&nbsp;para poder sobrevivir a temperaturas extremadamente bajas controlando entre otras cosas la respiraci\u00f3n. Te habl\u00e1bamos de todo ellos en uno de los&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/maldita-montana-2-un-mundo-congelado-senderismo-en-el-turismo-sostenible-wim-hof\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">primeros episodios de \u2018Maldita Monta\u00f1a\u2019<\/a>.<\/li>\n\n\n\n<li>Y nos despedimos con esta historia:&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11369\/descubiertos-glaciar-unos-esquis-fijaciones?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Descubiertos en un glaciar unos esqu\u00eds con fijaciones de 1.300 a\u00f1os de antig\u00fcedad&nbsp;<\/a><em>(Barrabes)<\/em>. Ya sab\u00e9is que el retroceso de los glaciares est\u00e1n descubriendo muchos restos. En este caso unas tablas de esqu\u00ed de la \u00e9poca previkinga. Lo llamativo tambi\u00e9n es que ya contaban con unas fijaciones: unos aros de abedul donde se introduc\u00eda el pie y unas tiras de cuero.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-13-octubre-2021\"> Mi\u00e9rcoles, 13 octubre 2021      <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.desnivel.com\/cultura\/piolets-dor-2021-para-mt-robson-y-sani-pakkush\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Dos grandes aperturas comparten premio en los Piolets d&#8217;Or 2021<\/a>&nbsp;<em>(Desnivel)&nbsp;<\/em>en el a\u00f1o marcado por las restricciones del&nbsp;<em>Covid<\/em>. Symon Welfringer y Pierrick Fine en la cara sur del<strong>&nbsp;Sani Pakkush<\/strong>&nbsp;(6.952m), un seismil del Karak\u00f3rum paksitan\u00ed, y la de Uisdean Hawthorn y Ethan Berman en la<strong>&nbsp;Emperor Face&nbsp;<\/strong>del Mt. Robson (3.954m) en las Rocosas Canadienses. La edici\u00f3n homenajea con&nbsp;<a href=\"https:\/\/www.desnivel.com\/cultura\/reconocimiento-especial-de-los-piolets-dor-a-silvia-vidal\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">reconocimiento especial a la alpinista catalana S\u00edlvia Vidal&nbsp;<\/a>por su contribuci\u00f3n al<em>&nbsp;big wall&nbsp;<\/em>en solitario.<\/li>\n\n\n\n<li>Si no has visto las im\u00e1genes de&nbsp;<a href=\"https:\/\/www.eitb.eus\/es\/deportes\/otrosdeportes\/videos\/detalle\/8378079\/video-rustam-nabiev-hombre-que-subio-8000-sin-piernas\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Rustam, sin piernas ascendiendo a un 8.000<\/a>&nbsp;<em>(eitb)<\/em>, te lo contamos.&nbsp;<a href=\"https:\/\/www.turiski.es\/rustam-nabiev-asciende-manaslu-primer-alpinista-sin-piernas-en-subir-8000-mil\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">El ruso Rustam Nabiev se convierte en el primer alpinista sin piernas en ascender a un ocho mil<\/a>&nbsp;<em>(Turiski)&nbsp;<\/em>con su escalada al Manaslu (8.163m). A diferencia de otros monta\u00f1eros amputados de ambas piernas, Nabiev no utiliza pr\u00f3tesis en sus ascensiones, por lo que utiliza una t\u00e9cnica en la que se mueve gracias a sus manos; camina con sus manos. La ascensi\u00f3n la realiz\u00f3 el pasado 2 de octubre junto con dos compa\u00f1eros y cinco sherpas. Ejemplo de superaci\u00f3n, sin duda.<\/li>\n\n\n\n<li>Si eres amante de la furgoneta o de la autocaravana, ya ser\u00e1s consciente del&nbsp;<a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/huesca\/2021\/10\/12\/los-ayuntamientos-del-pirineo-acotan-la-presencia-de-autocaravanas-en-las-calles-a-la-espera-de-la-ley-autonomica-1525771.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">aumento de las restricciones en los ayuntamientos del Pirineo<\/a>&nbsp;<em>(Heraldo)<\/em>. Ayuntamientos como Jaca o Sallent de G\u00e1llego modifican las ordenanzas para que no puedas aparcar m\u00e1s que en las zonas autorizadas. Benasque habilita otro parking, mientras otros municipios esperan a la nueva ley auton\u00f3mica.<\/li>\n\n\n\n<li>Para despedirnos os dejamos este documental que nos llega v\u00eda la&nbsp;<a href=\"https:\/\/www.revistaoxigeno.es\/deportes\/desmond-totem-linea-mitica-con-nueva-mirada_243614_102.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Revista Ox\u00edgeno<\/a>. Javi Guzm\u00e1n escala la v\u00eda \u201cDesmond Tutu\u201d en Patones, en estilo limpio de autoprotecci\u00f3n por primera vez. Roca blanda que se rompe,&nbsp;<em>friends&nbsp;<\/em>que saltan, vuelos inesperados\u2026Un dif\u00edcil y arriesgado reto solo a la altura de unos pocos.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"DESMOND TOTEM\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/CTremiHTOic?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-06-octubre-2021\">Mi\u00e9rcoles, 06 octubre 2021     <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.turiski.es\/bano-multitudes-victoria-kilian-jornet-ultra-pirineu-2021\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Kilian Jornet sum\u00f3 su tercera Ultra Pirineo, tras las de los a\u00f1os 2012 y 2015, ba\u00f1o de multitudes y victoria<\/a>&nbsp;(Turiski). Kilian Jornet reina de nuevo en estas monta\u00f1as que conoce como su palma de la mano, ya que es donde creci\u00f3 y se hizo atleta de&nbsp;<em>trail<\/em>. 100k, 6.600m de desnivel y 1200 atletas para la edici\u00f3n del 2021.<\/li>\n\n\n\n<li>La semana pasada, te adelant\u00e1bamos en las noticias de&nbsp;<a href=\"https:\/\/open.spotify.com\/episode\/53wmjOa3wt0Xuk7KM4tyPh?dl_branch=1&amp;si=eNOByVYGR3mSae6E7eFiGw&amp;utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u2018Maldita Monta\u00f1a\u2019<\/a>&nbsp;que Carlos Soria se retiraba del Dhaulagiri debido a las condiciones en la monta\u00f1a, con nieve muy h\u00fameda que le hac\u00edan impracticable el intento de cima y le obligaban a tomar est\u00e1 decisi\u00f3n.&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/expediciones-alpinistas\/carlos-soria-voy-al-dhaulagiri-a-subir-pero-no-me-tiro-de-los-pelos-si-no-lo-consigo-2\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u00abVoy al Dhaulagiri a subir, pero no me tiro de los pelos si no lo consigo\u00bb<\/a>, Carlos Soria&nbsp;<em>(Desnivel)<\/em>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Hoy os tenemos que dar una triste noticia desde el campo base del Dhaulagiri\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/BBM4SAI-vyc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La alpinista y esquiadora polaca&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/anna-tybor-completa-el-primer-descenso-femenino-en-esquis-del-manaslu-2\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Anna Tybor se ha convertido en la primera mujer en descender esquiando el Manaslu<\/a>&nbsp;<em>(Desnivel)<\/em>. Junto con sus compa\u00f1eros de expedici\u00f3n los gu\u00edas UIAGM italianos Marco Majori y Federico Secchi hicieron cima el d\u00eda 29 ascendiendo sin ox\u00edgeno y lleg\u00f3 de vuelta al campamento base el d\u00eda 30 tras pasar noche en el C4.<\/li>\n\n\n\n<li>Y nos despedimos comparti\u00e9ndoos el v\u00eddeo-<em>trailer <\/em>de la BBC:&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11358\/video_trailer-tom-ballard-historia-madre?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Tom Ballard,&nbsp;<em>The Last Mountain<\/em><\/a>, que nos llega v\u00eda el blog de Barrabes. Alison Hargreaves fue la primera mujer en ascender en solitario las 6 caras nortes de los Alpes y el Everest en solitario y sin ox\u00edgeno, una de las mejores alpinistas de todos los tiempos. Alison falleci\u00f3 en el K2 cuando su hijo Tom Ballard ten\u00eda 6 a\u00f1os. 24 a\u00f1os despu\u00e9s Tom fallece en el Nanga Parbat, sigui\u00f3 los pasos de su madre hasta el final: con 26 a\u00f1os repiti\u00f3 las 6 caras N alpinas en solitario de su madre en una misma temporada y en invierno. En 2019, a los 30, se uni\u00f3 a Daniele Nardi para intentar el ascenso invernal del Nanga Parbat, finalizando esa vida tan paralela a la de su madre.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"The story of Tom Ballard who disappeared on Nanga Parbat in 2019 | The Last Mountain - BBC\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/9txakl1RnVQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-29-septiembre-2021\">  Mi\u00e9rcoles, 29 septiembre 2021    <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Abrimos la secci\u00f3n con el viaje que est\u00e1 realizando&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11347\/tamara-lunger-todos-tresmiles-espana?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Tamara Lunger por Espa\u00f1a, como reto ascender los tresmiles del Pirineo, Sierra Nevada y el Teide en 70 d\u00edas<\/a><em>&nbsp;(Barrabes)<\/em>. Un viaje multiaventura en el que adem\u00e1s alternar\u00e1 actividades de kayak, parapente, escalada o gravel. Pod\u00e9is seguir su aventura en&nbsp;<a href=\"https:\/\/www.instagram.com\/tamaralunger\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">sus redes sociales<\/a>.<\/li>\n\n\n\n<li>Por otro lado,&nbsp;<a href=\"https:\/\/www.desnivel.com\/alpinismo\/simon-gietl-y-roger-schaeli-escalan-las-seis-caras-norte-de-los-alpes-en-18-dias\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">el viaje de Simon Gietl y Roger Schaeli en los Alpes finaliza con 6 grandes caras nortes en 18 d\u00edas&nbsp;<\/a><em>(Desnivel)<\/em>. Como os coment\u00e1bamos la semana pasada se encontraban inmersos en esta aventura, proyecto que han llamado&nbsp;<em>NORTH6<\/em>:&nbsp;escalar 6 caras norte cl\u00e1sicas de los Alpes, esquiando en las aproximaciones, descenso en parapente y bicicleta para ir de una monta\u00f1a a otra. Cima Grande di Lavaredo, el Piz Badile, el Eiger, el Matterhorn, el Petit Dru y las Grandes Jorasses, 30.000 metros de desnivel y m\u00e1s de 1.000 km de recorrido por Italia, Suiza y Francia.<\/li>\n\n\n\n<li>Y para seguir con inspiradores viajes, os hablamos del que han hecho&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11348\/gran-exploracion-escaladas-groenlandia-favresse?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Nico Favresse, Sean&nbsp;Villanueva, Jean-Luis Wertz Wertz y Aleksej Jaruta en Groenlandia&nbsp;<\/a><em>(Barrabes)<\/em>. 2 semanas en velero a trav\u00e9s del Atl\u00e1ntico para llegar a Groenlandia e iniciar una exploraci\u00f3n de 50 d\u00edas en los que han abierto 6 grandes paredes v\u00edrgenes.<\/li>\n\n\n\n<li>Y cerramos, con la pol\u00e9mica en cuanto a la TRUE cima en el Manaslu. Las agencias est\u00e1n proliferando la escalada de esta monta\u00f1a en oto\u00f1o: 1.313 personas han hollado la cima entre 2013 y 2019. Pero un estudio publicado por&nbsp;<a href=\"http:\/\/www.8000ers.com\/cms\/index.php?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">8000ers.com&nbsp;<\/a>anunci\u00f3 que la cima no era la verdadera, que quedaba a 20 metros o m\u00e1s siguiendo la arista somital. A ello se une que el gu\u00eda&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/mingma-g-lidera-la-primera-cima-verdadera-del-manaslu-en-nueve-anos\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Mingma G lidera la primera cima verdadera del Manaslu en nueve a\u00f1os&nbsp;<\/a><em>(Desnivel)<\/em>, hecho que desacredita tantas cimas en los \u00faltimos a\u00f1os.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Manaslu<br><br>Queda pendiente ver las fotos de los que est\u00e1n descendiendo todav\u00eda, para ver si llegaron a la cumbre del Manaslu o al que yo en adelante llamar\u00e9 FREP (Fixed Ropes\u2019 End Point) que no es la cumbre.<br><br>Les deseo a todos buen descenso y sin incidencias. <a href=\"https:\/\/t.co\/sF35SJ1eL1\">pic.twitter.com\/sF35SJ1eL1<\/a><\/p>&mdash; k2 (@KrisAnnapurna) <a href=\"https:\/\/twitter.com\/KrisAnnapurna\/status\/1442121938239959042?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">September 26, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-22-septiembre-2021\"> Mi\u00e9rcoles, 22 septiembre 2021   <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lo primero: \u00bfsab\u00e9is que ya ha regresado la nieve a los Pirineos?&nbsp;<a href=\"https:\/\/www.nieveaventura.com\/2021\/09\/20\/la-primera-nevada-tine-de-blanco-algunas-areas-de-los-pirineos\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">La primera nevada ti\u00f1e de blanco algunas zonas de los Pirineos<\/a>&nbsp;<em>(nieveyaventura)<\/em>. Una DANA, bolsa fr\u00eda en altura, ha llegado estos d\u00edas al norte peninsular y ha sido la \u201cculpable metereol\u00f3gica\u201d. Los copos de nieve se han podido ver bajando hasta los 2.100-2.500m.<\/li>\n\n\n\n<li>Estamos siguiendo la<strong>&nbsp;aventura de Simon Gietl y Roger Schaeli en los Alpes.&nbsp;<\/strong>Ambos son conocidos por sus actividades en las grandes cordilleras del planeta. Ahora en casa est\u00e1n realizando este proyecto que han llamado&nbsp;<strong>NORTH6<\/strong>: &nbsp;escalar 6 caras norte cl\u00e1sicas de los Alpes, esquiando en las aproximaciones, descenso en parapente y bicicleta para ir de una monta\u00f1a a otra. Han escalado \u2018Chant Du Cygne\u2019 en el Eiger y la norte del Matterhorn por la v\u00eda Schmid. Ahora pod\u00e9is seguir el desenlace de su aventura en Chamonix, con las Grandes Jorasses y el Petit Dru. En el&nbsp;<a href=\"https:\/\/www.instagram.com\/rogerschaeli\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">perfil de instagram de Roger Schaeli&nbsp;<\/a>ten\u00e9is instant\u00e1neas de todo el proyecto.<\/li>\n\n\n\n<li>Tambi\u00e9n os tenemos que hablar de las&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/adam-bielecki-y-janusz-golab-lideran-tres-primeras-polacas-a-seismiles-virgenes-en-shimshal\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">tres primeras polacas a seismiles v\u00edrgenes en Shimshal lideradas por Adam Bielecki y Janusz Golab<\/a>&nbsp;<em>(Desnivel)<\/em>. Ambos est\u00e1n al frente de la expedici\u00f3n del programa de Himalayismo Deportivo Polaco y est\u00e1n explorando las cumbres v\u00edrgenes de 6.000 y 7.000 metros de esta zona del norte del Karak\u00f3rum.<\/li>\n\n\n\n<li>Y para cerrar os hablamos del proyecto<strong>&nbsp;\u2018Mugak\u2019: historias de personas que fueron parte y vivieron el contrabando<\/strong>&nbsp;que se dio en la frontera pirenaica. Se ha abierto un&nbsp;<em>crowdfunding&nbsp;<\/em>para llevar a cabo el rodaje de este documental que contar\u00e1 las historias de hombres y mujeres&nbsp;de los valles fronterizos de&nbsp;<strong>Cinco Villas, Bazt\u00e1n o Ultzama<\/strong>&nbsp;y como vivieron el contrabando.&nbsp;<a href=\"https:\/\/www.verkami.com\/locale\/es\/projects\/31177-mugak?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Pod\u00e9is apoyar el proyecto aqu\u00ed&nbsp;<em>(Verkami)<\/em><\/a><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-15-septiembre-2021\">Mi\u00e9rcoles, 15 septiembre 2021  <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Empezamos la secci\u00f3n a paso lento pero sin pausa, como el del ganado que estos d\u00edas vuelve a las tierras del sur dejando atr\u00e1s el Pirineo. \u00abLos reba\u00f1os de Domingo Urzainqui y Francisco Fuertes salen ya del t\u00e9rmino de Santa B\u00e1rbara, en el Pirineo roncal\u00e9s, con destino a las <a href=\"https:\/\/travesiapirenaica.com\/bardenas-reales\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bardenas Reales de Navarra\u00bb<\/a>, nos cuentan desde <a href=\"https:\/\/twitter.com\/lakukula\" target=\"_blank\" rel=\"noreferrer noopener\">La Kukula&nbsp;<\/a>(colectivo para la difusi\u00f3n cultural). Nos ir\u00e1n compartiendo el d\u00eda a d\u00eda de la ruta trashumante en sus redes sociales.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Llegan ya las 2000 ovejas al monasterio de Leyre, cuna del Reino de Navarra y cuya cripta es una joya excepcional del arte pre-rom\u00e1nico. Confluyen as\u00ed nuestro patrimonio material e inmaterial en un singular enclave hist\u00f3rico, religioso y cultural. <a href=\"https:\/\/t.co\/xg3J8xeed4\">pic.twitter.com\/xg3J8xeed4<\/a><\/p>&mdash; La Kukula (@lakukula) <a href=\"https:\/\/twitter.com\/lakukula\/status\/1437845882569994241?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">September 14, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.revistaoxigeno.es\/actualidad\/mueren-dos-escaladores-mientras-hacian-psicobloc-en-mallorca_242223_102.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Dos escaladores fallecen en un sector de psicobloc de Cala Sa Nau&nbsp;<\/a><em>(Ox\u00edgeno)<\/em>, en Cova des Cos\u00ed (Mallorca). Como causa del accidente todo apunta a un desprendimiento de rocas cuando se acercaban al alto del acantilado. Los cuerpos fueron hallado en el agua sin vida. Lo comunicaban los Hermanos Pou en sus redes, que estos d\u00edas se encontraban en la zona.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Consternaci\u00f3n y mucha pena \ud83d\ude2d ante la noticia que nos acaba de llegar de la muerte de dos escaladores haciendo <a href=\"https:\/\/twitter.com\/hashtag\/Psicobloc?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Psicobloc<\/a> hoy en <a href=\"https:\/\/twitter.com\/hashtag\/calasanau?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#calasanau<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/mallorca?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#mallorca<\/a>, zona que estamos frecuentado estos d\u00edas y donde se tom\u00f3 esta foto&#8230;<br>Todo apunta a un desprendimiento de piedra&#8230; <br>DEP \ud83d\ude4f\ud83d\ude4f\ud83d\ude4f <a href=\"https:\/\/t.co\/cjIjewkhbY\">pic.twitter.com\/cjIjewkhbY<\/a><\/p>&mdash; Hermanos Pou (@hermanospou) <a href=\"https:\/\/twitter.com\/hermanospou\/status\/1437784129328885774?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">September 14, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><figcaption class=\"wp-element-caption\"><strong>Carlos Soria ya se encuentra en el campo base del Dhaulagiri<\/strong>. \u201cUna vez m\u00e1s a los pies de esta bella monta\u00f1a donde hemos pasado tan buenos momentos. De nuevo comenzamos a so\u00f1ar con pisar esa deseada cima y, sobre todo, disfrutar de este maravilloso rinc\u00f3n del planeta.\u201d, nos cuenta. Os dejamos aqu\u00ed el video que ha compartido en Youtube.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Ya hemos llegado al campo base del Dhaulagiri.\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/rj8Jur23L5k?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-8-septiembre-2021\"> Mi\u00e9rcoles, 8 septiembre 2021 <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Una aventura de 34 horas, 67 kil\u00f3metros y 6.129 metros de desnivel:&nbsp;<a href=\"https:\/\/www.desnivel.com\/alpinismo\/jonatan-garcia-escala-los-51-tresmiles-del-macizo-maladeta-aneto-en-34-horas-desde-benasque\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Jonatan Garc\u00eda escala los 51 tresmiles del macizo Maladeta-Aneto desde Benasque<\/a>&nbsp;<em>(Desnivel)<\/em>. \u00c9l la ha llamado \u201cLa vuelta al mundo\u201d, un recorrido en autosuficiencia.&nbsp;\u201cPara m\u00ed era importante no perder la \u00e9tica ni las formas, que eran la base del proyecto\u201d, recalca.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.elcorreo.com\/mendian\/montana\/alpinismo\/alex-txikon-volvera-20210903013145-nt.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Sajid Sadpara completa el grupo de \u00c1lex Txikon y Simone Moro para el Manaslu invernal<\/a>&nbsp;<em>(elcorreo)<\/em>. Ser\u00e1 un homenaje a Ali Sadpara, compa\u00f1ero de cordada que junto a Txikon y Simone logr\u00f3 la primera invernal al Nanga Parbat y que falleci\u00f3 en el pasado invierno en el K2. El joven Sajid ocupar\u00e1 el lugar de su padre para la reedici\u00f3n de la cordada. Ser\u00e1 la \u00faltima expedici\u00f3n invernal a un ochomil de Txikon. \u00abHa llegado la hora de cerrar un ciclo\u00bb, comenta Alex, que quiere sacarse la espina en su vuelta al Manaslu.<\/li>\n\n\n\n<li>Y cerramos la secci\u00f3n cont\u00e1ndote que&nbsp;<a href=\"https:\/\/www.elperiodicodearagon.com\/aragon\/2021\/09\/03\/pirineo-aragones-moviliza-practica-helibike-56921450.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">el Pirineo aragon\u00e9s se moviliza contra la pr\u00e1ctica del helibike<\/a>&nbsp;(elperiodicodearagon). Si no te suena esta actividad, te pongo r\u00e1pido en situaci\u00f3n: subir en helicoptero para bajar en bicicleta. La convocatoria ha sido en la cima de Punta Suelza, en Bielsa, punto de partida de estos aventureros \u201cun tanto vagos\u201d. \u00abHay lugares de Arag\u00f3n donde este deporte&nbsp;est\u00e1 expresamente prohibido (\u2026) El helibike es incompatible con el&nbsp;senderismo&nbsp;y con el respeto a la naturaleza\u00bb indica Luis Tirado, de SEO\/BirdLife.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-28-julio-2021\">Mi\u00e9rcoles, 28 julio 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Empiezan los primeros Juegos Ol\u00edmpicos Tokio 2020, y la escalada se estrena como deporte ol\u00edmpico. Te habr\u00e1s preguntado :&nbsp;<a href=\"https:\/\/woguclimbing.com\/donde-cuando-ver-television-escalada-juegos-olimpicos-tokio\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u00bfc\u00f3mo seguir la competici\u00f3n de la escalada?<\/a>&nbsp;<em>(Woguclimbing)<\/em>. El directo de las pruebas de escalada se puede seguir en abierto en&nbsp;<a href=\"https:\/\/www.rtve.es\/deportes\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Televisi\u00f3n Espa\u00f1ola<\/a>&nbsp;y en el&nbsp;<a href=\"https:\/\/olympics.com\/en\/olympic-channel?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Canal Ol\u00edmpico<\/a>. O bajo pago en&nbsp;<a href=\"https:\/\/www.eurosport.es\/juegos-olimpicos\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Eurosport<\/a>&nbsp;o DZN.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/localizados-los-cuerpos-de-ali-sadpara-juan-pablo-mohr-y-john-snorri-en-el-k2\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Se han localizado los cuerpos de Ali Sadpara, Juan Pablo Mohr y John Snorri en el K2<\/a>&nbsp;<em>(Desnivel)<\/em>. Sajid Sadpara, hijo de Ali, tiene previsto cruzar el Cuello de Botella para llegar al cuerpo de su padre a 8.300 m.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">According to updates from Sajid Sadpara, bodies of 3 climbers have been found in and around the bottleneck. More details for recovery and possibility of retrieval of the bodies will follow <a href=\"https:\/\/twitter.com\/hashtag\/K2Search?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#K2Search<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/MissionSadpara?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#MissionSadpara<\/a> <a href=\"https:\/\/t.co\/ecsZJj6f8c\">pic.twitter.com\/ecsZJj6f8c<\/a><\/p>&mdash; Team Ali Sadpara (@ali_sadpara) <a href=\"https:\/\/twitter.com\/ali_sadpara\/status\/1419877047216844815?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 27, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11296\/rick-allen-fallece-avalancha-k2?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Rick Allen fallece en una avalancha en el K2<\/a>&nbsp;<em>(Barrabes)<\/em>. El experimentado alpinista escoc\u00e9s de 68 a\u00f1os logr\u00f3 gran reconocimiento en 2012 por completar la primera escalada de la arista Mazeno al Nanga Parbat junto a Sandy Allan, que les vali\u00f3 el Piolet d&#8217;Or. Se encontraba junto a Jordi Tosas y Stephan Keck en la cara Sureste de la monta\u00f1a intentando abrir una nueva ruta en estilo alpino.<\/li>\n\n\n\n<li>Y cerramos la secci\u00f3n con una pregunta:&nbsp;<a href=\"https:\/\/www.salyroca.es\/articulo\/vida-eco\/incendios-mas-peligrosos\/20210726150201006932.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u00bfpor qu\u00e9 ahora hay m\u00e1s incendios y son m\u00e1s peligrosos?<\/a><em>&nbsp;(SalyRoca)<\/em>. \u201cAhora hay m\u00e1s incendios debido al cambio global que incluye factores tan determinantes como el cambio clim\u00e1tico y el cambio en la gesti\u00f3n del suelo\u201d, nos cuenta Rosa Mar\u00eda Canals, profesora de Ingenier\u00eda Agroalimentaria y del Medio Rural en la UPNA.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-21-julio-2021\">Mi\u00e9rcoles, 21 julio 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comenzamos la secci\u00f3n en Per\u00fa: Eneko e Iker Pou han comenzado su viaje de escalada a Per\u00fa de la mejor manera; con una nueva escalada mixta en la cara sur del Nevado&nbsp;Huamashraju Este (5.350 m), hasta ahora no escalada. \u201c\u00a1Viva Per\u00fa Carajo!\u201d, la han llamado. 15 horas de actividad en estilo libre y alpino para afrontar los 600 m (M7\/80\u00b0) en \u201cuna peque\u00f1a telara\u00f1a blanca, sobre un fondo de roca. Una l\u00ednea elegante y audaz (\u2026). Pasajes verticales entre roca m\u00e1s propios de los Alpes que de los Andes\u201d, que han exigido los mejor de los hermanos Pou.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"HERMANOS POU | \u201c\u00a1Viva Per\u00fa Carajo!\u201d M7\/80\u00ba\/600 m (HUAMASHRAJU ESTE 5.350m.)\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/en6TueyCcww?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.desnivel.com\/carreras-y-raids\/luis-alberto-hernando-sube-y-baja-del-aneto-en-3h3815\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Luis Alberto Hernando sube y baja del Aneto en 3h38\u201915\u201d<\/a><em>(Desnivel)<\/em>, rebajando la marca anterior en casi 5 minutos. Se trata del nuevo r\u00e9cord de ascensi\u00f3n al techo de los Pirineos desde Benasque. La ascensi\u00f3n la realiz\u00f3 por la ruta de Coronas, 2.300m de desnivel que abord\u00f3 en 2h14\u201931\u201d. Recorri\u00f3 en total 37,6 kil\u00f3metros.<\/li>\n\n\n\n<li>A qui\u00e9n no le ha mandado&nbsp;<em>Google Maps<\/em>&nbsp;por una \u201ccarreterucha\u201d . Bueno, pues todo se complica si utilizamos su algoritmo y tecnolog\u00eda para orientarnos y elegir ruta en monta\u00f1a.&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11292\/mountaineering-scotland-avisa-riesgos-rutas?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Mountaineering Scotland<\/em>&nbsp;avisa de los riesgos de las rutas de Google Maps en monta\u00f1a&nbsp;<\/a>(<em>Barrabes<\/em>). Accidentes en el Ben Nevis han hecho saltar las alarmas. Tambi\u00e9n se pone el foco en el exceso de informaci\u00f3n y tracks colgados en la red:&nbsp;\u201cHoy en d\u00eda, es demasiado f\u00e1cil asumir que la informaci\u00f3n en internet es siempre correcta\u00bb.<\/li>\n\n\n\n<li>Y para cerrar os traemos unas im\u00e1genes del Glaciar del Taill\u00f3n que nos han compartido desde&nbsp;<a href=\"https:\/\/twitter.com\/Meteo_Pyrenees?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><em>M\u00e9t\u00e9o Pyr\u00e9n\u00e9es<\/em><\/a>. Nos hemos hecho eco de muchos art\u00edculos sobre el retroceso de los glaciares en el Pirineo \u2014la semana pasado sin ir m\u00e1s lejos\u2014, pero como bien se dice, m\u00e1s vale una imagen que mil palabras: glaciar en 1921 versus este a\u00f1o.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"fr\" dir=\"ltr\">Le recensement des photos de l\u2019\u00e9tat des <a href=\"https:\/\/twitter.com\/hashtag\/glaciers?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#glaciers<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/pyrenees?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#pyrenees<\/a> pour cet \u00e9t\u00e9 2021 d\u00e9bute comme chaque ann\u00e9e \ud83d\udc49vous pouvez nous adresser vos photos r\u00e9centes ou des ann\u00e9es 50\/60\/70 par mail mtopyr@gmail.com <br>\ud83d\udcf7 Glacier du Taillon 1921 Vs l\u2019an dernier merci <a href=\"https:\/\/t.co\/OzuAZrqLuL\">pic.twitter.com\/OzuAZrqLuL<\/a><\/p>&mdash; M\u00e9t\u00e9o Pyr\u00e9n\u00e9es (@Meteo_Pyrenees) <a href=\"https:\/\/twitter.com\/Meteo_Pyrenees\/status\/1417079617828098049?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 19, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-14-julio-2021\">Mi\u00e9rcoles, 14 julio 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arrancamos con algo que ya hab\u00edamos comentado anteriormente, en el&nbsp;<em>trail running<\/em>&nbsp;el salto del asfalto a la monta\u00f1a cada vez se est\u00e1 haciendo m\u00e1s r\u00e1pido. \u201cPuede sonar extremo, pero es demasiado com\u00fan ver atletas sin experiencia en monta\u00f1a planificar o comenzar actividades alpinas sin ning\u00fan conocimiento de los riesgos y peligros que encaran\u00bb.&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11282\/kilian-jornet-advierte-inexperiencia-montana?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Kilian Jornet advierte sobre la inexperiencia en monta\u00f1a<\/a><em>&nbsp;(Barrabes)<\/em>. Tambi\u00e9n remarca la necesidad de aprender, \u201cbien en un club de monta\u00f1a, con gu\u00edas de monta\u00f1a, con mentores\u201d. Y habla de la necesidad de crear un \u00absistema de graduaci\u00f3n\u201d para las rutas de&nbsp;<em>trail<\/em>.<\/li>\n\n\n\n<li>Nos hacemos eco de la celebraci\u00f3n de los 200 a\u00f1os de historia de La Compa\u00f1\u00eda de Gu\u00edas de Chamonix. Lo han celebrado con&nbsp;<a href=\"https:\/\/www.desnivel.com\/cultura\/la-mayor-cordada-del-mundo-200-personas-en-el-mont-blanc\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=pocket_mylist\" target=\"_blank\" rel=\"noreferrer noopener\">la mayor cordada del mundo: 200 personas en el Mont Blanc&nbsp;<\/a><em>(Desnivel)<\/em>. Ocup\u00f3 6 kil\u00f3metros, cruzando la frontera franco-italiana en el macizo del&nbsp;Mont Blanc, entre la&nbsp;Aiguille du Midi&nbsp;(3.842 m) y la&nbsp;Punta Helbronner&nbsp;(3.642 m).<\/li>\n\n\n\n<li>Si vas a ir a Ordesa con tu mascota lee primero esto.<a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/huesca\/2021\/07\/11\/ordesa-aconseja-no-ir-con-perros-hacia-la-cola-de-caballo-para-evitar-incidentes-con-las-vacas-1505557.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;Ordesa aconseja no ir con perros hacia la Cola de Caballo para evitar incidentes con las vacas<\/a>&nbsp;<em>(Heraldo)<\/em>. Se toma esta medida tras los \u00faltimos incidentes entre los perros y el ganado que pasta en estas fechas por las inmediaciones de la Cola de Caballo. Los accesos a Soaso ya est\u00e1n jalonados con carteles amarillos que recomiendan no acercarse con perros. La medida se mantendr\u00e1 hasta finales de julio, que es la fecha en la que el ganado se mantiene en la zona.<\/li>\n\n\n\n<li>Ya es t\u00f3nica habitual que esta secci\u00f3n del bolet\u00edn traiga art\u00edculos hablando del retroceso de los glaciares en el Pirineo. En esta ocasi\u00f3n nos ha sorprendido la contundencia de este art\u00edculo:&nbsp;<a href=\"https:\/\/theobjective.com\/further\/los-glaciares-pirenaicos-han-resistido-otros-cambios-climaticos-pero-desapareceran-con-este?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u201cLos glaciares pirenaicos han resistido otros cambios clim\u00e1ticos, pero desaparecer\u00e1n con este\u201d<\/a>&nbsp;<em>(TheObjective)<\/em>. \u201cSe ha detectado que 33 de los 52 glaciares que hab\u00eda en el Pirineo en 1850 (al final de la Peque\u00f1a Edad del Hielo) han desaparecido, y 20 de ellos lo han hecho a partir de 1984.\u201d. Gran parte de la investigaci\u00f3n versa en torno al glaciar de Monte Perdido en el marco del proyecto de investigaci\u00f3n &nbsp;<a href=\"https:\/\/www.gsnci.upm.es\/es\/paleoice\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">EXPLORA PaleoICE<\/a>.<\/li>\n\n\n\n<li>Y nos despedimos con este video de Garnbret y \u0160kofic escalando<a href=\"https:\/\/twitter.com\/KrisAnnapurna\/status\/1414700312221323267?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;la chimenea m\u00e1s alta de Europa<\/a>. Se trata de la chimenea de la central el\u00e9ctrica de Trbovlje que se eleva 360 metros en el cielo de Eslovenia.&nbsp;Una escalada diferente de la mano de Red Bull.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Climbing The Highest Chimney In Europe | w\/ Janja Garnbret and Domen \u0160kofic\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/bpDymGNQy_I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-7-julio-2021\">Mi\u00e9rcoles, 7 julio 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11279\/jonatan-garcia-collado-salenques_pico-alba?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Jonatan Garc\u00eda, el vasco afincado en Benasque, complet\u00f3 la pasada semana la interminable cresta que une el collado de Salenques y el Pico de Alba, en 8 horas y cuarto<\/a>&nbsp;(11 horas y media desde la Besurta)&nbsp;<em>(Barrabes)<\/em>. Un total de 30 picos de m\u00e1s de 3.000 m, unidos por un terreno complejo, vertiginoso y en muchos tramos descompuesto, con pasos de hasta V.<\/li>\n\n\n\n<li><a href=\"https:\/\/explorersweb.com\/2021\/07\/05\/edu-marin-to-free-climb-eternal-flame-on-trango-tower\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Edu Mar\u00edn escalar\u00e1 en libre la v\u00eda original \u201cEternal Flame\u201d&nbsp;<\/a>en la Torre del Trango, Pakist\u00e1n&nbsp;<em>(explorersweb).<\/em>&nbsp;Una expedici\u00f3n minimalista de solo 37 d\u00edas, para los 1.100 m de escalada en roca muy t\u00e9cnica a 6.000 m.&nbsp;<a href=\"https:\/\/woguclimbing.com\/eternal-flame-decimo-aniversario-primera-ascension-en-libre-karakorum\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">La ruta&nbsp;<\/a>estableci\u00f3 un hito en la escalada de pared a gran altura, cuando Wolfgang Gullich, Kurt Albert, Christof Stiegler y Milan Sykora la abrieron por primera vez en 1989. Veinte a\u00f1os despu\u00e9s, Alex y Thomas Huber realizaron la primera escalada en libre con algunas variantes. Marin y sus compa\u00f1eros Miquel Mas y Mark Subirana repetir\u00e1n la ruta original de Gullich y compa\u00f1\u00eda.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Eternal Flame&#39;\u00a0is considered a big wall benchmark. It was opened by\u00a0Wolfgang G\u00fcllich,\u00a0Kurt Albert,\u00a0Christof Stiegler\u00a0and\u00a0Milan Sykora\u00a0in 1989. The route is located in the Trango Towers, above the 6.000 meters of altitude.<br>We want to try to free climb this king line! \ud83d\ude4f\ud83c\udffc\ud83d\udd25 <a href=\"https:\/\/t.co\/dG3UfvkYNE\">pic.twitter.com\/dG3UfvkYNE<\/a><\/p>&mdash; Edu Marin (@Edumarinclimb) <a href=\"https:\/\/twitter.com\/Edumarinclimb\/status\/1410283066279481348?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 30, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/martin-elias-jerome-sullivan-victor-saucede-y-jeremy-stagnetto-primera-ascension-del-k13\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Primera ascensi\u00f3n del Dansam Occidental&nbsp;<\/a>a cargo de Mart\u00edn El\u00edas, J\u00e9rome Sullivan, Victor Sauc\u00e8de y J\u00e9r\u00e9my Stagnetto&nbsp;<em>(Desnivel).<\/em>&nbsp;Hicieron cima en esta cumbre secundaria del conocido como K13 (6.666 m). En la cima encontraron un cordino, aunque no se conoc\u00eda ascensi\u00f3n previa, que si la debi\u00f3 haber. La ruta abierta escala el espol\u00f3n norte, 1.600 m t\u00e9cnicos con dificultad m\u00e1xima de M6.<\/li>\n\n\n\n<li>La Federaci\u00f3n de Monta\u00f1a y Escalada firma un convenio junto con el Ayuntamiento de Jaca para la&nbsp;<a href=\"https:\/\/www.radiohuesca.com\/comarcas\/jaca-se-convierte-en-referente-nacional-con-la-apertura-de-la-oficina-de-la-montana-06072021-156399.html?fbclid=IwAR0xjyRCGxYeF_wAHEoVVi0PiYt-KqEuRSorlwZ7pO_AanCqHMUDw7OR6TA&amp;utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">apertura de la Oficina de la Monta\u00f1a<\/a>&nbsp;<em>(Radio Huesca).<\/em>&nbsp;Estar\u00e1 abierta todos los d\u00edas en horario de tarde ( 5 a 9 pm). La Oficina estar\u00e1 gestionada por la Federaci\u00f3n, que instalar\u00e1 all\u00ed su oficina t\u00e9cnica y su observatorio de accidentes.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-30-junio-2021\">Mi\u00e9rcoles, 30 junio 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfHab\u00e9is visto el video del<strong>&nbsp;desprendimiento en la ladera del Balneario de Panticosa<\/strong>? Ocurri\u00f3 hace unos d\u00edas y fue captado con el m\u00f3vil, en el mismo momento que un bloque de piedra de gran tama\u00f1o se precipitaba pendiente abajo con gran estruendo, acompa\u00f1ado de todo tipo de materiales, como si de un r\u00edo de piedras se tratara. Por suerte no ha habido ninguna desgracia. Si no lo has visto, aqu\u00ed el video:<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Desprendimiento en el Balneario de <a href=\"https:\/\/twitter.com\/hashtag\/Panticosa?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Panticosa<\/a> \ud83c\udfd4 <a href=\"https:\/\/twitter.com\/hashtag\/AltoAragon?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#AltoAragon<\/a> <a href=\"https:\/\/t.co\/xZRcPWVOb1\">pic.twitter.com\/xZRcPWVOb1<\/a><\/p>&mdash; Bal de Tena &#8211; Biescas \ud83e\udd81\u26f7\u26f0 (@pzbaldetena) <a href=\"https:\/\/twitter.com\/pzbaldetena\/status\/1408170544940343305?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 24, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>A debate:<\/strong>&nbsp;<a href=\"https:\/\/www.desnivel.com\/escalada-roca\/seb-berthe-desequilibrio-en-los-grados-de-vias-multipitch\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u00bfEst\u00e1n bien los grados en v\u00edas de escalada \u2018<em>multipitch<\/em>\u2019?<\/a><em>&nbsp;(Desnivel).<\/em>&nbsp;El escalador belga Seb Berthe, que tiene en su haber algunas de las v\u00edas largas m\u00e1s duras del mundo, lanza este debate y comenta que a su parecer las v\u00edas largas de Europa est\u00e1n sobregraduadas. Seg\u00fan \u00e9l deber\u00edan graduarse<strong>&nbsp;los largos como si estuvieran en el suelo<\/strong>. La comunidad escaladora se ha pronunciado: \u00bfNo estar\u00e1s demasiado fuerte? \u00bfDeber\u00eda existir una graduaci\u00f3n general de la ruta?\u2026.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11267\/sajid-sadpara-busca-su-padre?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Sajid Sadpara, hijo de Ali Sadpara, y \u00faltimo que vio con vida a Ali, Juan Pablo Mohr y John Snorri en el K2 este invierno, vuelve a K2<\/a>&nbsp;<em>(Barrabes)&nbsp;<\/em>junto con el canadiense Elia Saikaly, que tambi\u00e9n formaba parte de la fat\u00eddica expedici\u00f3n. Sajid tuvo que darse la vuelta en la ascensi\u00f3n por problemas, el d\u00eda que desapareci\u00f3 su padre. Ahora, su objetivo es encontrar respuestas y dar con los cuerpos.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/huesca\/2021\/06\/29\/subi-de-un-tiron-214-tresmiles-y-sin-comodidades-1499992.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">214 tresmiles en 44 d\u00edas y \u201csin comodidades\u201d&nbsp;<\/a><em>(Heraldo);<\/em>&nbsp;esta fue la aventura de Ivan Rouco e I\u00f1igo Iruretagoiena, recogida en el documental \u201cGranito Buffet. Vagabundos pirenaicos\u201d. La cinta narra la vivencias, la log\u00edstica previa de \u00abdep\u00f3sitos\u00bb, el estilo y material utilizado. Presentada en Villan\u00faa y Pa\u00eds Vasco, en oto\u00f1o circular\u00e1 por lugares como Zaragoza, Segovia, Huesca o Andorra. Simplemente ver el tr\u00e1iler da una idea de la haza\u00f1a, aqu\u00ed os lo dejamos:<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/youtu.be\/wWz2PNM_I-Y\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-23-junio-2021\">Mi\u00e9rcoles, 23 junio 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>David Goettler, quien ha regresado hace poco del Everest, de su expedici\u00f3n con Kilian Jornet, escala el Espol\u00f3n de los Franceses, una de las rutas de escalada m\u00e1s cl\u00e1sicas de los Picos de Europa <em>(Barrabes)<\/em>, 1000 m de desnivel, MD, V+ y 17 largos de piedra caliza m\u00e1s una escalada de cresta expuesta<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11259\/david-goettler-escala-espolon-franceses\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;hasta la cima&nbsp;de Pe\u00f1a Vieja, con su padre de 81 a\u00f1os<\/a> (Barrab\u00e9s). Pod\u00e9is ver aqu\u00ed el <a href=\"https:\/\/www.facebook.com\/watch\/?v=326684855576066\" target=\"_blank\" rel=\"noreferrer noopener\">video&nbsp;<\/a>de la haza\u00f1a.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.elperiodico.com\/es\/deportes\/20210618\/muere-emma-roca-referente-deportes-11837963\" target=\"_blank\" rel=\"noreferrer noopener\">Muere Emma Roca, referente en los deportes de monta\u00f1a<\/a> y una de las pioneras en las carreras de monta\u00f1a <em>(elPeriodico)<\/em>, a los 47 a\u00f1os de c\u00e1ncer, lo que ha causado un hondo pesar en la comunidad monta\u00f1era.<\/li>\n\n\n\n<li>La escaladora y alpinista estadounidense <a href=\"https:\/\/www.desnivel.com\/alpinismo\/chantel-astorga-escala-la-cassin-al-denali-en-solitario-y-desciende-esquiando\/\" target=\"_blank\" rel=\"noreferrer noopener\">Chantel Astorga escala la \u2018Cassin\u2019 al Denali (6.194 m) en solitario y desciende esquiando<\/a> <em>(Desnivel)<\/em>. 14 horas y 39 minutos en subir y bajar West Rib y Seattle Ramp en esqu\u00eds para marcar la \u00abprimera femenina\u00bb de velocidad al pico m\u00e1s alto de Norteam\u00e9rica.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/2021\/06\/09\/proyecto-transfronterizo-busca-promocionar-70-refugios-de-montana-del-pirineoara-cooperacion-transfronteriza-1498361.html\" target=\"_blank\" rel=\"noreferrer noopener\">Un proyecto transfronterizo busca promocionar los 70 refugios de monta\u00f1a del Pirineo<\/a><em> (Heraldo)<\/em>. Se trata de la continuaci\u00f3n del ENTREPYR que uni\u00f3 refugios de monta\u00f1a del Pirineo. Ahora un espacio web aglutinar\u00e1 a la mayor\u00eda de los refugios de ambos lados del Pirineo.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-16-junio-2021\">Mi\u00e9rcoles, 16 junio 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>30 km y 2630 m de desnivel para recorrer las 7 cumbres m\u00e1s rese\u00f1ables en torno al reconstruido refugio \u00c1ngel Olor\u00f3n: puede que haya nacido la<strong>&nbsp;\u2018Integral de Belagua\u2019<\/strong>. 14h45 (seg\u00fan MIDE) para hacer cumbre a las cimas de A\u00f1elarra, Anie, Mesa de los Tres Reyes, Budogia, Ukerdi, Lapaquiza de Linzola, Lapazarra, y volver al refugio en el d\u00eda.&nbsp;<strong>El itinerario est\u00e1 en estudio por parte del Dpto. Medio Ambiente de Navarra&nbsp;<\/strong><em>(Fed. Navarra Monta\u00f1a)<\/em>, que si da el visto bueno, ser\u00e1 una ruta muy exigente para aquellos que busquen un gran reto.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Estudiado el itinerario, hemos visto la necesidad de solicitar al Dto Medio Ambiente (Secci\u00f3n Espacios Naturales y Especies Protegidas) el \u201cInforme Medioambiental\u201d preceptivo en cumplimiento de la Ley de Protecci\u00f3n y Gesti\u00f3n Fauna Silvestre y sus H\u00e1bitats (Ley Foral 2\/1993)<\/p>&mdash; FED. NAVARRA MONTA\u00d1A (@MENDINAVARRA) <a href=\"https:\/\/twitter.com\/MENDINAVARRA\/status\/1404344186858528769?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 14, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.desnivel.com\/escalada-roca\/scott-bennett-y-jordan-cannon-escalan-la-triple-crown-de-yosemite\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\">Scott Bennett y Jordan Cannon escalan la&nbsp;<strong>Triple Crown de Yosemite<\/strong><\/a><em>(Desnivel)<\/em>. Las tres paredes m\u00e1s emblem\u00e1ticas de Yosemite: El Capitan, Half Dome y Mt. Watkins de forma sucesiva y en menos de 24 horas. La sexta cordada en completar este reto en menos de un d\u00eda.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.turiski.es\/expedicion-catalana-gasherbrum-liderada-lluis-cortadellas\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\"><strong>Expedici\u00f3n catalana a los Gasherbrum liderada por Llu\u00eds Cortadellas<\/strong>&nbsp;<\/a><em>(Turiski)<\/em>. Gasherbrum I y II sin sherpas de apoyo ni ox\u00edgeno. Los cinco monta\u00f1eros buscan su primer ocho mil. Para ello quieren montar el Campamento Base en el C1, y as\u00ed evitar una zona de riesgo por la densidad de grietas y bloques de hielo.Una placa en mem\u00f3ria a Sergi Mingote les acompa\u00f1a con la idea de ponerla en el memorial que hay antes de llegar al CB del K2 d\u00f3nde Sergi perdi\u00f3 la vida en su intento del K2 invernal.<\/li>\n\n\n\n<li>Tras el \u201ccirco\u201d de la reciente temporada en el&nbsp;<strong>Everest<\/strong>, se habla de perdida de \u00e9tica, del fin del himalayismo, de uno nuevo, comercial, de las \u201cfotos\u201d buscando la notoriedad frente a patrocinadores. Y&nbsp;<a href=\"https:\/\/twitter.com\/KrisAnnapurna?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\">@KrisAnnapurna<\/a>&nbsp;nos plantea otra foto que quiz\u00e1 no hemos visto: la<strong>&nbsp;foto de la recogida de basura<\/strong>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">In Scandinavia there\u2019s a thing called \u201cplogging\u201d. It\u2019s when you go for a run and pick up trash along the way. Maybe we should do the same on Everest next season? If I get a free permit I can do some plogging in the area \ud83d\ude0a  No O2 needed!<\/p>&mdash; Hans Kristian Smedsr\u00f8d (@hanserino) <a href=\"https:\/\/twitter.com\/hanserino\/status\/1403050929893613571?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 10, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-9-junio-2021\">Mi\u00e9rcoles, 9 junio 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hemos conocido estos d\u00edas que el canadiense Ian Welsted y estadounidense Graham Zimmerman, ambos Piolet d\u2019Or, <a href=\"https:\/\/www.desnivel.com\/expediciones\/ian-welsted-y-graham-zimmerman-intentaran-el-k2-por-la-arista-oeste\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>intentar\u00e1n el K2 por la arista oeste<\/strong><\/a> <em>(Desnivel)<\/em>. La ruta cuenta con tres ascensiones en los 80&#8242; y 90&#8242;, con estilos que utilizaron muchas secciones de cuerda fija. Iremos conociendo m\u00e1s.<\/li>\n<\/ul>\n\n\n\n<p><em>\u00abLa arista oeste es impresionante. No es \u00absuperdif\u00edcil\u00bb, pero s\u00ed t\u00e9cnica. Si las condiciones son las adecuadas, ser\u00e1 segura (es decir, no hay grandes seracs), y tiene un final directo no escalado que parece muy bonito.\u00bb<\/em> \u2014<a href=\"https:\/\/www.instagram.com\/grahamzimmerman\/?hl=es\" target=\"_blank\" rel=\"noreferrer noopener\">Graham Zimmerman<\/a><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No queda nadie en la monta\u00f1a con posibilidades, se ha desmantelado ya la ruta en la Cascada de Hielo de Kjumbu. Se cierra as\u00ed la temporada de ascensiones en el <strong>Everest<\/strong>. El balance: <a href=\"https:\/\/www.desnivel.com\/expediciones\/acaba-la-temporada-en-el-everest-534-cumbres-y-0-sin-oxigeno\/\" target=\"_blank\" rel=\"noreferrer noopener\">534 cumbres y ninguna sin ox\u00edgeno<\/a> <em>(Desnivel)<\/em>. La temporada ha estado marcada por el brote de Covid-19.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Los Pou escalan en libre la v\u00eda \u00abJon\u00bb &nbsp;8a+\/8b en la Leze<\/strong>. <em>\u201cNosotros comenzamos a escalar en esta escuela a principios de los 90, al igual que todas las generaciones de alpinistas alaveses anteriores a la nuestra. Gente como \u00c1ngel Rosen, Juan Ignacio Lorente, Juanito Oiarzabal, Adolfo Madinabeitia, Atxo Apellaniz o Antonio Miranda, entre otros muchos, se han criado entre estas piedras\u201d<\/em> \u2014<a href=\"https:\/\/twitter.com\/hermanospou\" target=\"_blank\" rel=\"noreferrer noopener\">Eneko Pou<\/a>. Echa un vistazo a fabuloso video de la ruta:<\/li>\n<\/ul>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/xFxBhKWojkQ\" title=\"YouTube video player\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"100%\" height=\"315\" frameborder=\"0\"><\/iframe>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y para terminar os traemos un documental inspirador que narra <a href=\"https:\/\/www.revistaoxigeno.es\/deportes\/nueva-vida-james-pearson-caroline-ciavaldini_235430_102.html\" target=\"_blank\" rel=\"noreferrer noopener\">la nueva aventura de Caroline Ciavaldini y James Pearson: la paternidad&nbsp;<\/a><em>(Ox\u00edgeno)<\/em>. Veremos su cambio de prioridades, lo que supone criar a un hijo en un mundo que gira en torno a la escalada y la exploraci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/pW2bRh3lcqE\" title=\"YouTube video player\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"100%\" height=\"315\" frameborder=\"0\"><\/iframe>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-2-junio-2021\">Mi\u00e9rcoles, 2 junio 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los alpinistas checos&nbsp;<strong>Marek Holecek y Radoslav Groh est\u00e1n sanos y salvos tras su \u00e9pico descenso de 80 horas del Baruntse(7129 m)&nbsp;<\/strong>en el que sufrieron los embates del cicl\u00f3n Yass, despu\u00e9s de escalar en estilo alpino y establecer la primera a la cara noroeste. \u2018Trampa Celestial\u2019 le han llamado a la ruta.<a href=\"https:\/\/www.elcorreo.com\/mendian\/montana\/alpinismo\/marek-holecek-y-radoslav-groh-obran-el-milagro-del-barutse-himalaya-20210601073953-nt.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;10 d\u00edas en el filo en este sietemil nepal\u00ed, que no les ha hecho perder el humor<\/a>&nbsp;<em>(elcorreo)<\/em>: \u00abToda la escalada no ha sido nada comparada con regresar a Katmand\u00fa. (\u2026) Lo \u00fanico que nos molesta es que todav\u00eda no hay vuelos para regresar a casa, (\u2026) Probablemente tendremos que ir andado\u00bb \u2014<em>Marek Holecek<\/em><\/li>\n<\/ul>\n\n\n\n<blockquote class=\"twitter-tweet\"><p dir=\"ltr\" lang=\"es\">Entrevista con Marek Hole\u010dek esta tarde (link a la entrevista entera al final de este hilo)<br><br>Maara:<br>\u201cParecemos un anuncio de muerte, espero con ansias una buena cerveza. Perd\u00ed m\u00e1s de 10 kg en 10 d\u00edas, tenemos algunas congelaciones menores, pero por lo dem\u00e1s no tenemos nada.<br>sigue <a href=\"https:\/\/t.co\/cLTMCKFytD\">pic.twitter.com\/cLTMCKFytD<\/a><\/p>\u2014 k2 (@KrisAnnapurna) <a href=\"https:\/\/twitter.com\/KrisAnnapurna\/status\/1399821973086220298?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 1, 2021<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/kilian-jornet-y-david-gottler-abortan-en-el-collado-sur-un-intento-al-everest\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Kilian Jornet y David G\u00f6ttler abortan en el Collado Sur un intento al Everest&nbsp;<\/strong><\/a><em>(Desnivel)<\/em>. David desde el C2 y Kilian desde el CB partieron ayer para una intentona express. Ya en el Collado Sur (C4) se encontraron ambos, pero vieron que no se sent\u00edan al 100% y el viento era muy fuerte, as\u00ed que abortaron su ambicioso objetivo.<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"twitter-tweet\"><p dir=\"ltr\" lang=\"es\">Kilian <a href=\"https:\/\/twitter.com\/kilianj?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@kilianj<\/a> y David G\u00f6ttler abortan en Collado Sur (7.900 m.) intento  <a href=\"https:\/\/twitter.com\/hashtag\/Everest?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Everest<\/a> al no encontrarse al 100% \u00a1Mucho respeto por estos grandes! Por lo que intentan hacer y por su manera de contarlo. As\u00ed de sincero es David G\u00f6ttler en el relato que hace en su cuenta de Instagram <a href=\"https:\/\/t.co\/BWlKOocuPr\">pic.twitter.com\/BWlKOocuPr<\/a><\/p>\u2014 Dar\u00edo Rodr\u00edguez (@DarioDesnivel) <a href=\"https:\/\/twitter.com\/DarioDesnivel\/status\/1399658257027829764?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 1, 2021<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Os traemos el profundo art\u00edculo de&nbsp;<a href=\"https:\/\/es.linkedin.com\/in\/jose-antonio-masi%C3%A1-rodriguez-5260b957?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Jose Antonio Masi\u00e1<\/a>&nbsp;<em>(Trekking y Aventura)<\/em>&nbsp;sobre \u201c<a href=\"https:\/\/salyroca.publico.es\/articulo\/roca\/gran-circo-ochomiles\/20210527091117006854.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>El gran circo de los ochomiles<\/strong><\/a>\u201d&nbsp;<em>(SalyRoca)&nbsp;<\/em>en el que nos cuenta que todo va muy r\u00e1pido y c\u00f3mo la \u00e9tica es importante pero la sostenibilidad es esencial. Conocedor de c\u00f3mo est\u00e1 cambiando el himalayismo nos ayuda a desgranar las claves.<\/li>\n\n\n\n<li>Y cerramos con los estudios que publican en<em>&nbsp;Monta\u00f1a Segura&nbsp;<\/em>sobre<strong>&nbsp;rescates de 2020&nbsp;<\/strong><a href=\"https:\/\/montanasegura.com\/rescates-en-senderismo-en-el-pirineo-aragones-2020\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>en senderismo<\/strong><\/a><strong>&nbsp;y&nbsp;<\/strong><a href=\"https:\/\/montanasegura.com\/rescates-en-alta-montana-en-el-pirineo-aragones-2020\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>alta monta\u00f1a&nbsp;<\/strong><\/a>en el Pirineo aragon\u00e9s. En 2020,&nbsp;el 42% de los rescates realizados por el Servicio de Monta\u00f1a de la Guardia Civil fue en actividades de senderismo. En alta monta\u00f1a y crestas los tropiezos y ca\u00eddas son el 56% y los problemas en la toma de decisiones el 39%.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-26-mayo-2021\">Mi\u00e9rcoles, 26 mayo 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arrancamos la secci\u00f3n con la <strong>tragedia acontecida en una ultramarat\u00f3n de monta\u00f1a en China<\/strong>, <a href=\"https:\/\/www.elcorreo.com\/mendian\/trail\/21-deportistas-muertos-carrera-montana-china-20210523092055-nt.html?\" target=\"_blank\" rel=\"noreferrer noopener\">21 corredores mueren a causa de un temporal de fr\u00edo, viento y granizo<\/a> <em>(elcorreo) <\/em>que sorprendi\u00f3 a los participantes en la zona alta del recorrido de la <em>100 K Huanghe Shilin Mountain Marathon<\/em> y a la organizaci\u00f3n que no pudo trasladar a todos. Ante la noticia han surgido muchas preguntas y reflexiones, como: de qui\u00e9n es la responsabilidad, c\u00f3mo puede pasar esto en una carrera, etc., con las que hemos arrancado el bolet\u00edn de la semana.<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"twitter-tweet\"><p dir=\"ltr\" lang=\"es\">Tragedia en una carrera en la monta\u00f1a en China. Qui\u00e9n es responsable? Puede pasar aqu\u00ed?<a href=\"https:\/\/twitter.com\/deportegob?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@deportegob<\/a> <a href=\"https:\/\/twitter.com\/COE_es?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@COE_es<\/a> <a href=\"https:\/\/twitter.com\/fedme_es?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@fedme_es<\/a> <a href=\"https:\/\/twitter.com\/kilianj?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@kilianj<\/a> <a href=\"https:\/\/twitter.com\/TrailHernando?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@TrailHernando<\/a> <a href=\"https:\/\/twitter.com\/RevistaTrailRun?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@RevistaTrailRun<\/a> <a href=\"https:\/\/twitter.com\/TerritorioTrail?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@TerritorioTrail<\/a> <a href=\"https:\/\/twitter.com\/trailrunningESP?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@trailrunningESP<\/a> <a href=\"https:\/\/twitter.com\/moxigeno?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@moxigeno<\/a> <a href=\"https:\/\/twitter.com\/KielBellido?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@KielBellido<\/a> <a href=\"https:\/\/t.co\/Av52cclAk5\">pic.twitter.com\/Av52cclAk5<\/a><\/p>\u2014 Alberto Ayora (@seguridadriesgo) <a href=\"https:\/\/twitter.com\/seguridadriesgo\/status\/1397508041952616448?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">May 26, 2021<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.elcomercio.es\/asturias\/miguel-angel-roldan-20210420001009-ntvo.html?\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>El lunes 31 de mayo el triatleta cordob\u00e9s Miguel \u00c1ngel Rold\u00e1n subir\u00e1 al Urriellu para dar visibilidad a la enfermedad del ELA<\/strong><\/a> y recaudar fondos <em>(elcomercio)<\/em>. Su aventura se transmitir\u00e1 en directo y se llama \u00abUrriELA, escalada de vida\u00bb. Miguel, afectado por la Ela, ya ha ascendido al Teide con este mismo prop\u00f3sito.<\/li>\n\n\n\n<li>Nos hacemos eco de la <strong>entrevista en Desnivel a Carlos Soria<\/strong>, reci\u00e9n llegado de Katmand\u00fa tras abandonar su reto de ascensi\u00f3n al Dhaulagiri por la complicaci\u00f3n de la pandemia. <a href=\"https:\/\/www.desnivel.com\/expediciones\/expediciones-alpinistas\/carlos-soria-en-poco-mas-de-un-ano-ha-habido-cambios-muy-grandes-en-los-ochomiles\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00abEn poco m\u00e1s de un a\u00f1o ha habido cambios muy grandes en los ochomiles\u00bb<\/a>. En ella Carlos comenta como hay gente que ha ascendido un ochomil y no sabe ni d\u00f3nde est\u00e1 o la p\u00e9rdida de la \u00e9tica en las ascensiones a los ochomiles.<\/li>\n\n\n\n<li>Y cerramos la secci\u00f3n tray\u00e9ndoos una noticia que nos dice mucho sobre la <strong>evoluci\u00f3n de los Pirineos con el cambio clim\u00e1tico<\/strong>. \u00ab<a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/huesca\/2021\/05\/26\/aragon-bautiza-a-los-nuevos-ibones-nacidos-del-cambio-climatico-1494863.html?\" target=\"_blank\" rel=\"noreferrer noopener\">Arag\u00f3n bautiza los 10 nuevos ibones nacidos del cambio clim\u00e1tico<\/a>\u00bb <em>(Heraldo)<\/em>. Aparecen nuevos ibones de la fusi\u00f3n de los glaciares, como la peque\u00f1a charca de hace una d\u00e9cada a los pies del Aneto que ahora ya cuenta con dimensiones considerables.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-20-mayo-2021\">Mi\u00e9rcoles, 20 mayo 2021<\/h3>\n\n\n\n<p><strong>Todxs para casa, en Nepal la pandemia est\u00e1 descontrolada<\/strong>.&nbsp;<a href=\"https:\/\/www.turiski.es\/%e2%96%b7-50-personas-entre-alpinistas-y-turistas-pendientes-de-regresar-de-nepal\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\">Alpinistas y turistas pendientes de volar desde Katmand\u00fa<\/a>&nbsp;<em>(Turiski)<\/em>. Un vuelo de Iberia que lleva ayuda humanitaria los traer\u00e1 de regreso \u2014<a href=\"https:\/\/twitter.com\/sebas_alvaro\/status\/1394936309869813760?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\">con billete pagado por ellos mismos<\/a>&nbsp;<em>(Twitter)<\/em>, que esto ha suscitado mucha pol\u00e9mica estas semanas en las redes sociales\u2014. China que comparte cima de Everest con Nepal&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/china-cierra-la-cara-norte-del-everest-por-temor-al-covid\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\">cierra la cara norte del Everest&nbsp;<\/a><em>(Desnivel)&nbsp;<\/em>por temor a contagios de Covid en la cima.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>&nbsp;<strong>Kilian Jornet&nbsp;<\/strong>y David G\u00f6ttler&nbsp;siguen \u2014contin\u00faan con su proyecto\u2014 a la espera de una ventana de buen tiempo. Su reto:&nbsp;<strong>Everest por la arista oeste<\/strong>&nbsp;y, aunque no lo han confirmado, posible intento posterior de traves\u00eda hasta el Lhotse. Concluyeron la fase de aclimataci\u00f3n con una galopada hasta rozar los 8000 m \u2014os lo cont\u00e1bamos la semana pasada\u2014. Ahora descansan, en la espera.<\/li>\n<\/ul>\n\n\n\n<p><em>\u201cDavid y yo nos quedamos en Pheriche mientras el mal tiempo est\u00e1 en las monta\u00f1as m\u00e1s altas, haciendo algunas carreras en esos hermosos valles.\u201d \u2014<a href=\"https:\/\/www.instagram.com\/kilianjornet\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\">Kilian Jornet<\/a><\/em><\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p dir=\"ltr\" lang=\"und\"><a href=\"https:\/\/t.co\/IGCv7cBHmp\">pic.twitter.com\/IGCv7cBHmp<\/a><\/p>\u2014 kilian jornet (@kilianj) <a href=\"https:\/\/twitter.com\/kilianj\/status\/1394714621932576773?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">May 18, 2021<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dejamos el Himalaya para hablar de los Pirineos. Te habr\u00e1s dado cuenta:<strong>&nbsp;la masificaci\u00f3n ha llegado para quedarse<\/strong>. El verano pasado el volumen de visitante en algunas zonas naturales lleg\u00f3 al l\u00edmite. Y esto tiene visos de continuar m\u00e1s all\u00e1 de la pandemia, tenemos una necesidad de escapar al aire libre. La medida:<a href=\"https:\/\/www.publico.es\/sociedad\/medidas-covid-masificacion-regulacion-acceso-montana-catalunya.html?fbclid=IwAR2J43eCrq4NBOAqukuccXOjDGqIV2QLcn9JyjUEpZoXCFvYPn270AvIyH8&amp;utm_campaign=web&amp;utm_medium=social&amp;utm_source=facebook\" target=\"_blank\" rel=\"noopener\">&nbsp;regulaci\u00f3n del acceso a la monta\u00f1a, es lo que se prev\u00e9 ya en Catalunya<\/a>&nbsp;<em>(P\u00fablico)<\/em>. \u201cCada vez son m\u00e1s los espacios naturales de Catalunya que anuncian medidas para limitar el volumen de visitantes\u201d.<\/li>\n\n\n\n<li>Este video de&nbsp;<em>FotoJuanma Aventura y Drone Romeo FJ<\/em>&nbsp;de la&nbsp;<strong>Faja de las Flores<\/strong>&nbsp;en Ordesa y Monte Perdido (aqu\u00ed os dejo un enlace con&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/faja-de-las-flores-en-ordesa\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\">informaci\u00f3n de la ruta<\/a>) nos ha puesto los dientes largos. \u201cVertiginosa, impactante y sobrecogedora.\u201d<\/li>\n<\/ul>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/haiTbEGVl_c\" title=\"YouTube video player\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-12-mayo-2021\">Mi\u00e9rcoles, 12 mayo 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Empezamos en el Himalaya, donde la situaci\u00f3n es muy complicada en el Dhaulagiri y Everest,<a href=\"https:\/\/cumbresmountainmagazine.com\/dhaulagiri-everest-sobrepasados-por-covid-19\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\">&nbsp;sobrepasados por evacuaciones y casos de Covid-19<\/a>&nbsp;<em>(Cumbres)<\/em>. En el&nbsp;<strong>Dhaulagiri&nbsp;<\/strong><a href=\"https:\/\/www.turiski.es\/stefi-troguet-abandona-el-dhaulagiri-por-positivo-de-covid-19\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\">Stefi Troguet&nbsp;ha sido evacuada&nbsp;<\/a>del campamento base&nbsp;<em>(Turiski)<\/em>&nbsp;y se encuentra confinada en una habitaci\u00f3n de hotel en Katmandu por positivo por Covid. Por su parte Carlos Soria y su equipo han decidido&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/expediciones-alpinistas\/carlos-soria-donde-mejor-estamos-es-en-el-campo-base-del-dhaulagiri\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\">esperar en el Campamento Base del Dhaulagiri, \u00abDonde mejor estamos\u00bb<\/a>&nbsp;<em>(Desnivel)<\/em>. En el&nbsp;<strong>Everest&nbsp;<\/strong>las cosas no est\u00e1n mejor, Alex Txikon y sus compa\u00f1eros de expedici\u00f3n dan por terminada su aventura,&nbsp;<a href=\"https:\/\/twitter.com\/AlexTxikon\/status\/1391710202051940354?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\">\u00abdamos por concluida la expedici\u00f3n por responsabilidad a la vista del avance de la pandemia\u00bb&nbsp;<\/a><em>(Txikon)<\/em>.<\/li>\n\n\n\n<li>Quienes contin\u00faan con el \u201cbaile\u201d son Horia Colibasanu, Peter H\u00e1mor y Marius Gane en su intento de&nbsp;<strong>nueva ruta en el Dhaulagiri por &nbsp;la arista noroeste<\/strong>.&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/horia-colibasanu-peter-hamor-y-marius-gane-sobreviven-a-una-avalancha-a-6-800-m-en-plena-noche\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\">A 6.800 metros una avalancha golpe\u00f3 la tienda donde pasaban la noche<\/a>&nbsp;<em>(Desnivel)&nbsp;<\/em>y tuvieron que refugiarse en una peque\u00f1a cueva para al d\u00eda siguiente alcanzar la seguridad del C1.<\/li>\n\n\n\n<li>\u00bf\u201c<strong>Helidoping<\/strong>\u201d?, bueno\u2026 \u00a1c\u00f3mo est\u00e1 el patio! La pol\u00e9mica de la semana ha sido el uso que se est\u00e1 haciendo las expediciones del helic\u00f3ptero, para transportar material y hasta personas entre campamentos de altura. Os comparto este interesante<a href=\"https:\/\/twitter.com\/KrisAnnapurna\/status\/1389930389150572551?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\">&nbsp;hilo de Twitter<\/a>:<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"twitter-tweet\"><p dir=\"ltr\" lang=\"es\">Tema de \u201cAviation Assisted Climb\u201d<br><br>Hilo<br><br>Hace dos d\u00edas visteis conmigo un v\u00eddeo de un fot\u00f3grafo que film\u00f3 que un helic\u00f3ptero que transport\u00f3 a gente del BC al C2 en el Everest.<br>Tambi\u00e9n sabemos que transportan cuerdas,O2 y dem\u00e1s v\u00edveres en helic\u00f3pteros hasta el C2.<br>\u2b07\ufe0f<\/p>\u2014 k2 (@KrisAnnapurna) <a href=\"https:\/\/twitter.com\/KrisAnnapurna\/status\/1389930389150572551?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">May 5, 2021<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfHas visto el video de Andrzej Bargiel y Jedrek Baranowski?: escalan y descienden en esqu\u00eds \u2014desde 150 metros por debajo de la cima por las condiciones\u2014 el&nbsp;<strong>Laila Peak<\/strong>.<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"twitter-tweet\"><p dir=\"ltr\" lang=\"en\">We&#8217;re delighted with J\u0119drek Baranowski that our Laila Peak adventure was a success. It is the first Polish ascent to Laila Peak! \ud83c\uddf5\ud83c\uddf1 Grab the video with a ski descent \u26f7<br>\ud83c\udfa5<a href=\"https:\/\/twitter.com\/gzelaeu?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@gzelaeu<\/a><br> <a href=\"https:\/\/twitter.com\/GrupaMurapol?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@GrupaMurapol<\/a> <a href=\"https:\/\/twitter.com\/totalizator_sp?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@totalizator_sp<\/a> <a href=\"https:\/\/twitter.com\/redbullpolska?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@redbullpolska<\/a> <a href=\"https:\/\/twitter.com\/MBPolska?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@MBPolska<\/a> <a href=\"https:\/\/twitter.com\/SalomonSports?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@SalomonSports<\/a> <a href=\"https:\/\/t.co\/mFLBqWWn2o\">pic.twitter.com\/mFLBqWWn2o<\/a><\/p>\u2014 Andrzej Bargiel (@JedrekBargiel) <a href=\"https:\/\/twitter.com\/JedrekBargiel\/status\/1392045406599663619?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">May 11, 2021<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/kilian-jornet-y-david-gottler-finalizan-la-fase-de-aclimatacion-para-su-everest\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\"><strong>Kilian Jornet y David G\u00f6ttler&nbsp;<\/strong>dan por concluida la fase de aclimataci\u00f3n para su Everest<\/a>&nbsp;<em>(Desnivel)<\/em>. Contentos tras el \u00faltimo d\u00eda de aclimataci\u00f3n en el que se acercaron a los 8000 metros en la pared del Lhotse saliendo desde el C2 (6.500m). Estaremos atentos al ataque a su objetivo: Everest por la arista oeste&nbsp;y, aunque no lo han confirmado, posible intento posterior de traves\u00eda hasta el Lhotse.<\/li>\n\n\n\n<li>Para terminar te planteo:&nbsp;<a href=\"https:\/\/www.20minutos.es\/noticia\/4054792\/0\/de-donde-viene-la-expresion-hace-un-frio-que-pela\/?autoref=true&amp;utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noopener\">\u00bfsabes de d\u00f3nde viene la expresi\u00f3n \u201chace un fr\u00edo que pela\u201d?<\/a>&nbsp;<em>(Telecinco)&nbsp;<\/em>Nos situamos en 1950 en el Annapurna, Maurice Herzog y Louis Lachenal coronaron la cima, pero d\u00edas despu\u00e9s un temporal hizo que las temperaturas cayeran empicado 15 grados. La comida se echo a perder, salvo unos kilos que llevaban de almendras \u2014<a href=\"https:\/\/travesiapirenaica.com\/comida-para-montana\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\">comida que nunca falta en la mochila<\/a>&nbsp;del monta\u00f1ero\u2014. La cuesti\u00f3n es que con el fr\u00edo que hac\u00eda se pelaban con mucha facilidad. As\u00ed que no era la piel lo que se pelaba, sino las almendras.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-5-mayo-2021\">Mi\u00e9rcoles, 5 mayo 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Os empezamos contando que Alex Txikon se encuentra ya en el campo base del Everest, intentar\u00e1 en 3 semanas ascender al Everest por al ruta cl\u00e1sica en la vertiente nepal\u00ed. Como compa\u00f1eros lleva al periodista I\u00f1aki Makazaga y el fot\u00f3grafo Sendoa Elejalde. &nbsp;Makazaga nos va contando todos los pormenores y experiencias que van viviendo en el podcast <a href=\"https:\/\/www.piedradetoque.es\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00abPiedra de toque\u00bb<\/a>.<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"twitter-tweet\"><p dir=\"ltr\" lang=\"es\">[NUEVO PODCAST] Primer d\u00eda en el campo base del <a href=\"https:\/\/twitter.com\/hashtag\/Everest?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Everest<\/a> con noche en el campo uno del Pumori con <a href=\"https:\/\/twitter.com\/AlexTxikon?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@alextxikon<\/a> y las principales cimas del Himalaya <br><br>Esc\u00fachalo aqu\u00ed <a href=\"https:\/\/t.co\/DC8TVRXlkQ\">https:\/\/t.co\/DC8TVRXlkQ<\/a> \ud83c\uddf3\ud83c\uddf5\u26f0<a href=\"https:\/\/twitter.com\/hashtag\/piedradetoque?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#piedradetoque<\/a> <a href=\"https:\/\/twitter.com\/trangoworld?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@trangoworld<\/a> <a href=\"https:\/\/t.co\/HKbZq6TFr5\">pic.twitter.com\/HKbZq6TFr5<\/a><\/p>\u2014 I\u00f1aki Makazaga (@imakazaga) <a href=\"https:\/\/twitter.com\/imakazaga\/status\/1389251449188618242?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">May 3, 2021<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y sin movernos del Himalaya, ya se ha confirmado el compa\u00f1ero de aventura de Kilian. <a href=\"https:\/\/www.desnivel.com\/expediciones\/kilian-jornet-y-david-gottler-ya-aclimatan-juntos-en-el-everest\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Kilian Jornet y David G\u00f6ttler ya aclimatan juntos en el Everest<\/a>&nbsp;<em>(Desnivel)<\/em>. El objetivo ascender el&nbsp;Everest por la arista oeste, y quien sabe si realizar la primera&nbsp;traves\u00eda Everest-Lhotse&nbsp;sin ox\u00edgeno.<\/li>\n<\/ul>\n\n\n\n<p><em>\u201cEstoy deseando volver a pisar un terreno de aire fino. Cuando @david_goettler me envi\u00f3 un mensaje de texto el a\u00f1o pasado no necesit\u00e1bamos muchas palabras para planear una escalada juntos. Una idea simple y una alta posibilidad de fracaso resumen perfectamente lo que estamos buscando durante las pr\u00f3ximas semanas en la regi\u00f3n del Khumbu.<\/em><\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p dir=\"ltr\" lang=\"en\">Looking forward to be back on thin air terrain. When @david_goettler texted me last year we didn\u2019t need much words to plan a climb together. A simple idea and a high possibility of faillure summarizes perfectly what we\u2019re searching during the next weeks in the Khumbu region. <a href=\"https:\/\/t.co\/MfWKdT2ndC\">pic.twitter.com\/MfWKdT2ndC<\/a><\/p>\u2014 kilian jornet (@kilianj) <a href=\"https:\/\/twitter.com\/kilianj\/status\/1388087342423056389?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">April 30, 2021<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y hoy cerramos secci\u00f3n de noticias cont\u00e1ndoos que \u201c<a href=\"https:\/\/www.noticiasdenavarra.com\/vivir-on\/que-mundo\/2021\/05\/04\/descubren-pirineo-ave-gigante-fosil\/1143029.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">descubren en el Pirineo un ave gigante f\u00f3sil que convivi\u00f3 con los \u00faltimos dinosaurios<\/a>\u201d<em>&nbsp;(Noticias)<\/em>. Hallada en el Pirineo aragon\u00e9s, convivi\u00f3 con los \u00faltimos dinosaurios de Europa antes de la gran extinci\u00f3n al final del Cret\u00e1cico.&nbsp;<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-28-abril-2021\">Mi\u00e9rcoles, 28 abril 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Empezamos la secci\u00f3n de noticias lamentando el&nbsp;<a href=\"https:\/\/www.eldiario.es\/internacional\/periodistas-espanoles-asesinados-ataque-burkina-faso_1_7874403.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>asesinato de los periodistas David Beriain y Roberto Fraile&nbsp;<\/strong>en un ataque en Burkina Faso<\/a>&nbsp;<em>(elDiario)<\/em>. Se encontraban all\u00ed trabajando en un documental sobre la caza furtiva en el pa\u00eds, cuando la patrulla en la que iban empotrados sufri\u00f3 una emboscada. Contando lo que no se cuenta.&nbsp;<a href=\"https:\/\/elpais.com\/espana\/2021-04-27\/david-beriain-el-mejor-periodista-mi-mejor-amigo.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Beriain&nbsp;<\/a>dirigi\u00f3 grandes documentales como \u2018El Ej\u00e9rcito Perdido de la CIA\u2019, \u2018La Vida en Llamas\u2019, \u2018Amazonas Clandestino\u2019, \u2018Yasun\u00ed\u2019, \u2018Genocidio en la Selva\u2019, y \u2018Clandestino\u2019.<\/li>\n\n\n\n<li>Del Himalaya os contamos que&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/david-gottler-apunta-a-companero-de-kilian-jornet-en-la-arista-oeste-del-everest\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">David G\u00f6ttler&nbsp;ser\u00e1 posiblemente compa\u00f1ero de Kilian Jornet<\/a>&nbsp;en la arista oeste del&nbsp;<strong>Everest&nbsp;<\/strong>y la traves\u00eda hacia el Lhotse. A\u00fan por confirmar por ambos. Y en el&nbsp;<strong>Dhaulagiri<\/strong>, en su arista noroeste,&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/horia-colibasanu-peter-hamor-y-marius-gane-superan-su-punta-de-altura-de-2019-en-la-arista-noroeste-del-dhaulagiri\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Horia Colibasanu, Peter H\u00e1mor y Marius Gane siguen progresando<\/a>&nbsp;muy satisfactoriamente&nbsp;<em>(Desnivel)<\/em>&nbsp;despu\u00e9s de haber afrontado la parte m\u00e1s dura de la l\u00ednea y haber superado ya el punto m\u00e1s alto al que llegaron en su expedici\u00f3n en 2019.<\/li>\n\n\n\n<li>A\u00f1o a a\u00f1o, suma y sigue. Nuevo&nbsp;<strong>r\u00e9cord de permisos en el Everest<\/strong>. A todos nos vienen a la mente las fotograf\u00edas de la temporada pasada de colas interminables para acceder a la cumbre.&nbsp;<a href=\"https:\/\/www.turiski.es\/el-everest-2021-camino-del-overbooking-y-la-masificacion\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Masificaci\u00f3n y \u2018overbooking\u2019<\/a><em>&nbsp;(Turiski)<\/em>. Frente a ello Nepal va a establecer&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/nepal-establece-turnos-para-subir-al-everest\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">turnos para subir<\/a>. A todo esto se une que el&nbsp;<strong>Covid&nbsp;<\/strong>circula a sus anchas por el CB. \u201c<a href=\"https:\/\/www.desnivel.com\/expediciones\/el-covid-prolifera-en-un-everest-con-record-de-permisos\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Cuatro personas han sido evacuadas por coronavirus<\/a>&nbsp;y se teme un brote en toda regla.\u201d<em>&nbsp;(Desnivel)<\/em><\/li>\n\n\n\n<li>Y hablando de masificaciones, en&nbsp;<strong>Ordesa se est\u00e1 trabajando en un plan de movilidad para evitar concentraciones<\/strong>. Se examinan \u201c<a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/huesca\/2021\/04\/26\/huesca-parque-ordesa-examina-aforos-de-vehiculos-y-zonas-de-aparcamiento-para-mejorar-su-movilidad-1487496.html?autoref=true&amp;utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">aforos de veh\u00edculos y zonas de aparcamiento<\/a>\u201d&nbsp;<em>(Heraldo)<\/em>. Se han detectado algunas deficiencias como que en el parking de la Pradera no existe sistema de reserva y no sabes si est\u00e1 lleno hasta que llegas o los problemas en zonas como Pineta o el Ca\u00f1\u00f3n de A\u00f1isclo.<\/li>\n\n\n\n<li>Y para terminar os compartimos el video de Javi Sancho que se ha hecho viral estos d\u00edas (<a href=\"https:\/\/www.instagram.com\/p\/CN8E_56A-dL\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Pod\u00e9is pinchar AQU\u00cd para verlo<\/a>).&nbsp;<strong>El \u2018runner\u2019 que se r\u00ede de los \u2018runners\u2019<\/strong>: \u201cPuestos a ofender, intentar\u00eda ofender a un colectivo que le costara pillarme, pero a los raners nunca, recordad que soy uno de los vuestros, os quiero.\u201d<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"instagram-media\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/tv\/CN8E_56A-dL\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"13\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/tv\/CN8E_56A-dL\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\"> Ver esta publicaci\u00f3n en Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/tv\/CN8E_56A-dL\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida de Javi Sancho #RedIsFaster (@javisancho.extreme)<\/a><\/p><\/div><\/blockquote> <script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-21-abril-2021\">Mi\u00e9rcoles, 21 abril 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Empezamos el repaso semanal de la actualidad sabiendo que&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/kilian-jornet-planea-volver-al-himalaya-para-intentar-la-travesia-everest-lhotse\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Kilian Jornet <\/strong>volver\u00e1 al Himalaya para intentar la traves\u00eda Everest-Lhotse<\/a><em>&nbsp;(Desnivel)<\/em>. Lo ponemos bajo contexto, se trata de uno de los grandes desaf\u00edos pendientes del himalayismo. Supondr\u00eda \u201csubir el Everest por la&nbsp;arista oeste, descender hasta el&nbsp;Collado Sur&nbsp;(C4 del Everest, a unos 8.000 metros), atacar directamente desde all\u00ed el Lhotse por la&nbsp;ruta Urubko&nbsp;de 2010, y terminar descendiendo por la&nbsp;ruta normal&nbsp;del Lhotse.\u201d&nbsp;<a href=\"https:\/\/www.getrevue.co\/profile\/travesia\/issues\/picos-solitarios-en-los-altos-pirineos-y-el-alto-garona-542638?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Hace un par de semanas<\/a>&nbsp;os cont\u00e1bamos que tambi\u00e9n el estadounidense Colin O\u2019Brady podr\u00eda intentar la traves\u00eda.<\/li>\n\n\n\n<li>En el <strong>Dhaulagiri <\/strong>todas las miradas est\u00e1n en c\u00f3mo progresa la expedici\u00f3n de Horia Colibasanu, Peter H\u00e1mor y Marius Gane a la virgen y kilom\u00e9trica arista noroeste. \u201c<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11195\/dhaulagiri-avanza-intento-apertura-kilometrica?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Abren con mucho esfuerzo la muralla que da acceso a la arista<\/a>\u201d&nbsp;<em>(Barrabes)<\/em>. Ya lo intentaron en 2019. Por otro lado, Carlos Soria llega al campo base para su nuevo intento de alcanzar la cima a los 82 a\u00f1os.<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"twitter-tweet\"><p dir=\"ltr\" lang=\"es\">Pasamos nuestro primer d\u00eda en el campo base comenzando a hacer planes para alcanzar la so\u00f1ada cima del Dhaulagiri. Os lo contamos en este v\u00eddeo <a href=\"https:\/\/twitter.com\/Telefonica?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@Telefonica<\/a> <a href=\"https:\/\/twitter.com\/movistarlikes?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@movistarlikes<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Ignis_Energia?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Ignis_Energia<\/a> <a href=\"https:\/\/twitter.com\/IGME1849?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@IGME1849<\/a> <a href=\"https:\/\/twitter.com\/panasonicESP?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@panasonicESP<\/a> <a href=\"https:\/\/twitter.com\/txlab?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@txlab<\/a> <a href=\"https:\/\/t.co\/tFxGS1HpDW\">https:\/\/t.co\/tFxGS1HpDW<\/a><\/p>\u2014 Carlos Soria (@RetoCarlosSoria) <a href=\"https:\/\/twitter.com\/RetoCarlosSoria\/status\/1384153835606732801?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">April 19, 2021<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Una de las haza\u00f1as de escalada en Patagonia m\u00e1s recientes ha sido la <strong>Traves\u00eda del Fitz Roy<\/strong> en solitario&nbsp;realizada en febrero por el alpinista belga <strong>Sean Villanueva<\/strong>, bautizada \u201cMoonwalk Traverse\u201d. Patagonia nos comparte el video del \u201cmaking off\u201d de esta gran aventura.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Moonwalking | Behind the scenes of Sean Villanueva\u2019s solo Fitz Roy traverse\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/85CG527AST0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y cerramos la secci\u00f3n cont\u00e1ndote que&nbsp;<a href=\"https:\/\/viajes.nationalgeographic.com.es\/lifestyle\/google-earth-se-renueva-para-ser-mas-consciente-planeta_16723\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u201cGoogle Earth se renueva para ser m\u00e1s consciente con el Planeta\u201d<\/a>&nbsp;<em>(Viajes Natgeo)&nbsp;<\/em>y pone en marcha una nueva funcionalidad en la herramienta,&nbsp;<em><strong>Timelapse<\/strong><\/em>, con la que puedes ver la evoluci\u00f3n de las im\u00e1genes de lugares y ser conscientes de la emergencia clim\u00e1tica.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-14-abril-2021\">Mi\u00e9rcoles, 14 abril 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Empezamos las secci\u00f3n acerc\u00e1ndonos al Himalaya, y m\u00e1s concretamente al&nbsp;<strong>Dhaulagiri<\/strong>. All\u00ed se encuentran&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11185\/dhaulagiri-ruta-sin-equipar-jonatan?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Jonatan Garc\u00eda, Stefi Troguet, Carla P\u00e9rez&nbsp;y&nbsp;Esteban \u201cTopo\u201d Mena&nbsp;que han abierto huella y ruta hasta el campo 1<\/a>&nbsp;<em>(Barrabes)<\/em>. Dos expediciones que comparten aclimataci\u00f3n tras coincidir en el campo base. Jonatan y Stefi tienen en mente la ruta normal, Carla y Estevan, cuyas intenciones estaban en la larga arista noroeste, se pasan tambi\u00e9n a la ruta normal tras la<a href=\"https:\/\/www.desnivel.com\/expediciones\/cory-richards-renuncia-a-la-arista-noroeste-del-dhaulagiri\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;renuncia de su tercer integrante del equipo, el estadounidense Cory Richards, al intento de la arista y la expedici\u00f3n<\/a>&nbsp;<em>(Desnivel)<\/em>. Por su parte,&nbsp;<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11186\/carlos-soria-finaliza-su-aclimatacion?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Carlos Soria ha finalizado su aclimataci\u00f3n en el valle de Khumbu&nbsp;<\/a>y se acercar\u00e1 a la monta\u00f1a para su nuevo intento al Dhaulagiri\u00bb&nbsp;<em>(Barrabes)<\/em>.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.revistaoxigeno.es\/actualidad\/omar-di-felice-primero-en-llegar-campo-base-everest-en-bicicleta-en-invierno_231123_102.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Primero en llegar al Campo Base Everest en bici y en invierno<\/a>&nbsp;<em>(Ox\u00edgeno)<\/em>. El ultraciclista italiano Omar di Felice pone as\u00ed fin a su reto despu\u00e9s de 19 d\u00edas y 1.294 km en bicicleta de monta\u00f1a desde la capital de Nepal, Katmand\u00fa, y el campo base del Everest. En el siguiente video nos hace un repaso del equipo de&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/bikepacking\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">bikepacking&nbsp;<\/a>que ha utilizado para su aventura.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Bikepacking equipment for Himalaya Winter adventure\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/rBeQtmw3q5c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.elmundo.es\/ciencia-y-salud\/medio-ambiente\/2021\/04\/07\/606b4ff1fc6c8381278b45fb.html?fbclid=IwAR3VjK5aI5jcXoBRwqLQNJlkLFzCLbgYD7GdhCASrpsiuazx9ZWZaYtDZQY&amp;utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">El oso vuelve al Pirineo: un \u2018boom\u2019 de natalidad eleva la poblaci\u00f3n a su nivel m\u00e1s alto en un siglo<\/a><em>&nbsp;(El mundo)<\/em>. La especie en peligro de extinci\u00f3n sigue creciendo en los \u00faltimos tiempos. El a\u00f1o pasado se censaron 64 ejemplares y en ese tiempo nacieron 16 nuevas cr\u00edas.<\/li>\n\n\n\n<li>Que las monta\u00f1as se est\u00e1n masificando no es noticia: lo estamos viendo de excursi\u00f3n en excursi\u00f3n, y tambi\u00e9n nosotros hacemos n\u00famero. Eso es as\u00ed\u2026 Empiezan as\u00ed a endurecerse las restricciones en algunos parques del Pirineo.&nbsp;<a href=\"https:\/\/www.elperiodico.com\/es\/en-ruta-catalunya\/20210408\/parque-natural-alt-pirineu-regula-afluencia-turistas-verano-11643270?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">El Parque Natural del Alt Pirineu regular\u00e1 la afluencia de turistas este verano<\/a>&nbsp;<em>(El Peri\u00f3dico).&nbsp;<\/em>Con objeto de evitar la masificaci\u00f3n y los riesgos que todo ello pueda traer se implementar\u00e1n estrictas medidas.<\/li>\n\n\n\n<li>\u00bfSab\u00edas que el nombre Mont Blanc viene de&nbsp;<em>Montis Albis<\/em>, que hace referencia a \u2018monta\u00f1a nevada\u2019 o \u2018monta\u00f1a calc\u00e1rea\u2019? \u00bfO qu\u00e9 el origen de monte Elbr\u00fas se remonta al griego antiguo? En este art\u00edculo&nbsp;<em>National Geographic<\/em>&nbsp;nos descubre&nbsp;<a href=\"https:\/\/viajes.nationalgeographic.com.es\/lifestyle\/este-es-origen-nombre-montanas-mas-emblematicas-mundo_16679?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">el origen del nombre de las monta\u00f1as m\u00e1s emblem\u00e1ticas del mundo<\/a>, \u201cque hablan de su historia y que mezclan tradici\u00f3n, mitolog\u00eda y aventura\u201d.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-7-abril-2021\">Mi\u00e9rcoles, 7 abril 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/colin-obrady-intentara-el-everest-y-lhotse-sin-oxigeno\/\" target=\"_blank\" rel=\"noreferrer noopener\">Colin O\u2019Brady intentar\u00e1 el Everest y Lhotse sin ox\u00edgeno<\/a> <em>(Desnivel)<\/em>. En el \u00abtintero\u00bb queda si intentar\u00e1 el doblete o la traves\u00eda entre ambas monta\u00f1as, a\u00fan pendiente en el himalayismo, y que implica la ascensi\u00f3n y descenso por rutas diferentes.<\/li>\n\n\n\n<li>En 1965 Walter Bonatti abr\u00eda la v\u00eda directa en solitario a la norte del Cervino\/Matterhorn, y se retiraba \u00ab<a href=\"https:\/\/www.desnivel.com\/cultura\/22-febrero-1965-walter-bonatti-abre-norte-cervino-en-solitario-y-abandona-el-alpinismo\/\" target=\"_blank\" rel=\"noreferrer noopener\">como un cantante que se retira despu\u00e9s de su mejor concierto<\/a>\u00ab<em> (Desnivel)<\/em>. Un itinerario que representa parte de la historia de la monta\u00f1a y una de las rutas m\u00e1s espectaculares y complejas del alpinismo. Ahora los italianos&nbsp;Fran\u00e7ois Cazzanelli, Francesco Ratti y Matteo Della Bordella&nbsp;completan la emblem\u00e1tica v\u00eda Bonatti homenajeando a su admirado compatriota. \u00ab<a href=\"https:\/\/cumbresmountainmagazine.com\/italianos-via-bonatti-cara-norte-cervino\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tres italianos logran en el d\u00eda la v\u00eda Bonatti en la cara Norte del Cervino<\/a>\u00bb <em>(Cumbres)<\/em>. Lo hicieron en 16 horas.<\/li>\n\n\n\n<li>\u00bfHab\u00e9is visto el <a href=\"https:\/\/youtu.be\/p8NrGr3AbuY\" target=\"_blank\" rel=\"noreferrer noopener\">descenso en kayak de Aniol Serrasolses desde la cima del volc\u00e1n en Chile?<\/a><em>(Youtube)<\/em>. 25 kil\u00f3metros en kayak desde la cumbre del volc\u00e1n nevado Villarica, en la regi\u00f3n de la Araucan\u00eda, Chile, a trav\u00e9s de un bosque que culmina en un lago donde tambi\u00e9n consigue realizar la primera doble <em>kickflip <\/em>del mundo en kayak.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Kayaking At 100km\/h On Snow\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/p8NrGr3AbuY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La pol\u00e9mica est\u00e1 servida con las nuevas medidas (la Ley 2\/2021 en su art\u00edculo 6) sobre el&nbsp;<strong>uso obligatorio de las mascarillas en espacios al aire libre<\/strong>. No han tardado en surgir las discrepancias. \u201c<a href=\"https:\/\/www.marca.com\/deportes-aventura\/2021\/04\/03\/60686dee46163f6a5c8b45a1.html?fbclid=IwAR3BpSulc7q0bsTirjNY_iy50r4hJku7SYuoVDtFVDl&amp;utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Con la nueva normativa, un grupo de&nbsp;alpinistas en alta monta\u00f1a, un grupo de&nbsp;barranquistas&nbsp;cuando desciende un barranco o una&nbsp;cordada de escaladores, entre otros, todos y cada uno de ellos deber\u00eda usar la mascarilla.<\/a>\u201d&nbsp;<em>(Marca)<\/em>.&nbsp;<\/li>\n\n\n\n<li>Tambi\u00e9n pol\u00e9mico est\u00e1 siendo el nuevo proyecto previsto en el Pirineo de Huesca. \u201c<a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/huesca\/2021\/04\/03\/panticosa-proyecta-el-primer-tobogan-alpino-del-pais-con-2-6-kilometros-1482400.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Panticosa proyecta el primer tobog\u00e1n alpino de Espa\u00f1a de 2,7 kil\u00f3metros<\/a>\u201d (Heraldo). Con comentarios en las redes sociales como: \u201cSe empieza con unas pasarelas tur\u00edsticas de pago, se sigue con una tirolina a 150 por hora, ahora un tobog\u00e1n de casi 3km, suma y sigue. El pirineo se va convertir en propiedad de empresarios con parques de atracciones\u201d<em>&nbsp;(Facebook: AMIG@S de los PIRINEOS)<\/em>. De tirolinas a toboganes y tiro por que me toca.<\/li>\n\n\n\n<li>Y para cerrar con peor gusto \u2014si es que hay d\u00edas que no se pueden leer las noticias\u2026\u2014 os compartimos este art\u00edculo de&nbsp;<em>El Pa\u00eds<\/em>&nbsp;sobre los planes de Aram\u00f3n para Cerler. \u201c<a href=\"https:\/\/elpais.com\/clima-y-medio-ambiente\/2021-04-06\/la-estacion-de-esqui-de-pirineos-que-no-hace-caso-del-cambio-climatico.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">La estaci\u00f3n de esqu\u00ed de Pirineos que no hace caso del cambio clim\u00e1tico<\/a>\u201d. Ampliar las pistas de Cerler en 23 kil\u00f3metros pese a que la temperatura en los Pirineos aumenta m\u00e1s que la media mundial y los d\u00edas de nieve se reducen.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-31-marzo-2021\">Mi\u00e9rcoles, 31 marzo 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.zegama-aizkorri.com\/noticias\/265-2021-suspendido?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">En 2021 tampoco se realizar\u00e1 la Zegama-Aizkorri<\/a>. Se ten\u00eda previsto celebrar el 6 de junio. Se suspende tras analizar la actual situaci\u00f3n sanitaria y decidir que una carrera sin p\u00fablico no era lo mismo. \u201cS\u00f3lo una carrera con \u00e9lite no estar\u00eda dentro de nuestros valores, una Zegama sin p\u00fablico no tendr\u00eda ning\u00fan encanto\u201d&nbsp;<em>(Zegama-Aizkorri)<\/em>.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/las-expediciones-mas-interesantes-de-la-primavera-2021-en-el-himalaya\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">El Dhaulagiri y el Annapurna concentrar\u00e1n buena parte de la atenci\u00f3n ochomil\u00edstica esta primavera<\/a>&nbsp;<em>(Desnivel)<\/em>. En el Annapurna se espera el intento de Marc Batard en su plan de preparaci\u00f3n de la ascesi\u00f3n al Everest sin ox\u00edgeno. Tambi\u00e9n se espera al alpinista y esquiador franc\u00e9s Yoric Vion que tiene como objetivo la ascensi\u00f3n del Annapurna&nbsp;y su descenso en esqu\u00eds. En el Dhaulagiri habr\u00e1 intento a la arista noroeste a cargo de dos expediciones. En la ruta normal adem\u00e1s de otras expediciones estar\u00e1n Carlos Soria en su nuevo intento de ascensi\u00f3n a la edad de 82 a\u00f1os y la cordada formada por Jonatan Garc\u00eda y Stefi Troguet.<\/li>\n\n\n\n<li>Interesante la&nbsp;<a href=\"https:\/\/youtu.be\/3DcEhqMWPdM?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">charla de Adam Ondra y Alex Honnold&nbsp;<\/a><em>(Youtube)&nbsp;<\/em>hablando sobre escalada y grandes paredes que el propio Adam nos compart\u00eda en su canal de youtube.&nbsp;<a href=\"https:\/\/www.desnivel.com\/escalada-roca\/escaladores\/alex-honnold-y-adam-ondra-charlan-sobre-escalada\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">En&nbsp;<em>\u201cDesnivel\u201d&nbsp;<\/em>han rescatado las ideas m\u00e1s destacadas de la misma<\/a>. \u201c\u00bfConoces los&nbsp;<em>tepuys&nbsp;<\/em>de Venezuela? Grandes muros desplomados, escalada cl\u00e1sica dura\u2026 creo que ser\u00eda un desaf\u00edo para ambos.\u201c<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Adam Ondra and Alex Honnold talk | Sport climbing and big walls climbing\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/3DcEhqMWPdM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.revistaoxigeno.es\/rutas\/guia-sentiero-italia-trekking-mas-largo-mundo-gratis-online_230373_102.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">La gu\u00eda del<em>&nbsp;Sentiero Italia<\/em>, el trekking m\u00e1s largo del mundo<\/a>&nbsp;<em>(Revista Ox\u00edgeno)<\/em>. El<em>&nbsp;Sentiero Italia<\/em>&nbsp;es la alta v\u00eda que recorre todas las cordilleras de Italia, el&nbsp;sendero m\u00e1s largo del mundo, un&nbsp;recorrido de 7.000 km&nbsp;que une todo el \u201c<em>Bel Paese<\/em>\u201d, incluidas las islas, a trav\u00e9s de sus cordilleras. \u201c<em>Va\u2019 Sentiero<\/em>&nbsp;nace del sue\u00f1o de 3 chicos que se unen por el amor por las monta\u00f1as de su pa\u00eds\u201d<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>15 MESES DE CAMINATA, DESCUBRIENDO&nbsp;<em>SENTIERO ITALIA<\/em>. CAMINAR, DESCUBRIR, COMPARTIR:&nbsp;<em><a href=\"https:\/\/www.vasentiero.org\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">VA\u2019 SENTIERO<\/a><\/em> ES MUCHO M\u00c1S QUE UN VIAJE.ES UN NUEVO ACERCAMIENTO A LA MONTA\u00d1A, LA SEMILLA DE UN CAMBIO, EL PRIMER PASO DE UN LARGO VIAJE.<\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-24-marzo-2021\">Mi\u00e9rcoles, 24 marzo 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/youtu.be\/XZQGmUC__Es?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Iker Pou encadena Guggen-Hell 9a+\/9b<\/a>. Esta vez ha sido Iker el que nos vuelve a sorprender con una nueva realizaci\u00f3n al m\u00e1s alto nivel, con la primera ascensi\u00f3n de \u201cGUGGENHELL\u201d en Mallorca, para la que propone una dificultad de 9a+\/b&nbsp;<em>(Youtube).&nbsp;<\/em>En el siguiente video pod\u00e9is verle tirando de monodedos en una ruta imposible.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"IKER POU ENCADENA GUGGEN-HELL 9a+\/9b\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/XZQGmUC__Es?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Y sorprendente tambi\u00e9n es la escalada en solitario de Herv\u00e9 Barmasse en los Alpes.&nbsp;<a href=\"https:\/\/www.desnivel.com\/alpinismo\/herve-barmasse-escala-su-sexta-arista-en-solitario-al-cervino\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Herv\u00e9 Barmasse escala su sexta arista en solitario al Cervino&nbsp;<\/a><em>(Desnivel)<\/em>. En este art\u00edculo nos habla de la importancia de esta monta\u00f1a para \u00e9l, el Cervino, y como cierra un c\u00edrculo con esta ascensi\u00f3n. \u00abNo estoy de acuerdo con quien piensa que escalando en solitario desprecias la vida\u00bb<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>No emprend\u00ed esta escalada con la presunci\u00f3n de traer a casa un r\u00e9cord, sino con la necesidad espont\u00e1nea de tallar mi tiempo; mi momento fugaz que recog\u00ed con ambas manos para vivir profundamente a trav\u00e9s del monta\u00f1ismo solitario que da conocimiento y conciencia. \u2014<a href=\"https:\/\/www.instagram.com\/p\/CMkeMhjDPAt\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><em>@<\/em>hervebarmasse (<em>Instagram)<\/em><\/a><\/p>\n<\/blockquote>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Freeride<\/em>: \u201c<a href=\"https:\/\/www.turiski.es\/aymar-navarro-vuela-en-el-xtreme-verbier-y-consigue-podio-historico\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Aymar Navarro vuela en el Xtreme Verbier y consigue podio hist\u00f3rico<\/a>\u201d&nbsp;<em>(Turiski)<\/em>. Las im\u00e1genes volando sobre las rocas quiz\u00e1s las hayas visto en alguna televisi\u00f3n, sino&nbsp;<a href=\"https:\/\/www.eurosport.es\/free-ride\/no-apto-para-cardiacos-el-espectacular-descenso-del-espanol-aymar-navarro_vid1452743\/video.shtml?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed te lo dejamos<\/a>. Para conocer algo m\u00e1s la actividad de Aymar puedes ver esta cinta de 2018, \u201c<strong>South Lines\u201d<\/strong>, de la aventura de Aymar Navarro y Txema Trull a trav\u00e9s de Los Andes en su viaje anual al invierno austral de Sudam\u00e9rica buscando l\u00edneas de infarto.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"South Lines powered by KAYAK (2018) - Full Film\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/D_hrvsft_gY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Supongo que buscando \u00e9xitos tipo \u201c<a href=\"https:\/\/travesiapirenaica.com\/caminito-del-rey\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Caminito del Rey<\/a>\u201d o las m\u00e1s cercanas de Alquezar, \u201c<a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/huesca\/2021\/03\/20\/panticosa-abrira-el-27-de-marzo-las-nuevas-pasarelas-colgantes-sobre-el-rio-caldares-1479276.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Panticosa abrir\u00e1 el 27 de marzo las nuevas pasarelas colgantes sobre el r\u00edo Caldar\u00e9s<\/a>\u201d&nbsp;<em>(Heraldo)<\/em>. Acceso limitado y entrada de 4 euros (1 para federados). \u00bfQu\u00e9 opinas de este af\u00e1n por turistizar entornos naturales de dif\u00edcil acceso \u2014y gran belleza\u2014?<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En las redes:<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"twitter-tweet\"><p dir=\"ltr\" lang=\"es\">\u00bfBonito este rinc\u00f3n de monta\u00f1a, verdad? Es Basib\u00e9, en el Pirineo de Huesca.<br>Pues est\u00e1 siendo (va a ser) destruido para ampliar la estaci\u00f3n de esqu\u00ed de Cerler hacia Castanesa.<br>Mientras en Guadarrama desmantelan pistas de esqu\u00ed, aqu\u00ed en Arag\u00f3n, Aram\u00f3n avanza \u2620\ufe0f.<a href=\"https:\/\/twitter.com\/hashtag\/SalvemosCastanesa?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#SalvemosCastanesa<\/a> <a href=\"https:\/\/t.co\/mODQQt6SWk\">pic.twitter.com\/mODQQt6SWk<\/a><\/p>\u2014 Eduardo Vi\u00f1uales (@EduVinuales) <a href=\"https:\/\/twitter.com\/EduVinuales\/status\/1369212501347467265?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">March 9, 2021<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"jueves-18-marzo-2021\">Jueves, 18 marzo 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La serie documental \u201c<a href=\"https:\/\/www.rtve.es\/m\/alacarta\/videos\/rescate\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Rescate<\/a>\u201d de RTVE est\u00e1 teniendo un gran \u00e9xito entre la comunidad monta\u00f1era. 13 episodios \u2014vamos en el 10\u2014 en el que vivimos \u201c&nbsp;<a href=\"https:\/\/www.rtve.es\/rtve\/20210110\/2-estrena-rescate-serie-muestra-trabajo-equipos-guardia-civil-montana\/2064080.shtml?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">la intensidad, emoci\u00f3n y el peligro que envuelven las intervenciones de los profesionales m\u00e1s preparados para afrontar los rescates en dif\u00edciles situaciones en la monta\u00f1a.<\/a>\u201d&nbsp;<em>(RTVE)<\/em>&nbsp;En esta publicaci\u00f3n&nbsp;<em>(el Peri\u00f3dico)<\/em>&nbsp;<a href=\"https:\/\/www.elperiodicodearagon.com\/noticias\/deportes\/asi-hizo-rescate_1455033.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">su creador Daniel Salas nos cuenta \u201cc\u00f3mo se gest\u00f3\u201d y como documentaron el trabajo del&nbsp;Grupo de Rescate Especial de Intervenci\u00f3n en Monta\u00f1a<\/a>&nbsp;(GREIM)&nbsp;y el&nbsp;Servicio A\u00e9reo (SAER)&nbsp;que, apoyados por los m\u00e9dicos del 061, forman uno de los modelos de rescate m\u00e1s avanzados de Europa. \u00abNo quer\u00edamos falsear nada, solo contar historias reales\u00bb.<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"twitter-tweet\"><p dir=\"ltr\" lang=\"es\">\ud83d\ude81\u26f0\ufe0f Antes de ir a la monta\u00f1a es importante planificar y preparar bien la ruta para evitar posibles imprevistos que puedan provocar accidentes.<a href=\"https:\/\/twitter.com\/hashtag\/RescateRTVE?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#RescateRTVE<\/a>, ma\u00f1ana a las 20:15 h en <a href=\"https:\/\/twitter.com\/la2_tve?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@la2_tve<\/a> <a href=\"https:\/\/t.co\/LUOrJUcheC\">pic.twitter.com\/LUOrJUcheC<\/a><\/p>\u2014 RTVE Comunicaci\u00f3n (@RTVE_Com) <a href=\"https:\/\/twitter.com\/RTVE_Com\/status\/1370690349635538949?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">March 13, 2021<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201c<a href=\"https:\/\/www.turiski.es\/son-necesarias-medidas-para-regular-el-acceso-rodado-a-la-montana\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">\u00bfSon necesarias medidas para regular el acceso rodado a la monta\u00f1a?<\/a>\u201d&nbsp;<em>(Turiski)&nbsp;<\/em><a href=\"https:\/\/twitter.com\/GuinovartXevi?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Xevi Guinovart&nbsp;<\/a>analiza \u201cel por qu\u00e9 se llega a este punto y porqu\u00e9 \u2014piensa\u2014 que se debe regular\u201d. En el \u00faltimo a\u00f1o m\u00e1s que nunca hemos necesitado salir a la monta\u00f1a a tomar, nunca mejor dicho, aire sano. Quiz\u00e1s buscando un lugar \u201cseguro\u201d no masificado, que no hemos encontrado. A esto hay que a\u00f1adir el poco respeto que tenemos por el entorno natural y que queremos ir en coche \u201chasta el final de los finales\u201d. Personalmente me he encontrado lugares que no esperaba hasta los \u201ctopes\u201d de coches. \u00bfC\u00f3mo lo solucionamos? Todo el mundo tiene derecho a ir a la monta\u00f1a, eso por delante, pero con respeto. Buen debate.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Qu\u00e9 nos est\u00e1 pasando con las tirolinas\u2026 \u201c<a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/huesca\/2021\/03\/15\/abren-la-nueva-tirolina-ordesa-pirineo-que-alcanzara-entre-130-y-160-km-h-1477973.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Abren la nueva tirolina Ordesa Pirineo, que alcanzar\u00e1 entre 130 y 160 km\/h<\/a>\u201d&nbsp;<em>(Heraldo)<\/em>. Esto dar\u00eda para otro debate: por qu\u00e9 hacer de la monta\u00f1a un parque de atracciones\u2026<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfCu\u00e1nto estar\u00edas dispuesto a pagar por unas zapatillas? \u201c<a href=\"https:\/\/carrerasdemontana.com\/2021\/03\/16\/nike-moon-shoes\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>NIKE MOON SHOES<\/strong>, la ic\u00f3nica zapatilla ol\u00edmpica de 1972 , a subasta desde 150.000$.<\/a>\u201d&nbsp;<em>(Carreras de Monta\u00f1a)<\/em>&nbsp;Mayayo Ox\u00edgeno nos cuenta que ya por la subasta del \u00faltimo par en 2019 se abonaron 427.500$. Qui\u00e9n tuviera un para de esas, \u00bfeh? \ud83d\ude09<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-10-marzo-2021\">Mi\u00e9rcoles, 10 marzo 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arrancamos las noticias de esta semana conociendo que \u201c<a href=\"https:\/\/cumbresmountainmagazine.com\/nepal-prohibe-publicar-fotos-de-everest\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Nepal proh\u00edbe publicar fotos de Everest<\/a>\u201d, de otras personas, sin permiso oficial&nbsp;<em>(Cumbres)<\/em>. Nada tiene que entrometerse en el negocio que representa la cumbre m\u00e1s alta del planeta, y las im\u00e1genes de la \u00faltima temporada con filas interminables y \u201cestercoleros\u201d en los campamentos son publicidad muy negativa que se quiere evitar.<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"twitter-tweet\"><p dir=\"ltr\" lang=\"es\">En efecto, esa es la esencia de lo que est\u00e1 en juego: la monta\u00f1a m\u00e1s alta del planeta convertida en un gran negocio de unos pocos mientras sufre los devastadores efectos de la contaminaci\u00f3n y masificaci\u00f3n&#8230; Una verg\u00fcenza <a href=\"https:\/\/t.co\/FpewuKsVH7\">https:\/\/t.co\/FpewuKsVH7<\/a><\/p>\u2014 Sebastian Alvaro (@sebas_alvaro) <a href=\"https:\/\/twitter.com\/sebas_alvaro\/status\/1369646260433616902?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">March 10, 2021<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p>Este tema fue muy comentado en la \u00faltima semana en las redes. Junto al avance en la instalaci\u00f3n de antenas 5G en la vertiente norte. En abril del a\u00f1o pasado conoc\u00edamos que \u201c<a href=\"https:\/\/www.xataka.com\/energia\/hay-5g-everest-china-mobile-huawei-instalan-nuevas-antenas-cima-montana-alta-mundo?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">ya (hab\u00eda) 5G en el Everest<\/a>\u201d&nbsp;<em>(Xataka).&nbsp;<\/em>China Telecom explicaba que \u201cpermitir\u00e1 realizar emisiones en directo en alta calidad y poder retransmitir v\u00eddeos en 4K y 360 grados de la cima\u201d. Y me asalta la siguiente pregunta: \u00bfQu\u00e9 veremos esta temporada en el Everest? Espect\u00e1culo donde no lo debiera haber, al menos de esta forma.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p dir=\"ltr\" lang=\"en\">Interactive deep zooming 360\u00b0 drone photography of Mt. <a href=\"https:\/\/twitter.com\/hashtag\/Everest?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Everest<\/a> (8848.86 m) by Renan Oztruk. <a href=\"https:\/\/t.co\/UldZnwMbRL\">https:\/\/t.co\/UldZnwMbRL<\/a> <a href=\"https:\/\/t.co\/bbTyGFQAWZ\">pic.twitter.com\/bbTyGFQAWZ<\/a><\/p>\u2014 Everest Today (@EverestToday) <a href=\"https:\/\/twitter.com\/EverestToday\/status\/1368057497819381766?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">March 6, 2021<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Saltamos de continente para ver que \u201c<a href=\"https:\/\/www.revistaoxigeno.es\/actualidad\/kilimanjaro-tendra-teleferico_228785_102.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">avanzan los planes para instalar un telef\u00e9rico en el Kilimanjaro<\/a>\u201d&nbsp;<em>(Ox\u00edgeno)<\/em>. Se ha aprobado en Tanzania el plan para instalar un telef\u00e9rico en la cumbre m\u00e1s alta de \u00c1frica. Imagina ir subiendo por al ruta Machame y ver a tu lado un cable y turistas con c\u00e1mara en mano sac\u00e1ndote fotos mientras te falta el aliento. Un desprop\u00f3sito, \u00bfno?\u2026<\/li>\n\n\n\n<li>Cambiamos de tercio. Los Juegos Ol\u00edmpicos Tokio 2020 en 2021, ya tienen cerrada la lista de participantes. \u201c<a href=\"https:\/\/www.barrabes.com\/blog\/noticias\/2-11157\/juegos-olimpicos-tokio-2020_1-lista?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">20 mujeres y 20 hombres, entre ellos Adam Ondra, Jakob Schubert, Alex Megos, Alberto Gin\u00e9s, Laura Rogora, Julia Chanourdie<\/a>\u201d&nbsp;<em>(Barrabes)<\/em>. Se contemplan tres pruebas dificultad, b\u00falder y velocidad. La fechas de celebraci\u00f3n ir\u00e1n del 23 de julio y 8 de agosto \u2014salvo nuevos cambios por la incertidumbre pand\u00e9mica\u2014.<\/li>\n\n\n\n<li>Inici\u00e1bamos esta&nbsp;<em>newsletter&nbsp;<\/em>hablandode las ganas que ten\u00edamos que se abrieran las fronteras para poder ir al Pirineo sin restricciones. Y la cerramos pidiendo responsabilidad. \u201c<a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/huesca\/2021\/03\/08\/denunciado-por-saltarse-el-confinamiento-el-esquiador-sevillano-rescatado-en-benasque-1476194.html?autoref=true&amp;utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Denunciado por saltarse el confinamiento el esquiador (de otra comunidad) rescatado en Benasque<\/a>\u201d (Heraldo).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-03-marzo-2021\">Mi\u00e9rcoles, 03 marzo 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/alex-txikon-pone-fin-a-la-expedicion-invernal-al-manaslu\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Alex Txikon y el resto del equipo ponen fin a la expedici\u00f3n invernal al Manaslu<\/a>&nbsp;<em>(Desnivel)<\/em>. La semana pasada os cont\u00e1bamos que Simone Moro abandonaba ante las previsiones de mal tiempo hasta el final del invierno. No pudo ser. En el siguiente video el propio Txikon nos lo explica&nbsp;<em>(Youtube)<\/em>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"(28\/02\/2021) Manaslu Eki llega a su fin.\" width=\"720\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/6GUombI3VMI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El planeta sigue advirti\u00e9ndonos. Esta vez&nbsp;<a href=\"https:\/\/www.nationalgeographic.com.es\/naturaleza\/iceberg-doble-superficie-que-madrid-se-desprende-antartida_16517?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">un gigantesco bloque de hielo del doble de superficie que Madrid se desprende de la Ant\u00e1rtida<\/a>&nbsp;<em>(NatGeo).<\/em> <\/li>\n\n\n\n<li><a href=\"https:\/\/rockandice.com\/climbing-news\/tenzing-norgay-biography-to-become-netflix-film\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">La biograf\u00eda de Tenzing Norgay se convertir\u00e1 en una pel\u00edcula de Netflix<\/a>&nbsp;<em>(Rock and Ice)<\/em>. La biograf\u00eda de Ed Douglas sobre Tenzing Norgay, \u201c<a href=\"https:\/\/amzn.to\/3beISlO?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Tenzing Norgay: H\u00e9roe del Everest<\/em><\/a>\u201d, ser\u00e1 adaptada para Netflix. El libro documenta la vida del alpinista sherpa que realiz\u00f3 la primera ascensi\u00f3n al Everest con Sir Edmund Hillary en 1953.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/huesca\/2021\/03\/03\/sauerdogs-mantiene-idilio-benasque-con-el-cine-1475072.html?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">El rodaje de \u2018Sauerdogs\u2019 mantiene el idilio del Valle de Benasque con el cine<\/a><em>&nbsp;(Heraldo de Arag\u00f3n)<\/em>. Estos d\u00edas se est\u00e1 rodando en Plan de la Besurta y en el entorno del&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/forau-aiguallut\/?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Forau de Aigualluts<\/a>.&nbsp;La historia versa sobre las \u201candanzas de&nbsp;Bill y Hans, dos fracasados buscadores de oro que se han encontrado con que el invierno&nbsp;se ha adelantado\u201d. Esperemos que tan preciosos parajes sean respetados como deben.&nbsp;<\/li>\n\n\n\n<li><em>\u201c<\/em><a href=\"https:\/\/www.traveler.es\/naturaleza\/articulos\/sendero-hippie-the-overland-historia-paises-por-los-que-pasaba\/20300?utm_campaign=Traves%C3%ADa.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\" target=\"_blank\" rel=\"noreferrer noopener\"><em>The Overland<\/em>, la Ruta Hippie iniciada por tantos so\u00f1adores en furgonetas Volkswagen<\/a>\u201d&nbsp;<em>(Traveler)<\/em>. La historia del Sendero Hippie, cuando los sue\u00f1os, la libertad, tomaban las carreteras.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-24-febrero-2021\">Mi\u00e9rcoles, 24 febrero 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lo primero,&nbsp;<a href=\"https:\/\/www.facebook.com\/cnhelios\/posts\/10157503329096930\" target=\"_blank\" rel=\"noreferrer noopener\">\u00bfhab\u00e9is visto estas im\u00e1genes de la cima del Moncayo?<\/a>&nbsp;Las comparte el<em>&nbsp;Centro Nataci\u00f3n Helios<\/em>, su secci\u00f3n de monta\u00f1ismo&nbsp;<em>(Facebook)<\/em>. Parece que alguien \u00abse ha dejado la puerta abierta\u00bb, \u00bfno?<\/li>\n\n\n\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/simone-moro-hoy-termina-mi-expedicion-al-manaslu-invernal\/\" target=\"_blank\" rel=\"noreferrer noopener\">Simone Moro abandona la expedici\u00f3n al Manaslu invernal<\/a><em>(Desnivel)<\/em>, debido a las previsiones de mal tiempo hasta final del invierno metereol\u00f3gico y a que expira su permiso. En el CB contin\u00faan Alex Txikon y el resto del equipo, esperando una oportunidad. Tiempo de espera, quietud y con todos los ojos en la meteo.<a href=\"https:\/\/twitter.com\/AlexTxikon\/status\/1363890981599379465\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;Alex nos lo cuenta<\/a><em>&nbsp;(Twitter).<\/em><\/li>\n\n\n\n<li><a href=\"https:\/\/www.cmdsport.com\/nieve\/actualidad-nieve\/alertan-sobre-la-desaparicion-de-pistas-de-esqui-del-pirineo-en-cotas-bajas-o-expuestas-al-sol\/?fbclid=IwAR0KDlPh0l1nIGIAUIpPwZG-iB5KrSInqhYorSexbw9A0Gi7hbcXGXuez_Q\" target=\"_blank\" rel=\"noreferrer noopener\">Las pistas de esqu\u00ed en el Pirineo tienen fecha de caducidad<\/a>, las temporadas de esqu\u00ed tender\u00e1n a acortarse&nbsp;<em>(CMD&nbsp;Sport)<\/em>. El cambio clim\u00e1tico, \u00bfos suena?&#8230;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.salyroca.es\/articulo\/roca\/ascension-kilimanjaro-bici\/20210211092752006785.html\" target=\"_blank\" rel=\"noreferrer noopener\">\u00abTodo lo que necesitas saber para subir al Kilimanjaro en bici\u00bb<\/a><em>&nbsp;(Sal &amp; Roca)<\/em>. \u00bfSe puede subir al Kilimanjaro en bici? Eso me he preguntado yo al leer en titular. La respuesta es \u00abSi y No\u00bb,&nbsp;<em>Active Woman&nbsp;<\/em>nos lo cuenta en el art\u00edculo.<\/li>\n\n\n\n<li>Para terminar os proponemos el documental<a href=\"https:\/\/youtu.be\/Gv1dWkspBqk\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;\u00ab\u00bfPor qu\u00e9 hacemos esto?\u00bb<\/a><em>(Youtube)<\/em>&nbsp;es una pel\u00edcula-documental de 40 minutos de duraci\u00f3n, de esqu\u00ed, escalada y alpinismo. Dirigida por el asturiano Carlos Llerandi y protagonizada por Alexis Ferrera, Pol Tellosa, Jordi Mons, Peru Ortiz y el mismo Carlos Llerandi.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-17-febrero-2021\">Mi\u00e9rcoles, 17 febrero 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Patagonia, 9 picos en solitario,<a href=\"https:\/\/www.desnivel.com\/escalada-roca\/sean-villanueva-hace-la-travesia-del-fitz-9-picos-en-solitario\/\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;La Traves\u00eda del Fitz&nbsp;\u2018Moonwalk traverse\u2019&nbsp;de Sean Villanueva. Sean \u00abse anota la primera repetici\u00f3n de la hist\u00f3rica cabalgada de Tommy Caldwell y Alex Honnold\u00bb<\/a>. Toda una odisea.<em>&nbsp;(Desnivel)<\/em><\/li>\n\n\n\n<li><a href=\"http:\/\/www.escalando.org\/2021\/02\/liberan-documental-bajo-la-gran-montana-un-regalo-para-jp-mohr-mientras-sigue-la-busqueda\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00abPara el cumplea\u00f1os n\u00famero 34 de Juan Pablo Mohr, liberan&nbsp;el documental \u00abBajo la gran monta\u00f1a\u00bb<\/a>, un reflejo del legado de este monta\u00f1ista chileno\u00bb&nbsp;<em>(Escalando)&nbsp;<\/em>y una muestra de fuerza mientras la b\u00fasqueda contin\u00faa en el K2.<\/li>\n\n\n\n<li>Alex Txikon, Simone Moro y su equipo regresan al CB.<a href=\"https:\/\/www.desnivel.com\/expediciones\/empieza-el-intento-a-cumbre-en-el-manaslu-invernal\/\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;\u00abCancelado a 7.000 metros el intento al Manaslu invernal\u00bb<\/a>&nbsp;<em>(Desnivel)<\/em>. Tras planificar cima para el pasado Domingo, y llegar a 7.000m, las malas condiciones han hecho cancelar el intento de cima. &nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.turiski.es\/35-anos-del-record-de-permanencia-en-altura-de-fernando-garrido\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hace 35 a\u00f1os del r\u00e9cord de permanencia en altura del alpinista aragon\u00e9s Fernando Garrido, qui\u00e9n permaneci\u00f3 62 d\u00edas seguidos en la cima del Aconcagua<\/a>&nbsp;<em>(Turiski)<\/em>. En el haber de Fernando est\u00e1 tambi\u00e9n la primera invernal en solitario de un ocho mil, tan en boga ahora, con la ascensi\u00f3n del Cho Oyu.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-10-febrero-2021\">Mi\u00e9rcoles, 10 febrero 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Un k2 invernal tr\u00e1gico<\/strong>.&nbsp;<a href=\"https:\/\/www.abc.es\/deportes\/abci-tragico-peaje-querer-hacer-historia-202102091740_noticia.html\" target=\"_blank\" rel=\"noreferrer noopener\">\u00abCinco alpinistas han fallecido en la monta\u00f1a salvaje, que fue ascendida este a\u00f1o por primera vez en invierno\u00bb<\/a><em>&nbsp;(ABC Deportes)<\/em>. A la triste noticia del fallecimiento de&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/fallece-sergi-mingote-k2-invernal\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sergi Mingote&nbsp;<\/a>se un\u00eda el fallecimiento del b\u00falgaro&nbsp;Stanas Skatov al caer en su descenso desde el campo 3. Si esto no fuera suficiente, la esperanza de encontrar con vida a&nbsp;Snorri, Sadpara y Mohr en la monta\u00f1a&nbsp;<a href=\"https:\/\/www.desnivel.com\/expediciones\/k2-invernal-sin-noticias-de-john-snorri-ali-sadpara-y-juan-pablo-mohr\/\" target=\"_blank\" rel=\"noreferrer noopener\">se han desvanecido<\/a>&nbsp;<em>(Desnivel)<\/em>. Las b\u00fasquedas en helic\u00f3ptero han sido infructuosas.&nbsp;La expedici\u00f3n de<em>&nbsp;Seven Summits Treks&nbsp;<\/em>desmonta el campamento.&nbsp;<\/li>\n\n\n\n<li><strong>Manaslu invernal<\/strong>. Alex Txikon, Simone Moro y su equipo ya en pleno ataque a la monta\u00f1a<a href=\"https:\/\/www.elcorreo.com\/mendian\/montana\/alpinismo\/alex-txikon-parte-hacia-el-manaslu-objetivo-hacer-cima-domingo-20210209191234-nt.html\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;\u00abcon el objetivo de alcanzar la cima el domingo\u00bb<\/a>&nbsp;<em>(elcorreo). Tuvieron que<a href=\"https:\/\/twitter.com\/ana_azpi\/status\/1358715484250669056\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;reconstruir el CB tras fuertes tormentas<\/a>&nbsp;(@ana_azpi).<\/em><\/li>\n\n\n\n<li>Las arenas del Sahara llegaron a los Pirineos y cubrieron de una fina capa de barro la nieve. La&nbsp;<a href=\"https:\/\/www.elperiodicodearagon.com\/noticias\/aragon\/lluvia-polvo-sahara-tine-amarillo-gran-parte-aragon_1456113.html\" target=\"_blank\" rel=\"noreferrer noopener\">\u00abLluvia de polvo del S\u00e1hara ti\u00f1e de rojo gran parte de Arag\u00f3n\u00bb<\/a>&nbsp;<em>(el Peri\u00f3dico Arag\u00f3n)<\/em>. Es un fen\u00f3meno de polvo mineral en suspensi\u00f3n que suele afectar a Canarias pero que esta vez ha viajado&nbsp;mucho m\u00e1s lejos.&nbsp;<\/li>\n\n\n\n<li>En<em>&nbsp;<a href=\"https:\/\/twitter.com\/imakazaga\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Piedra de Toque<\/strong><\/a>&nbsp;(@imakazaga)&nbsp;<\/em>celebran \u00ablos 40 a\u00f1os que cumple la&nbsp;<strong>revista Desnivel<\/strong>&nbsp;viajando con su director y buen amigo del programa&nbsp;<a href=\"https:\/\/twitter.com\/DarioDesnivel\" target=\"_blank\" rel=\"noreferrer noopener\">Dar\u00edo Rodr\u00edguez<\/a>. De la m\u00e1quina de escribir a la irrupci\u00f3n de las redes sociales y la retransmisi\u00f3n en directo desde un ochomil.\u00bb,&nbsp;<a href=\"https:\/\/www.piedradetoque.es\/dario-rodriguez-cada-vez-es-mas-dificil-realizar-un-periodismo-de-montana-de-calidad\/\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed el Podcast<\/a>.&nbsp;&nbsp;<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"miercoles-03-febrero-2021\">Mi\u00e9rcoles, 03 febrero 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/twitter.com\/sebas_alvaro\/status\/1355267617200754690?s=03\" target=\"_blank\" rel=\"noreferrer noopener\">Sebastian Alvaro comparte un interesante hilo<\/a>&nbsp;en Twitter, tipo&nbsp;videopodcast, en el que responde a preguntas en torno al&nbsp;<strong>K2 invernal<\/strong>.&nbsp;<\/li>\n\n\n\n<li>Un estudio confirma la masificaci\u00f3n de las cumbres del Pirineo con casi 500&nbsp; monta\u00f1eros algunos d\u00edas de verano. (Heraldo)&nbsp;<a href=\"https:\/\/www.heraldo.es\/noticias\/aragon\/huesca\/2021\/02\/01\/monte-perdido-se-corona-como-la-cima-con-mas-tiron-con-casi-500-visitas-algunos-dias-de-verano-1417810.html?fbclid=IwAR15Bi7mQ7mKqDLZUPv3CKZoHwt6FR6VoTftIQHRS1BYNLsPx09kPsn2bT4\" target=\"_blank\" rel=\"noreferrer noopener\">M\u00e1s de 18.000 personas subieron a Monte Perdido de junio a septiembre<\/a>, el doble que al Aneto.&nbsp;<\/li>\n\n\n\n<li>Nuevas tecnolog\u00edas.&nbsp;La<strong>&nbsp;expedici\u00f3n al pico Manaslu<\/strong>&nbsp;(8.163m) liderada por el monta\u00f1ero&nbsp;<a href=\"https:\/\/twitter.com\/AlexTxikon\" target=\"_blank\" rel=\"noreferrer noopener\">Alex Txikon<\/a>&nbsp;(Tw) no gastar\u00e1 un solo litro de combustibles f\u00f3siles&nbsp;<a href=\"https:\/\/www.pv-magazine.es\/2021\/02\/02\/fotovoltaica-de-alto-nivel\/\" target=\"_blank\" rel=\"noreferrer noopener\">gracias a dos instalaciones fotovoltaicas port\u00e1tiles<\/a>&nbsp;(pv-magazine).&nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.salyroca.es\/articulo\/roca\/trail-running-organizacion-virtual-carreras-montana\/20210107104706006690.html\" target=\"_blank\" rel=\"noreferrer noopener\">Trail Running 2.0<\/a>: la organizaci\u00f3n virtual de carreras por monta\u00f1a (Sal &amp; Roca).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"jueves-28-enero-2021\">Jueves, 28 enero 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.20minutos.es\/noticia\/4557367\/0\/excursionistas-tienen-pagar-2600-euros-rescate\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Dos excursionistas tienen que pagar m\u00e1s de 2.600 euros por su rescate&nbsp;<\/a>(20minutos). Ante este noticia nos surge la pregunta:&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/federarse-en-montana\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00bfSon gratis los rescates en accidentes de monta\u00f1a en Espa\u00f1a?<\/a><\/li>\n\n\n\n<li>\u00ab<a href=\"https:\/\/youtu.be\/KkszaawGCi0\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Hermano a hermano, hombro a hombro, caminamos juntos a la cumbre&nbsp;<\/a>mientras cantaba el himno nacional nepal\u00ed. Todos nos detuvimos alrededor, 10 metros antes de llegar a la cumbre, para acurrucarnos y hacer nuestros \u00faltimos pasos juntos como un equipo para marcar esta haza\u00f1a hist\u00f3rica, la primera ascensi\u00f3n de K2 en invierno.\u00bb<em>&nbsp;Nirmal Purja&nbsp;<\/em>(Youtube)<\/li>\n\n\n\n<li><a href=\"https:\/\/cumbresmountainmagazine.com\/fuji-icono-de-japon-sin-nieve\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">El monte Fuji, el \u00edcono del Jap\u00f3n, se queda sin nieve<\/a>&nbsp;(Cumbres). La nieve se va. Tambi\u00e9n aqu\u00ed. En el siguiente art\u00edculo (El Pa\u00eds),&nbsp;<a href=\"https:\/\/elpais.com\/ciencia\/2021-01-02\/la-muerte-de-los-ultimos-glaciares-de-espana.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">La muerte de los \u00faltimos glaciares de Espa\u00f1a<\/a>, una gran investigaci\u00f3n y presentaci\u00f3n visual nos sobrecoge ante algo que se nos presenta como inevitable: la siguiente generaci\u00f3n va a conocer la desaparici\u00f3n de los glaciares.&nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.traveler.es\/naturaleza\/articulos\/treefm-la-radio-sonidos-bosques-del-mundo\/20105\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Tree.fm, la radio de los bosques del mundo<\/a>. (Traveler) \u201cEs un&nbsp;<em>shinrin-yoku<\/em>&nbsp;digital, un viaje virtual, una radio de \u00e1rboles, activismo climatol\u00f3gico, un escape de casa o de la oficina\u201d. Recuerda:&nbsp;C\u00f3mo la ciencia demuestra el&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/beneficio-bosques\/\" target=\"_blank\" rel=\"noreferrer noopener\">beneficio mental de vivir cerca de un bosque<\/a>.&nbsp;<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"jueves-21-enero-2021\">Jueves, 21 enero 2021<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.revistaoxigeno.es\/deportes\/nirmal-purja-lograba-cima-k2-invernal-sin-usar-oxigeno-artificial_226183_102.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Nirmal Purja lograba la cima del K2 invernal sin usar ox\u00edgeno artificial<\/a>. 10 nepal\u00edes ascend\u00edan al K2 invernal, de ellos&nbsp;Nirmal Purja&nbsp;ascend\u00eda sin utilizar ox\u00edgeno artificial.&nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.desnivel.com\/expediciones\/sergi-mingote-fallece-en-un-accidente-en-el-k2\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Sergi Mingote fallece en un accidente en el K2<\/a>. Nos sobrecogi\u00f3 la triste noticia, te echaremos de menos. Hace poco pudimos hablar con \u00e9l en&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/k2-invernal-sergi-mingote\/\" rel=\"noreferrer noopener\" target=\"_blank\">esta entrevista<\/a>.<\/li>\n\n\n\n<li>Adi\u00f3s a la leyenda del alpinismo&nbsp;<a href=\"https:\/\/www.eldiario.es\/campobase\/noticias\/cesare-maestri-alpinismo-leyenda-fallece-domolitas-cerro-torre_1_6949209.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Cesare Maestri<\/a><\/li>\n\n\n\n<li>En Hong Kong, Lai Chi-wai, ex-campe\u00f3n de escalada ahora paralizado de cintura para abajo,&nbsp;<a href=\"https:\/\/youtu.be\/EXkpRvGQiXE\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">alcanz\u00f3 una altura de unos 230 metros despu\u00e9s de escalar un rascacielos&nbsp;<\/a>en silla de ruedas.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"In theWeekly Newsletter we have incorporated a new section in which we select the weekly news and...","protected":false},"author":1,"featured_media":25094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3002],"tags":[],"series":[],"class_list":["post-25074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2015\/01\/Noticias.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/en\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"ebcaBu6sb1\"><a href=\"https:\/\/travesiapirenaica.com\/en\/noticias_2022\/\">Las noticias de alpinismo y monta\u00f1a m\u00e1s destacadas de 2022<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/en\/noticias_2022\/embed\/#?secret=ebcaBu6sb1\" width=\"500\" height=\"350\" title=\"&#8220;Las noticias de alpinismo y monta\u00f1a m\u00e1s destacadas de 2022&#8221; &#8212; Traves\u00eda.\" data-secret=\"ebcaBu6sb1\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":3002,"label":"Actualidad"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2015\/01\/Noticias-1024x768.jpg",1024,768,true],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/en\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":3002,"name":"Actualidad","slug":"actualidad","term_group":0,"term_taxonomy_id":3018,"taxonomy":"category","description":"Actualidad","parent":0,"count":74,"filter":"raw","cat_ID":3002,"category_count":74,"category_description":"Actualidad","cat_name":"Actualidad","category_nicename":"actualidad","category_parent":0}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2015\/01\/Noticias.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/posts\/25074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/comments?post=25074"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/posts\/25074\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/media\/25094"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/media?parent=25074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/categories?post=25074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/tags?post=25074"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/series?post=25074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}