{"id":49196,"date":"2025-07-01T09:14:57","date_gmt":"2025-07-01T07:14:57","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=49196"},"modified":"2026-04-25T18:05:19","modified_gmt":"2026-04-25T16:05:19","slug":"gr11-sallent-gallego-respomuso","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/en\/gr11-sallent-gallego-respomuso\/","title":{"rendered":"Stage 13: Sallent de Gallego - Respomuso Refuge"},"content":{"rendered":"<style>.kb-row-layout-id49196_7a11dd-b0 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id49196_7a11dd-b0 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id49196_7a11dd-b0 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:2000px;margin-left:auto;margin-right:auto;padding-right:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id49196_7a11dd-b0 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id49196_7a11dd-b0 > .kt-row-column-wrap{padding-right:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id49196_7a11dd-b0 > .kt-row-column-wrap{padding-right:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id49196_7a11dd-b0 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column49196_39ac88-38 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-4xl, 8rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);}.kadence-column49196_39ac88-38 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column49196_39ac88-38 > .kt-inside-inner-col,.kadence-column49196_39ac88-38 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column49196_39ac88-38 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column49196_39ac88-38 > .kt-inside-inner-col{flex-direction:column;}.kadence-column49196_39ac88-38 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column49196_39ac88-38 > .kt-inside-inner-col{background-color:var(--global-palette3, #1A202C);background-image:url('https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso.jpg');background-size:cover;background-position:66% 41%;background-attachment:scroll;background-repeat:no-repeat;}.kadence-column49196_39ac88-38 > .kt-inside-inner-col:before{opacity:0.13;background-color:var(--global-palette3, #1A202C);}.kadence-column49196_39ac88-38{position:relative;}@media all and (max-width: 1024px){.kadence-column49196_39ac88-38 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column49196_39ac88-38 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xxl, 5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column49196_39ac88-38 kb-section-has-overlay\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading49196_4d4789-e4, .wp-block-kadence-advancedheading.kt-adv-heading49196_4d4789-e4[data-kb-block=\"kb-adv-heading49196_4d4789-e4\"]{text-align:center;font-size:var(--global-kb-font-size-xxl, 4rem);font-style:normal;font-family:var( --global-heading-font-family, inherit );text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading49196_4d4789-e4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading49196_4d4789-e4[data-kb-block=\"kb-adv-heading49196_4d4789-e4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading49196_4d4789-e4 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading49196_4d4789-e4[data-kb-block=\"kb-adv-heading49196_4d4789-e4\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading49196_4d4789-e4 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading49196_4d4789-e4\">Etapa 13: Sallent de Gallego &#8211; Refugio de Respomuso<\/h2>\n\n\n\n<div class=\"wp-block-buttons has-custom-font-size has-small-font-size is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-small-font-size has-custom-font-size wp-element-button\" href=\"#guia-rapida\" style=\"border-style:none;border-width:0px;border-radius:30px\">\ud83d\udd25 Desc\u00e1rgate la gu\u00eda r\u00e1pida GR11<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-small-font-size has-custom-font-size wp-element-button\" href=\"#Dormir\/Servicios\" style=\"border-style:none;border-width:0px;border-radius:30px\">Dormir\/Servicios<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-small-font-size has-custom-font-size wp-element-button\" href=\"#Recorrido\" style=\"border-style:none;border-width:0px;border-radius:30px\"><strong>Recorrido\/Itinerario<\/strong><\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id49196_b015de-98 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id49196_b015de-98 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id49196_b015de-98 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1062px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id49196_b015de-98 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id49196_b015de-98 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id49196_b015de-98 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id49196_b015de-98 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column49196_c9857d-c7 > .kt-inside-inner-col,.kadence-column49196_c9857d-c7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column49196_c9857d-c7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column49196_c9857d-c7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column49196_c9857d-c7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column49196_c9857d-c7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column49196_c9857d-c7{position:relative;}@media all and (max-width: 1024px){.kadence-column49196_c9857d-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column49196_c9857d-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column49196_c9857d-c7\"><div class=\"kt-inside-inner-col\"><style>.kadence-column49196_64fa10-ed > .kt-inside-inner-col{display:flex;}.kadence-column49196_64fa10-ed > .kt-inside-inner-col,.kadence-column49196_64fa10-ed > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column49196_64fa10-ed > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column49196_64fa10-ed > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column49196_64fa10-ed > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column49196_64fa10-ed{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column49196_64fa10-ed{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column49196_64fa10-ed > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column49196_64fa10-ed > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column49196_64fa10-ed{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column49196_64fa10-ed{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column49196_64fa10-ed{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column49196_64fa10-ed > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column49196_64fa10-ed > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column49196_64fa10-ed{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column49196_64fa10-ed{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column49196_64fa10-ed > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column49196_64fa10-ed > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column49196_64fa10-ed\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns49196_0f7efe-9e{gap:var(--global-kb-gap-md, 2rem);justify-content:center;align-items:center;}.kt-btns49196_0f7efe-9e .kt-button{font-weight:normal;font-style:normal;}.kt-btns49196_0f7efe-9e .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns49196_0f7efe-9e .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns49196_0f7efe-9e .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns49196_0f7efe-9e .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns49196_0f7efe-9e .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns49196_0f7efe-9e .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns49196_0f7efe-9e .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns49196_0f7efe-9e{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns49196_0f7efe-9e\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn49196_c3a9fb-6b.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn49196_c3a9fb-6b.kb-button{color:var(--global-palette5, #4A5568);background:var(--global-palette9, #ffffff);font-size:var(--global-kb-font-size-sm, 0.9rem);}.kb-btn49196_c3a9fb-6b.kb-button .kb-svg-icon-wrap{color:var(--global-palette5, #4A5568);font-size:16px;--kb-button-icon-size:16px;}<\/style><a class=\"kb-button kt-button button kb-btn49196_c3a9fb-6b kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/travesiapirenaica.com\/gr11-candanchu-sallent-gallego\/\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowLeft kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"19\" y1=\"12\" x2=\"5\" y2=\"12\"\/><polyline points=\"12 19 5 12 12 5\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Candanch\u00fa<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn49196_906b3f-a8.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn49196_906b3f-a8.kb-button{color:var(--global-palette5, #4A5568);background:var(--global-palette9, #ffffff);font-size:var(--global-kb-font-size-sm, 0.9rem);}.kb-btn49196_906b3f-a8.kb-button .kb-svg-icon-wrap{color:var(--global-palette5, #4A5568);font-size:16px;--kb-button-icon-size:16px;}<\/style><a class=\"kb-button kt-button button kb-btn49196_906b3f-a8 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/travesiapirenaica.com\/gr11\/canfranc_estac-sallent_gallego.php\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowLeft kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"19\" y1=\"12\" x2=\"5\" y2=\"12\"\/><polyline points=\"12 19 5 12 12 5\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Canfranc<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn49196_8a585a-e3.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn49196_8a585a-e3.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);font-size:var(--global-kb-font-size-sm, 0.9rem);border-top:1px solid var(--global-palette1, #3182CE);border-right:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);border-left:1px solid var(--global-palette1, #3182CE);box-shadow:7px 3px 6px 0px rgba(0, 0, 0, 0.2);}.kb-btn49196_8a585a-e3.kb-button .kb-svg-icon-wrap{font-size:16px;--kb-button-icon-size:16px;}.wp-block-kadence-advancedbtn .kb-btn49196_8a585a-e3.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn49196_8a585a-e3.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom-color:var(--global-palette1, #3182CE);border-bottom-style:solid;border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn49196_8a585a-e3.kb-button{border-top:1px solid var(--global-palette1, #3182CE);border-right:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);border-left:1px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn49196_8a585a-e3.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn49196_8a585a-e3.kb-button:focus{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom-color:var(--global-palette1, #3182CE);border-bottom-style:solid;border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn49196_8a585a-e3.kb-button{border-top:1px solid var(--global-palette1, #3182CE);border-right:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);border-left:1px solid var(--global-palette1, #3182CE);}.wp-block-kadence-advancedbtn .kb-btn49196_8a585a-e3.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn49196_8a585a-e3.kb-button:focus{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom-color:var(--global-palette1, #3182CE);border-bottom-style:solid;border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn49196_8a585a-e3 kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/travesiapirenaica.com\/gr11\/respomuso-balneario_panticosa.php\"><span class=\"kt-btn-inner-text\">Siguiente<\/span><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-btn-icon-side-right\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><\/a><\/div>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><strong><a href=\"https:\/\/travesiapirenaica.com\/gr-11\/\" data-type=\"link\" data-id=\"https:\/\/travesiapirenaica.com\/gr-11\/\">GR11<\/a> \/ &nbsp;Etapa 13: Sallent de Gallego &#8211; Refugio de Respomuso<\/strong><\/p>\n\n\n\n\n\n<div class=\"wp-block-woocommerce-memberships-non-member-content\"><style>.kadence-column49196_468466-4e > .kt-inside-inner-col,.kadence-column49196_468466-4e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column49196_468466-4e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column49196_468466-4e > .kt-inside-inner-col{flex-direction:column;}.kadence-column49196_468466-4e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column49196_468466-4e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column49196_468466-4e{position:relative;}@media all and (max-width: 1024px){.kadence-column49196_468466-4e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column49196_468466-4e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column49196_468466-4e\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-center wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column49196_e1e52c-3a > .kt-inside-inner-col{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}.kadence-column49196_e1e52c-3a > .kt-inside-inner-col,.kadence-column49196_e1e52c-3a > .kt-inside-inner-col:before{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;}.kadence-column49196_e1e52c-3a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column49196_e1e52c-3a > .kt-inside-inner-col{flex-direction:column;}.kadence-column49196_e1e52c-3a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column49196_e1e52c-3a > .kt-inside-inner-col{background-color:var(--global-palette7, #EDF2F7);}.kadence-column49196_e1e52c-3a > .kt-inside-inner-col:before{opacity:0.22;}.kadence-column49196_e1e52c-3a{position:relative;}@media all and (max-width: 1024px){.kadence-column49196_e1e52c-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column49196_e1e52c-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column49196_e1e52c-3a\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-group has-border-color\" style=\"border-color:var(--global-palette7);border-width:20px;border-radius:10px\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">Este contenido es exclusivo para miembros. <\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns49196_58851e-45{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns49196_58851e-45 .kt-button{font-weight:normal;font-style:normal;}.kt-btns49196_58851e-45 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns49196_58851e-45 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns49196_58851e-45 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns49196_58851e-45 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns49196_58851e-45 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns49196_58851e-45 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns49196_58851e-45 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns49196_58851e-45\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn49196_50665b-b5.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn49196_50665b-b5 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/travesiapirenaica.com\/club\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"kt-btn-inner-text\">+ \u00danete<\/span><\/a><\/div>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">\u00bfYa eres miembro del Club? <strong><a href=\"https:\/\/travesiapirenaica.com\/my-account\/\" target=\"_blank\" rel=\"noreferrer noopener\">Inicia sesi\u00f3n.<\/a><\/strong><\/p>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box49196_d7ba2d-28 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box49196_d7ba2d-28 .kt-blocks-info-box-link-wrap{border-top:1px solid var(--global-palette7, #eeeeee);border-right:1px solid var(--global-palette7, #eeeeee);border-bottom:1px solid var(--global-palette7, #eeeeee);border-left:1px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;background:var(--global-palette8, #F7FAFC);padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box49196_d7ba2d-28 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box49196_d7ba2d-28 .kt-info-svg-icon-flip, .kt-info-box49196_d7ba2d-28 .kt-blocks-info-box-number{font-size:48px;}.kt-info-box49196_d7ba2d-28 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}.kt-info-box49196_d7ba2d-28 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box49196_d7ba2d-28 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box49196_d7ba2d-28 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box49196_d7ba2d-28 .kt-blocks-info-box-link-wrap{border-top:1px solid var(--global-palette7, #eeeeee);border-right:1px solid var(--global-palette7, #eeeeee);border-bottom:1px solid var(--global-palette7, #eeeeee);border-left:1px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 1024px){.kt-info-box49196_d7ba2d-28 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box49196_d7ba2d-28 .kt-info-svg-icon-flip, .kt-info-box49196_d7ba2d-28 .kt-blocks-info-box-number{font-size:50px;}}@media all and (max-width: 767px){.kt-info-box49196_d7ba2d-28 .kt-blocks-info-box-link-wrap{border-top:1px solid var(--global-palette7, #eeeeee);border-right:1px solid var(--global-palette7, #eeeeee);border-bottom:1px solid var(--global-palette7, #eeeeee);border-left:1px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box49196_d7ba2d-28\"><a class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.skool.com\/travesiapirenaica\/about\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_people kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M5.5 0c-.51 0-.95.35-1.22.88.45.54.72 1.28.72 2.13 0 .29-.03.55-.09.81.19.11.38.19.59.19.83 0 1.5-.9 1.5-2s-.67-2-1.5-2zm-3 1c-.83 0-1.5.9-1.5 2s.67 2 1.5 2 1.5-.9 1.5-2-.67-2-1.5-2zm4.75 3.16c-.43.51-1.02.82-1.69.84.27.38.44.84.44 1.34v.66h2v-1.66c0-.52-.31-.97-.75-1.19zm-6.5 1c-.44.22-.75.67-.75 1.19v1.66h5v-1.66c0-.52-.31-.97-.75-1.19-.45.53-1.06.84-1.75.84s-1.3-.32-1.75-.84z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong>Comunidad (Club Traves\u00eda Pirenaica)<\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Si te surge cualquier duda en esta etapa, puedes plantearla dentro del Club. All\u00ed compartimos experiencias reales, consejos y soluciones entre quienes estamos preparando o recorriendo el GR11.<\/p><\/div><\/a><\/div>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/travesiapirenaica.com\/gr11\/mapa-gr11.php?&#038;etapa=sallent-respomuso\" allow=\"fullscreen\" width=\"100%\" height=\"400\"><\/iframe>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns49196_444bf3-da{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns49196_444bf3-da .kt-button{font-weight:normal;font-style:normal;}.kt-btns49196_444bf3-da .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns49196_444bf3-da .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns49196_444bf3-da .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns49196_444bf3-da .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns49196_444bf3-da .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns49196_444bf3-da .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns49196_444bf3-da .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns49196_444bf3-da\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn49196_822c1b-c6.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn49196_822c1b-c6 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/travesiapirenaica.com\/gr11-descargar-tracks\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"kt-btn-inner-text\">Descargar track<\/span><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_download kt-btn-icon-side-right\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 15v4a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2v-4\"\/><polyline points=\"7 10 12 15 17 10\"\/><line x1=\"12\" y1=\"15\" x2=\"12\" y2=\"3\"\/><\/svg><\/span><\/a><\/div>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"813\" height=\"280\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Perfil-etapa.jpg\" alt=\"Perfil etapa GR11 Sallent de Gallego - Refugio de Respomuso\" class=\"wp-image-49199\" style=\"width:842px;height:auto\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Perfil-etapa.jpg 813w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Perfil-etapa-300x103.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Perfil-etapa-768x265.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Perfil-etapa-18x6.jpg 18w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Perfil-etapa-600x207.jpg 600w\" sizes=\"auto, (max-width: 813px) 100vw, 813px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-theme-palette-8-border-color has-theme-palette-7-background-color has-background\" style=\"border-width:1px;border-radius:10px\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>\u2194\ufe0f<\/strong> <strong>Distancia:<\/strong>&nbsp;11,2 km<br><strong>\ud83d\udcc8<\/strong> <strong>Desnivel<\/strong> (+902),(-36) <strong>\ud83d\udcc9<\/strong><br><strong>\ud83d\udd52<\/strong> <strong>Tiempo:<\/strong>&nbsp;3h15min (tiempo de marcha&nbsp;<strong>sin paradas<\/strong>) <br>\u26a0\ufe0f <strong>Dificultad:<\/strong>&nbsp;no presenta dificultades rese\u00f1ables salvo por el desnivel.<br><strong>Sugerencias:<\/strong>&nbsp;Se puede alargar esta etapa hasta el refugio de los ibones de Bachima\u00f1a o hasta el Balneario de Panticosa. Ver etapa siguiente.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:9px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style>.kt-accordion-id49196_1ad114-b5 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:10px;}.kt-accordion-id49196_1ad114-b5 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#ffffff;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id49196_1ad114-b5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;background:var(--global-palette1, #3182CE);font-weight:700;color:var(--global-palette9, #ffffff);padding-top:14px;padding-right:16px;padding-bottom:14px;padding-left:16px;}.kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette9, #ffffff);}.kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette9, #ffffff);}.kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette1, #3182CE);}.kt-accordion-id49196_1ad114-b5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id49196_1ad114-b5 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id49196_1ad114-b5 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id49196_1ad114-b5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#BE530B;border-top-color:#BE530B;border-top-style:solid;border-right-color:#BE530B;border-right-style:solid;border-bottom-color:#BE530B;border-bottom-style:solid;border-left-color:#BE530B;border-left-style:solid;}.kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id49196_1ad114-b5:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#BE530B;}@media all and (max-width: 1024px){.kt-accordion-id49196_1ad114-b5 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id49196_1ad114-b5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id49196_1ad114-b5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id49196_1ad114-b5 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id49196_1ad114-b5 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id49196_1ad114-b5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#BE530B;border-top-style:solid;border-right-color:#BE530B;border-right-style:solid;border-bottom-color:#BE530B;border-bottom-style:solid;border-left-color:#BE530B;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id49196_1ad114-b5 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id49196_1ad114-b5 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:10px;}.kt-accordion-id49196_1ad114-b5 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id49196_1ad114-b5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id49196_1ad114-b5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id49196_1ad114-b5 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id49196_1ad114-b5 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id49196_1ad114-b5 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#BE530B;border-top-style:solid;border-right-color:#BE530B;border-right-style:solid;border-bottom-color:#BE530B;border-bottom-style:solid;border-left-color:#BE530B;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id49196_1ad114-b5 kt-accordion-has-2-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane49196_26cbb5-09\" id=\"Recorrido\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Recorrido\/Itinerario:<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">\ud83d\udccc <strong>(0h0min; 0 kms) Sallent de Gallego (1288m).<\/strong>&nbsp;Dejar el pueblo por una pista que discurre inicialmente paralela al r\u00edo. Despu\u00e9s de unos minutos se toma un cruce a la izquierda, la pista se vuelve senda y tras un tramo de subida se enlaza con la carretera que asciende al embalse de la Sarra. Continuar por ella hasta la presa. Justo antes, sale un camino a la izquierda que no tarda en convertirse en una senda por la que se bordea el embalse en unos 15 minutos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">\ud83d\udccc <strong>(0h55min; 3,6 kms) Cola del embalse de la Sarra (1420m).<\/strong>&nbsp;Entrada de la reserva de la biosfera Ordesa-Vi\u00f1amala. En la otra orilla hay un peque\u00f1o aparcamiento y un bar-restaurante. Dejamos atr\u00e1s, sin cruzar, el Puente de las Faxas y poco despu\u00e9s una explanada recreativa (Plana Tornadizas). El sendero se introduce en el bosque y remonta el valle de Aguas Limpias por la margen derecha. Se cruzan varios barrancos, Bozitero, del Ministirio, de Balsaroleta y del Garmo Negro antes de llegar al Paso del Onso, una zona estrecha de grandes cortados. Despu\u00e9s se pasa el Llano Cheto donde se incorporan las aguas del barranco de Arriel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">\ud83d\udccc <strong>(2h00min; 7,6 kms) Cruce a los ibones de Arriel (1735m).<\/strong>&nbsp;Seguimos remontando el valle paralelos al r\u00edo, la senda se endurece, el valle se abre y por fin divisamos la presa del ib\u00f3n de Respomuso. La senda pasa junto a la ermita de la Virgen de las Nievas (junto a la presa) y contin\u00faa bordeando el embalse por la margen derecha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">\ud83d\udccc <strong>(3h15min; 11,2 kms) Refugio de Respomuso (2200m).<\/strong><\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div style=\"height:9px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" alt=\"Cerca de Sallent de Gallego bajo la Pe\u00f1a Foratata.\" class=\"wp-block-jetpack-slideshow_image wp-image-49202\" data-id=\"49202\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Sallent-de-Gallego-Pena-Foratata.jpg\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Sallent-de-Gallego-Pena-Foratata.jpg 960w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Sallent-de-Gallego-Pena-Foratata-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Sallent-de-Gallego-Pena-Foratata-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Sallent-de-Gallego-Pena-Foratata-18x12.jpg 18w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Sallent-de-Gallego-Pena-Foratata-600x400.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">Cerca de Sallent de Gallego bajo la Pe\u00f1a Foratata.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" alt=\"Tunel de avellanos\" class=\"wp-block-jetpack-slideshow_image wp-image-49203\" data-id=\"49203\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Tunel-de-avellanos.jpg\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Tunel-de-avellanos.jpg 960w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Tunel-de-avellanos-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Tunel-de-avellanos-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Tunel-de-avellanos-18x12.jpg 18w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Tunel-de-avellanos-600x400.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">Tunel de avellanos<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" alt=\"Embalse de La Sarra\" class=\"wp-block-jetpack-slideshow_image wp-image-49206\" data-id=\"49206\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Embalse-La-Sarra.jpg\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Embalse-La-Sarra.jpg 960w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Embalse-La-Sarra-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Embalse-La-Sarra-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Embalse-La-Sarra-18x12.jpg 18w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Embalse-La-Sarra-600x400.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">Embalse de La Sarra<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" alt=\"Cascada en el valle de Aguas Limpias\" class=\"wp-block-jetpack-slideshow_image wp-image-49207\" data-id=\"49207\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Cascada-valle-de-Aguas-Limpias.jpg\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Cascada-valle-de-Aguas-Limpias.jpg 960w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Cascada-valle-de-Aguas-Limpias-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Cascada-valle-de-Aguas-Limpias-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Cascada-valle-de-Aguas-Limpias-18x12.jpg 18w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Cascada-valle-de-Aguas-Limpias-600x400.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">Cascada en el valle de Aguas Limpias<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" alt=\"Paso del Onso\" class=\"wp-block-jetpack-slideshow_image wp-image-49208\" data-id=\"49208\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Paso-del-Onso.jpg\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Paso-del-Onso.jpg 960w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Paso-del-Onso-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Paso-del-Onso-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Paso-del-Onso-18x12.jpg 18w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Paso-del-Onso-600x400.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">Paso del Onso<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" alt=\"En la subida a Respomuso. Al fondo el Pic de Soques\" class=\"wp-block-jetpack-slideshow_image wp-image-49209\" data-id=\"49209\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_-subida-Respomuso-Pic-de-Soques.jpg\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_-subida-Respomuso-Pic-de-Soques.jpg 960w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_-subida-Respomuso-Pic-de-Soques-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_-subida-Respomuso-Pic-de-Soques-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_-subida-Respomuso-Pic-de-Soques-18x12.jpg 18w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_-subida-Respomuso-Pic-de-Soques-600x400.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">En la subida a Respomuso. Al fondo el Pic de Soques<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" alt=\"Subiendo a Respomuso.\" class=\"wp-block-jetpack-slideshow_image wp-image-49211\" data-id=\"49211\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Subiendo-Respomuso.jpg\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Subiendo-Respomuso.jpg 960w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Subiendo-Respomuso-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Subiendo-Respomuso-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Subiendo-Respomuso-18x12.jpg 18w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Subiendo-Respomuso-600x400.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">Subiendo a Respomuso.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" alt=\"Presa de Respomuso.  Detr\u00e1s el Pico de Campo Plano (2721), la Llena Cantal (2941) y el Pico de Piedrafita (2952).\" class=\"wp-block-jetpack-slideshow_image wp-image-49220\" data-id=\"49220\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Presa-de-Respomuso.jpg\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Presa-de-Respomuso.jpg 960w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Presa-de-Respomuso-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Presa-de-Respomuso-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Presa-de-Respomuso-18x12.jpg 18w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_Presa-de-Respomuso-600x400.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">Presa de Respomuso.\nDetr\u00e1s el Pico de Campo Plano (2721), la Llena Cantal (2941) y el Pico de Piedrafita (2952).<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" alt=\"LLegando al refugio de Respomuso.\" class=\"wp-block-jetpack-slideshow_image wp-image-49228\" data-id=\"49228\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_refugio-de-Respomuso.jpg\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_refugio-de-Respomuso.jpg 960w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_refugio-de-Respomuso-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_refugio-de-Respomuso-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_refugio-de-Respomuso-18x12.jpg 18w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso_refugio-de-Respomuso-600x400.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">LLegando al refugio de Respomuso.<\/figcaption><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style>.kt-accordion-id49196_76fbe3-32 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:10px;}.kt-accordion-id49196_76fbe3-32 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#ffffff;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id49196_76fbe3-32 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;background:#f2f2f2;color:#555555;padding-top:14px;padding-right:16px;padding-bottom:14px;padding-left:16px;}.kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id49196_76fbe3-32 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id49196_76fbe3-32 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id49196_76fbe3-32 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id49196_76fbe3-32 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#BE530B;border-top-color:#BE530B;border-top-style:solid;border-right-color:#BE530B;border-right-style:solid;border-bottom-color:#BE530B;border-bottom-style:solid;border-left-color:#BE530B;border-left-style:solid;}.kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id49196_76fbe3-32:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#BE530B;}@media all and (max-width: 1024px){.kt-accordion-id49196_76fbe3-32 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id49196_76fbe3-32 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id49196_76fbe3-32 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id49196_76fbe3-32 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id49196_76fbe3-32 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id49196_76fbe3-32 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#BE530B;border-top-style:solid;border-right-color:#BE530B;border-right-style:solid;border-bottom-color:#BE530B;border-bottom-style:solid;border-left-color:#BE530B;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id49196_76fbe3-32 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id49196_76fbe3-32 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:10px;}.kt-accordion-id49196_76fbe3-32 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id49196_76fbe3-32 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id49196_76fbe3-32 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id49196_76fbe3-32 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id49196_76fbe3-32 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id49196_76fbe3-32 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#BE530B;border-top-style:solid;border-right-color:#BE530B;border-right-style:solid;border-bottom-color:#BE530B;border-bottom-style:solid;border-left-color:#BE530B;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id49196_76fbe3-32 kt-accordion-has-7-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane49196_ea41de-17\" id=\"Dormir\/Servicios\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\ud83c\udfd5\ufe0f <strong><strong>D\u00f3nde dormir:<\/strong><\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">En la etapa anterior, en&nbsp;<strong>Formigal<\/strong>&nbsp;(a 40 minutos de Sallent de G\u00e1llego) hay variedad de hoteles y apartamentos. Muy pr\u00f3ximo al GR11 os recomendamos el&nbsp;<a href=\"https:\/\/www.snohotelformigal.com\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>SNO Formigal<\/strong><\/a>&nbsp;(<em>+34 974 490 030; reservas@snohotelformigal.com<\/em>). Muy comfortable y con restaurante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">En\u00a0<strong>Sallent de G\u00e1llego<\/strong>\u00a0hay variedad de alojamientos. Os recomendamos el\u00a0<a href=\"http:\/\/hostalcentrosallent.es\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>Hostal Centro<\/strong><\/a>\u00a0<em>(+34 974 488 019; vicenterouco@hotmail.com)<\/em>,\u00a0que adem\u00e1s cuenta con restaurante; y el\u00a0<a href=\"https:\/\/hotelmaximina.es\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>Hotel Maximina<\/strong><\/a>\u00a0<em>(+34 619 965 458\u00a0; contacto@hotelmaximina.es)<\/em>, la que fuera casa del gigante aragon\u00e9s Fermin Arrudi (2,29m) y que cuenta con bar-cafeter\u00eda para desayunos y cenas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Al final de la etapa, refugio guardado de&nbsp;<a href=\"http:\/\/www.alberguesyrefugiosdearagon.com\/refugio.php?id=9\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>Respomuso<\/strong><\/a><em>&nbsp;(+34 974337556; refugiorespomuso@hotmail.com)<\/em>.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane49196_91aed4-41\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\ud83d\ude8d <strong>Transporte:<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Para llegar a&nbsp;<strong>Sallent de Gallego<\/strong>&nbsp;consultar horarios de autobuses en&nbsp;<a href=\"http:\/\/alosa.avanzabus.com\/index.jsp\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>Alosa-avanzabus<\/strong><\/a>.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style>.kadence-column49196_527ef5-6e > .kt-inside-inner-col{display:flex;}.kadence-column49196_527ef5-6e{max-width:635px;margin-left:auto;margin-right:auto;}.wp-block-kadence-column.kb-section-dir-horizontal:not(.kb-section-md-dir-vertical)>.kt-inside-inner-col>.kadence-column49196_527ef5-6e{-webkit-flex:0 1 635px;flex:0 1 635px;max-width:unset;margin-left:unset;margin-right:unset;}.kadence-column49196_527ef5-6e > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column49196_527ef5-6e > .kt-inside-inner-col{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}.kadence-column49196_527ef5-6e > .kt-inside-inner-col,.kadence-column49196_527ef5-6e > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column49196_527ef5-6e > .kt-inside-inner-col{row-gap:var(--global-kb-gap-none, 0rem );column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column49196_527ef5-6e > .kt-inside-inner-col{flex-direction:column;}.kadence-column49196_527ef5-6e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column49196_527ef5-6e > .kt-inside-inner-col{background-color:var(--global-palette7, #EDF2F7);}.kadence-column49196_527ef5-6e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column49196_527ef5-6e{position:relative;}@media all and (min-width: 1025px){.wp-block-kadence-column.kb-section-dir-horizontal>.kt-inside-inner-col>.kadence-column49196_527ef5-6e{-webkit-flex:0 1 635px;flex:0 1 635px;max-width:unset;margin-left:unset;margin-right:unset;}}@media all and (max-width: 1024px){.kadence-column49196_527ef5-6e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.wp-block-kadence-column.kb-section-sm-dir-vertical:not(.kb-section-sm-dir-horizontal):not(.kb-section-sm-dir-specificity)>.kt-inside-inner-col>.kadence-column49196_527ef5-6e{max-width:635px;-webkit-flex:1;flex:1;margin-left:auto;margin-right:auto;}.kadence-column49196_527ef5-6e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column49196_527ef5-6e inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id49196_6d62ae-ac > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id49196_6d62ae-ac > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id49196_6d62ae-ac > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, calc(55% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(45% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id49196_6d62ae-ac > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id49196_6d62ae-ac > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id49196_6d62ae-ac > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id49196_6d62ae-ac alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column49196_1308e2-4d > .kt-inside-inner-col,.kadence-column49196_1308e2-4d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column49196_1308e2-4d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column49196_1308e2-4d > .kt-inside-inner-col{flex-direction:column;}.kadence-column49196_1308e2-4d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column49196_1308e2-4d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column49196_1308e2-4d{position:relative;}@media all and (max-width: 1024px){.kadence-column49196_1308e2-4d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column49196_1308e2-4d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column49196_1308e2-4d inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-image49196_59f666-19 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image49196_59f666-19 rounded-corners\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"152\" height=\"220\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/03\/guia_rapida4.gif\" alt=\"\" class=\"kb-img wp-image-40378\"\/><\/figure><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column49196_30c6d5-3b > .kt-inside-inner-col,.kadence-column49196_30c6d5-3b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column49196_30c6d5-3b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column49196_30c6d5-3b > .kt-inside-inner-col{flex-direction:column;}.kadence-column49196_30c6d5-3b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column49196_30c6d5-3b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column49196_30c6d5-3b{position:relative;}@media all and (max-width: 1024px){.kadence-column49196_30c6d5-3b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column49196_30c6d5-3b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column49196_30c6d5-3b inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading49196_3792bc-02, .wp-block-kadence-advancedheading.kt-adv-heading49196_3792bc-02[data-kb-block=\"kb-adv-heading49196_3792bc-02\"]{font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading49196_3792bc-02 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading49196_3792bc-02[data-kb-block=\"kb-adv-heading49196_3792bc-02\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading49196_3792bc-02 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading49196_3792bc-02[data-kb-block=\"kb-adv-heading49196_3792bc-02\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h5 id=\"guia-rapida\" class=\"kt-adv-heading49196_3792bc-02 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading49196_3792bc-02\"><em>Gu\u00eda r\u00e1pida <\/em><br><em>GR 11  <\/em><\/h5>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading49196_4fdee1-fc, .wp-block-kadence-advancedheading.kt-adv-heading49196_4fdee1-fc[data-kb-block=\"kb-adv-heading49196_4fdee1-fc\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading49196_4fdee1-fc mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading49196_4fdee1-fc[data-kb-block=\"kb-adv-heading49196_4fdee1-fc\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading49196_4fdee1-fc img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading49196_4fdee1-fc[data-kb-block=\"kb-adv-heading49196_4fdee1-fc\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading49196_4fdee1-fc wp-block-kadence-advancedheading has-theme-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading49196_4fdee1-fc\">con todo lo que debes saber antes de acometer la&nbsp;<strong>Senda Pirenaica<\/strong><br><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n\n\n<\/p>\n\n\n\n<script src=\"https:\/\/f.convertkit.com\/ckjs\/ck.5.js\"><\/script>\n      <form action=\"https:\/\/app.convertkit.com\/forms\/7013598\/subscriptions\" class=\"seva-form formkit-form\" method=\"post\" data-sv-form=\"7013598\" data-uid=\"2239231933\" data-format=\"inline\" data-version=\"5\" data-options=\"{&quot;settings&quot;:{&quot;after_subscribe&quot;:{&quot;action&quot;:&quot;message&quot;,&quot;success_message&quot;:&quot;\u00a1La tienes! Chequea tu email, que te hemos enviado la gu\u00eda r\u00e1pida. \\n&quot;,&quot;redirect_url&quot;:&quot;&quot;},&quot;analytics&quot;:{&quot;google&quot;:null,&quot;fathom&quot;:null,&quot;facebook&quot;:null,&quot;segment&quot;:null,&quot;pinterest&quot;:null,&quot;sparkloop&quot;:null,&quot;googletagmanager&quot;:null},&quot;modal&quot;:{&quot;trigger&quot;:&quot;timer&quot;,&quot;scroll_percentage&quot;:null,&quot;timer&quot;:5,&quot;devices&quot;:&quot;all&quot;,&quot;show_once_every&quot;:15},&quot;powered_by&quot;:{&quot;show&quot;:true,&quot;url&quot;:&quot;https:\/\/convertkit.com\/features\/forms?utm_campaign=poweredby&amp;utm_content=form&amp;utm_medium=referral&amp;utm_source=dynamic&quot;},&quot;recaptcha&quot;:{&quot;enabled&quot;:false},&quot;return_visitor&quot;:{&quot;action&quot;:&quot;show&quot;,&quot;custom_content&quot;:&quot;&quot;},&quot;slide_in&quot;:{&quot;display_in&quot;:&quot;bottom_right&quot;,&quot;trigger&quot;:&quot;timer&quot;,&quot;scroll_percentage&quot;:null,&quot;timer&quot;:5,&quot;devices&quot;:&quot;all&quot;,&quot;show_once_every&quot;:15},&quot;sticky_bar&quot;:{&quot;display_in&quot;:&quot;top&quot;,&quot;trigger&quot;:&quot;timer&quot;,&quot;scroll_percentage&quot;:null,&quot;timer&quot;:5,&quot;devices&quot;:&quot;all&quot;,&quot;show_once_every&quot;:15}},&quot;version&quot;:&quot;5&quot;}\" min-width=\"400 500 600 700 800\"><div data-style=\"clean\"><ul class=\"formkit-alert formkit-alert-error\" data-element=\"errors\" data-group=\"alert\"><\/ul><div data-element=\"fields\" data-stacked=\"false\" class=\"seva-fields formkit-fields\"><div class=\"formkit-field\"><input class=\"formkit-input\" name=\"email_address\" aria-label=\"Email Address\" placeholder=\"Email Address\" required=\"\" type=\"email\" style=\"color: rgb(0, 0, 0); border-color: rgb(227, 227, 227); border-radius: 4px; font-weight: 400;\"><\/div><button data-element=\"submit\" class=\"formkit-submit formkit-submit\" style=\"color: rgb(255, 255, 255); background-color: rgb(210, 219, 108); border-radius: 4px; font-weight: 700;\"><div class=\"formkit-spinner\"><div><\/div><div><\/div><div><\/div><\/div><span class=\"\">I WANT IT<\/span><\/button><\/div><div class=\"formkit-powered-by-convertkit-container\"><a href=\"https:\/\/convertkit.com\/features\/forms?utm_campaign=poweredby&amp;utm_content=form&amp;utm_medium=referral&amp;utm_source=dynamic\" data-element=\"powered-by\" class=\"formkit-powered-by-convertkit\" data-variant=\"dark\" target=\"_blank\" rel=\"nofollow noopener\">Built with ConvertKit<\/a><\/div><\/div><style>.formkit-form[data-uid=\"2239231933\"] *{box-sizing:border-box;}.formkit-form[data-uid=\"2239231933\"]{-webkit-font-smoothing:antialiased;-moz-osx-font-smoothing:grayscale;}.formkit-form[data-uid=\"2239231933\"] legend{border:none;font-size:inherit;margin-bottom:10px;padding:0;position:relative;display:table;}.formkit-form[data-uid=\"2239231933\"] fieldset{border:0;padding:0.01em 0 0 0;margin:0;min-width:0;}.formkit-form[data-uid=\"2239231933\"] body:not(:-moz-handler-blocked) fieldset{display:table-cell;}.formkit-form[data-uid=\"2239231933\"] h1,.formkit-form[data-uid=\"2239231933\"] h2,.formkit-form[data-uid=\"2239231933\"] h3,.formkit-form[data-uid=\"2239231933\"] h4,.formkit-form[data-uid=\"2239231933\"] h5,.formkit-form[data-uid=\"2239231933\"] h6{color:inherit;font-size:inherit;font-weight:inherit;}.formkit-form[data-uid=\"2239231933\"] h2{font-size:1.5em;margin:1em 0;}.formkit-form[data-uid=\"2239231933\"] h3{font-size:1.17em;margin:1em 0;}.formkit-form[data-uid=\"2239231933\"] p{color:inherit;font-size:inherit;font-weight:inherit;}.formkit-form[data-uid=\"2239231933\"] ol:not([template-default]),.formkit-form[data-uid=\"2239231933\"] ul:not([template-default]),.formkit-form[data-uid=\"2239231933\"] blockquote:not([template-default]){text-align:left;}.formkit-form[data-uid=\"2239231933\"] p:not([template-default]),.formkit-form[data-uid=\"2239231933\"] hr:not([template-default]),.formkit-form[data-uid=\"2239231933\"] blockquote:not([template-default]),.formkit-form[data-uid=\"2239231933\"] ol:not([template-default]),.formkit-form[data-uid=\"2239231933\"] ul:not([template-default]){color:inherit;font-style:initial;}.formkit-form[data-uid=\"2239231933\"] .ordered-list,.formkit-form[data-uid=\"2239231933\"] .unordered-list{list-style-position:outside !important;padding-left:1em;}.formkit-form[data-uid=\"2239231933\"] .list-item{padding-left:0;}.formkit-form[data-uid=\"2239231933\"][data-format=\"modal\"]{display:none;}.formkit-form[data-uid=\"2239231933\"][data-format=\"slide in\"]{display:none;}.formkit-form[data-uid=\"2239231933\"][data-format=\"sticky bar\"]{display:none;}.formkit-sticky-bar .formkit-form[data-uid=\"2239231933\"][data-format=\"sticky bar\"]{display:block;}.formkit-form[data-uid=\"2239231933\"] .formkit-input,.formkit-form[data-uid=\"2239231933\"] .formkit-select,.formkit-form[data-uid=\"2239231933\"] .formkit-checkboxes{width:100%;}.formkit-form[data-uid=\"2239231933\"] .formkit-button,.formkit-form[data-uid=\"2239231933\"] .formkit-submit{border:0;border-radius:5px;color:#ffffff;cursor:pointer;display:inline-block;text-align:center;font-size:15px;font-weight:500;cursor:pointer;margin-bottom:15px;overflow:hidden;padding:0;position:relative;vertical-align:middle;}.formkit-form[data-uid=\"2239231933\"] .formkit-button:hover,.formkit-form[data-uid=\"2239231933\"] .formkit-submit:hover,.formkit-form[data-uid=\"2239231933\"] .formkit-button:focus,.formkit-form[data-uid=\"2239231933\"] .formkit-submit:focus{outline:none;}.formkit-form[data-uid=\"2239231933\"] .formkit-button:hover > span,.formkit-form[data-uid=\"2239231933\"] .formkit-submit:hover > span,.formkit-form[data-uid=\"2239231933\"] .formkit-button:focus > span,.formkit-form[data-uid=\"2239231933\"] .formkit-submit:focus > span{background-color:rgba(0,0,0,0.1);}.formkit-form[data-uid=\"2239231933\"] .formkit-button > span,.formkit-form[data-uid=\"2239231933\"] .formkit-submit > span{display:block;-webkit-transition:all 300ms ease-in-out;transition:all 300ms ease-in-out;padding:12px 24px;}.formkit-form[data-uid=\"2239231933\"] .formkit-input{background:#ffffff;font-size:15px;padding:12px;border:1px solid #e3e3e3;-webkit-flex:1 0 auto;-ms-flex:1 0 auto;flex:1 0 auto;line-height:1.4;margin:0;-webkit-transition:border-color ease-out 300ms;transition:border-color ease-out 300ms;}.formkit-form[data-uid=\"2239231933\"] .formkit-input:focus{outline:none;border-color:#1677be;-webkit-transition:border-color ease 300ms;transition:border-color ease 300ms;}.formkit-form[data-uid=\"2239231933\"] .formkit-input::-webkit-input-placeholder{color:inherit;opacity:0.8;}.formkit-form[data-uid=\"2239231933\"] .formkit-input::-moz-placeholder{color:inherit;opacity:0.8;}.formkit-form[data-uid=\"2239231933\"] .formkit-input:-ms-input-placeholder{color:inherit;opacity:0.8;}.formkit-form[data-uid=\"2239231933\"] .formkit-input::placeholder{color:inherit;opacity:0.8;}.formkit-form[data-uid=\"2239231933\"] [data-group=\"dropdown\"]{position:relative;display:inline-block;width:100%;}.formkit-form[data-uid=\"2239231933\"] [data-group=\"dropdown\"]::before{content:\"\";top:calc(50% - 2.5px);right:10px;position:absolute;pointer-events:none;border-color:#4f4f4f transparent transparent transparent;border-style:solid;border-width:6px 6px 0 6px;height:0;width:0;z-index:999;}.formkit-form[data-uid=\"2239231933\"] [data-group=\"dropdown\"] select{height:auto;width:100%;cursor:pointer;color:#333333;line-height:1.4;margin-bottom:0;padding:0 6px;-webkit-appearance:none;-moz-appearance:none;appearance:none;font-size:15px;padding:12px;padding-right:25px;border:1px solid #e3e3e3;background:#ffffff;}.formkit-form[data-uid=\"2239231933\"] [data-group=\"dropdown\"] select:focus{outline:none;}.formkit-form[data-uid=\"2239231933\"] [data-group=\"checkboxes\"]{text-align:left;margin:0;}.formkit-form[data-uid=\"2239231933\"] [data-group=\"checkboxes\"] [data-group=\"checkbox\"]{margin-bottom:10px;}.formkit-form[data-uid=\"2239231933\"] [data-group=\"checkboxes\"] [data-group=\"checkbox\"] *{cursor:pointer;}.formkit-form[data-uid=\"2239231933\"] [data-group=\"checkboxes\"] [data-group=\"checkbox\"]:last-of-type{margin-bottom:0;}.formkit-form[data-uid=\"2239231933\"] [data-group=\"checkboxes\"] [data-group=\"checkbox\"] input[type=\"checkbox\"]{display:none;}.formkit-form[data-uid=\"2239231933\"] [data-group=\"checkboxes\"] [data-group=\"checkbox\"] input[type=\"checkbox\"] + label::after{content:none;}.formkit-form[data-uid=\"2239231933\"] [data-group=\"checkboxes\"] [data-group=\"checkbox\"] input[type=\"checkbox\"]:checked + label::after{border-color:#ffffff;content:\"\";}.formkit-form[data-uid=\"2239231933\"] [data-group=\"checkboxes\"] [data-group=\"checkbox\"] input[type=\"checkbox\"]:checked + label::before{background:#10bf7a;border-color:#10bf7a;}.formkit-form[data-uid=\"2239231933\"] [data-group=\"checkboxes\"] [data-group=\"checkbox\"] label{position:relative;display:inline-block;padding-left:28px;}.formkit-form[data-uid=\"2239231933\"] [data-group=\"checkboxes\"] [data-group=\"checkbox\"] label::before,.formkit-form[data-uid=\"2239231933\"] [data-group=\"checkboxes\"] [data-group=\"checkbox\"] label::after{position:absolute;content:\"\";display:inline-block;}.formkit-form[data-uid=\"2239231933\"] [data-group=\"checkboxes\"] [data-group=\"checkbox\"] label::before{height:16px;width:16px;border:1px solid #e3e3e3;background:#ffffff;left:0px;top:3px;}.formkit-form[data-uid=\"2239231933\"] [data-group=\"checkboxes\"] [data-group=\"checkbox\"] label::after{height:4px;width:8px;border-left:2px solid #4d4d4d;border-bottom:2px solid #4d4d4d;-webkit-transform:rotate(-45deg);-ms-transform:rotate(-45deg);transform:rotate(-45deg);left:4px;top:8px;}.formkit-form[data-uid=\"2239231933\"] .formkit-alert{background:#f9fafb;border:1px solid #e3e3e3;border-radius:5px;-webkit-flex:1 0 auto;-ms-flex:1 0 auto;flex:1 0 auto;list-style:none;margin:25px auto;padding:12px;text-align:center;width:100%;}.formkit-form[data-uid=\"2239231933\"] .formkit-alert:empty{display:none;}.formkit-form[data-uid=\"2239231933\"] .formkit-alert-success{background:#d3fbeb;border-color:#10bf7a;color:#0c905c;}.formkit-form[data-uid=\"2239231933\"] .formkit-alert-error{background:#fde8e2;border-color:#f2643b;color:#ea4110;}.formkit-form[data-uid=\"2239231933\"] .formkit-spinner{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;height:0px;width:0px;margin:0 auto;position:absolute;top:0;left:0;right:0;width:0px;overflow:hidden;text-align:center;-webkit-transition:all 300ms ease-in-out;transition:all 300ms ease-in-out;}.formkit-form[data-uid=\"2239231933\"] .formkit-spinner > div{margin:auto;width:12px;height:12px;background-color:#fff;opacity:0.3;border-radius:100%;display:inline-block;-webkit-animation:formkit-bouncedelay-formkit-form-data-uid-2239231933- 1.4s infinite ease-in-out both;animation:formkit-bouncedelay-formkit-form-data-uid-2239231933- 1.4s infinite ease-in-out both;}.formkit-form[data-uid=\"2239231933\"] .formkit-spinner > div:nth-child(1){-webkit-animation-delay:-0.32s;animation-delay:-0.32s;}.formkit-form[data-uid=\"2239231933\"] .formkit-spinner > div:nth-child(2){-webkit-animation-delay:-0.16s;animation-delay:-0.16s;}.formkit-form[data-uid=\"2239231933\"] .formkit-submit[data-active] .formkit-spinner{opacity:1;height:100%;width:50px;}.formkit-form[data-uid=\"2239231933\"] .formkit-submit[data-active] .formkit-spinner ~ span{opacity:0;}.formkit-form[data-uid=\"2239231933\"] .formkit-powered-by[data-active=\"false\"]{opacity:0.35;}.formkit-form[data-uid=\"2239231933\"] .formkit-powered-by-convertkit-container{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;width:100%;margin:10px 0;position:relative;}.formkit-form[data-uid=\"2239231933\"] .formkit-powered-by-convertkit-container[data-active=\"false\"]{opacity:0.35;}.formkit-form[data-uid=\"2239231933\"] .formkit-powered-by-convertkit{-webkit-align-items:center;-webkit-box-align:center;-ms-flex-align:center;align-items:center;background-color:#ffffff;border:1px solid #dde2e7;border-radius:4px;color:#373f45;cursor:pointer;display:block;height:36px;margin:0 auto;opacity:0.95;padding:0;-webkit-text-decoration:none;text-decoration:none;text-indent:100%;-webkit-transition:ease-in-out all 200ms;transition:ease-in-out all 200ms;white-space:nowrap;overflow:hidden;-webkit-user-select:none;-moz-user-select:none;-ms-user-select:none;user-select:none;width:190px;background-repeat:no-repeat;background-position:center;background-image:url(\"data:image\/svg+xml;charset=utf8,%3Csvg width='162' height='20' viewBox='0 0 162 20' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath d='M83.0561 15.2457C86.675 15.2457 89.4722 12.5154 89.4722 9.14749C89.4722 5.99211 86.8443 4.06563 85.1038 4.06563C82.6801 4.06563 80.7373 5.76407 80.4605 8.28551C80.4092 8.75244 80.0387 9.14403 79.5686 9.14069C78.7871 9.13509 77.6507 9.12841 76.9314 9.13092C76.6217 9.13199 76.3658 8.88106 76.381 8.57196C76.4895 6.38513 77.2218 4.3404 78.618 2.76974C80.1695 1.02445 82.4289 0 85.1038 0C89.5979 0 93.8406 4.07791 93.8406 9.14749C93.8406 14.7608 89.1832 19.3113 83.1517 19.3113C78.8502 19.3113 74.5179 16.5041 73.0053 12.5795C72.9999 12.565 72.9986 12.5492 73.0015 12.534C73.0218 12.4179 73.0617 12.3118 73.1011 12.2074C73.1583 12.0555 73.2143 11.907 73.2062 11.7359L73.18 11.1892C73.174 11.0569 73.2075 10.9258 73.2764 10.8127C73.3452 10.6995 73.4463 10.6094 73.5666 10.554L73.7852 10.4523C73.9077 10.3957 74.0148 10.3105 74.0976 10.204C74.1803 10.0974 74.2363 9.97252 74.2608 9.83983C74.3341 9.43894 74.6865 9.14749 75.0979 9.14749C75.7404 9.14749 76.299 9.57412 76.5088 10.1806C77.5188 13.1 79.1245 15.2457 83.0561 15.2457Z' fill='%23373F45'\/%3E%3Cpath d='M155.758 6.91365C155.028 6.91365 154.804 6.47916 154.804 5.98857C154.804 5.46997 154.986 5.06348 155.758 5.06348C156.53 5.06348 156.712 5.46997 156.712 5.98857C156.712 6.47905 156.516 6.91365 155.758 6.91365ZM142.441 12.9304V9.32833L141.415 9.32323V8.90392C141.415 8.44719 141.786 8.07758 142.244 8.07986L142.441 8.08095V6.55306L144.082 6.09057V8.08073H145.569V8.50416C145.569 8.61242 145.548 8.71961 145.506 8.81961C145.465 8.91961 145.404 9.01047 145.328 9.08699C145.251 9.16351 145.16 9.2242 145.06 9.26559C144.96 9.30698 144.853 9.32826 144.745 9.32822H144.082V12.7201C144.082 13.2423 144.378 13.4256 144.76 13.4887C145.209 13.5629 145.583 13.888 145.583 14.343V14.9626C144.029 14.9626 142.441 14.8942 142.441 12.9304Z' fill='%23373F45'\/%3E%3Cpath d='M110.058 7.92554C108.417 7.88344 106.396 8.92062 106.396 11.5137C106.396 14.0646 108.417 15.0738 110.058 15.0318C111.742 15.0738 113.748 14.0646 113.748 11.5137C113.748 8.92062 111.742 7.88344 110.058 7.92554ZM110.07 13.7586C108.878 13.7586 108.032 12.8905 108.032 11.461C108.032 10.1013 108.878 9.20569 110.071 9.20569C111.263 9.20569 112.101 10.0995 112.101 11.459C112.101 12.8887 111.263 13.7586 110.07 13.7586Z' fill='%23373F45'\/%3E%3Cpath d='M118.06 7.94098C119.491 7.94098 120.978 8.33337 120.978 11.1366V14.893H120.063C119.608 14.893 119.238 14.524 119.238 14.0689V10.9965C119.238 9.66506 118.747 9.16047 117.891 9.16047C117.414 9.16047 116.797 9.52486 116.502 9.81915V14.069C116.502 14.1773 116.481 14.2845 116.44 14.3845C116.398 14.4845 116.337 14.5753 116.261 14.6519C116.184 14.7284 116.093 14.7891 115.993 14.8305C115.893 14.8719 115.786 14.8931 115.678 14.8931H114.847V8.10918H115.773C115.932 8.10914 116.087 8.16315 116.212 8.26242C116.337 8.36168 116.424 8.50033 116.46 8.65577C116.881 8.19328 117.428 7.94098 118.06 7.94098ZM122.854 8.09713C123.024 8.09708 123.19 8.1496 123.329 8.2475C123.468 8.34541 123.574 8.48391 123.631 8.64405L125.133 12.8486L126.635 8.64415C126.692 8.48402 126.798 8.34551 126.937 8.2476C127.076 8.1497 127.242 8.09718 127.412 8.09724H128.598L126.152 14.3567C126.091 14.5112 125.986 14.6439 125.849 14.7374C125.711 14.831 125.549 14.881 125.383 14.8809H124.333L121.668 8.09713H122.854Z' fill='%23373F45'\/%3E%3Cpath d='M135.085 14.5514C134.566 14.7616 133.513 15.0416 132.418 15.0416C130.496 15.0416 129.024 13.9345 129.024 11.4396C129.024 9.19701 130.451 7.99792 132.191 7.99792C134.338 7.99792 135.254 9.4378 135.158 11.3979C135.139 11.8029 134.786 12.0983 134.38 12.0983H130.679C130.763 13.1916 131.562 13.7662 132.615 13.7662C133.028 13.7662 133.462 13.7452 133.983 13.6481C134.535 13.545 135.085 13.9375 135.085 14.4985V14.5514ZM133.673 10.949C133.785 9.87621 133.061 9.28752 132.191 9.28752C131.321 9.28752 130.734 9.93979 130.679 10.9489L133.673 10.949Z' fill='%23373F45'\/%3E%3Cpath d='M137.345 8.11122C137.497 8.11118 137.645 8.16229 137.765 8.25635C137.884 8.35041 137.969 8.48197 138.005 8.62993C138.566 8.20932 139.268 7.94303 139.759 7.94303C139.801 7.94303 140.068 7.94303 140.489 7.99913V8.7265C140.489 9.11748 140.15 9.4147 139.759 9.4147C139.31 9.4147 138.651 9.5829 138.131 9.8773V14.8951H136.462V8.11112L137.345 8.11122ZM156.6 14.0508V8.09104H155.769C155.314 8.09104 154.944 8.45999 154.944 8.9151V14.8748H155.775C156.23 14.8748 156.6 14.5058 156.6 14.0508ZM158.857 12.9447V9.34254H157.749V8.91912C157.749 8.46401 158.118 8.09506 158.574 8.09506H158.857V6.56739L160.499 6.10479V8.09506H161.986V8.51848C161.986 8.97359 161.617 9.34254 161.161 9.34254H160.499V12.7345C160.499 13.2566 160.795 13.44 161.177 13.503C161.626 13.5774 162 13.9024 162 14.3574V14.977C160.446 14.977 158.857 14.9086 158.857 12.9447ZM98.1929 10.1124C98.2033 6.94046 100.598 5.16809 102.895 5.16809C104.171 5.16809 105.342 5.44285 106.304 6.12953L105.914 6.6631C105.654 7.02011 105.16 7.16194 104.749 6.99949C104.169 6.7702 103.622 6.7218 103.215 6.7218C101.335 6.7218 99.9169 7.92849 99.9068 10.1123C99.9169 12.2959 101.335 13.5201 103.215 13.5201C103.622 13.5201 104.169 13.4717 104.749 13.2424C105.16 13.0799 105.654 13.2046 105.914 13.5615L106.304 14.0952C105.342 14.7819 104.171 15.0566 102.895 15.0566C100.598 15.0566 98.2033 13.2842 98.1929 10.1124ZM147.619 5.21768C148.074 5.21768 148.444 5.58663 148.444 6.04174V9.81968L151.82 5.58131C151.897 5.47733 151.997 5.39282 152.112 5.3346C152.227 5.27638 152.355 5.24607 152.484 5.24611H153.984L150.166 10.0615L153.984 14.8749H152.484C152.355 14.8749 152.227 14.8446 152.112 14.7864C151.997 14.7281 151.897 14.6436 151.82 14.5397L148.444 10.3025V14.0508C148.444 14.5059 148.074 14.8749 147.619 14.8749H146.746V5.21768H147.619Z' fill='%23373F45'\/%3E%3Cpath d='M0.773438 6.5752H2.68066C3.56543 6.5752 4.2041 6.7041 4.59668 6.96191C4.99219 7.21973 5.18994 7.62695 5.18994 8.18359C5.18994 8.55859 5.09326 8.87061 4.8999 9.11963C4.70654 9.36865 4.42822 9.52539 4.06494 9.58984V9.63379C4.51611 9.71875 4.84717 9.88721 5.05811 10.1392C5.27197 10.3882 5.37891 10.7266 5.37891 11.1543C5.37891 11.7314 5.17676 12.1841 4.77246 12.5122C4.37109 12.8374 3.81152 13 3.09375 13H0.773438V6.5752ZM1.82373 9.22949H2.83447C3.27393 9.22949 3.59473 9.16064 3.79688 9.02295C3.99902 8.88232 4.1001 8.64502 4.1001 8.31104C4.1001 8.00928 3.99023 7.79102 3.77051 7.65625C3.55371 7.52148 3.20801 7.4541 2.7334 7.4541H1.82373V9.22949ZM1.82373 10.082V12.1167H2.93994C3.37939 12.1167 3.71045 12.0332 3.93311 11.8662C4.15869 11.6963 4.27148 11.4297 4.27148 11.0664C4.27148 10.7324 4.15723 10.4849 3.92871 10.3237C3.7002 10.1626 3.35303 10.082 2.88721 10.082H1.82373Z' fill='%23373F45'\/%3E%3Cpath d='M13.011 6.5752V10.7324C13.011 11.207 12.9084 11.623 12.7034 11.9805C12.5012 12.335 12.2068 12.6089 11.8201 12.8022C11.4363 12.9927 10.9763 13.0879 10.4402 13.0879C9.6433 13.0879 9.02368 12.877 8.5813 12.4551C8.13892 12.0332 7.91772 11.4531 7.91772 10.7148V6.5752H8.9724V10.6401C8.9724 11.1704 9.09546 11.5615 9.34155 11.8135C9.58765 12.0654 9.96557 12.1914 10.4753 12.1914C11.4656 12.1914 11.9607 11.6714 11.9607 10.6313V6.5752H13.011Z' fill='%23373F45'\/%3E%3Cpath d='M15.9146 13V6.5752H16.9649V13H15.9146Z' fill='%23373F45'\/%3E%3Cpath d='M19.9255 13V6.5752H20.9758V12.0991H23.696V13H19.9255Z' fill='%23373F45'\/%3E%3Cpath d='M28.2828 13H27.2325V7.47607H25.3428V6.5752H30.1724V7.47607H28.2828V13Z' fill='%23373F45'\/%3E%3Cpath d='M41.9472 13H40.8046L39.7148 9.16796C39.6679 9.00097 39.6093 8.76074 39.539 8.44727C39.4687 8.13086 39.4262 7.91113 39.4116 7.78809C39.3823 7.97559 39.3339 8.21875 39.2665 8.51758C39.2021 8.81641 39.1479 9.03905 39.1039 9.18554L38.0405 13H36.8979L36.0673 9.7832L35.2236 6.5752H36.2958L37.2143 10.3193C37.3578 10.9199 37.4604 11.4502 37.5219 11.9102C37.5541 11.6611 37.6025 11.3828 37.6669 11.0752C37.7314 10.7676 37.79 10.5186 37.8427 10.3281L38.8886 6.5752H39.9301L41.0024 10.3457C41.1049 10.6943 41.2133 11.2158 41.3276 11.9102C41.3715 11.4912 41.477 10.958 41.644 10.3105L42.558 6.5752H43.6215L41.9472 13Z' fill='%23373F45'\/%3E%3Cpath d='M45.7957 13V6.5752H46.846V13H45.7957Z' fill='%23373F45'\/%3E%3Cpath d='M52.0258 13H50.9755V7.47607H49.0859V6.5752H53.9155V7.47607H52.0258V13Z' fill='%23373F45'\/%3E%3Cpath d='M61.2312 13H60.1765V10.104H57.2146V13H56.1643V6.5752H57.2146V9.20312H60.1765V6.5752H61.2312V13Z' fill='%23373F45'\/%3E%3C\/svg%3E\");}.formkit-form[data-uid=\"2239231933\"] .formkit-powered-by-convertkit:hover,.formkit-form[data-uid=\"2239231933\"] .formkit-powered-by-convertkit:focus{background-color:#ffffff;-webkit-transform:scale(1.025) perspective(1px);-ms-transform:scale(1.025) perspective(1px);transform:scale(1.025) perspective(1px);opacity:1;}.formkit-form[data-uid=\"2239231933\"] .formkit-powered-by-convertkit[data-variant=\"dark\"],.formkit-form[data-uid=\"2239231933\"] .formkit-powered-by-convertkit[data-variant=\"light\"]{background-color:transparent;border-color:transparent;width:166px;}.formkit-form[data-uid=\"2239231933\"] .formkit-powered-by-convertkit[data-variant=\"light\"]{color:#ffffff;background-image:url(\"data:image\/svg+xml;charset=utf8,%3Csvg width='162' height='20' viewBox='0 0 162 20' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath d='M83.0561 15.2457C86.675 15.2457 89.4722 12.5154 89.4722 9.14749C89.4722 5.99211 86.8443 4.06563 85.1038 4.06563C82.6801 4.06563 80.7373 5.76407 80.4605 8.28551C80.4092 8.75244 80.0387 9.14403 79.5686 9.14069C78.7871 9.13509 77.6507 9.12841 76.9314 9.13092C76.6217 9.13199 76.3658 8.88106 76.381 8.57196C76.4895 6.38513 77.2218 4.3404 78.618 2.76974C80.1695 1.02445 82.4289 0 85.1038 0C89.5979 0 93.8406 4.07791 93.8406 9.14749C93.8406 14.7608 89.1832 19.3113 83.1517 19.3113C78.8502 19.3113 74.5179 16.5041 73.0053 12.5795C72.9999 12.565 72.9986 12.5492 73.0015 12.534C73.0218 12.4179 73.0617 12.3118 73.1011 12.2074C73.1583 12.0555 73.2143 11.907 73.2062 11.7359L73.18 11.1892C73.174 11.0569 73.2075 10.9258 73.2764 10.8127C73.3452 10.6995 73.4463 10.6094 73.5666 10.554L73.7852 10.4523C73.9077 10.3957 74.0148 10.3105 74.0976 10.204C74.1803 10.0974 74.2363 9.97252 74.2608 9.83983C74.3341 9.43894 74.6865 9.14749 75.0979 9.14749C75.7404 9.14749 76.299 9.57412 76.5088 10.1806C77.5188 13.1 79.1245 15.2457 83.0561 15.2457Z' fill='white'\/%3E%3Cpath d='M155.758 6.91365C155.028 6.91365 154.804 6.47916 154.804 5.98857C154.804 5.46997 154.986 5.06348 155.758 5.06348C156.53 5.06348 156.712 5.46997 156.712 5.98857C156.712 6.47905 156.516 6.91365 155.758 6.91365ZM142.441 12.9304V9.32833L141.415 9.32323V8.90392C141.415 8.44719 141.786 8.07758 142.244 8.07986L142.441 8.08095V6.55306L144.082 6.09057V8.08073H145.569V8.50416C145.569 8.61242 145.548 8.71961 145.506 8.81961C145.465 8.91961 145.404 9.01047 145.328 9.08699C145.251 9.16351 145.16 9.2242 145.06 9.26559C144.96 9.30698 144.853 9.32826 144.745 9.32822H144.082V12.7201C144.082 13.2423 144.378 13.4256 144.76 13.4887C145.209 13.5629 145.583 13.888 145.583 14.343V14.9626C144.029 14.9626 142.441 14.8942 142.441 12.9304Z' fill='white'\/%3E%3Cpath d='M110.058 7.92554C108.417 7.88344 106.396 8.92062 106.396 11.5137C106.396 14.0646 108.417 15.0738 110.058 15.0318C111.742 15.0738 113.748 14.0646 113.748 11.5137C113.748 8.92062 111.742 7.88344 110.058 7.92554ZM110.07 13.7586C108.878 13.7586 108.032 12.8905 108.032 11.461C108.032 10.1013 108.878 9.20569 110.071 9.20569C111.263 9.20569 112.101 10.0995 112.101 11.459C112.101 12.8887 111.263 13.7586 110.07 13.7586Z' fill='white'\/%3E%3Cpath d='M118.06 7.94098C119.491 7.94098 120.978 8.33337 120.978 11.1366V14.893H120.063C119.608 14.893 119.238 14.524 119.238 14.0689V10.9965C119.238 9.66506 118.747 9.16047 117.891 9.16047C117.414 9.16047 116.797 9.52486 116.502 9.81915V14.069C116.502 14.1773 116.481 14.2845 116.44 14.3845C116.398 14.4845 116.337 14.5753 116.261 14.6519C116.184 14.7284 116.093 14.7891 115.993 14.8305C115.893 14.8719 115.786 14.8931 115.678 14.8931H114.847V8.10918H115.773C115.932 8.10914 116.087 8.16315 116.212 8.26242C116.337 8.36168 116.424 8.50033 116.46 8.65577C116.881 8.19328 117.428 7.94098 118.06 7.94098ZM122.854 8.09713C123.024 8.09708 123.19 8.1496 123.329 8.2475C123.468 8.34541 123.574 8.48391 123.631 8.64405L125.133 12.8486L126.635 8.64415C126.692 8.48402 126.798 8.34551 126.937 8.2476C127.076 8.1497 127.242 8.09718 127.412 8.09724H128.598L126.152 14.3567C126.091 14.5112 125.986 14.6439 125.849 14.7374C125.711 14.831 125.549 14.881 125.383 14.8809H124.333L121.668 8.09713H122.854Z' fill='white'\/%3E%3Cpath d='M135.085 14.5514C134.566 14.7616 133.513 15.0416 132.418 15.0416C130.496 15.0416 129.024 13.9345 129.024 11.4396C129.024 9.19701 130.451 7.99792 132.191 7.99792C134.338 7.99792 135.254 9.4378 135.158 11.3979C135.139 11.8029 134.786 12.0983 134.38 12.0983H130.679C130.763 13.1916 131.562 13.7662 132.615 13.7662C133.028 13.7662 133.462 13.7452 133.983 13.6481C134.535 13.545 135.085 13.9375 135.085 14.4985V14.5514ZM133.673 10.949C133.785 9.87621 133.061 9.28752 132.191 9.28752C131.321 9.28752 130.734 9.93979 130.679 10.9489L133.673 10.949Z' fill='white'\/%3E%3Cpath d='M137.345 8.11122C137.497 8.11118 137.645 8.16229 137.765 8.25635C137.884 8.35041 137.969 8.48197 138.005 8.62993C138.566 8.20932 139.268 7.94303 139.759 7.94303C139.801 7.94303 140.068 7.94303 140.489 7.99913V8.7265C140.489 9.11748 140.15 9.4147 139.759 9.4147C139.31 9.4147 138.651 9.5829 138.131 9.8773V14.8951H136.462V8.11112L137.345 8.11122ZM156.6 14.0508V8.09104H155.769C155.314 8.09104 154.944 8.45999 154.944 8.9151V14.8748H155.775C156.23 14.8748 156.6 14.5058 156.6 14.0508ZM158.857 12.9447V9.34254H157.749V8.91912C157.749 8.46401 158.118 8.09506 158.574 8.09506H158.857V6.56739L160.499 6.10479V8.09506H161.986V8.51848C161.986 8.97359 161.617 9.34254 161.161 9.34254H160.499V12.7345C160.499 13.2566 160.795 13.44 161.177 13.503C161.626 13.5774 162 13.9024 162 14.3574V14.977C160.446 14.977 158.857 14.9086 158.857 12.9447ZM98.1929 10.1124C98.2033 6.94046 100.598 5.16809 102.895 5.16809C104.171 5.16809 105.342 5.44285 106.304 6.12953L105.914 6.6631C105.654 7.02011 105.16 7.16194 104.749 6.99949C104.169 6.7702 103.622 6.7218 103.215 6.7218C101.335 6.7218 99.9169 7.92849 99.9068 10.1123C99.9169 12.2959 101.335 13.5201 103.215 13.5201C103.622 13.5201 104.169 13.4717 104.749 13.2424C105.16 13.0799 105.654 13.2046 105.914 13.5615L106.304 14.0952C105.342 14.7819 104.171 15.0566 102.895 15.0566C100.598 15.0566 98.2033 13.2842 98.1929 10.1124ZM147.619 5.21768C148.074 5.21768 148.444 5.58663 148.444 6.04174V9.81968L151.82 5.58131C151.897 5.47733 151.997 5.39282 152.112 5.3346C152.227 5.27638 152.355 5.24607 152.484 5.24611H153.984L150.166 10.0615L153.984 14.8749H152.484C152.355 14.8749 152.227 14.8446 152.112 14.7864C151.997 14.7281 151.897 14.6436 151.82 14.5397L148.444 10.3025V14.0508C148.444 14.5059 148.074 14.8749 147.619 14.8749H146.746V5.21768H147.619Z' fill='white'\/%3E%3Cpath d='M0.773438 6.5752H2.68066C3.56543 6.5752 4.2041 6.7041 4.59668 6.96191C4.99219 7.21973 5.18994 7.62695 5.18994 8.18359C5.18994 8.55859 5.09326 8.87061 4.8999 9.11963C4.70654 9.36865 4.42822 9.52539 4.06494 9.58984V9.63379C4.51611 9.71875 4.84717 9.88721 5.05811 10.1392C5.27197 10.3882 5.37891 10.7266 5.37891 11.1543C5.37891 11.7314 5.17676 12.1841 4.77246 12.5122C4.37109 12.8374 3.81152 13 3.09375 13H0.773438V6.5752ZM1.82373 9.22949H2.83447C3.27393 9.22949 3.59473 9.16064 3.79688 9.02295C3.99902 8.88232 4.1001 8.64502 4.1001 8.31104C4.1001 8.00928 3.99023 7.79102 3.77051 7.65625C3.55371 7.52148 3.20801 7.4541 2.7334 7.4541H1.82373V9.22949ZM1.82373 10.082V12.1167H2.93994C3.37939 12.1167 3.71045 12.0332 3.93311 11.8662C4.15869 11.6963 4.27148 11.4297 4.27148 11.0664C4.27148 10.7324 4.15723 10.4849 3.92871 10.3237C3.7002 10.1626 3.35303 10.082 2.88721 10.082H1.82373Z' fill='white'\/%3E%3Cpath d='M13.011 6.5752V10.7324C13.011 11.207 12.9084 11.623 12.7034 11.9805C12.5012 12.335 12.2068 12.6089 11.8201 12.8022C11.4363 12.9927 10.9763 13.0879 10.4402 13.0879C9.6433 13.0879 9.02368 12.877 8.5813 12.4551C8.13892 12.0332 7.91772 11.4531 7.91772 10.7148V6.5752H8.9724V10.6401C8.9724 11.1704 9.09546 11.5615 9.34155 11.8135C9.58765 12.0654 9.96557 12.1914 10.4753 12.1914C11.4656 12.1914 11.9607 11.6714 11.9607 10.6313V6.5752H13.011Z' fill='white'\/%3E%3Cpath d='M15.9146 13V6.5752H16.9649V13H15.9146Z' fill='white'\/%3E%3Cpath d='M19.9255 13V6.5752H20.9758V12.0991H23.696V13H19.9255Z' fill='white'\/%3E%3Cpath d='M28.2828 13H27.2325V7.47607H25.3428V6.5752H30.1724V7.47607H28.2828V13Z' fill='white'\/%3E%3Cpath d='M41.9472 13H40.8046L39.7148 9.16796C39.6679 9.00097 39.6093 8.76074 39.539 8.44727C39.4687 8.13086 39.4262 7.91113 39.4116 7.78809C39.3823 7.97559 39.3339 8.21875 39.2665 8.51758C39.2021 8.81641 39.1479 9.03905 39.1039 9.18554L38.0405 13H36.8979L36.0673 9.7832L35.2236 6.5752H36.2958L37.2143 10.3193C37.3578 10.9199 37.4604 11.4502 37.5219 11.9102C37.5541 11.6611 37.6025 11.3828 37.6669 11.0752C37.7314 10.7676 37.79 10.5186 37.8427 10.3281L38.8886 6.5752H39.9301L41.0024 10.3457C41.1049 10.6943 41.2133 11.2158 41.3276 11.9102C41.3715 11.4912 41.477 10.958 41.644 10.3105L42.558 6.5752H43.6215L41.9472 13Z' fill='white'\/%3E%3Cpath d='M45.7957 13V6.5752H46.846V13H45.7957Z' fill='white'\/%3E%3Cpath d='M52.0258 13H50.9755V7.47607H49.0859V6.5752H53.9155V7.47607H52.0258V13Z' fill='white'\/%3E%3Cpath d='M61.2312 13H60.1765V10.104H57.2146V13H56.1643V6.5752H57.2146V9.20312H60.1765V6.5752H61.2312V13Z' fill='white'\/%3E%3C\/svg%3E\");}@-webkit-keyframes formkit-bouncedelay-formkit-form-data-uid-2239231933-{0%,80%,100%{-webkit-transform:scale(0);-ms-transform:scale(0);transform:scale(0);}40%{-webkit-transform:scale(1);-ms-transform:scale(1);transform:scale(1);}}@keyframes formkit-bouncedelay-formkit-form-data-uid-2239231933-{0%,80%,100%{-webkit-transform:scale(0);-ms-transform:scale(0);transform:scale(0);}40%{-webkit-transform:scale(1);-ms-transform:scale(1);transform:scale(1);}}.formkit-form[data-uid=\"2239231933\"] blockquote{padding:10px 20px;margin:0 0 20px;border-left:5px solid #e1e1e1;}.formkit-form[data-uid=\"2239231933\"] .seva-custom-content{padding:15px;font-size:16px;color:#fff;mix-blend-mode:difference;}.formkit-form[data-uid=\"2239231933\"] .formkit-modal.guard{max-width:420px;width:100%;} .formkit-form[data-uid=\"2239231933\"]{max-width:700px;}.formkit-form[data-uid=\"2239231933\"] [data-style=\"clean\"]{width:100%;}.formkit-form[data-uid=\"2239231933\"] .formkit-fields{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-flex-wrap:wrap;-ms-flex-wrap:wrap;flex-wrap:wrap;margin:0 auto;}.formkit-form[data-uid=\"2239231933\"] .formkit-field,.formkit-form[data-uid=\"2239231933\"] .formkit-submit{margin:0 0 15px 0;-webkit-flex:1 0 100%;-ms-flex:1 0 100%;flex:1 0 100%;}.formkit-form[data-uid=\"2239231933\"] .formkit-powered-by-convertkit-container{margin:0;}.formkit-form[data-uid=\"2239231933\"] .formkit-submit{position:static;}.formkit-form[data-uid=\"2239231933\"][min-width~=\"700\"] [data-style=\"clean\"],.formkit-form[data-uid=\"2239231933\"][min-width~=\"800\"] [data-style=\"clean\"]{padding:10px;padding-top:56px;}.formkit-form[data-uid=\"2239231933\"][min-width~=\"700\"] .formkit-fields[data-stacked=\"false\"],.formkit-form[data-uid=\"2239231933\"][min-width~=\"800\"] .formkit-fields[data-stacked=\"false\"]{margin-left:-5px;margin-right:-5px;}.formkit-form[data-uid=\"2239231933\"][min-width~=\"700\"] .formkit-fields[data-stacked=\"false\"] .formkit-field,.formkit-form[data-uid=\"2239231933\"][min-width~=\"800\"] .formkit-fields[data-stacked=\"false\"] .formkit-field,.formkit-form[data-uid=\"2239231933\"][min-width~=\"700\"] .formkit-fields[data-stacked=\"false\"] .formkit-submit,.formkit-form[data-uid=\"2239231933\"][min-width~=\"800\"] .formkit-fields[data-stacked=\"false\"] .formkit-submit{margin:0 5px 15px 5px;}.formkit-form[data-uid=\"2239231933\"][min-width~=\"700\"] .formkit-fields[data-stacked=\"false\"] .formkit-field,.formkit-form[data-uid=\"2239231933\"][min-width~=\"800\"] .formkit-fields[data-stacked=\"false\"] .formkit-field{-webkit-flex:100 1 auto;-ms-flex:100 1 auto;flex:100 1 auto;}.formkit-form[data-uid=\"2239231933\"][min-width~=\"700\"] .formkit-fields[data-stacked=\"false\"] .formkit-submit,.formkit-form[data-uid=\"2239231933\"][min-width~=\"800\"] .formkit-fields[data-stacked=\"false\"] .formkit-submit{-webkit-flex:1 1 auto;-ms-flex:1 1 auto;flex:1 1 auto;} <\/style><\/form>\n\n\n<p>\n\n\n\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"Stage 13: Sallent de Gallego - Refugio de Respomuso GR11 \/ Stage 13: Sallent de...","protected":false},"author":1,"featured_media":49197,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_wp_convertkit_post_meta":{"form":"-1","landing_page":"","tag":"0","restrict_content":"0"},"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"right","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[3212],"series":[],"class_list":["post-49196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-transpirenaicas","tag-etapa-gr11"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/en\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"AaM9BWa4l4\"><a href=\"https:\/\/travesiapirenaica.com\/en\/gr11-sallent-gallego-respomuso\/\">Etapa 13: Sallent de Gallego &#8211; Refugio de Respomuso<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/en\/gr11-sallent-gallego-respomuso\/embed\/#?secret=AaM9BWa4l4\" width=\"500\" height=\"350\" title=\"&#8220;Etapa 13: Sallent de Gallego &#8211; Refugio de Respomuso&#8221; &#8212; Traves\u00eda.\" data-secret=\"AaM9BWa4l4\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":3,"label":"Transpirenaicas"}],"post_tag":[{"value":3212,"label":"Etapa GR11"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso-1024x404.jpg",1024,404,true],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/en\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":3,"name":"Transpirenaicas","slug":"transpirenaicas","term_group":0,"term_taxonomy_id":3,"taxonomy":"category","description":"Transpirenaicas","parent":5,"count":64,"filter":"raw","cat_ID":3,"category_count":64,"category_description":"Transpirenaicas","cat_name":"Transpirenaicas","category_nicename":"transpirenaicas","category_parent":5}],"tag_info":[{"term_id":3212,"name":"Etapa GR11","slug":"etapa-gr11","term_group":0,"term_taxonomy_id":3228,"taxonomy":"post_tag","description":"Etapa GR11","parent":0,"count":18,"filter":"raw"}],"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/06\/Travesia-pirenaica_gr11-Sallent-de-Gallego-Refugio-de-Respomuso.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/posts\/49196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/comments?post=49196"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/posts\/49196\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/media\/49197"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/media?parent=49196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/categories?post=49196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/tags?post=49196"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/series?post=49196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}