{"id":7784,"date":"2021-04-28T20:10:00","date_gmt":"2021-04-28T18:10:00","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=7784"},"modified":"2024-06-04T10:46:17","modified_gmt":"2024-06-04T08:46:17","slug":"the-road-to-santiago","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/en\/camino-de-santiago\/","title":{"rendered":"Camino de Santiago: advice and guide to routes and stages"},"content":{"rendered":"\n<p>Seg\u00fan la leyenda, la aparici\u00f3n de los restos del ap\u00f3stol Santiago llev\u00f3 a la construcci\u00f3n de Santiago de Compostela en el siglo IX. Pronto se convirti\u00f3 en un <strong><a href=\"http:\/\/www.caminodesantiago.gal\/es\/inicio\" target=\"_blank\" rel=\"noopener\">destino de peregrinaci\u00f3n<\/a><\/strong> a la par que Jerusal\u00e9n y Roma.<\/p>\n\n\n\n<p>El <strong>Camino de Santiago de Compostela (el Camino)<\/strong>, o&nbsp;<em>Way of Saint James<\/em> en ingl\u00e9s, est\u00e1 formado por una colecci\u00f3n de<a href=\"#rutas\"> antiguas rutas de peregrinaci\u00f3n que conducen a Santiago de Compostela<\/a> en Galicia, en el noroeste de Espa\u00f1a. All\u00ed se encuentra la catedral desde el siglo IX de Santiago de Compostela.<\/p>\n\n\n\n<p><strong>DE UN VISTAZO:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"#rutas\">1. Las Rutas<\/a><\/li><li><a href=\"#consejos\">2. Consejos para realizar el Camino de Santiago<\/a><\/li><li><a href=\"#entrenamiento\">3. C\u00f3mo prepararse para hacer el Camino de Santiago.<\/a><\/li><li><a href=\"#mochila\">4. La mochila: qu\u00e9 llevar para hacer el Camino de Santiago<\/a><\/li><li><a href=\"#credencial\">5. Credencial de Peregrino. La Compostelana<\/a><\/li><li><a href=\"#alojamiento\">6. Alojamiento en el Camino de Santiago<\/a><\/li><li><a href=\"#gastronomia\">7. Gastronom\u00eda del Camino<\/a><\/li><\/ul>\n\n\n\n<p>La necesidad de ir a peregrinaciones siempre ha sido una caracter\u00edstica humana. La gente ha recorrido caminos a destinos que prometieron milagros o penitencia, o expiar los pecados. E incluso en esta era racional, las personas se sienten atra\u00eddas por las b\u00fasquedas espirituales de los lugares sagrados del mundo. En el mundo cristiano, pocos sitios sagrados son m\u00e1s famosos que <strong>Santiago de Compostela<\/strong> en Galicia, en el norte de Espa\u00f1a. Los peregrinos han caminado esta ruta durante m\u00e1s de 1000 a\u00f1os. Y hoy en d\u00eda, <strong>m\u00e1s de 100000 peregrinos realizan anualmente el viaje<\/strong> que termina en la catedral de Santiago de Compostela. \u00bfQu\u00e9 los atrae all\u00ed?<\/p>\n\n\n\n<p>Haciendo El Camino podr\u00e1s vivir una incre\u00edble <strong>experiencia<\/strong>. Solo debes calzarte las botas o subirte a tu bicicleta para empezar a descubrir una de las maravillas de Espa\u00f1a de una manera muy peculiar.&nbsp; Podr\u00e1s pasar por <strong>emocionantes parajes naturales y encontrar\u00e1s pueblos que te ir\u00e1n inculcando un poco de su historia<\/strong> hasta que llegues a la meta del recorrido, Santiago de Compostela. Podr\u00e1s unirte a los miles de peregrinos que llegan cada a\u00f1o a esta ciudad gallega, y donde descansan los restos del ap\u00f3stol Santiago el Mayor. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Caminos de Santiago\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/4lvt20qVM10?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Hay muchas motivaciones para hacerlo: <strong>b\u00fasqueda personal o espiritual, reto deportivo o simple inter\u00e9s por toda la cultura que rodea a este camino<\/strong>. Da igual cu\u00e1l elijas, ya que lo disfrutar\u00e1s de cualquier forma. A esta experiencia personal se le une tambi\u00e9n una <a href=\"#gastronomia\"><strong>experiencia culinaria<\/strong> <\/a>sin precedentes, donde tendr\u00e1s la oportunidad de probar platos tradicionales del norte de Espa\u00f1a.<\/p>\n\n\n\n<p>Te encontrar\u00e1s edificios como catedrales u obras de arte como una infinidad de pinturas, pero tambi\u00e9n disfrutar\u00e1s de la <strong>cultura<\/strong> m\u00e1s profunda del norte, con sus tradiciones, fiestas y costumbres. Siempre te mantendr\u00e1s en contacto con la <strong>naturaleza<\/strong>, ya est\u00e9s en los Pirineos o llegando a tu destino. Maravillosos acantilados, parques nacionales\u2026 una gran belleza se esconde en cada rinc\u00f3n que visitas. Conocer\u00e1s a peregrinos como t\u00fa, as\u00ed como sus historias, en un ambiente al que muchos llaman hogar.<\/p>\n\n\n\n<p class=\"has-background\" style=\"background-color:#eeeeee\"><strong>LEE TAMBI\u00c9N: <\/strong><a rel=\"noreferrer noopener\" aria-label=\"Las mejores rutas de trekking en Espa\u00f1a\u00bb (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/travesiapirenaica.com\/trekking-espana\/\" target=\"_blank\"><strong>Las mejores rutas de trekking en Espa\u00f1a\u00bb<\/strong><\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"rutas\">1. Las Rutas<\/h2>\n\n\n\n<p>Aunque el destino final siempre es Santiago de Compostela, <a href=\"https:\/\/nco.ign.es\/CaminoSantiago\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>existen numerosas rutas<\/strong><\/a>. Mira lo que ofrece cada una.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Camino Franc\u00e9s<\/h3>\n\n\n\n<p class=\"has-background\" style=\"background-color:#eeeeee\"><strong>LEE TAMBI\u00c9N: <\/strong><a rel=\"noreferrer noopener\" aria-label=\"Camino Santiago Franc\u00e9s\u00bb (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/travesiapirenaica.com\/camino-santiago-frances\/\" target=\"_blank\"><strong>El Camino Franc\u00e9s\u00bb<\/strong><\/a><\/p>\n\n\n\n<iframe loading=\"lazy\" frameborder=\"0\" scrolling=\"no\" src=\"https:\/\/es.wikiloc.com\/wikiloc\/spatialArtifacts.do?event=view&amp;id=14369933&amp;measures=off&amp;title=off&amp;near=off&amp;images=off&amp;maptype=S\" width=\"500\" height=\"400\"><\/iframe>\n\n\n\n<p>De todos los muchos caminos que conducen a Santiago de Compostela, el m\u00e1s popular se conoce como el <strong>Camino Franc\u00e9s<\/strong>. Esta es una<strong> ruta de 750 kil\u00f3metros que comienza en Francia y cruza los Pirineos en Somport o <a href=\"https:\/\/soyviajero.com\/roncesvalles\/\" target=\"_blank\" rel=\"noreferrer noopener\">Roncesvalles<\/a><\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">Etapas del Camino Franc\u00e9s<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Etapa 1 | Saint Jean Pied de Port \u2013 Roncesvalles (25,7 Km)<\/li><li>Etapa 2 | Roncesvalles \u2013 Zubiri (21,5 Km)<\/li><li>Etapa 3 | Zubiri \u2013 Pamplona\/Iru\u00f1a (20,4 Km)<\/li><li>Etapa 4 | Pamplona\/Iru\u00f1a &#8211; Puente la Reina\/Gares (24 Km)<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Etapa 1 |  [por Somport] Somport &#8211; Jaca (30,5 Km)<\/li><li>Etapa 2 |  [por Somport] Jaca &#8211; Arr\u00e9s (25 Km)<\/li><li>Etapa 3 |  [por Somport] Arr\u00e9s &#8211; Ruesta (28,7 Km)<\/li><li>Etapa 4 |  [por Somport] Ruesta &#8211; Sang\u00fcesa (21,8 Km)<\/li><li>Etapa 4+1 |  [por Somport] Sang\u00fcesa &#8211; Monreal (27,25 Km)<\/li><li>Etapa 4+2 |  [por Somport] Monreal &#8211; Puente la Reina-Gares (31,1 Km)<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Etapa 5 | Puente la Reina\/Gares &#8211; Estella\/Lizarra (22 Km)<\/li><li>Etapa 6 | Estella\/Lizarra &#8211; Torres del R\u00edo (29 Km)<\/li><li>Etapa 7 | Torres del R\u00edo &#8211; Logro\u00f1o (20 Km)<\/li><li>Etapa 8 | Logro\u00f1o &#8211; N\u00e1jera (29,6 Km)<\/li><li>Etapa 9 | N\u00e1jera &#8211; Sto. Domingo de la Calzada (21 Km)<\/li><li>Etapa 10 | Sto. Domingo de la Calzada &#8211; Belorado (22,7 Km)<\/li><li>Etapa 11 | Belorado &#8211; Ag\u00e9s (27,4 Km)<\/li><li>Etapa 12 | Ag\u00e9s &#8211; Burgos (23 Km)<\/li><li>Etapa 13 | Burgos &#8211; Hontanas (31,1 Km)<\/li><li>Etapa 14 | Hontanas &#8211; Boadilla del Camino (28,5 Km)<\/li><li>Etapa 15 | Boadilla del Camino &#8211; Carrion de los Condes (24,6 Km)<\/li><li>Etapa 16 | Carri\u00f3n de los Condes &#8211; Terradillos de los Templarios (26,6 Km)<\/li><li>Etapa 17 | Terradillos de los Templarios &#8211; El Burgo Ranero (30,6 Km)<\/li><li>Etapa 18 | El Burgo Ranero &#8211; Le\u00f3n (37,1 Km)<\/li><li>Etapa 19 | Le\u00f3n &#8211; San Mart\u00edn del Camino (25,9 Km)<\/li><li>Etapa 20 | San Mart\u00edn del Camino &#8211; Astorga (24,2 Km)<\/li><li>Etapa 21 | Astorga &#8211; Foncebad\u00f3n (25,9 Km)<\/li><li>Etapa 22 | Foncebad\u00f3n &#8211; Ponferrada (27,3 Km)<\/li><li>Etapa 23 | Ponferrada &#8211; Villafranca del Bierzo (24,1 Km)<\/li><li>Etapa 24 | Villafranca del Bierzo &#8211; O Cebreiro (28,4 Km)<\/li><li>Etapa 25 | O Cebreiro &#8211; Triacastela (21,1 Km)<\/li><li>Etapa 26 | Triacastela &#8211; Sarria (18,3 Km)<\/li><li>Etapa 27 | Sarria &#8211; Portomar\u00edn (22,4 Km)<\/li><li>Etapa 28 | Portomar\u00edn &#8211; Palas de Rei (25 Km)<\/li><li>Etapa 29 | Palas de Rei &#8211; Arz\u00faa (28,8 Km)<\/li><li>Etapa 30 | Arz\u00faa \u2013 Pedrouzo (19,1 Km)<\/li><li>Etapa 31 | Pedrouzo &#8211; Santiago de Compostela (20 Km)<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<p>Podr\u00e1s sentirte como un verdadero viajero temporal con las numerosas <strong>etapas<\/strong> de este recorrido. Es la m\u00e1s tradicional, ya que se remonta a la Edad Media. Empezar\u00e1s esta visita cultural en los <a href=\"https:\/\/travesiapirenaica.com\/pirineos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pirineos<\/strong><\/a>, siguiendo posteriormente por la cara sur de la <strong>Cordillera Cant\u00e1brica<\/strong> hasta que por fin alcances <strong>Galicia<\/strong>. Podr\u00e1s empezar este camino tanto desde <strong>Roncesvalles<\/strong> (situado en Navarra) como de <strong>Somport<\/strong> (en Arag\u00f3n). Ambos caminos acaban uni\u00e9ndose a la altura de<strong> Puente la Reina<\/strong> (tambi\u00e9n en Navarra). Ve preparado para disfrutar de la belleza y la gastronom\u00eda.<\/p>\n\n\n\n<p>Si empiezas en <strong>Arag\u00f3n<\/strong> (<strong><a rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/travesiapirenaica.com\/camino-de-santiago-aragones\/\" target=\"_blank\">Camino de Santiago Aragon\u00e9s<\/a><\/strong>), podr\u00e1s disfrutar de enormes bosques y praderas que te har\u00e1n sentir como en un cuento, reforzado por la <strong><a rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/travesiapirenaica.com\/estacion-canfranc\/\" target=\"_blank\">Estaci\u00f3n de Canfranc<\/a><\/strong> y el fuerte de Coll de Ladrones, situados en Huesca. Podr\u00e1s hacer un alto en el camino a la altura de Villan\u00faa para visitar la Cueva de las G\u00fcixas, para posteriormente llegar a <strong><a href=\"https:\/\/soyviajero.com\/jaca-en-huesca\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\">Jaca<\/a><\/strong><a href=\"https:\/\/soyviajero.com\/jaca-en-huesca\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\"> <\/a>donde podr\u00e1s reponer fuerzas y encontrar provisiones. No puedes comenzar la siguiente etapa sin degustar el t\u00edpico bacalao al ajoarriero. Una vez con fuerzas, podr\u00e1s continuar hasta Arr\u00e9s, donde disfrutar\u00e1s de la maravillosa vista del mirador del Canal de Berd\u00fan.<\/p>\n\n\n\n\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--css-adjust-image-large\"  data-aawp-product-asin=\"8499358438\" data-aawp-product-id=\"41514\" data-aawp-tracking-id=\"travesiapiren-21\" data-aawp-product-title=\"El Camino de Santiago en tu mochila Camino Franc\u00e9s\" data-aawp-geotargeting=\"true\">\n\n    \n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\" href=\"https:\/\/www.amazon.es\/dp\/8499358438?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"El Camino de Santiago en tu mochila. Camino Franc\u00e9s\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/m.media-amazon.com\/images\/I\/51Y8DDlhplL.jpg\" alt=\"El Camino de Santiago en tu mochila. Camino Franc\u00e9s\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.es\/dp\/8499358438?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"El Camino de Santiago en tu mochila. Camino Franc\u00e9s\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            El Camino de Santiago en tu mochila. Camino Franc\u00e9s        <\/a>\n        <div class=\"aawp-product__description\">\n                    <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n            \n                            <span class=\"aawp-product__price aawp-product__price--current\">7,83 EUR<\/span>\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button--icon aawp-button--icon-black\" href=\"https:\/\/www.amazon.es\/dp\/8499358438?tag=travesiapiren-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Ver en Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Ver en Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n\n\n\n\n<p>Una vez en <strong>Navarra<\/strong>, podr\u00e1s degustar el famoso bocadillo de chistorra pamplon\u00e9s. Si tienes la suerte de pasar por <strong>Pamplona<\/strong> en la segunda semana de julio, podr\u00e1s ver los encierros de<strong> San Ferm\u00edn<\/strong>. Hay pueblos, como Obanos y su preciosa arquitectura, antes de llegar al puente rom\u00e1nico de <strong>Puente la Reina<\/strong>. Construido hace mil a\u00f1os, podr\u00e1s pasar por el mismo camino que recorrieron los peregrinos de anta\u00f1o. A solo dos kil\u00f3metros de este emblem\u00e1tico puente, podr\u00e1s encontrar uno de los s\u00edmbolos de este recorrido: la iglesia de <strong>Santa Mar\u00eda de Eunate<\/strong>. Es muy probable que ya la hayas visto, porque este edificio rom\u00e1nico se suele mostrar siempre en im\u00e1genes referentes al camino. En tu andar te encontrar\u00e1s con <strong>Estella-Lizarra<\/strong>, te sorprender\u00e1 su gran patrimonio monumental. Posteriormente continuar\u00e1s con tu viaje hasta<strong> La Rioja<\/strong>, una comunidad conocida por sus geniales vinos, que podr\u00e1s degustar acompa\u00f1\u00e1ndolos con unas ricas papas a la riojana. En <strong>Logro\u00f1o<\/strong> tendr\u00e1s que ir de tapas por la calle Laurel. Los monasterios de Yuso y Suso, en <strong>San Mill\u00e1n de la Cogolla<\/strong>, se consideran la cuna de nuestra lengua y est\u00e1n reconocidos por la UNESCO como Patrimonio de la Humanidad. Tambi\u00e9n pasar\u00e1s por <strong>Santo Domingo de la Calzada<\/strong>, una ciudad que naci\u00f3 del propio camino, y subir\u00e1s a la torre campanario para tener las mejores vistas de toda la zona.<\/p>\n\n\n\n<p>En tu recorrido no te olvides, eso s\u00ed, de descansar un rato para disfrutar de la morcilla de <strong>Burgos<\/strong> o el lechazo castellano. Sin salir de Burgos podr\u00e1s conocer los or\u00edgenes de la humanidad en la sierra de <strong>Atapuerca<\/strong>, con uno de los mayores yacimientos arqueol\u00f3gicos de Europa, considerado Patrimonio de la Humanidad por la UNESCO. Pasar\u00e1s por <strong>Palencia<\/strong>, donde podr\u00e1s hacer una parada en <strong>Terradillos de los Templarios<\/strong>, cuyo nombre recuerda la presencia de una de las \u00f3rdenes militares cristianas m\u00e1s poderosas que poblaron nuestro pa\u00eds durante toda la Edad Media.<\/p>\n\n\n\n<p>Tardar\u00e1s un poco en llegar a <strong>Le\u00f3n<\/strong>, comunidad que muchos eligen como comienzo del Camino. No hay mejor manera de comenzar que visitando la Catedral de Le\u00f3n. Otro punto fuerte de la ciudad es su antiguo Hospital de San Marcos. A pocos kil\u00f3metros de la capital, en <strong>Astorga<\/strong>, podr\u00e1s visitar el Palacio Episcopal, construido por Gaud\u00ed. Si contin\u00faas hacia tu destino, pasar\u00e1s por la comarca de <strong>El Bierzo<\/strong>, donde se encuentra <strong>Ponferrada<\/strong>, ciudad construida junto a un viejo castillo donde se asentaban los templarios. Si tienes tiempo, puedes hacer una parada en <strong>Villafranca del Bierzo<\/strong>, cuyo casco antiguo est\u00e1 considerado Bien de Inter\u00e9s Cultural. Tendr\u00e1s la oportunidad de degustar la deliciosa cecina de carne de vacuno curada, muy similar al jam\u00f3n serrano. A partir de este punto, el camino se hace m\u00e1s complicado, necesitando un mayor esfuerzo por tu parte para que puedas alcanzar puertos como el de la <strong>Cruz de Hierro<\/strong>, considerado el punto m\u00e1s alto de este recorrido. Cuando llegues al templo de Santa Mar\u00eda la Real, podr\u00e1s vislumbrar un precioso valle, oculto en caso de niebla. Ya en campos gallegos, entrar\u00e1s en la \u00faltima fase de todo el recorrido. Podr\u00e1s disfrutar de los maravillosos bosques, riachuelos y pastos gallegos. No te olvides de probar la gastronom\u00eda gallega, con sus reconfortantes caldos o sus deliciosas empanadas. Una vez en <strong>Lugo<\/strong>, podr\u00e1s sorprenderte con la iglesia rom\u00e1nica de Santa Mar\u00eda de Ferreiros, situada en medio del camino. Pasando por la Abad\u00eda de Samos, los monjes benedictinos que la habitan te ofrecer\u00e1n alojamiento y la posibilidad de que te unas a ellos en sus rezos ma\u00f1aneros. Tambi\u00e9n es importante la iglesia de San Salvador de Vilar de Donas, cerca de Palas de Rei. Dentro se sit\u00faa un extravagante museo con esculturas y retablos de tiempos cercanos al siglo XII.<\/p>\n\n\n\n<p>Pronto estar\u00e1s entrando en la provincia de A Coru\u00f1a, donde se sit\u00faa la meta del recorrido: <strong>Santiago de Compostela<\/strong>. Es una ciudad majestuosa y llena de magia y espiritualidad. Cuando vayas llegando a l<strong>a plaza del Obradoiro<\/strong> podr\u00e1s vislumbrar la imponente catedral. Disfruta del ambiente y de la cultura.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Camino del Norte<\/h3>\n\n\n\n<p class=\"has-background\" style=\"background-color:#eeeeee\"><strong>LEE TAMBI\u00c9N: <a rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/travesiapirenaica.com\/camino-santiago-del-norte\/\" target=\"_blank\">El Camino del Norte\u00bb<\/a><\/strong><\/p>\n\n\n\n<p>Si eliges este camino, recorrer\u00e1s la orilla del<strong> mar Cant\u00e1brico<\/strong>. Es una de las rutas m\u00e1s antiguas, al igual que el camino franc\u00e9s, y es tambi\u00e9n una de las m\u00e1s bonitas. Podr\u00e1s aprovechar para ver las bellezas, tanto culturales como culinarias, de comunidades como <strong>Cantabria, Asturias o Pa\u00eds Vasco<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">Etapas del Camino del Norte<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Etapa 1 | Irun &#8211; San Sebasti\u00e1n-Donostia (27,6 Km)<\/li><li>Etapa 2 | San Sebasti\u00e1n-Donostia &#8211; Zarautz (20,3 Km)<\/li><li>Etapa 3 | Zarautz &#8211; Deba (22 Km)<\/li><li>Etapa 4 | Deba &#8211; Markina-Xemein (24,3 Km)<\/li><li>Etapa 5 | Markina Xemein &#8211; Gernika Lumo (25 Km)<\/li><li>Etapa 6 | Gernika &#8211; Lezama (21,8 Km)<\/li><li>Etapa 7 | Lezama &#8211; Bilbao (11,2 Km)<\/li><li>Etapa 8 | Bilbao &#8211; Portugalete (19,7 Km)<\/li><li>Etapa 9 | Portugalete &#8211; Pobe\u00f1a (12,3 Km)<\/li><li>Etapa 10 | Pobe\u00f1a &#8211; Castro Urdiales (23,5 Km)<\/li><li>Etapa 11 | Castro Urdiales &#8211; Laredo (30,6 Km)<\/li><li>Etapa 12 | Laredo &#8211; G\u00fcemes (29,5 Km)<\/li><li>Etapa 13 | G\u00fcemes &#8211; Santander (20,5 Km)<\/li><li>Etapa 14 | Santander &#8211; Queveda (41,4 Km)<\/li><li>Etapa 15 | Queveda &#8211; Comillas (26,4 Km)<\/li><li>Etapa 16 | Comillas &#8211; Unquera (26,6 Km)<\/li><li>Etapa 17 | Unquera &#8211; Llanes (25,1 Km)<\/li><li>Etapa 18 | Llanes &#8211; San Esteban de Leces (33,9 Km)<\/li><li>Etapa 19 | San Esteban de Leces &#8211; Sebrayo (27,8 Km)<\/li><li>Etapa 20 | Sebrayo &#8211; Gij\u00f3n \/ Enlace hasta Oviedo y <a href=\"https:\/\/travesiapirenaica.com\/camino-santiago-primitivo\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Camino Primitivo  (abre en una nueva pesta\u00f1a)\">Camino Primitivo <\/a>(34,3 Km)<\/li><li>Etapa 21 | Gij\u00f3n &#8211; Avil\u00e9s (22,7 Km)<\/li><li>Etapa 22 | Avil\u00e9s &#8211; Soto de Lui\u00f1a (38 Km)<\/li><li>Etapa 23 | Soto de Lui\u00f1a &#8211; Cadavedo (23,9 Km)<\/li><li>Etapa 24 | Cadavedo &#8211; Luarca (16,3 Km)<\/li><li>Etapa 25 | Luarca &#8211; La Caridad (29,3 Km)<\/li><li>Etapa 26 | La Caridad &#8211; Ribadeo (22,3 Km)<\/li><li>Etapa 27 | Ribadeo &#8211; Lourenz\u00e1 (29,5 Km)<\/li><li>Etapa 28 | Lourenz\u00e1 &#8211; Abad\u00edn (24,8 Km)<\/li><li>Etapa 29 | Abad\u00edn &#8211; Vilalba (20,6 Km)<\/li><li>Etapa 30 | Vilalba &#8211; Baamonde (20,7 Km)<\/li><li>Etapa 31 | Baamonde &#8211; Sobrado dos Monxes (41,3 Km)<\/li><li>Etapa 32 | Sobrado dos Monxes &#8211; Arz\u00faa (21,5 Km)<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<p>Te meter\u00e1s de lleno en la Espa\u00f1a Verde, regi\u00f3n de inmensa belleza natural con paisajes monta\u00f1osos, riachuelos cristalinos, acantilados y frondosos bosques y praderas. Podr\u00e1s pasar por numerosas poblaciones que te brindar\u00e1n su historia. Es importante se\u00f1alar que esta variante del Camino es la que m\u00e1s Patrimonios de la Humanidad tiene.<\/p>\n\n\n\n\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--css-adjust-image-large\"  data-aawp-product-asin=\"8491581014\" data-aawp-product-id=\"41507\" data-aawp-tracking-id=\"travesiapiren-21\" data-aawp-product-title=\"CAMINO DE SANTIAGO EN TU MOCHILA CAMINO NORTE 4 ED  SIN COLECCION\" data-aawp-geotargeting=\"true\">\n\n    \n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\" href=\"https:\/\/www.amazon.es\/dp\/8491581014?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"CAMINO DE SANTIAGO EN TU MOCHILA. CAMINO NORTE 4 ED. (SIN COLECCION)\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/m.media-amazon.com\/images\/I\/51Q4uXZLIaL.jpg\" alt=\"CAMINO DE SANTIAGO EN TU MOCHILA. CAMINO NORTE 4 ED. (SIN COLECCION)\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.es\/dp\/8491581014?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"CAMINO DE SANTIAGO EN TU MOCHILA. CAMINO NORTE 4 ED. (SIN COLECCION)\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            CAMINO DE SANTIAGO EN TU MOCHILA. CAMINO NORTE 4 ED. (SIN COLECCION)        <\/a>\n        <div class=\"aawp-product__description\">\n                    <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n            \n                            <span class=\"aawp-product__price aawp-product__price--current\"><\/span>\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button--icon aawp-button--icon-black\" href=\"https:\/\/www.amazon.es\/dp\/8491581014?tag=travesiapiren-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Ver en Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Ver en Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n\n\n\n\n<p>Si tienes inter\u00e9s en recorrerlo entero, es importante que empieces en <strong>Ir\u00fan<\/strong> (situado en Euskadi) que tiene frontera con Francia. Recorrer\u00e1s toda <strong>Gip\u00fazcoa<\/strong> hasta su capital, <strong>San Sebasti\u00e1n<\/strong>, una preciosa ciudad costera con playas de arena blanca entre los montes Urgull e Igeldo. Es una ciudad muy tur\u00edstica, con caser\u00edos, mansiones se\u00f1oriales y barrios modernos en un precioso contraste. Es importante que visites el Museo de San Telmo, el Peine del Viento o el Kursaal, siempre con una mezcla de tradici\u00f3n y modernidad. La <strong>gastronom\u00eda<\/strong> donostiarra es realmente impresionante, con la mayor concentraci\u00f3n de restaurantes con estrella Michel\u00edn por metro cuadrado de todo el mundo. Podr\u00e1s degustar el vino blanco llamado txakol\u00ed. Las siguientes etapas te llevar\u00e1n por geniales localidades costeras como <strong>Zumaia<\/strong>, <strong>Deba<\/strong> o <strong>Zarautz<\/strong>. Tendr\u00e1s la suerte de observar los llamados \u201c<em>flysch<\/em>\u201d, formaciones geol\u00f3gicas con origen en las mareas y en la erosi\u00f3n. Tambi\u00e9n podr\u00e1s disfrutar de unas vistas geniales desde pueblos de gran altura como Elorriaga o Itziar.<\/p>\n\n\n\n<p>Si sigues tu camino acabar\u00e1s entrando en la provincia de <strong>Vizcaya<\/strong>. Pasar\u00e1s por <strong>Guernika<\/strong>, una ciudad donde podr\u00e1s sentir su historia. Fue destruida durante fuerzas alemanas\/italianas durante la Guerra Civil, lo cual inspir\u00f3 en cuadro del mismo nombre de Pablo Picasso. Tambi\u00e9n podr\u00e1s visitar <strong>Bilbao<\/strong>, capital de provincia, donde podr\u00e1s disfrutar de una de las composiciones arquitect\u00f3nicas m\u00e1s vanguardistas del mundo. Visitar el Guggenheim es casi obligatorio, con su particular forma y sus obras de arte, obra de Frank Gehry. En su casco antiguo disfrutaras de los pintxos, es decir, las tapas vascas. No te olvides de acompa\u00f1ar tu comida con un buen vino. Solo unos pocos kil\u00f3metros te separan de <strong>Cantabria<\/strong>, donde visitar\u00e1s preciosas localidades como <strong>Laredo<\/strong>, <strong>Noja<\/strong> o <strong>Castro Urdiales<\/strong>, antes de llegar a <strong>Santander<\/strong>. Esta ciudad combina monta\u00f1a y mar, con una de las bah\u00edas m\u00e1s bonitas del mundo. Sus numerosos miradores ofrecen unas vistas impresionantes de la zona, y su casco hist\u00f3rico est\u00e1 repleto de edificios con una larga historia.<\/p>\n\n\n\n<p>Si sigues por la costa cant\u00e1brica acabar\u00e1s en <strong>Comillas<\/strong>, declarada conjunto hist\u00f3rico art\u00edstico. Si paseas por sus calles, podr\u00e1s ir encontr\u00e1ndote con innumerables casas solariegas y edificios con aires modernistas. Es indispensable la visita de algunas construcciones como El Capricho, de Gaud\u00ed, el Palacio de Sobrellano, de estilo neog\u00f3tico o la Universidad Pontificia, s\u00edmbolo de la localidad. Solo te separan unos kil\u00f3metros de la poblaci\u00f3n de<strong> Santillana del Mar<\/strong>, hogar del hombre del Paleol\u00edtico Superior que habita en la cueva de <strong>Altamira<\/strong>. Cuenta con 18.000 a\u00f1os de antig\u00fcedad y se considera el mayor tesoro rupestre del pa\u00eds, obviamente declarado Patrimonio de la Humanidad. Una vez entres en <strong>Asturias<\/strong> las etapas se har\u00e1n llevaderas, con la genial comida que caracteriza la zona. Los concejos de <strong>Ribadesella<\/strong> o <strong>Llanes<\/strong> contienen muchas parroquias donde podr\u00e1s descansar de tus andadas. Es importante que para disfrutar del paraje que rodea la iglesia de Nuestra Se\u00f1ora de los Dolores y la playa de San Antol\u00edn.<\/p>\n\n\n\n<p>No tardar\u00e1s mucho en llegar a <strong>Gij\u00f3n<\/strong>, la capital asturiana, que combina una mezcla de aire marino, patrimonio hist\u00f3rico y estructura urban\u00edstica moderna a pocos metros de la playa. Estamos seguros de que te encantar\u00e1. Tanto la iglesia de San Andr\u00e9s de Ceares como la de Santa Mar\u00eda Magdalena constituyen ejemplos rom\u00e1nicos. Otras localidades importantes son <strong>Cudillero<\/strong> y <strong>Luarca<\/strong>, esta \u00faltima conocida como la Villa Blanca de la Costa Verde, situada a escasos kil\u00f3metros de Galicia. Una vez all\u00ed, en <strong>Lugo<\/strong>, visitar\u00e1s <strong>Modo\u00f1edo<\/strong>. Su casco antiguo est\u00e1 declarado Bien de Inter\u00e9s Cultural, y contiene una de las m\u00e1s imponentes catedrales neocl\u00e1sicas de Europa. En cuanto a gastronom\u00eda, no te podr\u00e1s perder su tradicional tarta, con ingredientes como hojaldre, frutos secos y frutas escarchadas. Cuando pases por <strong>Arz\u00faa<\/strong>, a escasos 40 kil\u00f3metros de Santiago, podr\u00e1s encontrarte con los peregrinos del <strong>Camino Franc\u00e9s<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Camino Primitivo<\/h3>\n\n\n\n<p class=\"has-background\" style=\"background-color:#eeeeee\"><strong>LEE TAMBI\u00c9N: <a rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/travesiapirenaica.com\/camino-santiago-primitivo\/\" target=\"_blank\">El Camino Primitivo\u00bb<\/a><\/strong><\/p>\n\n\n\n<p>Es la <strong>ruta m\u00e1s antigua de todas<\/strong>. Est\u00e1 basada en el <strong>recorrido de los peregrinos del siglo IX que trascurre por el interior oeste de Asturias<\/strong>. Es mucho menos popular que las otras dos rutas mencionadas, aunque est\u00e1 igual de bien se\u00f1alizada. Por si fuera poco, sus zonas boscosas son f\u00e1ciles de atravesar y el asfalto brilla por su ausencia, lo que te reportar\u00e1 las mejores vistas generales de todas las rutas. <\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">Etapas del Camino Primitivo<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Etapa 1 | Oviedo &#8211; San Juan de Villapa\u00f1ada (30,5 Km)<\/li><li>Etapa 2 | San Juan de Villapa\u00f1ada &#8211; Salas (20,2 Km)<\/li><li>Etapa 3 | Salas &#8211; Tineo (20,2 Km)<\/li><li>Etapa 4 | Tineo &#8211; Pola de Allande (28,2 Km)<\/li><li>Etapa 5 | Pola de Allande &#8211; La Mesa (22,8 Km)<\/li><li>Etapa 6 | La Mesa &#8211; Grandas de Salime (16,8 Km)<\/li><li>Etapa 7 | Grandas de Salime &#8211; Fonsagrada (28,1 Km)<\/li><li>Etapa 8 | A Fonsagrada (Padr\u00f3n) &#8211; O C\u00e1davo Baleira (23,4 Km)<\/li><li>Etapa 9 | C\u00e1davo Baleira &#8211; Lugo (30,5 Km)<\/li><li>Etapa 10 | Lugo &#8211; San Romao da Retorta (19,7 Km)<\/li><li>Etapa 11 | San Romao da Retorta &#8211; Melide (27,7 Km)<\/li><li>Etapa 12 | Melide &#8211; O Pedrouzo (33,3 Km)<\/li><li>Etapa 13 | O Pedrouzo &#8211; Santiago de Compostela (20 Km)<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<p>Tiene su inicio en <strong>Oviedo<\/strong>, la capital asturiana, la cual cuenta con grandes tesoros hist\u00f3ricos. Encontrar\u00e1s muchas iglesias prerrom\u00e1nicas como la de Santa Mar\u00eda del Naranco, San Miguel de Lillo o San Juli\u00e1n de Prados, todas ellas Patrimonio de la Humanidad. Como el casco antiguo es completamente peatonal, caminar por las calles de Oviedo es siempre un placer. En su catedral, la de San Salvador, podr\u00e1s visitar la C\u00e1mara Santa, una peque\u00f1a capilla cuya funci\u00f3n era guardar reliquias como el Santo Sudario. Si te pones ya en marcha, podr\u00e1s ver c\u00f3mo te invade la naturaleza, con los numerosos r\u00edos, bosques, cascadas y robledales. Podr\u00e1s visitar pueblos tan pintorescos como Salas, Conjunto Hist\u00f3rico.<\/p>\n\n\n\n\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--css-adjust-image-large\"  data-aawp-product-asin=\"8493904236\" data-aawp-product-id=\"41515\" data-aawp-tracking-id=\"travesiapiren-21\" data-aawp-product-title=\"GUIA PRACTICA DEL CAMINO PRIMITIVO A PIE Y EN BICI\" data-aawp-geotargeting=\"true\">\n\n    \n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\" href=\"https:\/\/www.amazon.es\/dp\/8493904236?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"GUIA PRACTICA DEL CAMINO PRIMITIVO A PIE Y EN BICI\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/m.media-amazon.com\/images\/I\/41RAQciucnL.jpg\" alt=\"GUIA PRACTICA DEL CAMINO PRIMITIVO A PIE Y EN BICI\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.es\/dp\/8493904236?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"GUIA PRACTICA DEL CAMINO PRIMITIVO A PIE Y EN BICI\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            GUIA PRACTICA DEL CAMINO PRIMITIVO A PIE Y EN BICI        <\/a>\n        <div class=\"aawp-product__description\">\n                    <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n            \n                            <span class=\"aawp-product__price aawp-product__price--current\"><\/span>\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button--icon aawp-button--icon-black\" href=\"https:\/\/www.amazon.es\/dp\/8493904236?tag=travesiapiren-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Ver en Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Ver en Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n\n\n\n\n<p>No deber\u00edas de olvidarte de visitar la colegiata de Santa Mar\u00eda, siendo uno de los mejores ejemplos de la arquitectura asturiana del periodo renacentista, adem\u00e1s de la Torre medieval, con un museo en su interior. En el cementerio, cuyas vistas son impresionantes, podr\u00e1s encontrar el Tejo de San Mart\u00edn de Salas, con 15 metros de altura y 6 metros de per\u00edmetro. Posteriormente te internar\u00e1s en los concejos de <strong>Allande<\/strong> y <strong>Grandas de Salime<\/strong>, cuyo Paisaje Protegido te sorprender\u00e1. Ya acerc\u00e1ndote a Galicia, disfrutar\u00e1s de unas maravillosas vistas en el Embalse de Salime. En <strong>Palas de Rei<\/strong> acabar\u00e1s encontr\u00e1ndote con el <strong>Camino Franc\u00e9s<\/strong>, aunque antes coronar\u00e1s el pintoresco <strong>Alto del Acebo<\/strong>, con un kil\u00f3metro de altura.<\/p>\n\n\n\n<p>No te olvides de probar la gastronom\u00eda asturiana, como los populares cachopos o la fabada. Tampoco pases por alto el arroz con leche o la sidra.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Otros Caminos<\/h3>\n\n\n\n<p>Es posible llegar a Santiago por otras rutas. Podr\u00e1s ir por el <strong><a rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/travesiapirenaica.com\/camino-santiago-ingles\" target=\"_blank\">Camino Ingl\u00e9s<\/a><\/strong>, usada por los peregrinos brit\u00e1nicos y norte\u00f1os que empezaba en Ferrol, o por el <strong>Camino <a rel=\"noreferrer noopener\" aria-label=\"Portugu\u00e9s (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/travesiapirenaica.com\/camino-santiago-Portugues\" target=\"_blank\">Portugu\u00e9s<\/a><\/strong>, que te lleva desde Lisboa a Galicia, pasando por Oporto. Tampoco puedes olvidar la <strong>V\u00eda de la Plata<\/strong>, que empieza en Sevilla y llega hasta Gij\u00f3n, pasando por muchos tramos del Camino. Y no olvidar que <a href=\"https:\/\/travesiapirenaica.com\/camino-santiago-francia-le-puy-pirineos\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"otras rutas llegan a los Pirineos  (abre en una nueva pesta\u00f1a)\">otras rutas llegan a los Pirineos <\/a>para luego afrontar la parte final del los caminos que acabamos de comentar. <\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"consejos\">2. Consejos para realizar el Camino de Santiago<\/h2>\n\n\n\n<p>Para hacerlo, deber\u00edas prepararte muy bien. Aqu\u00ed te brindamos algunos consejos para que no se te haga muy cuesta arriba.<\/p>\n\n\n\n<p><strong>Te aconsejamos que intentes salirte de las \u00e9pocas m\u00e1s concurridas<\/strong>, ya que el Camino se ha puesto tan de moda, que nunca mejor dicho en determinadas fechas es una \u00abperegrinaci\u00f3n\u00bb de mucha gente.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>A pie<\/strong> <\/h3>\n\n\n\n<p>Si quieres lo m\u00e1s tradicional, ir andando es una gran manera, adem\u00e1s de la m\u00e1s asequible. Podr\u00e1s ir a tu ritmo, disfrutar de la experiencia y conversar con otros caminantes. Tambi\u00e9n puedes optar por no hablar y centrarte en tu experiencia personal, sobre todo si quieres meditar. Deber\u00edas tener una buena <a href=\"https:\/\/travesiapirenaica.com\/equipo-senderismo-trekking\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>mochila que, llena, no superase los 8 kilos de peso<\/strong>. Es importante que elijas un <strong>calzado<\/strong> c\u00f3modo, como botas de trekking o unas buenas deportivas ya usadas. Es recomendable que lleves <strong>bast\u00f3n<\/strong> para apoyarte en las zonas empinadas. Tampoco olvides un <strong>botiqu\u00edn<\/strong> y cosas para el aseo.<\/a><\/p>\n\n\n\n<p>Es importante recordar que las temperaturas pueden bajar incluso durante el verano. Sobre todo en las etapas iniciales del Camino, en los Pirineos. Deber\u00edas llevar algo de abrigo y un chubasquero por si llueve. Tampoco deber\u00edas olvidar la crema solar y una gorra, porque puede llegar a hacer mucho sol. Mientras que algunos albergues ofrecen una cama donde extender tu saco, hay veces que tendr\u00e1s que dormir en el suelo, por lo que una esterilla no est\u00e1 de m\u00e1s.<\/p>\n\n\n\n<p>Los siguientes enlaces te ser\u00e1n de utilidad para la preparaci\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/travesiapirenaica.com\/ampollas-en-el-senderismo\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Las ampollas en el Camino de Santiago.&nbsp;<\/strong><\/a><\/li><li><a href=\"https:\/\/travesiapirenaica.com\/como-preparar-el-camino-de-santiago\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Preparaci\u00f3n f\u00edsica para recorrer el Camino de Santiago<\/strong><\/a><\/li><li><a href=\"https:\/\/travesiapirenaica.com\/lesiones-problemas-fisicos-senderistas-cicloturistas-camino-santiago\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>\u00bfCuales son las lesiones y problemas f\u00edsicos m\u00e1s comunes entre senderistas y cicloturistas del Camino de Santiago?<\/strong><\/a><\/li><\/ul>\n\n\n\n<p>Sea cual sea el motivo de la peregrinaci\u00f3n, finalmente llegar a la gran Catedral de Santiago de Compostela es una experiencia conmovedora. Los verdaderos peregrinos abrazan la estatua de Santiago y a menudo se rompen en l\u00e1grimas de felicidad. E incluso aquellos que viajaron por placer o la experiencia se vieron afectados de maneras que no pueden explicar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><a href=\"https:\/\/travesiapirenaica.com\/camino-de-santiago-en-bici\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"En bicicleta (abre en una nueva pesta\u00f1a)\">En bicicleta<\/a><\/strong><\/h3>\n\n\n\n<p>Si pedalear es lo tuyo, ir en bici es buena opci\u00f3n. Ir\u00e1s mucho m\u00e1s r\u00e1pido y podr\u00e1s visitar los puntos de inter\u00e9s de forma m\u00e1s eficiente. Si quieres disfrutar, elige una ruta seg\u00fan tu forma f\u00edsica y una estaci\u00f3n del a\u00f1o con temperaturas suaves y con lluvias muy ocasionales (aunque sea posible realizarlo en cualquier \u00e9poca, gracias a su gran cantidad de albergues). Tanto <strong>el Camino Franc\u00e9s como el Ingl\u00e9s son sencillos para ciclistas<\/strong>. El <strong>Camino de la Costa\/Norte y el Primitivo tienen un clima excepcional durante la primavera y el verano<\/strong>. <strong>La V\u00eda de la Plata puede tener temperaturas muy elevadas durante el verano<\/strong>, por lo que se debe tener en cuenta. Hay variantes en las rutas para ciclistas. La se\u00f1alizaci\u00f3n es muy buena, aunque siempre puedes informarte de antemano. Todo lo que recomendamos para los caminantes, sirve para los ciclistas. A\u00f1adiremos tambi\u00e9n el <strong>equipamiento para bicicletas<\/strong> (recambios, bomba de aire, desengrasante\u2026) y para ti (unas buenas gafas, un casco, chaleco reflectante\u2026).<\/p>\n\n\n\n<p>Es importante que sepas que en <strong>los albergues p\u00fablicos, a la hora de descansar, dan preferencia a los peregrinos que viajan a pie<\/strong>.<\/p>\n\n\n\n<p class=\"has-background\" style=\"background-color:#eeeeee\"><strong>LEE TAMBI\u00c9N: <a href=\"https:\/\/travesiapirenaica.com\/camino-de-santiago-en-bici\/\" target=\"_blank\" rel=\"noreferrer noopener\">Camino de Santiago en bici: consejos y gu\u00eda de rutas y etapas<\/a><\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>A caballo<\/strong> <\/h3>\n\n\n\n<p>Podr\u00e1s disfrutar de una experiencia milenaria. Es una forma muy pintoresca de recorrer la Ruta Jacobea. En este caso, el tiempo de preparaci\u00f3n ser\u00e1 mucho mayor, ya que tendr\u00e1s que <strong>reservar lugares donde tu caballo pueda descansar<\/strong>, adem\u00e1s de preparar el pienso que consumir\u00e1 tu amigo equino.<\/p>\n\n\n\n<p>Aunque es una forma relajada de hacer el Camino, requiere algo de forma f\u00edsica. No recorras mucho camino de una pasada porque podr\u00edas perderte muchas de sus experiencias. <strong>Tendr\u00e1s que avisar con varios d\u00edas de antelaci\u00f3n si quieres entrar a Santiago a caballo<\/strong>. Tendr\u00e1s que llamar a la Polic\u00eda Local (092), la cual te indicar\u00e1 cu\u00e1ndo y por d\u00f3nde tienes permitido el paso. Tambi\u00e9n te dar\u00e1n un permiso de entrada a la Plaza del Obradoiro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>En barco de vela<\/strong><\/h3>\n\n\n\n<p>Desde 2016 tambi\u00e9n puedes hacer el camino en barco, por el Mar Cant\u00e1brico. Los pioneros en esta forma de recorrer el camino fueron los ingleses y los irlandeses, all\u00e1 por el siglo XII. Es una buena forma de aumentar el nivel de aventura que supone el Camino. Durante el recorrido, llamado \u201c<strong><em>Sail the Way<\/em> \u2013 Navega el Camino<\/strong>\u201d, surcar\u00e1s el mar en paralelo con el Camino del Norte, pudiendo parar en los <strong>17 puertos deportivos repartidos entre el Pa\u00eds Vasco, Asturias, Galicia y Cantabria<\/strong>. Si quieres conseguir tu Compostela, deber\u00e1s haber recorrido 100 millas n\u00e1uticas (182 kil\u00f3metros), sellar tu credencial en cada uno de los puertos habilitados y terminar la \u00faltima etapa, que comprende el recorrido Monte do Gozo-Santiago, a pie.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"entrenamiento\">3. C\u00f3mo prepararse para hacer el Camino de Santiago.<\/h2>\n\n\n\n<p>Una buena preparaci\u00f3n con antelaci\u00f3n es la clave para culminar con \u00e9xito una gran ruta como el Camino de Santiago. Te ayudar\u00e1 a <strong>disfrutar m\u00e1s del trekking y a evitar las temidas lesiones y problemas f\u00edsico<\/strong>s. <\/p>\n\n\n\n<p>Un buen plan de entrenamiento y preparaci\u00f3n para realizar el Camino de Santiago puede tener una <strong>duraci\u00f3n de 3 meses<\/strong>, en el que se ir\u00e1 incrementando paulatinamente el nivel de actividad f\u00edsica y en el que te ir\u00e1s familiarizando con el equipo y vestimenta que llevar\u00e1s en ruta. <\/p>\n\n\n\n<p class=\"has-very-light-gray-background-color has-background\">Te puede interesar el siguiente art\u00edculo basado en un art\u00edculo cient\u00edfico sobre la<strong> <a href=\"https:\/\/travesiapirenaica.com\/como-preparar-el-camino-de-santiago\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"preparaci\u00f3n f\u00edsica para recorrer el Camino de Santiago (abre en una nueva pesta\u00f1a)\">preparaci\u00f3n f\u00edsica para recorrer el Camino de Santiago<\/a><\/strong>.<\/p>\n\n\n\n<p>Para que puedas guiarte te dejamos aqu\u00ed varios art\u00edculos que te dar\u00e1n las <strong><a rel=\"noreferrer noopener\" aria-label=\"claves para que prepares una ruta de gran recorrido (Haz click aqu\u00ed) (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/travesiapirenaica.com\/entrenamiento-para-senderismo-de-gran-recorrido\/\" target=\"_blank\">claves para que prepares una ruta de gran recorrido (Haz click aqu\u00ed)<\/a><\/strong> como el Camino de Santiago. Deber\u00e1s entrenar la musculatura y tambi\u00e9n la <a href=\"https:\/\/travesiapirenaica.com\/aumentar-capacidad-pulmonar-montana\/\"><strong>capacidad cardiorespiratoria<\/strong><\/a> y <strong><a rel=\"noreferrer noopener\" aria-label=\"resistencia (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/travesiapirenaica.com\/ejercicios-aumentar-fuerza-trekking\/\" target=\"_blank\">resistencia<\/a><\/strong>. <br><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"mochila\">4. La mochila: qu\u00e9 llevar para hacer el Camino de Santiago<\/h2>\n\n\n\n<p>El gran debate que vas a tener en cuanto decidas aventurarte a realizar el Camino de Santiago va a ser: \u00bfqu\u00e9 mochila deber\u00eda llevar?<\/p>\n\n\n\n<p>Nuestra recomendaci\u00f3n es que te decidas por un equipo minimalista que entre sin problema en una mochila de 25 a 40 litros. Lo que es una mochila que llevar\u00edamos para una salida de un d\u00eda de senderismo. \u00bfPor qu\u00e9? Porque las diferentes rutas del Camino de Santiago discurren generalmente entre pueblos y ciudades en las que vas a tener todo tipo de comodidades. Porque puedes ir de albergue en albergue y en los mismos dispondr\u00e1s de lugar donde poder lavar la ropa del d\u00eda (s\u00ed, con una prenda de repuesto y otra puesta puede ser suficiente), de mantas (con lo que con un saco s\u00e1bana ser\u00e1 suficiente) y de comida y avituallamiento en cada pueblo. Porque en definitiva ver\u00e1s que puedes pasar el d\u00eda con muy pocas cosas y que este es uno de los aprendizajes de una ruta como esta. Porque lo vas a disfrutar mucho. <\/p>\n\n\n\n<p class=\"has-very-light-gray-background-color has-background\">Elije tu <strong><a aria-label=\"mochila (recuerda: 25-40 litros) (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/travesiapirenaica.com\/mochilas-montana\/\" target=\"_blank\" rel=\"noreferrer noopener\">mochila (recuerda: 25-40 litros)<\/a> <\/strong>y escoge del <strong><a aria-label=\"equipo b\u00e1sico de senderismo (abre en una nueva pesta\u00f1a)\" rel=\"noreferrer noopener\" href=\"https:\/\/travesiapirenaica.com\/equipo-senderismo-trekking\/\" target=\"_blank\">equipo b\u00e1sico de senderismo<\/a><\/strong> el tuyo para el Camino de Santiago, pero que sea ante todo minimalista. En el siguiente listado tienes<strong> <a href=\"https:\/\/travesiapirenaica.com\/comida-para-montana\/\" target=\"_blank\" rel=\"noreferrer noopener\">ideas de comida que puedes llevar en ruta<\/a><\/strong>.  <\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"credencial\">5. Credencial de Peregrino. La Compostelana<\/h2>\n\n\n\n<p>Los peregrinos de hoy en d\u00eda hacen este viaje por varias razones, algunas de las cuales son espirituales. De hecho, m\u00e1s de 100.000 peregrinos de m\u00e1s de 100 pa\u00edses hacen el viaje cada a\u00f1o a pie, en bicicleta, en burro o a caballo. Y eso son solo los peregrinos oficiales con un<strong> &#8216;pasaporte&#8217; de peregrino: la credencial<\/strong>. La mayor\u00eda concluye, que es una experiencia conmovedora y gratificante en formas que no anticiparon<\/p>\n\n\n\n<p>As\u00ed, para que quede constancia de tu gran logro personal, te dar\u00e1n la Compostela, un certificado. Para poder conseguirlo, necesitar\u00e1s tanto tu documentaci\u00f3n personal como tu <strong>credencial de peregrino<\/strong>, la cual ir\u00e1s <strong>sellando en albergues, parroquias, ayuntamientos o bares autorizados<\/strong>. Si quieres esta credencial, deber\u00e1s ir a la parroquia o albergue donde comiences el camino o a alguna asociaci\u00f3n de Amigos del Camino de Santiago. El sello de Santiago lo conseguir\u00e1s en su <strong><a href=\"https:\/\/oficinadelperegrino.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Oficina del Peregrino<\/a><\/strong>.<\/p>\n\n\n\n<p>En primer lugar, debes <a href=\"https:\/\/oficinadelperegrino.com\/peregrinacion\/la-credencial\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>obtener una \u00abcredencial\u00bb de peregrino<\/strong> <\/a>registr\u00e1ndote en una ciudad como Roncesvalles en la frontera con Francia (dependiendo de tu lugar de inicio). Este documento te identifica como un peregrino y te permitir\u00e1 permanecer en los refugios o albergues en el camino con cierta preferencia respecto a otros viajeros. Estos albergues salpican las rutas a lo largo de las diferentes rutas del Camino de Santiago, a menudo, alojamiento barato o incluso gratuito. Estos generalmente disponen de habitaciones comunes con literas, y te facilitar\u00e1n todo lo que necesites en tu estancia en el lugar.<\/p>\n\n\n\n<p>La credencial tambi\u00e9n es necesaria para obtener la <strong>Compostelana<\/strong>, el <strong>certificado otorgado a los peregrinos que completan el camino<\/strong>. Para ganar esto, necesitas caminar un m\u00ednimo de 100 kil\u00f3metros o recorrer un m\u00ednimo de 200 kil\u00f3metros en tu peregrinaci\u00f3n. Para obtener tu compostelana, debes tener tu credencial estampada en las ciudades por las que pasas en tu peregrinaje. Esto prueba que recorriste la ruta reconocida por la Asociaci\u00f3n de Amigos del Camino de Santiago.&nbsp; Tambi\u00e9n es requisito haber hecho el Camino por motivos religiosos o espirituales. Si tu raz\u00f3n es otra, podr\u00e1s solicitar el certificado del peregrino. Tienes que empezar a decidir c\u00f3mo quieres hacer el camino.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image size-full wp-image-7790\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"500\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/05\/santiago-1211578_Filipevascar-_pixabay_760x500.jpg\" alt=\"Camino de Santiago de Compostela \/ Foto: Filipevascar (pixabay)\" class=\"wp-image-7790\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/05\/santiago-1211578_Filipevascar-_pixabay_760x500.jpg 760w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/05\/santiago-1211578_Filipevascar-_pixabay_760x500-600x395.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/05\/santiago-1211578_Filipevascar-_pixabay_760x500-300x197.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/05\/santiago-1211578_Filipevascar-_pixabay_760x500-100x65.jpg 100w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/05\/santiago-1211578_Filipevascar-_pixabay_760x500-260x170.jpg 260w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/05\/santiago-1211578_Filipevascar-_pixabay_760x500-759x500.jpg 759w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><figcaption> Camino de Santiago de Compostela \/ Foto: Filipevascar (pixabay)<\/figcaption><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"alojamiento\">6. Alojamiento en el Camino de Santiago<\/h2>\n\n\n\n<p>\u00bfD\u00f3nde te alojar\u00e1s?&nbsp;Hay muchas modalidades de alojamiento diferentes, y cada una te ofrece algunas prestaciones y experiencias.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Albergues<\/strong><\/h3>\n\n\n\n<p>Esta es la experiencia m\u00e1s aut\u00e9ntica, y se trata de hacer noche en la gran <strong>red de albergues del Camino<\/strong>. Los hay de dos tipos. Los p\u00fablicos tienen un precio reducido (en alguno de ellos tan solo tendr\u00e1s que pagar un peque\u00f1o donativo). Las plazas son limitadas, teniendo siempre<strong> preferencia los caminantes y los que van a caballo<\/strong> sobre los que van en bicicleta. No tengas miedo de quedarte sin sitio, ya que hay albergues privados si falta espacio. Tambi\u00e9n se habilitan iglesias, polideportivos e incluso colegios para acoger a peregrinos.<\/p>\n\n\n\n<p>Tienes que tener en cuenta que tendr\u00e1s que seguir las<strong> reglas del albergue<\/strong>, como los horarios de salida o entrada y la orden de silencio durante la noche. Es importante la solidaridad entre peregrinos. Esta es la experiencia m\u00e1s aut\u00e9ntica que podr\u00e1s vivir.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Hoteles<\/strong><\/h3>\n\n\n\n<p>En el Camino hay una gran variedad de hoteles privados que se ir\u00e1n adaptando a tu presupuesto y gustos. Hay hoteles de todo tipo, balnearios con spa\u2026 e incluso casas rurales, con un trato muy cercano y modesto.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Camping<\/strong> <\/h3>\n\n\n\n<p>Hay muchas zonas verdes que est\u00e1n habilitadas, la mayor\u00eda en las poblaciones que atravesar\u00e1s de forma natural. Todos cuentan con los servicios b\u00e1sicos, y algunos tienen hasta piscina o actividades l\u00fadicas. El Camino del Norte es el que m\u00e1s Campings tiene. Ten muy en cuenta que, en Espa\u00f1a,<strong> la acampada libre est\u00e1 regulada<\/strong>, y deber\u00e1s informarte bien de d\u00f3nde puedes llevarla a cabo.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Paradores de turismo<\/strong> <\/h3>\n\n\n\n<p>Si quieres disfrutar del Camino, esta es una gran forma. Son edificios singulares que se sit\u00faan en emplazamientos privilegiados: palacios, conventos, castillos\u2026 Monumentos con todas las comodidades que ofrece la \u00e9poca actual. Todos cuentan con una gran oferta gastron\u00f3mica, sobre todo con cocina tradicional de la regi\u00f3n. Ya hay casi un centenar por toda Espa\u00f1a.<\/p>\n\n\n\n<p>Si recorres el Camino del Norte, hay un Parador en Santillana del Mar (Cantabria), situado en una t\u00edpica casona monta\u00f1esa. Si pasas por Asturias, en concreto por Cangas de On\u00eds, podr\u00e1s sorprenderte con el Monasterio de San Pedro de Villanueva, rodeado por los Picos de Europa. En la comunidad de Galicia tendr\u00e1s maravillosas vistas mientras te alojes en los llamados \u201cpazos\u201d. Son casas t\u00edpicas de la regi\u00f3n, con car\u00e1cter se\u00f1orial, que podr\u00e1s disfrutar en el Parador de Ver\u00edn, en Ourense. Justo en esa provincia tambi\u00e9n podr\u00e1s alojarte en el Monasterio de Santo Estevo. Si el Camino Portugu\u00e9s es tu elecci\u00f3n, podr\u00e1s alojarte en el Parador de Baiona, en una gran fortaleza de Pontevedra.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"gastronomia\">7. Gastronom\u00eda del Camino<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/09\/Tarta_de_Santiago_by-Manel-Zaera_800x600.jpg\" alt=\"Tarta de Santiago \/ Foto: Manel Zaera\" class=\"wp-image-9635\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/09\/Tarta_de_Santiago_by-Manel-Zaera_800x600.jpg 800w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/09\/Tarta_de_Santiago_by-Manel-Zaera_800x600-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/09\/Tarta_de_Santiago_by-Manel-Zaera_800x600-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/09\/Tarta_de_Santiago_by-Manel-Zaera_800x600-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption>Tarta de Santiago \/ Foto: Manel Zaera<\/figcaption><\/figure>\n\n\n\n<p>La gran mayor\u00eda de los restaurantes tienen disponibles los llamados \u201c<strong>men\u00fas del peregrino<\/strong>\u201d, una genial manera de probar lo t\u00edpico de la regi\u00f3n sin dejarse la cartera. En el<strong> Pa\u00eds Vasco<\/strong> podr\u00e1s disfrutar de guisos como el <strong>bacalao<\/strong> (al pil-pil o a la vizca\u00edna), el <strong>marmitako<\/strong> (un guiso de bonito) o los <strong>chipirones en su tinta<\/strong>. <strong>Navarra<\/strong> cuenta con unas <strong>verduras<\/strong> excelentes, cultivadas junto al Ebro, por lo que no puedes dejar de probar la borraja al horno o el cardo con almejas. Tambi\u00e9n son notorios los <strong>esp\u00e1rragos blancos<\/strong>. La comunidad de <strong>La Rioja<\/strong> cuenta con una cultura vin\u00edcola sin precedentes, y si visitas una <strong>bodega<\/strong> podr\u00e1s ver c\u00f3mo usan los sarmientos, es decir, las ramas secas de vid, para asar <strong>chuletas de cordero<\/strong>. Otro plato t\u00edpico son los <strong>huevos a la riojana<\/strong>, huevos duros rehogados con ajo y pimiento rojo. Si pasas por <strong>Arag\u00f3n<\/strong> no te olvides de probar el <strong>pollo al chilindr\u00f3n<\/strong>, con verduras aragonesas en un delicioso sofrito. Los asados de <strong>lechazo<\/strong> y <strong>ternasco<\/strong> son muy conocidos en esta comunidad. Por <strong>Le\u00f3n<\/strong>, son muy t\u00edpicas las<strong> cecinas y el botillo<\/strong> (un embutido). <strong>Cantabria<\/strong> cuenta con guisos como el<strong> cocido lebaniego o el monta\u00f1\u00e9s<\/strong>, y en <strong>Asturias<\/strong> cuentan con muchas variedades de <strong>quesos<\/strong>. Tambi\u00e9n hay especialidades muy pintorescas, como el<strong> pulpo a feira<\/strong>, el<strong> pote gallego<\/strong> o las deliciosas <strong>filloas<\/strong> e incluso la<strong> tarta de Santiago<\/strong>. Lo m\u00e1s seguro es que la gastronom\u00eda del Camino no te deje indiferente.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n","protected":false},"excerpt":{"rendered":"Camino de Santiago, a modern pilgrimage. Guide to routes and stages, with all the advice and recommendations.","protected":false},"author":1,"featured_media":7789,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2945],"tags":[],"series":[],"class_list":["post-7784","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-camino-de-santiago","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/05\/spain-2451831.jpg_camino-de-santiago_760x500_by-larahcv_pixabay.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/en\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"ME0o7PS0o9\"><a href=\"https:\/\/travesiapirenaica.com\/en\/camino-de-santiago\/\">Camino de Santiago: consejos y gu\u00eda de rutas y etapas<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/en\/camino-de-santiago\/embed\/#?secret=ME0o7PS0o9\" width=\"500\" height=\"350\" title=\"&#8220;Camino de Santiago: consejos y gu\u00eda de rutas y etapas&#8221; &#8212; Traves\u00eda.\" data-secret=\"ME0o7PS0o9\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":2945,"label":"Camino de Santiago"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/05\/spain-2451831.jpg_camino-de-santiago_760x500_by-larahcv_pixabay.jpg",760,500,false],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/en\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":2945,"name":"Camino de Santiago","slug":"camino-de-santiago","term_group":0,"term_taxonomy_id":2961,"taxonomy":"category","description":"Camino de Santiago","parent":2930,"count":60,"filter":"raw","cat_ID":2945,"category_count":60,"category_description":"Camino de Santiago","cat_name":"Camino de Santiago","category_nicename":"camino-de-santiago","category_parent":2930}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/05\/spain-2451831.jpg_camino-de-santiago_760x500_by-larahcv_pixabay.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/posts\/7784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/comments?post=7784"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/posts\/7784\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/media\/7789"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/media?parent=7784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/categories?post=7784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/tags?post=7784"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/en\/wp-json\/wp\/v2\/series?post=7784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}