{"id":10276,"date":"2020-10-05T12:47:57","date_gmt":"2020-10-05T10:47:57","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=10276"},"modified":"2024-03-22T12:14:42","modified_gmt":"2024-03-22T11:14:42","slug":"quelle-est-la-mesure","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/que-es-el-mide\/","title":{"rendered":"Qu'est-ce que le MIDE ?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Le<b>&nbsp;MIDE ou Method for Excursion Reporting (M\u00e9thode d'\u00e9tablissement des rapports d'excursion) <\/b>est un outil capable d'indiquer le degr\u00e9 de difficult\u00e9 de n'importe quel itin\u00e9raire naturel de randonn\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'\u00e9ventail des sites que cette m\u00e9thode permet de d\u00e9crire est \u00e0 la fois vaste et vari\u00e9. <strong>de courtes promenades de courte dur\u00e9e \u00e0 de longues distances.<\/strong> n\u00e9cessitant l'utilisation d'outils et d'\u00e9quipements sp\u00e9cialis\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'apparition d\u00e9finitive de cette ing\u00e9nieuse plateforme d'information remonte \u00e0 2002, entre les mains d'Alberto Paris Roche, lors du lancement de l'exposition \"Le monde de l'eau\". <strong>Campagne \"Safe Mountain<\/strong>. L'initiative \u00e9tait un projet qui impliquait la <strong>Gouvernement d'Aragon et F\u00e9d\u00e9ration aragonaise d'alpinisme<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les donn\u00e9es fournies par MIDE sont organis\u00e9es en 3 sections :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>les informations provenant de <strong>r\u00e9f\u00e9rence<\/strong><\/li><li>les informations provenant de <strong>\u00e9valuation<\/strong><\/li><li>indications <strong>techniques <\/strong>de l'itin\u00e9raire<\/li><\/ul>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/7iCaTiTpW34\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">La MIDE et les informations de base : des donn\u00e9es essentielles pour une bonne compr\u00e9hension du terrain<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Calendrier<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le premier type de donn\u00e9es que le MIDE fournit est le <strong>l'horaire g\u00e9n\u00e9ral, estim\u00e9 en heures et en minutes<\/strong>Le temps total qui sera n\u00e9cessaire pour r\u00e9aliser l'itin\u00e9raire. Cette estimation ne tient pas compte de facteurs tels que les arr\u00eats, la condition physique des randonneurs ou d'\u00e9ventuels contretemps.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pente ascendante et pente descendante<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En plus de cette estimation du calendrier, le MIDE fournit des chiffres pour la <strong>l'ascension et la descente cumul\u00e9es<\/strong>. Ces chiffres tiennent compte de la dur\u00e9e totale du voyage, du point de d\u00e9part au point d'arriv\u00e9e.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Distance horizontale<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cette donn\u00e9e indique la distance entre le point de d\u00e9part et le point d'arriv\u00e9e. Ce param\u00e8tre ne tient pas compte des pentes, mais uniquement de la distance entre le point de d\u00e9part et le point d'arriv\u00e9e de l'itin\u00e9raire.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Type d'itin\u00e9raire<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L'information qui occupe le quatri\u00e8me param\u00e8tre de l'\u00e9chelle susmentionn\u00e9e montre les appr\u00e9ciations qui se r\u00e9f\u00e8rent au type d'itin\u00e9raire que le site a re\u00e7u. Cette classification se pr\u00e9sente sous trois modalit\u00e9s totalement diff\u00e9renci\u00e9es :<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Itin\u00e9raire, style de croisi\u00e8re<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ce type d'itin\u00e9raire p\u00e9n\u00e8tre dans le terrain de mani\u00e8re al\u00e9atoire, de sorte que le point de d\u00e9part et le point d'arriv\u00e9e se trouvent \u00e0 deux endroits compl\u00e8tement diff\u00e9rents.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Itin\u00e9raire aller-retour<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Il s'agit d'un itin\u00e9raire dont les points de d\u00e9part et d'arriv\u00e9e sont exactement les m\u00eames. L'excursion rejoint le point d'arriv\u00e9e et revient au point de d\u00e9part en suivant le m\u00eame itin\u00e9raire mais en sens inverse.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Itin\u00e9raire circulaire<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Dans l'itin\u00e9raire circulaire, les points de d\u00e9part et d'arriv\u00e9e sont exactement les m\u00eames, mais chaque lieu n'est arr\u00eat\u00e9 qu'une seule fois en cours de route.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu'est-ce qu'une information sur l'\u00e9valuation ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les informations relatives \u00e0 l'\u00e9valuation d\u00e9crivent les param\u00e8tres \u00e9tudi\u00e9s de mani\u00e8re quantitative, en utilisant une \u00e9chelle de un \u00e0 cinq. Cette \u00e9chelle mesure <strong>la complexit\u00e9 de l'itin\u00e9raire sur une \u00e9chelle de 1 \u00e0 5<\/strong>\u00e9quivalent au degr\u00e9 de complexit\u00e9 \u00e0 communiquer.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Informaci\u00f3n-de-valoraci\u00f3n-complejidad-del-itinerario_by-jean-frederic-fortier_800x600.jpg\" alt=\"Informations sur l&#039;\u00e9valuation : complexit\u00e9 de l&#039;itin\u00e9raire \/ Photo : Jean Frederic Fortier\" class=\"wp-image-11603\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Informaci\u00f3n-de-valoraci\u00f3n-complejidad-del-itinerario_by-jean-frederic-fortier_800x600.jpg 800w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Informaci\u00f3n-de-valoraci\u00f3n-complejidad-del-itinerario_by-jean-frederic-fortier_800x600-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Informaci\u00f3n-de-valoraci\u00f3n-complejidad-del-itinerario_by-jean-frederic-fortier_800x600-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Informaci\u00f3n-de-valoraci\u00f3n-complejidad-del-itinerario_by-jean-frederic-fortier_800x600-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption>Informations sur l'\u00e9valuation : complexit\u00e9 de l'itin\u00e9raire \/ Photo : Jean Frederic Fortier<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Les param\u00e8tres \u00e9tudi\u00e9s sont identifi\u00e9s par l'acronyme MIDE o\u00f9<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Moyen<\/strong>est l'environnement \u00e0 \u00e9tudier,<\/li><li><strong>Itin\u00e9raire<\/strong>le type de trajectoire \u00e0 suivre,<\/li><li><strong>D\u00e9placement<\/strong>qui pr\u00e9vient en fait du degr\u00e9 de difficult\u00e9 inh\u00e9rent \u00e0 la travers\u00e9e elle-m\u00eame,<\/li><li><strong>Effort<\/strong>L'\"effort physique\" est une mesure approximative de l'effort physique requis pour l'itin\u00e9raire indiqu\u00e9.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Gravit\u00e9 de l'environnement naturel<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La gravit\u00e9 de l'environnement naturel est le premier param\u00e8tre qui sera mesur\u00e9 en comptant son appr\u00e9ciation entre la note 1, qui indique que l'environnement est sans risque, et la note 5, qui indique que l'environnement pr\u00e9sente de nombreux facteurs de risque.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Orientation sur l'itin\u00e9raire<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ce param\u00e8tre mesure si les chemins \u00e0 suivre sont bien balis\u00e9s et s'il est possible de suivre les sentiers sans d\u00e9tour. Un indique que les chemins sont bien d\u00e9finis et cinq que la navigation est interrompue par des obstacles qu'il faut n\u00e9gocier.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Difficult\u00e9 de mouvement<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ce param\u00e8tre indique la difficult\u00e9 de se d\u00e9placer le long de l'itin\u00e9raire. Un indique qu'il est possible de se d\u00e9placer sur des surfaces lisses et fermes, comme une voie de transit, et cinq indique qu'il faut grimper pour avancer.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Effort \u00e0 fournir<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ce param\u00e8tre indique une mesure de temps pour d\u00e9crire la p\u00e9riode de marche n\u00e9cessaire pour parcourir l'itin\u00e9raire. Un indique que l'itin\u00e9raire peut \u00eatre parcouru en une heure de marche, tandis que cinq indique que l'itin\u00e9raire n\u00e9cessite 10 heures ou plus de marche effective. Cela signifie que l'itin\u00e9raire n\u00e9cessite un niveau \u00e9lev\u00e9 de condition physique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Notes techniques sur l'itin\u00e9raire : derniers conseils pour une excursion pleinement efficace.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dans cette derni\u00e8re section, et en fonction du type d'occasion rencontr\u00e9e, chaque tableau MIDE fournira des informations sur le type d'outils n\u00e9cessaires pour surmonter les obstacles que le terrain peut pr\u00e9senter.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/dicaciones-t\u00e9cnicas-del-Recorrido_by-kal-loftus_800x600.jpg\" alt=\"Instructions techniques \/ Photo : Kal Loftus\" class=\"wp-image-11604\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/dicaciones-t\u00e9cnicas-del-Recorrido_by-kal-loftus_800x600.jpg 800w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/dicaciones-t\u00e9cnicas-del-Recorrido_by-kal-loftus_800x600-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/dicaciones-t\u00e9cnicas-del-Recorrido_by-kal-loftus_800x600-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/dicaciones-t\u00e9cnicas-del-Recorrido_by-kal-loftus_800x600-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption>Instructions techniques \/ Photo : Kal Loftus<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cette section identifie principalement trois param\u00e8tres, parmi lesquels les donn\u00e9es concernant les <strong>les voies d'escalade, les pentes de neige \u00e0 traverser et la n\u00e9cessit\u00e9 de pratiquer les diff\u00e9rentes techniques de descente en rappel.<\/strong>. La pr\u00e9valence de ces conditions sur le terrain est le facteur qui d\u00e9terminera en soi la pr\u00e9sence de ces donn\u00e9es dans les tableaux MIDE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Faire en sorte que toute excursion soit totalement s\u00fbre et efficace, <strong><a rel=\"noreferrer noopener\" aria-label=\"Pour une randonn\u00e9e s\u00fbre et efficace, il est n\u00e9cessaire que l&#039;\u00e9quipe de randonneurs recherche des informations suppl\u00e9mentaires sur l&#039;itin\u00e9raire \u00e0 partir de sources telles que des livres, des guides illustr\u00e9s et divers portails Internet. Cela permettra de prendre des d\u00e9cisions plus efficaces sur le comportement \u00e0 adopter par le groupe (s&#039;ouvre dans un nouvel onglet).\" href=\"https:\/\/travesiapirenaica.com\/fr\/des-informations-sur-les-itineraires-de-randonnee\/\" target=\"_blank\">il est n\u00e9cessaire que l'\u00e9quipe de randonneurs recherche des informations suppl\u00e9mentaires sur l'itin\u00e9raire.<\/a><\/strong> par le biais de sources telles que des livres, des guides illustr\u00e9s et divers portails Internet. Cela permettra de prendre des d\u00e9cisions plus efficaces sur la mani\u00e8re dont le groupe doit se d\u00e9velopper.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est \u00e9galement n\u00e9cessaire de consulter le<strong> <a rel=\"noreferrer noopener\" aria-label=\"Il est \u00e9galement n\u00e9cessaire de v\u00e9rifier les conditions m\u00e9t\u00e9orologiques le jour de l&#039;excursion et de pr\u00e9parer \u00e0 l&#039;avance le mat\u00e9riel n\u00e9cessaire au voyage (s&#039;ouvre dans un nouvel onglet).\" href=\"https:\/\/travesiapirenaica.com\/fr\/meteo-de-montagne\/\" target=\"_blank\">les conditions m\u00e9t\u00e9orologiques<\/a> <\/strong>qui seront pr\u00e9sent\u00e9s le jour de l'excursion et <strong><a href=\"https:\/\/travesiapirenaica.com\/fr\/equipement-de-trekking\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Il est \u00e9galement n\u00e9cessaire de v\u00e9rifier les conditions m\u00e9t\u00e9orologiques le jour de l&#039;excursion et de pr\u00e9parer \u00e0 l&#039;avance le mat\u00e9riel n\u00e9cessaire au voyage (s&#039;ouvre dans un nouvel onglet).\">pr\u00e9parer \u00e0 l'avance le mat\u00e9riel qui devra \u00eatre utilis\u00e9 pendant le voyage<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est toujours n\u00e9cessaire d'insister sur ce point : lorsque vous partez en excursion, essayez toujours de partir en compagnie ; <strong>Ne jamais sortir seul<\/strong>. Assurez-vous toujours qu'un ami ou un membre de votre famille qui ne vous accompagne pas est au courant de votre excursion et sait quand vous rentrerez en cas d'urgence.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mise en \u0153uvre de chacun de ces conseils garantit une jouissance totale, absolue et s\u00fbre de l'environnement naturel.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>LIRE AUSSI : <a href=\"https:\/\/travesiapirenaica.com\/fr\/conseils-pour-le-trekking-aventure-en-toute-securite\/\" target=\"_blank\" rel=\"noreferrer noopener\">&gt; (s'ouvre dans un nouvel onglet)\"&gt;4 conseils de s\u00e9curit\u00e9 \u00e0 garder \u00e0 l'esprit lors d'une randonn\u00e9e &gt;&gt; (s'ouvre dans un nouvel onglet)\"&gt;4 conseils de s\u00e9curit\u00e9 \u00e0 garder \u00e0 l'esprit lors d'une randonn\u00e9e &gt;&gt; (s'ouvre dans un nouvel onglet)\"&gt;4 conseils de s\u00e9curit\u00e9 \u00e0 garder \u00e0 l'esprit lors d'une randonn\u00e9e<\/a><\/strong><\/h4>","protected":false},"excerpt":{"rendered":"La MIDE ou M\u00e9thode d'Information sur les Excursions est un outil capable d'indiquer le degr\u00e9 de difficult\u00e9 de n'importe quel itin\u00e9raire naturel de randonn\u00e9e.","protected":false},"author":191,"featured_media":11602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_wp_convertkit_post_meta":{"form":"-1","landing_page":"","tag":"0","restrict_content":"0"},"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2958],"tags":[],"series":[],"class_list":["post-10276","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-seguridad","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/\u00bfQu\u00e9-es-el-MIDE_BY-brandi-redd_800X600.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"vi4ds9hcMq\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/que-es-el-mide\/\">\u00bfQu\u00e9 es el MIDE?<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/que-es-el-mide\/embed\/#?secret=vi4ds9hcMq\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0\u00bfQu\u00e9 es el MIDE?\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"vi4ds9hcMq\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":2958,"label":"Seguridad"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/\u00bfQu\u00e9-es-el-MIDE_BY-brandi-redd_800X600.jpg",800,600,false],"author_info":{"display_name":"Eduardo Azcona","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/eduardo-2\/"},"comment_info":0,"category_info":[{"term_id":2958,"name":"Seguridad","slug":"seguridad","term_group":0,"term_taxonomy_id":2974,"taxonomy":"category","description":"Seguridad","parent":2946,"count":22,"filter":"raw","cat_ID":2958,"category_count":22,"category_description":"Seguridad","cat_name":"Seguridad","category_nicename":"seguridad","category_parent":2946}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/\u00bfQu\u00e9-es-el-MIDE_BY-brandi-redd_800X600.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/10276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/191"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=10276"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/10276\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/11602"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=10276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=10276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=10276"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=10276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}