{"id":10335,"date":"2025-01-09T17:44:31","date_gmt":"2025-01-09T16:44:31","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=10335"},"modified":"2025-01-09T17:44:33","modified_gmt":"2025-01-09T16:44:33","slug":"la-technique-de-course-en-trail","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/tecnica-de-carrera-en-trail-running\/","title":{"rendered":"Technique de course en trail"},"content":{"rendered":"<p>Du point de vue de la physioth\u00e9rapie, toutes les techniques de course en <em><strong><a href=\"https:\/\/travesiapirenaica.com\/fr\/course-sur-sentier\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (s&#039;ouvre dans un nouvel onglet)\">course sur sentier <\/a><\/strong><\/em>est sp\u00e9cialement con\u00e7u pour r\u00e9pondre \u00e0 deux objectifs principaux clairs et pr\u00e9cis :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>de fournir aux travaux du corridor <strong>un taux de rendement \u00e9lev\u00e9 <\/strong>et donc d'optimiser leurs mouvements, de les rendre plus efficaces et plus performants, de sorte que la d\u00e9pense \u00e9nerg\u00e9tique soit moindre et que la fatigue apparaisse plus tardivement. <\/li>\n\n\n\n<li><strong><a aria-label=\"de fournir au travail du coureur un indice de performance \u00e9lev\u00e9 et ainsi d&#039;optimiser son mouvement et de pr\u00e9venir les blessures en r\u00e9duisant les forces produites par l&#039;impact (s&#039;ouvre dans un nouvel onglet).\" href=\"https:\/\/travesiapirenaica.com\/fr\/blessures-problemes-physiques-randonneurs-cyclotouristes-sur-le-camino-santiago\/\" target=\"_blank\" rel=\"noreferrer noopener\">la pr\u00e9vention des blessures <\/a><\/strong>par la r\u00e9duction des forces produites par l'impact.<\/li>\n\n\n\n<li>plus de confiance, de fluidit\u00e9 et de coordination et, en fin de compte, un plus grand plaisir \u00e0 pratiquer l'activit\u00e9.  <\/li>\n<\/ul>\n\n\n\n<p>Que signifie la performance dans ce contexte ? Il s'agit tout simplement de la quantit\u00e9 d'\u00e9nergie n\u00e9cessaire pour courir. Une technique de course correcte en <em>course sur sentier <\/em>aidera \u00e0 disposer d'un <strong>un mouvement plus efficace d'un point de vue biom\u00e9canique<\/strong>Le \"geste\" qui permet \u00e0 un coureur de parcourir la plus grande distance, en faisant le moins d'effort possible et en maintenant cet effort pendant une p\u00e9riode prolong\u00e9e.<\/p>\n\n\n\n<p>Pour vous aider \u00e0 avoir une technique de course efficace, cet article vous pr\u00e9sentera ce qui caract\u00e9rise une technique de course inefficace et ce qui caract\u00e9rise une technique de course efficace.<\/p>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/tTkTNUyJvNY\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\"><\/iframe>\n\n\n\n<h4 class=\"wp-block-heading\">En un coup d'\u0153il :<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#tecnica\"><strong>Des \u00e9l\u00e9ments techniques efficaces. <\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#ejercicios\"><strong>Exercices : \u00e0 plat, en mont\u00e9e et en descente.<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#tecnica-correr-descalzo\"><strong>Technique de course pieds nus (chaussures minimalistes)<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"tecnica\">\u00c9l\u00e9ments \u00e0 prendre en compte pour une technique de course efficace et s\u00fbre en trail running<\/h2>\n\n\n\n<p>Une technique de course s\u00fbre est un mode d'action qui permet au coureur d'\u00e9viter tout type de blessure. Pour formuler et identifier les techniques s\u00fbres, les experts en physioth\u00e9rapie se basent sur deux crit\u00e8res \u00e9l\u00e9mentaires et n\u00e9cessaires :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>les <strong>force d'impact<\/strong> doit avoir une r\u00e9duction de vitesse<\/li>\n\n\n\n<li>les <strong>une meilleure stabilit\u00e9 <\/strong>du quadrant inf\u00e9rieur (pieds et jambes)<\/li>\n<\/ul>\n\n\n\n<p><strong>L'\u00e9quilibre que nous sommes capables de d\u00e9velopper joue un r\u00f4le fondamental dans le maintien de la stabilit\u00e9 du quadrant inf\u00e9rieur.<\/strong>Par cons\u00e9quent, l'une des strat\u00e9gies utilis\u00e9es par les coureurs consiste \u00e0 effectuer des exercices de conditionnement, en mont\u00e9e et en descente, qui renforceront l'endurance physique de l'athl\u00e8te.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/C\u00f3mo-elegir-ropa-para-el-trail-running_by-brian-metzler_800x600.jpg\" alt=\"Comment choisir ses v\u00eatements de trail running \/ Photo : Brian Metzler\" class=\"wp-image-10857\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/C\u00f3mo-elegir-ropa-para-el-trail-running_by-brian-metzler_800x600.jpg 800w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/C\u00f3mo-elegir-ropa-para-el-trail-running_by-brian-metzler_800x600-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/C\u00f3mo-elegir-ropa-para-el-trail-running_by-brian-metzler_800x600-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/C\u00f3mo-elegir-ropa-para-el-trail-running_by-brian-metzler_800x600-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption class=\"wp-element-caption\">Une bonne technique de course en trail est primordiale \/ Photo : Brian Metzler<\/figcaption><\/figure>\n\n\n\n<p>Une technique de course s\u00fbre, qui r\u00e9duit la vitesse de la force d'impact, sera automatiquement une technique plus efficace. La raison en est simple : <strong>le coureur n'utilisera pas autant d'\u00e9nergie pour avancer dans la course<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Les techniques de carri\u00e8re inefficaces : quelles sont-elles et sous quelles caract\u00e9ristiques peuvent-elles \u00eatre identifi\u00e9es ?<\/h3>\n\n\n\n<p>Le <strong>la consommation d'\u00e9nergie <\/strong>est l'un des facteurs les plus d\u00e9cisifs pour qualifier une technique de course. Une technique de course sera totalement inefficace si sa mise en \u0153uvre n\u00e9cessite une grande quantit\u00e9 d'\u00e9nergie corporelle, ce qui implique une diminution directe de la distance parcourue et du temps de course.<\/p>\n\n\n\n<p>Une technique inefficace est identifi\u00e9e par une foul\u00e9e trop longue, \u00e9loign\u00e9e de l'objet. <strong>centre de gravit\u00e9<\/strong>En quoi cela est-il pertinent ? Parce que, m\u00eame si son intention est d'acc\u00e9l\u00e9rer, le coureur va avancer en coupant continuellement l'inertie qui le propulse vers l'avant. Par cons\u00e9quent, le coureur devra faire un grand effort pour se propulser \u00e0 nouveau vers l'avant.<\/p>\n\n\n\n<p>Une autre chose \u00e0 noter \u00e0 propos de ces techniques de course \u00e0 pied est leur <strong>vitesse \u00e9lev\u00e9e \u00e0 la force d'impact (VLR)<\/strong>Cela a un impact cons\u00e9quent sur la structure osseuse du coureur et peut provoquer des blessures. S'il y a \u00e9galement un d\u00e9placement vertical notable, la cadence de course sera r\u00e9duite.<\/p>\n\n\n\n<p>En suivant une telle technique, la course ressemblera plus \u00e0 une progression de sauts successifs qu'\u00e0 un syst\u00e8me d'\u00e9tapes efficaces et coh\u00e9rentes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Comment identifier une technique de course efficace ? Facteurs de pr\u00e9vention des blessures<\/h3>\n\n\n\n<p>Une technique de course \u00e0 pied en <em>course sur sentier <\/em>Tous les physioth\u00e9rapeutes classeront la maladie dans la cat\u00e9gorie des <strong>efficace lorsque le niveau d'\u00e9nergie \u00e0 utiliser est minimal <\/strong>et faible par rapport \u00e0 la moyenne \u00e9tablie.<\/p>\n\n\n\n<p>Plusieurs raisons rendent possible cette \u00e9chelle de performance : d'une part, la charge \u00e9nerg\u00e9tique plus importante est \u00e9conomis\u00e9e en \u00e9tablissant un point de contact avec le sol tr\u00e8s proche du centre de gravit\u00e9 de l'athl\u00e8te ; d'autre part, la charge \u00e9nerg\u00e9tique plus importante est \u00e9conomis\u00e9e en \u00e9tablissant un point de contact avec le sol tr\u00e8s proche du centre de gravit\u00e9 de l'athl\u00e8te. En r\u00e9sum\u00e9, <strong>le talon doit toucher le sol juste en dessous du centre de gravit\u00e9 du corps<\/strong>.<\/p>\n\n\n\n<p>Une autre chose qui se produit, c'est qu'en ayant une technique d'ex\u00e9cution en <em>course sur sentier<\/em> efficace, c'est qu'il est<strong> r\u00e9duit la vitesse de la force d'impact<\/strong>Les pieds et les articulations du coureur sont moins vuln\u00e9rables aux blessures.<\/p>\n\n\n\n<p>De la m\u00eame mani\u00e8re, <strong>le temps de contact avec le sol sera beaucoup plus court.<\/strong>Le coureur pourra utiliser l'\u00e9lan qu'il a d\u00e9j\u00e0 pour continuer \u00e0 avancer. Si la technique <strong>r\u00e9duit le d\u00e9placement vertical<\/strong>Dans ce cas, la trajectoire du coureur sera plus lin\u00e9aire et optimale, car pour se d\u00e9placer, le coureur devra d\u00e9penser beaucoup moins d'\u00e9nergie.<\/p>\n\n\n\n<p>Pour clore cette section, une technique de course efficace <strong>aide \u00e0 augmenter le rythme de la marche<\/strong>. L'athl\u00e8te peut choisir celle avec laquelle il se sent le plus \u00e0 l'aise, mais il est possible d'atteindre une cadence d'environ 180 pas par minute.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"ejercicios\">Exercices de technique de course en trail running (plat, mont\u00e9e et descente)<\/h2>\n\n\n\n<p>La technique en Trail Running est fondamentale pour am\u00e9liorer l'\u00e9conomie de course, r\u00e9duire les blessures, augmenter la force et am\u00e9liorer nos temps. Nous allons vous pr\u00e9senter quelques exercices pour l'am\u00e9liorer. N'oubliez pas d'\u00e9valuer si ces exercices vous conviennent en fonction de votre condition physique, car ils pourraient \u00eatre nocifs. <\/p>\n\n\n\n<p>La technique dont nous aurons besoin en montagne n'a rien \u00e0 voir avec celle dont nous aurons besoin sur l'asphalte. L'id\u00e9al est de s'entra\u00eener en montagne, mais ce n'est pas toujours possible.  <\/p>\n\n\n\n<p>Nous nous sommes inspir\u00e9s de l'approche adopt\u00e9e par la Commission europ\u00e9enne. <strong>Sergio Sanchez <\/strong>dans la vid\u00e9o suivante, que nous estimons tr\u00e8s compl\u00e8te, et qui pr\u00e9sente des variantes que nous jugeons appropri\u00e9es. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Exercices de technique de course en trail running (plat, mont\u00e9e et descente)\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/oUl9cN_ywtQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Technique de course : \u00e0 plat<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Exercice 1 : des talons aux fesses.<\/strong> Le premier exercice propos\u00e9 par Sergio est un classique. Il nous conseille d'\u00e9viter de laisser les pieds morts. L'\u00e9lan doit \u00eatre synchronis\u00e9 et il faut surtout chercher \u00e0 obtenir un mouvement naturel. <\/li>\n\n\n\n<li><strong>Exercice 2 : foul\u00e9e<\/strong>. Nous lan\u00e7ons une jambe en avant et la jambe arri\u00e8re est compl\u00e8tement droite. Il est important que dans le bas du corps, les trois articulations, la hanche, le genou en flexion de hanche et la cheville activ\u00e9e avec tension, soient maintenues dans une bonne position. L'\u00e9volution de cet exercice sera les sauts sur une jambe.<\/li>\n\n\n\n<li><strong>Exercice 3 : Sauts \u00e0 une jambe.<\/strong> Ce qui compte, c'est la jambe d'appui. Nous sautons et atterrissons alternativement sur la m\u00eame jambe. <\/li>\n<\/ul>\n\n\n\n<p>Nous proposons maintenant plusieurs exercices de saut \u00e0 la corde. L'ex\u00e9cution de ces exercices est tr\u00e8s importante. N'oubliez pas : le dos droit, le regard droit devant, le coude \u00e0 90 degr\u00e9s, les poings serr\u00e9s, et l'\u00e9lan de fa\u00e7on \u00e0 ce que le bout des doigts touche les hanches. <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Exercice 4 : <em>Saut \u00e0 la corde<\/em>. <\/strong>Tronc droit, balancement \u00e9nergique et mont\u00e9e des genoux le plus haut possible, en ramenant les talons vers les fesses. Cet exercice est un classique.<\/li>\n<\/ul>\n\n\n\n<p>Nous allons maintenant pr\u00e9senter des variantes de cet exercice, dans le but d'activer et de stabiliser diff\u00e9rentes parties et muscles du corps.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Exercice 5 : <em>Saut \u00e0 la corde <\/em>1 jambe. <\/strong>Nous levons le genou d'un c\u00f4t\u00e9, tandis que l'autre genou accompagne naturellement le mouvement. <\/li>\n\n\n\n<li><strong>Exercice 6 : <em>Saut \u00e0 la corde <\/em>1 jambe lat\u00e9rale. <\/strong>M\u00eame exercice que le pr\u00e9c\u00e9dent mais en se d\u00e9pla\u00e7ant lat\u00e9ralement. Vous pouvez effectuer l'exercice en utilisant des haies.<\/li>\n\n\n\n<li><strong>Exercice 7 : <em>Saut \u00e0 la corde <\/em>toutes les trois \u00e9tapes. <\/strong>Variante plus complexe du saut \u00e0 la corde sur une jambe dans laquelle les deux jambes sont altern\u00e9es tous les trois pas. <\/li>\n\n\n\n<li><strong>Exercice 8 : <em>Saut \u00e0 la corde <\/em>tous les trois pas avec rebond. <\/strong>Il suffit d'ajouter un quatri\u00e8me mouvement o\u00f9 l'on reste statique en levant le genou et en faisant rebondir le pied. Le rebond am\u00e9liore la r\u00e9activit\u00e9 de la cheville. <\/li>\n\n\n\n<li><strong>Exercice 9 : <em>Saut \u00e0 la corde <\/em>lent.<\/strong> Un saut \u00e0 la corde au ralenti recommand\u00e9 pour am\u00e9liorer la coordination des bras et des jambes. <\/li>\n<\/ul>\n\n\n\n<p>Maintenant, un exercice pour stimuler l'impulsion.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Exercice 10 : Triple seconde. <\/strong>Nous nous concentrons sur la phase de propulsion, en renfor\u00e7ant l'extension et la flexion des hanches. Nous insisterons particuli\u00e8rement sur l'impulsion de la cheville, sans oublier l'envol de la jambe libre. En levant le genou, nous for\u00e7ons la jambe oppos\u00e9e \u00e0 effectuer la totalit\u00e9 de l'impulsion de la cheville jusqu'\u00e0 la fin.<\/li>\n\n\n\n<li><strong>Exercice 11 : les pas russes. <\/strong>Similaire \u00e0 <em>sauter <\/em>mais avec les genoux compl\u00e8tement tendus. Il est tr\u00e8s important de verrouiller les genoux et de laisser les chevilles et les hanches faire toute la pouss\u00e9e. Atterrissez toujours sur vos orteils et essayez de garder votre dos vertical et de coordonner vos jambes avec vos bras.<\/li>\n\n\n\n<li><strong>Exercice 12 : course lat\u00e9rale. <\/strong>Il ne s'agit pas d'un exercice sp\u00e9cifique, mais il vous aidera \u00e0 am\u00e9liorer la stabilit\u00e9 des chevilles et des hanches, tout en travaillant la coordination des jambes et des bras et leur mobilit\u00e9. Nous am\u00e9liorons \u00e9galement la puissance de notre foul\u00e9e et travaillons diff\u00e9rents groupes musculaires.<\/li>\n\n\n\n<li><strong>Exercice 13 : courir \u00e0 reculons. <\/strong>Un grand exercice oubli\u00e9 pour terminer les exercices sur le plat. Nous courons en arri\u00e8re sur quelques m\u00e8tres, en pliant les genoux, en entrant toujours avec l'avant-pied et en coordonnant le mouvement avec les bras.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Technique de course : Escalade<\/h3>\n\n\n\n<p>La principale chose \u00e0 faire lorsque vous courez en mont\u00e9e est de rester au sol et d'utiliser votre \u00e9lan vers l'avant. Inclinez votre centre de gravit\u00e9 vers l'avant. <\/p>\n\n\n\n<ul class=\"wp-block-list\" id=\"block-269221f3-499b-417a-8284-0e63b93bf89d\">\n<li><strong>Exercice 14 : allongement de la foul\u00e9e (marche). <\/strong>Nous le pratiquerons sur une mont\u00e9e plus raide. Il s'agit \u00e9galement d'un exercice de force sp\u00e9cifique. Nous pouvons poser nos mains sur les quadriceps pour guider et encourager le mouvement. <\/li>\n\n\n\n<li><strong>Exercice 15 : raccourcir la foul\u00e9e (marche). <\/strong>Nous r\u00e9duisons maintenant l'amplitude et augmentons la fr\u00e9quence. Cela doit se faire aux moments o\u00f9 la pente augmente. Elle favorise un mouvement qui consomme moins d'\u00e9nergie, \u00e0 partir d'une certaine pente.<\/li>\n\n\n\n<li><strong>Exercice 16 : Fr\u00e9quence maximale (course \u00e0 pied)<\/strong>. Des foul\u00e9es courtes et beaucoup de vitesse de d\u00e9placement. Pensez que nous faisons des exercices que nous appliquerons chacun en fonction de la pente que nous trouvons et de notre \u00e9tat \u00e0 ce moment-l\u00e0.<\/li>\n\n\n\n<li><strong>Exercice 17 : Freinage exag\u00e9r\u00e9. <\/strong>Propulsez-vous avec vos bras, en gardant \u00e0 l'esprit que vos bras vous propulsent \u00e9galement pendant la course. Sentez l'inertie de vos bras pour faciliter l'ascension. Le mouvement doit \u00eatre naturel, de fa\u00e7on \u00e0 ce que vous ayez l'air rel\u00e2ch\u00e9.<\/li>\n<\/ul>\n\n\n\n<p>En r\u00e8gle g\u00e9n\u00e9rale, vous devez garder votre pied sous votre centre de gravit\u00e9. Ne vous penchez pas trop en avant. Et, comme nous l'avons mentionn\u00e9 dans l'un des exercices, utilisez vos bras de mani\u00e8re naturelle, en les laissant libres, en profitant de leur inertie. Essayez de maintenir les gastrocn\u00e9miens et le sol\u00e9aire actifs, ce sera plus efficace et moins nocif.<\/p>\n\n\n\n<p>Lorsque la pente devient tr\u00e8s raide et que l'on constate que l'on d\u00e9pense beaucoup d'\u00e9nergie, il est temps de marcher. Vous pouvez poser vos mains sur vos quadriceps. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Technique de course : Descentes<\/h3>\n\n\n\n<p>Tout d'abord, il faut s'amuser et perdre sa peur. Dans les descentes, vous avez tendance \u00e0 abaisser votre centre de gravit\u00e9. L'\u00e9quilibre sera maintenu par les bras. Faites des pas courts et rapides. Et lorsque vous travaillez votre technique de course, \u00e9vitez de g\u00eeter pour r\u00e9duire l'impact. <\/p>\n\n\n\n<ul class=\"wp-block-list\" id=\"block-269221f3-499b-417a-8284-0e63b93bf89d\">\n<li><strong>Exercice 18 : bras crois\u00e9s. <\/strong>Exag\u00e9rer la position crois\u00e9e des bras pour am\u00e9liorer la stabilit\u00e9. Il faut se familiariser avec cette position jusqu'\u00e0 ce que les mouvements et la fa\u00e7on dont ils l'accompagnent deviennent totalement naturels.<\/li>\n\n\n\n<li><strong>Exercice 19 : Fr\u00e9quence maximale. <\/strong>Nous \u00e9craserons les descentes techniques en augmentant la fr\u00e9quence de nos pas. Ce sera un exercice en \u00e9toile, une fa\u00e7on de se d\u00e9placer en contr\u00f4lant le mouvement en fonction du terrain.<\/li>\n\n\n\n<li><strong>Exercice 20 : changer de chemin. <\/strong>Vous pouvez chercher des exercices plus difficiles si vous vous sentez \u00e0 l'aise. Apr\u00e8s tout, c'est en pratiquant que l'on s'am\u00e9liore.<em> coureur de fond<\/em>alors innovez dans les descentes. Cela les rendra \u00e9galement plus amusantes. <\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Technique de course : Plyom\u00e9trie. <\/h3>\n\n\n\n<p>Il s'agit d'exercices de musculation tr\u00e8s sp\u00e9cifiques pour <em>piste <\/em>et presque tous les sports gr\u00e2ce \u00e0 l'activation musculaire. Exercices dans lesquels on recherche une haute intensit\u00e9 dans le but d'am\u00e9liorer la force, la vitesse et l'explosivit\u00e9. <\/p>\n\n\n\n<ul class=\"wp-block-list\" id=\"block-216d64d2-53a5-4f21-9b1f-fa389fa6899e\">\n<li><strong>Exercice 21 : Saut en contre-mouvement (CMJ)<\/strong>. Nous commen\u00e7ons par une s\u00e9rie de sauts multiples, en les ex\u00e9cutant \u00e0 l'intensit\u00e9 maximale et en nous arr\u00eatant avant que la fatigue ne s'installe. Flexion-extension des hanches et des genoux \u00e0 la vitesse la plus \u00e9lev\u00e9e possible pour atteindre la plus grande hauteur possible. Au moment de la flexion maximale, le genou est \u00e0 90 degr\u00e9s. Il s'agit d'un exercice tr\u00e8s courant dans de nombreux sports, en plus de l'exercice d'endurance. <em>en cours d'ex\u00e9cution <\/em>y <em>course sur sentier<\/em>L'utilisation d'un niveau \u00e9lev\u00e9 de vitamine E renforce la contraction musculaire qui se produit lors de ces activit\u00e9s. <\/li>\n\n\n\n<li><strong>Exercice 22 : fentes saut\u00e9es (sauts en ciseaux)<\/strong>. Beaucoup plus intense, mais nous obtiendrons une plus grande activation des muscles tels que le fessier, le moyen fessier ou les muscles psoasiliaques.<\/li>\n\n\n\n<li><strong>Exercice 23 : <em>Saut en chute libre<\/em><\/strong>. Exercice tr\u00e8s efficace pour travailler la r\u00e9activit\u00e9 du bas du corps en g\u00e9n\u00e9ral. Attention, l'impact rend cet exercice assez dommageable pour les articulations. <\/li>\n\n\n\n<li><strong>Exercice 24 : grimper pieds joints<\/strong>. Sauter sur la pierre avec les pieds joints. Un exercice tr\u00e8s sp\u00e9cifique. On s'aide de l'impulsion des bras. Attention \u00e0 ne pas glisser.<\/li>\n\n\n\n<li><strong>Exercice 25 : Lev\u00e9es de la foul\u00e9e<\/strong>. Sa variante \u00e0 une jambe. Beaucoup plus intense et sp\u00e9cifique au trail. Cet exercice est tr\u00e8s utile pour d\u00e9tecter les d\u00e9s\u00e9quilibres entre une jambe et l'autre, dus \u00e0 un manque de force, de proprioception ou \u00e0 une surcharge de l'autre c\u00f4t\u00e9. Activation des gastrocn\u00e9miens et du sol\u00e9aire en levant la cheville.<\/li>\n\n\n\n<li><strong>Exercice 26 : rebonds de la cheville en hauteur<\/strong>. Un exercice ax\u00e9 sur l'am\u00e9lioration de la r\u00e9activit\u00e9 de la cheville, ce qui nous permettra d'\u00eatre plus performants. <\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"tecnica-correr-descalzo\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/chaussures-minimalistes\/\" target=\"_blank\" rel=\"noreferrer noopener\">Apprenez \u00e0 courir comme si vous \u00e9tiez pieds nus<\/a><\/h2>\n\n\n\n<p>Pour comprendre les diff\u00e9rences essentielles entre les deux techniques de course, ce qui est actuellement consid\u00e9r\u00e9 comme une technique de course efficace se retrouve chez les coureurs qui courent habituellement pieds nus.<\/p>\n\n\n\n<p>Lorsqu'il court pieds nus, le coureur peut ressentir une douleur s'il entre en contact avec le sol par le talon ; le contact est un peu violent. La seule fa\u00e7on pour le coureur de r\u00e9duire l'impact sur le pied et de ne pas ressentir de douleur est de <strong>soutenir d'abord le m\u00e9tatarsien puis le talon<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/Correr-con-zapatillas-minimalistas_by-asoggetti_800x600.jpg\" alt=\"Courir avec des chaussures minimalistes \/ Photo : Asoggetti\" class=\"wp-image-10496\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/Correr-con-zapatillas-minimalistas_by-asoggetti_800x600.jpg 800w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/Correr-con-zapatillas-minimalistas_by-asoggetti_800x600-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/Correr-con-zapatillas-minimalistas_by-asoggetti_800x600-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/Correr-con-zapatillas-minimalistas_by-asoggetti_800x600-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption class=\"wp-element-caption\">Courir avec des chaussures minimalistes \/ Photo : Asoggetti<\/figcaption><\/figure>\n\n\n\n<p>Cependant, la technique de course inefficace d\u00e9crite ci-dessus, dans laquelle le coureur avance avec le pied \u00e9loign\u00e9 du centre de gravit\u00e9 et le talon en premier, est un type de mouvement que l'on n'observe que chez les coureurs qui portent des chaussures de sport. La raison en est que les chaussures prot\u00e8gent le talon et amortissent une partie de l'impact sur cette partie du pied.<\/p>\n\n\n\n<p>Afin de disposer d'une technique de fonctionnement en <em>course sur sentier<\/em> pour \u00eatre efficace, il faudrait que le coureur s'entra\u00eene \u00e0 courir comme s'il \u00e9tait pieds nus tout en prot\u00e9geant son pied avec une chaussure de sport. <a href=\"https:\/\/travesiapirenaica.com\/fr\/zapatillas-trail-running\/\"><strong>des chaussures de sport appropri\u00e9es<\/strong><\/a>.<\/p>\n\n\n\n<p>La technique est plus importante que l'entra\u00eenement pour augmenter votre distance de course, car une technique correcte vous permettra d'aller plus vite et de maintenir votre effort plus longtemps. Vous serez un meilleur coureur \u00e0 tous les niveaux.<\/p>","protected":false},"excerpt":{"rendered":"Une technique de course en trail sera qualifi\u00e9e par tout physioth\u00e9rapeute d'efficace lorsque le niveau d'\u00e9nergie \u00e0 utiliser est minimal. Voici quelques secrets techniques.","protected":false},"author":1,"featured_media":11842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3010],"tags":[],"series":[],"class_list":["post-10335","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-running","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/12\/T\u00e9cnica-carrera-en-trail-running_by-Robin-McConnell-_Flickr_-CC-BY-2..0_800x600.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"ZUcig0DIxJ\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/tecnica-de-carrera-en-trail-running\/\">T\u00e9cnica de carrera en trail running<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/tecnica-de-carrera-en-trail-running\/embed\/#?secret=ZUcig0DIxJ\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0T\u00e9cnica de carrera en trail running\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"ZUcig0DIxJ\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":3010,"label":"Trail Running"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/12\/T\u00e9cnica-carrera-en-trail-running_by-Robin-McConnell-_Flickr_-CC-BY-2..0_800x600.jpg",800,600,false],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":3010,"name":"Trail Running","slug":"running","term_group":0,"term_taxonomy_id":3026,"taxonomy":"category","description":"Running","parent":1577,"count":9,"filter":"raw","cat_ID":3010,"category_count":9,"category_description":"Running","cat_name":"Trail Running","category_nicename":"running","category_parent":1577}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/12\/T\u00e9cnica-carrera-en-trail-running_by-Robin-McConnell-_Flickr_-CC-BY-2..0_800x600.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/10335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=10335"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/10335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/11842"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=10335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=10335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=10335"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=10335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}