{"id":10523,"date":"2018-10-25T16:58:41","date_gmt":"2018-10-25T14:58:41","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=10523"},"modified":"2025-02-19T23:37:52","modified_gmt":"2025-02-19T22:37:52","slug":"usine-royale-deugi","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/real-fabrica-de-eugi\/","title":{"rendered":"Les ruines \u00e9nigmatiques de l'usine royale de munitions \u00e0 Eugi"},"content":{"rendered":"\n<p>En el Pirineo navarro, escondidas bajo un tupido bosque de hayas, se encuentran las ruinas de la <strong>Real F\u00e1brica de Municiones de Eugi<\/strong>. Un lugar asombroso que nos har\u00e1 viajar en el tiempo a trav\u00e9s de la historia y que recuerda el pasado industrial que durante un tiempo se vivi\u00f3 en esta zona. Todo, en medio de un entorno natural privilegiado que merece la pena visitar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un poco de Historia<\/h2>\n\n\n\n<p>La construcci\u00f3n de la <strong>Real F\u00e1brica de Armas de Eugi<\/strong> se remonta al a\u00f1o 1766, durante el reinado de Carlos III, aunque anteriormente ya exist\u00edan en funcionamiento otras dos ferrer\u00edas por la zona, en Olaondoa, hoy bajo las aguas del embalse, y en Olazar, en la confluencia de la regata de Artesiaga y el r\u00edo Arga, o tambi\u00e9n conocidas como f\u00e1brica de arriba y f\u00e1brica de abajo. Adem\u00e1s, es sabido que en Eugi ya exist\u00edan ferrer\u00edas desde mucho antes, la primera en el a\u00f1o 1410, la de Orrerarri. Los motivos, una gran masa forestal con la que elaborar el carb\u00f3n vegetal, una mina de hierro y un r\u00edo capaz de mover la maquinaria.<\/p>\n\n\n\n<p>El emplazamiento de esta nueva f\u00e1brica se situar\u00eda m\u00e1s arriba que las dos anteriores, en el paraje de Olaberri, junto al r\u00edo Arga.  El concepto de la nueva f\u00e1brica fue pionero en su g\u00e9nero y estaba basado en los nuevos sistemas de producci\u00f3n en cadena propios de la revoluci\u00f3n industrial, lo que obligaba a un dise\u00f1o arquitect\u00f3nico con una gran coordinaci\u00f3n entre todas las instalaciones. En total, la nueva f\u00e1brica-poblaci\u00f3n ocupaba 10.000 metros cuadrados y lleg\u00f3 a albergar una poblaci\u00f3n de 500 personas.<\/p>\n\n\n\n<p>Su principal actividad se centr\u00f3 en la fabricaci\u00f3n de balas de ca\u00f1\u00f3n de diversos calibres para el ej\u00e9rcito espa\u00f1ol. La parte fabril  contaba con dos hornos, talleres de refiner\u00eda y molder\u00eda, carpinter\u00eda, dos grandes carboneras y ocho arcos de siller\u00eda  sobre el r\u00edo donde se colocaban las ruedas hidr\u00e1ulicas para mover fuelles y martinetes. Despu\u00e9s, por otro lado, estaba la parte destinada a la poblaci\u00f3n, que contaba con viviendas para los operarios, caballerizas, una casa palacio y capilla, entre otras cosas.<\/p>\n\n\n\n<p>El fin de su actividad lleg\u00f3 de pronto, un 17 de octubre de 1794, cuando fue destruida por las tropas de la Francia revolucionaria durante la Guerra de la Convenci\u00f3n, tras una batalla en la que hubo 200 muertos y 700 personas fueron apresadas. Nunca m\u00e1s lleg\u00f3 a retomar su actividad y a partir de entonces, la vegetaci\u00f3n comenz\u00f3 a adue\u00f1arse de la f\u00e1brica hasta pr\u00e1cticamente engullirla. Tras m\u00e1s de 200 a\u00f1os de abandono, los trabajos de recuperaci\u00f3n puestos en marcha en 2012 sacaron a la luz este lugar, que puede ser considerado como los restos m\u00e1s antiguos de actividad netamente industrial en Navarra, y en 2016, fue declarado Bien de Inter\u00e9s Cultural.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Algunas fotos<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/01_eugi-1024x768.jpg\" alt=\"\" class=\"wp-image-46815\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/01_eugi-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/01_eugi-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/01_eugi-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/01_eugi-16x12.jpg 16w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/01_eugi-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/01_eugi-150x113.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/01_eugi.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/02_eugi-1024x768.jpg\" alt=\"\" class=\"wp-image-46816\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/02_eugi-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/02_eugi-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/02_eugi-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/02_eugi-16x12.jpg 16w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/02_eugi-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/02_eugi-150x113.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/02_eugi.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/03_eugi-1024x768.jpg\" alt=\"\" class=\"wp-image-46817\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/03_eugi-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/03_eugi-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/03_eugi-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/03_eugi-16x12.jpg 16w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/03_eugi-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/03_eugi-150x113.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/03_eugi.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/04_eugi-1024x768.jpg\" alt=\"\" class=\"wp-image-46818\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/04_eugi-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/04_eugi-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/04_eugi-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/04_eugi-16x12.jpg 16w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/04_eugi-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/04_eugi-150x113.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/04_eugi.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Si quer\u00e9is visitar este lugar&#8230;<\/h2>\n\n\n\n<p>Se encuentra en la carretera del Puerto de Urkiaga, a 8 km de Eugi y a unos 10 km de la frontera con Francia. Desde Pamplona son algo m\u00e1s de 30 kil\u00f3metros. Ver en <a href=\"https:\/\/www.google.es\/maps\/place\/Real+F%C3%A1brica+de+Municiones+de+Eugi+(ruinas)\/@43.0162765,-1.4885478,17z\/data=!3m1!4b1!4m6!3m5!1s0xd50dd293c25d6fb:0x45c051c35fad3a3d!8m2!3d43.0162726!4d-1.4859729!16s%2Fg%2F11cn16cdxv?hl=es&amp;entry=ttu&amp;g_ep=EgoyMDI1MDIxMi4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\">Google Maps<\/a> c\u00f3mo llegar.<\/p>\n\n\n\n<p>El lugar est\u00e1 abierto al p\u00fablico y es gratuito. Junto a las ruinas pod\u00e9is dejar el coche y visitarlo a vuestro aire. Encontrar\u00e9is algunos paneles informativos.<\/p>\n\n\n\n<p>Otra opci\u00f3n es concertar una visita guiada. Pod\u00e9is preguntar en Eugi en el <a href=\"http:\/\/eugi.es\/es\/que-ver\/centro-de-referencia-historica-olondo.html\" target=\"_blank\" rel=\"noopener\">Centro de referencia Hist\u00f3rica Olondo<\/a>.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><\/ul>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id10523_b6b71c-94{margin-top:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);}.kb-row-layout-id10523_b6b71c-94 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id10523_b6b71c-94 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id10523_b6b71c-94 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-sm, 1rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id10523_b6b71c-94{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;overflow:clip;isolation:isolate;}.kb-row-layout-id10523_b6b71c-94 > .kt-row-layout-overlay{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kb-row-layout-id10523_b6b71c-94 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id10523_b6b71c-94 > .kt-row-column-wrap{row-gap:var(--global-kb-gap-lg, 4rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id10523_b6b71c-94 > .kt-row-column-wrap{row-gap:var(--global-kb-gap-sm, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id10523_b6b71c-94 alignnone has-theme-palette7-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column10523_f3d380-31 > .kt-inside-inner-col{padding-bottom:0px;}.kadence-column10523_f3d380-31 > .kt-inside-inner-col,.kadence-column10523_f3d380-31 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column10523_f3d380-31 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column10523_f3d380-31 > .kt-inside-inner-col{flex-direction:column;}.kadence-column10523_f3d380-31 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column10523_f3d380-31 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column10523_f3d380-31{position:relative;}.kadence-column10523_f3d380-31, .kt-inside-inner-col > .kadence-column10523_f3d380-31:not(.specificity){margin-bottom:0px;}@media all and (max-width: 1024px){.kadence-column10523_f3d380-31 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column10523_f3d380-31 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column10523_f3d380-31\"><div class=\"kt-inside-inner-col\">\n<h4 class=\"wp-block-heading has-medium-font-size\">Cerca de aqu\u00ed te puede interesar:<\/h4>\n<\/div><\/div>\n\n\n<style>.kadence-column10523_f4d2d8-38 > .kt-inside-inner-col,.kadence-column10523_f4d2d8-38 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column10523_f4d2d8-38 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column10523_f4d2d8-38 > .kt-inside-inner-col{flex-direction:column;}.kadence-column10523_f4d2d8-38 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column10523_f4d2d8-38 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column10523_f4d2d8-38{position:relative;}@media all and (max-width: 1024px){.kadence-column10523_f4d2d8-38 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column10523_f4d2d8-38 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column10523_f4d2d8-38\"><div class=\"kt-inside-inner-col\"><style>.kt-post-loop10523_f851a9-e7 .kadence-post-image{padding-top:0px;padding-right:16px;padding-left:0px;}.kt-post-loop10523_f851a9-e7 .kt-feat-image-align-left{grid-template-columns:30% auto;}.kt-post-loop10523_f851a9-e7 .kt-blocks-post-grid-item-inner-wrap .kt-blocks-post-grid-item-inner{display:flex;flex-direction:column;justify-content:flex-start;}.kt-post-loop10523_f851a9-e7 .kt-post-grid-wrap{gap:16px 16px;}.kt-post-loop10523_f851a9-e7 .kt-blocks-post-grid-item{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;overflow:hidden;}.kt-post-loop10523_f851a9-e7 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:0px;}.kt-post-loop10523_f851a9-e7 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{text-align:left;}.kt-post-loop10523_f851a9-e7 .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop10523_f851a9-e7 .kt-blocks-post-grid-item .kt-blocks-above-categories{font-size:13px;line-height:20px;text-transform:uppercase;}.kt-post-loop10523_f851a9-e7 .kt-blocks-post-grid-item .entry-title{padding-top:5px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:var(--global-kb-font-size-md, 1.25rem);line-height:18px;font-weight:bold;}.kt-post-loop10523_f851a9-e7 .entry-content{padding-top:0px;padding-right:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-left:0px;font-size:14px;line-height:24px;}.kt-post-loop10523_f851a9-e7 .kt-blocks-post-footer{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;text-transform:uppercase;}.kt-post-loop10523_f851a9-e7 .entry-content:after{height:0px;}.kt-post-loop10523_f851a9-e7 .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kt-post-loop10523_f851a9-e7 .kt-blocks-post-grid-item{border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;}}@media all and (max-width: 767px){.kt-post-loop10523_f851a9-e7 .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;}}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop10523_f851a9-e7 kt-post-grid-layout-grid \"><div class=\"kt-post-grid-layout-grid-wrap kt-post-grid-wrap\" data-columns-xxl=\"2\" data-columns-xl=\"2\" data-columns-md=\"2\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><article class=\"kt-blocks-post-grid-item post-327 post type-post status-publish format-image has-post-thumbnail hentry category-pirineos tag-navarra tag-pirineo-navarro tag-pirineos tag-rutas post_format-post-format-image\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-left kt-feat-image-mobile-align-side\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/travesiapirenaica.com\/fr\/eugui-gr-11-transpirenaica-subida-al-adi-desde-urkiaga\/\" aria-label=\"Subida al Adi (1457 m) desde Urkiaga\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"600\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/11\/Ascensi\u00f3n-al-adi-desde-Urkiaga.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Ascensi\u00f3n al adi desde Urkiaga\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/11\/Ascensi\u00f3n-al-adi-desde-Urkiaga.jpg 760w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/11\/Ascensi\u00f3n-al-adi-desde-Urkiaga-600x474.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/11\/Ascensi\u00f3n-al-adi-desde-Urkiaga-300x237.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/11\/Ascensi\u00f3n-al-adi-desde-Urkiaga-759x600.jpg 759w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h4 class=\"entry-title\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/eugui-gr-11-transpirenaica-subida-al-adi-desde-urkiaga\/\">Subida al Adi (1457 m) desde Urkiaga<\/a><\/h4><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-38691 post type-post status-publish format-standard has-post-thumbnail hentry category-rutas category-pirineos tag-navarra tag-pirineo-navarro tag-pirineos tag-rutas\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-left kt-feat-image-mobile-align-side\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/travesiapirenaica.com\/fr\/okoro\/\" aria-label=\"Okoro (1.259m) por el puerto de Artesiaga y el monte Erreguerena.\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/06_Artsal-1024x768.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/06_Artsal-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/06_Artsal-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/06_Artsal-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/06_Artsal-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/06_Artsal.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h4 class=\"entry-title\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/okoro\/\">Okoro (1.259m) por el puerto de Artesiaga y el monte Erreguerena.<\/a><\/h4><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-22342 post type-post status-publish format-image has-post-thumbnail hentry category-pirineos post_format-post-format-image\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-left kt-feat-image-mobile-align-side\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/travesiapirenaica.com\/fr\/real-fabrica-armas-orbaiceta\/\" aria-label=\"Real F\u00e1brica de Armas de Orbaiceta\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/05\/cc-F\u00e1brica_de_Armas_Orbaizeta_6_By-josemi-merino-torrens-Own-work-CC-BY-SA-4.0-httpscreativecommons.orglicensesby-sa4-1024x683.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"F\u00e1brica de Armas Orbaizeta \/ Foto: Josemi Merino Torrens [CC-BY-SA-4.0] Wikimedia Commons\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/05\/cc-F\u00e1brica_de_Armas_Orbaizeta_6_By-josemi-merino-torrens-Own-work-CC-BY-SA-4.0-httpscreativecommons.orglicensesby-sa4-1024x683.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/05\/cc-F\u00e1brica_de_Armas_Orbaizeta_6_By-josemi-merino-torrens-Own-work-CC-BY-SA-4.0-httpscreativecommons.orglicensesby-sa4-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/05\/cc-F\u00e1brica_de_Armas_Orbaizeta_6_By-josemi-merino-torrens-Own-work-CC-BY-SA-4.0-httpscreativecommons.orglicensesby-sa4-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/05\/cc-F\u00e1brica_de_Armas_Orbaizeta_6_By-josemi-merino-torrens-Own-work-CC-BY-SA-4.0-httpscreativecommons.orglicensesby-sa4-450x300.jpg 450w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/05\/cc-F\u00e1brica_de_Armas_Orbaizeta_6_By-josemi-merino-torrens-Own-work-CC-BY-SA-4.0-httpscreativecommons.orglicensesby-sa4-225x150.jpg 225w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/05\/cc-F\u00e1brica_de_Armas_Orbaizeta_6_By-josemi-merino-torrens-Own-work-CC-BY-SA-4.0-httpscreativecommons.orglicensesby-sa4-900x600.jpg 900w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/05\/cc-F\u00e1brica_de_Armas_Orbaizeta_6_By-josemi-merino-torrens-Own-work-CC-BY-SA-4.0-httpscreativecommons.orglicensesby-sa4-20x13.jpg 20w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/05\/cc-F\u00e1brica_de_Armas_Orbaizeta_6_By-josemi-merino-torrens-Own-work-CC-BY-SA-4.0-httpscreativecommons.orglicensesby-sa4-144x96.jpg 144w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/05\/cc-F\u00e1brica_de_Armas_Orbaizeta_6_By-josemi-merino-torrens-Own-work-CC-BY-SA-4.0-httpscreativecommons.orglicensesby-sa4-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/05\/cc-F\u00e1brica_de_Armas_Orbaizeta_6_By-josemi-merino-torrens-Own-work-CC-BY-SA-4.0-httpscreativecommons.orglicensesby-sa4.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h4 class=\"entry-title\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/real-fabrica-armas-orbaiceta\/\">Real F\u00e1brica de Armas de Orbaiceta<\/a><\/h4><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><article class=\"kt-blocks-post-grid-item post-9869 post type-post status-publish format-image has-post-thumbnail hentry category-rutas post_format-post-format-image\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-left kt-feat-image-mobile-align-side\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/travesiapirenaica.com\/fr\/selva-de-irati\/\" aria-label=\"Rutas en Selva de Irati, para conocer el reino del bosque\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/11_virgen_nieves.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Ermita Virgen de las Nieves\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/11_virgen_nieves.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/11_virgen_nieves-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/11_virgen_nieves-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/11_virgen_nieves-150x113.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/11_virgen_nieves-696x522.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/11_virgen_nieves-560x420.jpg 560w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/11_virgen_nieves-80x60.jpg 80w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/11_virgen_nieves-265x198.jpg 265w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/11_virgen_nieves-853x640.jpg 853w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/11_virgen_nieves-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h4 class=\"entry-title\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/selva-de-irati\/\">Rutas en Selva de Irati, para conocer el reino del bosque<\/a><\/h4><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Dans les Pyr\u00e9n\u00e9es navarraises, cach\u00e9es sous une \u00e9paisse for\u00eat de h\u00eatres, se trouvent les ruines de l'usine royale de munitions d'Eugi. Un lieu \u00e9tonnant qui nous fait voyager dans l'histoire et nous rappelle le pass\u00e9 industriel de cette r\u00e9gion. Le tout dans un environnement naturel privil\u00e9gi\u00e9 qui m\u00e9rite d'\u00eatre visit\u00e9.","protected":false},"author":1,"featured_media":46762,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[2815,2705,3066],"series":[],"class_list":["post-10523","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-pirineos","tag-navarra","tag-pirineo-navarro","tag-pirineos","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/lugar176-scaled.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"4eihHXLYQ4\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/real-fabrica-de-eugi\/\">Las enigm\u00e1ticas ruinas de la Real F\u00e1brica de Municiones de Eugi<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/real-fabrica-de-eugi\/embed\/#?secret=4eihHXLYQ4\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Las enigm\u00e1ticas ruinas de la Real F\u00e1brica de Municiones de Eugi\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"4eihHXLYQ4\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":5,"label":"Pirineos"}],"post_tag":[{"value":2815,"label":"Navarra"},{"value":2705,"label":"Pirineo navarro"},{"value":3066,"label":"Pirineos"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/lugar176-1024x683.jpg",1024,683,true],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":5,"name":"Pirineos","slug":"pirineos","term_group":0,"term_taxonomy_id":5,"taxonomy":"category","description":"","parent":0,"count":241,"filter":"raw","cat_ID":5,"category_count":241,"category_description":"","cat_name":"Pirineos","category_nicename":"pirineos","category_parent":0}],"tag_info":[{"term_id":2815,"name":"Navarra","slug":"navarra","term_group":0,"term_taxonomy_id":2831,"taxonomy":"post_tag","description":"Navarra ","parent":0,"count":5,"filter":"raw"},{"term_id":2705,"name":"Pirineo navarro","slug":"pirineo-navarro","term_group":0,"term_taxonomy_id":2721,"taxonomy":"post_tag","description":"Pirineo navarro ","parent":0,"count":5,"filter":"raw"},{"term_id":3066,"name":"Pirineos","slug":"pirineos","term_group":0,"term_taxonomy_id":3082,"taxonomy":"post_tag","description":"","parent":0,"count":18,"filter":"raw"}],"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/lugar176-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/10523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=10523"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/10523\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/46762"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=10523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=10523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=10523"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=10523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}