{"id":10689,"date":"2019-10-16T10:50:45","date_gmt":"2019-10-16T08:50:45","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=10689"},"modified":"2020-05-19T09:17:46","modified_gmt":"2020-05-19T07:17:46","slug":"sobrarbe-nature","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/sobrarbe-naturaleza\/","title":{"rendered":"Sobrarbe : l'explosion de la nature"},"content":{"rendered":"\n<p>La <strong>comarca del Sobrarbe<\/strong> situada en el coraz\u00f3n del <strong><a href=\"https:\/\/travesiapirenaica.com\/rutas-pirineo-aragones\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\">Pirineo aragon\u00e9s<\/a><\/strong> se caracteriza por su singular belleza reflejada en valles y monta\u00f1as. El aislamiento y la escasa poblaci\u00f3n han influido en la conservaci\u00f3n de un paisaje presidido por las altas cumbres y encerrando entre sus valles una gran diversidad de ecosistemas. La singularidad de la flora y fauna o del propio paisaje ha llevado a la protecci\u00f3n de grandes espacios de esta comarca, representados por el <strong><a href=\"https:\/\/travesiapirenaica.com\/parque-nacional-ordesa-monte-perdido\/\">Parque Nacional de Ordesa y Monte Perdido<\/a><\/strong><a href=\"https:\/\/travesiapirenaica.com\/parque-nacional-ordesa-monte-perdido\/\"> <\/a>como s\u00edmbolo de los espacios protegidos, o el <strong><a href=\"https:\/\/travesiapirenaica.com\/parque-natural-posets-madaleta\/\">Parque Natural de Poset-Maladeta<\/a><\/strong>, en el <strong>valle de Chistau o Gista\u00edn<\/strong>, espacio para las altas cumbres que conservan los \u00faltimos glaciares pirenaicos, as\u00ed como el <strong><a href=\"https:\/\/travesiapirenaica.com\/pirineos\/sierra-guara-somontano\/\">Parque Natural de la Sierra y Ca\u00f1ones de Guara<\/a><\/strong>, origen de los primeros asentamientos prehist\u00f3ricos de Arag\u00f3n, donde se puede disfrutar de la visi\u00f3n del mayor conjunto de ca\u00f1ones y gargantas del Pirineo.<\/p>\n\n\n\n<p>El Parque Nacional de <strong>Ordesa y Monte Perdido<\/strong>, uno de los m\u00e1s antiguos de Espa\u00f1a (1918) es el macizo calc\u00e1reo m\u00e1s alto de Europa. El paisaje se enmarca en anchos valles de origen glaciar (<strong><a href=\"https:\/\/pirineos.info\/que-hacer-en\/ordesa\/\" target=\"_blank\" rel=\"noopener\">Ordesa<\/a><\/strong><a href=\"https:\/\/pirineos.info\/que-hacer-en\/ordesa\/\" target=\"_blank\" rel=\"noopener\"> <\/a>y <strong><a href=\"https:\/\/travesiapirenaica.com\/valle-pineta\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (se abre en una nueva pesta\u00f1a)\">Pineta<\/a><\/strong>) y espectaculares ca\u00f1ones (<strong><a href=\"https:\/\/pirineos.info\/que-hacer-en\/canon-anisclo\/\" target=\"_blank\" rel=\"noopener\">A\u00f1isclo<\/a><\/strong> y <strong><a href=\"https:\/\/pirineos.info\/que-hacer-en\/garganta-de-escuain\/\" target=\"_blank\" rel=\"noopener\">Escuain<\/a><\/strong>) producidos por la erosi\u00f3n del agua. La tasca alpina, por encima de los 2.000 m. constituye la antesala de los grandes picos que forman el macizo del Monte Perdido.<\/p>\n\n\n\n<p>La mayor demanda de <strong>espacios naturales<\/strong> para el disfrute del tiempo libre unida a una mayor concienciaci\u00f3n sobre el medio ambiente, ha hecho de los espacios protegidos y de su entorno rural, zonas vulnerables precisas de una sensibilizaci\u00f3n acorde con la filosof\u00eda de protecci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/08\/Parque_nacional_monte_perdido_ordesa_By-Phqneste75_760x500.jpg\" alt=\"Parque Nacional de Ordesa y Monte Perdido \/ Foto: Phqneste75 (v\u00eda Wikimedia Commons)\" class=\"wp-image-7445\" width=\"760\" height=\"500\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/08\/Parque_nacional_monte_perdido_ordesa_By-Phqneste75_760x500.jpg 760w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/08\/Parque_nacional_monte_perdido_ordesa_By-Phqneste75_760x500-600x395.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/08\/Parque_nacional_monte_perdido_ordesa_By-Phqneste75_760x500-300x197.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/08\/Parque_nacional_monte_perdido_ordesa_By-Phqneste75_760x500-100x65.jpg 100w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/08\/Parque_nacional_monte_perdido_ordesa_By-Phqneste75_760x500-260x170.jpg 260w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/08\/Parque_nacional_monte_perdido_ordesa_By-Phqneste75_760x500-759x500.jpg 759w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><figcaption>Parque Nacional de Ordesa y Monte Perdido \/ Foto: Phqneste75 (v\u00eda Wikimedia Commons)<\/figcaption><\/figure>\n\n\n\n<p>Os proponemos recorrer los diferentes parajes de la comarca del Sobrarbe, tanto los impresionantes sectores del Parque Nacional de Ordesa y Monte Perdido y dem\u00e1s espacios protegidos, como las zonas lim\u00edtrofes, de igual belleza y sin embargo menos conocidas por el turismo, siempre bajo la filosof\u00eda de interpretar el paisaje, descubriendo la fauna, flora, las espectaculares formas; conocer las leyendas, supersticiones y tradiciones ancestrales de las gentes que pueblan estos paisajes, la forma de vida, el folklore y la gastronom\u00eda.<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comarca del Sobrarbe<\/h2>\n\n\n\n<p>El aislamiento hasta tiempos recientes de la comarca del Sobrarbe ha mantenido hasta nuestro d\u00edas un territorio pr\u00e1cticamente virgen. Con<strong> altas monta\u00f1as de belleza espectacular como <a href=\"https:\/\/travesiapirenaica.com\/cotiella\/\">Cotiella<\/a>, La Pe\u00f1a Monta\u00f1esa, Castillo Mayor, Montinier<\/strong> entre muchos otros. <\/p>\n\n\n\n<p>El antiguo Condado del Sobrarbe, se sit\u00faa en el coraz\u00f3n del Pirineo aragon\u00e9s, y presenta tres zonas geogr\u00e1ficas muy diferentes, tanto por el paisaje como por la forma de vida de sus gentes. <\/p>\n\n\n\n<p>Los altos<strong> Valles pirenaicos al norte<\/strong>: Torla, Broto, Vi\u00f3, La Solana, Pu\u00e9rtolas, Bielsa y Gistau, de clima h\u00famedo, dedicados tradicionalmente a la ganader\u00eda y a la explotaci\u00f3n forestal.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2016\/08\/180226_IG_desirecape_Pueblos-valle-de-ordesa_760x500.jpg\" alt=\"Los pueblos del Parque Nacional de Ordesa y Monte Perdido \/ Foto: @desirecape (Instagram)\" class=\"wp-image-6531\" width=\"760\" height=\"500\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2016\/08\/180226_IG_desirecape_Pueblos-valle-de-ordesa_760x500.jpg 760w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2016\/08\/180226_IG_desirecape_Pueblos-valle-de-ordesa_760x500-300x197.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2016\/08\/180226_IG_desirecape_Pueblos-valle-de-ordesa_760x500-150x99.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2016\/08\/180226_IG_desirecape_Pueblos-valle-de-ordesa_760x500-696x458.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2016\/08\/180226_IG_desirecape_Pueblos-valle-de-ordesa_760x500-146x96.jpg 146w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2016\/08\/180226_IG_desirecape_Pueblos-valle-de-ordesa_760x500-600x395.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2016\/08\/180226_IG_desirecape_Pueblos-valle-de-ordesa_760x500-100x65.jpg 100w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2016\/08\/180226_IG_desirecape_Pueblos-valle-de-ordesa_760x500-260x170.jpg 260w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2016\/08\/180226_IG_desirecape_Pueblos-valle-de-ordesa_760x500-759x500.jpg 759w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><figcaption>Los pueblos del Parque Nacional de Ordesa y Monte Perdido \/ Foto: @desirecape (Instagram)<\/figcaption><\/figure>\n\n\n\n<p>Las <strong>riberas de los r\u00edos Ara y Cinca<\/strong>, bien comunicadas, donde se encuentran Bolta\u00f1a y A\u00ednsa, principales localidades del Sobrarbe, y con el amplio valle de La Fueva forman lo que podr\u00edamos llamar \u00abBajo Sobrarbe\u00bb. <\/p>\n\n\n\n<p>El <strong>Viello Sobrarbe<\/strong>, Cabecera de la Sierra de Guara, tierra de los antiguos pobladores de la comarca y salpicado de pueblos como Arcusa, Ols\u00f3n, B\u00e1rcabo y otros muchos pueblos que guardan en su arquitectura medieval las reliquias de una historia pasada.<br><\/p>\n\n\n\n<p><strong>Los or\u00edgenes del Sobrarbe se remontan a \u00e9pocas prehist\u00f3ricas<\/strong>, siendo en tiempos medievales condado que contribuy\u00f3 a la <strong>formaci\u00f3n del reino de Arag\u00f3n<\/strong>. Testigo de su historia la comarca del Sobrarbe conserva un rico patrimonio hist\u00f3rico art\u00edstico en el que caben destacar las medievales construcciones militares y religiosas de Abizanda, Samitier, A\u00ednsa o Muro de Roda o el impresionante monasterio de San Victori\u00e1n, que en la Edad Media lleg\u00f3 a ejercer su dominio sobre las tierras del Alto Cinca y del \u00c9sera; el rom\u00e1nico de las iglesias del Valle de Vio o los pueblos y casas de Bestu\u00e9, Pu\u00e9rtolas, Tella, Guaso, Bolta\u00f1a, y tantos otros&#8230; que hace de esta comarca un rinc\u00f3n apasionante de la historia pasada en un paisaje de monta\u00f1as y valles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/travesiapirenaica.com\/parque-nacional-ordesa-monte-perdido\/\">Parque Nacional de Ordesa y Monte Perdido<\/a><\/h2>\n\n\n\n<p>Los valles de origen glaciar de <strong>Ordesa<\/strong> y <strong>Pineta<\/strong>, los ca\u00f1ones y gargantas de <strong><a href=\"https:\/\/travesiapirenaica.com\/canon-anisclo\/\">A\u00f1isclo<\/a><\/strong><a href=\"https:\/\/travesiapirenaica.com\/canon-anisclo\/\"> <\/a>y <strong><a href=\"https:\/\/travesiapirenaica.com\/garganta-de-escuain\/\">Escuain<\/a><\/strong>, los cerros que conforman el Macizo de <strong><a href=\"https:\/\/travesiapirenaica.com\/monte-perdido\/\">Monte Perdido<\/a><\/strong>, as\u00ed como la zona perif\u00e9rica del Parque Nacional ofrecen numerosos atractivos como para destinarles un tiempo y una visita, acercarse a su riqueza natural sin olvidarnos de la presencia de los habitantes monta\u00f1eses que desde el principio de la historia vivieron en esta zona.<\/p>\n\n\n\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link\" href=\"https:\/\/travesiapirenaica.com\/ordesa-y-monte-perdido\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ver la gu\u00eda de Ordesa<\/a><\/div>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"500\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/08\/El-rio-en-el-valle-de-Ordesa_Jes\u00fas-Alenda_Flickr_760x500.jpg\" alt=\"El rio en el valle de Ordesa \/ Foto: Jes\u00fas Alenda (v\u00eda Flickr)\" class=\"wp-image-7443\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/08\/El-rio-en-el-valle-de-Ordesa_Jes\u00fas-Alenda_Flickr_760x500.jpg 760w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/08\/El-rio-en-el-valle-de-Ordesa_Jes\u00fas-Alenda_Flickr_760x500-600x395.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/08\/El-rio-en-el-valle-de-Ordesa_Jes\u00fas-Alenda_Flickr_760x500-300x197.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/08\/El-rio-en-el-valle-de-Ordesa_Jes\u00fas-Alenda_Flickr_760x500-100x65.jpg 100w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/08\/El-rio-en-el-valle-de-Ordesa_Jes\u00fas-Alenda_Flickr_760x500-260x170.jpg 260w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/08\/El-rio-en-el-valle-de-Ordesa_Jes\u00fas-Alenda_Flickr_760x500-759x500.jpg 759w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><figcaption>El rio en el valle de Ordesa \/ Foto: Jes\u00fas Alenda (v\u00eda Flickr)<\/figcaption><\/figure>\n\n\n\n<p>El nombre de Ordesa est\u00e1 estrechamente ligado al origen de los espacios protegidos en el mundo, al influjo de rom\u00e1nticos y estudiosos, como <em>Lucien Briet<\/em>, el viajero, escritor y fot\u00f3grafo franc\u00e9s que lo visit\u00f3 por primera vez en el verano de 1901, y tantos otros que impulsaron la conservaci\u00f3n de este paraje natural, <strong>declar\u00e1ndose Parque Nacional en 1918<\/strong>, sobre una superficie inicial de 2.100 hect\u00e1reas, el valle del r\u00edo Arazas, en el t\u00e9rmino municipal de Torla.<\/p>\n\n\n\n<p>En 1982 el parque fue reclasificado y ampliado hasta las 15.600 hect\u00e1reas actuales &#8211; que incluyen el Macizo del Monte Perdido, los Valles de A\u00f1isclo y Escua\u00edn, y la cabecera del de Pineta -, siendo rebautizado como Parque Nacional de Ordesa y Monte Perdido.<\/p>\n\n\n\n<p>En 1988 fue galardonado adem\u00e1s con el Diploma Europeo a la Conservaci\u00f3n Natural, en su m\u00e1xima categor\u00eda.<\/p>\n\n\n\n<p>Entre sus valores naturales destaca ser el <strong>macizo calc\u00e1reo m\u00e1s alto de Europa \u20143.355 metros, en el Monte Perdido<\/strong>\u2014, cuyo agreste relieve ha favorecido la existencia de una enorme diversidad de ecosistemas, con una gran variedad de especies de fauna y flora, muchas de ellas end\u00e9micas del Pirineo.<\/p>\n\n\n\n<p>Cada uno de sus valles ofrecen senderos de singular belleza, desde el paso por frondosos y cerrados bosques de hayas y abetos, junto al salto del agua que produce bellas cascadas, hasta los itinerarios por los pastos alpinos de la alta monta\u00f1a sobre Ordesa, A\u00f1isclo, etc.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/travesiapirenaica.com\/parque-natural-posets-madaleta\/\">Parque Natural Poset-Maladeta<\/a><\/h2>\n\n\n\n<p>En los <strong>Pirineos Centrales<\/strong>, este Parque Natural albergan el <strong>mayor n\u00famero de cumbres que superan los tres mil metros de altitud, los glaciares m\u00e1s extensos de los Pirineos<\/strong>, cerca de un centenar de ibones o lagos de monta\u00f1a y algunas especies de flora y fauna en peligro de extinci\u00f3n. Todo ello convierte a este sector de la Cordillera Pirenaica en uno de los m\u00e1s &#8230;<\/p>\n\n\n\n<p>La incre\u00edble diversidad de paisajes son un regalo para los ojos del viajero que los contempla. Las rutas, de uno o varios d\u00edas, son tan amplias y variadas que siempre queda alg\u00fan m\u00e1gico lugar que recorrer.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Valle_Posets-Maladeta_By-Javier-Pina-CC-BY-SA-4.0_800x600.jpg\" alt=\"Valle Posets-Maladeta \/ Foto: Javier Pina [CC-BY-SA-4.0]\" class=\"wp-image-10705\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Valle_Posets-Maladeta_By-Javier-Pina-CC-BY-SA-4.0_800x600.jpg 800w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Valle_Posets-Maladeta_By-Javier-Pina-CC-BY-SA-4.0_800x600-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Valle_Posets-Maladeta_By-Javier-Pina-CC-BY-SA-4.0_800x600-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Valle_Posets-Maladeta_By-Javier-Pina-CC-BY-SA-4.0_800x600-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption>Valle Posets-Maladeta \/ Foto: Javier Pina [CC-BY-SA-4.0]<\/figcaption><\/figure>\n\n\n\n<p>Este parque natural contiene el mayor n\u00famero de cumbres que superan los tres mil metros, parajes alpinos con infinidad de ibones o lagos de monta\u00f1a como vestigio de su pasado glaciar, del que quedan muestra en el <strong>Pico Aneto, Maladeta, Posets<\/strong> y otros. Uno de los \u00faltimo para\u00edsos v\u00edrgenes para el amante de la alta monta\u00f1a pirenaica y de los ecosistemas que alberga.<\/p>\n\n\n\n<p>Por otro lado, la prolongada historia de ocupaci\u00f3n humana ha contribuido a incrementar la complejidad del territorio, en algunos casos aumentando su valor funcional y paisaj\u00edstico. la influencia humana es tan grande que pr\u00e1cticamente ninguno de los paisajes por debajo de los 2.100 metros de altitud puede explicarse sin recurrir a la forma en que el hombre ha explotado la monta\u00f1a.&nbsp;Esto hace que muchas piezas del actual mosaico paisaj\u00edstico solo pueden mantenerse tal como se conocen en la actualidad si pervive cierta presi\u00f3n humana.<\/p>\n\n\n\n<p>La orograf\u00eda y la presi\u00f3n humana son los dos hechos que condicionan que el Parque Natural Poset Maladeta sea un territorio de extremada complejidad que sirve de soporte a una fauna y una flora de gran valor.<\/p>\n\n\n\n<p>El macizo de la Maladeta se enclava en el centro geogr\u00e1fico de la cordillera, en la <strong>Alta Ribagorza<\/strong> aragonesa y re\u00fane a una buena parte de las cumbres m\u00e1s elevadas de toda la cadena.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/travesiapirenaica.com\/pirineos\/sierra-guara-somontano\/\">Parque Natural de Guara<\/a><\/h2>\n\n\n\n<p>Entre el Valle del Ebro y los Pirineos, la <strong>Sierra y Ca\u00f1ones de Guara<\/strong> constituyen un valioso enclave natural, su espectacular orograf\u00eda sorprende con sus bell\u00edsimos barrancos, ca\u00f1ones y grutas, algunas de las cuales muestran pinturas rupestres de gran valor, indicativo de su poblamiento.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Barranquismo-en-guara_1080x1350.jpg\" alt=\"Barranquismo en Guara\" class=\"wp-image-10704\"\/><figcaption>Barranquismo en Guara<\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link\" href=\"https:\/\/travesiapirenaica.com\/pirineos\/sierra-guara-somontano\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ver la gu\u00eda de Guara<\/a><\/div>\n\n\n\n<p><strong>Barrancos y ca\u00f1ones<\/strong> constituyen las principales se\u00f1as de identidad de este Parque Natural <strong>enclavado al noreste de Huesca<\/strong>. Aunque es conocido principalmente por el <strong>descenso de ca\u00f1ones<\/strong>, actividad deportiva que se populariz\u00f3 en los a\u00f1os 80, este enclave tiene otros grandes atractivos naturales, como su variedad de aves: por sus riscos y escarpados anidan el quebrantahuesos y otras rapaces.<br><\/p>\n\n\n\n<p>Guara es rico en <strong>endemismos bot\u00e1nicos<\/strong> o lo que es lo mismo, plantas y flores que \u00fanicamente se dan en el \u00e1mbito del parque a nivel mundial. Los bosques albergan una rica y variada fauna.<\/p>\n\n\n\n<p>La Sierra de Guara fue una de las zonas de Arag\u00f3n donde el hombre hizo su primera aparici\u00f3n, tal como lo demuestran las numerosas cuevas y abrigos con pinturas rupestres y <strong>restos arqueol\u00f3gicos del Paleol\u00edtico Medio<\/strong>.<\/p>\n\n\n\n<p>El parque se extiende por un total de 14 municipios en las dos vertientes, con n\u00facleos urbanos muy pintorescos, cuya recuperaci\u00f3n en los \u00faltimos a\u00f1os, despu\u00e9s del \u00e9xodo poblacional que vivieron hasta los a\u00f1os setenta, se debe, principalmente, al desarrollo de actividades deportivas y a las mejoras apoyos derivados de la declaraci\u00f3n como parque natural.<\/p>\n","protected":false},"excerpt":{"rendered":"La r\u00e9gion de Sobrarbe, situ\u00e9e au c\u0153ur des Pyr\u00e9n\u00e9es aragonaises, se caract\u00e9rise par une beaut\u00e9 unique qui se refl\u00e8te dans ses vall\u00e9es et ses montagnes.","protected":false},"author":1,"featured_media":10703,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[],"series":[],"class_list":["post-10689","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-pirineos","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/R\u00edo_Ara_by-By-Falk2-CC-BY-SA-4.0_800x600.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"hWRI5gZv36\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/sobrarbe-naturaleza\/\">Sobrarbe: la explosi\u00f3n de la naturaleza<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/sobrarbe-naturaleza\/embed\/#?secret=hWRI5gZv36\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Sobrarbe: la explosi\u00f3n de la naturaleza\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"hWRI5gZv36\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":5,"label":"Pirineos"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/R\u00edo_Ara_by-By-Falk2-CC-BY-SA-4.0_800x600.jpg",800,600,false],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":5,"name":"Pirineos","slug":"pirineos","term_group":0,"term_taxonomy_id":5,"taxonomy":"category","description":"","parent":0,"count":241,"filter":"raw","cat_ID":5,"category_count":241,"category_description":"","cat_name":"Pirineos","category_nicename":"pirineos","category_parent":0}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/R\u00edo_Ara_by-By-Falk2-CC-BY-SA-4.0_800x600.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/10689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=10689"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/10689\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/10703"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=10689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=10689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=10689"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=10689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}