{"id":11074,"date":"2017-11-15T14:41:31","date_gmt":"2017-11-15T13:41:31","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=11074"},"modified":"2021-08-12T18:08:18","modified_gmt":"2021-08-12T16:08:18","slug":"route-cycliste-francaise-etape-3-puente-la-reina-logrono","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/camino-frances-bici-etapa-3-puente-la-reina-logrono\/","title":{"rendered":"\u00c9tape 3 - Puente la Reina - Logro\u00f1o"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>Dur\u00e9e \u00e9tape<\/strong>73 Km<\/li><li><strong>Hauteur maximale<\/strong>: 665.96 m<\/li><li><strong>Hauteur minimale<\/strong>: 336.99 m<\/li><li><strong>Diff\u00e9rence d'altitude positive<\/strong>: 1197.07 m<\/li><li><strong>Diff\u00e9rence d'altitude n\u00e9gative<\/strong>: 1141.16 m<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><a rel=\"noreferrer noopener\" aria-label=\"Camino de Santiago Troisi\u00e8me \u00e9tape (ouvre dans un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/camino-de-santiago-en-velo\/\" target=\"_blank\">Le chemin de Saint-Jacques<\/a> Troisi\u00e8me \u00e9tape<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"889\" height=\"244\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Iconos-Etapa-3.jpg\" alt=\"\" class=\"wp-image-11079\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Iconos-Etapa-3.jpg 889w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Iconos-Etapa-3-600x165.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Iconos-Etapa-3-300x82.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Iconos-Etapa-3-768x211.jpg 768w\" sizes=\"auto, (max-width: 889px) 100vw, 889px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Dans cette \u00e9tape, nous remarquerons le changement d'orographie, ainsi que le changement de paysage. Malgr\u00e9 un kilom\u00e9trage plus \u00e9lev\u00e9 que les deux \u00e9tapes pr\u00e9c\u00e9dentes, cette \u00e9tape sera plus confortable \u00e0 parcourir, car il n'y a pas de grands cols de montagne et les jambes commenceront \u00e0 s'\u00e9chauffer ; cependant, plus d'un d'entre vous aura une frayeur, car le terrain se transforme parfois en casse-pattes.<\/p>\n\n\n\n<p>Cette \u00e9tape est accueillie par une vall\u00e9e que l'on suit le long du lit de l'Arga, que l'on traverse sur le c\u00e9l\u00e8bre pont roman qui donne son nom au village o\u00f9 l'on a pass\u00e9 la nuit ; Apr\u00e8s 2 km, elle se termine par une pente raide qui nous conduit au village de Ma\u00f1eru (km 5). \u00c0 la sortie de Ma\u00f1eru, nous entrons dans une autre vall\u00e9e qui porte le nom de ce village (entour\u00e9 de vignobles) et nous apercevons au sommet d'une colline le prochain village de l'itin\u00e9raire, la ville m\u00e9di\u00e9vale de Cirauqui (km 7,5).<\/p>\n\n\n\n<p>Nous descendons jusqu'\u00e0 ce que nous rencontrions une ancienne voie romaine et un pont de la m\u00eame \u00e9poque qui nous aide \u00e0 traverser la rivi\u00e8re ; apr\u00e8s avoir travers\u00e9 l'autoroute sur un autre pont, nous prenons une piste qui nous m\u00e8ne sans probl\u00e8me majeur \u00e0 la rivi\u00e8re Salado, de l\u00e0 jusqu'\u00e0 Lorca nous traversons des vignobles et juste un kilom\u00e8tre avant la ville une pente raide nous accueille \u00e0 la ville (km 13,5). Nous nous trouvons maintenant face \u00e0 un tron\u00e7on de 5 km que les travaux ont g\u00e2ch\u00e9 et qui n'a pas grand int\u00e9r\u00eat.&nbsp; <\/p>\n\n\n\n<p>Nous arrivons \u00e0 Villatuerta (km 18,5). D\u00e8s la sortie du village, nous montons jusqu'\u00e0 des r\u00e9servoirs d'eau, d'o\u00f9 nous entamons la descente \u00e0 travers des champs de vergers jusqu'\u00e0 la vall\u00e9e de la rivi\u00e8re Ega et la ville d'Estella (km 22) (connue comme la Tol\u00e8de du Nord, o\u00f9 les trois cultures ont coexist\u00e9).<\/p>\n\n\n\n<p>\u00c0 la sortie d'Estella, nous tombons sur Ayegui (une ville qui se trouve pratiquement \u00e0 l'int\u00e9rieur d'Estella mais qui a sa propre mairie), et nous nous dirigeons vers le monast\u00e8re d'Irache et sa c\u00e9l\u00e8bre fontaine \u00e0 vin (\u00e9quip\u00e9e d'une webcam), nous continuons sur une route rocailleuse jusqu'\u00e0 la ville d'Azqueta (km 27,5). Deux kilom\u00e8tres plus loin et apr\u00e8s avoir pass\u00e9 la c\u00e9l\u00e8bre fontaine mauresque, nous arrivons \u00e0 Villamayor de Monjar\u00edn (km 29).<\/p>\n\n\n\n<p>Nous continuons \u00e0 descendre par de longues pistes monotones, larges et bien rev\u00eatues, jusqu'au village de Los Arcos (km 41). \u00c0 partir de l\u00e0, le dernier tron\u00e7on de l'\u00e9tape se pr\u00e9sente, nous empruntons un chemin agricole qui nous m\u00e8ne \u00e0 Sansol (km 48), de ce point, de l'autre c\u00f4t\u00e9 de la coupure, nous pouvons voir la ville de Torres del rio (km 49) (notre prochaine destination), une fois que nous l'avons quitt\u00e9e, la route devient une mont\u00e9e et une descente sinueuses de 11,5 kilom\u00e8tres jusqu'\u00e0 ce que nous arrivions \u00e0 Viana (belle ville m\u00e9di\u00e9vale qui sera merveilleuse pour vos sens), les princes des Asturies, re\u00e7oivent \u00e9galement le titre de princes de Viana (km 60,5).<\/p>\n\n\n\n<p>Il ne reste plus qu'\u00e0 marcher sur des chemins confortables jusqu'\u00e0 ce que nous quittions la communaut\u00e9 de Navarre et entrions dans La Rioja, d'o\u00f9 nous descendons dans la vall\u00e9e de l'\u00c8bre et traversons un pont pour entrer dans la ville de Logro\u00f1o (km 73).<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h6 class=\"wp-block-heading\">Les \u00e9tapes :<\/h6>\n\n\n\n<ul class=\"wp-block-list\"><li><a rel=\"noreferrer noopener\" aria-label=\"\u00c9tape 1. Saint Jean Pied de Port - Zubiri&quot; (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/route-cycliste-francaise-etape-1-saint-jean-pied-de-port-zubiri\/\" target=\"_blank\"><strong>\u00c9tape 1. Saint Jean Pied de Port - Zubiri\".<\/strong><\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"\u00c9tape 2 : Zubiri - Puente la Reina&quot; (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/route-cycliste-francaise-etape-2-zubiri-puente-la-reina\/\" target=\"_blank\"><strong>\u00c9tape 2 : Zubiri - Puente la Reina\".<\/strong><\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"\u00c9tape 3. Puente la Reina - Logro\u00f1o&quot; (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/route-cycliste-francaise-etape-3-puente-la-reina-logrono\/\" target=\"_blank\"><strong>\u00c9tape 3. Puente la Reina - Logro\u00f1o\".<\/strong><\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"\u00c9tape 4. Logro\u00f1o - Belorado&quot; (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/route-cycliste-francaise-etape-4-logrono-belorado\/\" target=\"_blank\"><strong>\u00c9tape 4. Logro\u00f1o - Belorado\".<\/strong><\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"\u00c9tape 5 : Belorado - Hontanas&quot; (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/route-cycliste-francaise-etape-5-belorado-hontanas\/\" target=\"_blank\"><strong>\u00c9tape 5 : Belorado - Hontanas\".<\/strong><\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"\u00c9tape 6. Hontanas - Sahagun&quot; (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/route-cycliste-francaise-etape-6-hontanas-sahagun\/\" target=\"_blank\"><strong>\u00c9tape 6. Hontanas - Sahagun\".<\/strong><\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"\u00c9tape 7. Sahagun - Le\u00f3n&quot; (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/route-cycliste-francaise-etape-7-sahagun-leon\/\" target=\"_blank\"><strong>\u00c9tape 7. Sahagun - Le\u00f3n\".<\/strong><\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"\u00c9tape 8. Le\u00f3n - Rabanal del Camino&quot; (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/chemin-francais-a-velo-etape-8-leon-rabanal-del-camino\/\" target=\"_blank\"><strong>\u00c9tape 8. Le\u00f3n - Rabanal del Camino\".<\/strong><\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"\u00c9tape 9. Rabanal del camino - Ruitel\u00e1n&quot; (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/route-cycliste-francaise-etape-9-rabanal-del-camino-ruitelan\/\" target=\"_blank\"><strong>\u00c9tape 9. Rabanal del camino - Ruitel\u00e1n\".<\/strong><\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"\u00c9tape 10 : Ruitel\u00e1n - Sarria&quot; (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/voie-francaise-a-velo-etape-10-ruitelan-sarria\/\" target=\"_blank\"><strong>\u00c9tape 10 : Ruitel\u00e1n - Sarria\".<\/strong><\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"\u00c9tape 11. Sarria - Arzua&quot; (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/route-cycliste-francaise-etape-11-sarria-arzua\/\" target=\"_blank\"><strong>\u00c9tape 11. Sarria - Arzua\".<\/strong><\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"\u00c9tape 12. Arzua - Santiago de Compostela&quot; (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/la-voie-francaise-a-velo-etape-12-arzua-santiago-de-compostela\/\" target=\"_blank\"><strong>\u00c9tape 12. Arzua - Saint-Jacques-de-Compostelle\".<\/strong><\/a><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>","protected":false},"excerpt":{"rendered":"Dur\u00e9e de l'\u00e9tape : 73 Km Altitude maximale : 665,96 m Altitude minimale : 336,99 m D\u00e9nivel\u00e9 positif : 1197,07...","protected":false},"author":1,"featured_media":10985,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2945],"tags":[],"series":[],"class_list":["post-11074","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-camino-de-santiago","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Camino-Franc\u00e9s_by-jynus_-CC-BY-SA-2.5.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"Vm4BKmI84A\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/camino-frances-bici-etapa-3-puente-la-reina-logrono\/\">Etapa 3 \u2013 Puente la Reina \u2013 Logro\u00f1o<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/camino-frances-bici-etapa-3-puente-la-reina-logrono\/embed\/#?secret=Vm4BKmI84A\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Etapa 3 \u2013 Puente la Reina \u2013 Logro\u00f1o\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"Vm4BKmI84A\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":2945,"label":"Camino de Santiago"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Camino-Franc\u00e9s_by-jynus_-CC-BY-SA-2.5.jpg",800,673,false],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":2945,"name":"Camino de Santiago","slug":"camino-de-santiago","term_group":0,"term_taxonomy_id":2961,"taxonomy":"category","description":"Camino de Santiago","parent":2930,"count":60,"filter":"raw","cat_ID":2945,"category_count":60,"category_description":"Camino de Santiago","cat_name":"Camino de Santiago","category_nicename":"camino-de-santiago","category_parent":2930}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Camino-Franc\u00e9s_by-jynus_-CC-BY-SA-2.5.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/11074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=11074"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/11074\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/10985"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=11074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=11074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=11074"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=11074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}