{"id":17306,"date":"2016-06-25T18:24:50","date_gmt":"2016-06-25T16:24:50","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=17306"},"modified":"2019-06-25T18:32:04","modified_gmt":"2019-06-25T16:32:04","slug":"lac-atitlan-guatemala","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/lago-atitlan-guatemala\/","title":{"rendered":"Lac Atitl\u00e1n au Guatemala"},"content":{"rendered":"<h4 class=\"wp-block-heading\"><em>Le lac Atitl\u00e1n, situ\u00e9 dans la r\u00e9gion d'Antiplano, attire les touristes au Nicaragua depuis des d\u00e9cennies. Entour\u00e9 de volcans, de collines escarp\u00e9es et de villages o\u00f9 la culture maya coexiste avec le tourisme traditionnel, l'endroit se distingue par sa beaut\u00e9 naturelle.<\/em><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La principale ville autour du lac, d'o\u00f9 partent la plupart des visiteurs pour explorer Atitl\u00e1n, est Panajachel, o\u00f9 l'on trouve un certain nombre de possibilit\u00e9s d'h\u00e9bergement. L'Espagne propose des vols bon march\u00e9 pour Guatemala City, la capitale du Guatemala, qui se trouve \u00e0 environ 3 heures de Panajachel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Visite du lac Atitlan au Guatemala<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le lac Atitl\u00e1n est un lieu d'une beaut\u00e9 myst\u00e9rieuse. C'est un lac calme pendant la journ\u00e9e, sauf pendant la saison des vents, de novembre \u00e0 f\u00e9vrier, lorsque souffle un vent du sud-est connu sous le nom de Xocomil, qui agite la surface de l'eau \u00e0 partir de midi, rendant la navigation tr\u00e8s difficile. C'est pourquoi le matin est le meilleur moment pour naviguer ou se baigner dans le lac.Lac AtitlanLes excursions en bateau sur le lac sont une bonne option pour les voyageurs qui disposent de peu de temps. Les bateaux partent tous les matins de l'embarcad\u00e8re de la plage publique et effectuent un circuit qui comprend des arr\u00eats \u00e0 San Pedro La Laguna, Santiago Atitl\u00e1n, o\u00f9 l'on peut visiter le sanctuaire de Maxim\u00f3n, et San Antonio Palop\u00f3.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Faire du sport \u00e0 Atitl\u00e1n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le lac Atitl\u00e1n offre \u00e9galement la possibilit\u00e9 de faire du v\u00e9lo ou de la randonn\u00e9e sur ses pentes et ses coteaux. Ces activit\u00e9s peuvent \u00eatre pratiqu\u00e9es de mani\u00e8re autonome ou dans le cadre de visites guid\u00e9es en groupe. La plus courante est l'excursion d'une journ\u00e9e, qui consiste \u00e0 se rendre \u00e0 pied de Panajachel au sommet du volcan San Pedro en traversant le lac Atitlan en bateau.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sports nautiques au lac Atitlan au Nicaragua<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La plong\u00e9e est une autre attraction touristique du lac Atitl\u00e1n, d'autant plus int\u00e9ressante qu'il s'agit d'un c\u00f4ne volcanique avec des formations g\u00e9om\u00e9triques uniques et des courants d'eau chaude. C'est l'un des rares endroits au monde o\u00f9 l'on peut plonger en altitude sans avoir \u00e0 porter de combinaison \u00e9tanche. La meilleure saison de plong\u00e9e s'\u00e9tend d'octobre \u00e0 mai.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tourisme rural au lac Atitl\u00e1n au Guatemala<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Outre le lac Atitl\u00e1n, vous pouvez, depuis la ville de Panajachel, visiter la r\u00e9serve naturelle d'Atitl\u00e1n, une ancienne plantation de caf\u00e9 qui a \u00e9t\u00e9 reprise par la v\u00e9g\u00e9tation naturelle. \u00c0 pied ou \u00e0 v\u00e9lo, le sentier dure environ une heure et grimpe sur des ponts suspendus jusqu'\u00e0 une cascade, puis descend jusqu'\u00e0 une plate-forme d'o\u00f9 l'on peut observer une communaut\u00e9 locale de singes-araign\u00e9es ou pisotes. La r\u00e9serve comprend \u00e9galement un jardin d'herbes aromatiques, un enclos \u00e0 papillons et une petite plantation de caf\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il ne fait aucun doute que le lac Atitlan et ses environs sont un endroit \u00e0 consid\u00e9rer pour ceux qui aiment les promenades dans la nature, la voile et la beaut\u00e9 naturelle.<\/p>","protected":false},"excerpt":{"rendered":"Le lac Atitl\u00e1n, situ\u00e9 dans la r\u00e9gion d'El Antiplano, attire les touristes depuis des d\u00e9cennies....","protected":false},"author":1,"featured_media":17307,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_wp_convertkit_post_meta":{"form":"-1","landing_page":"0","tag":"0","restrict_content":"0"},"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[18],"tags":[],"series":[],"class_list":["post-17306","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-destinos","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2019\/06\/Lago-atitlan_by-chensiyuan-CC-BY-SA-4.0-Wikimedia-Commons_1000x750.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"pDA3uqogNV\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/lago-atitlan-guatemala\/\">Lago Atitl\u00e1n en Guatemala<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/lago-atitlan-guatemala\/embed\/#?secret=pDA3uqogNV\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Lago Atitl\u00e1n en Guatemala\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"pDA3uqogNV\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":18,"label":"Destinos"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2019\/06\/Lago-atitlan_by-chensiyuan-CC-BY-SA-4.0-Wikimedia-Commons_1000x750.jpg",1000,750,false],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":18,"name":"Destinos","slug":"destinos","term_group":0,"term_taxonomy_id":18,"taxonomy":"category","description":"","parent":0,"count":124,"filter":"raw","cat_ID":18,"category_count":124,"category_description":"","cat_name":"Destinos","category_nicename":"destinos","category_parent":0}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2019\/06\/Lago-atitlan_by-chensiyuan-CC-BY-SA-4.0-Wikimedia-Commons_1000x750.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/17306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=17306"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/17306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/17307"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=17306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=17306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=17306"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=17306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}