{"id":17351,"date":"2016-06-26T09:36:35","date_gmt":"2016-06-26T07:36:35","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=17351"},"modified":"2021-08-10T08:36:57","modified_gmt":"2021-08-10T06:36:57","slug":"tarif-du-surf","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/surf-tarifa\/","title":{"rendered":"Surf \u00e0 Tarifa"},"content":{"rendered":"<p><strong>Tarif<\/strong> est un village de p\u00eacheurs situ\u00e9 sur le d\u00e9troit de Gibraltar, qui s\u00e9pare les continents europ\u00e9en et africain. Cette r\u00e9gion poss\u00e8de d'excellentes plages de sable fin, o\u00f9 l'on peut pratiquer toutes sortes de sports pour tous les niveaux. Gr\u00e2ce \u00e0 sa situation g\u00e9ographique, Tarifa b\u00e9n\u00e9ficie de conditions de vent imbattables pour la pratique de la planche \u00e0 voile et d'autres sports nautiques, comme le fly surfing ou le kite surfing, qui sont de plus en plus \u00e0 la mode. Les vents de la M\u00e9diterran\u00e9e, ou Levante, et de l'oc\u00e9an Atlantique, ou Poniente, sont acc\u00e9l\u00e9r\u00e9s dans cette r\u00e9gion en raison de l'effet de goulot d'\u00e9tranglement naturel entre les deux continents.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><em><strong>Cat\u00e9gorie<\/strong><\/em>: fly surf<\/li><li><em><strong>Dur\u00e9e de l'accord<\/strong><\/em>En fonction de l'endurance physique. Les vents forts de Tarifa imposent une d\u00e9pense physique plus importante que la normale, de sorte que les journ\u00e9es de surf sont g\u00e9n\u00e9ralement plus courtes.<\/li><li><em><strong>Difficult\u00e9 : moyenne.<\/strong><\/em> Une exp\u00e9rience minimale du fly surf est souhaitable.<\/li><li><em><strong>Distance approximative<\/strong><\/em>Il est important de ne pas trop s'\u00e9loigner de la c\u00f4te, car les courants marins sont tr\u00e8s forts dans le d\u00e9troit de Gibraltar.<\/li><li><em><strong>Lieu<\/strong><\/em>Plage de Los Lances (Tarifa)<\/li><li><em><strong>P\u00e9riode de l'ann\u00e9e recommand\u00e9e<\/strong><\/em>: Avril<\/li><\/ul>\n\n\n\n<p>La plage de los Lances forme le bras de mer de Valdevaqueros. Lorsque le Levante souffle, au printemps, c'est le meilleur moment pour voler sur la planche de surf, en utilisant le cerf-volant comme propulsion. Les vents de cette zone permettent m\u00eame de planer dans les airs pendant quelques secondes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dans les environs<\/h2>\n\n\n\n<p>Spin out Los Porros : avec des vents d'est, c'est une zone assez s\u00fbre en raison de la protection naturelle offerte par la dune. En \u00e9t\u00e9 et pendant la semaine de P\u00e2ques, c'est un endroit tr\u00e8s fr\u00e9quent\u00e9 et plein d'ambiance. Il y a un bar de plage avec une zone prot\u00e9g\u00e9e pour prendre le soleil et deux \u00e9coles de location (Spin-out et UCPA). Fond sablonneux sans rochers.<\/p>","protected":false},"excerpt":{"rendered":"Tarifa est un village de p\u00eacheurs situ\u00e9 sur le d\u00e9troit de Gibraltar, qui s\u00e9pare le continent europ\u00e9en du...","protected":false},"author":1,"featured_media":17354,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2944],"tags":[],"series":[],"class_list":["post-17351","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-agua-espana","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2016\/06\/Surf-en-Tarifa_pxhere_1000x750.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"5dd9Ee1gJr\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/surf-tarifa\/\">Surf en Tarifa<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/surf-tarifa\/embed\/#?secret=5dd9Ee1gJr\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Surf en Tarifa\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"5dd9Ee1gJr\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":2944,"label":"Agua"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2016\/06\/Surf-en-Tarifa_pxhere_1000x750.jpg",1000,750,false],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":2944,"name":"Agua","slug":"agua-espana","term_group":0,"term_taxonomy_id":2960,"taxonomy":"category","description":"Agua en Espa\u00f1a","parent":2930,"count":2,"filter":"raw","cat_ID":2944,"category_count":2,"category_description":"Agua en Espa\u00f1a","cat_name":"Agua","category_nicename":"agua-espana","category_parent":2930}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2016\/06\/Surf-en-Tarifa_pxhere_1000x750.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/17351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=17351"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/17351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/17354"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=17351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=17351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=17351"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=17351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}