{"id":17848,"date":"2015-07-01T19:26:04","date_gmt":"2015-07-01T17:26:04","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=17848"},"modified":"2021-10-20T17:06:11","modified_gmt":"2021-10-20T15:06:11","slug":"atlas-trekking-maroc","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/trekking-atlas-marruecos\/","title":{"rendered":"Trekking au Maroc"},"content":{"rendered":"<h3 class=\"wp-block-heading\">Pr\u00e9parer son voyage   <\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Le guide fournit des informations g\u00e9n\u00e9rales sur les habitants, la culture et l'histoire de la r\u00e9gion, ainsi qu'une foule de conseils pour organiser son voyage, ce qui en fait un guide indispensable pour explorer la r\u00e9gion. <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Quand partir ? <\/li><li>Se rendre sur place et se d\u00e9placer  <\/li><li>Manger et boire <\/li><li>Bureaucratie    <\/li><li>Argent et conditions d'entr\u00e9e  <\/li><li>Guides locaux  <\/li><li>Langue et culture locales   <\/li><li>Sant\u00e9, urgences et s\u00e9curit\u00e9    <\/li><li>Ce qu'il faut apporter  <\/li><li>Cartes      <\/li><li> Informations et guides    <\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Quand partir ?<\/h4>\n\n\n\n<p>En hiver, vous devrez faire face aux chutes de neige et porter l'\u00e9quipement n\u00e9cessaire pour l'escalade et le trekking hivernaux.  <strong>Nous d\u00e9conseillons les randonn\u00e9es dans la r\u00e9gion en novembre, d\u00e9cembre et janvier \u00e0 cause de la neige.<\/strong>. Au printemps, les montagnes se r\u00e9veillent et les fleurs colorent les hauts plateaux jusqu'\u00e0 la fin de l'\u00e9t\u00e9 ; en juillet, les temp\u00e9ratures commencent \u00e0 augmenter et restent \u00e9lev\u00e9es jusqu'\u00e0 l'automne, lorsque les temp\u00eates sont moins probables. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Difficult\u00e9<\/h4>\n\n\n\n<p>Les itin\u00e9raires propos\u00e9s et recommand\u00e9s conviendront \u00e0 tout alpiniste exp\u00e9riment\u00e9. L'effet de l'altitude sur certains itin\u00e9raires et le fort soleil d'\u00e9t\u00e9 ne doivent pas \u00eatre sous-estim\u00e9s.  Les randonn\u00e9es vont de faciles (2 heures) \u00e0 tr\u00e8s difficiles (13 heures).<\/p>\n\n\n\n<p style=\"background-color:#eeeeee\" class=\"has-background\"><strong>LIRE AUSSI : <a href=\"https:\/\/travesiapirenaica.com\/fr\/trekking-afrique\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (s&#039;ouvre dans un nouvel onglet)\">Les meilleurs treks en Afrique \"<\/a>&nbsp; <\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"text-align:left\">Le Haut Atlas : les grandes montagnes du Maroc.<\/h2>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Le meilleur du trekking et de l'escalade dans les montagnes du Haut Atlas au Maroc, en Afrique du Nord. Itin\u00e9raires incluant le Jbel Toubkal, le Tazekka et l'Igdat.<\/p>\n\n\n\n<p>Les montagnes du Haut Atlas, en Afrique du Nord, offrent certaines des meilleures possibilit\u00e9s de trekking et d'escalade au monde, avec des guides hospitaliers, un temps cl\u00e9ment une grande partie de l'ann\u00e9e et un potentiel d'alpinisme presque intact, des paysages contrast\u00e9s, les villes romantiques du Maroc et ses habitants accueillants, il est facile de se laisser s\u00e9duire.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">\u00c0 ne pas manquer :<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Jbel Toubkal (4167m) - la plus haute montagne d'Afrique du Nord<\/li><li>Tazekka - couverte jusqu'au sommet de magnifiques for\u00eats de c\u00e8dres<\/li><li>Igdat - premi\u00e8re ascension lors d'un remarquable exploit d'alpinisme par Joseph Thomson en 1888<\/li><li>L'ascension de la tour rocheuse de la cath\u00e9drale <\/li><li>Tizi Mkorn - entre les gorges du Dad\u00e8s et du Todra<\/li><li>Les sommets en bordure du plateau de Tichka<\/li><li>Ouaougoulzat - une destination populaire pour le ski de montagne<\/li><li>Et surtout : la culture et le peuple berb\u00e8re, hauts en couleur. <\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">Villes et services<\/h4>\n\n\n\n<p>Marrakech, F\u00e8s, Imlil, Ouarzazate, Bou Guemez, Tinerhir et Boumalne des Dad\u00e8s<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Moyen Atlas et Haut Atlas oriental    \n<\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">Jbel Tazekka  <\/h4>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Autres itin\u00e9raires :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Jbel bou Naceur, Moussa ou Salah et Jbel bou Iblane   <\/li><li>Jbel Ayyachi et Jbel Masker     <\/li><li>Jbel Hayane      <\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Haut Atlas central    \n<\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">La cath\u00e9drale (Mastfrane)     <\/h4>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Autres itin\u00e9raires :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Jbel Msedrit     <\/li><li>Jbel Laqroun     <\/li><li>Mouriq     <\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Cha\u00eene de montagnes du Mgoun    \n<\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">Ighil Mgoun (Oumsoud)     <\/h4>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Autres itin\u00e9raires :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Tizi Mkorn     <\/li><li>Aroudane (Aioui)     <\/li><li>Jbel Azurki     <\/li><li>Ouaougoulzat     <\/li><li>Adar n' Ouchane, Jbel Anzig, Jbel Amezrika et Imejdag     <\/li><li>Jbel Tigounatine     <\/li><li>Jbel-n-Nig Oumassine et Jbel Tazoult-n-Ouguerd (Aslad)     <\/li><li>Jbel Aklim     <\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Atlas central occidental    \n<\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Autres itin\u00e9raires :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Jbel Tizoula     <\/li><li>Jbel Rhat et Tignousti     <\/li><li>Jbel Anghomer     <\/li><li>Tissili n' Warg     <\/li><li>Groupe Jbel Tastwiyt     <\/li><li>Adrar Tircht (Jbel bou Ourioul)     <\/li><li>Adrar Yagour     <\/li><li>Adrar Meltzen     <\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Massif du Toubkal    \n<\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/trekking-toubkal-maroc\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Jbel Toubkal &quot; (ouvre un nouvel onglet)\">Jbel Toubkal \"&nbsp;  <\/a><\/h4>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Autres itin\u00e9raires :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Bord du plateau de Kik     <\/li><li>Les Ouanoukrims     <\/li><li>Aksou\u00e2l     <\/li><li>Adrar n' Inghemar     <\/li><li>Angour     <\/li><li>Taska n' Zat     <\/li><li>Tazaghart     <\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Ouest de la route d'essai de\nRoute d'essai de Tizi n'    \n<\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">Igdat     <\/h4>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Autres itin\u00e9raires :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Jbel Gourza     <\/li><li>Jbel Erdouz     <\/li><li>Adrar-n-Oumzra     <\/li><li>Jbel Tabgourt     <\/li><li>Jbel Ikkis     <\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Le plateau de Tichka    \n<\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Autres itin\u00e9raires :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Amendach     <\/li><li>Takoucht     <\/li><li>Flillis     <\/li><li>Moulay Ali     <\/li><li>Imaradene (Tassiwt)     <\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Plus \u00e0 l'ouest    \n<\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Autres itin\u00e9raires :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ras Moulay Ali     <\/li><li>Mtdadene     <\/li><li>Jbel Awlim et Jbel Tinergwet     <\/li><li>Azegza     <\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"> Anti-Atlas du sud du Maroc<\/h2>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Les montagnes de l'Anti-Atlas du sud du Maroc, des paysages sauvages et accident\u00e9s. Nous aurons Tafraout et la vall\u00e9e d'Ameln comme camp principal. <\/p>\n\n\n\n<p>Les itin\u00e9raires d'aventure de 3 \u00e0 40 km incluent Jebel el Kest, Adra Mkorn et Ait Mansour, avec un trek de longue dur\u00e9e \u00e0 travers le nord-ouest de l'Anti-Atlas. <\/p>\n\n\n\n<p>Tafraout, Jebel El Kest, Ait Mansour,\nVall\u00e9e de l'Ameln, Taskra et Tanalt<\/p>\n\n\n\n<p>Les montagnes et les paysages de l\nL'Anti-Atlas s'\u00e9tend sur plus de 300 km au nord-est de l'oc\u00e9an Atlantique \u00e0 Jebel Sirwa\nde l'oc\u00e9an Atlantique au Jebel Sirwa (3305m). Ce guide couvre une zone de\nplus de 4000m\u00b2 au nord-ouest de la r\u00e9gion. L'environnement spectaculaire et\nLes environs spectaculaires et accident\u00e9s comprennent des montagnes, des ravins, des vall\u00e9es et des paysages d\u00e9sertiques, qu'il s'agisse de l'oc\u00e9an Atlantique ou de l'oc\u00e9an Atlantique.\npaysages d\u00e9sertiques, qu'il s'agisse de l'embl\u00e9matique Face de Lion surplombant la vall\u00e9e de l'Ameln et l'oasis de la vall\u00e9e de l'Ameln.\nla vall\u00e9e de l'Ameln et l'oasis de Tafraout, les profonds canyons d'Ait Mansour, les anciens villages d'Ait Mansour, les anciens villages d'Ait Mansour, les anciens villages d'Ait Mansour.\nAit Mansour, les anciens villages de la vall\u00e9e de l'Ameln ou la campagne de Tanalt.\nTanalt.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">\u00c0 ne pas manquer :<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Les montagnes du Jebel El Kest (2375 m) et de l'Adrar Mqorn (2344 m) surplombent Tafraout, <\/li><li>les formations rocheuses \u00e9tranges, alt\u00e9r\u00e9es et \u00e9rod\u00e9es, <\/li><li>les gorges profondes d'Ait Mansour et le bord de l'horizon, <\/li><li>les fleurs printani\u00e8res de l'escarpement du Tizi N'Takoucht, <\/li><li>les villages de la vall\u00e9e de l'Ameln <\/li><li>et l'insaisissable Adad Medni.<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">Villes et services<\/h4>\n\n\n\n<p>Tafraout et la vall\u00e9e de l'Ameln sont les principales bases.\nLa Kasbah Tizourgane, \u00e0 Ida Ougnidif, offre la possibilit\u00e9 d'un s\u00e9jour plus court.\nLa Kasbah Tizourgane \u00e0 Ida Ougnidif offre la possibilit\u00e9 d'un s\u00e9jour plus court.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Six zones principales sont couvertes, notamment Tafraout, Jebel El Kest, Ait Mansour, la vall\u00e9e d'Ameln, Taskra et Tanalt.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Tafraute<\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">Les Roches peintes et l'arri\u00e8re-pays de Tafraout<\/h4>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Autres itin\u00e9raires :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Trekking dans le bassin du d\u00e9sert de Ouadou<\/li><li>La trompe de l'\u00e9l\u00e9phant<\/li><li>Le chapeau de Napol\u00e9on et le combat des trois drapeaux<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Adrar Mqorn<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>En direct d'Ayerd<\/li><li>Travers\u00e9e de l'ar\u00eate sud-est<\/li><li>L'escalade de la cr\u00eate de la grille<\/li><li>Trekking aux sommets du Tahala<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Ait Mansour et le Sud<\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li>Course de cr\u00eate d'Afra<\/li><li>Promenade \u00e0 Tasselt  <\/li><li>La cr\u00eate de Tizi<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Ait Mansour<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Ligne d'horizon du Nord  <\/li><li>Bordure sud-ouest et sommets  <\/li><li>Tours du sud-est<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Vall\u00e9e de l'Ameln et Cirque d'Abdellah  <\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li>Jebel Amagdour (Route du fer \u00e0 cheval)  <\/li><li>Marche d'Ardrar Idekel<\/li><li>La cr\u00eate de Tizgut<\/li><li>Route sur la face du lion <\/li><li>Sous la face du lion<\/li><li>Trekking dans la vall\u00e9e des villages d'Ameln<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Cirque Abdellah<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>La randonn\u00e9e de la cr\u00eate d'Abdellah et le sommet de l'Azarhar<\/li><li>Pic d'Isefsas<\/li><li>La course des cr\u00eates d'Azgour  <\/li><li>Le pic Oumsnat \u00e0 travers la fen\u00eatre ouest du mur des dinosaures<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Jebel el Kest<\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">Les sommets du Jebel El Kest et de l'Ameln  <\/h4>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Autres itin\u00e9raires :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Les sommets depuis Tagdicht  <\/li><li>Tagdicht Skyline Scramble<\/li><li>Mont\u00e9e de l'ar\u00eate ouest et sommets d'Anergui<\/li><li>La course des cr\u00eates de l'ouest d'Afantinzar<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Taskra et le Nord-Est<\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">Jebel Taskra et l'horizon du Tizi<\/h4>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Autres itin\u00e9raires :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Forteresse de Tamgelochte<\/li><li>Sommet d'Amzkhssan<\/li><li>Hauteurs de Tassilla<\/li><li>L'horizon de Targa<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Tanalt et le Nord-Ouest<\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00c0 la recherche de Dark Vador<\/li><li>Circuit Dwawj<\/li><li>La vall\u00e9e de la rivi\u00e8re Tirki et la grotte du potier<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Adad Medni<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Le monde perdu d'Adad Medni<\/li><li>Marche circulaire Adad Medni Tighmert Face<\/li><li>Jebel Imzi et les gorges de l'Arbre-Dragon<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Travers\u00e9e de l'anti-Atlas du Nord-Ouest<\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li>D'Ait Baha \u00e0 Ait Mansour. Voyage d'une semaine du nord au sud de l'Anti-Atlas.  <\/li><\/ul>\n\n\n\n<p style=\"background-color:#eeeeee\" class=\"has-background\"><strong><a rel=\"noreferrer noopener\" aria-label=\"Autres lieux de trekking en Afrique &quot; (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/trekking-marruecos\/\" target=\"_blank\">Autres lieux de trekking en Afrique <\/a><\/strong><a rel=\"noreferrer noopener\" aria-label=\"Autres lieux de trekking en Afrique &quot; (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/trekking-marruecos\/\" target=\"_blank\">\"<\/a><strong> : <a href=\"https:\/\/travesiapirenaica.com\/fr\/atlas-trekking-maroc\/\">Maroc <\/a>| <a href=\"https:\/\/travesiapirenaica.com\/fr\/trekking-au-drakensberg-afrique-du-sud\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Afrique du Sud (ouvre un nouvel onglet)\">Afrique du Sud <\/a>| <a rel=\"noreferrer noopener\" aria-label=\"Tanzanie (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/kilimandjaro\/\" target=\"_blank\">Tanzanie <\/a>|  <\/strong><\/p>","protected":false},"excerpt":{"rendered":"Pr\u00e9parer son voyage Le guide fournit des informations g\u00e9n\u00e9rales sur la population, la culture et la...","protected":false},"author":1,"featured_media":16186,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2934],"tags":[],"series":[],"class_list":["post-17848","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-africa","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/06\/Ascensi\u00f3n-al-Toubkal_by-Toubkal4167_CC-BY-SA-4.0_Wikimedia-Commons_1000x750.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"fGjLvvOpuA\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/trekking-atlas-marruecos\/\">Trekking en Marruecos<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/trekking-atlas-marruecos\/embed\/#?secret=fGjLvvOpuA\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Trekking en Marruecos\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"fGjLvvOpuA\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":2934,"label":"\u00c1frica"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/06\/Ascensi\u00f3n-al-Toubkal_by-Toubkal4167_CC-BY-SA-4.0_Wikimedia-Commons_1000x750.jpg",1000,750,false],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":2934,"name":"\u00c1frica","slug":"africa","term_group":0,"term_taxonomy_id":2950,"taxonomy":"category","description":"\u00c1frica","parent":18,"count":6,"filter":"raw","cat_ID":2934,"category_count":6,"category_description":"\u00c1frica","cat_name":"\u00c1frica","category_nicename":"africa","category_parent":18}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/06\/Ascensi\u00f3n-al-Toubkal_by-Toubkal4167_CC-BY-SA-4.0_Wikimedia-Commons_1000x750.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/17848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=17848"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/17848\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/16186"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=17848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=17848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=17848"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=17848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}