{"id":19738,"date":"2015-08-13T12:08:08","date_gmt":"2015-08-13T10:08:08","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=19738"},"modified":"2019-08-13T12:49:03","modified_gmt":"2019-08-13T10:49:03","slug":"brianconnais-hautes-alpes","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/brianconnais-altos-alpes\/","title":{"rendered":"Randonn\u00e9e dans le Brian\u00e7onnais : sentiers de randonn\u00e9e dans les Alpes fran\u00e7aises pr\u00e8s de Brian\u00e7on"},"content":{"rendered":"<p>Le Brian\u00e7onnais est une \u00e9tonnante r\u00e9gion montagneuse sauvage qui regorge de pics enneig\u00e9s, de vall\u00e9es idylliques, de p\u00e2turages remplis de fleurs sauvages, de lacs alpins \u00e9tincelants, de forteresses historiques et d'un labyrinthe de sentiers tranquilles. Avec son charme rural et son climat plus doux que celui des Alpes du Nord, c'est une r\u00e9gion \u00e0 d\u00e9couvrir, et ce guide est le point de d\u00e9part id\u00e9al.<\/p>\n\n\n\n<p>Brian\u00e7on en France vous surprendra avec les vall\u00e9es \u00e0 couper le souffle de la Clar\u00e9e, de la Cerveyrette, des Ayes, de la Durance et de la Guisane, et les magnifiques paysages alpins de Vallouise et de Montgen\u00e8vre.<\/p>\n\n\n\n<figure><iframe loading=\"lazy\" width=\"100%\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/2VFRRREDpu8\" rel=\"nofollow\" allowfullscreen=\"\"><\/iframe><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Guide pratique<\/h2>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Quand partir ?<\/h3>\n\n\n\n<p>De mai \u00e0 octobre. Certains hauts sommets et cols seront enneig\u00e9s jusqu'\u00e0 la fin du mois de juin. La principale saison de randonn\u00e9e s'\u00e9tend donc de la mi-juin \u00e0 la fin du mois de septembre.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c0 ne pas manquer<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>5 vall\u00e9es \u00e9tonnantes autour de Brian\u00e7on - Clar\u00e9e, Cerveyrette, Ayes, Durance et Guisane. <\/li><li>Magnifiques paysages alpins autour de Vallouise et Montgen\u00e8vre.<\/li><li>Des sommets, des lacs et des vall\u00e9es magnifiques.<\/li><li>Forteresses historiques.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Villes et services<\/h3>\n\n\n\n<p>Brian\u00e7on, La Grave, Le Monetier-les-Bains, Montgen\u00e8vre, N\u00e9vache, Vallouise<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Les itin\u00e9raires <\/h2>\n\n\n\n<p>Les excursions permettent d'explorer les magnifiques paysages autour de Brian\u00e7on, couvrant les vall\u00e9es de la Clar\u00e9e, de la Cerveyrette, de l'Ayes, de la Durance et de la Guisane, ainsi que la r\u00e9gion de Vallouise et de Montgen\u00e8vre. <\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>VALL\u00c9E DE LA CLAR\u00c9E \/\/\/ <\/strong>Col de Dormillouse \/ Fort de l'Olive et Fort de Lenlon \/ Col des Thures \/ Lac Noir \/ Refuge de Buff\u00e8re le long de la C\u00f4te Rouge \/ Pic du Lac Blanc, Lac Laramon et Lac du Serpent \/ Col des Muandes \/ <strong>Tour du Massif des Cerces <\/strong>\/  <\/li><\/ul>\n\n\n\n<figure><iframe loading=\"lazy\" src=\"https:\/\/es.wikiloc.com\/wikiloc\/spatialArtifacts.do?event=view&amp;id=18780657&amp;measures=off&amp;title=off&amp;near=off&amp;images=off&amp;maptype=H\" rel=\"nofollow\" width=\"100%\" height=\"400\"><\/iframe><\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>MONTGEN\u00c8VRE \/\/\/ <\/strong>Le Chenaillet \/ Fort du Gondran \/ Mont Chaberton \/<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>VALL\u00c9E DE LA CERVELLE \/\/\/ <\/strong>Alp du Pied \/ Fort de la Lausette et du Peygus \/ Col de Bousson \/ Lac des Cordes \/  <\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>AYES VALLEY \/\/\/<\/strong> Lac du Plan Vallon \/ Col des Ayes \/ Fort de la Croix de Bretagne et la Grande Maye \/ Lac de l'Orceyrette \/  <\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>VALL\u00c9E DE LA DURANCE \/\/\/ <\/strong>Lac Palluel et Lac Faravel \/ Lac de Fangeas \/ Circutio alto Dormillouse \/ Cr\u00eate de la Rortie \/ La Grande Cabane \/ La Blanche \/ Chapelle St Hippolyte \/ Croix de la Salcette \/ Cime de la Condamine \/ La Croix d'Aquila \/<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>VALL\u00c9E DE LA GUISANE \/\/\/<\/strong> Brian\u00e7on et Fort des Salettes \/ La Croix de Toulouse \/ Circuit du Grand Area \/ La Grande Peyrolle par la Cr\u00eate de Peyrolle \/ Grand Lac de l'Oule \/ La Cime des Conchiers \/ Lac de Combeynot \/ Les Ar\u00eates de la Bruy\u00e8re \/ Circuit L'Aiguillette du Lauzet \/ Lacs du Glacier d'Arsine \/ Plateau d'Emparis \/<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>","protected":false},"excerpt":{"rendered":"Le Brian\u00e7onnais est une r\u00e9gion montagneuse sauvage \u00e9tonnante, avec des sommets enneig\u00e9s, des vall\u00e9es idylliques,...","protected":false},"author":1,"featured_media":19754,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"series":[],"class_list":["post-19738","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-sin-categoria","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2015\/08\/Lac_de_la_Clar\u00e9e_by-Silyba-CC-BY-SA-4.0-Wikimedia-Commons_1200x900.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"fwh3cPTtQW\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/brianconnais-altos-alpes\/\">Excursiones en el Brian\u00e7onnais: rutas de senderismo en los Alpes franceses cerca de Brian\u00e7on<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/brianconnais-altos-alpes\/embed\/#?secret=fwh3cPTtQW\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Excursiones en el Brian\u00e7onnais: rutas de senderismo en los Alpes franceses cerca de Brian\u00e7on\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"fwh3cPTtQW\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":1,"label":"Sin categor\u00eda"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2015\/08\/Lac_de_la_Clar\u00e9e_by-Silyba-CC-BY-SA-4.0-Wikimedia-Commons_1200x900-1024x768.jpg",1024,768,true],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":1,"name":"Sin categor\u00eda","slug":"sin-categoria","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":207,"filter":"raw","cat_ID":1,"category_count":207,"category_description":"","cat_name":"Sin categor\u00eda","category_nicename":"sin-categoria","category_parent":0}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2015\/08\/Lac_de_la_Clar\u00e9e_by-Silyba-CC-BY-SA-4.0-Wikimedia-Commons_1200x900.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/19738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=19738"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/19738\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/19754"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=19738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=19738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=19738"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=19738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}