{"id":20491,"date":"2015-09-17T11:55:35","date_gmt":"2015-09-17T09:55:35","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=20491"},"modified":"2019-09-24T09:36:56","modified_gmt":"2019-09-24T07:36:56","slug":"livres-ecologie-nature","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/libros-ecologia-naturaleza\/","title":{"rendered":"Les meilleurs livres sur l'\u00e9cologie et la nature"},"content":{"rendered":"<hr class=\"wp-block-separator\"\/>\n\n\n\n\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--ribbon aawp-product--sale aawp-product--css-adjust-image-large\"  data-aawp-product-asin=\"849801350X\" data-aawp-product-id=\"41751\" data-aawp-tracking-id=\"travesiapiren-21\" data-aawp-product-title=\"Elogio del agua\" data-aawp-geotargeting=\"true\">\n\n    <span class=\"aawp-product__ribbon aawp-product__ribbon--sale\">Vente<\/span>\n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\" href=\"https:\/\/www.amazon.es\/dp\/849801350X?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"\u00c0 la gloire de l&#039;eau\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/m.media-amazon.com\/images\/I\/31MZuVe4cmL.jpg\" alt=\"\u00c0 la gloire de l&#039;eau\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.es\/dp\/849801350X?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"\u00c0 la gloire de l&#039;eau\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            \u00c0 la gloire de l'eau        <\/a>\n        <div class=\"aawp-product__description\">\n                    <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n                                                        \n                            <span class=\"aawp-product__price aawp-product__price--current\">33,25 EUR<\/span>\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button--icon aawp-button--icon-black\" href=\"https:\/\/www.amazon.es\/dp\/849801350X?tag=travesiapiren-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Voir sur Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Voir sur Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n\n\n\n\n\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--ribbon aawp-product--sale aawp-product--css-adjust-image-large\"  data-aawp-product-asin=\"8449335892\" data-aawp-product-id=\"41752\" data-aawp-tracking-id=\"travesiapiren-21\" data-aawp-product-title=\"Un ge\u00f3logo en apuros  Un viaje a trav\u00e9s del tiempo y hacia lo m\u00e1s profundo de la Tierra  Para curiosos\" data-aawp-geotargeting=\"true\">\n\n    <span class=\"aawp-product__ribbon aawp-product__ribbon--sale\">Vente<\/span>\n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\" href=\"https:\/\/www.amazon.es\/dp\/8449335892?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Un g\u00e9ologue en d\u00e9tresse : un voyage \u00e0 travers le temps et dans les profondeurs de la Terre (Pour les curieux)\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/m.media-amazon.com\/images\/I\/51Ay6VKRorL.jpg\" alt=\"Un g\u00e9ologue en d\u00e9tresse : un voyage \u00e0 travers le temps et dans les profondeurs de la Terre (Pour les curieux)\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.es\/dp\/8449335892?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Un g\u00e9ologue en d\u00e9tresse : un voyage \u00e0 travers le temps et dans les profondeurs de la Terre (Pour les curieux)\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            Un g\u00e9ologue en d\u00e9tresse : un voyage \u00e0 travers le temps et dans les profondeurs de la Terre (Pour les curieux)        <\/a>\n        <div class=\"aawp-product__description\">\n                    <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n                                                        \n                            <span class=\"aawp-product__price aawp-product__price--current\">16,10 EUR<\/span>\n            \n            <a href=\"https:\/\/www.amazon.es\/gp\/prime\/?tag=travesiapiren-21\" title=\"Amazon Prime\" rel=\"nofollow noopener sponsored\" target=\"_blank\" class=\"aawp-check-prime\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/plugins\/aawp\/assets\/img\/icon-check-prime.svg\" height=\"16\" width=\"55\" alt=\"Amazon Prime\" \/><\/a>        <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button--icon aawp-button--icon-black\" href=\"https:\/\/www.amazon.es\/dp\/8449335892?tag=travesiapiren-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Voir sur Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Voir sur Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n\n\n\n\n\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--ribbon aawp-product--sale aawp-product--css-adjust-image-large\"  data-aawp-product-asin=\"8483218925\" data-aawp-product-id=\"41753\" data-aawp-tracking-id=\"travesiapiren-21\" data-aawp-product-title=\"LITICA 100 PIEDRAS SINGULARES DE TERUEL  LOSA MORA\" data-aawp-geotargeting=\"true\">\n\n    <span class=\"aawp-product__ribbon aawp-product__ribbon--sale\">Vente<\/span>\n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\" href=\"https:\/\/www.amazon.es\/dp\/8483218925?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"LITICA. 100 PIERRES UNIQUES DE TERUEL (LOSA MORA)\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/m.media-amazon.com\/images\/I\/51ngI9wy5SL.jpg\" alt=\"LITICA. 100 PIERRES UNIQUES DE TERUEL (LOSA MORA)\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.es\/dp\/8483218925?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"LITICA. 100 PIERRES UNIQUES DE TERUEL (LOSA MORA)\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            LITICA. 100 PIERRES UNIQUES DE TERUEL (LOSA MORA)        <\/a>\n        <div class=\"aawp-product__description\">\n                    <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n                                                        \n                            <span class=\"aawp-product__price aawp-product__price--current\">19,00 EUR<\/span>\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button--icon aawp-button--icon-black\" href=\"https:\/\/www.amazon.es\/dp\/8483218925?tag=travesiapiren-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Voir sur Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Voir sur Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n\n\n\n\n\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--css-adjust-image-large\"  data-aawp-product-asin=\"8480147849\" data-aawp-product-id=\"41754\" data-aawp-tracking-id=\"travesiapiren-21\" data-aawp-product-title=\"Parque Nacional de Aig\u00fcestortes i Estany de Sant Maurici Gu\u00eda geol\u00f3gica  Gu\u00edas geol\u00f3gicas de Parques Nacionales\" data-aawp-geotargeting=\"true\">\n\n    \n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\" href=\"https:\/\/www.amazon.es\/dp\/8480147849?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Parc national d&#039;Aig\u00fcestortes i Estany de Sant Maurici. Guide g\u00e9ologique (Guides g\u00e9ologiques des parcs nationaux)\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/m.media-amazon.com\/images\/I\/51+dWEs6djL.jpg\" alt=\"Parc national d&#039;Aig\u00fcestortes i Estany de Sant Maurici. Guide g\u00e9ologique (Guides g\u00e9ologiques des parcs nationaux)\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.es\/dp\/8480147849?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Parc national d&#039;Aig\u00fcestortes i Estany de Sant Maurici. Guide g\u00e9ologique (Guides g\u00e9ologiques des parcs nationaux)\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            Parc national d'Aig\u00fcestortes i Estany de Sant Maurici. Guide g\u00e9ologique (Guides g\u00e9ologiques des parcs nationaux)        <\/a>\n        <div class=\"aawp-product__description\">\n                    <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n            \n                            <span class=\"aawp-product__price aawp-product__price--current\"><\/span>\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button--icon aawp-button--icon-black\" href=\"https:\/\/www.amazon.es\/dp\/8480147849?tag=travesiapiren-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Voir sur Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Voir sur Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n\n\n\n\n\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--css-adjust-image-large\"  data-aawp-product-asin=\"8483212870\" data-aawp-product-id=\"41755\" data-aawp-tracking-id=\"travesiapiren-21\" data-aawp-product-title=\"Itinerarios geol\u00f3gicos por arag\u00f3n\" data-aawp-geotargeting=\"true\">\n\n    \n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\" href=\"https:\/\/www.amazon.es\/dp\/8483212870?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Itin\u00e9raires g\u00e9ologiques \u00e0 travers l&#039;Aragon\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/m.media-amazon.com\/images\/I\/51UmXDCN8KL.jpg\" alt=\"Itin\u00e9raires g\u00e9ologiques \u00e0 travers l&#039;Aragon\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.es\/dp\/8483212870?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Itin\u00e9raires g\u00e9ologiques \u00e0 travers l&#039;Aragon\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            Itin\u00e9raires g\u00e9ologiques \u00e0 travers l'Aragon        <\/a>\n        <div class=\"aawp-product__description\">\n                    <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n            \n                            <span class=\"aawp-product__price aawp-product__price--current\"><\/span>\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button--icon aawp-button--icon-black\" href=\"https:\/\/www.amazon.es\/dp\/8483212870?tag=travesiapiren-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Voir sur Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Voir sur Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n\n\n\n\n\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--ribbon aawp-product--sale aawp-product--css-adjust-image-large\"  data-aawp-product-asin=\"8484489205\" data-aawp-product-id=\"41756\" data-aawp-tracking-id=\"travesiapiren-21\" data-aawp-product-title=\"LOS PAISAJES GLACIARES DE BURBIA Y OTROS LUGARES DE INTER\u00c9S NATURAL DE VEGA DE ESPINAREDA  GEOGRAFIA\" data-aawp-geotargeting=\"true\">\n\n    <span class=\"aawp-product__ribbon aawp-product__ribbon--sale\">Vente<\/span>\n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\" href=\"https:\/\/www.amazon.es\/dp\/8484489205?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"LES PAYSAGES GLACIAIRES DE BURBIA ET AUTRES SITES D&#039;INT\u00c9R\u00caT NATUREL DE VEGA DE ESPINAREDA (G\u00c9OGRAPHIE)\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/m.media-amazon.com\/images\/I\/011K9M-BqBL.jpg\" alt=\"LES PAYSAGES GLACIAIRES DE BURBIA ET AUTRES SITES D&#039;INT\u00c9R\u00caT NATUREL DE VEGA DE ESPINAREDA (G\u00c9OGRAPHIE)\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.es\/dp\/8484489205?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"LES PAYSAGES GLACIAIRES DE BURBIA ET AUTRES SITES D&#039;INT\u00c9R\u00caT NATUREL DE VEGA DE ESPINAREDA (G\u00c9OGRAPHIE)\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            LES PAYSAGES GLACIAIRES DE BURBIA ET AUTRES SITES D'INT\u00c9R\u00caT NATUREL DE VEGA DE ESPINAREDA (G\u00c9OGRAPHIE)        <\/a>\n        <div class=\"aawp-product__description\">\n            <ul><\/ul>        <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n                                                        \n                            <span class=\"aawp-product__price aawp-product__price--current\">19,76 EUR<\/span>\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button--icon aawp-button--icon-black\" href=\"https:\/\/www.amazon.es\/dp\/8484489205?tag=travesiapiren-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Voir sur Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Voir sur Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n\n\n\n\n\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--css-adjust-image-large\"  data-aawp-product-asin=\"8480147865\" data-aawp-product-id=\"41757\" data-aawp-tracking-id=\"travesiapiren-21\" data-aawp-product-title=\"Parque Nacional de Los Picos de Europa  Guia Geologica\" data-aawp-geotargeting=\"true\">\n\n    \n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\" href=\"https:\/\/www.amazon.es\/dp\/8480147865?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Parc national des Pics d&#039;Europe : Guide g\u00e9ologique\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/m.media-amazon.com\/images\/I\/51NIdrV90OL.jpg\" alt=\"Parc national des Pics d&#039;Europe : Guide g\u00e9ologique\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.es\/dp\/8480147865?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Parc national des Pics d&#039;Europe : Guide g\u00e9ologique\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            Parc national des Pics d'Europe : Guide g\u00e9ologique        <\/a>\n        <div class=\"aawp-product__description\">\n                    <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n            \n                            <span class=\"aawp-product__price aawp-product__price--current\">675,00 EUR<\/span>\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button--icon aawp-button--icon-black\" href=\"https:\/\/www.amazon.es\/dp\/8480147865?tag=travesiapiren-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Voir sur Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Voir sur Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n\n\n\n\n\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--css-adjust-image-large\"  data-aawp-product-asin=\"8480148039\" data-aawp-product-id=\"41758\" data-aawp-tracking-id=\"travesiapiren-21\" data-aawp-product-title=\"Parque Nacional de la Caldera de Taburiente Gu\u00eda geol\u00f3gica  Gu\u00edas geol\u00f3gicas de Parques Nacionales\" data-aawp-geotargeting=\"true\">\n\n    \n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\" href=\"https:\/\/www.amazon.es\/dp\/8480148039?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Parc national de la Caldera de Taburiente. Guide g\u00e9ologique (Guides g\u00e9ologiques des parcs nationaux)\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/m.media-amazon.com\/images\/I\/51P4gAUE9QL.jpg\" alt=\"Parc national de la Caldera de Taburiente. Guide g\u00e9ologique (Guides g\u00e9ologiques des parcs nationaux)\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.es\/dp\/8480148039?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Parc national de la Caldera de Taburiente. Guide g\u00e9ologique (Guides g\u00e9ologiques des parcs nationaux)\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            Parc national de la Caldera de Taburiente. Guide g\u00e9ologique (Guides g\u00e9ologiques des parcs nationaux)        <\/a>\n        <div class=\"aawp-product__description\">\n                    <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n            \n                            <span class=\"aawp-product__price aawp-product__price--current\"><\/span>\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button--icon aawp-button--icon-black\" href=\"https:\/\/www.amazon.es\/dp\/8480148039?tag=travesiapiren-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Voir sur Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Voir sur Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n\n\n\n\n\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--ribbon aawp-product--sale aawp-product--css-adjust-image-large\"  data-aawp-product-asin=\"8495744937\" data-aawp-product-id=\"41759\" data-aawp-tracking-id=\"travesiapiren-21\" data-aawp-product-title=\"El cambio clim\u00e1tico en los glaciares de los Pirineos   la agon\u00eda de las masas de hielo en el Parque Natural Posets-Maladeta\" data-aawp-geotargeting=\"true\">\n\n    <span class=\"aawp-product__ribbon aawp-product__ribbon--sale\">Vente<\/span>\n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\" href=\"https:\/\/www.amazon.es\/dp\/8495744937?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Le changement climatique dans les glaciers des Pyr\u00e9n\u00e9es : l&#039;agonie des masses de glace dans le Parc Naturel des Posets-Maladeta.\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/m.media-amazon.com\/images\/I\/51sHMsZdBkL.jpg\" alt=\"Le changement climatique dans les glaciers des Pyr\u00e9n\u00e9es : l&#039;agonie des masses de glace dans le Parc Naturel des Posets-Maladeta.\"  \/>\n        <\/a>\n\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.es\/dp\/8495744937?tag=travesiapiren-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Le changement climatique dans les glaciers des Pyr\u00e9n\u00e9es : l&#039;agonie des masses de glace dans le Parc Naturel des Posets-Maladeta.\" rel=\"nofollow noopener sponsored\" target=\"_blank\">\n            Le changement climatique dans les glaciers des Pyr\u00e9n\u00e9es : l'agonie des masses de glace dans le Parc Naturel des Posets-Maladeta.        <\/a>\n        <div class=\"aawp-product__description\">\n                    <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n                                                        \n                            <span class=\"aawp-product__price aawp-product__price--current\">29,50 EUR<\/span>\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button--icon aawp-button--icon-black\" href=\"https:\/\/www.amazon.es\/dp\/8495744937?tag=travesiapiren-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Voir sur Amazon\" target=\"_blank\" rel=\"nofollow noopener sponsored\">Voir sur Amazon<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n\n\n\n\n<hr class=\"wp-block-separator\"\/>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"series":[],"class_list":["post-20491","post","type-post","status-publish","format-image","hentry","category-sin-categoria","post_format-post-format-image"],"episode_featured_image":false,"episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"iA8ZnJC4aS\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/libros-ecologia-naturaleza\/\">Los mejores libros sobre ecolog\u00eda y naturaleza<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/libros-ecologia-naturaleza\/embed\/#?secret=iA8ZnJC4aS\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Los mejores libros sobre ecolog\u00eda y naturaleza\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"iA8ZnJC4aS\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":1,"label":"Sin categor\u00eda"}]},"featured_image_src_large":false,"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":1,"name":"Sin categor\u00eda","slug":"sin-categoria","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":207,"filter":"raw","cat_ID":1,"category_count":207,"category_description":"","cat_name":"Sin categor\u00eda","category_nicename":"sin-categoria","category_parent":0}],"tag_info":false,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/20491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=20491"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/20491\/revisions"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=20491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=20491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=20491"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=20491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}