{"id":20873,"date":"2017-09-30T17:10:15","date_gmt":"2017-09-30T15:10:15","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=20873"},"modified":"2024-06-28T12:50:29","modified_gmt":"2024-06-28T10:50:29","slug":"pena-oroel","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/pena-oroel\/","title":{"rendered":"Itin\u00e9raire vers Pe\u00f1a Oroel"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Les&nbsp;<strong>Pe\u00f1a Oroel&nbsp;<\/strong>est l'un de ces lieux magiques et l\u00e9gendaires. On dit que les feux allum\u00e9s \u00e0 son sommet ont \u00e9t\u00e9 le signal du d\u00e9but de la Reconqu\u00eate et qu'il est l'un des sommets du triangle magique qui forme, avec San Adri\u00e1n de Sasabe et&nbsp;<strong><a rel=\"noreferrer noopener\" aria-label=\" (s&#039;ouvre dans un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/san-juan-de-la-pena\/\" target=\"_blank\">San Juan de la Pe\u00f1a<\/a><\/strong>. Et bien s\u00fbr, une visite et un must pour les habitants et les visiteurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si cette montagne vous a d\u00e9j\u00e0 intrigu\u00e9 et que vous vous \u00eates demand\u00e9 si vous pouviez l'escalader, cette randonn\u00e9e est parfaite pour vous mettre sur la voie et voir comment vous vous sentez. Il s'agit d'une randonn\u00e9e familiale qui pourrait \u00eatre le d\u00e9but d'une longue amiti\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il s'agit d'un itin\u00e9raire de base dans les Pyr\u00e9n\u00e9es, m\u00eame si, \u00e0 proprement parler, Pe\u00f1a Oroel ne fait pas partie des Pyr\u00e9n\u00e9es, mais est nich\u00e9e dans la cha\u00eene de montagnes ext\u00e9rieure. Cependant, si le jour est clair, la vue sur la cha\u00eene de montagnes des Pyr\u00e9n\u00e9es est spectaculaire.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Comment s'y rendre<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L'acc\u00e8s est tr\u00e8s facile : \u00e0 partir de\u00a0<strong>Jaca\u00a0<\/strong>prendre la route A-1205 et, avant d'arriver \u00e0 Bernu\u00e9s, vous verrez une bifurcation indiquant le Parador de Oroel. Nous voil\u00e0 \u00e0 neuf kilom\u00e8tres de Jaca. Nous empruntons une belle route \u00e9troite qui nous m\u00e8ne au parking du Parador de Oroel. <strong>Parador<\/strong>o\u00f9 nous avons laiss\u00e9 la voiture. <\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Itin\u00e9raire : Ascension de la Pe\u00f1a Oroel<\/h2>\n\n\n\n<figure><iframe loading=\"lazy\" src=\"https:\/\/es.wikiloc.com\/wikiloc\/spatialArtifacts.do?event=view&amp;id=38886117&amp;measures=off&amp;title=off&amp;near=off&amp;images=off&amp;maptype=H\" rel=\"nofollow\" target=\"_blank\" width=\"100%\" height=\"400\"><\/iframe><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">L'itin\u00e9raire est facile \u00e0 suivre : depuis le parking, en face de la fontaine en pierre, vous verrez un sentier et un panneau indiquant l'itin\u00e9raire que nous allons suivre, marqu\u00e9 PR-HU 66 et S7.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous commen\u00e7ons notre parcours en serpentant dans une for\u00eat de pins, de sapins et de h\u00eatres, que nous traversons et laissons derri\u00e8re nous. Ensuite, le chemin s'\u00e9claircit et nous atteignons les anciennes fosses \u00e0 neige. Vous pourrez voir les constructions qui servaient autrefois \u00e0 stocker la neige et qui permettaient d'avoir de la glace en \u00e9t\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous sommes d\u00e9j\u00e0 dans la&nbsp;<strong>Collado de las Neveras<\/strong>Vous savez d'o\u00f9 vient son nom. D'ici, on a une belle vue en direction du sud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous continuons. Nous arrivons \u00e0 l'embranchement de la&nbsp;<strong>ermitage de la Vierge de la Grotte<\/strong>Un lieu qui vaut \u00e9galement la peine d'\u00eatre visit\u00e9. Il a sa propre tradition l\u00e9gendaire, selon laquelle un berger, surpris que chaque jour une de ses brebis disparaisse pour revenir \u00e0 la derni\u00e8re minute, d\u00e9cide un jour de la suivre et d\u00e9couvre une grotte avec un objet sacr\u00e9, l'image de la vierge.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notre ascension se termine au sommet du<strong>&nbsp;Pe\u00f1a Oroel<\/strong>&nbsp;(1.770 m). En plus des vues impressionnantes sur les Pyr\u00e9n\u00e9es que les panneaux d'information vous expliquent, vous pourrez voir les&nbsp;<strong>Croix d'Oroel<\/strong>en fer et d'une hauteur de pr\u00e8s de neuf m\u00e8tres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Profitez de la vue sur la vall\u00e9e d'Aragon, sur une grande partie des Pyr\u00e9n\u00e9es et, bien s\u00fbr, sur Jaca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au total, la promenade nous a pris un peu plus de deux heures et demie (aller et retour), une promenade douce - que l'on peut faire en raquettes si le chemin est enneig\u00e9 -, qui culmine dans un paysage qui, peu importe le nombre de fois qu'on le visite, ne cesse jamais d'\u00eatre beau.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>","protected":false},"excerpt":{"rendered":"Pe\u00f1a Oroel est l'un de ces lieux magiques et l\u00e9gendaires. On dit que les feux...","protected":false},"author":1,"featured_media":20877,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_wp_convertkit_post_meta":{"form":"-1","landing_page":"","tag":"0","restrict_content":"0"},"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[3158],"series":[],"class_list":["post-20873","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-pirineos","tag-rutas-pirineo-aragones","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/09\/Pe\u00f1a-Oroel_by-Cherubino-CC-BY-SA-3.0-Wikimedia-Commons_1200x900.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"pfDYDM2e5M\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/pena-oroel\/\">Ruta a la Pe\u00f1a Oroel<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/pena-oroel\/embed\/#?secret=pfDYDM2e5M\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Ruta a la Pe\u00f1a Oroel\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"pfDYDM2e5M\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":5,"label":"Pirineos"}],"post_tag":[{"value":3158,"label":"Rutas Pirineo aragon\u00e9s"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/09\/Pe\u00f1a-Oroel_by-Cherubino-CC-BY-SA-3.0-Wikimedia-Commons_1200x900-1024x768.jpg",1024,768,true],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":5,"name":"Pirineos","slug":"pirineos","term_group":0,"term_taxonomy_id":5,"taxonomy":"category","description":"","parent":0,"count":242,"filter":"raw","cat_ID":5,"category_count":242,"category_description":"","cat_name":"Pirineos","category_nicename":"pirineos","category_parent":0}],"tag_info":[{"term_id":3158,"name":"Rutas Pirineo aragon\u00e9s","slug":"rutas-pirineo-aragones","term_group":0,"term_taxonomy_id":3174,"taxonomy":"post_tag","description":"","parent":0,"count":28,"filter":"raw"}],"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/09\/Pe\u00f1a-Oroel_by-Cherubino-CC-BY-SA-3.0-Wikimedia-Commons_1200x900.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/20873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=20873"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/20873\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/20877"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=20873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=20873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=20873"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=20873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}