{"id":20929,"date":"2017-10-03T09:55:17","date_gmt":"2017-10-03T07:55:17","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=20929"},"modified":"2021-08-12T17:31:48","modified_gmt":"2021-08-12T15:31:48","slug":"ski-de-fond-pyrenees","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/esqui-de-fondo-pirineo\/","title":{"rendered":"Les meilleurs endroits pour faire du ski de fond dans les Pyr\u00e9n\u00e9es"},"content":{"rendered":"<p>Les d\u00e9fenseurs de la<strong> Ski nordique<\/strong> ne se lassent pas d'en vanter les m\u00e9rites. C'est une forme de ski beaucoup plus \u00e9conomique que le ski alpin, tant la location du mat\u00e9riel que l'acc\u00e8s aux pistes sont moins chers. Il n'y a pas de remont\u00e9es m\u00e9caniques ni de file d'attente. Vous \u00eates libre de choisir votre propre itin\u00e9raire \u00e0 travers les for\u00eats, les prairies... et quand vous voulez vous arr\u00eater, vous le faites. Vous pouvez le pratiquer sur des pistes balis\u00e9es ou en dehors (modalit\u00e9&nbsp;<strong>arri\u00e8re-pays<\/strong>). La plupart des \u00e9coles de ski nordique dans les stations organiseront des itin\u00e9raires pour vous, si vous le souhaitez.<\/p>\n\n\n\n<p>Saviez-vous que le ski nordique est aussi l'un des sports les plus complets ? Le ski nordique fait travailler tous les muscles du corps, tout comme la natation. Contrairement au ski alpin, le ski nordique fait travailler le corps sans contrainte et sans impact sur les articulations, ce qui r\u00e9duit consid\u00e9rablement le risque de blessure. La quasi-absence de pentes et le fait que le talon ne soit pas attach\u00e9 contribuent \u00e9galement au fait que les blessures sont moins fr\u00e9quentes.<\/p>\n\n\n\n<p>Si vous n'avez jamais pratiqu\u00e9 le ski nordique, il n'est jamais trop tard pour commencer. L'apprentissage est relativement facile, vous pouvez le faire vous-m\u00eame. Il existe deux styles, le&nbsp;<strong>classique&nbsp;<\/strong>dans lequel les skis glissent sur des traces ou des pistes. Ce style est recommand\u00e9 si vous d\u00e9butez, car vous devrez vous concentrer sur votre \u00e9quilibre. Le deuxi\u00e8me style est le <strong>patineur<\/strong>Vous avancez sur des skis, vous gagnez en vitesse et c'est un mode qui demande un peu plus d'entra\u00eenement.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Ski de fond dans les Pyr\u00e9n\u00e9es aragonaises<\/h2>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Dans les Pyr\u00e9n\u00e9es aragonaises, il y a<strong> 9 espaces<\/strong> o\u00f9 l'on peut pratiquer le ski nordique et un total de 138 kilom\u00e8tres de pistes. Il existe des \u00e9coles dans chaque station et vous pouvez louer du mat\u00e9riel. Il ne vous reste plus qu'\u00e0 choisir le paysage ou l'endroit pour faire du ski. <\/p>\n\n\n\n<p>Le ski de fond est le sport d'endurance hivernal par excellence.&nbsp;<strong>Il se pratique sur des terrains plats ou l\u00e9g\u00e8rement inclin\u00e9s.<\/strong>&nbsp;et les Pyr\u00e9n\u00e9es aragonaises offrent un grand nombre de pistes o\u00f9 l'on peut le pratiquer, comme le circuit de Candanch\u00fa, ceux de Linza, Lizara et Gabardito - dans le Parque Natural de los Valles Occidentales, dans la r\u00e9gion de Hecho et Ans\u00f3 - ou encore le&nbsp;<strong>station transfrontali\u00e8re de&nbsp;<strong>Somport&nbsp;<\/strong><\/strong>-Tout pr\u00e8s d'Ast\u00fan et de Candanch\u00fa, dans le col du m\u00eame nom.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/la-vallee-de-la-tena-en-trois-jours\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Valle de Tena (ouvre un nouvel onglet)\">Vall\u00e9e de la Tena<\/a><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Spa Panticosa<\/strong>. Dans la vall\u00e9e de Tena (3 pistes et 5,5 km) \u00e0 une altitude de 1 636 m, autour du lac d'origine glaciaire.<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/connaitre-les-moindres-details-de-la-vallee-daragon-et-de-la-jaca\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Valle de Arag\u00f3n (ouvre un nouvel onglet)\">Vall\u00e9e d'Aragon<\/a><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a rel=\"noreferrer noopener\" aria-label=\"Candanch\u00fa (ouvre un nouvel onglet)\" href=\"https:\/\/travesiapirenaica.com\/fr\/candanchu\/\" target=\"_blank\">Candanch\u00fa<\/a><\/strong>. Dans la vall\u00e9e d'Aragon (3 pistes et 15 km skiables).   <strong><strong>Candanch\u00fa<\/strong>&nbsp;a trois circuits de fond,<\/strong>&nbsp;dans la zone de Rinconada, de 2,5 km, 5 km et 7,5 km, adapt\u00e9es aux d\u00e9butants et aux experts, qui traversent des lieux d'une grande beaut\u00e9, comme la Ciudad de Piedra ou la vall\u00e9e de Puerto Viejo, en bordure de la partie fran\u00e7aise du Parc national des Pyr\u00e9n\u00e9es. Le prix d'une journ\u00e9e de ski est de 8 euros. <\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Somport<\/strong>(4 pistes et 35 km), accessible depuis les versants espagnol et fran\u00e7ais, reliant les vall\u00e9es d'Aspe et d'Aragon.   <strong>Somport<\/strong>&nbsp;est un autre endroit propice \u00e0 la pratique du ski de fond. On y acc\u00e8de en traversant la France par le port du m\u00eame nom, \u00e0 un kilom\u00e8tre de la douane. La station offre un itin\u00e9raire vari\u00e9 \u00e0 travers les&nbsp;<strong>les clairi\u00e8res et les sous-bois de la Haute Vall\u00e9e d'Aspe,<\/strong>&nbsp;\u00e0 1 600 m\u00e8tres d'altitude. Sa visite est vivement recommand\u00e9e, m\u00eame si vous ne pratiquez pas le ski. <\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Ast\u00fan<\/strong>. La station de ski d'Ast\u00fan dispose d'une piste de ski de fond, situ\u00e9e dans la zone d'Entre Lagos, d'une longueur de 4 kilom\u00e8tres. <\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/ordesa-et-monte-perdido\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Parque Nacional de Ordesa y Monte Perdido (ouvre un nouvel onglet)\">Parc national d'Ordesa et de Monte Perdido<\/a><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Fanlo<\/strong>Vall\u00e9e de Vi\u00f3 (8 pistes et 35 km skiables). Il s'agit du domaine nordique le plus \u00e9lev\u00e9 des Pyr\u00e9n\u00e9es aragonaises. <\/li><li><strong><a href=\"https:\/\/travesiapirenaica.com\/fr\/vallee-de-pineta\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (s&#039;ouvre dans un nouvel onglet)\">Pineta<\/a><\/strong>Dans la vall\u00e9e de Pineta, \u00e0 10 kilom\u00e8tres de Bielsa, se trouve ce circuit de ski de fond et de ski nordique (4 circuits, 25 km skiables).<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/parc-naturel-des-vallees-occidentales\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Parc naturel de Valles Occidentales (s&#039;ouvre dans un nouvel onglet)\">Parc naturel des vall\u00e9es occidentales<\/a><\/h4>\n\n\n\n<p>Dans le cadre de la&nbsp;<strong>Parc naturel des vall\u00e9es occidentales<\/strong>&nbsp;vous pouvez skier \u00e0 Linza, Lizara et Gabardito,&nbsp;<strong>entre for\u00eats de pins, for\u00eats de h\u00eatres et prairies naturelles. A l'heure actuelle&nbsp;<strong>Linza<\/strong><\/strong>&nbsp;Trois circuits de longue dur\u00e9e sont propos\u00e9s. Le plus long monte jusqu'au ravin de Petrachena, se poursuit jusqu'\u00e0 1 460 m d'altitude, d'o\u00f9 l'on jouit d'une vue spectaculaire, et revient le long d'une cascade de l'autre c\u00f4t\u00e9 du ravin jusqu'au point de d\u00e9part, dans la zone du refuge - qui peut accueillir 50 personnes et dispose d'un bar et d'un service de restauration - et de l'aire de luge. Le prix d'une journ\u00e9e de ski \u00e0 Linza est de 10 euros. Il est \u00e9galement possible de faire de la raquette \u00e0 neige pour 10 euros\/jour, ou de louer un taxi-neige, un v\u00e9hicule particulier de dix places, pour faire le tour de la r\u00e9gion.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Linza<\/strong>Vall\u00e9e de l'Ans\u00f3 (4 pistes et 7,5 km skiables). <\/li><li><strong>Lizara<\/strong>Vall\u00e9e d'Arag\u00fces del Puerto (4 pistes et 5 km skiables). <\/li><li><strong>Oza-Gabardito<\/strong>Vall\u00e9e de Hecho. Pentes de Gabardito et La Espata, \u00e0 Selva de Oza.<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/benasque\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (s&#039;ouvre dans un nouvel onglet)\">Benasque<\/a><\/h4>\n\n\n\n<p><strong>Llanos del Hospital<\/strong>\u00e0 Benasque, dans le parc naturel des Posets-Maladeta (3 pistes, 30 km skiables). Aux Llanos del Hospital, \u00e0 Benasque, vous disposez de 30 km de pistes de ski de fond balis\u00e9es, en trois circuits, \u00e0 une altitude comprise entre 1 750 et 1 940 m, ainsi que d'autres itin\u00e9raires pour le ski de fond et les raquettes, au pied de la montagne des Posets-Maladeta.&nbsp;<strong>Aneto et Maladeta.<\/strong>  <\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>","protected":false},"excerpt":{"rendered":"Les partisans du ski nordique ne se lassent pas de d\u00e9fendre ses avantages. Il s'agit d'une modalit\u00e9...","protected":false},"author":1,"featured_media":11542,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2925],"tags":[],"series":[],"class_list":["post-20929","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-nieve","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Preparaci\u00f3n-f\u00edsica-para-el-esqu\u00ed-de-fondo_-by-phillip-belena_800x600.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"aeUM8n5WXX\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/esqui-de-fondo-pirineo\/\">Los mejores lugares para practicar esqu\u00ed de fondo en el Pirineo<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/esqui-de-fondo-pirineo\/embed\/#?secret=aeUM8n5WXX\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Los mejores lugares para practicar esqu\u00ed de fondo en el Pirineo\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"aeUM8n5WXX\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":2925,"label":"Nieve"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Preparaci\u00f3n-f\u00edsica-para-el-esqu\u00ed-de-fondo_-by-phillip-belena_800x600.jpg",800,600,false],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":2925,"name":"Nieve","slug":"nieve","term_group":0,"term_taxonomy_id":2941,"taxonomy":"category","description":"Nieve en los Pirineos","parent":5,"count":6,"filter":"raw","cat_ID":2925,"category_count":6,"category_description":"Nieve en los Pirineos","cat_name":"Nieve","category_nicename":"nieve","category_parent":5}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Preparaci\u00f3n-f\u00edsica-para-el-esqu\u00ed-de-fondo_-by-phillip-belena_800x600.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/20929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=20929"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/20929\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/11542"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=20929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=20929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=20929"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=20929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}