{"id":22569,"date":"2015-06-08T10:21:00","date_gmt":"2015-06-08T08:21:00","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=22569"},"modified":"2020-06-08T10:24:22","modified_gmt":"2020-06-08T08:24:22","slug":"grotte-de-la-verna","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/grotte-de-la-verna\/","title":{"rendered":"Salle La Verna"},"content":{"rendered":"<p>Depuis 2010, le public peut visiter les impressionnantes grottes qui composent la Sala La Verna, situ\u00e9e dans la ville basque fran\u00e7aise de Saint-Engrace, en Aquitaine, en France. Elles ont \u00e9t\u00e9 d\u00e9couvertes en 1953 et constituent le plus grand espace souterrain ouvert aux visiteurs aujourd'hui.<\/p>\n\n\n\n<p>Cette merveille de la nature, au c\u0153ur du massif calcaire de la Piedra de San Mart\u00edn, propose une visite guid\u00e9e, avec un parcours s\u00e9curis\u00e9 de 800 m\u00e8tres, adapt\u00e9 aux personnes handicap\u00e9es.<\/p>\n\n\n\n<p>Pour profiter au mieux de la visite, il est recommand\u00e9 d'utiliser des jumelles. En outre, les temp\u00e9ratures polaires qui r\u00e8gnent \u00e0 l'int\u00e9rieur de la salle imposent de porter des v\u00eatements chauds et des chaussures adapt\u00e9es \u00e0 la randonn\u00e9e. La temp\u00e9rature se situe entre 6 et 8 degr\u00e9s Celsius, selon le parcours.<\/p>\n\n\n\n<p>Les visiteurs de la Sala La Verna re\u00e7oivent un casque. S'il s'agit de visiteurs \u00e9trangers, ils disposeront d'un audioguide en plusieurs langues, afin de ne rien manquer des informations int\u00e9ressantes fournies par les guides.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Itin\u00e9raires<\/h2>\n\n\n\n<p>Les visiteurs de la Sala La Verna peuvent suivre plusieurs itin\u00e9raires, chacun d'entre eux \u00e9tant adapt\u00e9 \u00e0 des besoins et \u00e0 des go\u00fbts diff\u00e9rents. Le premier parcours, appel\u00e9 \"D\u00e9couverte\", est le moins difficile et est adapt\u00e9 aux personnes ayant des besoins particuliers.<\/p>\n\n\n\n<p>Ensuite, vous pouvez partir \u00e0 la d\u00e9couverte de la rivi\u00e8re. Cet itin\u00e9raire requiert un \u00e2ge minimum de 7 ans. Vous empruntez un tunnel de 660 m\u00e8tres de long \u00e0 l'entr\u00e9e de la grotte, avant l'acc\u00e8s proprement dit \u00e0 La Verna.<\/p>\n\n\n\n<p>Un long escalier taill\u00e9 dans la roche m\u00e8ne au d\u00e9versoir de la rivi\u00e8re et au barrage. De l\u00e0, on peut profiter d'une vue panoramique sur la Sala et la galerie o\u00f9 sont arriv\u00e9s les d\u00e9couvreurs. Cet itin\u00e9raire peut \u00eatre r\u00e9alis\u00e9 en un peu plus de deux heures.<\/p>\n\n\n\n<p>Le parcours \"Chevalier\", d'une dur\u00e9e d'environ trois heures, est une randonn\u00e9e de niveau moyen et requiert un \u00e2ge minimum de 12 ans. Cette randonn\u00e9e se d\u00e9roule hors des sentiers, en suivant le cours de la rivi\u00e8re jusqu'\u00e0 la salle Chevalier.<\/p>\n\n\n\n<p>Le parcours \"Ad\u00e9lie\" est une randonn\u00e9e de cinq heures, recommand\u00e9e aux randonneurs exp\u00e9riment\u00e9s. L'\u00e2ge minimum d'acc\u00e8s est de 12 ans. Il s'agit d'une sortie sp\u00e9l\u00e9ologique sportive. Elle se d\u00e9roule \u00e9galement en dehors des sentiers, en suivant la rivi\u00e8re jusqu'\u00e0 la salle Ad\u00e9lie. Il est recommand\u00e9 d'apporter de la nourriture pour la promenade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Plus long<\/h2>\n\n\n\n<p>Le parcours \"Aranzadi\" dure \u00e9galement cinq heures. Il s'agit d'une excursion sp\u00e9l\u00e9ologique sportive et technique, de niveau sportif. L'\u00e2ge minimum des randonneurs est de 14 ans. L'acc\u00e8s \u00e0 la galerie Aranzadi se fait par une mont\u00e9e de 80 m\u00e8tres. Il est n\u00e9cessaire d'emporter de la nourriture pour le parcours.<\/p>\n\n\n\n<p>L'itin\u00e9raire \"Las Grandes Salas\" n\u00e9cessite une journ\u00e9e enti\u00e8re de visite, puisqu'il dure 8 heures. Pour visiter Aranzadi et Chevalier en une journ\u00e9e, les visiteurs doivent \u00eatre \u00e2g\u00e9s d'au moins 16 ans pour profiter de ce m\u00e9lange de sport et d'aventure. Il est \u00e9galement n\u00e9cessaire d'apporter des provisions.<\/p>\n\n\n\n<p>L'autre visite d'une journ\u00e9e est la Sala L\u00e9pineux, qui est une visite sportive experte. L'\u00e2ge minimum requis est de 16 ans. Il s'agit d'une excursion sp\u00e9l\u00e9ologique sportive et technique \u00e0 la base de la Sima L\u00e9pineux, l'entr\u00e9e historique de la Sima de La Piedra de San Mart\u00edn. Le repas est obligatoire.<\/p>","protected":false},"excerpt":{"rendered":"Cette merveille de la nature, au c\u0153ur du massif calcaire de la Piedra de San Mart\u00edn, fait l'objet d'une visite guid\u00e9e, avec un parcours s\u00e9curis\u00e9 de 800 m\u00e8tres.","protected":false},"author":1,"featured_media":22570,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[],"series":[],"class_list":["post-22569","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-pirineos","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/06\/cc-La_Verna_waterfall_By-Camuspeleo-CC-BY-SA-4.0-httpscreativecommons.orglicensesby-sa4.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"U4WfYD3DwQ\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/grotte-de-la-verna\/\">Sala de La Verna<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/grotte-de-la-verna\/embed\/#?secret=U4WfYD3DwQ\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Sala de La Verna\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"U4WfYD3DwQ\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":5,"label":"Pirineos"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/06\/cc-La_Verna_waterfall_By-Camuspeleo-CC-BY-SA-4.0-httpscreativecommons.orglicensesby-sa4-1024x683.jpg",1024,683,true],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":5,"name":"Pirineos","slug":"pirineos","term_group":0,"term_taxonomy_id":5,"taxonomy":"category","description":"","parent":0,"count":241,"filter":"raw","cat_ID":5,"category_count":241,"category_description":"","cat_name":"Pirineos","category_nicename":"pirineos","category_parent":0}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/06\/cc-La_Verna_waterfall_By-Camuspeleo-CC-BY-SA-4.0-httpscreativecommons.orglicensesby-sa4.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/22569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=22569"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/22569\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/22570"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=22569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=22569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=22569"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=22569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}