{"id":23178,"date":"2020-10-30T11:40:31","date_gmt":"2020-10-30T10:40:31","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=23178"},"modified":"2021-08-12T16:57:14","modified_gmt":"2021-08-12T14:57:14","slug":"carlos-suarez","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/carlos-suarez\/","title":{"rendered":"Carlos Su\u00e1rez : le charme du vide"},"content":{"rendered":"<p>Carlos Su\u00e1rez (Madrid, 1972) est un exemple de l'extr\u00eame, de l'audace, du charme que peut procurer le fait de se laisser tomber d'une hauteur de plusieurs m\u00e8tres. Un amoureux du vide. L'alpiniste madril\u00e8ne a laiss\u00e9 un enregistrement audiovisuel de plusieurs de ses exploits, que nous passerons en revue dans ce texte.<\/p>\n\n\n\n<p>Outre les films, son exp\u00e9rience a \u00e9t\u00e9 refl\u00e9t\u00e9e dans plusieurs articles publi\u00e9s par des m\u00e9dias sp\u00e9cialis\u00e9s et il a pr\u00e9sent\u00e9 des livres tels que <em><a href=\"https:\/\/amzn.to\/37VzhiU\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Mourir pour le sommet<\/a><\/em>, <em>Solo. Techniques et exp\u00e9riences  <\/em>y <em><a href=\"https:\/\/amzn.to\/3oHtLX2\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Citations alpines<\/a>.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><em>Obsession<\/em> (2019)<\/h2>\n\n\n\n<p>L'examen commence par le mat\u00e9riel le plus r\u00e9cent, <em>Obsession<\/em>Su\u00e1rez a r\u00e9alis\u00e9 un court m\u00e9trage sur sa tentative d'escalade du Cerro Torre en Patagonie, Argentine, en plein hiver. Cette r\u00e9gion, situ\u00e9e au sud du continent am\u00e9ricain, a \u00e9t\u00e9 visit\u00e9e \u00e0 de nombreuses reprises par Su\u00e1rez, qui s'est d\u00e9velopp\u00e9 au cours des 30 derni\u00e8res ann\u00e9es en tant qu'alpiniste, grimpeur solitaire et base jumper.<\/p>\n\n\n\n<p><em>Obsession, <\/em>dirig\u00e9e par Jorge Saffie, a \u00e9t\u00e9 pr\u00e9sent\u00e9e pour la premi\u00e8re fois en 2019 et a \u00e9t\u00e9 mise en ligne sur YouTube cette ann\u00e9e, la rendant ainsi accessible \u00e0 tous les publics.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Film &quot;Obsession&quot; (Patagonie en hiver)\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/wlOnygjLviE?start=89&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Parmi les principales philosophies de Su\u00e1rez figure le respect de la montagne. Dans plusieurs interviews, l'alpiniste met en garde : \"Ne tombez pas dans l'exc\u00e8s d'ego, soyez humbles et sachez vous rendre compte de vos limites. Respecter la montagne, descendre quand on a un instinct, une intuition qui nous dit que \u00e7a ne va pas. Je pense qu'il faut s'\u00e9couter quand on est en montagne\". <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><em>Mourir pour le sommet <\/em>(2016)<\/h2>\n\n\n\n<p>La carri\u00e8re de l'alpiniste et grimpeur, qui dure depuis 25 ans, a commenc\u00e9 lorsqu'il avait 14 ans. Cette histoire est racont\u00e9e dans un long m\u00e9trage de 80 minutes intitul\u00e9 <em>Mourir pour le sommet<\/em> (2016), r\u00e9alis\u00e9 par Pablo Mart\u00edn.<\/p>\n\n\n\n<p>Su\u00e1rez a notamment \u00e9t\u00e9 le premier alpiniste \u00e0 escalader la face ouest du Naranjo de Bulnes (Espagne), en solo int\u00e9gral. Il a \u00e9galement \u00e9t\u00e9 trois fois champion d'Espagne d'escalade sportive dans la cat\u00e9gorie vitesse.<\/p>\n\n\n\n<p>Alex Txikon, Armando del Rey, Beto Rocasolano, Carlos Soria, Dar\u00edo Barrio, Leo Houlding et Ram\u00f3n Portilla ont particip\u00e9 \u00e0 ce long m\u00e9trage, chacun donnant sa propre vision de l'athl\u00e8te.<\/p>\n\n\n\n<p><em>Mourir pour le sommet<\/em>qui est \u00e9galement un livre, a remport\u00e9 plusieurs prix au Festival Cuentamontes 2017, au Prix \u00c1lvaro Bult\u00f3, \u00e0 la Semana de Cine de Monta\u00f1a de Castell\u00f3n et dans d'autres festivals internationaux.<\/p>\n\n\n\n<p>En tant que base jumper, Su\u00e1rez a trouv\u00e9 le moyen, en prenant des risques, de sauter avec seulement un parachute comme assurance. En 2012, l'alpiniste a m\u00eame \u00e9t\u00e9 victime d'un accident en pleine action, ce qui l'a contraint \u00e0 rester hors de la montagne pendant un an, sans courir de risques \u00e9lev\u00e9s.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"&quot;DIE FOR THE TOP&quot; Bande-annonce officielle\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/7-XYcHHw6Q0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><em>Le projet Asgard<\/em>&nbsp;(2009)<\/h2>\n\n\n\n<p>Le projet Asgard, un court-m\u00e9trage de 2009 con\u00e7u par Alastair Lee et Leo Houlding, qui raconte le voyage au mont Asgard sur l'\u00eele de Baffin (Canada), est un autre mat\u00e9riel audiovisuel permettant de mieux conna\u00eetre Su\u00e1rez.<\/p>\n\n\n\n<p>Ce film rassemble plusieurs images de l'alpiniste madril\u00e8ne lors de son entra\u00eenement sur diff\u00e9rentes montagnes \u00e0 Riglos, Brento et Yosemite, avant son arriv\u00e9e \u00e0 Baffin. Il s'agit d'images d'escalade et de base jumping.  Su\u00e1rez a r\u00e9alis\u00e9 cette exp\u00e9dition avec Leo Houlding et Sean Leary.<\/p>\n\n\n\n<p><em>Le projet Asgard&nbsp;<\/em>a particip\u00e9 \u00e0 plusieurs festivals l'ann\u00e9e de sa cr\u00e9ation et a \u00e9t\u00e9 reconnu, entre autres, par le Kendal Festival.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Le projet Asgard\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/rgF1uSmk4vw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Parmi les itin\u00e9raires de Su\u00e1rez<\/h2>\n\n\n\n<p>Comme mentionn\u00e9 ci-dessus, l'alpiniste a \u00e9t\u00e9 le premier \u00e0 escalader la face ouest du Naranjo de Bulnes, ainsi que l'obsession qu'il a pour la beaut\u00e9 et la complexit\u00e9 des massifs de Patagonie et le parcours d'entra\u00eenement qu'il a suivi pour s'attaquer au mont Asgard ; cependant, ce ne sont pas les seuls endroits qu'il a visit\u00e9s en tant qu'alpiniste professionnel, parmi lesquels figurent dix voyages dans l'Himalaya, un voyage au cours duquel il a atteint le sommet du Cho-Oyu.<\/p>\n\n\n\n<p>Entre deux voyages, Su\u00e1rez revient toujours dans les montagnes de son pays natal. Il convient \u00e9galement de noter que l'une des disciplines qu'il pratique est le base jump.<\/p>\n\n\n\n<p>Toutes les voies qu'il a r\u00e9alis\u00e9es jusqu'\u00e0 pr\u00e9sent lui ont servi \u00e0 \u00e9crire les publications pr\u00e9sent\u00e9es \u00e0 ce jour, devenant non seulement un exemple de ce qui peut \u00eatre fait mais aussi une r\u00e9f\u00e9rence anecdotique et th\u00e9orique de ce qu'est la passion et le respect de la montagne.<\/p>\n\n\n\n<p>El Diario Vasco a publi\u00e9 une interview de l'alpiniste en 2018. Su\u00e1rez y \u00e9voquait son r\u00f4le de formateur et de communicateur de ses exp\u00e9riences \u00e0 d'autres personnes qui d\u00e9butent : \" Je vais utiliser ma carri\u00e8re dans le monde de la montagne comme fil conducteur, mais je ne veux pas trop tomber dans l'\u00e9gocentrisme, mais je veux transmettre le message que mon exp\u00e9rience en montagne m'a donn\u00e9, la fa\u00e7on dont je vois le risque, l'aventure en elle-m\u00eame \".<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">De l'enfermement<\/h2>\n\n\n\n<p>Comme le monde entier, Su\u00e1rez a \u00e9t\u00e9 paralys\u00e9 au d\u00e9but de l'ann\u00e9e 2020 par une pand\u00e9mie qui a fait des millions de morts et d'infect\u00e9s ; malgr\u00e9 cela, apr\u00e8s quelques mois de flexibilit\u00e9, l'alpiniste a r\u00e9ussi \u00e0 se rendre dans certains endroits, car il est difficile de se s\u00e9parer d'une passion.<\/p>\n\n\n\n<p>La position de Su\u00e1rez sur la pand\u00e9mie est celle de la pr\u00e9vention, et il l'a clairement fait savoir sur ses r\u00e9seaux sociaux. Il y a un jour, il a t\u00e9l\u00e9charg\u00e9 une photo de Madrid dans laquelle il r\u00e9fl\u00e9chit un peu au contexte :<\/p>\n\n\n\n<p>\"Je ne sais pas si cette photo est pertinente ou si elle exprime \u00e0 quel point la situation est chaotique et foutue dans toutes les grandes villes en particulier. J'ai commenc\u00e9 \u00e0 utiliser le masque m\u00eame pour mes proches ! Nous n'avons pas le choix, vu l'invisibilit\u00e9 de la mati\u00e8re... et que n'importe qui peut l'attraper \u00e0 n'importe quelle porte, beaucoup de force...\".<\/p>\n\n\n\n<blockquote class=\"instagram-media\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CGx9vrMDZC-\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"13\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CGx9vrMDZC-\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener noreferrer\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewbox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\"> Voir ce message sur Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CGx9vrMDZC-\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener noreferrer\">A post shared by Carlos Suarez (@carlos.suarez_climb)<\/a> sur <time style=\" font-family:Arial,sans-serif; font-size:14px; line-height:17px;\" datetime=\"2020-10-25T20:56:09+00:00\">25 Oct, 2020 at 1:56 PDT<\/time><\/p><\/div><\/blockquote> <script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n\n\n\n<p>Cette publication intervient au moment o\u00f9 le pays conna\u00eet un nouveau pic d'infections et une nouvelle s\u00e9rie de mesures pr\u00e9ventives.<\/p>\n\n\n\n<p>Su\u00e1rez, pand\u00e9mie ou pas, est toujours en contact avec la nature, en train d'acqu\u00e9rir une exp\u00e9rience qu'il transmettra aux nouvelles g\u00e9n\u00e9rations, cette m\u00eame cha\u00eene dans laquelle il s'est inscrit lorsque, \u00e0 ses d\u00e9buts, il s'inspirait des personnages du pass\u00e9 pour prendre des risques.<\/p>\n\n\n\n<p><strong>Photo de couverture : Carlos Su\u00e1rez<\/strong><\/p>","protected":false},"excerpt":{"rendered":"L'alpiniste a sorti cette ann\u00e9e le court-m\u00e9trage \"Obsession\", qui documente son voyage au Cerro Torre en Patagonie, en Argentine.","protected":false},"author":953,"featured_media":23596,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3001],"tags":[],"series":[],"class_list":["post-23178","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-protagonistas-personajes","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/10\/Carlos-Suarez_Newsletter.png","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"AvPGWDyENz\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/carlos-suarez\/\">Carlos Su\u00e1rez: el encanto por el vac\u00edo<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/carlos-suarez\/embed\/#?secret=AvPGWDyENz\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Carlos Su\u00e1rez: el encanto por el vac\u00edo\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"AvPGWDyENz\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":3001,"label":"Protagonistas \/ Personajes"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/10\/Carlos-Suarez_Newsletter-1024x768.png",1024,768,true],"author_info":{"display_name":"Carolyn Manrique","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/carolyn-manrique\/"},"comment_info":0,"category_info":[{"term_id":3001,"name":"Protagonistas \/ Personajes","slug":"protagonistas-personajes","term_group":0,"term_taxonomy_id":3017,"taxonomy":"category","description":"Protagonistas \/ Personajes","parent":0,"count":16,"filter":"raw","cat_ID":3001,"category_count":16,"category_description":"Protagonistas \/ Personajes","cat_name":"Protagonistas \/ Personajes","category_nicename":"protagonistas-personajes","category_parent":0}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/10\/Carlos-Suarez_Newsletter.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/23178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/953"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=23178"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/23178\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/23596"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=23178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=23178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=23178"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=23178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}