{"id":23311,"date":"2020-11-05T13:14:23","date_gmt":"2020-11-05T12:14:23","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=23311"},"modified":"2022-03-23T10:26:51","modified_gmt":"2022-03-23T09:26:51","slug":"histoire-du-surf","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/historia-del-surf\/","title":{"rendered":"D\u00e9couvrez l'histoire int\u00e9ressante du surf"},"content":{"rendered":"<p>Le surf, c'est l'\u00e9motion, la passion et l'adr\u00e9naline ; c'est ce qui caract\u00e9rise le surf, o\u00f9 savoir utiliser la puissance de la mer \u00e0 son avantage et avoir la bonne technique est la cl\u00e9 qui vous permettra de r\u00e9aliser des exploits impressionnants et de ressentir le frisson de ce sport.<\/p>\n\n\n\n<p>Mais il est curieux que l'un des sports les plus populaires de la plan\u00e8te soit en m\u00eame temps l'un des plus anciens. <strong>L'histoire du Sud est jalonn\u00e9e d'\u00e9v\u00e9nements qui, d'une part, auraient pu mettre fin \u00e0 ce sport et, d'autre part, d'une s\u00e9rie d'\u00e9v\u00e9nements fortuits qui lui ont donn\u00e9 un \u00e9lan impressionnant.<\/strong>Le projet est devenu ce qu'il est aujourd'hui.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L'histoire du surf<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf.-1-1024x768.jpg\" alt=\"\" class=\"wp-image-23549\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf.-1-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf.-1-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf.-1-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf.-1-450x338.jpg 450w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf.-1-225x169.jpg 225w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf.-1-900x675.jpg 900w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf.-1-20x15.jpg 20w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf.-1-128x96.jpg 128w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf.-1-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf.-1.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Histoire du surf \/ Photo : Free-Photos (Pixabay)<\/figcaption><\/figure>\n\n\n\n<p>L'histoire du surf remonte au 18e si\u00e8cle, plus pr\u00e9cis\u00e9ment \u00e0 l'ann\u00e9e 1778. C'est cette ann\u00e9e-l\u00e0 que l'on a observ\u00e9 pour la premi\u00e8re fois d'autres personnes pratiquer quelque chose de similaire \u00e0 ce que nous connaissons aujourd'hui sous le nom de surf. Nous soulignons ce dernier point, car c'est la premi\u00e8re fois que d'autres personnes ont \u00e9t\u00e9 observ\u00e9es en train de pratiquer ce sport dans la modalit\u00e9 qui existait \u00e0 l'\u00e9poque. Cependant, on ne sait pas avec certitude quand ce sport a r\u00e9ellement commenc\u00e9.<\/p>\n\n\n\n<p>Pour mieux comprendre ce qui pr\u00e9c\u00e8de, il faut remonter \u00e0 cette ann\u00e9e-l\u00e0, lorsqu'une exp\u00e9dition britannique dirig\u00e9e par l'ambassadeur de Grande-Bretagne \u00e0 Londres a \u00e9t\u00e9 mise sur pied.<strong> Capitaine James Cook<\/strong> Alors qu'il se dirigeait vers Tahiti pour rejoindre les \u00c9tats-Unis, il tomba par hasard sur une s\u00e9rie d'\u00eeles inconnues \u00e0 l'\u00e9poque, que nous connaissons aujourd'hui sous le nom d'\"\u00eeles\". <a href=\"https:\/\/travesiapirenaica.com\/fr\/hawaii\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hawa\u00ef<\/a>.<\/p>\n\n\n\n<p>L'exp\u00e9dition de James Cook s'est arr\u00eat\u00e9e sur ces \u00eeles afin de les cartographier et de prendre note de leurs caract\u00e9ristiques et du mode de vie des habitants.<\/p>\n\n\n\n<p>Cependant, un \u00e9v\u00e9nement malheureux se produisit pendant le s\u00e9jour sur les \u00eeles, car une vive dispute \u00e9clata avec les indig\u00e8nes \u00e0 propos du vol d'un bateau. La dispute ne s'arr\u00eata pas l\u00e0 et se transforma en un acte de violence au cours duquel le capitaine Cook perdit la vie lorsque l'une des lances des indig\u00e8nes le frappa.<\/p>\n\n\n\n<p>C'est pourquoi le lieutenant James King prend le commandement de l'exp\u00e9dition, et c'est l\u00e0 qu'il r\u00e9dige le journal de bord, qui fait manifestement r\u00e9f\u00e9rence aux \u00e9v\u00e9nements qui se sont d\u00e9roul\u00e9s, et qui constitue la premi\u00e8re r\u00e9f\u00e9rence \u00e9crite connue au surf.<\/p>\n\n\n\n<p>Le lieutenant explique dans cette note quelques-uns des divertissements courants des indig\u00e8nes de l'\u00eele. Dans l'ancien texte de Jacques, il y a un fragment o\u00f9 il explique que l'un des divertissements les plus courants des indig\u00e8nes des \u00eeles se d\u00e9roule dans l'eau.<\/p>\n\n\n\n<p>Selon James King, le divertissement auquel il fait r\u00e9f\u00e9rence est pratiqu\u00e9 par les indig\u00e8nes lorsque la mer est haute et que les vagues se brisent pr\u00e8s du rivage. Les habitants de l'\u00eele, en particulier les hommes \u00e2g\u00e9s de 20 \u00e0 30 ans, sont les plus actifs sur l'\u00eele, <strong>entrent dans la mer et s'allongent sur une planche ovale en bois de m\u00eame hauteur et de m\u00eame largeur, en gardant les jambes jointes en haut et en se servant de leurs bras pour guider la planche.<\/strong><\/p>\n\n\n\n<p>Une fois dans l'eau, ils attendent l'arriv\u00e9e des plus grosses vagues et commencent alors \u00e0 pagayer avec les bras pour rester en haut de la vague, qui les propulse \u00e0 une vitesse vertigineuse. Ce sport pratiqu\u00e9 par les insulaires vise \u00e0 guider la planche pour qu'elle reste dans la bonne direction au sommet de la vague lorsqu'elle change de direction.<\/p>\n\n\n\n<p>James King ajoute dans sa note que lorsque la vague dirige l'un d'entre eux pr\u00e8s des rochers quelques instants avant qu'il ne soit pris par la d\u00e9ferlante, il est f\u00e9licit\u00e9 par tous. Il est clair que la raison de cette pratique est purement ludique et divertissante, et n'a rien \u00e0 voir avec des tests d'adresse, ce qui donne aux habitants de l'\u00eele un grand plaisir dans cet exercice.<\/p>\n\n\n\n<p>Il est frappant de constater qu'il s'agit de la premi\u00e8re r\u00e9f\u00e9rence \u00e0 la pratique du surf qui, comme nous l'avons vu, a \u00e9t\u00e9 d\u00e9couverte \u00e0 la suite d'une s\u00e9rie d'\u00e9v\u00e9nements fortuits et malheureux.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le surf a failli dispara\u00eetre au d\u00e9but du 19e si\u00e8cle.<\/h2>\n\n\n\n<p>Des d\u00e9cennies pass\u00e8rent et des missionnaires \u00e9cossais et allemands arriv\u00e8rent sur l'\u00eele en 1821, interdisant certaines traditions et pratiques comme le surf, jug\u00e9 immoral. Au d\u00e9but du XIXe si\u00e8cle, la pratique du surf avait presque enti\u00e8rement disparu, seul un petit groupe d'Hawa\u00efens continuant \u00e0 pratiquer ce sport et \u00e0 faire de la planche \u00e0 voile. <a href=\"https:\/\/soyviajero.com\/como-elegir-tabla-de-surf\/\" target=\"_blank\" rel=\"noreferrer noopener\">tables<\/a>.<\/p>\n\n\n\n<p>Cependant, alors que ce sport semblait sur le point de dispara\u00eetre compl\u00e8tement, au si\u00e8cle suivant, c'est-\u00e0-dire au d\u00e9but du XXe si\u00e8cle, un petit groupe de descendants d'anciens rois hawa\u00efens d\u00e9cida de reprendre la pratique de l'utilisation de planches en bois pour chevaucher les vagues, en commen\u00e7ant par la plage de Waikiki. L'un des meilleurs de ce groupe s'appelait<strong> Duke Kahanamoku<\/strong>.<\/p>\n\n\n\n<h2 class=\"has-text-align-left wp-block-heading\">Le p\u00e8re du surf moderne Duke Kahanamoku.<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf..-1024x768.jpg\" alt=\"\" class=\"wp-image-23546\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf..-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf..-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf..-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf..-450x338.jpg 450w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf..-225x169.jpg 225w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf..-900x675.jpg 900w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf..-20x15.jpg 20w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf..-128x96.jpg 128w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf..-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf...jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Statue de Duke Kahanamoku \/ Photo : Andym5855 (Flickr)<\/figcaption><\/figure>\n\n\n\n<p><strong>Duke Kahanamoku, aujourd'hui consid\u00e9r\u00e9 comme le p\u00e8re du surf moderne. <\/strong>Ce n'est \u00e9videmment pas parce qu'il a invent\u00e9 le surf, mais parce qu'il est consid\u00e9r\u00e9 comme l'inventeur du surf tel que nous le connaissons aujourd'hui. Surnomm\u00e9 le Grand Kahuna, il a r\u00e9invent\u00e9 un sport \u00e0 une \u00e9poque o\u00f9 il avait pratiquement disparu, le rendant c\u00e9l\u00e8bre et populaire de son vivant.<\/p>\n\n\n\n<p>Ses exploits sportifs sont impressionnants et, bien qu'il se soit distingu\u00e9 \u00e0 ses d\u00e9buts en natation, en battant d'importants records, c'est lui qui a popularis\u00e9 le surf, en se rendant dans d'autres parties du monde, comme l'Australie, pour donner des d\u00e9monstrations de surf qui, jusqu'alors, n'\u00e9taient connues qu'\u00e0 Hawaii.<\/p>\n\n\n\n<p>L'une de ses d\u00e9monstrations les plus importantes, qui repr\u00e9sente un avant et un apr\u00e8s dans l'histoire du surf, est celle qu'il a faite \u00e0 la Freshwater Beach de Sydney, o\u00f9 il a donn\u00e9 un v\u00e9ritable r\u00e9cital le 23 d\u00e9cembre 1914. La d\u00e9monstration \u00e9tait si impressionnante qu'elle est consid\u00e9r\u00e9e comme le jour le plus important pour le surf en Australie. On sait \u00e9galement que Duke a favoris\u00e9 l'expansion de ce sport \u00e0 Hawa\u00ef et au-del\u00e0, avec une forte pr\u00e9sence en Australie et aux \u00c9tats-Unis.<\/p>\n\n\n\n<p>Au fil des ans, le d\u00e9veloppement de ce sport s'est surtout fait \u00e0 Hawa\u00ef, en Californie, en Australie et au P\u00e9rou, o\u00f9 il y avait quelques surfeurs. Cependant, en 1959, la sortie du film Gidget a fait du surf un engouement national aux \u00c9tats-Unis.<\/p>\n\n\n\n<p>Il n'a pas fallu longtemps pour que des s\u00e9ries t\u00e9l\u00e9vis\u00e9es, telles que la s\u00e9rie B ou les Beach Boys, fassent du surf l'un des sports les plus populaires de Californie.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L'histoire du surf en Espagne.<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf....-1024x768.jpg\" alt=\"\" class=\"wp-image-23552\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf....-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf....-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf....-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf....-450x338.jpg 450w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf....-225x169.jpg 225w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf....-900x675.jpg 900w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf....-20x15.jpg 20w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf....-128x96.jpg 128w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf....-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf.....jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Histoire du surf en Espagne \/ Photo : Free-Photos (Pixabay)<\/figcaption><\/figure>\n\n\n\n<p>C'est pr\u00e9cis\u00e9ment \u00e0 partir de 1960, alors que le surf \u00e9tait populaire \u00e0 Hawa\u00ef, en Australie et aux \u00c9tats-Unis, que la mode du surf est apparue en Espagne. Plus pr\u00e9cis\u00e9ment, entre 1963 et 1965, ce sport a commenc\u00e9 \u00e0 \u00eatre pratiqu\u00e9 de mani\u00e8re ind\u00e9pendante dans diff\u00e9rentes parties de la p\u00e9ninsule.<\/p>\n\n\n\n<p>La pratique du surf en Espagne a d\u00e9but\u00e9 principalement en <strong>Asturies, Pays basque, Cadix, Cantabrie<\/strong>C'est aux \u00eeles Canaries qu'il a commenc\u00e9 \u00e0 \u00eatre pratiqu\u00e9, et un peu plus tard, il est devenu populaire dans les \u00eeles Canaries.<\/p>\n\n\n\n<p>Cependant, avant 1963, il y avait d\u00e9j\u00e0 une personne qui avait os\u00e9 surfer dans notre pays. C'\u00e9tait en 1957, lorsque l'Am\u00e9ricain<strong> Peter Viertel, sc\u00e9nariste d'un film intitul\u00e9 \"Fiesta\", qui a \u00e9t\u00e9 produit \u00e0 Pampelune, a d\u00e9cid\u00e9 d'apporter certaines de ses planches dans le pays, ainsi que son mat\u00e9riel cin\u00e9matographique.<\/strong> C'est la premi\u00e8re planche de surf \u00e0 avoir \u00e9t\u00e9 vue en Espagne, et c'est officiellement la premi\u00e8re personne \u00e0 avoir pratiqu\u00e9 ce sport dans le pays.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Surfeurs espagnols qui ont fait la promotion de ce sport.<\/h2>\n\n\n\n<p>Deux jeunes hommes de Gij\u00f3n, F\u00e9lix Cueto et Amador Rodr\u00edguez, ont cr\u00e9\u00e9 une planche de surf sculpt\u00e9e \u00e0 la main, car ils avaient d\u00e9couvert le surf gr\u00e2ce \u00e0 une couverture de l'une des s\u00e9ries les plus populaires, celle des Beach Boys. Cette couverture montrait un surfeur chevauchant une vague gigantesque avec une dext\u00e9rit\u00e9 incroyable, une image qu'ils n'arrivaient pas \u00e0 oublier.<\/p>\n\n\n\n<p><strong>VOUS POUVEZ \u00caTRE INT\u00c9RESS\u00c9 PAR : <a href=\"https:\/\/travesiapirenaica.com\/fr\/tarif-du-surf\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/soyviajero.com\/destinos-para-hacer-surf-espana\/\" target=\"_blank\" rel=\"noreferrer noopener\">Les meilleures destinations de surf en Espagne<\/a><\/strong><\/p>\n\n\n\n<p>Les deux amis ont essay\u00e9 de construire leur propre planche, mais ils se sont aper\u00e7us qu'elle \u00e9tait trop lourde et qu'ils ne pouvaient la transporter qu'\u00e0 deux. Ils ont exp\u00e9riment\u00e9 cet \u00e9t\u00e9-l\u00e0 sans grand succ\u00e8s. Mais l'hiver suivant, F\u00e9lix construisit une autre planche, beaucoup plus l\u00e9g\u00e8re, en se basant sur les instructions d'un magazine am\u00e9ricain connu \u00e0 l'\u00e9poque sous le nom de Popular Mechanics.<\/p>\n\n\n\n<p>Les efforts ont port\u00e9 leurs fruits, puisque l'\u00e9t\u00e9 suivant, apr\u00e8s de nombreuses tentatives et d'innombrables chutes, son partenaire Amador Rodr\u00edguez a r\u00e9ussi \u00e0 surfer la premi\u00e8re vague tandis que F\u00e9lix sautait de joie sur la plage. Ce moment marque le d\u00e9but du surf en Espagne.<\/p>\n\n\n\n<p><strong>Histoire du surf \/ Photo de couverture : <a rel=\"noreferrer noopener nofollow\" href=\"https:\/\/pixabay.com\/es\/photos\/surf-puesta-del-sol-mar-2212948\/\" target=\"_blank\">KANENORY (Pixabay)<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"Le surf, c'est de l'\u00e9motion, de la passion et de l'adr\u00e9naline ; c'est ce qui caract\u00e9rise le surf, o\u00f9 savoir...","protected":false},"author":959,"featured_media":23548,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2948],"tags":[],"series":[],"class_list":["post-23311","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-deportes-acuaticos","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"kck2e7hxfW\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/historia-del-surf\/\">Descubre la interesante historia del surf<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/historia-del-surf\/embed\/#?secret=kck2e7hxfW\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Descubre la interesante historia del surf\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"kck2e7hxfW\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":2948,"label":"Deportes acu\u00e1ticos"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf-1024x683.jpg",1024,683,true],"author_info":{"display_name":"Gabriel Ruiz","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/gabriel-ruiz\/"},"comment_info":0,"category_info":[{"term_id":2948,"name":"Deportes acu\u00e1ticos","slug":"deportes-acuaticos","term_group":0,"term_taxonomy_id":2964,"taxonomy":"category","description":"Deportes acu\u00e1ticos","parent":1577,"count":7,"filter":"raw","cat_ID":2948,"category_count":7,"category_description":"Deportes acu\u00e1ticos","cat_name":"Deportes acu\u00e1ticos","category_nicename":"deportes-acuaticos","category_parent":1577}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2020\/11\/Historia-del-surf.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/23311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/959"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=23311"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/23311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/23548"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=23311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=23311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=23311"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=23311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}