{"id":27727,"date":"2023-03-01T05:08:00","date_gmt":"2023-03-01T04:08:00","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=27727"},"modified":"2023-03-01T11:34:51","modified_gmt":"2023-03-01T10:34:51","slug":"initiation-a-la-via-ferrata","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/via-ferrata-iniciacion\/","title":{"rendered":"Vias Ferrata : initiation et tout ce qu'il faut savoir pour progresser sur les via ferratas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">De primeras, la v\u00eda ferrata es una actividad de aventura que permite disfrutar de las alturas, con un grado de compromiso menor que en rutas de escalada cl\u00e1sica \u2014ello depender\u00e1 de la dificultad de la ferrata, que las hay muy \u00abacongojantes\u00bb\u2014. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiero hacer un repaso general que sirva de gu\u00eda para iniciados en la actividad. Os dejo aqu\u00ed alg\u00fan atajo, para que pod\u00e1is ir a la secci\u00f3n que os interese: <strong><a href=\"#equipo\">Equipo <\/a><\/strong>\/ <strong><a href=\"#tecnica\">T\u00e9cnica <\/a><\/strong>\/ <strong><a href=\"#grados\">Grados dificultad<\/a> <\/strong>\/ <strong><a href=\"#rutas\">Rutas en Espa\u00f1a<\/a><\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es una V\u00eda Ferrata?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Como <strong>V\u00eda Ferrata<\/strong> se conoce al conjunto de instalaciones artificiales que se han colocado en una pared rocosa o en un <strong>itinerario<\/strong> horizontal, para poder subir bajo cierta seguridad una ruta, sea de senderismo o de monta\u00f1ismo.&nbsp;Sin embargo, hay que tener en cuenta que una&nbsp;ca\u00edda de una v\u00eda ferrata puede ser muy peligrosa si no se siguen al pie de la letra las normas de seguridad.&nbsp; <\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los materiales que suelen usarse en las v\u00edas ferratas son <strong>clavos, pasamanos, cadenas, grapas, tirolinas y presas<\/strong>, entre otros. Las v\u00edas ferratas m\u00e1s cl\u00e1sicas se encuentran en los Alpes italianos, Francia, Suiza, Alemania y Espa\u00f1a.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En los lugares escarpados, sin la presencia del equipamiento propio de la v\u00eda ferrata, la progresi\u00f3n por ese sitio requerir\u00eda el conocimiento de t\u00e9cnicas de escalada con cuerda, propios del alpinismo. <\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Un poco de historia<\/strong>: \u00bfCu\u00e1ndo surgen las v\u00edas ferrata?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La monta\u00f1a <strong>Hoher Dachstein<\/strong>, en Austria, con sus 2.995 metros de altura, fue la que vio nacer <strong>la primera V\u00eda Ferrata en 1843<\/strong>. Para 1869, tambi\u00e9n en Austria, se equip\u00f3 una v\u00eda ferrata en el monte <strong>Grossglockner<\/strong> y en 1903 en <strong><a aria-label=\" (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/travesiapirenaica.com\/ferratas-dolomitas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Las Dolomitas<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(TE PUEDE INTERESAR: <a href=\"https:\/\/travesiapirenaica.com\/ferratas-dolomitas\/\" target=\"_blank\" rel=\"noreferrer noopener\">V\u00edas Ferratas de los Dolomitas Italianos<\/a>)<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/Via-Ferrata-en-Brenta_By-Justin-Clements-CC-BY-2.0_1080x1350-819x1024.jpg\" alt=\"Via Ferrata en Brenta \/ Foto: Justin Clements [CC-BY-2.0]\" class=\"wp-image-10310\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/Via-Ferrata-en-Brenta_By-Justin-Clements-CC-BY-2.0_1080x1350-819x1024.jpg 819w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/Via-Ferrata-en-Brenta_By-Justin-Clements-CC-BY-2.0_1080x1350-600x750.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/Via-Ferrata-en-Brenta_By-Justin-Clements-CC-BY-2.0_1080x1350-240x300.jpg 240w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/Via-Ferrata-en-Brenta_By-Justin-Clements-CC-BY-2.0_1080x1350-768x960.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/10\/Via-Ferrata-en-Brenta_By-Justin-Clements-CC-BY-2.0_1080x1350.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">Via Ferrata en Brenta \/ Foto: Justin Clements [CC-BY-2.0]<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ya para fines del siglo XIX, muchas zona monta\u00f1osas de Europa contaban con v\u00edas ferratas, pero el mayor auge de ellas surgi\u00f3 durante la guerra, ya que<strong> los soldados las utilizaban par llegar a los puestos de avanzada en las zonas de m\u00e1s dif\u00edcil acceso de los Alpes<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el fin de las guerras, estos enclaves utilizados en su momento con fines militares, se convirtieron en senderos aprovechados por los aficionados al senderismo y al monta\u00f1ismo, dedic\u00e1ndose al tiempo de ocio y a la recreaci\u00f3n. &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre estos caminos, anta\u00f1o militares, destacan la <strong>Ferrata de las Trincheras<\/strong> en la Marmolada, la <strong>Ferrata Ivano Dibona<\/strong>, en el <strong>Monte Cristallo<\/strong>, el <strong>Camino de los Alpinos<\/strong> en las Dolomitas de Sesto y la <strong>Ferrata Lipella<\/strong> en Tofane.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"equipo\">Equipo y material necesario: \u00bfQu\u00e9 se necesita para hacer una v\u00eda ferrata?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">(TE PUEDE INTERESAR: <a href=\"https:\/\/travesiapirenaica.com\/vias-ferratas-material-basico-e-iniciacion\/\" target=\"_blank\" rel=\"noreferrer noopener\">Equipo y material b\u00e1sico para las v\u00edas ferrata<\/a>)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCu\u00e1l es el equipamiento principal para v\u00eda ferrata? (os incluyo una elecci\u00f3n de producto para cada categor\u00eda de material) <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Elemento <\/strong>de amarre con <strong>absorbedor de energ\u00eda (<a href=\"https:\/\/amzn.to\/3uzg5SS\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Edelrid &#8211; Kit Ultralite 5.0<\/a>)<\/strong>. \u00bfPor qu\u00e9 un elemento de amarre espec\u00edfico para v\u00eda ferrata? Se trata de un disipador de la energ\u00eda en caso de ca\u00edda. Si utilizamos una simple baga el factor de ca\u00edda ser\u00e1 enorme y corremos el riesgo de rotura de la misma o de lesiones en nuestro cuerpo. Los diferentes sistemas de disipaci\u00f3n har\u00e1n que una ca\u00edda no represente riesgo. <strong>Atenci\u00f3n: <\/strong>No enganchar nunca una cinta del elemento de amarre al arn\u00e9s (impide el despliegue del absorbedor de energ\u00eda)<\/li>\n\n\n\n<li><strong>Casco (<a href=\"https:\/\/amzn.to\/3eIjdEc\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">PETZL Borea<\/a>).<\/strong><\/li>\n\n\n\n<li><strong>Aparato para asegurar, descendedor, cuerda, mosquetones (<a href=\"https:\/\/amzn.to\/3f90Mr4\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Edelrid HMS<\/a>), cintas expr\u00e9s<\/strong>, cintas (<a href=\"https:\/\/amzn.to\/3uJPPTl\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>SALEWA Dyneema Sling<\/strong><\/a>). Estamos en territorio vertical y dependiendo de la exposici\u00f3n deberemos de contar con equipamiento para asegurar alguna secci\u00f3n o bien para descender de la v\u00eda.<\/li>\n\n\n\n<li><strong>Arn\u00e9s<\/strong>. <strong>(<a href=\"https:\/\/amzn.to\/3JD2YEu\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Black Diamond, Unisex<\/a>)<\/strong> Es recomendable que el arn\u00e9s sea regulable en las piernas. <\/li>\n\n\n\n<li><strong>Guantes<\/strong> <strong>(<a href=\"https:\/\/amzn.to\/3vYzYR6\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Black Diamond Crag<\/a>)<\/strong>. Aunque no es indispensable el uso&nbsp;de&nbsp;guantes en las&nbsp;v\u00edas ferratas,&nbsp;si&nbsp;es recomendable llevarlos, ya que proteger\u00e1n las manos&nbsp;de&nbsp;ampollas, callos y otras heridas.<\/li>\n\n\n\n<li><strong>Calzado (<a href=\"https:\/\/amzn.to\/3eEzNV9\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">SALEWA Wildfire Edge GTX<\/a>) y ropa monta\u00f1a. <\/strong><\/li>\n\n\n\n<li><strong>Gafas y frontal (<a href=\"https:\/\/amzn.to\/33AKH8a\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">PETZL Tikka<\/a>).<\/strong><\/li>\n\n\n\n<li><strong>Mochila (<a href=\"https:\/\/amzn.to\/3OcyGfs\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Black Diamond Rock Blitz 15<\/a>)<\/strong><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"tecnica\">T\u00e9cnica de progresi\u00f3n en una v\u00eda ferrata<\/h2>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/CDJVSMavBdg?rel=0&amp;showinfo=0\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen=\"\"><\/iframe>\n\n\n\n<p class=\"wp-block-paragraph\">Es necesario avanzar con calma y midiendo cada paso. A menudo percibida como una actividad de f\u00e1cil iniciaci\u00f3n, la v\u00eda ferrata es una actividad con riesgo que requiere una formaci\u00f3n, como cualquier otra actividad en el medio vertical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recopilamos una selecci\u00f3n de consejos t\u00e9cnicos para la progresi\u00f3n en v\u00eda ferrata con elementos de amarre. (RECOMIENDO echar un vistazo a las ilustraciones que acompa\u00f1an los art\u00edculos t\u00e9cnicos que PETZL tienen al respecto, <a href=\"https:\/\/www.petzl.com\/ES\/es\/Sport\/Via-ferrata\" target=\"_blank\" rel=\"noreferrer noopener\">pincha <\/a><a href=\"https:\/\/www.petzl.com\/ES\/es\/Sport\/Via-ferrata\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">A<\/a><a href=\"https:\/\/www.petzl.com\/ES\/es\/Sport\/Via-ferrata\" target=\"_blank\" rel=\"noreferrer noopener\">QU\u00cd<\/a>. No sustituyen una formaci\u00f3n pero ayudan a reforzar los conceptos.)<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Regla b\u00e1sica: siempre estar asegurado al cable.<\/strong> Mantenga siempre como m\u00ednimo una cinta conectada al cable de seguridad<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En general, para avanzar por las v\u00edas ferratas se usa el <strong>m\u00e9todo de progresi\u00f3n en \u201cY\u201d<\/strong>. Este &nbsp;consiste en que los dos cabos de anclaje procedan de una misma cuerda que posee un extremo b\u00edfido, al que los mosquetones son acoplados. En el otro extremo de la cuerda est\u00e1 el disipador y se une al arn\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para iniciar la progresi\u00f3n, con los dos cabos de anclaje sujetos al cable de seguridad, se ir\u00e1n sorteando los anclajes fijos pasando los mosquetones de uno en uno. La idea es que siempre haya un mosquet\u00f3n asegurado al cable y que se pueda realizar la progresi\u00f3n con uno de los cabos asegurado al cable en todo momento.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Una sola persona por tramo de cable. <strong>En cada tramo o distancia entre cada anclaje, s\u00f3lo debe haber una persona<\/strong> y siempre habr\u00e1 que mantener al menos una distancia de cuatro metros entre un escalador y otro.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En caso de cansancio: <strong>Posici\u00f3n de reposo.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Para descansar, es posible buscar un lugar al que anclarse. <\/li>\n\n\n\n<li>Mosquet\u00f3n fijado al punto de reposo y operativo. En este caso, ser\u00e1 de utilidad el tercer mosquet\u00f3n, que suele tener la posibilidad de amarrar al disipador para utilizar como punto de reposo. <\/li>\n\n\n\n<li>Relaja los brazos siempre que sientas la necesidad de hacerlo<\/li>\n\n\n\n<li>Tambi\u00e9n es conveniente chequear que los otros escaladores se encuentren bien situados antes de ponerse a descansar.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfCu\u00e1ndo utilizar la cuerda?<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En cualquier situaci\u00f3n, adem\u00e1s del elemento absorbedor de energ\u00eda,<\/li>\n\n\n\n<li>tambi\u00e9n es recomendable asegurar con una cuerda.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Para utilizar una cuerda, la cordada debe organizarse de la misma forma que en escalada, con un primero de cordada con conocimientos suficientes para asegurar a los segundos.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Atenci\u00f3n: los elementos de amarre para v\u00eda ferrata no est\u00e1n dise\u00f1ados para las personas de menos de 40 kg y de m\u00e1s de 120 kg.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"grados\">\u00bfC\u00f3mo se clasifican las v\u00edas ferrata? \u00bfC\u00f3mo se mide la dificultad de una v\u00eda ferrata?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se rige por la nueva escala H\u00fcsler, que te ayudar\u00e1 a no confundirte: K1 (f\u00e1cil) , K2 (poco dif\u00edcil) , K3 (algo dif\u00edcil) , K4(dif\u00edcil) , K5 (muy dif\u00edcil) y K6 (extremadamente dif\u00edcil).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(TE PUEDE INTERESAR: <a href=\"https:\/\/deandar.com\/post\/graduacion-ferratas\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Sistema de graduaci\u00f3n de las v\u00edas ferratas<\/a>)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"rutas\">Las v\u00edas ferrata m\u00e1s famosas de Espa\u00f1a<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os hago una selecci\u00f3n de 7 ferratas. Est\u00e1n repartidas por toda la geograf\u00eda espa\u00f1ola. A la breve descripci\u00f3n se le a\u00f1ade el grado-dificultad y un tiempo orientativo de ferrata, a la actividad habr\u00e1 que a\u00f1adirle el tiempo de aproximaci\u00f3n y regreso.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La <strong><a href=\"https:\/\/ferratalahermida.com\/\" rel=\"noreferrer noopener nofollow\" target=\"_blank\">v\u00eda ferrata La Hermida<\/a><\/strong> <em>(K3, 1h30&#8242; ferrata)<\/em>, tiene el honor de considerarse la m\u00e1s larga de Espa\u00f1a. Se encuentra en Cantabria, municipio de Pe\u00f1arrubia,  el desfiladero del r\u00edo deba, a medio camino de la costa a Picos de Europa. Gestionada por empresa, acceso libre, pero debemos registrarnos.<\/li>\n\n\n\n<li>La v\u00eda ferrata <strong><a href=\"https:\/\/deandar.com\/ferratas\/via-ferrata-baumes-corcades\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Baumes Corcades<\/a><\/strong> <em>(K4, 2 h25&#8242; ferrata)<\/em> en Centelles (Barcelona) es de las m\u00e1s populares, tendr\u00e1s que reservar entrada para acceder. Pasos laterales, puente nepal\u00ed de 68 metros, hacen de la v\u00eda un itinerario deportivo que nos pondr\u00e1 a prueba.  <\/li>\n\n\n\n<li>La v\u00eda ferrata<strong> <a href=\"https:\/\/deandar.com\/ferratas\/via-ferrata-sant-feliu\" target=\"_blank\" rel=\"noreferrer noopener\">Sant Feliu de Gu\u00edxols o Cala del Mol\u00ed<\/a> <\/strong><em>(K3, 1h30&#8242; de ferrata)<\/em> es una cl\u00e1sica en la Costa Brava. Discurre junto al mar, con lo que te puedes hacer una idea de lo frecuentada que es. Elige temporada baja o entresemana.<\/li>\n\n\n\n<li>En el coraz\u00f3n del Parque Nacional de Ordesa y Monte Perdido se encuentra la v\u00eda ferrata de la <strong><a href=\"https:\/\/deandar.com\/ferratas\/via-ferrata-broto\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Cascada del Sorrosal<\/a><\/strong> <em>(K3, 1h30&#8242; de ferrata)<\/em>, concretamente al pie del pueblo de Broto. El itinerario salva la pared de la cascada por su izquierda. Un puente, varias escaleras y un peque\u00f1o tunel la hacen muy variada y entretenida. Cerrada durante el invierno. <\/li>\n\n\n\n<li>La v\u00eda ferrata <a href=\"https:\/\/deandar.com\/ferratas\/via-ferrata-hoces-priego-buitreras\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>Hoces de Priego o de Las Buitreras <\/strong><\/a>(K4, 1h30&#8242; ferrata)se encuentra en Cuenca, entre las poblaciones de Ca\u00f1amares y Priego en Cuenca, sobre el r\u00edo Escabas. El primer tramo es muy vertical, salvado este tendremos una traves\u00eda horizontal. Se pueden ver muchas buitreras y aves, hecho que hace que por restricciones en \u00e9pocas de nidificaci\u00f3n se encuentre cerrada. Consultar antes de ir.<\/li>\n\n\n\n<li>La <strong><a href=\"https:\/\/alandalusactiva.com\/actividades\/vias-ferratas-en-andalucia\/via-ferrata-del-tajo-de-ronda\/#:~:text=La%20V%C3%ADa%20ferrata%20del%20Tajo%20de%20Ronda%20se%20utiliz%C3%B3%20por,de%20agua%20de%20la%20zona.&amp;text=Ademas%20se%20le%20conoce%20tambi%C3%A9n,o%20v%C3%ADa%20ferrata%20de%20M%C3%A1laga.\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">v\u00eda ferrata del Tajo de Ronda<\/a><\/strong> o La Sevillana (K2)&nbsp;, enclavada en un lugar privilegiado, ideal para iniciaci\u00f3n, f\u00e1cil pero muy emocionante. La V\u00eda ferrata del Tajo de Ronda se utiliz\u00f3 por los obreros de la Sevillana en los a\u00f1os 20 para sujetar los tajos con muros de mamposter\u00eda, con los que proteger los Molinos y las acequias de agua de la zona.<\/li>\n\n\n\n<li>La v\u00eda ferrata del<strong><a href=\"https:\/\/www.ferratavillalbadelasierra.com\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> Ventano del Diablo<\/a><\/strong> se encuentra a los pies del conocido mirador natural del Ventano del Diablo, en el pueblo de Villalba de la Sierra, a tan s\u00f3lo 21km de Cuenca ciudad. Dos recorridos (K3 y K4).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">(Si est\u00e1s buscando una v\u00eda ferrata en particular, TE RECOMIENDO que visites el cat\u00e1logo de itinerarios rese\u00f1ados en deandar.com (pincha <a href=\"https:\/\/deandar.com\/ferratas\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">AQU\u00cd<\/a>).<\/p>\n","protected":false},"excerpt":{"rendered":"Tout d'abord, la via ferrata est une activit\u00e9 d'aventure qui permet de profiter de la...","protected":false},"author":191,"featured_media":27756,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_wp_convertkit_post_meta":{"form":"-1","landing_page":"0","tag":"0","restrict_content":"0"},"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2956],"tags":[],"series":[],"class_list":["post-27727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vias-ferratas"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/05\/Ferrata-en-Schladming-dachstein-Austria_by-maja-kochanowska-unsplash_1200x900.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"NbFAxyDhOd\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/via-ferrata-iniciacion\/\">V\u00edas Ferrata: iniciaci\u00f3n y todo lo que tienes que saber para la progresi\u00f3n en v\u00edas ferrata<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/via-ferrata-iniciacion\/embed\/#?secret=NbFAxyDhOd\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0V\u00edas Ferrata: iniciaci\u00f3n y todo lo que tienes que saber para la progresi\u00f3n en v\u00edas ferrata\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"NbFAxyDhOd\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":2956,"label":"V\u00edas ferratas"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/05\/Ferrata-en-Schladming-dachstein-Austria_by-maja-kochanowska-unsplash_1200x900-1024x768.jpg",1024,768,true],"author_info":{"display_name":"Eduardo Azcona","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/eduardo-2\/"},"comment_info":0,"category_info":[{"term_id":2956,"name":"V\u00edas ferratas","slug":"vias-ferratas","term_group":0,"term_taxonomy_id":2972,"taxonomy":"category","description":"V\u00edas ferratas","parent":2946,"count":1,"filter":"raw","cat_ID":2956,"category_count":1,"category_description":"V\u00edas ferratas","cat_name":"V\u00edas ferratas","category_nicename":"vias-ferratas","category_parent":2946}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/05\/Ferrata-en-Schladming-dachstein-Austria_by-maja-kochanowska-unsplash_1200x900.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/27727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/191"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=27727"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/27727\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/27756"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=27727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=27727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=27727"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=27727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}