{"id":28855,"date":"2021-06-23T07:00:00","date_gmt":"2021-06-23T05:00:00","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=28855"},"modified":"2021-11-10T12:45:24","modified_gmt":"2021-11-10T11:45:24","slug":"torches-olight","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/linternas-olight\/","title":{"rendered":"[REVIEW] Olight presenta las nuevas linternas: Warrior Mini 2 &#038; Freyr"},"content":{"rendered":"<p>Des torches de haute qualit\u00e9 et tr\u00e8s innovantes, voil\u00e0 ce que je savais des torches Olight : une entreprise am\u00e9ricaine qui se distingue par ses torches LED. Lorsqu'on nous a demand\u00e9 de r\u00e9aliser un <em>examen <\/em>de leurs nouvelles torches, je me suis dit : \"il va falloir chercher un environnement sombre avec de l'eau, de la boue...\". Ces jours-ci, j'ai test\u00e9 leurs nouveaux mod\u00e8les <a href=\"https:\/\/amzn.to\/3ogtU4f\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">WARRIOR Mini 2<\/a> y  <a href=\"https:\/\/amzn.to\/3Hc2fKj\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Freyr<\/a>. Je suis all\u00e9 en montagne avec ces deux petits jouets, et je vais maintenant vous dire ce que j'en ai pens\u00e9. Tout d'abord, je peux vous dire que la taille est tr\u00e8s petite - pour le Warrior Mini 2, mais aussi pour le Freyr - et que lorsqu'on \u00e9claire de loin \u00e0 pleine puissance - dans mon cas sur une paroi rocheuse \u00e0 des centaines de m\u00e8tres de l\u00e0 o\u00f9 je me trouvais - on se rend compte de la haute technologie que l'on tient dans sa main. <\/p>\n\n\n\n<p>Vous pouvez acc\u00e9der sp\u00e9cifiquement \u00e0 l'examen de chaque mod\u00e8le en cliquant sur les raccourcis suivants : <a href=\"#Warrior-Mini-2\">Olight Warrior Mini 2<\/a> \/ <a href=\"#Freyr\">Olight Freyr<\/a> . Nous incluons \u00e9galement <a href=\"#otros-modelos\">autres mod\u00e8les<\/a> de la marque Olight.  <\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Warrior-Mini-2\">Olight Warrior Mini 2 <\/h2>\n\n\n\n<p>Les <a href=\"https:\/\/amzn.to\/3ogtU4f\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Warrior Mini 2<\/a> est une torche LED de poche, c'est-\u00e0-dire une torche tactique EDC dans le jargon de la survie. Elle est tr\u00e8s puissante par rapport \u00e0 d'autres lampes de poche similaires sur le march\u00e9, avec une puissance maximale de 1750 lumens et une distance de faisceau de 220 m\u00e8tres. Nous sommes surpris par cette puissance \u00e9lev\u00e9e dans un petit format.  Il s'agit de la version am\u00e9lior\u00e9e de la Warrior Mini pr\u00e9c\u00e9dente qui, bien que l\u00e9g\u00e8rement plus petite, n'atteint pas la puissance de la Warrior Mini 2 : 17% plus lumineuse et 16% plus longue port\u00e9e.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Unboxing du Olight Warrior Mini 2<\/h3>\n\n\n\n<p>Une petite bo\u00eete en carton, d'o\u00f9 l'on extrait un bo\u00eetier en plastique pour la torche. <a href=\"https:\/\/amzn.to\/3ogtU4f\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Warrior Mini 2<\/a>La lampe de poche est livr\u00e9e avec un c\u00e2ble de recharge USB-magn\u00e9tique (USB type A d'un c\u00f4t\u00e9 et connecteur magn\u00e9tique de l'autre), une lani\u00e8re pour attacher la lampe au poignet et un clip de poche (sur la photo, ils sont d\u00e9j\u00e0 attach\u00e9s \u00e0 la lampe), un anneau mousqueton et le mode d'emploi. La torche n'est pas livr\u00e9e avec un \u00e9tui ou une pochette. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-WARRIOR-Mini-2_1200x900-1024x768.jpg\" alt=\"Olight WARRIOR Mini 2\" class=\"wp-image-28868\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-WARRIOR-Mini-2_1200x900-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-WARRIOR-Mini-2_1200x900-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-WARRIOR-Mini-2_1200x900-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-WARRIOR-Mini-2_1200x900-150x113.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-WARRIOR-Mini-2_1200x900-696x522.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-WARRIOR-Mini-2_1200x900-1068x801.jpg 1068w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-WARRIOR-Mini-2_1200x900-560x420.jpg 560w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-WARRIOR-Mini-2_1200x900-80x60.jpg 80w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-WARRIOR-Mini-2_1200x900-265x198.jpg 265w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-WARRIOR-Mini-2_1200x900-853x640.jpg 853w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-WARRIOR-Mini-2_1200x900-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-WARRIOR-Mini-2_1200x900.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Le corps principal de la lanterne est enti\u00e8rement noir, avec la marque et le nom inscrits sur le c\u00f4t\u00e9. La queue est argent\u00e9e, avec une bordure bleue sur la t\u00eate et un clip de poche bleu. La queue est munie d'un bouton qui permet de contr\u00f4ler certaines fonctions de la lampe, mais aussi d'un aimant qui permet de brancher le chargeur. J'ai appr\u00e9ci\u00e9 le fait qu'elle puisse \u00e9galement \u00eatre utilis\u00e9e pour fixer la torche sur des surfaces m\u00e9talliques. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Premi\u00e8res impressions <\/h3>\n\n\n\n<p>J'ai ador\u00e9 la taille du <a href=\"https:\/\/amzn.to\/3ogtU4f\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Warrior Mini 2<\/a>Il est id\u00e9al pour \u00eatre transport\u00e9 dans votre poche lorsque vous allez camper ou faire de la randonn\u00e9e. Je suis plut\u00f4t un adepte de l'orientation frontale, mais c'est une bonne alternative en termes de taille et de poids. <\/p>\n\n\n\n<p>La premi\u00e8re impression est celle de la robustesse et de la durabilit\u00e9, de la solidit\u00e9. Le corps est fait d'un alliage d'aluminium qui le rend tr\u00e8s solide. Il est grav\u00e9, de sorte que la texture et les asp\u00e9rit\u00e9s sont parfaitement ressenties dans la paume de la main et qu'il est tr\u00e8s facile \u00e0 saisir lorsqu'il est mouill\u00e9 ou que nos mains sont boueuses.<\/p>\n\n\n\n<p>Lorsque vous l'allumez et la r\u00e9glez \u00e0 pleine puissance (mode turbo : 1 700 lumens), vous vous rendez compte de la puissance de cette \"petite chose\" que vous tenez dans votre main. <\/p>\n\n\n\n<p>Et une chose sur laquelle je n'avais pas compt\u00e9, c'est la r\u00e9sistance \u00e0 l'eau. C'est certainement tr\u00e8s important pour les aventures qui en d\u00e9pendent. Je l'ai d\u00e9couvert en le testant dans l'eau : il b\u00e9n\u00e9ficie d'une protection IPX8 (submersible jusqu'\u00e0 une certaine profondeur dans l'eau). Au d\u00e9but, je n'osais pas l'immerger dans l'eau, mais j'ai vu qu'il fonctionnait toujours sous l'eau. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fonctionnement <\/h3>\n\n\n\n<p>Excellente performance : j'ai \u00e9t\u00e9 surpris par la puissance : <strong>1 750 lumens<\/strong> (en mode turbo), ainsi que l'autonomie, jusqu'\u00e0<strong> 220 m\u00e8tres<\/strong>. Si l'on veut analyser l'autonomie dans le mode <em>lune <\/em>nous passons \u00e0 45 jours d'activit\u00e9. <\/p>\n\n\n\n<p><strong>Plusieurs modes de luminosit\u00e9.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><em>Turbo<\/em>1750 lumens, 4 minutes, 220 m\u00e8tres<\/li><li><em>Haut<\/em>500 lumens, 218 minutes, 117 m\u00e8tres<\/li><li><em>Les m\u00e9dias<\/em>120 lumens, 19 heures, 57 m\u00e8tres<\/li><li><em>Baja<\/em>15 lumens, 164 heures, 19 m\u00e8tres<\/li><li><em>Lune<\/em>1 lumen, 45 jours, - m\u00e8tres<\/li><li><em>Strobe<\/em>: \u00bf?<\/li><\/ul>\n\n\n\n<p>A <strong>capteur de proximit\u00e9 <\/strong>diminue automatiquement l'intensit\u00e9 de la lumi\u00e8re et l'\u00e9teint apr\u00e8s 1 minute d'obstruction de l'objectif afin d'\u00e9viter la surchauffe. Cette fonction peut s'av\u00e9rer importante pour \u00e9viter la surchauffe dans votre sac \u00e0 dos ou votre poche si vous l'allumez par erreur. <\/p>\n\n\n\n<p><strong>Indice d'\u00e9tanch\u00e9it\u00e9 IPX8<\/strong>Prot\u00e9g\u00e9 contre l'immersion jusqu'\u00e0 une certaine profondeur, sp\u00e9cifi\u00e9e par le fabricant, g\u00e9n\u00e9ralement jusqu'\u00e0 3 m\u00e8tres.<\/p>\n\n\n\n<p><strong>Deux interrupteurs<\/strong>L'interrupteur lat\u00e9ral (poign\u00e9e) et l'interrupteur de queue. Interrupteur de queue : action rapide gr\u00e2ce \u00e0 cet interrupteur \u00e0 deux niveaux. Vous pouvez activer le turbo rapidement. Interrupteur lat\u00e9ral pratique. <\/p>\n\n\n\n<p><strong>Batterie rechargeable<\/strong>. Le c\u00e2ble de chargement se fixe de mani\u00e8re pratique \u00e0 la queue de la lanterne par aimantation. Il suffit de placer la torche sur le connecteur magn\u00e9tique et de connecter le port USB \u00e0 une source d'alimentation pour que la batterie rechargeable 18650 de 3 500 mAh se charge.<\/p>\n\n\n\n<p>La lanterne <a href=\"https:\/\/amzn.to\/3ogtU4f\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Warrior Mini 2<\/a> a \u00e9t\u00e9 soumis \u00e0 des tests d'impact jusqu'\u00e0<strong> 1,5 m\u00e8tre<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Prix : <strong>107\u00a0\u20ac<\/strong> <\/li><li><a href=\"https:\/\/amzn.to\/3ogtU4f\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Acheter une torche. <\/a><\/li><li><strong style=\"color: initial;\">Note<\/strong><span style=\"color: initial;\">:<\/span><em style=\"color: initial;\"> Ce produit nous a \u00e9t\u00e9 envoy\u00e9 gratuitement pour \u00eatre test\u00e9. Nous n'avons re\u00e7u aucune autre compensation et, comme toujours, toutes les opinions sont les n\u00f4tres (si seulement...). Il se peut que nous gagnions de l'argent gr\u00e2ce aux liens figurant sur cette page (une bonne fa\u00e7on de soutenir le projet), mais nous ne recommandons que les produits que nous approuvons. <\/em><\/li><\/ul>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link\" href=\"https:\/\/amzn.to\/3ogtU4f\" target=\"_blank\" rel=\"nofollow noopener\">Acheter Olight Warrior Mini 2 <\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Guerrier mini 2\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/WZJCEgIyOlo?start=52&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Freyr\">Olight Freyr<\/h2>\n\n\n\n<p>Les<a href=\"https:\/\/amzn.to\/3Hc2fKj\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> Olight Freyr<\/a> est une torche tactique multicolore d'une puissance maximale de 1750 lumens et d'une port\u00e9e de 360 m\u00e8tres (la Warrior Mini 2 atteint 220 m). Un c\u00f4ne de signalisation inclus permet de l'utiliser pour diriger la circulation ou la signalisation, ce qui lui conf\u00e8re une fonctionnalit\u00e9 suppl\u00e9mentaire.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Unboxing du Olight Freyr<\/h3>\n\n\n\n<p>A <em>l'emballage <\/em>excellent : une belle bo\u00eete blanche \u00e0 fermeture magn\u00e9tique avec une photo de la lanterne au recto et des informations techniques au verso.<\/p>\n\n\n\n<p>Que trouve-t-on \u00e0 l'int\u00e9rieur ? La lanterne <a href=\"https:\/\/amzn.to\/3Hc2fKj\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Freyr<\/a>Batterie Olight 21700 custom (\u00e0 l'int\u00e9rieur de la torche), chargeur MCC3 (rouge \u00e0 l'int\u00e9rieur), clip de poche bidirectionnel, c\u00f4ne de signalisation en silicone, \u00e9tui et manuel.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-Freyr_1200x900-1024x768.jpg\" alt=\"Olight Freyr\" class=\"wp-image-28870\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-Freyr_1200x900-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-Freyr_1200x900-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-Freyr_1200x900-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-Freyr_1200x900-150x113.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-Freyr_1200x900-696x522.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-Freyr_1200x900-1068x801.jpg 1068w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-Freyr_1200x900-560x420.jpg 560w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-Freyr_1200x900-80x60.jpg 80w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-Freyr_1200x900-265x198.jpg 265w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-Freyr_1200x900-853x640.jpg 853w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-Freyr_1200x900-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/06\/Olight-Freyr_1200x900.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>La queue est magn\u00e9tique avec le bouton tactique \u00e0 2 positions. Il sert \u00e9galement de point d'attache pour le chargeur MCC. Le corps en alliage d'aluminium comporte des rainures qui lui donnent une texture agressive. Il se plante bien dans la main nue ou avec des gants, et tout aussi bien lorsque la torche est mouill\u00e9e. Le clip peut \u00eatre fix\u00e9 \u00e0 l'une ou l'autre des extr\u00e9mit\u00e9s. La t\u00eate est coll\u00e9e au tube du corps et poss\u00e8de l'interrupteur \u00e9lectronique typique d'Olight. Elle comporte un point sur\u00e9lev\u00e9 au centre, avec un indicateur de niveau de puissance au centre.<\/p>\n\n\n\n<p>Si nous l'analysons en d\u00e9tail, le <a href=\"https:\/\/amzn.to\/3Hc2fKj\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Olight Freyr<\/a> est un hybride entre la Olight Warrior X Pro et la M2R Warrior Pro avec l'ajout de la fonction RGB pour des utilisations plus polyvalentes dans diverses situations de faible luminosit\u00e9. La <a href=\"https:\/\/amzn.to\/3Hc2fKj\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Freyr <\/a>reprend le capuchon arri\u00e8re et le tube du corps de la Olight M2R Pro, avec une nouvelle t\u00eate plus large pour permettre l'utilisation des LED RVB et du capteur de proximit\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Premi\u00e8res impressions<\/h3>\n\n\n\n<p>Les<a href=\"https:\/\/amzn.to\/3Hc2fKj\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> Olight Freyr <\/a>est aussi durable que la Olight M2R et peut r\u00e9sister aux chutes et aux manipulations quotidiennes normales. Test\u00e9e pour une chute de 1,5 m\u00e8tre et certifi\u00e9e \u00e9tanche selon la norme IPX8. <\/p>\n\n\n\n<p>Avec un poids de 202 g et une longueur de 136 mm, il est suffisamment compact et l\u00e9ger pour \u00eatre utilis\u00e9 au quotidien.<\/p>\n\n\n\n<p>Les lumi\u00e8res LED color\u00e9es ajoutent une fonctionnalit\u00e9 suppl\u00e9mentaire, bien qu'en fonction de l'utilisation que vous souhaitez en faire, je pense qu'il ne s'agit que d'un accessoire, et vous devrez peut-\u00eatre vous demander si d'autres mod\u00e8les Olight (par exemple la Warrior Mini 2) ne vous int\u00e9resseraient pas davantage. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fonctionnement<\/h3>\n\n\n\n<p><strong>Une grande puissance dans un petit format<\/strong>La puissance lumineuse atteint 1 750 lumens avec une distance de rayonnement de 360 m\u00e8tres. L'autonomie de la batterie est incroyablement longue, jusqu'\u00e0 15 jours dans l'obscurit\u00e9. <em>lune<\/em> (clair de lune). Les <a href=\"https:\/\/amzn.to\/3Hc2fKj\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Freyr <\/a>poss\u00e8de une LED principale au centre de son optique, puis 3 LED color\u00e9es et un capteur de proximit\u00e9 qui brillent \u00e0 travers des tubes dans l'optique.<\/p>\n\n\n\n<ul class=\"wp-block-list\" id=\"block-5363b347-ea6a-4895-9960-42ae421b8a4f\"><li>Intensit\u00e9 lumineuse - 1750 Lm \/ 300 Lm \/ 5 Lm<\/li><li>Distance de projection - 360m \/ 150m \/ 19m<\/li><li>Candela - 32400 Cd<\/li><li>Lumi\u00e8res RVB - Rouge (30 lm), Vert (60 lm), Bleu (25 lm)<\/li><\/ul>\n\n\n\n<p><strong>Multicolore et polyvalent<\/strong>. En plus de la lumi\u00e8re blanche normale, il est \u00e9galement \u00e9quip\u00e9 de lumi\u00e8res RVB pour r\u00e9agir correctement \u00e0 chaque situation. Une combinaison parfaite avec la baguette de signalisation en silicone incluse. Elle peut \u00eatre int\u00e9ressante au niveau professionnel ou pour la signalisation d'urgence. <\/p>\n\n\n\n<p>Il a<strong> double interrupteur<\/strong>Un interrupteur lat\u00e9ral permet de s\u00e9lectionner une lumi\u00e8re color\u00e9e et d'acc\u00e9der aux diff\u00e9rents niveaux, et un interrupteur arri\u00e8re permet d'actionner tactilement la lumi\u00e8re blanche.<\/p>\n\n\n\n<p>Fonction de <strong>Recharge par USB<\/strong> fait de cette lampe un choix tr\u00e8s \u00e9conomique pour tous les types d'utilisateurs. Aliment\u00e9e par une batterie lithium-ion haute capacit\u00e9 de <strong>5000mAh<\/strong> 3.6V 21700 personnalis\u00e9.<\/p>\n\n\n\n<p>Con\u00e7u pour une utilisation prolong\u00e9e, il tient bien dans la main <strong>solidit\u00e9 et robustesse<\/strong> gr\u00e2ce \u00e0 sa conception compacte en alliage d'aluminium. <strong>R\u00e9sistance certifi\u00e9e<\/strong> \u00e9tanche (IPX8) et r\u00e9sistant aux chutes (1,5 m).<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Prix : <strong><strong><strong>155\u00a0\u20ac<\/strong>\u00a0<\/strong><\/strong><\/li><li><a href=\"https:\/\/amzn.to\/3Hc2fKj\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Acheter une torche <\/a><\/li><li><strong>Note<\/strong>: <em><em>Ce produit nous a \u00e9t\u00e9 envoy\u00e9 gratuitement pour \u00eatre test\u00e9. Nous n'avons re\u00e7u aucune autre compensation et, comme toujours, toutes les opinions sont les n\u00f4tres (si seulement...). Il se peut que nous gagnions de l'argent gr\u00e2ce aux liens figurant sur cette page (une bonne fa\u00e7on de soutenir le projet), mais nous ne recommandons que les produits que nous approuvons.<\/em><\/em><\/li><\/ul>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link\" href=\"https:\/\/amzn.to\/3Hc2fKj\" target=\"_blank\" rel=\"nofollow noopener\">Acheter Olight Freyr <\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"otros-modelos\">Autres mod\u00e8les Olight :<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/amzn.to\/30cP1fe\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Olight Javelot pro<\/a><\/li><li><a href=\"https:\/\/amzn.to\/30cP1fe\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Olight M2R Pro<\/a><\/li><li><a href=\"https:\/\/amzn.to\/30cP1fe\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Olight Warrior x Pro<\/a><\/li><li><a href=\"https:\/\/amzn.to\/30cP1fe\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Olight Warrior Mini<\/a><\/li><\/ul>","protected":false},"excerpt":{"rendered":"Des lanternes de haute qualit\u00e9 et tr\u00e8s innovantes, voil\u00e0 ce que je savais des...","protected":false},"author":191,"featured_media":28872,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"series":[],"class_list":["post-28855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-material"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/06\/Linternas-Olight_1200x900.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"LhwQyuG5jV\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/linternas-olight\/\">[REVIEW] Olight presenta las nuevas linternas: Warrior Mini 2 &#038; Freyr<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/linternas-olight\/embed\/#?secret=LhwQyuG5jV\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0[REVIEW] Olight presenta las nuevas linternas: Warrior Mini 2 &#038; Freyr\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"LhwQyuG5jV\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":21,"label":"Material"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/06\/Linternas-Olight_1200x900-1024x768.jpg",1024,768,true],"author_info":{"display_name":"Eduardo Azcona","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/eduardo-2\/"},"comment_info":0,"category_info":[{"term_id":21,"name":"Material","slug":"material","term_group":0,"term_taxonomy_id":21,"taxonomy":"category","description":"Material","parent":0,"count":51,"filter":"raw","cat_ID":21,"category_count":51,"category_description":"Material","cat_name":"Material","category_nicename":"material","category_parent":0}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/06\/Linternas-Olight_1200x900.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/28855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/191"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=28855"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/28855\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/28872"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=28855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=28855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=28855"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=28855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}