{"id":29342,"date":"2021-07-20T17:00:00","date_gmt":"2021-07-20T15:00:00","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=29342"},"modified":"2021-07-22T23:34:54","modified_gmt":"2021-07-22T21:34:54","slug":"quel-pantalon-de-trekking-choisir-selon-la-saison-de-lannee","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/que-pantalon-de-trekking-elegir-segun-la-estacion-del-ano\/","title":{"rendered":"Quel pantalon de trekking choisir selon la saison de l'ann\u00e9e ?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Le pantalon de trekking est un \u00e9l\u00e9ment essentiel de l'\u00e9quipement n\u00e9cessaire pour pratiquer ce sport dans le confort et la s\u00e9curit\u00e9. Il convient d'accorder l'attention n\u00e9cessaire \u00e0 leurs caract\u00e9ristiques, en tenant compte de facteurs tels que l'itin\u00e9raire \u00e0 suivre et la p\u00e9riode de l'ann\u00e9e \u00e0 laquelle vous allez faire votre trekking, entre autres. Vous devez tenir compte de tous les d\u00e9tails afin d'acqu\u00e9rir un pantalon de trekking de grande qualit\u00e9, qui durera longtemps, qui sera confortable et qui vous prot\u00e9gera.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Caract\u00e9ristiques du pantalon de trekking<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les principales caract\u00e9ristiques d'un bon <strong>pantalon de trekking<\/strong> sont d\u00e9cisifs pour le succ\u00e8s de la marche :<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Protection de l'environnement<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les pantalons de trekking doivent \u00e9galement servir de protection contre les \u00e9l\u00e9ments environnementaux et les chutes \u00e9ventuelles. Il doit \u00eatre renforc\u00e9 aux genoux, \u00e0 l'entrejambe et \u00e0 l'assise, de pr\u00e9f\u00e9rence dans une couleur qui contraste avec celle du pantalon. Ce renfort doit \u00eatre r\u00e9alis\u00e9 en tissu double et de haute r\u00e9sistance, tel que le mod\u00e8le unisexe Prote Fl de la collection de pantalons de randonn\u00e9e. <strong>Marque Trangoworld.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le pantalon doit vous prot\u00e9ger contre :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Les bosses et les chocs :<\/strong> Elles peuvent \u00eatre caus\u00e9es par des pierres, des branches ou des chutes. Le tissu doit \u00eatre solide pour assurer la protection.<\/li><li><strong>Zone lombaire et abdominale :<\/strong> La taille haute de ce pantalon prot\u00e8ge \u00e9galement le bas du dos et l'abdomen, en particulier contre les changements de temps. La partie lombaire de ce pantalon est plus haute que la partie avant.<\/li><li><strong>Protection contre les insectes et les petits animaux :<\/strong> Certains de ces pantalons sont dot\u00e9s d'une sangle de cheville ou d'un syst\u00e8me similaire pour \u00e9viter les piq\u00fbres d'insectes et l'inconfort.<\/li><li><strong>Protection UV :<\/strong> Presque tous les pantalons de trekking offrent une protection contre les UV.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Confort<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Lors d'une marche en montagne, vous effectuez des mouvements que vous n'avez pas l'habitude de faire en ville.<strong> des pantalons qui vous donnent une libert\u00e9 de mouvement sans risque de d\u00e9chirure.<\/strong> Il doit comporter des zones pr\u00e9form\u00e9es, par exemple au niveau des genoux, afin que le pantalon puisse s'adapter \u00e0 tous les mouvements. Il doit \u00eatre fait d'un mat\u00e9riau \u00e9lastique pour plus de confort et d'agilit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les caract\u00e9ristiques \u00e0 rechercher sont les suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Coutures plates et repositionn\u00e9es pour \u00e9viter les frottements dans certaines zones, comme l'int\u00e9rieur des cuisses.<\/li><li>Au niveau de la taille, il est pr\u00e9f\u00e9rable de ne pas avoir de grandes boucles ou d'endroits rigides, mais des boucles de tissu larges et plates, et le dos peut \u00eatre dot\u00e9 d'une boucle en forme d'accord\u00e9on sur toute la longueur de la taille.<\/li><li>Certains ont leur propre ceinture ou syst\u00e8me de r\u00e9glage ; si ce n'est pas le cas, n'utilisez pas de ceinture encombrante.<\/li><li>La taille du pantalon est haute, pour un plus grand confort lors du port du sac \u00e0 dos.<\/li><li>Ils sont hauts au niveau de la taille, pour \u00e9viter que la zone de frottement \u00e9ventuelle du sac \u00e0 dos ne co\u00efncide avec la zone de nos os.<\/li><li>En outre, ils sont plus protecteurs et s'adaptent mieux, ce qui les emp\u00eache de glisser pendant l'utilisation.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">R\u00e9sistance<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ils doivent \u00eatre tr\u00e8s r\u00e9sistants, car ils seront soumis \u00e0 un traitement de haute intensit\u00e9. Outre les frottements et les chutes, ils doivent \u00e9galement pouvoir r\u00e9sister \u00e0 de longues heures de marche, en particulier dans certaines zones, comme l'entrejambe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce sont les trois principales caract\u00e9ristiques qu'un <strong>pantalon de trekking,<\/strong> mais d'autres sont \u00e9galement essentiels :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>L\u00e9g\u00e8ret\u00e9 :<\/strong> Ces pantalons sont g\u00e9n\u00e9ralement tr\u00e8s l\u00e9gers, malgr\u00e9 la protection qu'ils offrent. Cela est d\u00fb aux nouvelles technologies utilis\u00e9es dans la fabrication de ce type de v\u00eatements.<\/li><li><strong>R\u00e9sistance \u00e0 l'humidit\u00e9 :<\/strong> Il doit \u00eatre capable d'\u00e9vacuer rapidement la transpiration et donc de s\u00e9cher rapidement. L'une des caract\u00e9ristiques exceptionnelles des pantalons de trekking est qu'ils n'augmentent pas de poids lorsqu'ils sont mouill\u00e9s ou humides et qu'ils s\u00e8chent rapidement \u00e0 l'air libre.<\/li><li>Il doit \u00e9galement prot\u00e9ger de la pluie s'il s'agit d'un pantalon de trekking, sans \u00eatre n\u00e9cessairement imperm\u00e9able, mais avec un traitement DWR (Durable Water Repellency), qui permet au liquide de rester sur le tissu.<\/li><li><strong>Protection thermique :<\/strong> Cette exigence n'est n\u00e9cessaire que pour les pantalons qui ne sont pas des pantalons 3 saisons. Mais s'ils sont utilis\u00e9s pendant la saison hivernale, ils doivent tenir le bas du corps au chaud.<\/li><li><strong>Poches :<\/strong> Ils sont g\u00e9n\u00e9ralement plats et doivent \u00eatre munis d'un syst\u00e8me de fermeture, soit une fermeture \u00e0 glissi\u00e8re, soit une fermeture velcro.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Pantalon de trekking selon la saison de l'ann\u00e9e<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L'un des principaux facteurs \u00e0 prendre en compte lors du choix d'une <strong><a href=\"https:\/\/xn--outletmontaa-khb.com\/ropa-mujer\/pantalones-trekking-baratos-mujer\/\" target=\"_blank\" rel=\"noreferrer noopener\">pantalon de trekking femme pas cher<\/a>,<\/strong> est la p\u00e9riode de l'ann\u00e9e \u00e0 laquelle il sera port\u00e9, car les pantalons d'\u00e9t\u00e9 ne sont pas les m\u00eames que les pantalons d'hiver.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pantalons pour l'automne et l'hiver<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque la temp\u00e9rature commence \u00e0 baisser, il est n\u00e9cessaire que le pantalon puisse <strong>assurer une protection thermique.<\/strong> Le pantalon doit pouvoir r\u00e9sister aux conditions hivernales. Dans ces conditions, il doit non seulement vous tenir chaud, mais aussi vous prot\u00e9ger du vent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour se prot\u00e9ger de la pluie, il existe deux types de pantalons pr\u00e9sentant les caract\u00e9ristiques suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Softshell :<\/strong> Ils poss\u00e8dent certaines propri\u00e9t\u00e9s thermiques et sont capables d'emp\u00eacher l'eau de s'infiltrer. Il convient de noter qu'ils ne prot\u00e8gent pas contre les fortes pluies.<\/li><li><strong>Coque rigide :<\/strong> Ce pantalon pr\u00e9sente une r\u00e9sistance \u00e9lev\u00e9e \u00e0 l'eau, prot\u00e9geant non seulement de la pluie, mais aussi du vent, et est 100% respirant.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Pantalons pour le printemps et l'\u00e9t\u00e9<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les pantalons de cette saison doivent avoir une excellente respirabilit\u00e9 et offrir une protection contre les rayons UV. En \u00e9t\u00e9, il est tr\u00e8s courant de porter<strong> shorts de trekking,<\/strong> Ils sont plus frais, mais ont aussi leurs inconv\u00e9nients, car ils ne prot\u00e8gent pas contre les \u00e9gratignures et les blessures, ni contre le soleil. Les shorts de trekking sont recommand\u00e9s pour les sentiers et les pistes faciles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a aussi les pantalons convertibles, qui permettent d'enlever chacune des jambes gr\u00e2ce \u00e0 une fermeture \u00e9clair, afin de les porter courtes ou longues en fonction de l'itin\u00e9raire et du temps.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quel pantalon de trekking acheter ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Presque toutes les marques de v\u00eatements et d'accessoires de plein air ont<strong> pantalon de trakking.<\/strong> Cependant, si vous souhaitez un pantalon de trekking avec un excellent rapport qualit\u00e9\/prix, vous devriez vous tourner vers les pantalons Trangoworld, qui offrent une excellente ligne de pantalons que vous pouvez porter en toute saison :<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pantalon unisexe MANASLU<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"737\" height=\"1024\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-manaslu-PC007159-310-737x1024.jpg\" alt=\"\" class=\"wp-image-29344\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-manaslu-PC007159-310-737x1024.jpg 737w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-manaslu-PC007159-310-216x300.jpg 216w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-manaslu-PC007159-310-768x1067.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-manaslu-PC007159-310-1106x1536.jpg 1106w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-manaslu-PC007159-310-150x208.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-manaslu-PC007159-310-300x417.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-manaslu-PC007159-310-696x967.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-manaslu-PC007159-310-1068x1483.jpg 1068w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-manaslu-PC007159-310-302x420.jpg 302w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-manaslu-PC007159-310-600x833.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-manaslu-PC007159-310.jpg 1440w\" sizes=\"auto, (max-width: 737px) 100vw, 737px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ce pantalon est \u00e9lastiqu\u00e9 et ceintur\u00e9, il a une coupe \u00e9troite et des genoux pr\u00e9form\u00e9s pour une protection et une solidit\u00e9 accrues. Les ourlets et les poches lat\u00e9rales sont zipp\u00e9s. Il peut \u00eatre utilis\u00e9 par temps de pluie, car il est d\u00e9perlant.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pantalon unisexe GOYM<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"737\" height=\"1024\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-largo-goym-PC006515-510-737x1024.jpg\" alt=\"\" class=\"wp-image-29345\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-largo-goym-PC006515-510-737x1024.jpg 737w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-largo-goym-PC006515-510-216x300.jpg 216w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-largo-goym-PC006515-510-768x1067.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-largo-goym-PC006515-510-1106x1536.jpg 1106w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-largo-goym-PC006515-510-150x208.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-largo-goym-PC006515-510-300x417.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-largo-goym-PC006515-510-696x967.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-largo-goym-PC006515-510-1068x1483.jpg 1068w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-largo-goym-PC006515-510-302x420.jpg 302w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-largo-goym-PC006515-510-600x833.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-largo-goym-PC006515-510.jpg 1440w\" sizes=\"auto, (max-width: 737px) 100vw, 737px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ce pantalon est dot\u00e9 de poches horizontales, lat\u00e9rales et arri\u00e8re avec fermeture \u00e0 glissi\u00e8re et demi-battement. La taille est \u00e9lastiqu\u00e9e et ceintur\u00e9e. De plus, gr\u00e2ce \u00e0 sa conception, il garde le corps au chaud et offre donc une bonne protection contre le froid.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pantalon unisexe FARGREB<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"737\" height=\"1024\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-fargreb-PC007676-3G0-737x1024.jpg\" alt=\"\" class=\"wp-image-29346\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-fargreb-PC007676-3G0-737x1024.jpg 737w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-fargreb-PC007676-3G0-216x300.jpg 216w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-fargreb-PC007676-3G0-768x1067.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-fargreb-PC007676-3G0-1106x1536.jpg 1106w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-fargreb-PC007676-3G0-150x208.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-fargreb-PC007676-3G0-300x417.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-fargreb-PC007676-3G0-696x967.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-fargreb-PC007676-3G0-1068x1483.jpg 1068w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-fargreb-PC007676-3G0-302x420.jpg 302w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-fargreb-PC007676-3G0-600x833.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/pantalon-fargreb-PC007676-3G0.jpg 1440w\" sizes=\"auto, (max-width: 737px) 100vw, 737px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pantalon tr\u00e8s l\u00e9ger et respirant avec un syst\u00e8me de fronces au niveau des jambes. Il est r\u00e9glable \u00e0 l'arri\u00e8re par un cordon de serrage et les poches lat\u00e9rales se ferment par un zip et un rabat. Le pantalon peut \u00eatre compress\u00e9 pour prendre peu de place dans le sac \u00e0 dos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O\u00f9 acheter<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez trouver plusieurs magasins en ligne et physiques o\u00f9 vous pouvez acheter <strong>pantalon de trekking, <\/strong>d'une grande qualit\u00e9 \u00e0 un prix de vente, tels que le <a href=\"https:\/\/xn--outletmontaa-khb.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">magasin de montagne en ligne Outlet Monta\u00f1a<\/a>qui propose des pantalons pour le trekking, parmi lesquels se distingue la marque Trangoworld. On y trouve non seulement des pantalons, mais aussi des v\u00eatements pour les activit\u00e9s sportives de plein air.<\/p>","protected":false},"excerpt":{"rendered":"Le pantalon de trekking est un \u00e9l\u00e9ment essentiel de l'\u00e9quipement pour cette activit\u00e9 sportive....","protected":false},"author":1,"featured_media":29347,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_wp_convertkit_post_meta":{"form":"-1","landing_page":"0","tag":"0","restrict_content":"0"},"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[],"series":[],"class_list":["post-29342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-material"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/Pantalones-montana_1200x900.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"pMc6WZwh0m\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/que-pantalon-de-trekking-elegir-segun-la-estacion-del-ano\/\">Qu\u00e9 pantal\u00f3n de trekking elegir seg\u00fan la estaci\u00f3n del a\u00f1o<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/que-pantalon-de-trekking-elegir-segun-la-estacion-del-ano\/embed\/#?secret=pMc6WZwh0m\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Qu\u00e9 pantal\u00f3n de trekking elegir seg\u00fan la estaci\u00f3n del a\u00f1o\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"pMc6WZwh0m\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":21,"label":"Material"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/Pantalones-montana_1200x900-1024x768.jpg",1024,768,true],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":21,"name":"Material","slug":"material","term_group":0,"term_taxonomy_id":21,"taxonomy":"category","description":"Material","parent":0,"count":51,"filter":"raw","cat_ID":21,"category_count":51,"category_description":"Material","cat_name":"Material","category_nicename":"material","category_parent":0}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2021\/07\/Pantalones-montana_1200x900.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/29342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=29342"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/29342\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/29347"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=29342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=29342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=29342"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=29342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}