{"id":32958,"date":"2022-04-25T19:10:00","date_gmt":"2022-04-25T17:10:00","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=32958"},"modified":"2022-04-27T13:46:11","modified_gmt":"2022-04-27T11:46:11","slug":"histoires-de-haute-altitude-i-kairos","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/relatos-de-altura-i-kairos\/","title":{"rendered":"Kairos"},"content":{"rendered":"<p><em>Nous poursuivons la publication des micro-r\u00e9cits de la premi\u00e8re \u00e9dition du concours :&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/fr\/concours-de-micro-recits\/\">Histoires de haute altitude<\/a>nous vous laissons profiter de \"Kair\u00f3s\", par&nbsp;<em><em>Aida Bruy Tuneu<\/em><\/em><\/em>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"aqui-y-ahora\"><em>Kairos<\/em><\/h2>\n\n\n\n<p><em>-par&nbsp;<em>Aida Bruy Tuneu<\/em>-<\/em><\/p>\n\n\n\n<p>Et j'\u00e9tais l\u00e0, apr\u00e8s avoir march\u00e9 800 kilom\u00e8tres \u00e0 travers les Pyr\u00e9n\u00e9es pendant 36 jours, \u00e9puis\u00e9, transpirant, sale, affam\u00e9, souffrant. Certains jours, je m'\u00e9tais interrog\u00e9 sur la raison pour laquelle j'avais parcouru le GR11 seul et jusqu'alors, je ne connaissais pas la r\u00e9ponse exacte. Ce fut une exp\u00e9rience difficile, l'itin\u00e9raire m'a pouss\u00e9 \u00e0 la limite. Mais le dernier jour, lorsque j'ai aper\u00e7u le phare du Cap de Creus, j'ai su et ressenti ce qui m'avait pouss\u00e9 \u00e0 entreprendre ce voyage et ce qui m'avait fait pers\u00e9v\u00e9rer. En parcourant les derniers kilom\u00e8tres, je me suis rendu compte que, malgr\u00e9 les difficult\u00e9s et les adversit\u00e9s, je le referais, je marcherais dans les Pyr\u00e9n\u00e9es, ses montagnes, ses vall\u00e9es, ses for\u00eats et ses lacs, et que je voudrais revenir pour jouir de ses paysages uniques, pour ressentir cette euphorie et cette libert\u00e9 que transmettent les montagnes et qui nous font r\u00eaver.<\/p>\n\n\n\n<p>Je suis arriv\u00e9 au bout de mon voyage, apr\u00e8s 800 kilom\u00e8tres. Et j'\u00e9tais l\u00e0, heureux.<\/p>","protected":false},"excerpt":{"rendered":"Nous poursuivons la publication des micro-r\u00e9cits de la premi\u00e8re \u00e9dition du concours : Relatos de Altura,...","protected":false},"author":1,"featured_media":32965,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[54],"tags":[3022],"series":[],"class_list":["post-32958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-microrrelatos"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/04\/Relatos-de-altura-I-Kairos.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"kg5wl13PN7\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/relatos-de-altura-i-kairos\/\">Kair\u00f3s<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/relatos-de-altura-i-kairos\/embed\/#?secret=kg5wl13PN7\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Kair\u00f3s\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"kg5wl13PN7\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":54,"label":"Cultura"}],"post_tag":[{"value":3022,"label":"microrrelatos"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/04\/Relatos-de-altura-I-Kairos-1024x768.jpg",1024,768,true],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":54,"name":"Cultura","slug":"cultura","term_group":0,"term_taxonomy_id":54,"taxonomy":"category","description":"","parent":0,"count":239,"filter":"raw","cat_ID":54,"category_count":239,"category_description":"","cat_name":"Cultura","category_nicename":"cultura","category_parent":0}],"tag_info":[{"term_id":3022,"name":"microrrelatos","slug":"microrrelatos","term_group":0,"term_taxonomy_id":3038,"taxonomy":"post_tag","description":"","parent":0,"count":212,"filter":"raw"}],"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/04\/Relatos-de-altura-I-Kairos.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/32958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=32958"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/32958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/32965"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=32958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=32958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=32958"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=32958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}