{"id":33020,"date":"2021-02-20T11:27:36","date_gmt":"2021-02-20T10:27:36","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=33020"},"modified":"2023-06-13T07:06:09","modified_gmt":"2023-06-13T05:06:09","slug":"le-chemin-de-santiago-en-kayak","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/camino-de-santiago-en-kayak\/","title":{"rendered":"Camino de Santiago en kayak"},"content":{"rendered":"<p>Les formes les plus populaires de p\u00e8lerinage \u00e0 Compostelle sont la marche ou la bicyclette, mais de nos jours, le nombre de p\u00e8lerins int\u00e9ress\u00e9s par le p\u00e8lerinage a augment\u00e9. <strong>Camino de Santiago en kayak.<\/strong> Vous aurez ainsi l'occasion de naviguer dans des paysages \u00e0 couper le souffle et de passer par des parcs \u00e0 palourdes et \u00e0 hu\u00eetres.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ce que vous trouverez en faisant le Camino de Santiago en kayak<\/h2>\n\n\n\n<p>Faire de la <strong>Camino de Santiago en kayak<\/strong> vous permettra de voir des paysages extraordinaires et de camper tout au long de la route dans des endroits \u00e0 couper le souffle face \u00e0 la mer.<\/p>\n\n\n\n<p>Vous pouvez vous baigner, faire de la plong\u00e9e avec masque et tuba, p\u00eacher en kayak et faire des barbecues sur la plage dans des paysages marins \u00e9poustouflants avec des baies peu profondes, des r\u00e9cifs et des criques cach\u00e9es de sable blanc par endroits.<\/p>\n\n\n\n<p>La derni\u00e8re \u00e9tape de la <strong>Camino de Santiago en kayak<\/strong> Il s'agit d'une marche de 25 km jusqu'\u00e0 Saint-Jacques-de-Compostelle, o\u00f9 vous pourrez rejoindre les nombreux p\u00e8lerins qui se rendent \u00e0 la c\u00e9l\u00e8bre cath\u00e9drale et qui ont fait leur voyage \u00e0 pied le long du chemin portugais. Vous pourrez demander le certificat unique d'avoir effectu\u00e9 ce p\u00e8lerinage en kayak.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Itin\u00e9raires du Camino de Santiago en kayak<\/h2>\n\n\n\n<p>Vous pouvez ensuite consulter les itin\u00e9raires que vous pouvez emprunter \u00e0 partir de l'adresse suivante<strong> Camino de Santiago en kayak.<\/strong> Pour certains d'entre eux, aucune exp\u00e9rience pr\u00e9alable en kayak n'est n\u00e9cessaire.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L'itin\u00e9raire de traslatio en kayak<\/h3>\n\n\n\n<p>Il s'agit de l'un des itin\u00e9raires les plus connus pour effectuer la <strong>Camino de Santiago en kayak.<\/strong> Il s'agit de l'itin\u00e9raire final de la variante spirituelle du Chemin portugais. Il est \u00e9galement connu sous le nom de Route maritime ou Route de la mer d'Arousa et de la rivi\u00e8re Ulla.<\/p>\n\n\n\n<p>Cet itin\u00e9raire de la <strong>Camino de Santiago en kayak<\/strong> est le plus populaire pour les agences qui organisent des voyages selon cette modalit\u00e9. Dans certaines d'entre elles, ce circuit est combin\u00e9 avec d'autres activit\u00e9s sportives, telles que la plong\u00e9e avec tuba et la randonn\u00e9e.<\/p>\n\n\n\n<p>S'il est pratiqu\u00e9 par des sp\u00e9cialistes, il n'est pas n\u00e9cessaire d'avoir une exp\u00e9rience pr\u00e9alable du kayak. En revanche, il faut savoir nager et \u00eatre en bonne condition physique pour s'attaquer \u00e0 ce parcours.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Certificat d'accr\u00e9ditation<\/h4>\n\n\n\n<p>Cette route maritime poss\u00e8de son propre certificat qui garantit le p\u00e8lerinage le long de l'estuaire. Ce document est connu sous le nom de Traslatio.<\/p>\n\n\n\n<p>Le certificat est d\u00e9livr\u00e9 par le bureau des p\u00e8lerins de Padr\u00f3n \u00e0 tous ceux qui parcourent un minimum de 40 milles nautiques. Pour l'obtenir, il faut apposer le cachet de la carte de p\u00e8lerin dans au moins trois endroits diff\u00e9rents entre Pontevedra et la Corogne.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Chemin c\u00f4tier portugais en kayak<\/h3>\n\n\n\n<p>La route c\u00f4ti\u00e8re portugaise est la route qui longe la c\u00f4te atlantique du Portugal. Ce tron\u00e7on de la <strong>Le chemin de Saint-Jacques<\/strong> peut \u00e9galement se faire en kayak.<\/p>\n\n\n\n<p>Cependant, peu d'agences proposent cet itin\u00e9raire dans leur offre de voyages organis\u00e9s. Pour faire la route c\u00f4ti\u00e8re portugaise en kayak par soi-m\u00eame, il faut avoir une exp\u00e9rience de la navigation et disposer de l'\u00e9quipement n\u00e9cessaire.<\/p>\n\n\n\n<p>Pour planifier cet itin\u00e9raire, il faut \u00e9tudier les conditions maritimes et m\u00e9t\u00e9orologiques, car vous naviguerez en mer.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Camino de Santiago del Norte en kayak<\/h3>\n\n\n\n<p>Le Chemin de Saint-Jacques-de-Compostelle est un autre des itin\u00e9raires c\u00f4tiers de l'Union europ\u00e9enne. <strong>Camino de Santiago.<\/strong> Il est donc possible de le faire en kayak.<\/p>\n\n\n\n<p>En raison des caract\u00e9ristiques de la mer Cantabrique, cet itin\u00e9raire est recommand\u00e9 lorsque la mer est calme. Normalement, cela se produit \u00e0 la fin du printemps, en \u00e9t\u00e9 et au d\u00e9but de l'automne.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le chemin des balises en kayak<\/h3>\n\n\n\n<p>Le Chemin des Phares est un autre des itin\u00e9raires qui peuvent \u00eatre parcourus en kayak. Bien qu'il ne soit pas consid\u00e9r\u00e9 comme un chemin jacquaire, si vous le faites en kayak et que vous effectuez le p\u00e8lerinage \u00e0 pied ou \u00e0 v\u00e9lo de Finisterre \u00e0 Santiago, vous pourrez poser votre candidature pour la Compostela.<\/p>\n\n\n\n<p>Cet itin\u00e9raire longe la c\u00f4te galicienne connue sous le nom de Costa da Morte. Dans cette r\u00e9gion de Galice, la mer est forte. C'est pourquoi il est recommand\u00e9 de ne r\u00e9aliser cette exp\u00e9rience qu'avec une agence sp\u00e9cialis\u00e9e dans le kayak.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quelle est la meilleure p\u00e9riode pour faire du kayak sur le Chemin de Saint-Jacques ?<\/h2>\n\n\n\n<p>Le meilleur moment pour faire le<strong> Camino de Santiago en kayak,<\/strong> est de la fin du printemps et de l'\u00e9t\u00e9, c'est-\u00e0-dire de mai \u00e0 la mi-septembre. \u00c0 cette \u00e9poque, les temp\u00e9ratures sont g\u00e9n\u00e9ralement plus \u00e9lev\u00e9es, ce qui signifie que le soleil et la chaleur vous accompagnent en permanence pendant le voyage.<\/p>\n\n\n\n<p>Ces mois sont \u00e9galement id\u00e9aux car c'est la p\u00e9riode des vacances, vous y trouverez donc des touristes du monde entier. Les groupes de kayakistes ont g\u00e9n\u00e9ralement v\u00e9cu plus d'aventures.<\/p>\n\n\n\n<p>En faisant ce parcours tous les jours, vous pourrez vous adapter au kayak et vous verrez qu'il n'est pas n\u00e9cessaire d'\u00eatre en bonne forme physique ou d'avoir d\u00e9j\u00e0 pratiqu\u00e9 ce sport.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p>Gr\u00e2ce aux informations que vous avez obtenues sur les <strong>Chemin de Saint-Jacques en kayak,<\/strong> vous pouvez planifier votre p\u00e8lerinage dans ce mode de navigation. Pour ce faire, vous devez utiliser ces informations afin d'\u00e9valuer les itin\u00e9raires disponibles et de d\u00e9cider lequel est le plus adapt\u00e9 \u00e0 vos int\u00e9r\u00eats.<\/p>","protected":false},"excerpt":{"rendered":"Les moyens les plus populaires de faire le p\u00e8lerinage \u00e0 Compostelle sont la marche ou le v\u00e9lo, mais...","protected":false},"author":954,"featured_media":33051,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2945,1],"tags":[],"series":[],"class_list":["post-33020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-camino-de-santiago","category-sin-categoria"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/04\/camino-de-santiago-en-kayak.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"rMmZvPLCSo\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/camino-de-santiago-en-kayak\/\">Camino de Santiago en kayak<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/camino-de-santiago-en-kayak\/embed\/#?secret=rMmZvPLCSo\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Camino de Santiago en kayak\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"rMmZvPLCSo\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":2945,"label":"Camino de Santiago"},{"value":1,"label":"Sin categor\u00eda"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/04\/camino-de-santiago-en-kayak-1024x556.jpg",1024,556,true],"author_info":{"display_name":"Moises Campos","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/moises-campos\/"},"comment_info":0,"category_info":[{"term_id":2945,"name":"Camino de Santiago","slug":"camino-de-santiago","term_group":0,"term_taxonomy_id":2961,"taxonomy":"category","description":"Camino de Santiago","parent":2930,"count":60,"filter":"raw","cat_ID":2945,"category_count":60,"category_description":"Camino de Santiago","cat_name":"Camino de Santiago","category_nicename":"camino-de-santiago","category_parent":2930},{"term_id":1,"name":"Sin categor\u00eda","slug":"sin-categoria","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":207,"filter":"raw","cat_ID":1,"category_count":207,"category_description":"","cat_name":"Sin categor\u00eda","category_nicename":"sin-categoria","category_parent":0}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/04\/camino-de-santiago-en-kayak.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/33020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/954"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=33020"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/33020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/33051"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=33020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=33020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=33020"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=33020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}