{"id":34989,"date":"2023-05-19T05:14:00","date_gmt":"2023-05-19T03:14:00","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=34989"},"modified":"2024-01-24T13:49:40","modified_gmt":"2024-01-24T12:49:40","slug":"joc-oca","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/joc-oca\/","title":{"rendered":"Le ravin du Joc de l'Oca"},"content":{"rendered":"\n<p><font size=\"+1\">El paso del tiempo ha formado en Montserrat muchos barrancos, canales y cuevas. Algunas de estas hendiduras caprichosas se pueden recorrer sin ayuda de ning\u00fan medio t\u00e9cnico, pero hay otras para las que necesitaremos pertrecharnos con equipaci\u00f3n de barranquismo. Una de estas brechas \u00abt\u00e9cnicas\u00bb de esta monta\u00f1a, es el conocido como barranco del <strong>Joc de l&#8217;Oca<\/strong>.<\/font><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Traducido como Juego de la Oca, el nombre le viene del esfuerzo tit\u00e1nico que supon\u00eda subir el barranco, que era como jugar al famoso juego e ir de casilla en casilla, remontando  cuerdas y cadenas. Actualmente, este barranco ha sido desequipado en sentido ascendente, debido a los frecuentes rescates de gente que se quedaba atrapada, hoy en d\u00eda,  solo se puede descender.<\/p>\n\n\n\n<p style=\"color:#c45a25\"><b>CONTRATAR UN GU\u00cdA ES LA OPCI\u00d3N INTELIGENTE<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El barranquismo es una actividad que no est\u00e1 exenta de riesgos, que exige conocer bien el medio en el que se desenvuelve, y por supuesto, las propias limitaciones f\u00edsicas y t\u00e9cnicas del grupo. Cuando uno no est\u00e1 capacitado, contratar los servicios de un gu\u00eda es la opci\u00f3n inteligente. Pero si adem\u00e1s la gu\u00eda es nuestra amiga <strong>Noelia Novoa<\/strong>, la persona que hay detr\u00e1s de&nbsp;<strong><a href=\"https:\/\/www.barrancslopallars.com\/portfolio-items\/barranco-joc-de-loca\/\" target=\"_blank\" rel=\"noreferrer noopener\">Barrancs lo Pallars<\/a><\/strong>, entonces la experiencia ser\u00e1 plena. 100% recomendable.<\/p>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box34989_99fee6-7d .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box34989_99fee6-7d .kt-blocks-info-box-link-wrap{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box34989_99fee6-7d.wp-block-kadence-infobox{max-width:100%;}.kt-info-box34989_99fee6-7d .kadence-info-box-image-inner-intrisic-container{max-width:100px;}.kt-info-box34989_99fee6-7d .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:400px;height:0px;max-width:100%;}.kt-info-box34989_99fee6-7d .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box34989_99fee6-7d .kt-info-svg-icon-flip, .kt-info-box34989_99fee6-7d .kt-blocks-info-box-number{font-size:50px;}.kt-info-box34989_99fee6-7d .kt-blocks-info-box-media{border-color:var(--global-palette7, #eeeeee);border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box34989_99fee6-7d .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box34989_99fee6-7d .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box34989_99fee6-7d .kt-infobox-textcontent h3.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box34989_99fee6-7d .kt-blocks-info-box-text{font-weight:400;}.kt-info-box34989_99fee6-7d .kt-blocks-info-box-learnmore{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box34989_99fee6-7d\"><a class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.barrancslopallars.com\/barrancos-guiados\/\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/Noe-perfil-2b.jpg\" alt=\"\" width=\"400\" height=\"400\" class=\"kt-info-box-image wp-image-35306\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/Noe-perfil-2b.jpg 400w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/Noe-perfil-2b-300x300.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/Noe-perfil-2b-150x150.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/Noe-perfil-2b-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">\u00abDescubre los barrancos de moda en Catalu\u00f1a\u00bb<\/h3><p class=\"kt-blocks-info-box-text\">Desde nivel iniciaci\u00f3n a nivel avanzado. <br\/>Pincha en el siguiente enlace para ver mi propuesta de actividades. <br\/><\/p><div class=\"kt-blocks-info-box-learnmore-wrap\"><span class=\"kt-blocks-info-box-learnmore\">Ver actividades<\/span><\/div><\/div><\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>ITINERARIO: aproximaci\u00f3n + barranco + retorno<\/strong><\/h2>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/travesiapirenaica.com\/rutas\/rutas.php?&amp;ruta=joc-oca\" allow=\"fullscreen\" width=\"100%\" height=\"400\"><\/iframe>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"has-background\" style=\"background-color:#eeeeee;padding:10px\"><span style=\"color:#c45a25\"><strong>GU\u00cdA PR\u00c1CTICA<\/strong><\/span><br><strong><u>Distancia:<\/u><\/strong> 5,7km (unos 650m de barranco)<br><strong><u>Desnivel:<\/u><\/strong> +350m \/ -350m (unos 180m de barranco)<br><strong><u>Horario:<\/u><\/strong> unas 4-5 horas. En la aproximaci\u00f3n invertiremos algo m\u00e1s de <u>una hora<\/u>. El barranco depende de nuestra experiencia y puede rondar las <u>dos horas<\/u>. El retorno es de unos <u>45 minutos<\/u>.\n<br><strong><u>Dificultad:<\/u><\/strong> dificultad del barranco V3a1 III.\n<br><strong><u>Inicio\/Final:<\/u><\/strong> parking <strong><a href=\"https:\/\/www.google.es\/maps\/place\/Restaurant+Vinyanova\/@41.5831906,1.808976,17z\/data=!3m1!4b1!4m6!3m5!1s0x12a4618ef6f82d51:0x9e134b3a449dccc1!8m2!3d41.5831906!4d1.808976!16s%2Fg%2F1q5bpk4bv?hl=es\" target=\"_blank\" rel=\"noopener\">Vinya Nova<\/a><\/strong><br><strong><u>\u00c9poca del a\u00f1o:<\/u><\/strong> cualquiera. Vigilar si ha llovido, si la roca est\u00e1 h\u00fameda puede dificultar el avance.<br><strong><u>Equipo t\u00e9cnico necesario:<\/u><\/strong> arn\u00e9s de barranquismo, casco, descendedor ocho, mosquetones, guantes y cuerdas para la actividad.<br><strong><u>Agencia recomendada:<\/u><\/strong> <a href=\"https:\/\/www.barrancslopallars.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Barrancs lo Pallars<\/a><\/strong>. Tel. +34 657 994 821 <a href=\"mailto:barrancslopallars@gmail.com\" target=\"_blank\" rel=\"noreferrer noopener\">barrancslopallars@gmail.com<\/a><\/p><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La aproximaci\u00f3n al barranco&#8230;<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La ma\u00f1ana comenz\u00f3 en un bar de <strong><a href=\"https:\/\/www.google.es\/maps\/place\/08293+Collbat%C3%B3,+Barcelona\/@41.566929,1.8054722,15z\/data=!3m1!4b1!4m6!3m5!1s0x12a46018cd98938d:0x4d87c114a63040d!8m2!3d41.5644495!4d1.8147696!16s%2Fg%2F11bc5z7mw0?hl=es\" target=\"_blank\" rel=\"noreferrer noopener\">Collbat\u00f3<\/a><\/strong>, que utilizamos como punto de encuentro. Para llegar a esta localidad de la falda de Montserrat, que dista unos 48 km de Barcelona, fuimos por la A-2. Aqu\u00ed nos montamos todos en un veh\u00edculo y nos desplazamos al inicio del itinerario, el parking de <strong><a href=\"https:\/\/www.google.es\/maps\/place\/Restaurant+Vinyanova\/@41.5831906,1.8067873,17z\/data=!3m1!4b1!4m6!3m5!1s0x12a4618ef6f82d51:0x9e134b3a449dccc1!8m2!3d41.5831906!4d1.808976!16s%2Fg%2F1q5bpk4bv?hl=es\" target=\"_blank\" rel=\"noreferrer noopener\">Vinya Nova<\/a><\/strong>, en el municipio vecino de El Bruc. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noelia y Sergio (t\u00e9cnico ayudante), nos distribuyeron nuestra parte del equipo, el arn\u00e9s, los guantes y los cascos. Ellos en sus \u00abmochilones\u00bb transportaban las cuerdas y el resto de los pertrechos. Comenzamos a caminar por una pista hasta llegar al inicio del \u00abcam\u00ed dels francesos o del bassals dels gats\u00bb. Toda la monta\u00f1a est\u00e1 llena de top\u00f3nimos que hacen referencia a la invasi\u00f3n francesa de 1812.<\/p>\n\n\n\n<div class=\"has-background\" style=\"background-color:#eeeeee;padding:10px\"><p><em>En esta zona de la monta\u00f1a se inspira la <strong>leyenda del \u00abTimbaler del Bruc\u00bb <\/strong>, que relata la victoria de un pu\u00f1ado de combatientes de la zona, frente al ej\u00e9rcito franc\u00e9s. Gracias a la reverberaci\u00f3n ac\u00fastica de la monta\u00f1a, los tambores de la poblaci\u00f3n local hicieron creer a los franceses que sus efectivos eran mayores y se dieron a la fuga. Se cree que est\u00e1 inspirada en hechos reales.<\/em><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comenzamos a subir de manera bastante acusada, son unos 45 minutos por un camino serpenteante. Con la torrentera debajo de nosotros, primero entre pinos y m\u00e1s tarde por un encinar. A nuestro lado vemos la \u00abAjaguda\u00bb (tumbada o recostada en castellano), aguja rocosa con un peque\u00f1o agujero. Cogemos un desv\u00edo a la izquierda y llegamos al Coll del Bassal dels Gats.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/ajaguda-1024x768.jpg\" alt=\"\" class=\"wp-image-35172\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/ajaguda-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/ajaguda-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/ajaguda-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/ajaguda-1536x1152.jpg 1536w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/ajaguda-2048x1536.jpg 2048w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/ajaguda-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">La aguja \u00abAjaguda\u00bb con su caracter\u00edstico \u00abagujero\u00bb causado por los fen\u00f3menos atmosf\u00e9ricos<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/Coll-bassal-gats-1024x768.jpg\" alt=\"\" class=\"wp-image-35001\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/Coll-bassal-gats-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/Coll-bassal-gats-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/Coll-bassal-gats-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/Coll-bassal-gats-1536x1152.jpg 1536w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/Coll-bassal-gats-2048x1536.jpg 2048w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/Coll-bassal-gats-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Panor\u00e1mica desde el Coll dels Bassals dels Gats: el Montgr\u00f2s y los \u00abPlecs de Llibre\u00bb (pliegues de libro, ya que se asemeja a estos) en la parte izquierda. En medio el torrente del Migd\u00eda, por el que bajaremos y a  la derecha la Albarda Castellana.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de recuperar el aliento, continuamos por el sendero en bajada, acompa\u00f1ados por el encinar con boj hasta llegar al canal de Migdia. En esta hendidura que separa el macizo en dos partes queda un reducto de la vegetaci\u00f3n primitiva de la monta\u00f1a, tejos, acebos y arces crecen de manera aislada. Vamos a la izquierda hasta llegar al principio del barranco. Un poco antes nos sorprende una v\u00edbora hocicuda. Estos animales siempre han estado muy mitificados y gozan de mala fama. <\/p>\n\n\n\n<div class=\"has-background\" style=\"background-color:#eeeeee;padding:10px\"><p><em>En Montserrat, hay una leyenda que hace referencia al conocido como \u201c<strong> Pla dels escur\u00e7ons<\/strong>\u201d (explanada de las v\u00edboras, situada encima del monasterio). Esta leyenda est\u00e1 recogida en el libro \u00abLlegendes i tradicions de Montserrat\u00bb de Joan Amades. En \u00e9l explica que todas las v\u00edboras de Catalu\u00f1a iban a reproducirse a este lugar de Montserrat. Como todas estas serpientes eran nacidas aqu\u00ed, siempre miraban a Montserrat, estuvieran donde estuvieran. Los cazadores de v\u00edboras, para cogerles la \u00abpiedra viborera\u00bb (que ten\u00edan en la cabeza de propiedades curativas), la pod\u00edan extraer sin miedo si las atrapaban del lado que miraba a la monta\u00f1a sagrada. La abundancia de estos reptiles era tal que hab\u00eda m\u00e1s v\u00edboras, que rocas, y si una v\u00edbora tocaba una hierba, esta cog\u00eda propiedades curativas. Estas v\u00edboras solo muerden si eran tocadas y los remedios, seg\u00fan la tradici\u00f3n, pod\u00edan ser de dos tipos: quemar la parte herida con brasas o coger la v\u00edbora, machacarla hasta hacer una cataplasma para poner encima de la herida. De esta forma, la carne del reptil atrapar\u00e1 su propio veneno. Ya lo dice el refr\u00e1n: \u00abPicada d&#8217;escur\u00e7\u00f3, no hi es a temps l&#8217;extremunci\u00f3\u00bb. La pod\u00edamos traducir como: si te pica una v\u00edbora, no est\u00e1s a tiempo de la extremaunci\u00f3n.<\/em><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por toda la zona de Montserrat podemos encontrar la v\u00edbora hocicuda, con una peque\u00f1a protuberancia en la cabeza (de ah\u00ed posiblemente sale el t\u00e9rmino \u00abpiedra viborera\u00bb). Son serpientes de peque\u00f1o tama\u00f1o, dotadas de un veneno peligroso, pero que suelen huir con facilidad. Evidentemente, solo la fotografiamos y la dejamos en paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG_20200705_104329-1024x768.jpg\" alt=\"\" class=\"wp-image-35065\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG_20200705_104329-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG_20200705_104329-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG_20200705_104329-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG_20200705_104329-1536x1152.jpg 1536w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG_20200705_104329-2048x1536.jpg 2048w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG_20200705_104329-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">La cabeza triangular con su \u00abcuerno\u00bb, el peque\u00f1o tama\u00f1o y el dise\u00f1o en zigzag caracterizan a la v\u00edbora hocicuda.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora comenzaba la parte interesante. La primera parte es un senderito encajonado y llegamos a un cartel informativo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/1664393029065-768x1024.jpg\" alt=\"\" class=\"wp-image-35012\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/1664393029065-768x1024.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/1664393029065-225x300.jpg 225w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/1664393029065-1152x1536.jpg 1152w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/1664393029065-600x800.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/1664393029065.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Noelia, la l\u00edder de la expedici\u00f3n, encabezando el primer tramo del descenso a pie. <\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Barranco, parte t\u00e9cnica<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de empezar con la cr\u00f3nica del descenso comentar un poco las caracter\u00edsticas t\u00e9cnicas del barranco. Son 650 metros de recorrido por un lecho seco, en el cual descenderemos 180 metros de desnivel negativo, para ello necesitaremos hacer 13 r\u00e1peles y alg\u00fan descenso sin ayuda de cuerdas. La clasificaci\u00f3n en la jerarqu\u00eda barranquista, es <strong>V3a1 III<\/strong>, V3 hace referencia a la verticalidad, la escala va de 1 a 7. El 3 ser\u00eda poco dif\u00edcil, ya que los r\u00e1peles son inferiores a 30 metros y los pasos de escalada son poco expuestos. El 1 que viene a continuaci\u00f3n, indica que es un barranco seco. Y el III en numeraci\u00f3n romana, nos marcar\u00eda el compromiso y la envergadura. Estos valores van de I a VII, donde III nos indica que la escapatoria del recorrido nos invertir\u00eda una hora m\u00e1xima de recorrido y el tiempo total oscilar\u00eda entre 4 y 8 horas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este barranco forma parte del desaf\u00edo \u00ab<strong><a href=\"https:\/\/www.feec.cat\/activitats\/50-barrancs\/\" target=\"_blank\" rel=\"noreferrer noopener\">50 barrancs<\/a><\/strong>\u00bb promovido por la FEEC (Federaci\u00f3 d&#8217;entitats excursionistes de Catalunya). Este reto consiste en completar la m\u00e1xima cantidad de barrancos posibles por el territorio catal\u00e1n. Actualmente, hay 73 propuestas, de las cuales 5 son en Montserrat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Empezamos con la parte t\u00e9cnica, pasamos unos carteles informativos y vamos \u00abdesgrimpando\u00bb unos tramos encajonados con la ayuda de manos, piernas y la protecci\u00f3n de resistencia del arn\u00e9s. Un poco m\u00e1s tarde pasamos por un caos de bloques y por un \u00abagujero\u00bb. Y ya nos encontramos con el primer <strong>r\u00e1pel<\/strong> de 15 metros. Luego el r\u00e1pel 2 de 5 metros. El r\u00e1pel 3 de 8 metros. El r\u00e1pel 4 de 15 metros, el r\u00e1pel 5 de 10 metros, el r\u00e1pel 6 de 15 metros y el r\u00e1pel 7 de 15 metros. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/1664393028883-768x1024.jpg\" alt=\"\" class=\"wp-image-35064\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/1664393028883-768x1024.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/1664393028883-225x300.jpg 225w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/1664393028883-1152x1536.jpg 1152w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/1664393028883-600x800.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/1664393028883.jpg 1512w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">El recorrido es espectacular, encajonados en la monta\u00f1a<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/1664393028865-768x1024.jpg\" alt=\"\" class=\"wp-image-35026\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/1664393028865-768x1024.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/1664393028865-225x300.jpg 225w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/1664393028865-1152x1536.jpg 1152w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/1664393028865-600x800.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/1664393028865.jpg 1512w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">El descenso es en todo momento fiable, cuenta con todas las medidas de seguridad, ya que el barranco se encuentra equipado con reuniones con cadena de anclaje qu\u00edmico, por donde se pasan las cuerdas. <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora tenemos un peque\u00f1o descanso y bajamos entre rocas unos 50 metros. Estamos en el r\u00e1pel 8 de unos 15 metros, el primer trozo es encajonado y no pudimos pasar con la mochila. En la segunda parte bajas \u00absuspendido\u00bb y llegas a una peque\u00f1a cueva. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG-20200705-WA0004-768x1024.jpg\" alt=\"\" class=\"wp-image-35030\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG-20200705-WA0004-768x1024.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG-20200705-WA0004-225x300.jpg 225w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG-20200705-WA0004-1152x1536.jpg 1152w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG-20200705-WA0004-600x800.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG-20200705-WA0004.jpg 1488w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Aqu\u00ed despu\u00e9s de descender a la peque\u00f1a cueva. M\u00e1s tarde, Noelia hace bajar la mochila.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00fan nos quedaba el r\u00e1pel 9 de 10 metros y el r\u00e1pel 10 de 15 metros. Caminamos un trocito m\u00e1s a ratos ayud\u00e1ndonos de las manos y llegamos al r\u00e1pel 11 de 15 metros. Nos deja en  una peque\u00f1a repisa de piedra, donde tenemos el r\u00e1pel 12 de 18 metros. Y ya estamos en el \u00faltimo r\u00e1pel del barranco, el 13 con sus 11 metros.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG-20200705-WA0008-768x1024.jpg\" alt=\"\" class=\"wp-image-35032\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG-20200705-WA0008-768x1024.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG-20200705-WA0008-225x300.jpg 225w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG-20200705-WA0008-1152x1536.jpg 1152w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG-20200705-WA0008-600x800.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/IMG-20200705-WA0008.jpg 1488w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Nuestro \u00faltimo r\u00e1pel, el 13, es bastante vertical.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El retorno&#8230;<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez acabada la parte t\u00e9cnica a\u00fan nos quedaba un trecho de sendero. Pasamos a tocar de la cueva \u00ab<strong>Degotalls de Can Jorba<\/strong>\u00bb y continuamos descendiendo hasta llegar a Can Jorba. Ahora salimos a una pista que en sentido izquierdo nos llevar\u00e1 hasta el punto de partida en <a href=\"https:\/\/www.google.es\/maps\/place\/Restaurant+Vinyanova\/@41.5831906,1.8067873,17z\/data=!3m1!4b1!4m6!3m5!1s0x12a4618ef6f82d51:0x9e134b3a449dccc1!8m2!3d41.5831906!4d1.808976!16s%2Fg%2F1q5bpk4bv?hl=es\" target=\"_blank\" rel=\"noopener\">V<strong>inya Nova<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora solo nos quedaba recorrer en coche los pocos kil\u00f3metros, donde hab\u00edamos dejado nuestro veh\u00edculo. Y como ya era la hora de comer, decidimos acabar la jornada comiendo juntos en un bar de la zona y relatando las diferentes peripecias de la jornada. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cerca de aqu\u00ed te puede interesar:<\/h3>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:29% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"666\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/IMG_2673-copia-1024x666.jpg\" alt=\"Sant Jeroni, el Mirador del Moro y la Albarda Castellana, desde la cima del Montgr\u00f3s\" class=\"wp-image-34815 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/IMG_2673-copia-1024x666.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/IMG_2673-copia-300x195.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/IMG_2673-copia-768x500.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/IMG_2673-copia-1536x999.jpg 1536w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/IMG_2673-copia-2048x1332.jpg 2048w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/IMG_2673-copia-600x390.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<a href=\"https:\/\/travesiapirenaica.com\/sant-jeroni-monasterio-montserrat\/\"><strong>Circular desde el monasterio de Montserrat a Sant Jeroni y la Albarda Castellana<\/strong><\/a><p>Si quieres conocer la monta\u00f1a de Montserrat y empezar por un recorrido impresionante, la subida a Sant Jeroni (1.236m), el techo de Montserrat, ser\u00eda el recomendado. [3h30min; 11,7km; +\/-760m].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:29% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/portada-1024x768.jpg\" alt=\"Montserrat, desde Collbat\u00f3. Foto: Rafa L\u00f3pez Mart\u00edn\" class=\"wp-image-33923 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/portada-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/portada-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/portada-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/portada-150x113.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/portada-696x522.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/portada-1068x801.jpg 1068w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/portada-560x420.jpg 560w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/portada-80x60.jpg 80w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/portada-265x198.jpg 265w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/portada-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/11\/portada.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<a href=\"https:\/\/travesiapirenaica.com\/circular-por-montserrat-desde-collbato\/\"><strong>Circular por Montserrat. Caminos, ermitas y agujas rocosas.<\/strong><\/a><p>Ruta por Montserrat desde Collbat\u00f3, en la vertiente sur del macizo [5h30min; 14,6km; +\/-1.269m].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:29% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/01\/01_portada-1024x768.jpg\" alt=\"\" class=\"wp-image-39399 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/01\/01_portada-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/01\/01_portada-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/01\/01_portada-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/01\/01_portada-1536x1152.jpg 1536w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/01\/01_portada-2048x1536.jpg 2048w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/01\/01_portada-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<a href=\"https:\/\/travesiapirenaica.com\/circular-agulles-montserrat\/\"><strong>Circular a les Agulles y els Frares Encantats desde Can Ma\u00e7ana<\/strong><\/a><p>Can Ma\u00e7ana &#8211; Collet de Can Guirl\u00f3 &#8211; Roca Foradada &#8211; Coll de Port\/Porc &#8211; Refugio Vicen\u00e7 Barb\u00e9 &#8211; Collet de Can Guirl\u00f3 &#8211; Can Ma\u00e7ana. [3h20min; 7,5km; +\/-470m]<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"Canyon sec - Niveau moyen - Dur\u00e9e totale : 5-6 h. Approche : 60\u2032 env. Descente : 2-3 h. Retour : 40\u2032.","protected":false},"author":1141,"featured_media":34994,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_wp_convertkit_post_meta":{"form":"-1","landing_page":"0","tag":"0","restrict_content":"0"},"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3067],"tags":[3026,3053,3060,3059],"series":[],"class_list":["post-34989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-barranquismo","tag-cataluna","tag-catalunya","tag-montserrat","tag-rutas"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/1664393029147-copia.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"uBYSPRRa1C\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/joc-oca\/\">El barranco del Joc de l&#8217;Oca<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/joc-oca\/embed\/#?secret=uBYSPRRa1C\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0El barranco del Joc de l&#8217;Oca\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"uBYSPRRa1C\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":3067,"label":"Barranquismo"}],"post_tag":[{"value":3026,"label":"Catalu\u00f1a"},{"value":3053,"label":"catalunya"},{"value":3060,"label":"Montserrat"},{"value":3059,"label":"Rutas"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/1664393029147-copia-768x1024.jpg",768,1024,true],"author_info":{"display_name":"Rafa L\u00f3pez Mart\u00edn","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/rafalopez\/"},"comment_info":0,"category_info":[{"term_id":3067,"name":"Barranquismo","slug":"barranquismo","term_group":0,"term_taxonomy_id":3083,"taxonomy":"category","description":"","parent":0,"count":7,"filter":"raw","cat_ID":3067,"category_count":7,"category_description":"","cat_name":"Barranquismo","category_nicename":"barranquismo","category_parent":0}],"tag_info":[{"term_id":3026,"name":"Catalu\u00f1a","slug":"cataluna","term_group":0,"term_taxonomy_id":3042,"taxonomy":"post_tag","description":"","parent":0,"count":22,"filter":"raw"},{"term_id":3053,"name":"catalunya","slug":"catalunya","term_group":0,"term_taxonomy_id":3069,"taxonomy":"post_tag","description":"","parent":0,"count":7,"filter":"raw"},{"term_id":3060,"name":"Montserrat","slug":"montserrat","term_group":0,"term_taxonomy_id":3076,"taxonomy":"post_tag","description":"","parent":0,"count":16,"filter":"raw"},{"term_id":3059,"name":"Rutas","slug":"rutas","term_group":0,"term_taxonomy_id":3075,"taxonomy":"post_tag","description":"","parent":0,"count":27,"filter":"raw"}],"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/1664393029147-copia.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/34989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1141"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=34989"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/34989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/34994"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=34989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=34989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=34989"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=34989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}