{"id":39015,"date":"2024-01-02T23:59:52","date_gmt":"2024-01-02T22:59:52","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=39015"},"modified":"2025-02-23T23:02:43","modified_gmt":"2025-02-23T22:02:43","slug":"nous-recherchons2023","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/buscamos2023\/","title":{"rendered":"Nous recherchons ce lieu : 2023"},"content":{"rendered":"\n<p id=\"block-0492b27a-7ed2-4e18-a58e-577c116ef4d5\">Al igual que ya hici\u00e9ramos en a\u00f1os anteriores, comenzamos este 2024 con un recopilatorio de todos aquellos lugares que os propusimos averiguar cada semana.<\/p>\n\n\n\n<p id=\"block-c15b4d1d-5028-4444-ad9d-77c13a739aba\">La soluci\u00f3n, como siempre, la pod\u00edais encontrar en la newsletter semanal que os compartimos los jueves. Pero, por si os alguno se ha perdido alguna, aqu\u00ed est\u00e1n los 45 lugares escogidos en 2023.<\/p>\n\n\n<style>.kadence-column39015_6608e0-1b{max-width:565px;margin-left:auto;margin-right:auto;}.wp-block-kadence-column.kb-section-dir-horizontal:not(.kb-section-md-dir-vertical)>.kt-inside-inner-col>.kadence-column39015_6608e0-1b{-webkit-flex:0 1 565px;flex:0 1 565px;max-width:unset;margin-left:unset;margin-right:unset;}.kadence-column39015_6608e0-1b > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column39015_6608e0-1b > .kt-inside-inner-col{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}.kadence-column39015_6608e0-1b > .kt-inside-inner-col,.kadence-column39015_6608e0-1b > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column39015_6608e0-1b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column39015_6608e0-1b > .kt-inside-inner-col{flex-direction:column;}.kadence-column39015_6608e0-1b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column39015_6608e0-1b > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column39015_6608e0-1b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column39015_6608e0-1b{position:relative;}@media all and (min-width: 1025px){.wp-block-kadence-column.kb-section-dir-horizontal>.kt-inside-inner-col>.kadence-column39015_6608e0-1b{-webkit-flex:0 1 565px;flex:0 1 565px;max-width:unset;margin-left:unset;margin-right:unset;}}@media all and (max-width: 1024px){.kadence-column39015_6608e0-1b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.wp-block-kadence-column.kb-section-sm-dir-vertical:not(.kb-section-sm-dir-horizontal):not(.kb-section-sm-dir-specificity)>.kt-inside-inner-col>.kadence-column39015_6608e0-1b{max-width:565px;-webkit-flex:1;flex:1;margin-left:auto;margin-right:auto;}.kadence-column39015_6608e0-1b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column39015_6608e0-1b inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id39015_4cae30-47 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id39015_4cae30-47 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id39015_4cae30-47 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, calc(55% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(45% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id39015_4cae30-47 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id39015_4cae30-47 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id39015_4cae30-47 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id39015_4cae30-47 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column39015_4c3c60-eb > .kt-inside-inner-col,.kadence-column39015_4c3c60-eb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column39015_4c3c60-eb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column39015_4c3c60-eb > .kt-inside-inner-col{flex-direction:column;}.kadence-column39015_4c3c60-eb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column39015_4c3c60-eb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column39015_4c3c60-eb{position:relative;}@media all and (max-width: 1024px){.kadence-column39015_4c3c60-eb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column39015_4c3c60-eb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column39015_4c3c60-eb inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-image39015_7fab40-fe.kb-image-is-ratio-size, .kb-image39015_7fab40-fe .kb-image-is-ratio-size{max-width:482px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image39015_7fab40-fe.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image39015_7fab40-fe .kb-image-is-ratio-size{align-self:unset;}.kb-image39015_7fab40-fe{max-width:482px;}.image-is-svg.kb-image39015_7fab40-fe{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image39015_7fab40-fe img{width:100%;}.kb-image39015_7fab40-fe .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image39015_7fab40-fe size-large rounded-corners\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/01\/Blue-and-Pink-Soft-Magazine-Cover-Mockup-Instagram-Post-1-1024x1024.png\" alt=\"\" class=\"kb-img wp-image-46232\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/01\/Blue-and-Pink-Soft-Magazine-Cover-Mockup-Instagram-Post-1-1024x1024.png 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/01\/Blue-and-Pink-Soft-Magazine-Cover-Mockup-Instagram-Post-1-300x300.png 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/01\/Blue-and-Pink-Soft-Magazine-Cover-Mockup-Instagram-Post-1-150x150.png 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/01\/Blue-and-Pink-Soft-Magazine-Cover-Mockup-Instagram-Post-1-768x768.png 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/01\/Blue-and-Pink-Soft-Magazine-Cover-Mockup-Instagram-Post-1-12x12.png 12w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/01\/Blue-and-Pink-Soft-Magazine-Cover-Mockup-Instagram-Post-1-600x600.png 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/01\/Blue-and-Pink-Soft-Magazine-Cover-Mockup-Instagram-Post-1-100x100.png 100w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/01\/Blue-and-Pink-Soft-Magazine-Cover-Mockup-Instagram-Post-1-96x96.png 96w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2025\/01\/Blue-and-Pink-Soft-Magazine-Cover-Mockup-Instagram-Post-1.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column39015_8056bf-0a > .kt-inside-inner-col,.kadence-column39015_8056bf-0a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column39015_8056bf-0a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column39015_8056bf-0a > .kt-inside-inner-col{flex-direction:column;}.kadence-column39015_8056bf-0a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column39015_8056bf-0a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column39015_8056bf-0a{position:relative;}@media all and (max-width: 1024px){.kadence-column39015_8056bf-0a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column39015_8056bf-0a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column39015_8056bf-0a inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading39015_b57592-14, .wp-block-kadence-advancedheading.kt-adv-heading39015_b57592-14[data-kb-block=\"kb-adv-heading39015_b57592-14\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading39015_b57592-14 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading39015_b57592-14[data-kb-block=\"kb-adv-heading39015_b57592-14\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading39015_b57592-14 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading39015_b57592-14[data-kb-block=\"kb-adv-heading39015_b57592-14\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h5 class=\"kt-adv-heading39015_b57592-14 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading39015_b57592-14\">25 <em>SPOTS FOTOGR\u00c1FICOS <\/em>en los Pirineos \ud83d\udcf8<\/h5>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading39015_6ff1ae-f2, .wp-block-kadence-advancedheading.kt-adv-heading39015_6ff1ae-f2[data-kb-block=\"kb-adv-heading39015_6ff1ae-f2\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading39015_6ff1ae-f2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading39015_6ff1ae-f2[data-kb-block=\"kb-adv-heading39015_6ff1ae-f2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading39015_6ff1ae-f2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading39015_6ff1ae-f2[data-kb-block=\"kb-adv-heading39015_6ff1ae-f2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading39015_6ff1ae-f2 wp-block-kadence-advancedheading has-theme-palette-5-color has-text-color\" data-kb-block=\"kb-adv-heading39015_6ff1ae-f2\">Acceso a mapa <strong>Google Maps<\/strong> \ud83d\udccccon las localizaciones m\u00e1s emblem\u00e1ticas en la cordillera pirenaica<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #74:<\/h2>\n\n\n\n<p>Continuamos por el Pirineo navarro, esta vez en busca del lugar desde el que ha sido tomado esta fotograf\u00eda. \u00bfLo reconoces? Los picos del fondo son los primeros dosmiles viniendo desde el Cant\u00e1brico.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/12\/lugar074.jpg\" alt=\"\" class=\"wp-image-34338 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/12\/lugar074.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/12\/lugar074-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/12\/lugar074-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/12\/lugar074-150x113.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/12\/lugar074-696x522.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/12\/lugar074-560x420.jpg 560w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/12\/lugar074-80x60.jpg 80w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/12\/lugar074-265x198.jpg 265w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2022\/12\/lugar074-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Su cima est\u00e1 coronada por un v\u00e9rtice geod\u00e9sico.<\/li>\n\n\n\n<li>Ninguna otra cima supera a esta en altitud de aqu\u00ed al Cant\u00e1brico.<\/li>\n\n\n\n<li>Cerca de aqu\u00ed tuvo lugar una famosa batalla, desastrosa para las tropas de Carlomagno.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>La fotograf\u00eda de la semana pasada estaba tomada desde la cima de Ortzanzurieta (1.565m), el pico m\u00e1s alto de las monta\u00f1as situadas entre Roncesvalles y la Selva de Irati. Un pico del que hace tiempo os tra\u00edamos una <a href=\"https:\/\/travesiapirenaica.com\/urkulu-ortzanzurieta\/\">ruta desde la Real F\u00e1brica de Municiones de Orbaizeta<\/a> y en la que visit\u00e1bamos varios lugares con un importante atractivo hist\u00f3rico y natural.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #75:<\/h2>\n\n\n\n<p>La monta\u00f1a que buscamos esta semana es una de esas que para subir, hay que gan\u00e1rsela. Se trata de un pico tranquilo, solitario, que pasa algo desapercibido por la proximidad de otras monta\u00f1as m\u00e1s conocidas.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar075.jpg\" alt=\"\" class=\"wp-image-34430 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar075.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar075-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar075-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar075-150x113.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar075-696x522.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar075-560x420.jpg 560w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar075-80x60.jpg 80w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar075-265x198.jpg 265w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar075-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Como dec\u00edamos, nuestra monta\u00f1a tiene pocos pretendientes por varios motivos. Entre otros: no es la m\u00e1s alta ni la m\u00e1s conocida de la zona, tiene marchas de aproximaci\u00f3n muy largas por cualquiera de sus rutas, mucho desnivel y presenta alg\u00fan pasito de escalada.<\/li>\n\n\n\n<li>Este pico recibe dos nombres igualmente conocidos.<\/li>\n\n\n\n<li>Si accedemos a ella por la vertiente sur, lo haremos pasando por el ib\u00f3n del mismo nombre.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>El pico que busc\u00e1bamos la semana pasada era la Pala de Alca\u00f1iz o Pico Bucuesa (2.765m). Se encuentra en el pirineo oscense, a caballo entre los valles de Canfranc (r\u00edo Arag\u00f3n) y Acumuer (r\u00edo Aur\u00edn), cerrando el circo de Ip. Probablemente la presencia de otras monta\u00f1as m\u00e1s altas como el Collarada y la Pala de Ip, as\u00ed como de otras m\u00e1s bellas como Punta Escarra, restan pretendientes a una monta\u00f1a que ya de por s\u00ed requiere de demasiado esfuerzo para atraer a la muchedumbre.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #76:<\/h2>\n\n\n\n<p>El lugar de esta semana nos lo env\u00eda Miguel Hern\u00e1ndez, una fotograf\u00eda tomada a los pies de \u00abel Monarca\u00bb en la que, apuntando hacia abajo del valle, sobresale la monta\u00f1a que estamos buscando.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar076.jpg\" alt=\"\" class=\"wp-image-34465 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar076.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar076-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar076-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar076-150x113.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar076-696x522.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar076-560x420.jpg 560w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar076-80x60.jpg 80w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar076-265x198.jpg 265w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/01\/lugar076-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>El pico que estamos buscando es como un faro, siempre visible al recorrer este valle.<\/li>\n\n\n\n<li>Su posici\u00f3n enfrentada a los \u00abMontes Malditos\u00bb, la convierten en un privilegiado mirador del macizo.<\/li>\n\n\n\n<li>En invierno, el valle desde el que est\u00e1 tomada la fotograf\u00eda se convierte en una pista de esqu\u00ed n\u00f3rdico.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>La monta\u00f1a que os ped\u00edamos averiguar la semana pasada era el Mall Pintrat o Tuca del Puerto Viello de Gorgutes (2.845m). Su posici\u00f3n avanzada hacia el valle de Benasque, dominando toda la zona de los Llanos del Hospital y marcando la entrada al valle de Remu\u00f1e, hace que sea un pico muy visible, no por ello muy visitado. Una buena opci\u00f3n para esos d\u00edas en los que el valle est\u00e1 a tope.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #77:<\/h2>\n\n\n\n<p>Una piedra en el camino&#8230;, no, no, no os pong\u00e1is a cantar. Esta semana os proponemos encontrar una piedra, pero no una cualquiera, esta piedra de arenisca roja tiene una inscripci\u00f3n que con un poco de esfuerzo quiz\u00e1s alcanc\u00e9is a leer.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar077.jpg\" alt=\"\" class=\"wp-image-34505 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar077.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar077-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar077-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar077-150x113.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar077-696x522.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar077-560x420.jpg 560w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar077-80x60.jpg 80w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar077-265x198.jpg 265w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar077-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>La inscripci\u00f3n es una advertencia dirigida a los soldados que guarnec\u00edan la frontera.<\/li>\n\n\n\n<li>El mugarri en cuesti\u00f3n se halla a pie de ruta <a href=\"https:\/\/travesiapirenaica.com\/gr11\/gr11.php\">GR11\/Senda Pirenaica<\/a>.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>El hito que busc\u00e1bamos la semana pasada era el Moj\u00f3n de Soroeta o De los Desertores, el cual tiene grabada la siguiente inscripci\u00f3n que reproducimos separando con punto y coma cada l\u00ednea: DESDE; AQUI LA; DESERCI; ON TIE; NE PE; NA DE; LA VI: DA.<br>Al parecer, seg\u00fan Serapio M\u00fagica, su origen se remonta al siglo XVIII, cuando las deserciones a Francia por parte de los soldados que defend\u00edan la frontera eran bastante frecuentes. Si quer\u00e9is saber m\u00e1s, pod\u00e9is encontrar m\u00e1s informaci\u00f3n de este moj\u00f3n y de otros que hay por la zona en el blog <a href=\"http:\/\/bidasoatxingudi.blogspot.com\/2008\/11\/los-mojones-y-las-lindes.html\" target=\"_blank\" rel=\"noreferrer noopener\">Bidasoa-Txingudi<\/a> de Ricardo Berodia.<strong><\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #78:<\/h2>\n\n\n\n<p>Los tres picos que os pedimos averiguar esta semana son f\u00e1cilmente reconocibles, aunque no tanto desde esta perspectiva, &nbsp;y con esto ya ten\u00e9is la primera pista.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar078.jpg\" alt=\"\" class=\"wp-image-34542 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar078.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar078-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar078-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar078-150x113.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar078-696x522.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar078-560x420.jpg 560w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar078-80x60.jpg 80w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar078-265x198.jpg 265w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar078-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Estas tres cimas forman una trilog\u00eda de picos indisoluble.<\/li>\n\n\n\n<li>Estamos viendo la cara norte.<\/li>\n\n\n\n<li>Para su origen tenemos dos explicaciones igualmente incre\u00edbles, la m\u00e1s reciente apunta a la orogenia alpina, la m\u00e1s antigua y con aires de divinidad, a que se tratar\u00eda en realidad de tres j\u00f3venes muchachas petrificadas.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Quiz\u00e1s alguno de vosotros pens\u00f3 al leer las pistas que nos est\u00e1bamos refiriendo a las Tres Sorores o Treserols, pero no, a tan solo 6kms de ese lugar tenemos una trilog\u00eda mucho m\u00e1s modesta conocida como Las Tres Mar\u00edas o Tucas de Sesa, y que por separado tienen tambi\u00e9n su propio nombre. De Este a Oeste, como aparec\u00edan en la foto: Zuca Plana (2702m), Zuca Roncha (2757m) y Zuca Punchuda (2781 m).<\/p>\n\n\n\n<p><br>Alberto Martinez Embid, en su libro \u00ab<a href=\"https:\/\/www.amazon.es\/Monte-perdido-historia-gigante-pirenaico\/dp\/8489969981\/ref=sr_1_4?__mk_es_ES=%25C3%2585M%25C3%2585%25C5%25BD%25C3%2595%25C3%2591&amp;crid=2BWVZ130V71HC&amp;keywords=Monte+Perdido&amp;qid=1676480963&amp;s=books&amp;sprefix=monte+perdid\" target=\"_blank\" rel=\"noreferrer noopener\">Monte Perdido, Historia y mitos del gigante pirenaico<\/a>\u00ab, recog\u00eda dos leyendas, o m\u00e1s bien, dos versiones con id\u00e9ntico resultado de una misma leyenda, que explicaban un supuesto origen divino de esta triada de picos. En la primera versi\u00f3n, se tratar\u00eda de las tres hijas del Rey moro de Zaragoza (Mohamed Altabill), que huyendo del islam deseosas de abrazar el cristianismo, quedaron sepultadas en ese lugar bajo un alud de nieve y roca cuando sus perseguidores estaban a punto de darles caza. En la segunda versi\u00f3n, se tratar\u00eda de tres mujeres v\u00edrgenes que prisioneras en una cueva, tambi\u00e9n por Mohamed Altabill, clamaron al cielo y fueron transformadas en monta\u00f1as recubiertas de nieve, s\u00edmbolo de pureza y virtud femenina.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #79:<\/h2>\n\n\n\n<p>Mediados de febrero suele ser por lo general, una \u00e9poca ideal para la escalada en nieve y hielo en los Pirineos. Por si es el caso y se dan las condiciones, esta semana os traemos entre las pistas dos propuestas muy interesantes de ascender a esta monta\u00f1a. \u00bfLa reconoces?<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar079.jpg\" alt=\"\" class=\"wp-image-34558 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar079.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar079-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar079-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar079-150x113.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar079-696x522.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar079-560x420.jpg 560w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar079-80x60.jpg 80w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar079-265x198.jpg 265w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar079-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>La primera v\u00eda a la que hacemos referencia asciende por el centro de la pir\u00e1mide de la izquierda y es conocida como la de la Cara Norte (AD+ a D-). Esta v\u00eda finaliza en la cumbre del pico despu\u00e9s de recorrer un tramo final de arista, y fue abierta en el verano de 1976 por J.A Romero, P.Alcay y E.Enmanuel, y repetida en el invierno de 1983 por S.Le\u00f3n y J.A.Romero.<\/li>\n\n\n\n<li>El segundo corredor asciende por el centro del contrafuerte situado a la derecha. Es una l\u00ednea evidente pero algo m\u00e1s dif\u00edcil que la anterior (D+), y que desde que fuese abierta en 1990 por Julio Armesto, Enrique Villasur y Tom\u00e1s Uriguen, no ha dejado de repetirse, convirti\u00e9ndose en una s\u00faper cl\u00e1sica de la zona.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>La monta\u00f1a que busc\u00e1bamos la semana pasada era la Pe\u00f1a Sabocos (2.751m), la cumbre m\u00e1s destacada en la parte occidental de la Sierra de Tende\u00f1era y que domina por el sur el pueblo y las pistas de esqu\u00ed de Panticosa. Precisamente, la presencia de las pistas acerca en gran medida a esta monta\u00f1a, acortando notablemente la aproximaci\u00f3n de las v\u00edas que os propon\u00edamos, Cara Norte (AD+ a D-) y Panticosa Ice (D+).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #80:<\/h2>\n\n\n\n<p>No cambiamos de valle. Ya sab\u00e9is d\u00f3nde nos encontramos si averiguasteis el buscamos de la semana pasada, o nos le\u00e9is a trav\u00e9s de la newsletter semanal \u00abAires de Altura\u00bb en la que cada semana revelamos la respuesta.<br>Esta semana continuamos poni\u00e9ndoos los dientes largos con otro bonito corredor, una l\u00ednea muy elegante y asequible (AD+) que desemboca en la misma cima de este pico.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar080.jpg\" alt=\"\" class=\"wp-image-34583 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar080.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar080-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar080-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar080-150x113.jpg 150w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar080-696x522.jpg 696w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar080-560x420.jpg 560w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar080-80x60.jpg 80w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar080-265x198.jpg 265w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/02\/lugar080-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Nos encontramos en el mismo valle de la semana pasada.<\/li>\n\n\n\n<li>En la zona existe otro pico con el mismo nombre.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>El lugar que busc\u00e1bamos la semana pasada era el Corredor Oeste (200m; AD+) al Pico Serrato (2.888m). Una forma elegante de alcanzar este pico situado cerca del Balneario de Panticosa en invierno. Las principales dificultades de la v\u00eda se concentran al inicio (65\u00ba), donde puede haber algun paso en roca de III+ si no hay suficiente nieve.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #81:<\/h2>\n\n\n\n<p>Tras los dos corredores que os propon\u00edamos hace un par de semanas a la Pe\u00f1a Sabocos (Cara Norte y Panticosa Ice), y el de la semana pasada al Pico Serrato, continuamos por el valle de Tena con el que podr\u00edamos considerar, la joya de la corona en su dificultad. Dicho esto, como ser\u00eda demasiado f\u00e1cil si adem\u00e1s os ponemos una buena foto del corredor, os tendr\u00e9is que conformar con ver su entrada.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar081.jpg\" alt=\"\" class=\"wp-image-34733 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar081.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar081-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar081-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar081-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Este famoso corredor se encuentra en el valle de Tena, en una de las geol\u00f3gicamente conocidas como Sierras Interiores.<\/li>\n\n\n\n<li>El nombre de este corredor no es muy original que digamos. Ese mismo nombre lo podemos encontrar en otras monta\u00f1as como Untzillaitz, Pedraforca, Balait\u00fas o Raymond D\u2019Espouy, entre otras.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Por supuesto, el corredor de la semana pasada era la Gran Diagonal a Pe\u00f1a Telera. Uno de los corredores m\u00e1s largos (700m) que podemos hacer en los Pirineos con una dificultad que oscila seg\u00fan la gu\u00eda consultada y las condiciones, entre AD y AD+. Un supercl\u00e1sico que no os puede faltar si practic\u00e1is la escalada en nieve y hielo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #82:<\/h2>\n\n\n\n<p>Casi sin cambiar de valle continuamos con otra propuesta invernal que se suma a las de las \u00faltimas semanas por el valle de Tena. En este caso, nuestra monta\u00f1a se sit\u00faa en la divisoria entre el citado valle y su vecino, si bien es cierto, el corredor se encuentra en este segundo valle.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/01\/lugar082.jpg\" alt=\"\" class=\"wp-image-39037 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/01\/lugar082.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/01\/lugar082-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/01\/lugar082-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/01\/lugar082-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>El pico se encuentra a caballo entre el valle de Tena y otro valle.<\/li>\n\n\n\n<li>Aunque muy cerca hay otros picos m\u00e1s altos, esta monta\u00f1a es muy apreciada por su altiva silueta, no por ello muy frecuentada. Quiz\u00e1s es porque se encuentra un poco lejos de todo y para alcanzar su cima hay que trepar un poco.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Efectivamente, el lugar de la semana pasada era el corredor norte a Punta Escarra. Un corredor sencillo (PD) de 250 metros con una inclinaci\u00f3n m\u00e1xima de 55\u00ba, un cl\u00e1sico del esqu\u00ed de monta\u00f1a. La subida hasta la cumbre es m\u00e1s complicada (AD) con varios tramos de mixto. En invierno la aproximaci\u00f3n se reduce considerablemente desde el aparcamiento de Sarrios (Formigal), <a href=\"https:\/\/travesiapirenaica.com\/escarra-balsera\/\">en verano, la ruta m\u00e1s interesante es la que parte desde Canfranc<\/a>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #83:<\/h2>\n\n\n\n<p>Bonito verdad, el lugar nos pareci\u00f3 tan bonito que lleva 7 a\u00f1os ocupando la portada de la p\u00e1gina principal del <a href=\"https:\/\/travesiapirenaica.com\/gr11\/gr11.php\">GR11<\/a>. Y eso que ten\u00edamos 800 kil\u00f3metros donde elegir, unos 1000 contando las variantes.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar083-1024x683.jpg\" alt=\"\" class=\"wp-image-34809 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar083-1024x683.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar083-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar083-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar083-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar083.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Se encuentra en Huesca la Magia.<\/li>\n\n\n\n<li>Para proteger este lugar existe un proyecto de Parque Natural que al parecer, para el Gobierno de Arag\u00f3n, ha caducado.<\/li>\n\n\n\n<li>Se pretende malgastar el 78% de los fondos europeos de los Planes de Sostenibilidad Tur\u00edstica destinados a todo Arag\u00f3n, a destruir este lugar \u00fanico, con la instalaci\u00f3n de un telesilla, 37 pilonas, una estaci\u00f3n intermedia de grandes dimensiones y el consiguiente trasiego de maquinaria.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>El buscamos de la semana pasada no pod\u00eda ser otro que Canal Roya, el lugar que pone a t\u00edtulo a nuestro art\u00edculo principal de esta semana: Salvemos Canal Roya. En la fotograf\u00eda podemos ver el Plano de la Rinconada con Espelunciecha al fondo y el Pico de Anayet a la derecha en primer plano.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #84:<\/h2>\n\n\n\n<p>Esta semana nos desplazamos al Pirineo oriental, donde este nos muestra su lado m\u00e1s Mediterr\u00e1neo y donde aunque ya no tenga la altura que alcanzaba en las comarcas centrales catalanas, se muestra igualmente abrupto y salvaje.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar084-1024x768.jpg\" alt=\"\" class=\"wp-image-34924 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar084-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar084-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar084-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar084-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar084.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>La monta\u00f1a que veis en la fotograf\u00eda no es especialmente alta, ni siquiera dentro de la zona en la que se encuentra.<\/li>\n\n\n\n<li>Nos encontramos muy cerca del l\u00edmite de las comarcas de la Alta Garrotxa y el Alt Empord\u00e0.<\/li>\n\n\n\n<li>A sus pies se encuentra un peque\u00f1o monasterio, hoy deshabitado, fundado en el a\u00f1o 859 por una comunidad de monjes benedictinos.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>La monta\u00f1a que ve\u00edamos la semana anterior era el Puig d\u2019en Coll (1.031m). Como os dec\u00edamos en las pistas, este pico no es de los m\u00e1s elevados de la zona pero, su car\u00e1cter individualizado le confiere cierto aire importante y la verdad, nos pareci\u00f3 muy bonito cuando lo fotografiamos mientras recorr\u00edamos la <a href=\"https:\/\/travesiapirenaica.com\/gr11\/talaixa-albanya.php\">etapa del GR11 entre Talaix\u00e0 y Albany\u00e0<\/a>. Por cierto, el monasterio al que hac\u00edamos referencia en las pistas era Sant Aniol d\u2019Aguja.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #85:<\/h2>\n\n\n\n<p>La primavera es la \u00e9poca ideal para visitar cascadas. La monta\u00f1a se deshace del manto blanco que ha vestido durante el invierno y la nieve, ahora transformada en agua, desciende impetuosa por valles y barrancos.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"767\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar085.jpg\" alt=\"\" class=\"wp-image-35242 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar085.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar085-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar085-768x575.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/03\/lugar085-600x449.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>En el valle de Ordesa son famosas las cascadas de la Cola de Caballo, de la cueva, las Gradas de Soaso y muchas m\u00e1s, pero no tanto esta de la fotograf\u00eda.<\/li>\n\n\n\n<li>Se sit\u00faa en la mitad menos visitada de este valle.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>El lugar que ve\u00edamos la semana pasada era la cascada de Abetos, una de las numerosas cascadas que podremos ver en el <a href=\"https:\/\/travesiapirenaica.com\/rutas-por-ordesa-monte-perdido\/\">valle de Ordesa<\/a>, si en lugar de coger el bus para acceder a la Pradera, tomamos el camino de Turieto Bajo, el camino utilizado anta\u00f1o antes de la construcci\u00f3n de la carretera.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #86:<\/h2>\n\n\n\n<p>La monta\u00f1a que buscamos esta semana es, si no la primera, una de las primeras del Pirineo por Occidente, como salta a la vista en esta fotograf\u00eda tomada desde la orilla del mar en Hondarribia.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/lugar086.jpg\" alt=\"\" class=\"wp-image-35328 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/lugar086.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/lugar086-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/lugar086-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/lugar086-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>La cumbre de esta gran monta\u00f1a, a pesar de no llegar a 1000 metros, destaca por unas impresionantes vistas 360\u00ba que alcanzan hasta el Pirineo Central, como por lo decepcionante de la misma, afeada por la presencia de un repetidor, un helipuerto, un par de ventas y hasta un tren cremallera por el que cada fin de semana acceden decenas de turistas.<\/li>\n\n\n\n<li>Por su cumbre pasa la <a href=\"https:\/\/travesiapirenaica.com\/arp\/pirineooccidental\/hendaya-lizuniaga.html\">primera etapa de la Alta Ruta Pirenaica<\/a>.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>La fotograf\u00eda que ve\u00edamos la semana pasada tomada desde la orilla del mar, en Hondarribia, era del monte Lar\u00fan (901m), tambi\u00e9n llamado Larr\u00fan, Larh\u00fan o La Rhune. Una monta\u00f1a que a pesar de su modesta altitud tiene una prominencia nada despreciable de 670 metros y un desnivel de 870 metros si la subimos desde Bera.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #87:<\/h2>\n\n\n\n<p>Pocas cimas resultan tan ic\u00f3nicas como esta que os mostramos esta semana. Su silueta no pasa inadvertida para el caminante o el escalador que de inmediato, fijar\u00e1 sus ojos en esta especie de muela fracturada.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/lugar087.jpg\" alt=\"\" class=\"wp-image-35427 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/lugar087.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/lugar087-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/lugar087-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/04\/lugar087-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Se encuentra en el Parque Natural de los Valles Occidentales.<\/li>\n\n\n\n<li>Es una monta\u00f1a muy visible desde el GR11.1.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>La monta\u00f1a de la semana pasada eran los Mallos de Lecherines (2.452m), con el pico Rig\u00fcelo (2.299m) en primer t\u00e9rmino. Desde luego se trata de una monta\u00f1a singular, comparada muchas veces con una fortaleza o una muela, como os dec\u00edamos en la descripci\u00f3n. La v\u00eda normal asciende por su cara Este, por la chimenea Faus (PD). Para llegar a ella se suele acceder por cercan\u00eda por el valle de A\u00edsa, pasando por el refugio L\u00f3pez Huici, o con m\u00e1s esfuerzo desde Canfranc. En ambos casos siguiendo el GR11.1.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #88:<\/h2>\n\n\n\n<p>La fotograf\u00eda de esta semana es cortes\u00eda de Pintxo, que dice as\u00ed: \u00abnos encontramos frente a uno de esos lugares que quedan grabados en la retina, uno de esos paisajes de cuento a los que uno no se cansa de volver en invierno o en verano, con las primeras nieves o con el deshielo\u00bb.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar088.jpg\" alt=\"\" class=\"wp-image-36778 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar088.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar088-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar088-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar088-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Se encuentra en el Pirineo oscense.<\/li>\n\n\n\n<li>Este valle tiene una inusual orientaci\u00f3n Sur-Norte, despu\u00e9s gira.<\/li>\n\n\n\n<li>El valle es atravesado por el GR11.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>El lugar de la semana pasada era el valle de Aguas Tuertas, situado en el extremo occidental del Pirineo aragon\u00e9s, dentro del Parque Natural de los Valles Occidentales y perteneciente al municipio de Ans\u00f3.<\/p>\n\n\n\n<p>El valle de Aguas Tuertas, aparte de ser un lugar de gran belleza por los espectaculares meandros que ha dibujado el r\u00edo, resulta muy curioso desde un punto de vista geol\u00f3gico. Se trata de un valle glaciar en el que, tras retirarse la lengua de hielo, qued\u00f3 al descubierto una cubeta de sobreexcavaci\u00f3n que origin\u00f3 un ib\u00f3n y que, con el paso del tiempo y la sedimentaci\u00f3n, fue totalmente colmatado originando este fondo plano que hoy podemos contemplar, por el que divaga el Arag\u00f3n Subord\u00e1n.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #89:<\/h2>\n\n\n\n<p>Esta semana os pedimos averiguar qu\u00e9 lago es este de aguas oscuras, como sugiere su nombre nada casual y su no menos oscura leyenda.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar089.jpg\" alt=\"\" class=\"wp-image-35876 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar089.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar089-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar089-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar089-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>El lago fue represado en 1934 y utilizado para la producci\u00f3n energ\u00e9tica.<\/li>\n\n\n\n<li>Se encuentra en el Principado de Andorra.<\/li>\n\n\n\n<li>Bordeando su orilla discurre el GR11.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>El lugar que os ped\u00edamos averiguar la semana pasada era el lago de Engolasters, situado en la parroquia de Encamp, en el Principado de Andorra. Se trata de un bonito lugar para realizar peque\u00f1as excursiones o visitar con ni\u00f1os, y donde seg\u00fan cuenta una oscura leyenda, en el fondo del mismo existi\u00f3 un poblado, hoy engullido por el fango. Si quer\u00e9is descubrir que pas\u00f3, precisamente esta semana hemos preparado un art\u00edculo sobre la <a href=\"https:\/\/travesiapirenaica.com\/leyenda-engolasters\/\">Leyenda del lago de Engolasters<\/a>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #90:<\/h2>\n\n\n\n<p>La fotograf\u00eda de esta semana es algo complicada, ya que adem\u00e1s, esta no es la versi\u00f3n del pico a la que normalmente estamos m\u00e1s acostumbrados. En cualquier caso, la fotograf\u00eda es bonita, y si con ella conseguimos que alguien se anime a descubrir este rinc\u00f3n salvaje de los Pirineos Atl\u00e1nticos, habremos hecho una buena labor.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar090.jpg\" alt=\"\" class=\"wp-image-35878 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar090.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar090-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar090-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar090-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>La cara que estamos observando es la norte.<\/li>\n\n\n\n<li>El valle por el que se introducen las nubes es la cabecera de uno de los barrancos m\u00e1s bellos, visitados y fotog\u00e9nicos de todo el Pirineo.<\/li>\n\n\n\n<li>Por unas pocas decenas de metros, su cima no alcanza los 2000 metros de altura.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>El pico que os mostr\u00e1bamos era Otsogorrigaina (1.920m), que puede traducirse como Alto del Oso Rojo, aunque Otso, tambi\u00e9n pudiera traducirse por lobo. Es un pico que hace un tiempo os recomend\u00e1bamos en un art\u00edculo sobre <a href=\"https:\/\/travesiapirenaica.com\/pirineos-picos-solitarios-valles-occidentales\/\">Picos Solitarios en la parte occidental del Pirineo<\/a> y que como dec\u00edamos en las pistas, se encuentra en la cabecera de uno de los barrancos m\u00e1s bellos de todo el Pirineo. Nos refer\u00edamos por supuesto, a las <a href=\"https:\/\/travesiapirenaica.com\/pasarela-holtzarte\/\">Gorgues de Holtzarte<\/a>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #91:<\/h2>\n\n\n\n<p>La fotograf\u00eda de esta semana no hace justicia a la magia de este lugar, un gran sumidero k\u00e1rstico por el que misteriosamente desaparecen las aguas de los glaciares del monarca pirenaico.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar091-1024x768.jpg\" alt=\"\" class=\"wp-image-36042 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar091-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar091-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar091-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar091-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar091.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>El agua de este r\u00edo, que por la orograf\u00eda natural del terreno debiera acabar en el Mediterr\u00e1neo, acaba sorprendentemente en el oc\u00e9ano Atl\u00e1ntico.<\/li>\n\n\n\n<li>Este lugar est\u00e1 \u00edntimamente ligado a otro situado en el valle de Ar\u00e1n.<\/li>\n\n\n\n<li>No es exactamente una pista pero, si el famoso espele\u00f3logo franc\u00e9s Norbert Casteret no hubiese resuelto el misterio en 1931, este lugar podr\u00eda haberse convertido en un horrendo sitio para la captaci\u00f3n de agua.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Seguro que muchos de vosotros lo hab\u00e9is averiguado nada m\u00e1s ver la fotograf\u00eda. Se trata de el Forau d\u2019Aigualluts, uno de los lugares m\u00e1s visitados del valle de Benasque junto a la cascada y el Plan del mismo nombre. Tres lugares muy recomendables que pueden visitarse f\u00e1cilmente siguiendo una <a href=\"que%20parte%20de%20La%20Besurta\">ruta de ida y vuelta que parte de La Besurta<\/a>, de menos de 5 kil\u00f3metros. El forau d\u2019Aigualluts es un sumidero k\u00e1rstico situado a los pies del Aneto, por el que desaparecen las aguas del r\u00edo \u00c9sera procedentes de los glaciares del Aneto, Tempestades y Barrancs; y de su afluente, el Escaleta. El curso natural del valle es hacia el sur, hacia Benasque, el valle del Ebro y el Mediterr\u00e1neo, sin embargo, el agua se filtra para aparecer a unos 4 kil\u00f3metros de distancia en la Artiga de Lin (Valle de Ar\u00e1n), al otro lado de la divisoria, y acabar en el Garona y finalmente en el Atl\u00e1ntico. La surgencia por la que mana el agua es conocida como Uelhs deth Jo\u00e8u, que significa \u201cLos Ojos del Diablo o de Jupiter\u201d.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #92:<\/h2>\n\n\n\n<p>Esta semana no buscamos un lugar sino una flor, una que por estas fechas se est\u00e1 preparando para hacer su gran aparici\u00f3n en los bosques de pino negro, su lugar preferido.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar092-1024x768.jpg\" alt=\"\" class=\"wp-image-36179 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar092-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar092-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar092-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar092-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar092.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>En la pen\u00ednsula ib\u00e9rica solo habita en los Pirineos.<\/li>\n\n\n\n<li>Es propia de ambientes de monta\u00f1a europeos: Alpes, Apeninos, Carpatos\u2026<\/li>\n\n\n\n<li>Existen m\u00e1s de 1000 especies conocidas de esta planta. Una de ellas es la flor nacional de cierto pa\u00eds del Himalaya \u00bfCu\u00e1l ser\u00e1?<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Nos refer\u00edamos al Rhododendron ferrugineum, com\u00fanmente llamado rododendro, bujo o rosa de los Alpes. Este arbusto abundante en los Pirineos, suele habitar en pinares subalpinos y abetales, y entre sus claros, entre los 1.500 y los 2.500 metros de altitud. As\u00ed que ya sab\u00e9is, abrid bien los ojos en vuestra pr\u00f3xima ruta por los Pirineos, porque el rododendro florece entre junio y agosto.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #93:<\/h2>\n\n\n\n<p>La monta\u00f1a que buscamos esta semana no es una m\u00e1s, qu\u00e9 se lo pregunten a los habitantes de la ciudad que haya a sus pies. \u00a1C\u00f3mo imagin\u00e1rsela sin este gran decorado!<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar093-1024x768.jpg\" alt=\"\" class=\"wp-image-36255 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar093-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar093-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar093-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar093-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar093.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Precisamente, desde esta conocida localidad est\u00e1 tomada la fotograf\u00eda.<\/li>\n\n\n\n<li>A pesar de no ser un pico muy elevado, es una de las 50 m\u00e1s prominentes de la pen\u00ednsula ib\u00e9rica.<\/li>\n\n\n\n<li>Aislada al sur del eje pirenaico, su silueta es como un faro en las idas y venidas a esta comarca pirenaica.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Esta era f\u00e1cil, la silueta de la Pe\u00f1a Oroel (1.770m) desde Jaca es inconfundible. La subida m\u00e1s cl\u00e1sica es la que sube desde el parador (1.200m) por la zona de Las Neveras, aunque tambi\u00e9n hay quien prefiere comenzar en Jaca y enfrentarse a sus 1.000 metros de desnivel, o a\u00f1adirle un poco m\u00e1s de dificultad por la v\u00eda Mayencos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #94:<\/h2>\n\n\n\n<p>Sin lugar a dudas, si hici\u00e9semos un peque\u00f1o listado con los sitios imprescindibles que hay que visitar alguna vez en los Pirineos, este ser\u00eda uno de ellos. C\u00f3mo veis, no hacen falta muchas pistas para acertar de qu\u00e9 lugar se trata pero por si acaso, ah\u00ed van:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar094-1024x768.jpg\" alt=\"\" class=\"wp-image-36425 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar094-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar094-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar094-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar094-600x450.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar094.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Este lugar est\u00e1 distinguido desde 1997 conjuntamente con el Monte Perdido, Patrimonio Mundial de la Unesco.<\/li>\n\n\n\n<li>Se encuentra dentro del Parc National des Pyr\u00e9n\u00e9es.<\/li>\n\n\n\n<li>La gran cascada que vemos a la izquierda, es la m\u00e1s alta de Francia y de los Pirineos.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Exacto, era el circo de Gavarnie y la Gran cascada, la m\u00e1s alta de Francia y del Pirineo con 423 metros de altura. Uno de esos lugares imprescindibles que hay que visitar y que ser\u00e1 mejor evitar en temporada alta. La caminata desde el pueblo de Gavarnie, un paseo de unas 2 horas y media, ida y vuelta, es apta para personas de todas las edades y condici\u00f3n f\u00edsica, con todo lo bueno y lo malo que esto conlleva.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #95:<\/h2>\n\n\n\n<p>Continuamos una semana m\u00e1s por el departamento franc\u00e9s de los Hautes Pyr\u00e9n\u00e9es, pero esta vez, en busca de un bonito lago. \u00bfLo reconoces? No? A ver si con las pistas\u2026<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar095-1024x682.jpg\" alt=\"\" class=\"wp-image-36645 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar095-1024x682.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar095-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar095-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar095-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar095.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>El lago que buscamos se encuentra dentro del Parc National des Pyr\u00e9n\u00e9es.<\/li>\n\n\n\n<li>Junto al lago se encuentra el refugio del mismo nombre.<\/li>\n\n\n\n<li>Aunque no es lo habitual, pasando por este lugar saldr\u00eda una ruta muy original para subir al Vignemale.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>El lago que os propon\u00edamos averiguar era el Lac d\u2019Estom, en la cabecera del valle de Lutour. Un lago rodeado por picos que rondan los 2800-2900 metros de altura y en el que al fondo destaca el Pic de Labas (2.946m), oculto por las nubes, y que est\u00e1 siempre presente a lo largo de toda aproximaci\u00f3n desde La Fruitiere (4h ida\/vuelta; 10,5km).<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #96:<\/h2>\n\n\n\n<p>Contemplar una cascada, sobre todo ahora en verano, es una de esas cosas que nos encanta a todo el mundo. Ver precipitarse el agua, escuchar el sonido que produce, refrescarse en ella y respirar esas part\u00edculas de agua que siempre se desprenden y que nos ponen de buen humor, demostrado cient\u00edficamente. La cascada que os pedimos averiguar, por el lugar en que se encuentra, es bastante conocida. \u00bfSab\u00e9is cual es?<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"734\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar096-1024x734.jpg\" alt=\"\" class=\"wp-image-36768 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar096-1024x734.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar096-300x215.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar096-768x550.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar096-600x430.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar096.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Se encuentra en uno de los espacios naturales m\u00e1s visitados del Pirineo catal\u00e1n.<\/li>\n\n\n\n<li>La cascada recibe el mismo nombre que el r\u00edo, estany y pico, donde nacen sus aguas.<\/li>\n\n\n\n<li>Si quer\u00e9is visitarla y contornear el lago, lo mejor ser\u00e1 seguir la ruta del mirador, la n\u00famero 8 del folleto del Parque Nacional.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>La cascada que ve\u00edamos en la fotograf\u00eda era la Cascada de Ratera, en el P.N de Aig\u00fcestortes i Estany de Sant Maurici. Este salto se encuentra situado junto al mismo Estany de Sant Maurici, en la orilla derecha si vamos subiendo hacia el Estany de Ratera. Si quer\u00e9is visitarla, una buena forma es seguir la ruta del mirador, un recorrido de 6,6km en los que se rodea completamente el estany de Sant Maurici y se visitan varios lugares de inter\u00e9s, como la propia cascada, el estany de Ratera y el mirador, todo ello con grandes vistas hacia monta\u00f1as como Els Encantats y muchas otras m\u00e1s.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #97:<\/h2>\n\n\n\n<p>La puntiaguda cumbre que os proponemos averiguar esta semana ve desfilar cada verano a centenares de monta\u00f1eros, sin embargo, solo unos pocos se desv\u00edan para intentar ascenderla. Es lo que tiene ser un pico \u201csecundario\u201d.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"717\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar097-1024x717.jpg\" alt=\"\" class=\"wp-image-36871 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar097-1024x717.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar097-300x210.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar097-768x538.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar097-600x420.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/06\/lugar097.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Nuestra puntiaguda cumbre es la segunda monta\u00f1a m\u00e1s elevada enteramente en territorio galo, solo por detr\u00e1s del otro pico que veis situado a su derecha.<\/li>\n\n\n\n<li>Bajo la vertical de su cima se distingue una brecha, se trata de la salida del corredor m\u00e1s famoso de todo el Pirineo.<\/li>\n\n\n\n<li>La fotograf\u00eda est\u00e1 tomada desde el \u00fanico glaciar con lengua que a\u00fan queda, en el Pirineo.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>La afilada punta que ve\u00edamos en la fotograf\u00eda era el Pit\u00f3n Carr\u00e9 (3.197m), la segunda cumbre m\u00e1s elevada del Pirineo, enteramente en territorio franc\u00e9s, tras la Punta Chausenque (3.204m), a la derecha de la fotograf\u00eda. Respecto a las dem\u00e1s pistas, la brecha que ve\u00edamos a sus pies era la brecha de Gaube, la salida del couloir m\u00e1s prestigioso del Pirineo; y el glaciar era el de Ossoue, que con cerca de 37 ha se sit\u00faa como el tercer glaciar por extensi\u00f3n del Pirineo y el \u00fanico con lengua.<\/p>\n\n\n\n<p>El Pit\u00f3n Carr\u00e9 (F) suele subirse habitualmente en combinaci\u00f3n con otros picos cuando se recorre la corona del Vignemale, (AD-) desde el Petit Vignemale. Si os anim\u00e1is, aqu\u00ed os dejamos esta <a href=\"https:\/\/travesiapirenaica.com\/vignemale-bujaruelo\/\">ruta desde Bujaruelo por el corredor de la Moskowa en la que ascendemos a 8 tresmiles<\/a>, el Pit\u00f3n Carr\u00e9 entre ellos por supuesto.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #98:<\/h2>\n\n\n\n<p>Nos encontramos en uno de los grandes macizos pirenaicos, un laberinto de picos, valles en \u201cU\u201d, circos glaciares e infinidad de lagos y de afiladas crestas gran\u00edticas. Las agujas que vemos son un buen ejemplo de ello, \u00bflas reconoces?<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"717\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/07\/lugar098-1024x717.jpg\" alt=\"\" class=\"wp-image-36980 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/07\/lugar098-1024x717.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/07\/lugar098-300x210.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/07\/lugar098-768x538.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/07\/lugar098-600x420.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/07\/lugar098.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Estas dos agujas son unas de las m\u00e1s ic\u00f3nicas del macizo y hasta hace poco, ocupaban la portada del mapa de Alpina de esta zona.<\/li>\n\n\n\n<li>Se encuentran a media hora del refugio y el estany del mismo nombre que estas.<\/li>\n\n\n\n<li>Aunque estas dos agujas parezcan territorio exclusivo de escaladores, la vertiente oeste ofrece un punto flaco a senderistas trepadores.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Seguro que lo hab\u00e9is averiguado, se trataba de las Agullas d\u2019Amitges, la Agulla Inferior (2.657m) a la izquierda y la Agulla Superior (2.662m) a la derecha. La fotograf\u00eda est\u00e1 tomada cerca del refugio de Amitges, hacia donde muestra su silueta m\u00e1s conocida, separando los circos glaciares de Saboredo y Bassiero. Su aspecto inexpugnable no debe desanimar al \u201csenderista\u201d, rodeando las agujas por el lado Oeste existe un peque\u00f1o corredor (F) por el que se accede sin apenas dificultad ni exposici\u00f3n hasta la Agulla Superior. La inferior est\u00e1 reservada a escaladores, que se la gozaran escalando sus fisuras sobre un granito excelente.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #99:<\/h2>\n\n\n\n<p>Esta semana viajamos al Pirineo Occidental en busca de esta conocida monta\u00f1a, tan querida y apreciada por los mendizales de la zona.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"717\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/07\/lugar099-1024x717.jpg\" alt=\"\" class=\"wp-image-37301 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/07\/lugar099-1024x717.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/07\/lugar099-300x210.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/07\/lugar099-768x538.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/07\/lugar099-600x420.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/07\/lugar099.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Es uno de los primeros picos en superar los 1.000 metros de altitud viniendo del Cant\u00e1brico.<\/li>\n\n\n\n<li>Por su cumbre pasa el GR10 y la ARP.<\/li>\n\n\n\n<li>Frontera natural entre Espa\u00f1a y Francia, la ruta m\u00e1s habitual parte de la antigua aduana.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Se trataba del Iparla (1.049m), m\u00e1xima altura del cordal entre el puerto de Izpegui y Bidarrai, que separa el valle de Bazt\u00e1n de la Baja Navarra, hacia donde cae abruptamente casi mil metros. La ruta m\u00e1s habitual a este rojizo pico de arenisca es la que parte del puerto de Izpegui siguiendo el GR10, que contin\u00faa hasta Bidarrai por toda la cresta, y que si se dispone de dos coches resulta una magnifica opci\u00f3n. Otras rutas habituales son desde Bidarrai y desde Gaztigarko Lepoa.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #100:<\/h2>\n\n\n\n<p>Como ya sab\u00e9is, el buscamos de esta semana era especial. Enhorabuena a Ignacio por esta foto que nos enviaba de cuando hace unas semanas, realizaba la Alta Ruta de los Perdidos. E aqu\u00ed las pistas que nos enviaba.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar100-1024x682.jpg\" alt=\"\" class=\"wp-image-37592 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar100-1024x682.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar100-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar100-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar100-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar100.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Es un refugio franc\u00e9s cuyo nombre podr\u00eda ser una traducci\u00f3n muy mala de un plato de pasta italiano (espaguetis).<\/li>\n\n\n\n<li>Es la etapa 3 de la alta ruta de los perdidos.<\/li>\n\n\n\n<li>Est\u00e1 situado a 2027m de altitud en las alturas de Gavarnie.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>El marco no puede ser m\u00e1s hermoso, el circo de Gavarnie con el Casco (3.011m), la Brecha de Rolando, la Punta Bazillac (2.976m), el Taill\u00f3n (3.144m), el Gabieto Norte (3.031m)\u2026, unas vistas dif\u00edciles de superar. Por cierto, el lugar que busc\u00e1bamos era el refugio de Espuguettes, situado en plena Alta ruta de los Perdidos y Alta Ruta Pirenaica (ARP \/ HRP), y un m\u00e1gnifico lugar para descubrir la cara norte de los Astazous.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #101:<\/h2>\n\n\n\n<p>El buscamos de esta semana, nos lo enviaba Yasmina P\u00e9rez, que dec\u00eda: \u201c La vida es como un espejo, te sonr\u00ede si la miras sonriendo\u201d<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar101-1024x682.jpeg\" alt=\"\" class=\"wp-image-37751 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar101-1024x682.jpeg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar101-300x200.jpeg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar101-768x512.jpeg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar101-600x400.jpeg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar101.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Desde Respomuso saldr\u00e1s<\/li>\n\n\n\n<li>A Fabr\u00e8gues llegar\u00e1s<\/li>\n\n\n\n<li>De pa\u00eds cambiar\u00e1s<\/li>\n\n\n\n<li>De cuento Disney el nombre parecer\u00e1<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Impresionante las vistas y la calma que se respiran en este ib\u00f3n al pie del pico Pal\u00e1s, nos referimos a los ibones de Arriel, o m\u00e1s concretamente, al ib\u00f3n de Arriel Alto. Una fabulosa imagen que captaba Yasmina P\u00e9rez, no sabemos si realizando la traves\u00eda entre Respomuso y el Lac de Fabr\u00e8gues que nos dec\u00eda en las pistas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #102:<\/h2>\n\n\n\n<p>El lugar de esta semana nos lo enviaba Fernando Royo, una imagen en la que jugaba con el contraste de luces y sombras y en la que nos ped\u00eda averiguar qu\u00e9 pico era este que se ve al fondo. Ah\u00ed van las pistas que&nbsp; nos daba:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar102-1024x683.jpg\" alt=\"\" class=\"wp-image-37874 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar102-1024x683.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar102-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar102-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar102-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/08\/lugar102.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Hablamos de la segunda cima m\u00e1s alta de la cordillera pirenaica, despu\u00e9s del Aneto.<\/li>\n\n\n\n<li>La v\u00eda normal viene desde el Refugio \u00c1ngel Or\u00fas, tambi\u00e9n se le llama ruta real.<\/li>\n\n\n\n<li>Su nombre viene de unos pozos de su vertiente Oeste&#8230; y es como se le llama a la zona en Gista\u00edn.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Con las pistas que os d\u00e1bamos no hab\u00eda dudas, se trata del Posets o Llardana (3.368m) visto desde el lago de Ordiceto. Adem\u00e1s de la ascensi\u00f3n desde el refugio \u00c1ngel Or\u00fas, otras rutas normales son las que parten de los refugios de Viad\u00f3s y Est\u00f3s, tres refugios estrat\u00e9gicamente ubicados que posibilitan un recorrido circular alrededor del macizo o&nbsp;<a href=\"https:\/\/travesiapirenaica.com\/ruta-tres-refugios-posets-maladeta\/?utm_campaign=Traves\u00eda.&amp;utm_medium=email&amp;utm_source=Revue%20newsletter\">Ruta de los tres refugios<\/a>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #103:<\/h2>\n\n\n\n<p>La fotograf\u00eda de esta semana nos la enviaba Ana Remirez de Ganuza, que a\u00f1ad\u00eda lo siguiente: \u201cNos encontramos en unos de los macizos del Pirineo m\u00e1s occidentales, en la frontera entre Espa\u00f1a y Francia\u201d.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar103-1024x682.jpg\" alt=\"\" class=\"wp-image-37941 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar103-1024x682.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar103-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar103-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar103-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar103.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Cuenta la leyenda un sobrino de Carlomagno fue el art\u00edfice de este accidente geogr\u00e1fico. <\/li>\n\n\n\n<li>Ha sido uno de los temas del podcast &#8216;Maldita monta\u00f1a&#8217;.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Seguro que hab\u00e9is acertado. Se trataba de la Brecha de Rolando, la que seg\u00fan cuenta la <a href=\"https:\/\/travesiapirenaica.com\/leyenda-brecha-rolando\/\">leyenda<\/a>, Rolando abri\u00f3 con su espada Durandarte. El pico que se ve detr\u00e1s es el Casco de Marbor\u00e9 (3.011m) que aunque parezca estar reservado \u00fanicamente a escaladores, la muralla que se observa en su base esconde un curioso paso subterr\u00e1neo que posibilita, cuando no est\u00e1 taponado por la nieve, superarla sin demasiadas dificultades (F+). Si es el caso, mejor ser\u00e1 seguir la v\u00eda normal por el Paso de los Sarrios que asciende por la vertiente sur (F).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #104:<\/h2>\n\n\n\n<p>El lugar de esta semana nos lo enviaba Mar\u00eda Garc\u00eda, que dec\u00eda: se trata de un pico casi olvidado, pues son pocos los monta\u00f1eros que suelen ascenderlo, ya que la mayor\u00eda se dirige siempre hacia el segundo pico m\u00e1s alto del Pirineo. La foto est\u00e1 tomada desde el Collado con el que comparte nombre.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar104-1024x682.jpg\" alt=\"\" class=\"wp-image-37942 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar104-1024x682.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar104-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar104-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar104-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar104.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Parece imposible su ascenso, pero un peque\u00f1o sendero que sale a su izquierda con alg\u00fan hito desperdigado nos lleva hasta su cima sin necesidad de escalar.<\/li>\n\n\n\n<li>Comparte parte del nombre con su vecino, el segundo pico m\u00e1s alto de Pirineos.<\/li>\n\n\n\n<li>Se suele llegar hasta su base ascendiendo por la Canal Fonda, frecuentada por lo monta\u00f1eros que acuden hacia su vecino, el segundo pico m\u00e1s alto de Pirineos.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Pues s\u00ed, como dec\u00eda Mar\u00eda, puede que muchos no hay\u00e1is estado nunca en el Diente de Llardana (3.089m), pero seguro que lo hab\u00e9is visto al subir al Posets por la Canal Fonda. El Diente de Llardana es uno de los 17 tresmiles catalogados del sector Posets \u2013 Eriste y, aunque su aspecto inexpugnable puede echar a m\u00e1s de uno para atr\u00e1s, una trepada (PD-) por terreno algo descompuesto es el mayor obst\u00e1culo a superar.<\/p>\n\n\n\n<p>Como curiosidad, una foto&nbsp; muy similar del Diente de Llardana aparec\u00eda en la portada del libro \u00a1Qu\u00e9 bonito son los Pirineos!, de Hipolito Maeso Rueda, primera persona en ascender de forma \u201cconsecutiva\u201d los 212 tresmiles que por el a\u00f1o 1999 hab\u00eda catalogados. Est\u00e1 escrito a modo \u201cdiario\u201d y aunque a ratos pueda resultar muy descriptivo, lo cuenta con mucha gracia. Uno de los <a href=\"https:\/\/travesiapirenaica.com\/literatura-pirineos\/\">10 libros de literatura pirenaica<\/a> que hace un tiempo os recomend\u00e1bamos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #105:<\/h2>\n\n\n\n<p>La fotograf\u00eda de esta semana nos la enviaba Leire Muxica, un lugar por el casualmente hace una semana os tra\u00edamos una ruta (pista extra). Vamos all\u00e1 con las pistas de Leire:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar105-1024x682.jpg\" alt=\"\" class=\"wp-image-37967 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar105-1024x682.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar105-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar105-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar105-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar105.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>El lugar est\u00e1 a 2.200 metros de altitud, al lado del refugio con el mismo nombre.<\/li>\n\n\n\n<li>Pertenece a la provincia de Huesca.<\/li>\n\n\n\n<li>Est\u00e1 ubicado dentro del circo de Piedrafita.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Se trataba del embalse y refugio de Respomuso, situado a los pies del Balait\u00fas. Los picos que se ven al fondo son la Gran Facha (3.005m), Pico de Campo ro Plano (2.717m), Pico de Piedrafita (2.952m), Pico de las Marmoleras (2.908m) y Pico de Tebarrai (2.886m), entre otros.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #106:<\/h2>\n\n\n\n<p>La monta\u00f1a que buscamos esta semana es una de las m\u00e1s pintorescas del Pirineo, una cumbre apartada 30 kil\u00f3metros al sur del eje pirenaico.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar106-1024x682.jpg\" alt=\"\" class=\"wp-image-37986 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar106-1024x682.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar106-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar106-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar106-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/09\/lugar106.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Sin ser una cumbre especialmente alta, su aislada situaci\u00f3n la convierte en una de las 100 m\u00e1s prominentes de la pen\u00ednsula ib\u00e9rica.<\/li>\n\n\n\n<li>Por el sur, desde donde est\u00e1 tomada la fotograf\u00eda, tiene el aspecto de un \u201cvolc\u00e1n\u201d; por el norte, en cambio, encierra un alargado valle en su interior que lo asemeja a una herradura.<\/li>\n\n\n\n<li>Muchos coches llevan uno.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Se trataba del Turb\u00f3n, un mirador excepcional sobre todo el Pirineo Central que abarca desde el Collarada al Pedrafora pasando por Cotiella, La Munia, Pic Long de Neouvielle, Bachimala, Posets, Perdiguero, Aneto, Punta Alta o el Puigmal. Una monta\u00f1a ideal para subir en un d\u00eda claro y disfrutar de las vistas, o para uno de esos d\u00edas en los que hace malo en las grandes cumbres pero aqu\u00ed m\u00e1s al sur el tiempo aguanta.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #107:<\/h2>\n\n\n\n<p>El lugar de esta vez nos lo enviaba hace unas semanas Garazi Autor, uno de esos sitios a los que no nos cansamos de regresar. En este caso, la foto no corresponde con el lugar por el que Garazi nos pregunta seg\u00fan las pistas, sino con el paisaje que dejamos atr\u00e1s al ir hacia ese lugar. Vamos all\u00e1!!<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"686\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar107-1024x686.jpg\" alt=\"\" class=\"wp-image-38074 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar107-1024x686.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar107-300x201.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar107-768x514.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar107-600x402.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar107.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Aqui se retuercen las aguas y los corazones.<\/li>\n\n\n\n<li>Podr\u00e1s quedarte tuerto ante la belleza de este paraje.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Con estas pistas no hab\u00eda duda, nos refer\u00edamos al valle de Aguas Tuertas, en el Pirineo oscense. La fotograf\u00eda en realidad no es del propio valle de Aguas Tuertas, sino del paisaje que dejamos atr\u00e1s al acceder hasta el. Al fondo podemos divisar destacando entre todos los picos, la triangular silueta del <a href=\"https:\/\/travesiapirenaica.com\/acherito-desde-linza\/\">Mallo de Acherito<\/a>. A su izquierda sobresale tambi\u00e9n el <a href=\"https:\/\/travesiapirenaica.com\/chinebral-gamueta-linza\/\">Chinebral de Gamueta<\/a>, la Gorreta de los Gabachos, el Mallo Gorreta, Anzotiello, Quimboa, Petraficha y Chipeta Alto.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #108:<\/h2>\n\n\n\n<p>Esta semana nos desplazamos al Pirineo catal\u00e1n en busca de este refugio de marco incomparable.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar108-1024x683.jpg\" alt=\"\" class=\"wp-image-38188 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar108-1024x683.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar108-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar108-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar108-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar108.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Detr\u00e1s del refugio podemos distinguir varios picos de m\u00e1s de 3.000 metros.<\/li>\n\n\n\n<li>En el centro de la imagen tenemos un pico que recibe el nombre con el que se comercializaba tradicionalmente el az\u00facar a finales del siglo XIX, al igual que la emblem\u00e1tica roca que domina Rio de Janeiro.<\/li>\n\n\n\n<li>Por aqu\u00ed pasa la ruta circular entre refugios de una semana m\u00e1s famosa de los Pirineos.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Se trataba del refugio Joan Ventosa i Calvell, situado en la cabecera del valle de Bo\u00ed en el P.N de Aig\u00fcestortes. Dicho refugio recibe el nombre de un pol\u00edtico catal\u00e1n, fundador de la Lliga Regionista y &nbsp;tres veces ministro de Alfonso XIII, que ayud\u00f3 decisivamente a Franco durante la Guerra Civil bloqueando financieramente al gobierno republicano. Ventosa cre\u00eda que al final de la contienda podr\u00eda obtener un puesto relevante en el futuro r\u00e9gimen pol\u00edtico, sin embargo, acabada la guerra, este comprendi\u00f3 que hab\u00eda sido utilizado (aunque se forr\u00f3) y fue uno de los firmantes del \u201cManifiesto de los Veintisiete\u201d que solicitaba a Franco la restauraci\u00f3n de la monarqu\u00eda.<\/p>\n\n\n\n<p>El refugio original de 1942, propiedad privada de Joan Ventosa, recib\u00eda en un principio el nombre de Estany Negre. Fue en 1954 cuando este decidi\u00f3 donarlo al \u201cCentre Excursionista de Catalunya\u201d que en agradecimiento puso su nombre.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #109:<\/h2>\n\n\n\n<p>Esta semana nos vamos de excursi\u00f3n hasta una de las cumbres m\u00e1s representativas de Navarra. \u00bfLa reconoces?<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar109-1024x682.jpg\" alt=\"\" class=\"wp-image-38216 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar109-1024x682.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar109-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar109-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar109-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/10\/lugar109.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Por su importancia y cercan\u00eda a Pamplona, es una de las monta\u00f1as m\u00e1s frecuentadas de la comunidad.<\/li>\n\n\n\n<li>Se encuentra sobre la divisoria de aguas cant\u00e1brico-mediterr\u00e1nea.<\/li>\n\n\n\n<li>Es la cumbre m\u00e1s elevada del Bazt\u00e1n.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Se trataba del Saioa (1.418m), una de las principales cumbres de la monta\u00f1a navarra, punto culminante del valle de Baztan y cima m\u00e1s alta del cordal que se extiende entre los puertos de Velate y Artesiaga, desde donde parten sus dos rutas m\u00e1s habituales. Otra alternativa m\u00e1s que interesante es subir al <a href=\"https:\/\/travesiapirenaica.com\/saioa-lantz\/\">Saioa desde Lantz<\/a>, una ruta que os tra\u00edamos hace un tiempo en la que adem\u00e1s de este, enlaz\u00e1bamos un buen n\u00famero de cumbres en torno al barranco de Elzarrain.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #110:<\/h2>\n\n\n\n<p>Los picos que buscamos esta semana forman una trilog\u00eda de tresmiles situados, como un ap\u00e9ndice, al sur de uno de los m\u00e1s grandes tresmiles pirenaicos.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar110-1024x683.jpg\" alt=\"\" class=\"wp-image-38263 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar110-1024x683.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar110-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar110-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar110-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar110.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Aunque en la intro habl\u00e1bamos de una trilog\u00eda de tresmiles, en la foto solo vemos dos.<\/li>\n\n\n\n<li>El nombre m\u00e1s habitual para referirse a estos picos responde al nombre de la poblaci\u00f3n que se encuentra debajo.<\/li>\n\n\n\n<li>Se encuentra a caballo entre los valles de Gista\u00edn\/Chistau y Benasque\/Ben\u00e1s.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Nos refer\u00edamos a \u201cLos Eristes\u201d o Picos de Bag\u00fce\u00f1ola. En concreto a los dos que ve\u00edamos, el Eriste Norte (3.031m), tambi\u00e9n llamado Pico Beraldi o Bag\u00fce\u00f1ola Norte; y al Eriste Central (3.056m), m\u00e1s conocido por Gran Eriste o Gran Tuca de Bag\u00fce\u00f1ola (3.056m). Los Eristes se enmarcan dentro del macizo del Posets, en una zona que destaca por la presencia de cuencas lacustres, como las de los dos ibones que pueden verse al pie de estos picos: el ib\u00f3n d\u2019es Leners\/de Len\u00e9s y el ib\u00f3n d\u2019es Millars\/Millares. Dos ibones que hace un tiempo visit\u00e1bamos en esta ruta: <a href=\"https:\/\/travesiapirenaica.com\/ibones-pixon-luzeros-leners-millars\/\">Ruta circular a los ibones de Pix\u00f3n, Solana\/Luzeros, Leners y Millars<\/a>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #111:<\/h2>\n\n\n\n<p>El reto de esta semana nos lleva hasta este peque\u00f1o embalse rodeado por frondosos bosques y altas monta\u00f1as, en la vertiente norte de los Pirineos. \u00bfLo reconoces?<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar111-1024x682.jpg\" alt=\"\" class=\"wp-image-38310 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar111-1024x682.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar111-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar111-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar111-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar111.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Nos encontramos en el departamento franc\u00e9s de los Altos Pirineos (Hautes-Pyr\u00e9n\u00e9es), en uno de los 7 valles que componen la hist\u00f3rica regi\u00f3n del Laved\u00e1n.<\/li>\n\n\n\n<li>La monta\u00f1a nevada que vemos al fondo supera los 3.000 metros de altitud.<\/li>\n\n\n\n<li>Por aqu\u00ed transita el GR10.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Se trataba del Lac du Tech con el Balaitous (3.146m), la Pourgadou (2.344m) y l\u2019Arriougrand (2.586m) de fondo. El Lac du Tech se encuentra en el valle d\u2019Arrens, un valle secundario de la Val d\u2019Azun. La gave (r\u00edo) de Arrens, junto con el torrente que desciende del valle de Estaing, forma la gave de Azun, uno de los 3 r\u00edos principales que junto a los de Cauterets y Gavarnie (Pau) hacen grande a la gave de Pau, uno de los r\u00edos m\u00e1s importantes de Francia.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #112:<\/h2>\n\n\n\n<p>Esta semana no queremos que nos dig\u00e1is que es lo que se ve en la fotograf\u00eda, sino el lugar desde donde est\u00e1 tomada.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar112-1024x768.jpg\" alt=\"\" class=\"wp-image-38387 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar112-1024x768.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar112-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar112-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar112-1536x1152.jpg 1536w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar112-2048x1536.jpg 2048w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar112-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Nos encontramos muy cerca de un conocido puerto de monta\u00f1a que a\u00f1o si, a\u00f1o no, se asciende en la Vuelta a Espa\u00f1a.<\/li>\n\n\n\n<li>En realidad, este puerto se encuentra en el Principado de Andorra.<\/li>\n\n\n\n<li>Los principales picos que se ven al fondo son, a la izquierda el Pic Alt del Griu (2.874m) y a la derecha, las Crestes de Gargantillar (2.843m).<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>La fotograf\u00eda est\u00e1 tomada muy cerca del Coll d\u2019Ordino (1.980m), en pleno <a href=\"https:\/\/travesiapirenaica.com\/gr11\/arans-encamp.php\">GR11 o Senda Pirenaica<\/a>. Un puerto muy conocido en el mundillo ciclista aunque no sea especialmente duro. Su nombre le viene de la localidad que hay debajo en la vertiente Oeste. Desde este lado son 10km con una pendiente media al 7%. La otra vertiente, la de Canill\u00f3, es m\u00e1s sencilla, 9km al 5,1% de pendiente media pero con alguna bajada entre medio que distorsiona la estad\u00edstica. El Coll d\u2019Ordino es tambi\u00e9n punto de partida de dos monta\u00f1as bien conocidas, el Bony de las Neres (2.211m) y los picos de Casamanya (2.757m).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #113:<\/h2>\n\n\n\n<p>Existen lugares en los que el silencio se escucha, el reloj se detiene y tan solo contemplarlos, es como una bocanada de aire puro que invade nuestros pulmones.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar113-1024x682.jpg\" alt=\"\" class=\"wp-image-38505 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar113-1024x682.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar113-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar113-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar113-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar113.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Nos encontramos en los Valles Occidentales, como m\u00e1s de uno pod\u00eda sospechar al ver la roca caliza.<\/li>\n\n\n\n<li>Se encuentra sobre la divisoria de los dos principales valles que forman el Parque Natural.<\/li>\n\n\n\n<li>En diciembre bufanda y en mayo gorrita.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Se trataba del Mallo Gorreta (2.266m) y la Brecha de Gamueta (2.181m). La ruta normal al Mallo Gorreta asciende hasta la citada brecha para descender unos metros hacia la vertiente Este y ascender por una bonita canal (II) con roca algo descompuesta, al pie de la primera aguja de Gamueta. En invierno, esta canal se transforma en un bonito corredor que dependiendo de las condiciones puede oscilar entre PD y AD. Desde la misma Brecha de Gamueta, tambi\u00e9n es posible acometer la ascensi\u00f3n por una chimenea (IV) que se supera en un solo largo. Otra actividad habitual es la de unir el Mallo Gorreta y la Gorreta de los Gabachos a trav\u00e9s de una cresta (PD), en la que la mayor dificultad se centra en un destrepe con mucho ambiente.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #114:<\/h2>\n\n\n\n<p>La monta\u00f1a que buscamos esta semana es inconfundible, \u00bfla reconoces?, o necesitas algunas pistas. Vamos con ellas:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar090.jpg\" alt=\"\" class=\"wp-image-35878 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar090.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar090-300x225.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar090-768x576.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/05\/lugar090-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Se encuentra en el P.N de los Valles Occidentales<\/li>\n\n\n\n<li>Midi d\u2019Ossau, Balit\u00fas, Frondiellas\u2026 son los picos que vemos de fondo.<\/li>\n\n\n\n<li>Sus cuatro caras defendidas por paredes verticales le han valido el apelativo de \u201cfortaleza\u201d.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>No hab\u00eda duda, se tratabaEl Castillo D\u2019Acher, una de las monta\u00f1as imprescindibles que hay que subir en esta parte del Pirineo (<a href=\"https:\/\/travesiapirenaica.com\/castillo-acher\/\">Ver ruta desde Oza<\/a>). Una ascensi\u00f3n en la que partiremos de la Selva de Oza, atravesando un magn\u00edfico bosque de abetos y hayas, y que nos sorprender\u00e1 con algunas particularidades geol\u00f3gicas de gran belleza, como las coloridas rocas rojizas que encontramos a lo largo de toda la subida o el valle suspendido que corona la parte cimera.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #115:<\/h2>\n\n\n\n<p>Nos encantan las cascadas y a qui\u00e9n no. En este caso, obviamente, buscamos el nombre de esta cascada, pero no el nombre con el que es conocida y que aparece en todo tipo de mapas, si no su nombre verdadero.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar115-1024x682.jpg\" alt=\"\" class=\"wp-image-38628 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar115-1024x682.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar115-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar115-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar115-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/11\/lugar115.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Nos encontramos en el Pirineo franc\u00e9s, junto a la confluencia de dos grandes torrentes que juntos formar\u00e1n uno de los principales afluentes de la gave de Pau.<\/li>\n\n\n\n<li>Si dese\u00e1is visitarla no tendr\u00e9is que andar mucho, la cascada se encuentra a unos 200 metros de una carretera.<\/li>\n\n\n\n<li>Podr\u00e9is dejar el coche en el aparcamiento que hay junto a los ba\u00f1os de aguas termales.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Se trataba de la cascada de Pisse-Arros, m\u00e1s (mal) conocida como cascada de Lutour. El nombre local de Pisse-Arros se traduce en franc\u00e9s como Pisse Ros\u00e9e, es decir, la cascada que desprende espuma que cae como finas perlas de agua. Si quer\u00e9is visitarla se encuentra junto a La Raillere, una zona de ventas, restaurantes y aguas termales, a 3km de Cauterets. Y si os gustan las cascadas, no os pod\u00e9is perder el <a href=\"https:\/\/travesiapirenaica.com\/sentier-cascades\/\">Sendero de las Cascadas<\/a> entre La Raillere y el Pont d\u2019Espagne.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #116:<\/h2>\n\n\n\n<p>El aspecto inexpugnable de la monta\u00f1a que buscamos esta semana puede que despiste a m\u00e1s de uno habituado a contemplar su vertiente sur, m\u00e1s accesible y amable, por la que muchos se inician en la monta\u00f1a invernal y que hace las delicias de los esquiadores de monta\u00f1a.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar116-1024x682.jpg\" alt=\"\" class=\"wp-image-38756 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar116-1024x682.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar116-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar116-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar116-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar116.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>No hay ning\u00fan otro pico m\u00e1s alto desde aqu\u00ed al Cant\u00e1brico.<\/li>\n\n\n\n<li>La ruta m\u00e1s habitual discurre desde el refugio ubicado en la vertiente sur, aunque tambi\u00e9n es bastante habitual la que parte del refugio ubicado en la vertiente oeste.<\/li>\n\n\n\n<li>El GR11 y un variante del mismo rodean por completo este pico y son parte de las principales rutas de ascenso.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Se trataba del Bisaur\u00edn (2.670m), el pico m\u00e1s alto de toda esta zona. Una monta\u00f1a muy conocida y frecuentada en invierno y verano por lo destacado de la misma y por lo accesible de sus rutas normales. Las m\u00e1s habituales son las que parten de los refugios de Lizara y Gabardito, en ambos casos siguiendo la variante GR11.1 hasta el cuello de lo Forat\u00f3n, aunque tambi\u00e9n existen varias alternativas sencillas para el que quiera descubrirlas, como la que asciende por la Plana Mistresa y la vertiente Este (F), la arista NE (F+) o las Fetas (F).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #117:<\/h2>\n\n\n\n<p>Los puentes siempre han tenido un significado positivo, de uni\u00f3n, de concordia. El que os proponemos encontrar esta semana es del siglo XIX y se encuentra en el departamento franc\u00e9s de los Altos Pirineos.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar117-1024x682.jpg\" alt=\"\" class=\"wp-image-38822 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar117-1024x682.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar117-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar117-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar117-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar117.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Se encuentra a la salida de una localidad conocida, entre otras cosas, por ser el inicio del que seguramente sea el puerto m\u00e1s famoso del mundo.<\/li>\n\n\n\n<li>Hoy en d\u00eda, el paisaje que rodea a este lugar atrae a miles de turistas, monta\u00f1eros o ciclistas, sin embargo, en otros tiempos, fueron arist\u00f3cratas y emperadores los que comenzaron a frecuentarlo, atra\u00eddos por sus aguas curativas.<\/li>\n\n\n\n<li>El puente est\u00e1 abierto al tr\u00e1fico de veh\u00edculos, suele practicarse el puenting y en su base existe una v\u00eda ferrata y una escuela de escalada.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Se trataba del Puente de Napole\u00f3n, situado sobre la gave de Gavarnie, a la salida de Luz-Saint-Sauveur. El nombre del puente est\u00e1 dedicado a Napole\u00f3n III, el \u00faltimo emperador de Francia, quien sol\u00eda visitar los ba\u00f1os de aguas termales junto a su esposa, la emperatriz Eug\u00e9nie, en busca de un remedio contra la infertilidad. Seg\u00fan se cuenta, tanto la construcci\u00f3n del puente como su emplazamiento, fueron idea del emperador. Las obras del puente fueron lideradas por el ingeniero Bruniquel, duraron dos a\u00f1os y finalizaron en junio de 1861. Tiene una longitud de 68 metros y una altura de 63 metros sobre el r\u00edo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Buscamos este lugar #118:<\/h2>\n\n\n\n<p>El \u00faltimo buscamos del a\u00f1o se merec\u00eda un paisaje nevado, de esos de postal navide\u00f1a. Un lugar que nos encanta y que tantos recuerdos nos trae a la cabeza \u00a1Seguro que no somos los \u00fanicos!<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar118-1024x682.jpg\" alt=\"\" class=\"wp-image-38961 size-full\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar118-1024x682.jpg 1024w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar118-300x200.jpg 300w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar118-768x512.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar118-600x400.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2023\/12\/lugar118.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">Pistas:<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>El pico grande de la derecha es el m\u00e1s alto del sector oriental de la sierra.<\/li>\n\n\n\n<li>En su base se encuentra un ib\u00f3n muy conocido y visitado.<\/li>\n\n\n\n<li>Nos encontramos en el valle de Tena.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/ol>\n\n\n\n<p><strong>Soluci\u00f3n:<\/strong><\/p>\n\n\n\n<p>Se trataba de <a href=\"https:\/\/travesiapirenaica.com\/telera-parda-blanca\/\">Pe\u00f1a Telera (2.762m)<\/a>, el pico m\u00e1s conocido y emblem\u00e1tico de la sierra de Partacua y el segundo m\u00e1s alto tras <a href=\"https:\/\/travesiapirenaica.com\/retona-acumuer\/\">Pe\u00f1a Retona (2.770m)<\/a>. La panor\u00e1mica completa es la siguente: Corona del Mallo y Pe\u00f1a Blanca (que pr\u00e1cticamente se confunden en un solo pico), canal de Covachirizas, Pe\u00f1a Parda, Pe\u00f1a Telera, Capullo (el puntiagudo en la sombra), Pico Sin Nombre (el siguiente), Punta Plana (que sobresale como una muesca negra del anterior) y Pabell\u00f3n (el blanco y soleado que aparenta ser m\u00e1s bajo por la perspectiva).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"Au cours de l'ann\u00e9e \u00e9coul\u00e9e, nous avons recherch\u00e9 chaque semaine un lieu dans les Pyr\u00e9n\u00e9es. Si vous avez manqu\u00e9 l'une d'entre elles, nous commen\u00e7ons l'ann\u00e9e avec un r\u00e9capitulatif des 45 lieux que nous avons recherch\u00e9s en 2023.","protected":false},"author":1,"featured_media":39016,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[],"series":[],"class_list":["post-39015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pirineos"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/01\/recopilatorio2023.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"dN8JcENIQ2\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/buscamos2023\/\">Buscamos este lugar: 2023<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/buscamos2023\/embed\/#?secret=dN8JcENIQ2\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Buscamos este lugar: 2023\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"dN8JcENIQ2\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":5,"label":"Pirineos"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/01\/recopilatorio2023-1024x690.jpg",1024,690,true],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":5,"name":"Pirineos","slug":"pirineos","term_group":0,"term_taxonomy_id":5,"taxonomy":"category","description":"","parent":0,"count":241,"filter":"raw","cat_ID":5,"category_count":241,"category_description":"","cat_name":"Pirineos","category_nicename":"pirineos","category_parent":0}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/01\/recopilatorio2023.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/39015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=39015"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/39015\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/39016"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=39015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=39015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=39015"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=39015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}