{"id":39687,"date":"2024-02-02T10:21:18","date_gmt":"2024-02-02T09:21:18","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=39687"},"modified":"2024-10-09T13:34:57","modified_gmt":"2024-10-09T11:34:57","slug":"angel-lopez-cintero-prix-dhonneur-du-festival-du-film-de-montagne-de-pirineos","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/angel-lopez-cintero-premio-honorifico-del-pirineos-mountain-film-festival\/","title":{"rendered":"\u00c1ngel L\u00f3pez \"Cintero\", prix d'honneur du Festival du film de montagne des Pyr\u00e9n\u00e9es"},"content":{"rendered":"<p class=\"wp-block-paragraph\">L'ALPINISTE ARAGONAIS EST UNE IC\u00d4NE DE L'ALPINISME ET LE PLUS ANCIEN ALPINISTE EN ACTIVIT\u00c9 DANS LE MONDE AUJOURD'HUI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> LE TH\u00c9\u00c2TRE OLIMPIA ACCUEILLERA LA C\u00c9R\u00c9MONIE D'HOMMAGE LE JEUDI 22 F\u00c9VRIER ET LA PROJECTION DU FILM PRIM\u00c9 \"MONTAGNES D'HIER\". <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'EXPOSITION \"LA D\u00c9CENNIE PRODIGIEUSE 1953-1963 DE L'ALPINISME ARAGONAIS\" COMPL\u00c8TERA L'HOMMAGE RENDU \u00c0 SA FIGURE ET \u00c0 TOUTE UNE G\u00c9N\u00c9RATION. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'alpiniste \u00c1ngel L\u00f3pez de Saragosse recevra le prix d'honneur du Festival du film de montagne des Pyr\u00e9n\u00e9es 2024, une reconnaissance qui met en avant la figure de personnes et d'institutions ayant un travail important li\u00e9 \u00e0 la montagne et \u00e0 l'environnement naturel.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Populairement connu sous le nom de \"el Cintero\", ce pionnier de l'alpinisme aragonais, qui est aussi le plus ancien grimpeur en activit\u00e9 en Espagne, sera dans la capitale de Huesca le 22 f\u00e9vrier. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La c\u00e9r\u00e9monie de remise des prix aura lieu au th\u00e9\u00e2tre Olimpia (20h30) et le film \"Yesterday's Mountains\", plusieurs fois prim\u00e9, sera projet\u00e9 en m\u00eame temps. Ce film porte sur la \"d\u00e9cennie prodigieuse\", une \u00e9poque dont L\u00f3pez est l'un des embl\u00e8mes ; cette production cin\u00e9matographique a remport\u00e9 plusieurs prix, dont celui du meilleur film sur la culture montagnarde \u00e0 Banff.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le m\u00eame jour sera inaugur\u00e9e l'exposition \"LA DECADA PRODIGIOSA 1953-1963 del Alpinismo Aragon\u00e9s\" (la d\u00e9cennie productive 1953-1963 de l'alpinisme aragonais), compos\u00e9e de mat\u00e9riel in\u00e9dit et original de cette g\u00e9n\u00e9ration qui a gravi pour la premi\u00e8re fois la face ouest du Mallo Pis\u00f3n \u00e0 Riglos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Festival du film de montagne des Pyr\u00e9n\u00e9es d\u00e9cernera son prix d'honneur \u00e0 l'alpiniste aragonais \u00c1ngel L\u00f3pez, connu sous le nom de \"el Cintero\". Une reconnaissance qui met en valeur sa carri\u00e8re li\u00e9e \u00e0 la montagne et \u00e0 la nature, puisqu'il a \u00e9t\u00e9 l'un des pionniers de l'escalade en Aragon et a fait partie de ce que l'on appelle la \"d\u00e9cennie prodigieuse\".  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Saragosse sera pr\u00e9sent au festival pour recevoir le prix le jeudi 22 f\u00e9vrier au Teatro Olimpia (20h30). \"Il est une ic\u00f4ne, une r\u00e9f\u00e9rence nationale, un exemple de d\u00e9vouement, de d\u00e9votion et de passion pour la montagne tout au long de sa vie. Sa personne repr\u00e9sente parfaitement l'esprit et le sens de ce prix\", d\u00e9clare David Asensio, directeur du Festival du film de montagne, d'aventure et de nature des Pyr\u00e9n\u00e9es. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Br\u00e8ve pr\u00e9sentation d'\u00c1ngel L\u00f3pez<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c1ngel L\u00f3pez est n\u00e9 \u00e0 Saragosse en 1936 et, \u00e0 l'\u00e2ge de dix ans, il a rejoint la centurie Montolar du Frente de Juventudes, le seul moyen d'escalade en montagne \u00e0 l'\u00e9poque. Apr\u00e8s avoir appris les techniques et rencontr\u00e9 ses compagnons d'escalade : Alberto Rabad\u00e1, Manuel Besc\u00f3s et Rafael Montaner, entre autres ; avec les deux premiers et \u00e0 seulement 17 ans, L\u00f3pez a r\u00e9alis\u00e9 la premi\u00e8re r\u00e9p\u00e9tition de la Pe\u00f1a Sola de Ag\u00fcero. Trois mois plus tard, avec la m\u00eame \u00e9quipe, il r\u00e9alise la premi\u00e8re ascension du Puro de Riglos, un jour avant l'\u00e9quipe du Catalan Jordi Panyella. Cette \u00e9tape marquera l'histoire de l'alpinisme en Espagne, une ann\u00e9e 1953 qui marquera le d\u00e9but de la \"d\u00e9cennie prodigieuse\" de l'alpinisme aragonais. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parmi ses r\u00e9alisations au cours de cette d\u00e9cennie figurent des ouvertures dans des endroits tels que les Mallos de Riglos, la Pe\u00f1a del Moro \u00e0 Mezalocha, Ricla ou la Foz de Salinas, ainsi que les premi\u00e8res r\u00e9p\u00e9titions de l'Espol\u00f3n Clos, de la Brecha de Rold\u00e1n, du Puro de Vadiello ou de l'Huevo de San Cosme. En 1957, avec Alberto Rabad\u00e1, Rafael Montaner et Juan Jos\u00e9 D\u00edaz, il r\u00e9alise une autre de ses ascensions les plus remarquables, la premi\u00e8re voie directe vers la face ouest du Mallo Pis\u00f3n \u00e0 Riglos par la voie qu'ils baptisent Ser\u00f3n-Mill\u00e1n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ses r\u00e9alisations sportives et sa reconnaissance institutionnelle comprennent la m\u00e9daille d'or des montagnards d'Aragon et le prix du ma\u00eetre du gouvernement d'Aragon pour l'ensemble de sa carri\u00e8re sportive. Il est membre honoraire du Groupe espagnol de haute montagne et membre du Groupe pyr\u00e9n\u00e9en de haute montagne de France. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Une projection et une exposition compl\u00e8teront l'hommage. <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La journ\u00e9e du 22 f\u00e9vrier sera cl\u00f4tur\u00e9e par la projection d'un long m\u00e9trage et l'inauguration d'une exposition sur cette g\u00e9n\u00e9ration. Le film Monta\u00f1as de ayer (Montagnes d'hier) sera le point culminant de l'\u00e9v\u00e9nement, qui d\u00e9butera \u00e0 20h30 au Teatro Olimpia de la capitale de Huesca. Documentaire avec des touches de fiction r\u00e9alis\u00e9 par Guillermo Campo et Jes\u00fas Bosque en 1998, le film se concentre sur la conqu\u00eate, dans les ann\u00e9es 1930-40, de \"El Puro\" \u00e0 Riglos, la derni\u00e8re des aiguilles \u00e0 \u00eatre achev\u00e9e \u00e0 l'\u00e9poque. De nombreuses r\u00e9compenses nationales et internationales attestent de sa qualit\u00e9 et de sa beaut\u00e9, parmi lesquelles le prix du meilleur film sur la culture de montagne \u00e0 Banff (Canada), la gentiane d'or \u00e0 Trente (Italie) ou le prix sp\u00e9cial du jury \u00e0 Teplice Nad Metuji (R\u00e9publique tch\u00e8que). <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"717\" height=\"1024\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/Montanas-de-Ayer_cartel-717x1024.jpg\" alt=\"\" class=\"wp-image-39692\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/Montanas-de-Ayer_cartel-717x1024.jpg 717w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/Montanas-de-Ayer_cartel-210x300.jpg 210w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/Montanas-de-Ayer_cartel-768x1097.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/Montanas-de-Ayer_cartel-600x857.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/Montanas-de-Ayer_cartel.jpg 993w\" sizes=\"auto, (max-width: 717px) 100vw, 717px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Le m\u00eame jour, l'exposition \" LA DECADA PRODIGIOSA 1953-1963 del Alpinismo Aragon\u00e9s \" ouvrira ses portes. Il s'agit d'une revue exhaustive r\u00e9alis\u00e9e par Jes\u00fas Bosque lui-m\u00eame, avec des audiovisuels, des photographies et du mat\u00e9riel original et in\u00e9dit de cette \" d\u00e9cennie prodigieuse \", une p\u00e9riode de dix ans au cours de laquelle l'escalade nationale s'est int\u00e9ress\u00e9e \u00e0 ce qui se faisait en Aragon et plus particuli\u00e8rement aux voies inaugur\u00e9es par Rabad\u00e1 et Navarro. Un ensemble de mat\u00e9riels th\u00e9matiques qui permet de d\u00e9couvrir les exploits du groupe form\u00e9 par Pepe D\u00edaz, Manuel Besc\u00f3s, Jos\u00e9 Antonio Besc\u00f3s, Rafael Montaner, Juli\u00e1n Vicente \"Nan\u00edn\" et \u00c1ngel L\u00f3pez \"Cintero\" lui-m\u00eame. Jusqu'au 23 mars, le Centre Ibercaja - Palacio de Villahermosa accueille l'h\u00e9ritage des conqu\u00eates de ces pionniers, comme la conqu\u00eate de la face ouest du Naranjo de Bulnes ou de la face nord de l'Eiger. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"705\" height=\"1024\" src=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/La-Decada-Prodigiosa_Navarro-y-Rabada-delante-del-Naranjo_baja-705x1024.jpg\" alt=\"\" class=\"wp-image-39691\" srcset=\"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/La-Decada-Prodigiosa_Navarro-y-Rabada-delante-del-Naranjo_baja-705x1024.jpg 705w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/La-Decada-Prodigiosa_Navarro-y-Rabada-delante-del-Naranjo_baja-206x300.jpg 206w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/La-Decada-Prodigiosa_Navarro-y-Rabada-delante-del-Naranjo_baja-768x1116.jpg 768w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/La-Decada-Prodigiosa_Navarro-y-Rabada-delante-del-Naranjo_baja-600x872.jpg 600w, https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/La-Decada-Prodigiosa_Navarro-y-Rabada-delante-del-Naranjo_baja.jpg 912w\" sizes=\"auto, (max-width: 705px) 100vw, 705px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Ce programme complet d'\u00e9v\u00e9nements vient compl\u00e9ter le prix d\u00e9cern\u00e9 \u00e0 \u00c1ngel L\u00f3pez, deuxi\u00e8me nom sur la liste du PMFF apr\u00e8s les groupes de sauvetage et d'intervention en montagne de la Guardia Civil de Huesca et le service d'h\u00e9licopt\u00e8res de la Guardia Civil, r\u00e9compens\u00e9s l'ann\u00e9e derni\u00e8re. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le festival du film de montagne Pirineos est organis\u00e9 par la Fundaci\u00f3n Festival Internacional de Cine de Huesca avec le soutien de la Diputaci\u00f3n Provincial de Huesca, Ayuntamiento de Huesca, Gobierno de Arag\u00f3n, TuHuesca, Aram\u00f3n, Fundaci\u00f3n Deporte Joven del Consejo Superior de Deportes, Instituto Aragon\u00e9s de la Mujer, Fundaci\u00f3n Ibercaja, Turismo de Arag\u00f3n et Pe\u00f1a Guara en tant qu'organisateur d'activit\u00e9s sportives \u00e0 Huesca. <\/p>","protected":false},"excerpt":{"rendered":"L'ALPINISTE ARAGONAIS EST UNE IC\u00d4NE DE L'ALPINISME ET LE PLUS ANCIEN ALPINISTE EN ACTIVIT\u00c9 \u00c0 L'HEURE ACTUELLE...","protected":false},"author":954,"featured_media":39694,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_wp_convertkit_post_meta":{"form":"-1","landing_page":"","tag":"0","restrict_content":"0"},"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3002,3001],"tags":[3182],"series":[],"class_list":["post-39687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-protagonistas-personajes","tag-pmff"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/Angel-Lopez_Gredos-1954-1.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"2EI6uuinhp\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/angel-lopez-cintero-premio-honorifico-del-pirineos-mountain-film-festival\/\">\u00c1ngel L\u00f3pez \u201cCintero\u201d, premio honor\u00edfico del Pirineos Mountain Film Festival<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/angel-lopez-cintero-premio-honorifico-del-pirineos-mountain-film-festival\/embed\/#?secret=2EI6uuinhp\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0\u00c1ngel L\u00f3pez \u201cCintero\u201d, premio honor\u00edfico del Pirineos Mountain Film Festival\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"2EI6uuinhp\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":3002,"label":"Actualidad"},{"value":3001,"label":"Protagonistas \/ Personajes"}],"post_tag":[{"value":3182,"label":"PMFF"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/Angel-Lopez_Gredos-1954-1-1024x768.jpg",1024,768,true],"author_info":{"display_name":"Moises Campos","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/moises-campos\/"},"comment_info":0,"category_info":[{"term_id":3002,"name":"Actualidad","slug":"actualidad","term_group":0,"term_taxonomy_id":3018,"taxonomy":"category","description":"Actualidad","parent":0,"count":74,"filter":"raw","cat_ID":3002,"category_count":74,"category_description":"Actualidad","cat_name":"Actualidad","category_nicename":"actualidad","category_parent":0},{"term_id":3001,"name":"Protagonistas \/ Personajes","slug":"protagonistas-personajes","term_group":0,"term_taxonomy_id":3017,"taxonomy":"category","description":"Protagonistas \/ Personajes","parent":0,"count":16,"filter":"raw","cat_ID":3001,"category_count":16,"category_description":"Protagonistas \/ Personajes","cat_name":"Protagonistas \/ Personajes","category_nicename":"protagonistas-personajes","category_parent":0}],"tag_info":[{"term_id":3182,"name":"PMFF","slug":"pmff","term_group":0,"term_taxonomy_id":3198,"taxonomy":"post_tag","description":"","parent":0,"count":11,"filter":"raw"}],"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/Angel-Lopez_Gredos-1954-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/39687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/954"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=39687"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/39687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/39694"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=39687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=39687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=39687"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=39687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}