{"id":39740,"date":"2024-02-06T12:13:44","date_gmt":"2024-02-06T11:13:44","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=39740"},"modified":"2024-10-09T13:17:10","modified_gmt":"2024-10-09T11:17:10","slug":"le-compte-a-rebours-commence-pour-la-15eme-edition-de-lultra-pirineu-de-salomon","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/empieza-la-cuenta-atras-para-la-15a-edicion-de-la-salomon-ultra-pirineu\/","title":{"rendered":"Le compte \u00e0 rebours de la 15e \u00e9dition de la Salomon Ultra Pirineu a commenc\u00e9."},"content":{"rendered":"<p class=\"wp-block-paragraph\"><span id=\"docs-internal-guid-c030c41b-7fff-3d69-6537-b728f02aba10\"><\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette ann\u00e9e encore, la <strong><a href=\"https:\/\/travesiapirenaica.com\/fr\/ultra-pirineu-2024\/\">Salomon Ultra Pirineu<\/a><\/strong>l'un des \u00e9v\u00e9nements internationaux de trail running les plus renomm\u00e9s, les plus authentiques et les plus passionnants du pays, <strong>est d\u00e9sormais ouvert \u00e0 l'inscription.<\/strong> Dans les prochains jours, le parc naturel du Cad\u00ed Moixer\u00f3 redeviendra, une fois de plus, le lieu de pr\u00e9dilection des touristes. <strong>4, 5 et 6 octobre 2024<\/strong>Le Salomon Ultra Pirineu est l'\u00e9picentre du trail running, accueillant une nouvelle \u00e9dition du Salomon Ultra Pirineu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'\u00e9v\u00e9nement pyr\u00e9n\u00e9en par excellence c\u00e9l\u00e8bre cette ann\u00e9e la <strong>15 ans d'exp\u00e9rience <\/strong>15 \u00e9ditions que les organisateurs veulent marquer par des nouveaut\u00e9s qui ne laisseront s\u00fbrement personne indiff\u00e9rent et qui seront bient\u00f4t annonc\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce dont nous pouvons \u00eatre s\u00fbrs, c'est la r\u00e9p\u00e9tition des quatre formats de course \u00e9tablis, qui garantissent un \u00e9v\u00e9nement plus adaptable et plus durable, avec des parcours am\u00e9lior\u00e9s et uniques : <a href=\"https:\/\/ultrapirineu.com\/curses\/marato\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>Salomon Ultra Pirineu 100k\u00ae<\/strong><\/a> (SUP100k), le <a href=\"https:\/\/ultrapirineu.com\/curses\/marato\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Salomon Marat\u00f3 Pirineu 42K\u00ae Marathon<\/strong><\/a> (SMP42k), le <a href=\"https:\/\/ultrapirineu.com\/curses\/mitja\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>Salomon Mitja Pirineu 21K\u00ae (Semi-marathon des Pyr\u00e9n\u00e9es 21K\u00ae)<\/strong><\/a><strong> <\/strong>(SMP21k) et le <a href=\"https:\/\/ultrapirineu.com\/curses\/nit\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>Molina Nit Pirineu VK<\/strong><\/a> (LMNPVK).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cependant, cette ann\u00e9e voit la naissance d'une nouvelle distance : le <a href=\"https:\/\/ultrapirineu.com\/curses\/junior\/\" target=\"_blank\" rel=\"noopener\"><strong>Salomon Junior Pirineu 12k\u00ae - pour les enfants de moins de 18 ans<\/strong><\/a>L'\u00e9v\u00e9nement pour les jeunes de 16 \u00e0 20 ans sera le dernier \u00e9v\u00e9nement du circuit. <strong>S\u00e9rie Next Gen <\/strong>de Salomon ainsi que les courses Junior de Zegama et l'Olla de N\u00faria. Avec <strong>12 kilom\u00e8tres et 920 m\u00e8tres de d\u00e9nivel\u00e9 positif,<\/strong> la plus jeune course de la famille fera ses d\u00e9buts \u00e0 Bag\u00e0 en octobre 2024.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ouverture des inscriptions<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le prochain <strong>6 f\u00e9vrier \u00e0 10:00h<\/strong> la vente des dossards pour la distance sera ouverte <strong>Ultra<\/strong>tandis que les autres courses se d\u00e9rouleront les jours suivants. <strong>Marat\u00f3 le fera le 7 f\u00e9vrier<\/strong> ce jour-l\u00e0 <strong>La Mitja et le Nit Pirineu se tiendront le 8 f\u00e9vrier.<\/strong> \u00e9galement dans la<strong> 10:00h<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les donn\u00e9es de ces derni\u00e8res ann\u00e9es montrent que l'Ultra Pirineu est l'une des courses les plus attendues par les coureurs de trail. Pour l'\u00e9dition 2023 <strong>50% des dossards disponibles ont \u00e9t\u00e9 vendus dans les premi\u00e8res 24 heures.<\/strong> et, quelques jours plus tard, le panneau Sold Out \u00e9tait accroch\u00e9 dans les diff\u00e9rentes salles. Ainsi, en tant que <strong>15\u00e8me anniversaire de l'\u00e9v\u00e9nement<\/strong> Il ne serait pas surprenant que de nombreux coureurs aient pu obtenir leur dossard au cours des premi\u00e8res heures.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conform\u00e9ment \u00e0 la d\u00e9cision prise ces derni\u00e8res ann\u00e9es, les organisateurs ont limit\u00e9 le nombre de dossards afin de garantir le bon d\u00e9roulement de la course et de minimiser l'impact sur l'environnement naturel du parc naturel Cad\u00ed-Moixer\u00f3.<strong>1 200 dossards seront disponibles pour l'ultra et le marathon, 900 pour la demi-distance et 200 pour le Nit Pirineu.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vente ne sera disponible que sur leur site web : <a href=\"https:\/\/ultrapirineu.com\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">www.ultrapirineu.com<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/TR1IaMJVrQcYArIeEo7yJmJOmQodXlrE07i0JEe0w1MogYQYma96kOlkTOFEBSuAYlCPDdxQG5rl6CtScehxGt0Q-sFmHFAAct8-PXE5zdAr6WKHps0pGopmiMf00G3IdOGg2xlXWxkgd0OCVNin1qA\" alt=\"\"\/><figcaption class=\"wp-element-caption\">Salomon Ultra Pirineu 2023. Cr\u00e9dit : Borja Iban Grava CS<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">La course vers l'avenir dans un environnement naturel sans pr\u00e9c\u00e9dent<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L'\u00e9quipe Salomon Ultra Pirineu continue d'avancer vers l'avenir, en mettant en \u0153uvre les valeurs cl\u00e9s de son slogan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis sa premi\u00e8re \u00e9dition, elle a adopt\u00e9 une politique environnementale forte dans le but de minimiser son impact sur le parc naturel. Cette politique comprend des mesures telles que la limitation de la capacit\u00e9, le nettoyage des sentiers apr\u00e8s la course, le choix d'une date en dehors de la p\u00e9riode de reproduction de la faune locale et l'utilisation de sentiers pr\u00e9existants. En outre, il est demand\u00e9 aux coureurs de ne pas s'\u00e9carter des sentiers balis\u00e9s. Ces actions ont contribu\u00e9 \u00e0 ce que les rapports post-course r\u00e9alis\u00e9s par le parc naturel indiquent un impact environnemental presque imperceptible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'organisation travaille non seulement en \u00e9troite collaboration avec les coureurs, les sponsors et les entit\u00e9s locales pour promouvoir la r\u00e9duction, la r\u00e9utilisation et le recyclage des mat\u00e9riaux, mais elle a \u00e9galement obtenu des r\u00e9sultats remarquables en termes de gestion des d\u00e9chets. Par exemple, lors de l'\u00e9dition 2021, une r\u00e9duction de 74% des d\u00e9chets g\u00e9n\u00e9r\u00e9s a \u00e9t\u00e9 r\u00e9alis\u00e9e par rapport \u00e0 l'ann\u00e9e pr\u00e9c\u00e9dente, avec un total de 1 300 kg de d\u00e9chets collect\u00e9s. Ceux-ci ont \u00e9t\u00e9 r\u00e9partis en 19% de mati\u00e8res organiques, 23% d'emballages, 19% de papier et de carton, et 38% de d\u00e9chets, d\u00e9passant ainsi les attentes de l'organisation en termes de durabilit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour plus d'informations, veuillez consulter le site <a href=\"https:\/\/ultrapirineu.com\/corrent-cap-al-futur\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/ultrapirineu.com\/corrent-cap-al-futur\/<\/a>&nbsp;<span id=\"docs-internal-guid-c030c41b-7fff-3d69-6537-b728f02aba10\"><\/span><\/p>","protected":false},"excerpt":{"rendered":"Cette ann\u00e9e encore, la Salomon Ultra Pirineu, l'une des plus importantes courses de trail...","protected":false},"author":954,"featured_media":39743,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_wp_convertkit_post_meta":{"form":"-1","landing_page":"","tag":"0","restrict_content":"0"},"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3002],"tags":[3181],"series":[],"class_list":["post-39740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-ultra-pirineu"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/Credito-Borja-Iban-Grava-CS.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"45oH3EL2mb\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/empieza-la-cuenta-atras-para-la-15a-edicion-de-la-salomon-ultra-pirineu\/\">Empieza la cuenta atr\u00e1s para la 15\u00aa edici\u00f3n de la Salomon Ultra Pirineu<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/empieza-la-cuenta-atras-para-la-15a-edicion-de-la-salomon-ultra-pirineu\/embed\/#?secret=45oH3EL2mb\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Empieza la cuenta atr\u00e1s para la 15\u00aa edici\u00f3n de la Salomon Ultra Pirineu\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"45oH3EL2mb\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":3002,"label":"Actualidad"}],"post_tag":[{"value":3181,"label":"Ultra Pirineu"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/Credito-Borja-Iban-Grava-CS-1024x768.jpg",1024,768,true],"author_info":{"display_name":"Moises Campos","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/moises-campos\/"},"comment_info":0,"category_info":[{"term_id":3002,"name":"Actualidad","slug":"actualidad","term_group":0,"term_taxonomy_id":3018,"taxonomy":"category","description":"Actualidad","parent":0,"count":74,"filter":"raw","cat_ID":3002,"category_count":74,"category_description":"Actualidad","cat_name":"Actualidad","category_nicename":"actualidad","category_parent":0}],"tag_info":[{"term_id":3181,"name":"Ultra Pirineu","slug":"ultra-pirineu","term_group":0,"term_taxonomy_id":3197,"taxonomy":"post_tag","description":"","parent":0,"count":3,"filter":"raw"}],"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2024\/02\/Credito-Borja-Iban-Grava-CS.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/39740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/954"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=39740"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/39740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/39743"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=39740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=39740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=39740"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=39740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}