{"id":45374,"date":"2023-12-09T14:57:00","date_gmt":"2023-12-09T13:57:00","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=45374"},"modified":"2024-12-09T15:01:31","modified_gmt":"2024-12-09T14:01:31","slug":"garmin-etrex","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/garmin-etrex\/","title":{"rendered":"Garmin Etrex 30x"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Le populaire GPS Yolk avec aiguille magn\u00e9tique \u00e0 trois axes, affichage am\u00e9lior\u00e9 et cartes pr\u00e9install\u00e9es. eTrex 30x est notre version am\u00e9lior\u00e9e du populaire eTrex 30, avec un courage d'affichage am\u00e9lior\u00e9 et un certificat interne \u00e9tendu avec une capacit\u00e9 pour un plus grand nombre de cartes. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"J&#039;OUVRE LA BO\u00ceTE DU GARMIN ETREX SE\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/h7LQ03NeIUw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La carte TopoActive pr\u00e9charg\u00e9e de Garmin est compatible avec une grande vari\u00e9t\u00e9 d'activit\u00e9s telles que la randonn\u00e9e, le g\u00e9ocaching, le cyclisme, l'alpinisme et la p\u00eache, offrant ainsi de meilleures exp\u00e9riences. L'eTrex 30x pr\u00e9sente des caract\u00e9ristiques am\u00e9lior\u00e9es par rapport \u00e0 l'eTrex 30, tout en conservant sa facilit\u00e9 d'utilisation, son prix abordable et sa robustesse.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00c9cran couleur de 2,2 pouces<\/li>\n\n\n\n<li>Carte TopoActive de l'Europe occidentale pr\u00e9install\u00e9e<\/li>\n\n\n\n<li>R\u00e9cepteur GPS haute sensibilit\u00e9 avec support HotFix et GLONASS<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Le GPS populaire avec aiguille magn\u00e9tique \u00e0 trois axes, affichage am\u00e9lior\u00e9 et cartes pr\u00e9charg\u00e9es. eTrex 30x est notre version am\u00e9lior\u00e9e du populaire eTrex 30, avec un courage d'affichage am\u00e9lior\u00e9 et un certificat interne \u00e9tendu avec une capacit\u00e9 pour un plus grand nombre de cartes. La carte Garmin TopoActive pr\u00e9charg\u00e9e est compatible avec une grande vari\u00e9t\u00e9 d'activit\u00e9s telles que la randonn\u00e9e, le g\u00e9ocaching, le cyclisme, l'alpinisme et la p\u00eache, offrant ainsi de meilleures exp\u00e9riences. L'eTrex 30x poss\u00e8de des caract\u00e9ristiques am\u00e9lior\u00e9es par rapport \u00e0 l'eTrex 30, tout en conservant sa facilit\u00e9 d'utilisation, son prix abordable et sa durabilit\u00e9 \u00e0 toute \u00e9preuve.<\/p>","protected":false},"excerpt":{"rendered":"Le c\u00e9l\u00e8bre GPS Yolk est dot\u00e9 d'une aiguille magn\u00e9tique \u00e0 trois axes, d'un affichage am\u00e9lior\u00e9 et d'une carte...","protected":false},"author":1,"featured_media":11173,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_wp_convertkit_post_meta":{"form":"-1","landing_page":"","tag":"0","restrict_content":"0"},"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2985],"tags":[],"series":[],"class_list":["post-45374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-electronica"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Garmin-eTrex-30x-_.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"SJPabCwkh8\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/garmin-etrex\/\">Garmin Etrex 30x<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/garmin-etrex\/embed\/#?secret=SJPabCwkh8\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Garmin Etrex 30x\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"SJPabCwkh8\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":2985,"label":"Electr\u00f3nica"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Garmin-eTrex-30x-_.jpg",800,600,false],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":2985,"name":"Electr\u00f3nica","slug":"electronica","term_group":0,"term_taxonomy_id":3001,"taxonomy":"category","description":"Electr\u00f3nica","parent":21,"count":8,"filter":"raw","cat_ID":2985,"category_count":8,"category_description":"Electr\u00f3nica","cat_name":"Electr\u00f3nica","category_nicename":"electronica","category_parent":21}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/11\/Garmin-eTrex-30x-_.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/45374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=45374"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/45374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/11173"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=45374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=45374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=45374"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=45374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}