{"id":7503,"date":"2014-05-29T11:14:12","date_gmt":"2014-05-29T09:14:12","guid":{"rendered":"https:\/\/travesiapirenaica.com\/?p=7503"},"modified":"2019-01-21T19:05:49","modified_gmt":"2019-01-21T18:05:49","slug":"choisir-les-bottes-montana","status":"publish","type":"post","link":"https:\/\/travesiapirenaica.com\/fr\/elegir-botas-montana\/","title":{"rendered":"Comment choisir les chaussures de randonn\u00e9e adapt\u00e9es \u00e0 votre activit\u00e9 ?"},"content":{"rendered":"<p>Quel est le probl\u00e8me avec le <a href=\"https:\/\/travesiapirenaica.com\/fr\/bottes-montana\/\" target=\"_blank\" rel=\"noopener\"><strong>bottes de trekking<\/strong><\/a>? Outre le fait qu'ils sont chers, je veux dire, mais a-t-on vraiment besoin d'acheter un objet aussi cher quand on d\u00e9bute ?<\/p>\n<p>\"La r\u00e9ponse est oui.<\/p>\n<p>Les chaussures de randonn\u00e9e sont en effet l'un des \u00e9l\u00e9ments les plus importants de votre vie. <a href=\"https:\/\/travesiapirenaica.com\/fr\/equipement-de-trekking\/\" target=\"_blank\" rel=\"noopener\"><strong>\u00e9quipement de randonn\u00e9e<\/strong><\/a>. En randonn\u00e9e, vous utiliserez vos pieds plus souvent que n'importe quelle autre partie de votre corps, raison de plus pour leur assurer une bonne protection. Les <strong>bottes de trekking<\/strong> qui sont robustes et peuvent prot\u00e9ger vos pieds des routes accident\u00e9es.<\/p>\n<p>Suivez le guide ci-dessous pour obtenir une liste des \u00e9l\u00e9ments \u00e0 prendre en compte lors de l'achat de vos chaussures de randonn\u00e9e :<\/p>\n<h2>Ce sentiment de \"solidit\u00e9<\/h2>\n<p>C'est l\u00e0 tout l'int\u00e9r\u00eat des chaussures de randonn\u00e9e. Les bonnes chaussures ont une semelle \"solide\", ce qui signifie que vous ne devez pas sentir les pierres ou les cailloux \u00e0 travers la semelle. Et si vous les sentez ? T\u00f4t ou tard, apr\u00e8s avoir parcouru de nombreux kilom\u00e8tres sur le sentier, il y a de fortes chances que vos pieds commencent \u00e0 vous faire mal, et ce n'est pas une bonne chose, surtout si vous devez encore parcourir les derniers kilom\u00e8tres avant la fin de votre randonn\u00e9e.<\/p>\n<p>Lorsque vous achetez une paire de chaussures de randonn\u00e9e, <strong>prouve sa solidit\u00e9<\/strong>. Essayez d'appuyer la plante de votre pouce sur le fond de la chaussure. Si elle est molle, ces bottes ne peuvent pas offrir \u00e0 vos pieds la protection dont ils ont besoin. Vous pouvez \u00e9galement essayer de tordre les semelles. Si vous y parvenez, elles sont probablement trop souples pour la randonn\u00e9e.<\/p>\n<p>N'oubliez jamais que les sentiers ne sont pas comme le trottoir devant votre maison. Ils sont rocailleux et si vous ne portez pas une bonne paire de chaussures de randonn\u00e9e, vous risquez de souffrir apr\u00e8s des kilom\u00e8tres de marche sur un terrain tr\u00e8s rocailleux.<\/p>\n<h2>Protection lat\u00e9rale<\/h2>\n<p>Le dessous de vos chaussures de randonn\u00e9e n'est pas le seul \u00e9l\u00e9ment important. De bonnes chaussures doivent \u00e9galement offrir une protection sur les c\u00f4t\u00e9s. En fait, la raison pour laquelle on les appelle des chaussures de randonn\u00e9e \"lourdes\" est qu'elles ont un rembourrage suppl\u00e9mentaire pour prot\u00e9ger votre pied des pierres, des rochers et des branches sur lesquels vous risquez de marcher et qui pourraient percer le c\u00f4t\u00e9.<\/p>\n<p>Si vous avez choisi des bottes en tissu, veillez \u00e0 les porter avec des \"passepoils\" de protection. Ceux-ci se trouvent \u00e0 environ 10 cm ou plus de la semelle afin de fournir une protection suppl\u00e9mentaire.<\/p>\n<h2>Support de cheville<\/h2>\n<p>Il est clair que <em>Achille<\/em> il ne connaissait rien aux bottes et n'avait donc rien pour se prot\u00e9ger lorsqu'il <em>Paris<\/em> l'a frapp\u00e9 d'une fl\u00e8che \u00e0 la cheville. Ne suivez pas les traces d'Achille. Choisissez de bonnes chaussures de randonn\u00e9e avec un bon maintien de la cheville.<\/p>\n<p>Voici comment les choisir :<\/p>\n<p>Saisir le haut de la botte.<\/p>\n<p>Essayez de le plier sur le c\u00f4t\u00e9.<\/p>\n<p>S'il se plie facilement, il n'offrira probablement pas le niveau de protection n\u00e9cessaire en montagne.<\/p>\n<p>La tige de la chaussure doit \u00eatre suffisamment rigide pour maintenir la cheville en place. C'est ainsi que l'on d\u00e9termine une paire de chaussures de randonn\u00e9e offrant un bon maintien.<\/p>\n<h2>Ne laissez pas l'eau entrer<\/h2>\n<p>Les pieds mouill\u00e9s provoquent des ampoules. Les ampoules sont douloureuses. Les ampoules sont diaboliques. <a href=\"https:\/\/travesiapirenaica.com\/fr\/ampollas-en-los-pies\/\" target=\"_blank\" rel=\"noopener\"><strong>Pr\u00e9vient les ampoules<\/strong> <\/a>\u00e0 tout prix. Achetez des chaussures de randonn\u00e9e imperm\u00e9ables. Outre les populaires <a href=\"https:\/\/travesiapirenaica.com\/fr\/gore-tex\/\"><strong>Gore-Tex<\/strong> <\/a>Il existe d'innombrables membranes imperm\u00e9ables qui, en plus de la protection contre l'eau, assurent la respirabilit\u00e9 - un aspect essentiel pour \u00e9viter l'humidit\u00e9 sur les pieds -. Si vous trouvez des chaussures de randonn\u00e9e qui ne sont pas imperm\u00e9ables, assurez-vous au moins qu'elles peuvent l'\u00eatre. Les chaussures en tissu peuvent \u00eatre imperm\u00e9abilis\u00e9es \u00e0 l'aide de solutions d'imperm\u00e9abilisation sp\u00e9ciales, telles que le silicone liquide. Toutefois, ces solutions ne sont g\u00e9n\u00e9ralement pas assez imperm\u00e9ables pour que les chaussures soient utiles.<\/p>\n<p><span style=\"font-size: 18pt;\"><strong>LIRE AUSSI :<\/strong><\/span><\/p>\n<ul style=\"list-style-type: disc;\">\n<li><a href=\"https:\/\/travesiapirenaica.com\/fr\/equipement-de-trekking\/\" target=\"_blank\" rel=\"noopener\"><strong><span style=\"font-size: 18pt;\">Ce que vous devez avoir dans votre kit de randonn\u00e9e de base &gt;&gt;&gt;&gt;<\/span><\/strong><\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"Quel est le probl\u00e8me avec les chaussures de randonn\u00e9e ? Outre le fait qu'elles sont...","protected":false},"author":1,"featured_media":7505,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[689],"tags":[],"series":[],"class_list":["post-7503","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-calzado","post_format-post-format-image"],"episode_featured_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/04\/andres-gerlotti-560523-unsplash.jpg_760x500.jpg","episode_player_image":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2017\/12\/Caratula-Podcast-Maldita-Montana_1500x1500_72pp-p_.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/travesiapirenaica.com\/fr\/feed\/podcast\/maldita-montana","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"35XnQGmBVM\"><a href=\"https:\/\/travesiapirenaica.com\/fr\/elegir-botas-montana\/\">C\u00f3mo elegir unas botas de monta\u00f1a adecuadas a tu actividad<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/travesiapirenaica.com\/fr\/elegir-botas-montana\/embed\/#?secret=35XnQGmBVM\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0C\u00f3mo elegir unas botas de monta\u00f1a adecuadas a tu actividad\u00a0\u00bb &#8212; Traves\u00eda.\" data-secret=\"35XnQGmBVM\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/travesiapirenaica.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"taxonomy_info":{"category":[{"value":689,"label":"Calzado"}]},"featured_image_src_large":["https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/04\/andres-gerlotti-560523-unsplash.jpg_760x500.jpg",760,500,false],"author_info":{"display_name":"Traves\u00eda Pirenaica","author_link":"https:\/\/travesiapirenaica.com\/fr\/author\/travesia-pirenaica\/"},"comment_info":0,"category_info":[{"term_id":689,"name":"Calzado","slug":"calzado","term_group":0,"term_taxonomy_id":689,"taxonomy":"category","description":"","parent":685,"count":7,"filter":"raw","cat_ID":689,"category_count":7,"category_description":"","cat_name":"Calzado","category_nicename":"calzado","category_parent":685}],"tag_info":false,"jetpack_featured_media_url":"https:\/\/travesiapirenaica.com\/wp-content\/uploads\/2018\/04\/andres-gerlotti-560523-unsplash.jpg_760x500.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/7503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/comments?post=7503"}],"version-history":[{"count":0,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/posts\/7503\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media\/7505"}],"wp:attachment":[{"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/media?parent=7503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/categories?post=7503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/tags?post=7503"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/travesiapirenaica.com\/fr\/wp-json\/wp\/v2\/series?post=7503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}